{"id":11683,"date":"2022-06-19T22:55:02","date_gmt":"2022-06-20T03:55:02","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/comentario-de-1-cronicas-258-exegesis-y-hermeneutica-de-la-biblia\/"},"modified":"2022-06-19T22:55:02","modified_gmt":"2022-06-20T03:55:02","slug":"comentario-de-1-cronicas-258-exegesis-y-hermeneutica-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/comentario-de-1-cronicas-258-exegesis-y-hermeneutica-de-la-biblia\/","title":{"rendered":"Comentario de 1 Cr\u00f3nicas 25:8 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia"},"content":{"rendered":"<h3 align='center'><b><i>Echaron suertes para establecer los turnos del servicio, participando tanto el peque\u00f1o como el grande, lo mismo el maestro que el alumno.<\/i><\/b><\/h3>\n<p><b><i>Y echaron suertes.<\/i><\/b> <span class='bible'>1Cr 24:5<\/span>; <span class='bible'>Lev 16:8<\/span>; <span class='bible'>1Sa 14:41<\/span>, <span class='bible'>1Sa 14:42<\/span>; <span class='bible'>Pro 16:33<\/span>; <span class='bible'>Hch 1:26<\/span>. <\/p>\n<p>\n<b><i>el peque\u00f1o con el grande.<\/i><\/b> <span class='bible'>1Cr 24:31<\/span>; <span class='bible'>1Cr 26:13<\/span>, <span class='bible'>1Cr 26:16<\/span>; <span class='bible'>Neh 12:24<\/span>.<\/p>\n<p><b><i>lo mismo el maestro.<\/i><\/b> A\u00fan entre los veinticuatro l\u00edderes, algunos eran m\u00e1s expertos que otros, sin embargo, cada uno fue tomado por de acuerdo al sorteo, sin ninguna consideraci\u00f3n a su experiencia musical. Todas estas cosas fueron dispuestas as\u00ed para el preservar de la orden, y para evitar cualquier disputa acerca de preferencia. <span class='bible'>1Cr 15:22<\/span>; <span class='bible'>2Cr 23:13<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: El Tesoro del Conocimiento B\u00edblico<\/b><\/i><\/h3>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\"><b>peque\u00f1o \u2026 grande \u2026 maestro \u2026 disc\u00edpulo:<\/b>\u00a0La igualdad de todos estos siervos de Dios se aprecia en la distribuci\u00f3n equitativa de sus tareas, un principio que tambi\u00e9n determin\u00f3 la naturaleza del ministerio de los sacerdotes (<\/span><span style=\"color:#008000\"><span class='bible'>1Cr 24:31<\/span><\/span>).<\/span><\/p>\n<p><\/p>\n<h3 align='right'><i><b>Fuente: Nuevo Comentario Ilustrado de la Biblia Caribe<\/b><\/i><\/h3>\n<p>REFERENCIAS CRUZADAS<\/p>\n<p>i 1607 Pro 16:33; Pro 18:18; Hch 1:26<\/p>\n<p>j 1608 1Cr 24:31<\/p>\n<p>k 1609 1Cr 15:22<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n del Nuevo Mundo<\/b><\/i><\/h3>\n<p><p> echaron suertes para designar sus cargos.  Hab\u00eda 24 grupos de m\u00fasicos que correspond\u00edan a los 24 grupos de sacerdotes (v. coment. en 24:4).<\/p>\n<p><h3 align='right'><i><b>Fuente: La Biblia de las Am\u00e9ricas<\/b><\/i><\/h3>\n<p>Los maestros (los aptos) eran los 288 del v. <span class='bible'>1Cr 25:7<\/span> y los disc\u00edpulos eran los 4.000 de <span class='bible'>1Cr 23:5<\/span>. Echaron suertes para establecer que el turno de los 24 grupos armonizaba con las 24 clases o familias de los sacerdotes.<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio Anotada por Ryrie<\/b><\/i><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Echaron suertes para establecer los turnos del servicio, participando tanto el peque\u00f1o como el grande, lo mismo el maestro que el alumno. Y echaron suertes. 1Cr 24:5; Lev 16:8; 1Sa 14:41, 1Sa 14:42; Pro 16:33; Hch 1:26. el peque\u00f1o con el grande. 1Cr 24:31; 1Cr 26:13, 1Cr 26:16; Neh 12:24. lo mismo el maestro. A\u00fan &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/comentario-de-1-cronicas-258-exegesis-y-hermeneutica-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abComentario de 1 Cr\u00f3nicas 25:8 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11683","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/11683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=11683"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/11683\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=11683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=11683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=11683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}