{"id":11762,"date":"2022-06-19T22:57:42","date_gmt":"2022-06-20T03:57:42","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/comentario-de-1-cronicas-2724-exegesis-y-hermeneutica-de-la-biblia\/"},"modified":"2022-06-19T22:57:42","modified_gmt":"2022-06-20T03:57:42","slug":"comentario-de-1-cronicas-2724-exegesis-y-hermeneutica-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/comentario-de-1-cronicas-2724-exegesis-y-hermeneutica-de-la-biblia\/","title":{"rendered":"Comentario de 1 Cr\u00f3nicas 27:24 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia"},"content":{"rendered":"<h3 align='center'><b><i>Joab, hijo de Sarvia, hab\u00eda comenzado a contar, pero no acab\u00f3, pues por esto vino la ira sobre Israel. Y el n\u00famero no fue registrado en el libro de las cr\u00f3nicas del rey David.<\/i><\/b><\/h3>\n<p><b><i>hab\u00eda comenzado a contar.<\/i><\/b> <span class='bible'>1Cr 21:1-17<\/span>; <span class='bible'>2Sa 24:1-15<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: El Tesoro del Conocimiento B\u00edblico<\/b><\/i><\/h3>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\">La cuenta de Joab incluy\u00f3 a todas las tribus, excepto las de Lev\u00ed y Benjam\u00edn (<\/span><span style=\"color:#008000\"><span class='bible'>1Cr 21:6<\/span><\/span>). Si bien estas dos tribus se incluyen en la presente lista (v.<\/span> <span style=\"color:#008000\"><span class='bible'>1Cr 27:17<\/span><\/span>,<\/span> <span style=\"color:#008000\"><span class='bible'>1Cr 27:21<\/span><\/span>), nada se dijo acerca de si se contaron. Por otra parte, Aser y Gad, omitidos en esta lista (vv.<\/span> <span style=\"color:#008000\"><span class='bible'>1Cr 27:16-22<\/span><\/span>) se debieron incluir en el\u00a0<b>censo<\/b>\u00a0de Joab.<\/span><\/p>\n<p><\/p>\n<h3 align='right'><i><b>Fuente: Nuevo Comentario Ilustrado de la Biblia Caribe<\/b><\/i><\/h3>\n<p><b>las cr\u00f3nicas del rey David.<\/b> Durante el reinado de David se mantuvieron registros diarios. No se guard\u00f3 registro alguno de esta acci\u00f3n calamitosa, porque fue un acontecimiento demasiado doloroso.<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio MacArthur<\/b><\/i><\/h3>\n<p><span class='bible'>1Cr 21:2-7<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n Interconfesional HispanoAmericana<\/b><\/i><\/h3>\n<p>REFERENCIAS CRUZADAS<\/p>\n<p>j 1713 2Sa 24:2<\/p>\n<p>k 1714 1Cr 21:6<\/p>\n<p>l 1715 2Sa 24:15; 1Cr 21:7<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n del Nuevo Mundo<\/b><\/i><\/h3>\n<p>V\u00e9ase nota en <span class='bible'>1Cr 21:1<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio Anotada por Ryrie<\/b><\/i><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Joab, hijo de Sarvia, hab\u00eda comenzado a contar, pero no acab\u00f3, pues por esto vino la ira sobre Israel. Y el n\u00famero no fue registrado en el libro de las cr\u00f3nicas del rey David. hab\u00eda comenzado a contar. 1Cr 21:1-17; 2Sa 24:1-15. Fuente: El Tesoro del Conocimiento B\u00edblico La cuenta de Joab incluy\u00f3 a todas &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/comentario-de-1-cronicas-2724-exegesis-y-hermeneutica-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abComentario de 1 Cr\u00f3nicas 27:24 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11762","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/11762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=11762"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/11762\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=11762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=11762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=11762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}