{"id":11808,"date":"2022-06-19T22:59:17","date_gmt":"2022-06-20T03:59:17","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/comentario-de-1-cronicas-2915-exegesis-y-hermeneutica-de-la-biblia\/"},"modified":"2022-06-19T22:59:17","modified_gmt":"2022-06-20T03:59:17","slug":"comentario-de-1-cronicas-2915-exegesis-y-hermeneutica-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/comentario-de-1-cronicas-2915-exegesis-y-hermeneutica-de-la-biblia\/","title":{"rendered":"Comentario de 1 Cr\u00f3nicas 29:15 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia"},"content":{"rendered":"<h3 align='center'><b><i>Somos forasteros y advenedizos delante de ti, as\u00ed como todos nuestros padres. Nuestros d\u00edas son como una sombra sobre la tierra, y sin esperanza.<\/i><\/b><\/h3>\n<p><b><i>Porque nosotros, extranjeros \u2026 somos.<\/i><\/b> <span class='bible'>G\u00e9n 47:9<\/span>; <span class='bible'>Sal 39:12<\/span>; <span class='bible'>Sal 119:19<\/span>; <span class='bible'>Heb 11:13-16<\/span>; <span class='bible'>1Pe 2:11<\/span>.<\/p>\n<p><b><i>y nuestros d\u00edas sobre la tierra.<\/i><\/b> <span class='bible'>Job 14:2<\/span>; <span class='bible'>Sal 90:9<\/span>; <span class='bible'>Sal 102:11<\/span>; <span class='bible'>Sal 144:4<\/span>; <span class='bible'>Ecl 6:12<\/span>; <span class='bible'>Isa 40:6-8<\/span>; <span class='bible'>Stg 4:14<\/span>. <\/p>\n<h3 align='right'><i><b>Fuente: El Tesoro del Conocimiento B\u00edblico<\/b><\/i><\/h3>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\"><b>extranjeros y advenedizos:<\/b>\u00a0David afirma que la vida en la tierra es transitoria e incluso n\u00f3mada. S\u00f3lo cuando una persona toma consciencia de su lugar en el cuidado y bendici\u00f3n de un Dios soberano, la vida se transforma en m\u00e1s que una\u00a0<b>sombra<\/b>. De repente, la\u00a0<b>esperanza<\/b>\u00a0de un futuro con Dios ilumina el viaje de esa persona en esta tierra (<\/span><span style=\"color:#008000\"><span class='bible'>Heb 11:13-16<\/span><\/span>;<\/span> <span style=\"color:#008000\"><span class='bible'>Heb 13:14<\/span><\/span>).<\/span><\/p>\n<p><\/p>\n<h3 align='right'><i><b>Fuente: Nuevo Comentario Ilustrado de la Biblia Caribe<\/b><\/i><\/h3>\n<p><span class='bible'>Sal 39:12<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n Interconfesional HispanoAmericana<\/b><\/i><\/h3>\n<p><i><b>\u2014 una sombra ef\u00edmera:<\/b><\/i> Lit. una sombra sin esperanza; es decir, sin esperanza de permanencia definitiva.<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n Interconfesional HispanoAmericana<\/b><\/i><\/h3>\n<p>REFERENCIAS CRUZADAS<\/p>\n<p>x 1863 Lev 25:23; Heb 11:13<\/p>\n<p>y 1864 Job 14:2; Stg 4:14<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n del Nuevo Mundo<\/b><\/i><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Somos forasteros y advenedizos delante de ti, as\u00ed como todos nuestros padres. Nuestros d\u00edas son como una sombra sobre la tierra, y sin esperanza. Porque nosotros, extranjeros \u2026 somos. G\u00e9n 47:9; Sal 39:12; Sal 119:19; Heb 11:13-16; 1Pe 2:11. y nuestros d\u00edas sobre la tierra. Job 14:2; Sal 90:9; Sal 102:11; Sal 144:4; Ecl 6:12; &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/comentario-de-1-cronicas-2915-exegesis-y-hermeneutica-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abComentario de 1 Cr\u00f3nicas 29:15 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11808","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/11808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=11808"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/11808\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=11808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=11808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=11808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}