{"id":15652,"date":"2022-06-20T01:17:36","date_gmt":"2022-06-20T06:17:36","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/comentario-de-salmos-733-exegesis-y-hermeneutica-de-la-biblia\/"},"modified":"2022-06-20T01:17:36","modified_gmt":"2022-06-20T06:17:36","slug":"comentario-de-salmos-733-exegesis-y-hermeneutica-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/comentario-de-salmos-733-exegesis-y-hermeneutica-de-la-biblia\/","title":{"rendered":"Comentario de Salmos 73:3 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia"},"content":{"rendered":"<h3 align='center'><b><i>porque tuve envidia de los arrogantes, al ver la prosperidad de los imp\u00edos.<\/i><\/b><\/h3>\n<p><b><i>Porque tuve envidia de los insensatos.<\/i><\/b> <span class='bible'>Sal 37:1<\/span>, <span class='bible'>Sal 37:7<\/span>; <span class='bible'>Job 21:7<\/span>; <span class='bible'>Pro 3:31<\/span>; <span class='bible'>Pro 24:1<\/span>; <span class='bible'>Jer 12:1<\/span>; <span class='bible'>Stg 4:5<\/span>. <\/p>\n<h3 align='right'><i><b>Fuente: El Tesoro del Conocimiento B\u00edblico<\/b><\/i><\/h3>\n<p><span class='bible'>Sal 37:1<\/span>; <span class='bible'>Jer 12:1<\/span>; <span class='bible'>Mal 3:15<\/span>; <span class='bible'>Job 21:7<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n Interconfesional HispanoAmericana<\/b><\/i><\/h3>\n<p><i><b>\u2014 la dicha de los malos:<\/b><\/i> Esta felicidad de los malos contradice el principio b\u00edblico de que Dios da a cada uno seg\u00fan merecen sus obras; al mismo tiempo cuestiona la utilidad de mantener una conducta recta.<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n Interconfesional HispanoAmericana<\/b><\/i><\/h3>\n<p>REFERENCIAS CRUZADAS<\/p>\n<p>e 2446 Pro 23:17; Pro 24:1; Pro 24:19<\/p>\n<p>f 2447 Job 21:7; Sal 37:1; Sal 37:7; Jer 12:1<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n del Nuevo Mundo<\/b><\/i><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>porque tuve envidia de los arrogantes, al ver la prosperidad de los imp\u00edos. Porque tuve envidia de los insensatos. Sal 37:1, Sal 37:7; Job 21:7; Pro 3:31; Pro 24:1; Jer 12:1; Stg 4:5. Fuente: El Tesoro del Conocimiento B\u00edblico Sal 37:1; Jer 12:1; Mal 3:15; Job 21:7. Fuente: Traducci\u00f3n Interconfesional HispanoAmericana \u2014 la dicha de &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/comentario-de-salmos-733-exegesis-y-hermeneutica-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abComentario de Salmos 73:3 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-15652","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/15652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=15652"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/15652\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=15652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=15652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=15652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}