{"id":19153,"date":"2022-06-20T03:33:22","date_gmt":"2022-06-20T08:33:22","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/comentario-de-isaias-4319-exegesis-y-hermeneutica-de-la-biblia\/"},"modified":"2022-06-20T03:33:22","modified_gmt":"2022-06-20T08:33:22","slug":"comentario-de-isaias-4319-exegesis-y-hermeneutica-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/comentario-de-isaias-4319-exegesis-y-hermeneutica-de-la-biblia\/","title":{"rendered":"Comentario de Isa\u00edas 43:19 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia"},"content":{"rendered":"<h3 align='center'><b><i>He aqu\u00ed que yo hago una cosa nueva; pronto surgir\u00e1. \u00bfNo la conocer\u00e9is? Otra vez os har\u00e9 un camino en el desierto, y r\u00edos en el sequedal.<\/i><\/b><\/h3>\n<p><b><i>He aqu\u00ed que yo hago cosa nueva.<\/i><\/b> <span class='bible'>Isa 42:9<\/span>; <span class='bible'>Isa 48:6<\/span>; <span class='bible'>Jer 31:22<\/span>; <span class='bible'>Apo 21:5<\/span>.<\/p>\n<p>\n<b><i>Otra vez abrir\u00e9 camino en el desierto.<\/i><\/b> <span class='bible'>Isa 35:6-10<\/span>; <span class='bible'>Isa 40:3<\/span>, <span class='bible'>Isa 40:4<\/span>; <span class='bible'>Isa 48:21<\/span>; <span class='bible'>Luc 3:4<\/span>, <span class='bible'>Luc 3:5<\/span>.<\/p>\n<p><b><i>y r\u00edos en la soledad.<\/i><\/b> <span class='bible'>Isa 41:18<\/span>; <span class='bible'>Isa 48:21<\/span>, <span class='bible'>Isa 48:22<\/span>; <span class='bible'>\u00c9xo 17:6<\/span>; <span class='bible'>N\u00fam 20:11<\/span>; <span class='bible'>Deu 8:15<\/span>; <span class='bible'>Sal 78:16-20<\/span>; <span class='bible'>Sal 105:41<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: El Tesoro del Conocimiento B\u00edblico<\/b><\/i><\/h3>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\"><b>cosa nueva<\/b>\u00a0se refiere a la orden de Ciro que se\u00f1ala el regreso a Jerusal\u00e9n; a la ca\u00edda de Babilonia y la restauraci\u00f3n de Israel (v.<\/span> <span style=\"color:#008000\"><span class='bible'>Isa 43:20<\/span><\/span>); y a la restauraci\u00f3n de todas las cosas (<\/span><span style=\"color:#008000\"><span class='bible'>Isa 65:17-19<\/span><\/span>). Se usa una frase semejante en<\/span> <span style=\"color:#008000\"><span class='bible'>Isa 48:6<\/span><\/span>.<\/span><\/p>\n<p> <\/p>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\"><b>camino en el desierto:<\/b>\u00a0El Se\u00f1or les otorgar\u00e1 a los deportados un sendero por donde volver a la tierra prometida que no tendr\u00e1 obst\u00e1culos (<\/span><span style=\"color:#008000\"><span class='bible'>Isa 40:3-5<\/span><\/span>).<\/span><\/p>\n<p> <\/p>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\"><b>r\u00edos en la soledad:<\/b>\u00a0Hasta en las regiones desoladas Dios refrescar\u00e1 a su pueblo (<\/span><span style=\"color:#008000\"><span class='bible'>Isa 41:18<\/span><\/span>,<\/span> <span style=\"color:#008000\"><span class='bible'>Isa 41:19<\/span><\/span>).<\/span><\/p>\n<p><\/p>\n<h3 align='right'><i><b>Fuente: Nuevo Comentario Ilustrado de la Biblia Caribe<\/b><\/i><\/h3>\n<p><b>r\u00edos \u2026 aguas \u2026 r\u00edos.<\/b> En el reino futuro del Mes\u00edas, los lugares secos de Israel estar\u00e1n bien irrigados (<span class='bible'>Isa 41:18<\/span>) y refrescar\u00e1n en abundancia al pueblo elegido de Dios (<span class='bible'>Isa 43:1<\/span>).<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio MacArthur<\/b><\/i><\/h3>\n<p><span class='bible'>Isa 40:3<\/span>; <span class='bible'>Isa 42:9<\/span>; <span class='bible'>Isa 65:17<\/span>; <span class='bible'>2Co 5:17<\/span>; <span class='bible'>Apo 21:5<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n Interconfesional HispanoAmericana<\/b><\/i><\/h3>\n<p>REFERENCIAS CRUZADAS<\/p>\n<p>e 2135 Isa 42:9<\/p>\n<p>f 2136 Isa 40:5; Luc 3:6<\/p>\n<p>g 2137 Isa 11:16; Isa 40:3<\/p>\n<p>h 2138 Deu 8:15; Sal 78:16; Isa 41:18<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n del Nuevo Mundo<\/b><\/i><\/h3>\n<p><i><b>soledad&#8230;<\/b><\/i> En sentido figurado.<i><b><\/b><\/i> Otras traducciones posibles: <i>p\u00e1ramo, desierto, yermo<\/i>.<\/span><\/p>\n<h3 align='right'><i><b>Fuente: Biblia Textual IV Edici\u00f3n<\/b><\/i><\/h3>\n<p>En sentido figurado <em>rtf1fbidisansiansicpg1252deff0fonttblf0fromanfprq2fcharset2 Wingdings 3;<\/em> N p\u00e1ramo, desierto, yermo.<\/p>\n<h3 align='right'><i><b>Fuente: La Biblia Textual III Edici\u00f3n<\/b><\/i><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>He aqu\u00ed que yo hago una cosa nueva; pronto surgir\u00e1. \u00bfNo la conocer\u00e9is? Otra vez os har\u00e9 un camino en el desierto, y r\u00edos en el sequedal. He aqu\u00ed que yo hago cosa nueva. Isa 42:9; Isa 48:6; Jer 31:22; Apo 21:5. Otra vez abrir\u00e9 camino en el desierto. Isa 35:6-10; Isa 40:3, Isa 40:4; &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/comentario-de-isaias-4319-exegesis-y-hermeneutica-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abComentario de Isa\u00edas 43:19 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-19153","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/19153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=19153"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/19153\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=19153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=19153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=19153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}