{"id":19171,"date":"2022-06-20T03:34:09","date_gmt":"2022-06-20T08:34:09","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/comentario-de-isaias-449-exegesis-y-hermeneutica-de-la-biblia\/"},"modified":"2022-06-20T03:34:09","modified_gmt":"2022-06-20T08:34:09","slug":"comentario-de-isaias-449-exegesis-y-hermeneutica-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/comentario-de-isaias-449-exegesis-y-hermeneutica-de-la-biblia\/","title":{"rendered":"Comentario de Isa\u00edas 44:9 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia"},"content":{"rendered":"<h3 align='center'><b><i>Los que dan forma a las im\u00e1genes talladas, todos son s\u00f3lo vanidad; lo m\u00e1s precioso de ellos no sirve para nada. Y en cuanto a sus testigos, ellos mismos no ven ni conocen, para su propia verg\u00fcenza.<\/i><\/b><\/h3>\n<p><b><i>Los formadores de im\u00e1genes de talla.<\/i><\/b> <span class='bible'>Isa 41:24<\/span>, <span class='bible'>Isa 41:29<\/span>; <span class='bible'>Deu 27:15<\/span>; <span class='bible'>Sal 97:7<\/span>; <span class='bible'>Jer 10:3-8<\/span>, <span class='bible'>Jer 10:14<\/span>, <span class='bible'>Jer 10:15<\/span>.<\/p>\n<p>\n<b><i>y lo m\u00e1s precioso.<\/i><\/b> <span class='bible'>Isa 2:20<\/span>, <span class='bible'>Isa 2:21<\/span>; <span class='bible'>Isa 37:18-20<\/span>; <span class='bible'>Isa 46:1<\/span>, <span class='bible'>Isa 46:2<\/span>, <span class='bible'>Isa 46:6<\/span>, <span class='bible'>Isa 46:7<\/span>; <span class='bible'>Jue 10:14<\/span>; <span class='bible'>1Re 18:26-40<\/span>; <span class='bible'>Jer 2:11<\/span>, <span class='bible'>Jer 2:27<\/span>, <span class='bible'>Jer 2:28<\/span>; <span class='bible'>Jer 14:22<\/span>; <span class='bible'>Jer 16:19<\/span>, <span class='bible'>Jer 16:20<\/span>; <span class='bible'>Dan 5:23<\/span>; <span class='bible'>Dan 11:38<\/span>; <span class='bible'>Ose 8:4-6<\/span>; <span class='bible'>Hab 2:18-20<\/span>; <span class='bible'>1Co 8:4<\/span>.<\/p>\n<p><b><i>ellos mismos son testigos.<\/i><\/b> <span class='bible'>Isa 44:18<\/span>, <span class='bible'>Isa 44:20<\/span>; <span class='bible'>Isa 42:18<\/span>; <span class='bible'>Isa 43:8<\/span>; <span class='bible'>Isa 45:20<\/span>; <span class='bible'>Sal 115:8<\/span>; <span class='bible'>Sal 135:18<\/span>; <span class='bible'>Rom 1:22<\/span>; <span class='bible'>2Co 4:4<\/span>; <span class='bible'>Efe 4:18<\/span>; <span class='bible'>Efe 5:8<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: El Tesoro del Conocimiento B\u00edblico<\/b><\/i><\/h3>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\">Esta s\u00e1tira a la idolatr\u00eda consiste de<\/p>\n<p><\/p>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\">(1) una introducci\u00f3n que condena a los \u00eddolos y a aquellos que los fabrican (vv.<\/span> <span style=\"color:#008000\"><span class='bible'>Isa 44:9-12<\/span><\/span>);<\/span><\/p>\n<p><\/p>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\">(2) una secci\u00f3n principal que muestra lo absurdo de la idolatr\u00eda al describir c\u00f3mo se hacen estos \u00eddolos de madera y metal (vv.<\/span> <span style=\"color:#008000\"><span class='bible'>Isa 44:12-17<\/span><\/span>; y<\/span><\/p>\n<p><\/p>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\">(3) una conclusi\u00f3n did\u00e1ctica que habla en contra de la fabricaci\u00f3n estos \u00eddolos (vv.<\/span> <span style=\"color:#008000\"><span class='bible'>Isa 44:18-20<\/span><\/span>). El profeta Isa\u00edas le hablaba a las generaciones futuras advirti\u00e9ndoles de la necedad que implica el adorar \u00eddolos (<\/span><span style=\"color:#008000\"><span class='bible'>Isa 40:19<\/span><\/span>,<\/span> <span style=\"color:#008000\"><span class='bible'>Isa 40:20<\/span><\/span>;<\/span> <span style=\"color:#008000\"><span class='bible'>Isa 41:21-29<\/span><\/span>;<\/span> <span style=\"color:#008000\"><span class='bible'>Isa 42:17<\/span><\/span>).<\/span><\/p>\n<p><\/p>\n<h3 align='right'><i><b>Fuente: Nuevo Comentario Ilustrado de la Biblia Caribe<\/b><\/i><\/h3>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\"><b>im\u00e1genes:<\/b>\u00a0Este es el t\u00e9rmino que se usa en el segundo mandamiento para describir un \u00eddolo (<\/span><span style=\"color:#008000\"><span class='bible'>\u00c9xo 20:4<\/span><\/span>).<\/span><\/p>\n<p> <\/p>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\"><b>Para nada es \u00fatil<\/b>\u00a0se traduce en<\/span> <span style=\"color:#008000\"><span class='bible'>G\u00e9n 1:2<\/span><\/span>\u00a0como \u00abdesordenada\u00bb.<\/span><\/p>\n<p><\/p>\n<h3 align='right'><i><b>Fuente: Nuevo Comentario Ilustrado de la Biblia Caribe<\/b><\/i><\/h3>\n<p><b>para su confusi\u00f3n \u2026 avergonzados \u2026 avergonzados.<\/b> Los art\u00edfices que fabricaban \u00eddolos eran hombres y no pod\u00edan hacer algo igual o mejor que el hombre. Ellos y todos los que ponen su confianza en los \u00eddolos ten\u00edan muchos motivos para temer y avergonzarse por tal necedad (v. <span class='bible'>Isa 44:11<\/span>; cp. el v. <span class='bible'>Isa 44:8<\/span>).<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio MacArthur<\/b><\/i><\/h3>\n<p><span class='bible'>Isa 40:18-20<\/span>+.<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n Interconfesional HispanoAmericana<\/b><\/i><\/h3>\n<p>NOTAS<\/p>\n<p>(1) O: \u201ccosas deseadas\u201d.<\/p>\n<p>(2) \u201cY como sus testigos.\u201d Heb.: we\u201be\u00b7dheh\u00b7h\u00e9m. La palabra siguiente (h\u00e9m\u00b7mah, \u201cellas [son]\u201d) est\u00e1 marcada con puntos extraordinarios de los soferim, lo cual indica que debe anularse por ser simplemente una repetici\u00f3n de la terminaci\u00f3n pronominal (hem, \u201csus\u201d) de la palabra que la precede. El pronombre para \u201cellas\u201d est\u00e1 ausente tambi\u00e9n en Sy. Seg\u00fan esto, el pasaje deber\u00eda decir: \u201cy como sus testigos ellas [las predilectas; las im\u00e1genes talladas] no ven nada ni saben nada, a fin de que ellos [los formadores de la imagen tallada] se averg\u00fcencen\u201d. Si se pasaran por alto los puntos extraordinarios, el pasaje dir\u00eda: \u201cy ellas [heb.: h\u00e9m\u00b7mah] son sus testigos que no ven nada y que no saben nada, a fin de que ellos se averg\u00fcencen\u201d. V\u00e9ase Ap. 2A.<\/p>\n<p>REFERENCIAS CRUZADAS<\/p>\n<p>a 2187 1Sa 12:21; Sal 97:7; Isa 41:29<\/p>\n<p>b 2188 Jue 10:14; 1Re 18:26; 1Co 8:4<\/p>\n<p>c 2189 Sal 115:5; Sal 135:17<\/p>\n<p>d 2190 Sal 97:7; Jer 51:17<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n del Nuevo Mundo<\/b><\/i><\/h3>\n<p><p> sus propios testigos.  Es decir, sus sacerdotes y profetas, que tienen que actuar como las voces de las im\u00e1genes, ya que las im\u00e1genes no pueden hablar. Mientras tales l\u00edderes pueden ser inteligentes desde el punto de vista del mundo, espiritualmente son ignorantes del conocimiento de Dios, y para su propia verg\u00fcenza fomentan su religi\u00f3n falsa.<\/p>\n<p><h3 align='right'><i><b>Fuente: La Biblia de las Am\u00e9ricas<\/b><\/i><\/h3>\n<p>Otro devastador ataque contra la idolatr\u00eda (un intento de \u00abinmunizaci\u00f3n\u00bb contra el peligro de la idolatr\u00eda en Babilonia).<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio Anotada por Ryrie<\/b><\/i><\/h3>\n<p>Se sigue LXX \u2192 \u00a7<span class=\"dct\">194<\/span>.<\/span><\/p>\n<h3 align='right'><i><b>Fuente: Biblia Textual IV Edici\u00f3n<\/b><\/i><\/h3>\n<p> O, <i>una imagen tallada<\/i> <\/p>\n<p><p>  O, <i>vacuidad<\/i> <\/p>\n<h3 align='right'><i><b>Fuente: La Biblia de las Am\u00e9ricas<\/b><\/i><\/h3>\n<p> N <em> desencanten, desilusionen.<\/p>\n<h3 align='right'><i><b>Fuente: La Biblia Textual III Edici\u00f3n<\/b><\/i><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Los que dan forma a las im\u00e1genes talladas, todos son s\u00f3lo vanidad; lo m\u00e1s precioso de ellos no sirve para nada. Y en cuanto a sus testigos, ellos mismos no ven ni conocen, para su propia verg\u00fcenza. Los formadores de im\u00e1genes de talla. Isa 41:24, Isa 41:29; Deu 27:15; Sal 97:7; Jer 10:3-8, Jer 10:14, &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/comentario-de-isaias-449-exegesis-y-hermeneutica-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abComentario de Isa\u00edas 44:9 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-19171","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/19171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=19171"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/19171\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=19171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=19171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=19171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}