{"id":24661,"date":"2022-06-20T09:15:02","date_gmt":"2022-06-20T14:15:02","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/comentario-de-mateo-2524-exegesis-y-hermeneutica-de-la-biblia\/"},"modified":"2022-06-20T09:15:02","modified_gmt":"2022-06-20T14:15:02","slug":"comentario-de-mateo-2524-exegesis-y-hermeneutica-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/comentario-de-mateo-2524-exegesis-y-hermeneutica-de-la-biblia\/","title":{"rendered":"Comentario de Mateo 25:24 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia"},"content":{"rendered":"<h3 align='center'><b><i>Pero cuando se present\u00f3 el que hab\u00eda recibido un talento, dijo: \u201cSe\u00f1or, yo te conozco que eres un hombre duro, que cosechas donde no sembraste y recoges donde no esparciste.<\/i><\/b><\/h3>\n<p \/><span>25:24<\/span> Pero llegando tambi\u00e9n el que hab\u00eda recibido un talento, dijo: Se\u00f1or, te conoc\u00eda que eres hombre duro, que siegas donde no sembraste y recoges donde no esparciste; \u2014 SKLEROS, comp\u00e1rese la palabra \u00abarteriosclerosis\u00bb, endurecimiento de las arterias. Fara\u00f3n era duro y cruel en su tratamiento de los israelitas (<span>\u00c9xo 5:7-8<\/span>). Roboam era duro y cruel con el pueblo (<span>1Re 12:12<\/span>). \u00bfPor qu\u00e9 acusa este siervo a su se\u00f1or de esta manera? Es probable que este siervo describi\u00f3 a s\u00ed mismo al atribuir estas caracter\u00edsticas a su se\u00f1or. Muchos culpan a otros de ser como ellos mismos. Dijo que sab\u00eda que su se\u00f1or era duro, cruel, exigente y ego\u00edsta, sacando ganancia del trabajo de otros y que, por eso, tem\u00eda invertir el talento de su se\u00f1or en los negocios, porque si ganaba algo, el se\u00f1or se lo llevar\u00eda todo, y si perdiera el talento, entonces el se\u00f1or lo castigar\u00eda. \u00bfCu\u00e1l es la conclusi\u00f3n de esta acusaci\u00f3n? Obviamente este siervo se sent\u00eda justificado en lo que hizo. Cre\u00eda que \u00e9l mismo era inocente, que no ten\u00eda culpa alguna, que su se\u00f1or ten\u00eda la culpa. Cre\u00eda que su conducta era justificable, que la \u00fanica alternativa que le quedaba era esconder el talento en la tierra para despu\u00e9s entregarlo al se\u00f1or. Tal vez cre\u00eda que el se\u00f1or debiera pedirle disculpas y darle gracias. La acusaci\u00f3n era falsa. V\u00e9anse los vers 22, 23.<\/p>\n<p \/> Nuestro concepto de Dios tiene mucho que ver con nuestro cumplimiento o incumplimiento de su voluntad. Para \u201cjustificar\u201d (disculpar) la desobediencia muchos critican a Dios, diciendo que El permite guerras y mucho sufrimiento, injusticias, etc. Otros quieren justificar su negligencia diciendo, \u00abSi Dios me hubiera dado el talento o el dinero que dio al hno. Fulano, yo tambi\u00e9n habr\u00eda hecho grandes cosas por El\u00bb.<\/p>\n<p \/> La excusa de muchos (la \u00abraz\u00f3n\u00bb seg\u00fan ellos) para justificar su incumplimiento del deber es que el discipulado es duro, exigente, y vienen persecuciones y tribulaciones. Directa o indirectamente acusan a Dios de ser injusto.<\/p>\n<p \/> Recu\u00e9rdese que este hombre de un talento acept\u00f3 el dinero del se\u00f1or, y al hacerlo acept\u00f3 tambi\u00e9n su responsabilidad. Por esa raz\u00f3n estaba sin justificaci\u00f3n alguna. No obedecemos al Se\u00f1or con ojos cerrados. <span>Mat 5:10-12<\/span>; <span>Mat 10:34-37<\/span>; <span>Mat 16:24<\/span>; <span>Luc 14:33<\/span>; <span>1Co 9:27<\/span>; <span>2Ti 3:12<\/span>.<\/p>\n<p \/> Los infieles culpan a la iglesia, al predicador, o a cualquier miembro. Esto se llama \u00abtransferir culpa\u00bb; los que usan esta t\u00e1ctica quieren transferir la culpa de s\u00ed mismos a otros. Las excusas comunes hechas por la gente hoy en d\u00eda son tan insensatas como la del hombre de un talento: \u00abCuando yo era ni\u00f1o, mis padres me obligaron a asistir a las reuniones de la iglesia y, por esa causa yo estoy resentido y ellos tienen la culpa\u00bb. Otra t\u00e1ctica com\u00fan es que se dice \u00abS\u00ed, tengo culpa, pero usted tambi\u00e9n tiene culpa\u00bb (a veces se dice, \u00abUsted es peor que yo\u00bb). El punto es que la respuesta insensata del hombre de un talento bien tipifica o representa todas las excusas necias que se hacen para no ser fieles (comp\u00e1rese <span>Luc 14:18-20<\/span>.<\/p>\n<p \/>\n<h3 align='right'><i><b>Fuente: Comentario al Nuevo Testamento por Partain<\/b><\/i><\/h3>\n<p><b><i>Se\u00f1or.<\/i><\/b> <span class='bible'>Mat 7:21<\/span>; <span class='bible'>Luc 6:46<\/span>.<\/p>\n<p><b><i>te conoc\u00eda.<\/i><\/b> <span class='bible'>Mat 20:12<\/span>; <span class='bible'>Job 21:14<\/span>, <span class='bible'>Job 21:15<\/span>; <span class='bible'>Isa 58:3<\/span>; <span class='bible'>Jer 2:31<\/span>; <span class='bible'>Jer 44:16-18<\/span>; <span class='bible'>Eze 18:25-29<\/span>; <span class='bible'>Mal 1:12<\/span>, <span class='bible'>Mal 1:13<\/span>; <span class='bible'>Mal 3:14<\/span>, <span class='bible'>Mal 3:15<\/span>; <span class='bible'>Luc 15:29<\/span>; <span class='bible'>Luc 19:20-22<\/span>; <span class='bible'>Rom 8:7<\/span>; <span class='bible'>Rom 9:20<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: El Tesoro del Conocimiento B\u00edblico<\/b><\/i><\/h3>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\">El siervo malo fue perezoso y desleal, porque si realmente hubiese temido a su se\u00f1or, habr\u00eda entregado el\u00a0<\/span><span style=\"font-weight:bold\">dinero a los banqueros<\/span>. Entonces el se\u00f1or habr\u00eda\u00a0<\/span><span style=\"font-weight:bold\">recibido<\/span>\u00a0lo que es suyo con los\u00a0<\/span><span style=\"font-weight:bold\">intereses<\/span>.<\/span><\/p>\n<p><\/p>\n<h3 align='right'><i><b>Fuente: Nuevo Comentario Ilustrado de la Biblia Caribe<\/b><\/i><\/h3>\n<p><b>hombre duro.<\/b> Dando esta caracterizaci\u00f3n, difam\u00f3 a su se\u00f1or present\u00e1ndolo como un hombre cruel y oportunista que \u00absegaba y recog\u00eda\u00bb donde no ten\u00eda derecho a hacerlo. Este siervo perezoso no representa a un genuino creyente por lo que es obvio que nunca conoci\u00f3 verdaderamente al Maestro.<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio MacArthur<\/b><\/i><\/h3>\n<p>25:24 Pero llegando tambi\u00e9n el que hab\u00eda recibido un talento, dijo: Se\u00f1or, te conoc\u00eda que eres hombre duro, que siegas donde no sembraste y recoges donde no esparciste; &#8212; SKLEROS, comp\u00e1rese la palabra \u00abarteriosclerosis\u00bb, endurecimiento de las arterias. Fara\u00f3n era duro y cruel en su tratamiento de los israelitas (\u00c9xo 5:7-8). Roboam era duro y cruel con el pueblo (1Re 12:12). \u00bfPor qu\u00e9 acusa este siervo a su se\u00f1or de esta manera? Es probable que este siervo describi\u00f3 a s\u00ed mismo al atribuir estas caracter\u00edsticas a su se\u00f1or. Muchos culpan a otros de ser como ellos mismos. Dijo que sab\u00eda que su se\u00f1or era duro, cruel, exigente y ego\u00edsta, sacando ganancia del trabajo de otros y que, por eso, tem\u00eda invertir el talento de su se\u00f1or en los negocios, porque si ganaba algo, el se\u00f1or se lo llevar\u00eda todo, y si perdiera el talento, entonces el se\u00f1or lo castigar\u00eda. \u00bfCu\u00e1l es la conclusi\u00f3n de esta acusaci\u00f3n? Obviamente este siervo se sent\u00eda justificado en lo que hizo. Cre\u00eda que \u00e9l mismo era inocente, que no ten\u00eda culpa alguna, que su se\u00f1or ten\u00eda la culpa. Cre\u00eda que su conducta era justificable, que la \u00fanica alternativa que le quedaba era esconder el talento en la tierra para despu\u00e9s entregarlo al se\u00f1or. Tal vez cre\u00eda que el se\u00f1or debiera pedirle disculpas y darle gracias. La acusaci\u00f3n era falsa. V\u00e9anse los vers 22, 23.<br \/>\n\tNuestro concepto de Dios tiene mucho que ver con nuestro cumplimiento o incumplimiento de su voluntad. Para \u201cjustificar\u201d (disculpar) la desobediencia muchos critican a Dios, diciendo que El permite guerras y mucho sufrimiento, injusticias, etc. Otros quieren justificar su negligencia diciendo, \u00abSi Dios me hubiera dado el talento o el dinero que dio al hno. Fulano, yo tambi\u00e9n habr\u00eda hecho grandes cosas por El\u00bb.<br \/>\n\tLa excusa de muchos (la \u00abraz\u00f3n\u00bb seg\u00fan ellos) para justificar su incumplimiento del deber es que el discipulado es duro, exigente, y vienen persecuciones y tribulaciones. Directa o indirectamente acusan a Dios de ser injusto.<br \/>\n\tRecu\u00e9rdese que este hombre de un talento acept\u00f3 el dinero del se\u00f1or, y al hacerlo acept\u00f3 tambi\u00e9n su responsabilidad. Por esa raz\u00f3n estaba sin justificaci\u00f3n alguna. No obedecemos al Se\u00f1or con ojos cerrados. Mat 5:10-12; Mat 10:34-37; Mat 16:24; Luc 14:33; 1Co 9:27; 2Ti 3:12.<br \/>\n\tLos infieles culpan a la iglesia, al predicador, o a cualquier miembro. Esto se llama \u00abtransferir culpa\u00bb; los que usan esta t\u00e1ctica quieren transferir la culpa de s\u00ed mismos a otros. Las excusas comunes hechas por la gente hoy en d\u00eda son tan insensatas como la del hombre de un talento: \u00abCuando yo era ni\u00f1o, mis padres me obligaron a asistir a las reuniones de la iglesia y, por esa causa yo estoy resentido y ellos tienen la culpa\u00bb. Otra t\u00e1ctica com\u00fan es que se dice \u00abS\u00ed, tengo culpa, pero usted tambi\u00e9n tiene culpa\u00bb (a veces se dice, \u00abUsted es peor que yo\u00bb). El punto es que la respuesta insensata del hombre de un talento bien tipifica o representa todas las excusas necias que se hacen para no ser fieles (comp\u00e1rese Luc 14:18-20.<\/p>\n<h3 align='right'><i><b>Fuente: Notas Reeves-Partain<\/b><\/i><\/h3>\n<p>NOTAS<\/p>\n<p>(1) O: \u201cduro\u201d.<\/p>\n<p>REFERENCIAS CRUZADAS<\/p>\n<p>c 1218 Luc 19:20<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n del Nuevo Mundo<\/b><\/i><\/h3>\n<p>\n24<strong> (1)<\/strong> El que hab\u00eda recibido un solo talento y no hab\u00eda producido ninguna ganancia para el Se\u00f1or, tambi\u00e9n compareci\u00f3 ante el tribunal de Cristo en los aires. Esto demuestra que no s\u00f3lo era salvo, sino que tambi\u00e9n hab\u00eda sido arrebatado a los aires. Ning\u00fan incr\u00e9dulo podr\u00e1 ser arrebatado ni podr\u00e1 comparecer ante el tribunal de Cristo.<\/p>\n<\/p>\n<p>\n24<strong> (2)<\/strong> La palabra griega se refiere al conocimiento exterior y objetivo, no a la comprensi\u00f3n interior y subjetiva.<\/p>\n<\/p>\n<p>\n24<strong> (3)<\/strong> Aparentemente, el Se\u00f1or es duro por ser tan estricto. El exige que usemos el don al m\u00e1ximo para Su obra, lo cual requiere nuestra entrega absoluta.<\/p>\n<\/p>\n<p>\n24<strong> (4)<\/strong> Aparentemente, la obra del Se\u00f1or comienza siempre en cero; parece exigir que trabajemos por El sin nada, segando donde no sembr\u00f3 y recogiendo donde no avent\u00f3. Aquel que recibi\u00f3 un talento no debe tomar eso como pretexto para descuidar el uso de su don; m\u00e1s bien, deber\u00eda sentirse obligado a ejercitar su fe para usar su don al m\u00e1ximo.<\/p>\n<\/p>\n<p>\n24<strong> (5)<\/strong> Lit., esparciste. As\u00ed tambi\u00e9n en el v. 26.<\/p>\n<h3 align='right'><i><b>Fuente: Comentario Del Nuevo Testamento Versi\u00f3n Recobro<\/b><\/i><\/h3>\n<p>BD342(1) El sentido perfecto se usa en \u03b5\u1f30\u03bb\u03b7\u03c6\u03ce\u03c2 para denotar un efecto continuo: el poseedor (comp. R909 y MT238). <\/p>\n<p> BD437 Se usa \u1f45\u03b8\u03b5\u03bd (cuando) en lugar de \u1f10\u03ba\u03b5\u1fd6\u03b8\u03b5\u03bd \u03bf\u1f57 (donde) en los vv. 24 y 26. <\/p>\n<h3 align='right'><i><b>Fuente: Ayuda gramatical para el Estudio del Nuevo Testamento Griego<\/b><\/i><\/h3>\n<p>Lit. <em>ha recibido.<\/em><\/p>\n<h3 align='right'><i><b>Fuente: La Biblia Textual III Edici\u00f3n<\/b><\/i><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Pero cuando se present\u00f3 el que hab\u00eda recibido un talento, dijo: \u201cSe\u00f1or, yo te conozco que eres un hombre duro, que cosechas donde no sembraste y recoges donde no esparciste. 25:24 Pero llegando tambi\u00e9n el que hab\u00eda recibido un talento, dijo: Se\u00f1or, te conoc\u00eda que eres hombre duro, que siegas donde no sembraste y recoges &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/comentario-de-mateo-2524-exegesis-y-hermeneutica-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abComentario de Mateo 25:24 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-24661","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/24661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=24661"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/24661\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=24661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=24661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=24661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}