{"id":24668,"date":"2022-06-20T09:15:20","date_gmt":"2022-06-20T14:15:20","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/comentario-de-mateo-2531-exegesis-y-hermeneutica-de-la-biblia\/"},"modified":"2022-06-20T09:15:20","modified_gmt":"2022-06-20T14:15:20","slug":"comentario-de-mateo-2531-exegesis-y-hermeneutica-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/comentario-de-mateo-2531-exegesis-y-hermeneutica-de-la-biblia\/","title":{"rendered":"Comentario de Mateo 25:31 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia"},"content":{"rendered":"<h3 align='center'><b><i>Cuando el Hijo del Hombre venga en su gloria y todos los \u00e1ngeles con \u00e9l, entonces se sentar\u00e1 sobre el trono de su gloria;<\/i><\/b><\/h3>\n<p \/><span>25:31<\/span> Cuando el Hijo del Hombre venga en su gloria, y todos los santos \u00e1ngeles con \u00e9l, entonces se sentar\u00e1 en su trono de gloria, \u2014 Habla con toda confianza de su triunfo final. Los eventos finales. Cuando Cristo venga (<span>Hch 1:9-11<\/span>), la tierra ser quemada (<span>2Pe 3:10<\/span>; <span>Apo 20:11<\/span>, \u00abY vi un gran trono blanco y al que estaba sentado en \u00e9l, de delante del cual huyeron la tierra y el cielo, y ning\u00fan lugar se encontr\u00f3 para ellos\u00bb); los muertos ser\u00e1n resucitados; y los vivos ser\u00e1n transformados (<span>Jua 5:28-29<\/span>; <span>1Co 15:50-52<\/span>; <span>1Ts 4:16-17<\/span>); entonces todos comparecer\u00e1n ante el tribunal de Cristo (<span>2Co 5:10<\/span>). No cabe en ninguno de estos textos la teor\u00eda de un reino terrenal de mil a\u00f1os.<\/p>\n<p \/> Este texto no es una par\u00e1bola. No es cierto, como dicen algunos comentaristas (por ejemplo, Barclay), que este texto es otra par\u00e1bola, porque habla claramente del Hijo del Hombre (Cristo) y del juicio final. Hay contraste entre su humillaci\u00f3n terrenal y su gloria celestial (\u00abgloria de su Padre\u00bb, 16:27). V\u00e9ase este contraste explicado en <span>Flp 2:5-11<\/span>. Muchos hombres y mujeres <\/p>\n<p \/>\u2014 jud\u00edos y romanos \u2014 vieron a Jes\u00fas cuando le clavaron a una cruz romana como si fuera un criminal (lo crucificaron entre dos criminales para indicar que Jes\u00fas era un criminal). Fue una escena de gran humillaci\u00f3n. En Aquel D\u00eda Final todos lo ver\u00e1n en su gloria suprema.<\/p>\n<p \/> Los ap\u00f3stoles Pedro, Juan y Jacobo vieron la transfiguraci\u00f3n de Jes\u00fas: \u00abse transfigur\u00f3 delante de ellos, y resplandeci\u00f3 su rostro como el sol, y sus vestidos se hicieron blancos como la luz\u00bb (<span>Mat 17:2<\/span>). Vieron, pues, una demostraci\u00f3n de la gloria celestial de Jes\u00fas. Comp\u00e1rese el Hijo del Hombre como Juan lo vio en la isla de Patmos (<span>Apo 1:13-16<\/span>), \u00a1el Cristo Din\u00e1mico!<\/p>\n<p \/> \u2014 y todos los santos \u00e1ngeles con \u00e9l. LBLA omite la palabra \u00absantos\u00bb porque no aparece en los manuscritos m\u00e1s antiguos. Comp\u00e1rese 13:41, 42, \u00abEnviar\u00e1 el Hijo del Hombre a sus \u00e1ngeles, y recoger\u00e1n de su reino (el mundo, ver 37) a todos los que sirven de tropiezo, y a los que hacen iniquidad, y los echar\u00e1n en el horno de fuego; all\u00ed ser\u00e1 el lloro y el crujir de dientes\u00bb; tambi\u00e9n 16:27, \u00abPorque el Hijo del Hombre vendr\u00e1 en la gloria de su Padre con sus \u00e1ngeles, y entonces pagar\u00e1 a cada uno conforme a sus obras\u00bb.<\/p>\n<p \/>\n<p \/>\u2014 entonces se sentar\u00e1 en su trono de gloria \u2014 \u00abel gran trono blanco\u00bb (<span>Apo 20:11<\/span>). Los jud\u00edos esperaban que el Mes\u00edas ocupara un trono literal en Jerusal\u00e9n para dar libertad pol\u00edtica a Israel y para castigar a los romanos. En <span>Mat 19:28<\/span> Jes\u00fas habla de ocupar su trono, pero no ten\u00eda nada que ver con el concepto de los jud\u00edos. <span>Mat 19:28<\/span> no es paralelo con <span>Mat 25:31<\/span>, porque en aquel texto Jes\u00fas se refiere al trono que El ocup\u00f3 cuando ascendi\u00f3 al cielo despu\u00e9s de su resurrecci\u00f3n (<span>Hch 2:30<\/span>; <span>Hch 2:33<\/span>), y en \u00e9ste se refiere al juicio final. Cuando Jes\u00fas ocup\u00f3 su trono despu\u00e9s de su resurrecci\u00f3n, los ap\u00f3stoles tambi\u00e9n ocuparon tronos como los embajadores de Cristo, por lo cual la iglesia persevera en su doctrina (<span>Hch 2:32<\/span>) y sigue su ejemplo (<span>Hch 14:23<\/span>; <span>Hch 20:7<\/span>; <span>1Co 4:16-17<\/span>; <span>Flp 4:9<\/span>).<\/p>\n<p \/>\n<h3 align='right'><i><b>Fuente: Comentario al Nuevo Testamento por Partain<\/b><\/i><\/h3>\n<p><b><i>el Hijo del Hombre.<\/i><\/b> <span class='bible'>Mat 25:6<\/span>; <span class='bible'>Mat 16:27<\/span>; <span class='bible'>Mat 19:28<\/span>; <span class='bible'>Mat 26:64<\/span>; <span class='bible'>Dan 7:13<\/span>, <span class='bible'>Dan 7:14<\/span>; <span class='bible'>Zac 14:5<\/span>; <span class='bible'>Mar 8:38<\/span>; <span class='bible'>Mar 14:62<\/span>; <span class='bible'>Luc 9:26<\/span>; <span class='bible'>Luc 22:69<\/span>; <span class='bible'>Jua 1:51<\/span>; <span class='bible'>Jua 5:27-29<\/span>; <span class='bible'>Hch 1:11<\/span>; <span class='bible'>1Ts 4:16<\/span>; <span class='bible'>2Ts 1:7<\/span>, <span class='bible'>2Ts 1:8<\/span>; <span class='bible'>Heb 1:8<\/span>; <span class='bible'>Jud 1:14<\/span>; <span class='bible'>Apo 1:7<\/span>.<\/p>\n<p><b><i>entonces se sentar\u00e1 sobre el trono.<\/i><\/b> <span class='bible'>Sal 9:7<\/span>; <span class='bible'>Apo 3:21<\/span>; <span class='bible'>Apo 20:11<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: El Tesoro del Conocimiento B\u00edblico<\/b><\/i><\/h3>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\">La secci\u00f3n final de este discurso involucra juicio. Mateo ha sido llamado \u00abel Evangelio de juicio\u00bb porque el tema ocurre a menudo (<\/span><span style=\"color:#008000\"><span class='bible'>Mat 3:12<\/span><\/span>;<\/span> <span style=\"color:#008000\"><span class='bible'>Mat 6:2<\/span><\/span>,<\/span> <span style=\"color:#008000\"><span class='bible'>Mat 6:5<\/span><\/span>,<\/span> <span style=\"color:#008000\"><span class='bible'>Mat 6:16<\/span><\/span>;<\/span> <span style=\"color:#008000\"><span class='bible'>Mat 7:24-27<\/span><\/span>;<\/span> <span style=\"color:#008000\"><span class='bible'>Mat 13:30<\/span><\/span>,<\/span> <span style=\"color:#008000\"><span class='bible'>Mat 13:48<\/span><\/span>,<\/span> <span style=\"color:#008000\"><span class='bible'>Mat 13:49<\/span><\/span>;<\/span> <span style=\"color:#008000\"><span class='bible'>Mat 18:23-34<\/span><\/span>;<\/span> <span style=\"color:#008000\"><span class='bible'>Mat 20:1-16<\/span><\/span>;<\/span> <span style=\"color:#008000\"><span class='bible'>Mat 21:33-41<\/span><\/span>;<\/span> <span style=\"color:#008000\"><span class='bible'>Mat 22:1-14<\/span><\/span>;<\/span> <span style=\"color:#008000\"><span class='bible'>Mat 24:45-51<\/span><\/span>;<\/span> <span style=\"color:#008000\"><span class='bible'>Mat 25:1-12<\/span><\/span>,<\/span> <span style=\"color:#008000\"><span class='bible'>Mat 25:14-46<\/span><\/span>). Esto era de esperar puesto que Mateo hace \u00e9nfasis en la venida del Reino y por lo tanto, al juicio que lo acompa\u00f1a. En las dos par\u00e1bolas previas, Jes\u00fas hab\u00eda hablado del juicio contra los israelitas que no estaban preparados para la venida del Mes\u00edas. En la \u00faltima par\u00e1bola de este discurso, Jes\u00fas centra su atenci\u00f3n sobre todas las naciones de la tierra.<\/span><\/p>\n<p> <\/p>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\">C<\/span><span style=\"font-weight:bold\">uando el Hijo del Hombre venga en su gloria<\/span>\u00a0recalca las palabras de<\/span> <span style=\"color:#008000\"><span class='bible'>Dan 7:13<\/span><\/span>,<\/span> <span style=\"color:#008000\"><span class='bible'>Dan 7:14<\/span><\/span>,<\/span> <span style=\"color:#008000\"><span class='bible'>Dan 7:27<\/span><\/span>\u00a0y anuncia el futuro Reino de Cristo (<\/span><span style=\"color:#008000\"><span class='bible'>Apo 5:9<\/span><\/span>,<\/span> <span style=\"color:#008000\"><span class='bible'>Apo 5:10<\/span><\/span>;<\/span> <span style=\"color:#008000\"><span class='bible'>Apo 19:11-18<\/span><\/span>;<\/span> <span style=\"color:#008000\"><span class='bible'>Apo 20:4-6<\/span><\/span>).<\/span><\/p>\n<p><\/p>\n<h3 align='right'><i><b>Fuente: Nuevo Comentario Ilustrado de la Biblia Caribe<\/b><\/i><\/h3>\n<p><b>se sentar\u00e1 en su trono de gloria.<\/b> Esto se refiere al reino terrenal de Cristo descrito en <span class='bible'>Apo 20:4-6<\/span>. El juicio descrito aqu\u00ed en los vv. <span class='bible'>Mat 25:32-46<\/span> es diferente del juicio ante el gran trono blanco de <span class='bible'>Apo 20:11-15<\/span>. Este juicio precede al reino milenario de Cristo, y los sujetos parecen ser solamente aquellos que est\u00e9n vivos para el momento de su venida. Este es referido algunas veces como el juicio de las naciones, pero sus veredictos se dirigen a los individuos de esas naciones y no a las naciones como un todo (cp. v. <span class='bible'>Mat 25:46<\/span>).<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio MacArthur<\/b><\/i><\/h3>\n<p>25:31 Cuando el Hijo del Hombre venga en su gloria, y todos los santos \u00e1ngeles con \u00e9l, entonces se sentar\u00e1 en su trono de gloria, &#8212; Habla con toda confianza de su triunfo final.  Los eventos finales. Cuando Cristo venga (Hch 1:9-11), la tierra ser quemada (2Pe 3:10; Apo 20:11, \u00abY vi un gran trono blanco y al que estaba sentado en \u00e9l, de delante del cual huyeron la tierra y el cielo, y ning\u00fan lugar se encontr\u00f3 para ellos\u00bb); los muertos ser\u00e1n resucitados; y los vivos ser\u00e1n transformados (Jua 5:28-29; 1Co 15:50-52; 1Ts 4:16-17); entonces todos comparecer\u00e1n ante el tribunal de Cristo (2Co 5:10). No cabe en ninguno de estos textos la teor\u00eda de un reino terrenal de mil a\u00f1os.<br \/>\n\tEste texto no es una par\u00e1bola. No es cierto, como dicen algunos comentaristas (por ejemplo, Barclay), que este texto es otra par\u00e1bola, porque habla claramente del Hijo del Hombre (Cristo) y del juicio final. Hay contraste entre su humillaci\u00f3n terrenal y su gloria celestial (\u00abgloria de su Padre\u00bb, 16:27). V\u00e9ase este contraste explicado en Flp 2:5-11. Muchos hombres y mujeres &#8212; jud\u00edos y romanos &#8212; vieron a Jes\u00fas cuando le clavaron a una cruz romana como si fuera un criminal (lo crucificaron entre dos criminales para indicar que Jes\u00fas era un criminal). Fue una escena de gran humillaci\u00f3n. En Aquel D\u00eda Final todos lo ver\u00e1n en su gloria suprema.<br \/>\n\tLos ap\u00f3stoles Pedro, Juan y Jacobo vieron la transfiguraci\u00f3n de Jes\u00fas: \u00abse transfigur\u00f3 delante de ellos, y resplandeci\u00f3 su rostro como el sol, y sus vestidos se hicieron blancos como la luz\u00bb (Mat 17:2). Vieron, pues, una demostraci\u00f3n de la gloria celestial de Jes\u00fas. Comp\u00e1rese el Hijo del Hombre como Juan lo vio en la isla de Patmos (Apo 1:13-16), \u00a1el Cristo Din\u00e1mico!<br \/>\n\t&#8212; y todos los santos \u00e1ngeles con \u00e9l. LBLA omite la palabra \u00absantos\u00bb porque no aparece en los manuscritos m\u00e1s antiguos. Comp\u00e1rese 13:41, 42, \u00abEnviar\u00e1 el Hijo del Hombre a sus \u00e1ngeles, y recoger\u00e1n de su reino (el mundo, ver 37) a todos los que sirven de tropiezo, y a los que hacen iniquidad, y los echar\u00e1n en el horno de fuego; all\u00ed ser\u00e1 el lloro y el crujir de dientes\u00bb; tambi\u00e9n 16:27, \u00abPorque el Hijo del Hombre vendr\u00e1 en la gloria de su Padre con sus \u00e1ngeles, y entonces pagar\u00e1 a cada uno conforme a sus obras\u00bb.<br \/>\n\t&#8212; entonces se sentar\u00e1 en su trono de gloria &#8212; \u00abel gran trono blanco\u00bb (Apo 20:11). Los jud\u00edos esperaban que el Mes\u00edas ocupara un trono literal en Jerusal\u00e9n para dar libertad pol\u00edtica a Israel y para castigar a los romanos. En Mat 19:28 Jes\u00fas habla de ocupar su trono, pero no ten\u00eda nada que ver con el concepto de los jud\u00edos. Mat 19:28 no es paralelo con Mat 25:31, porque en aquel texto Jes\u00fas se refiere al trono que El ocup\u00f3 cuando ascendi\u00f3 al cielo despu\u00e9s de su resurrecci\u00f3n (Hch 2:30; Hch 2:33), y en \u00e9ste se refiere al juicio final. Cuando Jes\u00fas ocup\u00f3 su trono despu\u00e9s de su resurrecci\u00f3n, los ap\u00f3stoles tambi\u00e9n ocuparon tronos como los embajadores de Cristo, por lo cual la iglesia persevera en su doctrina (Hch 2:32) y sigue su ejemplo (Hch 14:23; Hch 20:7; 1Co 4:16-17; Flp 4:9).<\/p>\n<h3 align='right'><i><b>Fuente: Notas Reeves-Partain<\/b><\/i><\/h3>\n<p><strong><u>EL BAREMO DE DIOS<\/u><\/strong><\/p>\n<\/p>\n<p><strong><span class='bible'>Mateo 25:31-46<\/span><\/strong><\/p>\n<\/p>\n<p><em>-Cuando venga el Hijo del Hombre con todos Sus \u00e1ngeles, ocupar\u00e1 Su puesto en Su trono glorioso, y todas das naciones se reunir\u00e1n delante de \u00c9l; y \u00c9l separar\u00e1 a unos de otros como separa un pastor las ovejas de las cabras, colocando las ovejas a su derecha y las cabras a su izquierda. Entonces el Rey les dir\u00e1 a <\/em>los <em>de Su mano derecha: \u00abVenid, vosotros a quienes ha bendecido Mi Padre, entrad en posesi\u00f3n del Reino que se os ha preparado desde la creaci\u00f3n del mundo! Porque cuando Yo estaba hambriento Me disteis de comer; cuando estaba sediento, Me disteis de beber; cuando era un forastero, Me recibisteis; cuando estaba desnudo, Me vestisteis; cuando estaba enfermo, vinisteis a visitarme; cuando estaba en la c\u00e1rcel, vinisteis a verme.\u00bb Entonces los \u00edntegros Le contestar\u00e1n: \u00abSe\u00f1or, \u00bfcu\u00e1ndo Te vimos hambriento, y Te dimos de comer; o sediento, y Te dimos de beber; \u00f3 cuando Te vimos forastero, y Te recibimos en nuestras casas; o desnudo, y Te vestimos? \u00bfCu\u00e1ndo Te vimos enfermo, o en la c\u00e1rcel, y fuimos a verte?\u00bb Y entonces el Rey les contestar\u00e1: \u00abOs digo la pura verdad: En tanto en cuanto se lo hicisteis a uno de los m\u00e1s peque\u00f1itos de estos Mis hermanos, Me lo hicisteis a M\u00ed:\u00bb Entonces les dir\u00e1 a los de Su izquierda: \u00ab\u00a1Alejaos de M\u00ed, malditos, al fuego eterno que est\u00e1 preparado para el diablo y sus \u00e1ngeles! Porque estuve hambriento, y no Me disteis de comer; sediento, y no Me disteis de beber; fui forastero, y no Me recibisteis entre vosotros; desnuda, y no Me vestisteis, enfermo y en la c\u00e1rcel, y no vinisteis a visitarme.\u00bb Entonces esos tambi\u00e9n Le contestar\u00e1n: \u00abSe\u00f1or, \u00bfcu\u00e1ndo Te vimos hambriento, o sediento, o forastero, o desnudo, o enfermo, o en la c\u00e1rcel, y no Te prestamos ning\u00fan servicio?\u00bb Entonces \u00c9l les responder\u00e1: \u00abOs digo la pura verdad: En tanto en cuanto no se lo hicisteis a uno de los m\u00e1s peque\u00f1os de estos, no Me lo hicisteis a M\u00ed.\u00bb Y estos se retirar\u00e1n al castigo eterno, y los \u00edntegros ir\u00e1n a la vida eterna.<\/em><\/p>\n<\/p>\n<p>Esta es una de las par\u00e1bolas m\u00e1s gr\u00e1ficas que Jes\u00fas dijo nunca, y su lecci\u00f3n est\u00e1 clara como el agua: Que Dios nos juzgar\u00e1 de acuerdo con nuestra reacci\u00f3n a las necesidades humanas. Su juicio no ser\u00e1 en funci\u00f3n de los conocimientos que hayamos amasado, o de la fama que hayamos adquirido, o de la fortuna que hayamos ganado, sino de la ayuda que hayamos restado.<br \/>Hay ciertas cosas que esta par\u00e1bola nos ense\u00f1a acerca de la ayuda que debemos prestar a otros.<br \/>(i) Debe ser la ayuda en cosas sencillas. Las cosas que Jes\u00fas escoge mencionar -dar una comida a un hambriento, o algo de beber a un sediento, recibir a un forastero, animar a un enfermo, visitar a un preso son cosas que cualquiera puede hacer. No se trata de dar millones de pesetas, ni de escribir nuestros nombres en los anales de la Historia; sino de prestar una sencilla ayuda a personas que nos encontramos todos los d\u00edas. No hay ninguna otra par\u00e1bola que le abra el camino de la gloria de tal manera a la gente sencilla.<br \/>(ii) Debe ser una ayuda desinteresada. Los que la prestaron no lo hicieron pensando que estaban ayudando a Cristo o haciendo m\u00e9ritos para la eternidad; ayudaban porque no pod\u00edan por menos. Era la reacci\u00f3n natural, instintiva, totalmente desinteresada, del coraz\u00f3n amante. Mientras que, por la otra parte, la actitud de los que dejaron de ayudar era: \u00bb Si hubi\u00e9ramos sabido que eras T\u00fa, Te habr\u00edamos ayudado con mil amores; pero cre\u00edmos que era simplemente una persona corriente que no val\u00eda la pena ayudar.\u00bb Sigue siendo verdad que hay algunos que ayudar\u00edan si hubieran de recibir por ello alabanzas y gracias y publicidad; pero ayudar de esa manera no es ayudar; es apilarse m\u00e9ritos. No es prestar por generosidad, sino por ego\u00edsmo disfrazado. La ayuda que obtiene la aprobaci\u00f3n de Dios es la que se da nada m\u00e1s que para ayudar.<br \/>(iii) Jes\u00fas nos coloca cara a cara con la maravillosa verdad de que toda ayuda de esta clase que prestemos a nuestros semejantes se Le da a \u00c9l, y toda la ayuda que se niega, se Le niega a \u00c9l. \u00bfC\u00f3mo puede ser esto? Si de veras queremos alegrar el coraz\u00f3n de un padre, si de veras queremos moverle a gratitud, la mejor manera de hacerlo es ayudando a uno de sus hijos. Dios es el gran Padre; y la manera de alegrar el coraz\u00f3n de Dios es ayudando a Sus hijos, nuestros semejantes.<br \/>Hubo dos hombres que encontraron esta par\u00e1bola benditamente cierta. Uno fue Francisco de As\u00eds; era rico y de elevado nacimiento y clase, pero no era feliz, porque ten\u00eda el sentimiento de que la vida era incompleta. Un buen d\u00eda iba d\u00e1ndose un paseo a caballo, y se encontr\u00f3 con un leproso, horrible y repulsivo por la fealdad de su enfermedad. Algo movi\u00f3 a Francisco a bajar del caballo y abrazar a aquel miserable doliente; y en sus brazos el rostro del leproso se transform\u00f3 en el rostro de Cristo.<\/p>\n<p>El otro fue Mart\u00edn de Tours. Era soldado romano, y cristiano. Un fr\u00edo d\u00eda de invierno, cuando entraba en una ciudad, le par\u00f3 un mendigo para pedirle limosna. Mart\u00edn no ten\u00eda dinero; pero el mendigo estaba azul y tiritando de fr\u00edo, y Mart\u00edn le dio lo que ten\u00eda. Se quit\u00f3 su capa militar, usada y desgastada como estaba, la cort\u00f3 en dos y le dio la mitad al mendigo.<\/p>\n<p>Aquella noche tuvo un sue\u00f1o. En \u00e9l vio los lugares celestiales, y a todos los \u00e1ngeles, y a Jes\u00fas en medio de ellos; y Jes\u00fas llevaba puesta la media capa de un soldado romano. Uno de los \u00e1ngeles Le pregunt\u00f3: \u00bb Maestro, \u00bfpor qu\u00e9 llevas esa capa vieja y desgastada? \u00bfQui\u00e9n Te la ha dado?\u00bb Y Jes\u00fas le contest\u00f3 suavemente: \u00abMe la ha dado Mi siervo Mart\u00edn.\u00bb<\/p>\n<p>Cuando aprendemos la generosidad que ayuda sin inter\u00e9s a las personas en las cosas m\u00e1s sencillas, nosotros tambi\u00e9n experimentamos el gozo de ayudar a Jesucristo mismo.<\/p>\n<h3 align='right'><i><b>Fuente: Comentario al Nuevo Testamento<\/b><\/i><\/h3>\n<p><i><b>\u2014 el Hijo del hombre:<\/b><\/i> Ver nota a <span class='bible'>Mat 8:20<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n Interconfesional HispanoAmericana<\/b><\/i><\/h3>\n<p><span class='bible'>Mat 10:23<\/span>; <span class='bible'>Mat 13:41<\/span>; <span class='bible'>Mat 19:28<\/span>; <span class='bible'>Mat 24:42<\/span>; <span class='bible'>Mat 24:44<\/span>; <span class='bible'>Zac 14:5<\/span>; <span class='bible'>Jud 1:14<\/span>; <span class='bible'>Apo 3:21<\/span>; <span class='bible'>Apo 20:11<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n Interconfesional HispanoAmericana<\/b><\/i><\/h3>\n<p>El juicio final. Como el juicio ha sido el tema a trav\u00e9s de este discurso, concluye apropiadamente con esta magn\u00edfica descripci\u00f3n del Hijo del Hombre entronizado en gloria, juzgando a todas las naciones. Aunque con frecuencia se describe como una par\u00e1bola, no es un relato ilustrativo, sino una visi\u00f3n del futuro. El \u00fanico elemento que contiene como \u201cpar\u00e1bola\u201d es el s\u00edmil como cuando el pastor separa las ovejas de los cabritos en los vv. 32, 33.<\/p>\n<p>El lenguaje acerca de la llegada del Hijo del Hombre, su gloria, los \u00e1ngeles, el trono para juzgar, se deriva de Dan. 7:9-14. Esta es la realizaci\u00f3n final de su majestad real y su autoridad que dicha profec\u00eda vislumbraba del Hijo del Hombre, y a la que Jes\u00fas ya hab\u00eda aludido en varias oportunidades (10:23; 16:28; 19:28; 24:30). Todas las naciones ser\u00e1n reunidas delante de \u00e9l para juicio hace recordar la visi\u00f3n en Joel 3:2; pero all\u00ed Dios mismo es el juez. Todo el pasaje sencillamente atribuye a Jes\u00fas la autoridad y realeza que en el AT s\u00f3lo pertenecen a Dios.<\/p>\n<p>Con frecuencia se entiende que este pasaje ense\u00f1a que la salvaci\u00f3n final se basa sobre actos de bondad solamente, de modo que no queda nada particularmente cristiano acerca de los criterios del juicio. Pero eso ser\u00eda ignorar la descripci\u00f3n importante de los recipientes de esta bondad como mis hermanos m\u00e1s peque\u00f1os (40;  cf. v. 45). Esta expresi\u00f3n sugiere que no son solamente algunos que hayan sido ayudados por los justos e ignorados por los dem\u00e1s; son, en realidad, los disc\u00edpulos necesitados. La expresi\u00f3n m\u00e1s peque\u00f1os nos recuerda a \u201clos peque\u00f1itos\u201d en 10:42; 18:6, 10, 14, y m\u00e1s arriba hemos visto que este es un t\u00e9rmino para designar a los disc\u00edpulos de Jes\u00fas. Cuando Jes\u00fas dice que al ayudarles a ellos a m\u00ed me lo hicisteis, dicha identificaci\u00f3n de Jes\u00fas con sus \u201chermanos\u201d hace recordar el principio en 10:40-42, donde el recibir a los disc\u00edpulos es recibir a Jes\u00fas, y es un vaso de agua dado a \u201cuno de estos peque\u00f1os por ser mi disc\u00edpulo\u201d que ser\u00e1 recompensado. En ese caso, el criterio del juicio no es mera filantrop\u00eda (a pesar de lo bueno que sea), sino la respuesta de la gente al reino de los cielos como lo han conocido en la persona de los \u201chermanos\u201d de Jes\u00fas.<\/p>\n<p>Notas. 34 El reino que ha sido preparado para vosotros puede referirse, sencillamente, a la entrada al reino de Jes\u00fas, pero el t\u00e9rmino heredad sugiere, m\u00e1s bien, que ellos mismos comparten la condici\u00f3n de reyes (como en 19:28), tal como una porci\u00f3n de la autoridad del maestro fue dada a los siervos fieles de los vv. 21, 23. 41, 46 Eterno puede significar \u201cque dura para siempre\u201d, pero m\u00e1s generalmente significa \u201cde la era venidera\u201d; es una declaraci\u00f3n de calidad en vez de duraci\u00f3n. Estos vers\u00edculos, por lo tanto, no resuelven la disputa entre aquellos que comprenden el infierno como un tormento consciente que no tiene fin, y aquellos que lo ven como aniquilamiento o la p\u00e9rdida de la existencia.<\/p>\n<h3 align='right'><i><b>Fuente: Nuevo Comentario B\u00edblico Siglo Veintiuno<\/b><\/i><\/h3>\n<p>REFERENCIAS CRUZADAS<\/p>\n<p>i 1224 Dan 7:13; Mat 16:27; Hch 1:11; Rev 1:7<\/p>\n<p>j 1225 Zac 14:5; Mat 13:41; Mat 19:28<\/p>\n<p>k 1226 Rev 3:21<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n del Nuevo Mundo<\/b><\/i><\/h3>\n<p><p> Hijo del Hombre.  V\u00e9ase coment. en 8:20. <\/p>\n<p><p> se sentar\u00e1&#8230;trono de su gloria.  En su segunda venida, Cristo establecer\u00e1 el reino milenario profetizado en el A.T. (2 S 7:16; Is 9:6\u2013 7; 11:1\u2013 10) y prometido a Mar\u00eda cuando Jes\u00fas naci\u00f3 (Lc 1:31\u2013 33).<\/p>\n<p><h3 align='right'><i><b>Fuente: La Biblia de las Am\u00e9ricas<\/b><\/i><\/h3>\n<p>\n31<strong> (1)<\/strong> <em> Pero <\/em> indica que los vs. 31-46 forman otra secci\u00f3n, la que trata de los gentiles.<\/p>\n<\/p>\n<p>\n31<strong> (2)<\/strong> <em> Hijo del Hombre <\/em> es el t\u00edtulo de Cristo en relaci\u00f3n con Su reino, el reino mesi\u00e1nico (13:41). Su juicio aqu\u00ed es una preparaci\u00f3n para ese reino.<\/p>\n<\/p>\n<p>\n31<strong> (3)<\/strong> Este es el aspecto visible de la venida del Se\u00f1or. (V\u00e9anse las notas 27<strong> (1)<\/strong> y 37<strong> (1)<\/strong> del cap.24.) Ser\u00e1 la continuaci\u00f3n de Su venida, mencionada en 24:30.<\/p>\n<\/p>\n<p>\n31<strong> (4)<\/strong> La gloria del Se\u00f1or consta de la gloria de Su divinidad ( Jua_17:22 , Jua_17:24), la gloria de Su humanidad ( Sal_45:3), la gloria de Su resurrecci\u00f3n ( Jua_7:39 ; Hch_3:13-15), y la gloria de Su ascensi\u00f3n ( Heb_2:9). <\/p>\n<\/p>\n<p>\n31<strong> (5)<\/strong> El trono de David ( Luc_1:32-33), el cual estar\u00e1 en Jerusal\u00e9n (19:28; Jer_3:17). <\/p>\n<\/p>\n<p>\n31<strong> (a)<\/strong> Mat_8:20 <\/p>\n<\/p>\n<p>\n31<strong> (b)<\/strong> Mat_16:27 ; Zac_14:5 ; Jud_1:14 <\/p>\n<\/p>\n<p>\n31<strong> (c) <\/strong> Mat_19:28 ; Luc_1:32-33 Jer_3:17 <\/p>\n<h3 align='right'><i><b>Fuente: Comentario Del Nuevo Testamento Versi\u00f3n Recobro<\/b><\/i><\/h3>\n<p>Este pasaje contiene una descripci\u00f3n que nuestro Se\u00f1or hizo del juicio final.<br \/>\nNotemos primero qui\u00e9n ser\u00e1 el Juez. Lo ser\u00e1 el Hijo del hombre, \u00f3 sea Jes\u00fas mismo. Que los creyentes piensen en esto y se consuelen. Aquel que se sentar\u00e1 en  el trono en el d\u00eda grande y terrible ser\u00e1 su Salvador, su Pastor, su Sumo Sacerdote, su Hermano, su Protector. Cuando lo vean no tendr\u00e1n por qu\u00e9 alarmarse.<br \/>\nQue los impenitentes piensen en esto y teman. Su Juez ser\u00e1 aquel mismo Jesucristo cuyo Evangelio desprecian ahora y cuyas exhortaciones reh\u00fasan o\u00edr. \u00a1Cuan  grande no ser\u00e1 al fin su turbaci\u00f3n si contin\u00faan en la incredulidad y mueren sin arrepentirse! Notemos, en segundo lugar, qui\u00e9nes ser\u00e1n juzgados. Se nos dice que ante Jesucristo se congregar\u00e1n todas las naciones.<br \/>\nTodos tendr\u00e1n que obedecer el llamamiento del Rey y presentarse \u00e1 recibir la sentencia. Los que no quisieron adorar \u00e1 Jesucristo en la tierra tendr\u00e1n que  comparecer ante su tribunal cuando venga \u00e1 juzgar al mundo.<br \/>\nTodos los que fueren juzgados ser\u00e1n divididos en dos grandes clases. No habr\u00e1 ya distinciones entre reyes y s\u00fabditos, entre amos y criados, entre cat\u00f3licos  romanos y protestantes. La conversi\u00f3n \u00f3 la impenitencia, la fe \u00f3 la carencia de ella ser\u00e1n los \u00fanicos distintivos en el \u00faltimo d\u00eda. Los que hubieren confiado en  Jesucristo ser\u00e1n colocados con las ovejas, \u00e1 su diestra; los que no hubieren confiado en El ser\u00e1n colocados con los cabritos, \u00e1 su siniestra.<br \/>\nNotemos, en tercer lugar, qu\u00e9 procedimiento se seguir\u00e1 en el juicio final. Los pormenores que incluye la descripci\u00f3n son varios.<br \/>\nSe proceder\u00e1 con arreglo \u00e1 las pruebas del caso. Las obras, y sobre todo las de caridad, ser\u00e1n los testigos. Lo que se indagar\u00e1 no ser\u00e1 meramente lo que  hubi\u00e9remos dicho, sino lo que hubi\u00e9remos hecho; no solamente lo que hubi\u00e9remos profesado, sino lo que hubi\u00e9remos practicado. Es cierto que nuestras obras  no pueden justificarnos, puesto que somos justificados por la fe sin las obras de la ley. Mas nuestra conducta ser\u00e1 la prueba de la sinceridad de nuestra fe. \u00abLa  fe si no tuviere obras es muerta por s\u00ed misma.\u00bb Jam 2:11.<br \/>\nEl juicio final ser\u00e1 motivo de gozo para los verdaderos creyentes. \u00c1 sus o\u00eddos llegar\u00e1n estas dulces palabras: \u00bb Venid, benditos de mi Padre, poseed el  reino.\u00bbEllos ser\u00e1n reconocidos por su Maestro ante el Padre y ante los santos \u00e1ngeles.<br \/>\nEse mismo acontecimiento ser\u00e1 motivo de turbaci\u00f3n para los impenitentes. \u00c1 sus o\u00eddos llegar\u00e1n esas terribles palabras: \u00abIdos de m\u00ed, malditos, al fuego  eterno.\u00bb Ser\u00e1n desechados por el Jefe de la iglesia ante el mundo congregado. Como sembraron en la carne, de la carne segar\u00e1n corrupci\u00f3n.<br \/>\nEn el juicio final se revelar\u00e1n de una manera muy prominente los caracteres de los justos, y los de los condenados. Los de la derecha estar\u00e1n a\u00fan revestidos de  humildad, y se maravillar\u00e1n de que se mencionen y se encomien sus obras. Los de la izquierda permanecer\u00e1n en la ceguedad y vanagloria espirituales. No  tendr\u00e1n conciencia de haber rechazado \u00e1 Jesucristo. \u00abSe\u00f1or,\u00bb dir\u00e1n ellos, \u00ab\u00bfcu\u00e1ndo te vimos hambriento, \u00f3 sediento, etc., y no te servimos?.<br \/>\nNotemos, por \u00faltimo, cu\u00e1les ser\u00e1n los resultados ulteriores del d\u00eda del juicio. Se nos ha revelado esto en palabras que no debi\u00e9ramos olvidar jam\u00e1s: \u00bb E ir\u00e1n  estos (los malos) al suplicio eterno, y los justos \u00e1 la vida eterna..<br \/>\nEl estado de los hombres despu\u00e9s del juicio es inmutable y eterno. Ni los sufrimientos de los condenados ni la bienaventuranza de los justos tendr\u00e1n fin. Esta  verdad ha sido claramente revelada en la sagrada Escritura. La eternidad de Dios, del cielo y del infierno descansa sobre la misma base. Tan cierto es que habr\u00e1 en el cielo un d\u00eda sin t\u00e9rmino, y en el infierno una noche de infinita duraci\u00f3n, como que Dios es eterno.<br \/>\n\u00bfQui\u00e9n podr\u00e1 describir la felicidad de la vida eterna? El hombre no alcanza \u00e1 concebirla. Solo se puede medirla por medio del contraste y de la comparaci\u00f3n.<br \/>\nUn descanso eterno despu\u00e9s de combates y conflictos; la sociedad eterna de los santos despu\u00e9s de pugnar con un mundo perverso: un cuerpo glorioso y sin  dolor despu\u00e9s de luchar con enfermedades y flaquezas; la contemplaci\u00f3n del rostro de Jes\u00fas despu\u00e9s de haber vivido por la fe: todo esto es dicha, en verdad.<br \/>\n\u00bfQui\u00e9n podr\u00e1 describir los horrores de las penas eternas? Son indescriptibles, porque son inconcebibles. El padecer sin tregua del cuerpo; el aguij\u00f3n constante  de una conciencia culpable; la sociedad eterna de los malos, del demonio y sus \u00e1ngeles; el recuerdo indeleble de haber hecho escarnio del Salvador y de no  haber aprovechado muchas oportunidades; la expectativa interminable de penas sin interrupci\u00f3n, de porvenir sin esperanza.<br \/>\nAl terminar el cap\u00edtulo hag\u00e1monos esta seria pregunta: \u00ab\u00bfEn qu\u00e9 lado es probable que estemos en el d\u00eda postrero&#8211;en el  derecho \u00f3 en el izquierdo?.<\/p>\n<h3 align='right'><i><b>Fuente: Los Evangelios Explicados<\/b><\/i><\/h3>\n<p><i><b>\u00e1ngeles&#8230;<\/b><\/i> M\u2193 <i>santos \u00e1ngeles<\/i> \u2192 <span style=\"color:#008000\"><span class=\"bible\">Mat 16:27<\/span>; <span class=\"bible\">Mat 19:28<\/span><\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: Biblia Textual IV Edici\u00f3n<\/b><\/i><\/h3>\n<p>M i a\u00f1aden <em>santos.<\/em><\/p>\n<p> 25.31 g 16.27.<\/p>\n<p> 25.31 g 19.28.<\/p>\n<h3 align='right'><i><b>Fuente: La Biblia Textual III Edici\u00f3n<\/b><\/i><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Cuando el Hijo del Hombre venga en su gloria y todos los \u00e1ngeles con \u00e9l, entonces se sentar\u00e1 sobre el trono de su gloria; 25:31 Cuando el Hijo del Hombre venga en su gloria, y todos los santos \u00e1ngeles con \u00e9l, entonces se sentar\u00e1 en su trono de gloria, \u2014 Habla con toda confianza de &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/comentario-de-mateo-2531-exegesis-y-hermeneutica-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abComentario de Mateo 25:31 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-24668","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/24668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=24668"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/24668\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=24668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=24668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=24668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}