{"id":24689,"date":"2022-06-20T09:16:17","date_gmt":"2022-06-20T14:16:17","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/comentario-de-mateo-266-exegesis-y-hermeneutica-de-la-biblia\/"},"modified":"2022-06-20T09:16:17","modified_gmt":"2022-06-20T14:16:17","slug":"comentario-de-mateo-266-exegesis-y-hermeneutica-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/comentario-de-mateo-266-exegesis-y-hermeneutica-de-la-biblia\/","title":{"rendered":"Comentario de Mateo 26:6 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia"},"content":{"rendered":"<h3 align='center'><b><i>Estando Jes\u00fas en Betania, en casa de Sim\u00f3n el leproso,<\/i><\/b><\/h3>\n<p \/><span>26:6<\/span> Y estando Jes\u00fas en Betania, en casa de Sim\u00f3n el leproso, \u2014 Seg\u00fan <span>Lev 13:1-59<\/span>, \u201c45 Y el leproso en quien hubiere llaga llevar\u00e1 vestidos rasgados y su cabeza descubierta, y embozado pregonar\u00e1: \u00a1Inmundo! \u00a1inmundo! 46 Todo el tiempo que la llaga estuviere en \u00e9l, ser\u00e1 inmundo; estar\u00e1 impuro, y habitar\u00e1 solo; fuera del campamento ser\u00e1 su morada\u201d. Es obvio, pues, que Sim\u00f3n era un ex leproso. Es muy posible que Jes\u00fas lo hubiera limpiado. Todav\u00eda se llamaba \u00abel leproso\u00bb, de la manera que Rahab siempre se llamaba la ramera.<\/p>\n<p \/> Comp\u00e1rese <span>Jua 12:1-8<\/span>. El tiempo exacto de esta cena no se puede saber. Algunos creen que en cuanto a la cronolog\u00eda correcta, este evento debe colocarse entre los cap\u00edtulos veinte y veintiuno (comp\u00e1rense <span>Mar 14:3-9<\/span>; <span>Jua 12:1-11<\/span>). Creen que Mateo y Marcos incluyen este evento en este lugar para conectarlo con la acci\u00f3n de Judas, el cual provey\u00f3 un plan para los jud\u00edos para la ejecuci\u00f3n de Jes\u00fas. McGarvey sigue la cronolog\u00eda de Juan y cree que esta cena ocurri\u00f3 en la noche al terminar el s\u00e1bado, la noche antes de la Entrada Triunfal que ocurri\u00f3 el domingo de la semana en la cual se crucific\u00f3. Seg\u00fan esto, <span>Mat 26:6<\/span> no fija el tiempo exacto de este evento y no sigue en orden cronol\u00f3gico los vers\u00edculos 1-5.<\/p>\n<p \/>\n<h3 align='right'><i><b>Fuente: Comentario al Nuevo Testamento por Partain<\/b><\/i><\/h3>\n<p><b><i>en Betania.<\/i><\/b> <span class='bible'>Mat 21:17<\/span>; <span class='bible'>Mar 11:12<\/span>; <span class='bible'>Jua 11:1<\/span>, <span class='bible'>Jua 11:2<\/span>; <span class='bible'>Jua 12:1<\/span>. <\/p>\n<p><b><i>en casa de Sim\u00f3n el leproso.<\/i><\/b> <span class='bible'>Mar 14:3<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: El Tesoro del Conocimiento B\u00edblico<\/b><\/i><\/h3>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\">Aparentemente Jes\u00fas pas\u00f3 sus noches en\u00a0<\/span><span style=\"font-weight:bold\">Betania<\/span>, a unos pocos kil\u00f3metros fuera de Jerusal\u00e9n, sobre el Monte de los Olivos.<\/span><\/p>\n<p> <\/p>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\"><span style=\"font-weight:bold\">Sim\u00f3n<\/span>\u00a0era un leproso que evidentemente hab\u00eda sido limpiado por Jes\u00fas. Podr\u00eda ser el padre de L\u00e1zaro, Mar\u00eda y Marta (<\/span><span style=\"color:#008000\"><span class='bible'>Jua 12:1<\/span><\/span>,<\/span> <span style=\"color:#008000\"><span class='bible'>Jua 12:2<\/span><\/span>).<\/span><\/p>\n<p><\/p>\n<h3 align='right'><i><b>Fuente: Nuevo Comentario Ilustrado de la Biblia Caribe<\/b><\/i><\/h3>\n<p><b>Sim\u00f3n el leproso.<\/b> Seguramente fue alguien a quien Jes\u00fas hab\u00eda sanado de la lepra. Los leprosos eran tenidos por impuros y, por esto, no se les permit\u00eda socializar con las dem\u00e1s personas e incluso vivir en las ciudades. <i>Vea la nota sobre<\/i> <span class='bible'>Lev 13:2<\/span> <i>para conocer m\u00e1s sobre la lepra.<\/i><\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio MacArthur<\/b><\/i><\/h3>\n<p>26:6 Y estando Jes\u00fas en Betania, en casa de Sim\u00f3n el leproso, &#8212; Seg\u00fan Lev 13:1-59, \u201c45 Y el leproso en quien hubiere llaga llevar\u00e1 vestidos rasgados y su cabeza descubierta, y embozado pregonar\u00e1: \u00a1Inmundo! \u00a1inmundo! 46 Todo el tiempo que la llaga estuviere en \u00e9l, ser\u00e1 inmundo; estar\u00e1 impuro, y habitar\u00e1 solo; fuera del campamento ser\u00e1 su morada\u201d. Es obvio, pues, que Sim\u00f3n era un ex leproso. Es muy posible que Jes\u00fas lo hubiera limpiado. Todav\u00eda se llamaba \u00abel leproso\u00bb, de la manera que Rahab siempre se llamaba la ramera.<br \/>\n\tComp\u00e1rese Jua 12:1-8. El tiempo exacto de esta cena no se puede saber. Algunos creen que en cuanto a la cronolog\u00eda correcta, este evento debe colocarse entre los cap\u00edtulos veinte y veintiuno (comp\u00e1rense Mar 14:3-9; Jua 12:1-11). Creen que Mateo y Marcos incluyen este evento en este lugar para conectarlo con la acci\u00f3n de Judas, el cual provey\u00f3 un plan para los jud\u00edos para la ejecuci\u00f3n de Jes\u00fas. McGarvey sigue la cronolog\u00eda de Juan y cree que esta cena ocurri\u00f3 en la noche al terminar el s\u00e1bado, la noche antes de la Entrada Triunfal que ocurri\u00f3 el domingo de la semana en la cual se crucific\u00f3. Seg\u00fan esto, Mat 26:6 no fija el tiempo exacto de este evento y no sigue en orden cronol\u00f3gico los vers\u00edculos 1-5.<\/p>\n<h3 align='right'><i><b>Fuente: Notas Reeves-Partain<\/b><\/i><\/h3>\n<p><strong><u>LA PRODIGALIDAD DEL AMOR<\/u><\/strong><\/p>\n<\/p>\n<p><strong><span class='bible'>Mateo 26:6-13<\/span><\/strong><\/p>\n<\/p>\n<p><em>Estando Jes\u00fas en Betania, en la casa de Sim\u00f3n el leproso, se Le acerc\u00f3 una mujer con un pomito de alabastro lleno de un perfume muy costoso, y lo verti\u00f3 sobre la cabeza de Jes\u00fas cuando estaba reclinado a la mesa. Cuando los disc\u00edpulos vieron aquello, se disgustaron mucho, y se pusieron a decir:<br \/>-\u00bfPara qu\u00e9 sirve este derroche? Ese perfume se habr\u00eda podido vender por mucho dinero, y hab\u00e9rselo dado a los pobres.<\/em><\/p>\n<p><em>Jes\u00fas sab\u00eda lo que estaban hablando, y les dijo:<br \/>\u00bfPor qu\u00e9 os met\u00e9is con esta mujer? Lo que ha hecho conmigo ha sido una cosa preciosa; porque a los pobres siempre los ten\u00e9is, pero a M\u00ed no Me vais a tener siempre. Al derramar este perfume sobre Mi cuerpo lo ha hecho para prepararme de antemano para el entierro. Pod\u00e9is creerme que, dondequiera que se predique el Evangelio por todo el mundo, se recordar\u00e1 esto que ha hecho ella en su memoria.<\/em><\/p>\n<\/p>\n<p>La historia de la unci\u00f3n en Betania nos la cuentan tambi\u00e9n Marcos y Juan. El relato de Marcos es casi .exactamente el mismo que el de Mateo; pero Juan a\u00f1ade el detalle significativo de que la mujer que ungi\u00f3 a Jes\u00fas fue nada menos que Mar\u00eda, la hermana de Marta y de L\u00e1zaro. Lucas no nos cuenta esta historia, pero s\u00ed la de la unci\u00f3n en la casa de Sim\u00f3n el fariseo<span class='bible'> <\/span><span class='bible'>Lc 7:36<\/span><em> -SO); pero en la historia de Lucas la mujer que ungi\u00f3 los pies de Jes\u00fas y los enjug\u00f3 con sus cabellos era una conocida pecadora.<\/em><\/p>\n<p><em>Siempre quedar\u00e1 la interesante posibilidad de que la historia que nos cuenta Lucas sea la misma que nos cuentan los otros tres evangelistas. En ambos casos el nombre del anfitri\u00f3n es Sim\u00f3n, aunque en Lucas <\/em>es Sim\u00f3n el fariseo, mientras que en <em>Mateo y Marcos <\/em>es Sim\u00f3n el leproso. En Juan, el anfitri\u00f3n no se nombra, aunque el relato parece dar la impresi\u00f3n de que se trataba de la casa de Marta y Mar\u00eda y L\u00e1zaro. Sim\u00f3n era un nombre muy corriente. Hay por lo menos diez Simones en el Nuevo Testamento, y m\u00e1s de veinte en el libro de historia de Josefo. La mayor dificultad para identificar las historias de Lucas y de los otros tres evangelistas es que Lucas nos dice que la mujer era una conocida pecadora, y no tenemos la menor indicaci\u00f3n de que ese fuera el caso de Mar\u00eda de Betania. Por otra parte, la misma intensidad con que Mar\u00eda amaba a Jes\u00fas podr\u00eda sugerir las profundidades de las que \u00c9l la rescat\u00f3.<\/p>\n<p>Sea cual fuere la respuesta que se d\u00e9 a la cuesti\u00f3n de la identificaci\u00f3n, la historia es desde luego lo que Jes\u00fas la llam\u00f3: la historia de una cosa muy hermosa; y nos atesora ciertas verdades muy preciosas.<br \/>(i) Nos muestra <em>la prodigalidad <\/em>del amor. La mujer tom\u00f3 lo m\u00e1s precioso que ten\u00eda; y se lo derram\u00f3 a Jes\u00fas en la cabeza. A las mujeres jud\u00edas les encantaban los perfumes; y era corriente que llevaran un frasquito de alabastro con perfume corriente en el collar. Ese perfume era muy costoso. Tanto Marcos como Juan nos relatan que los disc\u00edpulos dijeron que ese perfume podr\u00eda haberse vendido por trescientos <em>denarios (<\/em><em><span class='bible'>Marcos 14<\/span><\/em><em>: S; <\/em>Jbi12: S); lo que quiere decir que ese frasquito de perfume representaba casi el sueldo de un a\u00f1o de un obrero. O podemos verlo<\/p>\n<p>de esta otra manera. Cuando Jes\u00fas -y Sus disc\u00edpulos estaba hablando de c\u00f3mo se podr\u00eda dar de comer a la multitud, la respuesta de Felipe fue que 200 <em>denarios <\/em>apenas bastar\u00edan para alimentarlos. Este frasco de perfume, por tanto, costaba tantos como la comida necesaria para cinco mil personas:<\/p>\n<p>Era algo tan precioso como todo eso lo que esta mujer U dio a Jes\u00fas, y Se lo dio porque era lo m\u00e1s precioso que ten\u00eda. El amor nunca calcula; al amor siempre le parece demasiado poco todo lo que da; el \u00fanico deseo del amor es dar hasta &#8216;lo \u00faltimo; y, cuando ha dado todo lo que ten\u00eda, a\u00fan le parece demasiado poco. No hemos ni empezado a ser cristianos si pensamos en darle a Cristo y a Su Iglesia lo menos que resulte aceptable.<br \/>(ii) Nos muestra que hay momentos en los que se falla viendo las cosas con sentido com\u00fan. En esta ocasi\u00f3n, la voz del sentido com\u00fan dec\u00eda: \u00ab\u00a1Qu\u00e9 derroche!\u00bb Y no hay duda que era verdad. Pero hay un mundo de diferencia entre la econom\u00eda del sentido com\u00fan y la econom\u00eda del amor. El sentido com\u00fan obedece los dictados de la prudencia; pero el amor obedece los dictados del coraz\u00f3n. En la vida hay que aplicar el sentido com\u00fan en muchos casos; pero hay momentos en los que solo la prodigalidad puede satisfacer las demandas del amor. Un regalo no es nunca realmente un regalo cuando es algo que nos podemos permitir f\u00e1cilmente; un regalo llega a ser un regalo solamente cuando implica un sacrificio, y cuando damos mucho m\u00e1s de lo que podemos permitimos.<br \/>(iii) Nos muestra que algunas cosas han de hacerse cuando surge la oportunidad, o no se har\u00e1n nunca. Los disc\u00edpulos estaban interesados en ayudar a los pobres; pero los mismos rabinos dec\u00edan: \u00abDios permite que haya pobres siempre con nosotros para que no nos falten nunca las oportunidades para hacerles bien.\u00bb Hay algunas cosas que podemos hacer en cualquier momento; hay algunas cosas que podemos hacer solo una vez; y el desaprovechar la ocasi\u00f3n de hacerlas entonces es perder la oportunidad para siempre. A menudo nos sentimos movidos por un impulso generoso, pero no nos dejamos llevar por \u00e9l; y todas las posibilidades est\u00e1n en contra de que se nos vuelvan a presentar las circunstancias, la .persona, el tiempo y el impulso. Para muchos de nosotros lo tr\u00e1gico es que nuestra vida es la historia de las oportunidades de hacer el bien que no hemos aprovechado.<br \/>(iv) Nos dice que la fragancia de una acci\u00f3n hermosa no se desvanece nunca. Hay tan pocas cosas hermosas, que cada una brilla como una luz en un mundo .oscuro&#8230; Al final de la vida de Jes\u00fas hab\u00eda tanta amargura, tanta traici\u00f3n, tanta intriga, tanta tragedia, que esta historia brilla como un oasis de luz en un mundo tenebroso. En este mundo hay pocas cosas m\u00e1s grandes que se puedan hacer que dejar el recuerdo de una obra hermosa.<\/p>\n<\/p>\n<p><strong>LAS \u00daLTIMAS HORAS DE LA VIDA DEL TRAIDOR<\/strong><\/p>\n<\/p>\n<p>En vez de seguir la historia de Judas por trozos como aparece en el relato evang\u00e9lico, la tomaremos en conjunto leyendo uno tras otro los \u00faltimos incidentes hasta el suicidio del traidor.<\/p>\n<h3 align='right'><i><b>Fuente: Comentario al Nuevo Testamento<\/b><\/i><\/h3>\n<p><i><b>\u2014 Betania:<\/b><\/i> Ver nota a <span class='bible'>Mat 21:17<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n Interconfesional HispanoAmericana<\/b><\/i><\/h3>\n<p><span class='bible'>Luc 7:36-37<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n Interconfesional HispanoAmericana<\/b><\/i><\/h3>\n<p>Ungimiento en Betania (ver Mar. 14:3-9;  cf. Luc. 7:36-50). El ungimiento sugiere el papel de Jes\u00fas como el Mes\u00edas (palabra que significa \u201cel ungido\u201d), pero, a la vez, presagia su muerte (12). El acto extravagante de la mujer simboliza el sufrimiento mesi\u00e1nico de Jes\u00fas que se avecinaba. Fue un acto de amor y devoci\u00f3n, una buena obra, a pesar de su mensaje horrendo. Pero los disc\u00edpulos s\u00f3lo pod\u00edan ver el desperdicio. La respuesta de Jes\u00fas no tuvo la intenci\u00f3n de minimizar el cuidado de los pobres; el v. 11 infiere que esto ser\u00eda un inter\u00e9s continuo de sus seguidores. Pero aun este inter\u00e9s correcto podr\u00eda conducir a errores, si eliminara la extravagancia espont\u00e1nea del amor en las circunstancias especiales del sacrificio del Maestro que se aproximaba. Los actos individuales de caridad pueden ser olvidados pronto, pero lo que esta mujer ha hecho permanecer\u00eda como un modelo de devoci\u00f3n dondequiera que este evangelio sea predicado (cf. 24:14).<\/p>\n<p>Notas. 6 Betania era el hogar de Marta y Mar\u00eda, y Juan 12:3 dice que la mujer era Mar\u00eda. Este Sim\u00f3n es un desconocido; quiz\u00e1 Jes\u00fas lo hab\u00eda curado de su lepra. 7 El perfume era nardo, un aceite importado de la India, que a veces se usaba para ungir a los muertos (por ende v. 12), pero tambi\u00e9n era valorado como un cosm\u00e9tico de lujo.<\/p>\n<h3 align='right'><i><b>Fuente: Nuevo Comentario B\u00edblico Siglo Veintiuno<\/b><\/i><\/h3>\n<p>REFERENCIAS CRUZADAS<\/p>\n<p>f 1263 Mat 21:17<\/p>\n<p>g 1264 Mat 8:2<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n del Nuevo Mundo<\/b><\/i><\/h3>\n<p>\n6<strong> (1)<\/strong> Un leproso representa un pecador (8:2 y la nota 1), Sim\u00f3n, el leproso, debe de haber sido el que fue sanado por el Se\u00f1or. Por agradecimiento al Se\u00f1or y por amor a El, prepar\u00f3 una fiesta (v.7) en su casa para el Se\u00f1or y Sus disc\u00edpulos con el fin de disfrutar Su presencia. Un pecador salvo siempre hace eso.<\/p>\n<\/p>\n<p>\n6<strong> (a)<\/strong> vs.6-13: Mar_14:3-9 ; Jua_12:1-8 ; cfr. Luc_7:36-39 <\/p>\n<\/p>\n<p>\n6<strong> (b)<\/strong> Mat_21:17 ; Jua_11:1 , Jua_11:18 <\/p>\n<h3 align='right'><i><b>Fuente: Comentario Del Nuevo Testamento Versi\u00f3n Recobro<\/b><\/i><\/h3>\n<p><b><i>Sim\u00f3n el leproso<\/i><\/b>. Nada m\u00e1s se sabe de \u00e9l. Quiz\u00e1 le hab\u00eda sanado Cristo.<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio Anotada por Ryrie<\/b><\/i><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Estando Jes\u00fas en Betania, en casa de Sim\u00f3n el leproso, 26:6 Y estando Jes\u00fas en Betania, en casa de Sim\u00f3n el leproso, \u2014 Seg\u00fan Lev 13:1-59, \u201c45 Y el leproso en quien hubiere llaga llevar\u00e1 vestidos rasgados y su cabeza descubierta, y embozado pregonar\u00e1: \u00a1Inmundo! \u00a1inmundo! 46 Todo el tiempo que la llaga estuviere en &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/comentario-de-mateo-266-exegesis-y-hermeneutica-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abComentario de Mateo 26:6 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-24689","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/24689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=24689"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/24689\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=24689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=24689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=24689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}