{"id":24692,"date":"2022-06-20T09:16:26","date_gmt":"2022-06-20T14:16:26","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/comentario-de-mateo-269-exegesis-y-hermeneutica-de-la-biblia\/"},"modified":"2022-06-20T09:16:26","modified_gmt":"2022-06-20T14:16:26","slug":"comentario-de-mateo-269-exegesis-y-hermeneutica-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/comentario-de-mateo-269-exegesis-y-hermeneutica-de-la-biblia\/","title":{"rendered":"Comentario de Mateo 26:9 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia"},"content":{"rendered":"<h3 align='center'><b><i>Porque esto podr\u00eda haberse vendido a un gran precio y haberse dado a los pobres.<\/i><\/b><\/h3>\n<p \/><span>26:9<\/span> Porque esto pod\u00eda haberse vendido a gran precio, \u2014 <span>Mar 14:5<\/span>, \u00abm\u00e1s de trescientos denarios\u00bb, el sueldo de un d\u00eda de trabajo era un denario (<span>Mat 20:2<\/span>). <span>Jua 6:7<\/span>, Felipe dice, \u00abDoscientos denarios de pan no bastar\u00edan para que cada uno de ellos tomase un poco\u00bb (hablando de la alimentaci\u00f3n de los cinco mil). La ofrenda de Mar\u00eda val\u00eda aproximadamente el salario de un jornaleros para un a\u00f1o. Es muy posible que le costara a Mar\u00eda todos los ahorros. \u201cMar\u00eda hubiera tenido que ahorrar veinte denarios por a\u00f1o por quince a\u00f1os para juntar esta cantidad\u201d (HF).<\/p>\n<p \/>\n<p \/>\u2014 y haberse dado a los pobres. \u2014 <span>Jua 12:5-6<\/span>; <span>Jua 13:29<\/span>. Jes\u00fas amaba a los pobres intensamente. Ayudar a los pobres era uno de los temas fundamentales de la ense\u00f1anza y pr\u00e1ctica de Jes\u00fas. En el discurso anterior dijo claramente que El se identificaba con los disc\u00edpulos necesitados, aun con los m\u00e1s peque\u00f1os. Entonces preguntamos: \u00bfJes\u00fas permiti\u00f3 una injusticia contra los pobres? \u00bfJudas era el amigo y campe\u00f3n de los pobres? \u00bfJudas era el que sab\u00eda lo que correcto y justo, y defendi\u00f3 los derechos de los pobres? Si Mar\u00eda hubiera vendido el perfume para entregar el dinero a Judas, \u00bflo habr\u00eda regalado a los pobres?<\/p>\n<p \/> \u2014 Marcos: \u00abY murmuraban contra ella\u00bb. Implican que Mar\u00eda no amaba a los pobres, que era indiferente hacia las necesidades de ellos. Pero \u00bfde qui\u00e9n era el perfume? Era la propiedad de Mar\u00eda y ella pod\u00eda usarlo como ella juzgara mejor. \u00bfSe habr\u00edan quejado si Mar\u00eda hubiera vendido este perfume para comprar calzado, ropa, comida, muebles y cortinas para la casa? Seg\u00fan el mundo el cristiano \u00abdesperdicia\u00bb su dinero cuando lo da al Se\u00f1or. Seguramente Judas habr\u00eda criticado a los de Jerusal\u00e9n (<span>Hch 2:45<\/span>; <span>Hch 4:32<\/span>), a los macedonios (<span>2Co 8:4-5<\/span>) y a la pobre viuda (<span>Mar 12:43-44<\/span>).<\/p>\n<p \/> En todo esto Mar\u00eda no dijo nada (que sepamos). No tuvo que hablar, porque su hecho habl\u00f3 por s\u00ed mismo.<\/p>\n<p \/>\n<h3 align='right'><i><b>Fuente: Comentario al Nuevo Testamento por Partain<\/b><\/i><\/h3>\n<p><span class='bible'>Jos 7:20<\/span>, <span class='bible'>Jos 7:21<\/span>; <span class='bible'>1Sa 15:9<\/span>, <span class='bible'>1Sa 15:21<\/span>; <span class='bible'>2Re 5:20<\/span>; <span class='bible'>Mar 14:5<\/span>; <span class='bible'>Jua 12:5<\/span>, <span class='bible'>Jua 12:6<\/span>; <span class='bible'>2Pe 2:15<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: El Tesoro del Conocimiento B\u00edblico<\/b><\/i><\/h3>\n<p>26:9 Porque esto pod\u00eda haberse vendido a gran precio, &#8212; Mar 14:5, \u00abm\u00e1s de trescientos denarios\u00bb, el sueldo de un d\u00eda de trabajo era un denario (Mat 20:2). Jua 6:7, Felipe dice, \u00abDoscientos denarios de pan no bastar\u00edan para que cada uno de ellos tomase un poco\u00bb (hablando de la alimentaci\u00f3n de los cinco mil). La ofrenda de Mar\u00eda val\u00eda aproximadamente el salario de un jornaleros para un a\u00f1o. Es muy posible que le costara a Mar\u00eda todos los ahorros. \u201cMar\u00eda hubiera tenido que ahorrar veinte denarios por a\u00f1o por quince a\u00f1os para juntar esta cantidad\u201d (HF).<br \/>\n\t&#8212; y haberse dado a los pobres. &#8212; Jua 12:5-6; Jua 13:29. Jes\u00fas amaba a los pobres intensamente. Ayudar a los pobres era uno de los temas fundamentales de la ense\u00f1anza y pr\u00e1ctica de Jes\u00fas. En el discurso anterior dijo claramente que El se identificaba con los disc\u00edpulos necesitados, aun con los m\u00e1s peque\u00f1os. Entonces preguntamos: \u00bfJes\u00fas permiti\u00f3 una injusticia contra los pobres? \u00bfJudas era el amigo y campe\u00f3n de los pobres? \u00bfJudas era el que sab\u00eda lo que correcto y justo, y defendi\u00f3 los derechos de los pobres? Si Mar\u00eda hubiera vendido el perfume para entregar el dinero a Judas, \u00bflo habr\u00eda regalado a los pobres?<br \/>\n\t&#8212; Marcos: \u00abY murmuraban contra ella\u00bb. Implican que Mar\u00eda no amaba a los pobres, que era indiferente hacia las necesidades de ellos. Pero \u00bfde qui\u00e9n era el perfume? Era la propiedad de Mar\u00eda y ella pod\u00eda usarlo como ella juzgara mejor. \u00bfSe habr\u00edan quejado si Mar\u00eda hubiera vendido este perfume para comprar calzado, ropa, comida, muebles y cortinas para la casa? Seg\u00fan el mundo el cristiano \u00abdesperdicia\u00bb su dinero cuando lo da al Se\u00f1or. Seguramente Judas habr\u00eda criticado a los de Jerusal\u00e9n (Hch 2:45; Hch 4:32), a los macedonios (2Co 8:4-5) y a la pobre viuda (Mar 12:43-44).<br \/>\n\tEn todo esto Mar\u00eda no dijo nada (que sepamos). No tuvo que hablar, porque su hecho habl\u00f3 por s\u00ed mismo.<\/p>\n<h3 align='right'><i><b>Fuente: Notas Reeves-Partain<\/b><\/i><\/h3>\n<p>REFERENCIAS CRUZADAS<\/p>\n<p>j 1267 Mar 14:5; Jua 12:5<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n del Nuevo Mundo<\/b><\/i><\/h3>\n<p>\n9<strong> (a)<\/strong> Jua_13:29 <\/p>\n<h3 align='right'><i><b>Fuente: Comentario Del Nuevo Testamento Versi\u00f3n Recobro<\/b><\/i><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Porque esto podr\u00eda haberse vendido a un gran precio y haberse dado a los pobres. 26:9 Porque esto pod\u00eda haberse vendido a gran precio, \u2014 Mar 14:5, \u00abm\u00e1s de trescientos denarios\u00bb, el sueldo de un d\u00eda de trabajo era un denario (Mat 20:2). Jua 6:7, Felipe dice, \u00abDoscientos denarios de pan no bastar\u00edan para que &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/comentario-de-mateo-269-exegesis-y-hermeneutica-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abComentario de Mateo 26:9 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-24692","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/24692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=24692"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/24692\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=24692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=24692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=24692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}