{"id":24693,"date":"2022-06-20T09:16:28","date_gmt":"2022-06-20T14:16:28","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/comentario-de-mateo-2610-exegesis-y-hermeneutica-de-la-biblia\/"},"modified":"2022-06-20T09:16:28","modified_gmt":"2022-06-20T14:16:28","slug":"comentario-de-mateo-2610-exegesis-y-hermeneutica-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/comentario-de-mateo-2610-exegesis-y-hermeneutica-de-la-biblia\/","title":{"rendered":"Comentario de Mateo 26:10 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia"},"content":{"rendered":"<h3 align='center'><b><i>Como Jes\u00fas se dio cuenta, les dijo: \u2014\u00bfPor qu\u00e9 molest\u00e1is a la mujer? Pues ha hecho una buena obra conmigo.<\/i><\/b><\/h3>\n<p \/>26: 10 Y entendi\u00e9ndolo Jes\u00fas, les dijo: \u00bfPor qu\u00e9 molest\u00e1is a esta mujer? pues ha hecho conmigo una buena obra. \u2014 de amor, gratitud, simpat\u00eda. <span>Mar 14:8<\/span>, \u00abha hecho lo que pod\u00eda\u00bb. <span>Mat 25:40<\/span> habla de servir a Jes\u00fas indirectamente; pero en este acto Mar\u00eda le honr\u00f3 directamente. \u00bfQu\u00e9 dice esta buena obra acerca de la fe de Mar\u00eda? Ella sab\u00eda qui\u00e9n era Jes\u00fas, que no era otro rab\u00ed m\u00e1s entre los jud\u00edos, sino el Cristo de Dios.<\/p>\n<p \/>\n<h3 align='right'><i><b>Fuente: Comentario al Nuevo Testamento por Partain<\/b><\/i><\/h3>\n<p><b><i>\u00bfPor qu\u00e9 molest\u00e1is a esta mujer?<\/i><\/b> <span class='bible'>Job 13:7<\/span>; <span class='bible'>Mar 14:6<\/span>; <span class='bible'>Luc 7:44-50<\/span>; <span class='bible'>G\u00e1l 1:7<\/span>; <span class='bible'>G\u00e1l 5:12<\/span>; <span class='bible'>G\u00e1l 6:17<\/span>.<\/p>\n<p><b><i>ha hecho conmigo una buena obra.<\/i><\/b> <span class='bible'>Neh 2:18<\/span>; <span class='bible'>2Co 9:8<\/span>; <span class='bible'>Efe 2:10<\/span>; <span class='bible'>Col 1:10<\/span>; <span class='bible'>2Ts 2:17<\/span>; <span class='bible'>1Ti 3:1<\/span>; <span class='bible'>1Ti 5:10<\/span>; <span class='bible'>2Ti 2:21<\/span>; <span class='bible'>Tit 1:16<\/span>; <span class='bible'>Tit 2:14<\/span>; <span class='bible'>Tit 3:1<\/span>, <span class='bible'>Tit 3:8<\/span>, <span class='bible'>Tit 3:14<\/span>; <span class='bible'>Heb 13:21<\/span>; <span class='bible'>1Pe 2:12<\/span>. <\/p>\n<h3 align='right'><i><b>Fuente: El Tesoro del Conocimiento B\u00edblico<\/b><\/i><\/h3>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\">Jes\u00fas consider\u00f3 el derramamiento del\u00a0<\/span><span style=\"font-weight:bold\">perfume<\/span>\u00a0sobre su cuerpo como un anuncio de su muerte (<\/span><span style=\"color:#008000\"><span class='bible'>Mar 14:8<\/span><\/span>). El b\u00e1lsamo perfumado fue vertido sobre su cuerpo antes de su muerte; normalmente se habr\u00eda usado despu\u00e9s de su muerte. El costoso aceite se\u00f1ala<\/span><\/p>\n<p><\/p>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\">(1) el valor de la muerte de Jes\u00fas y<\/p>\n<p><\/p>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\">(2) el alto costo de la devoci\u00f3n hacia \u00c9l.<\/p>\n<p><\/p>\n<h3 align='right'><i><b>Fuente: Nuevo Comentario Ilustrado de la Biblia Caribe<\/b><\/i><\/h3>\n<p>26: 10 Y entendi\u00e9ndolo Jes\u00fas, les dijo: \u00bfPor qu\u00e9 molest\u00e1is a esta mujer? pues ha hecho conmigo una buena obra. &#8211; de amor, gratitud, simpat\u00eda. Mar 14:8, \u00abha hecho lo que pod\u00eda\u00bb. Mat 25:40 habla de servir a Jes\u00fas indirectamente; pero en este acto Mar\u00eda le honr\u00f3 directamente. \u00bfQu\u00e9 dice esta buena obra acerca de la fe de Mar\u00eda? Ella sab\u00eda qui\u00e9n era Jes\u00fas, que no era otro rab\u00ed m\u00e1s entre los jud\u00edos, sino el Cristo de Dios.<\/p>\n<h3 align='right'><i><b>Fuente: Notas Reeves-Partain<\/b><\/i><\/h3>\n<p>REFERENCIAS CRUZADAS<\/p>\n<p>k 1268 Jua 12:6<\/p>\n<p>l 1269 Mar 14:6<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n del Nuevo Mundo<\/b><\/i><\/h3>\n<p>\n10<strong> (1)<\/strong> O, un acto de nobleza.<\/p>\n<h3 align='right'><i><b>Fuente: Comentario Del Nuevo Testamento Versi\u00f3n Recobro<\/b><\/i><\/h3>\n<p>M69 \u0395\u1f30\u03c2 \u1f10\u03bc\u03ad se usa en lugar de un simple dativo: a m\u00ed.<\/p>\n<p> MT116 \u1f28\u03c1\u03b3\u03ac\u03c3\u03b1\u03c4\u03bf se usa como un aoristo de acci\u00f3n definida, que hace hincapi\u00e9 en la actividad, y no en su producto. <\/p>\n<h3 align='right'><i><b>Fuente: Ayuda gramatical para el Estudio del Nuevo Testamento Griego<\/b><\/i><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Como Jes\u00fas se dio cuenta, les dijo: \u2014\u00bfPor qu\u00e9 molest\u00e1is a la mujer? Pues ha hecho una buena obra conmigo. 26: 10 Y entendi\u00e9ndolo Jes\u00fas, les dijo: \u00bfPor qu\u00e9 molest\u00e1is a esta mujer? pues ha hecho conmigo una buena obra. \u2014 de amor, gratitud, simpat\u00eda. Mar 14:8, \u00abha hecho lo que pod\u00eda\u00bb. Mat 25:40 habla &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/comentario-de-mateo-2610-exegesis-y-hermeneutica-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abComentario de Mateo 26:10 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-24693","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/24693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=24693"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/24693\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=24693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=24693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=24693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}