{"id":24695,"date":"2022-06-20T09:16:33","date_gmt":"2022-06-20T14:16:33","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/comentario-de-mateo-2612-exegesis-y-hermeneutica-de-la-biblia\/"},"modified":"2022-06-20T09:16:33","modified_gmt":"2022-06-20T14:16:33","slug":"comentario-de-mateo-2612-exegesis-y-hermeneutica-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/comentario-de-mateo-2612-exegesis-y-hermeneutica-de-la-biblia\/","title":{"rendered":"Comentario de Mateo 26:12 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia"},"content":{"rendered":"<h3 align='center'><b><i>Porque al derramar este perfume sobre mi cuerpo, ella lo hizo para prepararme para la sepultura.<\/i><\/b><\/h3>\n<p \/><span>26:12<\/span> Porque al derramar este perfume sobre mi cuerpo, lo ha hecho a fin de prepararme para la sepultura. \u2014 Comp\u00e1rese <span>Jua 19:39-40<\/span>; <span>Mar 16:1<\/span>. Les hab\u00eda dicho repetidas veces que los jud\u00edos le iban a matar; \u00bfera injusto que Mar\u00eda preparara su cuerpo para la sepultura? \u00bfSe quejaban de lo que se gastaba para su sepultura? \u00bfellos no se preocupaban por ello? \u00bfno les interesaba?<\/p>\n<p \/> Mar\u00eda aprovech\u00f3 este momento oportuno. Otras mujeres llevaron especias arom\u00e1ticas para el cuerpo de Jes\u00fas, pero las llevaron a una tumba vac\u00eda. Solamente Mar\u00eda ungi\u00f3 el cuerpo vivo del Se\u00f1or. Nosotros no podemos proveer perfume costoso para ungir el cuerpo f\u00edsico de Jes\u00fas, pero s\u00ed podemos ofrendar generosamente para el bien del cuerpo espiritual de Jes\u00fas.<\/p>\n<p \/> Jes\u00fas dedic\u00f3 su vida entera para prepararse para su muerte. <span>Luc 2:49<\/span>; <span>Luc 9:51<\/span>; <span>Jua 12:27<\/span>. <span>Mat 26:1-75<\/span> empieza el relato de las preparaciones finales para su muerte. <span>Jua 12:7<\/span>, \u00abpara el d\u00eda de mi sepultura ha guardado esto\u00bb, es decir, ha guardado (ha observado) esta ceremonia. Es posible que Mar\u00eda tambi\u00e9n entend\u00eda el significado de su acto. Recu\u00e9rdese que ella ungi\u00f3 no solamente su cabeza, sino tambi\u00e9n sus pies y, por lo tanto, Jes\u00fas dice \u00abse ha anticipado a ungir mi cuerpo para la sepultura\u00bb, <span>Mar 14:8<\/span>. Mar\u00eda escuchaba atentamente a Jes\u00fas (<span>Luc 10:42<\/span>). Era una disc\u00edpula verdadera.<\/p>\n<p \/>\n<h3 align='right'><i><b>Fuente: Comentario al Nuevo Testamento por Partain<\/b><\/i><\/h3>\n<p><span class='bible'>2Cr 16:14<\/span>; <span class='bible'>Mar 14:8<\/span>; <span class='bible'>Mar 16:1<\/span>; <span class='bible'>Luc 23:56<\/span>; <span class='bible'>Luc 24:1<\/span>; <span class='bible'>Jua 12:7<\/span>; <span class='bible'>Jua 19:39<\/span>, <span class='bible'>Jua 19:40<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: El Tesoro del Conocimiento B\u00edblico<\/b><\/i><\/h3>\n<p><b>lo ha hecho a fin de prepararme para la sepultura.<\/b> Esto no significa que Mar\u00eda estuviera plenamente consciente del significado de sus acciones. Es dudoso que ella supiera de su muerte cercana, o al menos lo pronto que ser\u00eda. Pero este fue, sin duda alguna, un acto sincero de adoraci\u00f3n. Su coraz\u00f3n fue movido por Dios para realizar un acto de sacrificio y simb\u00f3lico, cuyo pleno significado quiz\u00e1s ella misma no conoc\u00eda.<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio MacArthur<\/b><\/i><\/h3>\n<p>26:12 Porque al derramar este perfume sobre mi cuerpo, lo ha hecho a fin de prepararme para la sepultura. &#8211; Comp\u00e1rese Jua 19:39-40; Mar 16:1. Les hab\u00eda dicho repetidas veces que los jud\u00edos le iban a matar; \u00bfera injusto que Mar\u00eda preparara su cuerpo para la sepultura? \u00bfSe quejaban de lo que se gastaba para su sepultura? \u00bfellos no se preocupaban por ello? \u00bfno les interesaba?<br \/>\n\tMar\u00eda aprovech\u00f3 este momento oportuno. Otras mujeres llevaron especias arom\u00e1ticas para el cuerpo de Jes\u00fas, pero las llevaron a una tumba vac\u00eda. Solamente Mar\u00eda ungi\u00f3 el cuerpo vivo del Se\u00f1or. Nosotros no podemos proveer perfume costoso para ungir el cuerpo f\u00edsico de Jes\u00fas, pero s\u00ed podemos ofrendar generosamente para el bien del cuerpo espiritual de Jes\u00fas.<br \/>\n\tJes\u00fas dedic\u00f3 su vida entera para prepararse para su muerte. Luc 2:49; Luc 9:51; Jua 12:27. Mat 26:1-75 empieza el relato de las preparaciones finales para su muerte. Jua 12:7, \u00abpara el d\u00eda de mi sepultura ha guardado esto\u00bb, es decir, ha guardado (ha observado) esta ceremonia. Es posible que Mar\u00eda tambi\u00e9n entend\u00eda el significado de su acto. Recu\u00e9rdese que ella ungi\u00f3 no solamente su cabeza, sino tambi\u00e9n sus pies y, por lo tanto, Jes\u00fas dice \u00abse ha anticipado a ungir mi cuerpo para la sepultura\u00bb, Mar 14:8. Mar\u00eda escuchaba atentamente a Jes\u00fas (Luc 10:42). Era una disc\u00edpula verdadera.<\/p>\n<h3 align='right'><i><b>Fuente: Notas Reeves-Partain<\/b><\/i><\/h3>\n<p><i><b>\u2014 para el entierro:<\/b><\/i> El recibir honrosa sepultura era para los jud\u00edos algo muy importante. En consecuencia, quien preparaba adecuadamente el cad\u00e1ver mediante un esmerado proceso de embalsamamiento, llevaba a cabo una acci\u00f3n muy meritoria, tanto al menos como la de ayudar a los necesitados (ver <span class='bible'>3Ma 1:18-19<\/span>; <span class='bible'>3Ma 2:4-7<\/span>).<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n Interconfesional HispanoAmericana<\/b><\/i><\/h3>\n<p>REFERENCIAS CRUZADAS<\/p>\n<p>\u00f1 1272 Mar 14:8; Jua 12:7<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n del Nuevo Mundo<\/b><\/i><\/h3>\n<p><p> prepararme para la sepultura.  Es evidente que Mar\u00eda entendi\u00f3 las predicciones de Jes\u00fas acerca de su muerte (16:21; 17:22; 20:17\u2013 19), y en contraste con los disc\u00edpulos, ella acept\u00f3 y comprendi\u00f3 las profec\u00edas. El ungimiento de Mar\u00eda (Jn 12:3) fue un acto prof\u00e9tico que anticip\u00f3 la muerte y sepultura de Jes\u00fas (Jn 19:40).<\/p>\n<p><h3 align='right'><i><b>Fuente: La Biblia de las Am\u00e9ricas<\/b><\/i><\/h3>\n<p>\n12<strong> (1)<\/strong> Mar\u00eda recibi\u00f3 la revelaci\u00f3n de la muerte del Se\u00f1or con lo que El dijo en 16:21; 17:22-23; 20:18-19; 26:2. As\u00ed que, aprovech\u00f3 la oportunidad para derramar sobre el Se\u00f1or lo mejor que ten\u00eda. Amar al Se\u00f1or con lo mejor de nosotros requiere que tengamos una revelaci\u00f3n con respecto a El.<\/p>\n<\/p>\n<p>\n12<strong> (a)<\/strong> Jua_19:40 ; Mat_27:59-60 <\/p>\n<h3 align='right'><i><b>Fuente: Comentario Del Nuevo Testamento Versi\u00f3n Recobro<\/b><\/i><\/h3>\n<p><b><i>lo ha hecho a fin de prepararme para la sepultura<\/i><\/b>. Aunque los disc\u00edpulos olvidaban muchas de las predicciones de Cristo acerca de Su muerte, parece ser que esta mujer las cre\u00eda y las ten\u00eda en cuenta (<span class='bible'>Mat 16:21<\/span>; <span class='bible'>Mat 17:22<\/span>; <span class='bible'>Mat 20:18<\/span>). Juan la identifica como Mar\u00eda (<span class='bible'>Jua 12:3<\/span>).<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio Anotada por Ryrie<\/b><\/i><\/h3>\n<p><i><b>sepultura&#8230;<\/b><\/i> \u2192 \u00a7<span class=\"dct\">318<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: Biblia Textual IV Edici\u00f3n<\/b><\/i><\/h3>\n<p>R1075 \u03a0\u03c1\u1f78\u03c2 \u03c4\u03cc se usa con el infinitivo para denotar prop\u00f3sito: a fin de prepararme para la sepultura. <\/p>\n<h3 align='right'><i><b>Fuente: Ayuda gramatical para el Estudio del Nuevo Testamento Griego<\/b><\/i><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Porque al derramar este perfume sobre mi cuerpo, ella lo hizo para prepararme para la sepultura. 26:12 Porque al derramar este perfume sobre mi cuerpo, lo ha hecho a fin de prepararme para la sepultura. \u2014 Comp\u00e1rese Jua 19:39-40; Mar 16:1. Les hab\u00eda dicho repetidas veces que los jud\u00edos le iban a matar; \u00bfera injusto &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/comentario-de-mateo-2612-exegesis-y-hermeneutica-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abComentario de Mateo 26:12 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-24695","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/24695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=24695"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/24695\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=24695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=24695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=24695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}