{"id":25252,"date":"2022-06-20T09:42:31","date_gmt":"2022-06-20T14:42:31","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/comentario-de-marcos-1035-exegesis-y-hermeneutica-de-la-biblia\/"},"modified":"2022-06-20T09:42:31","modified_gmt":"2022-06-20T14:42:31","slug":"comentario-de-marcos-1035-exegesis-y-hermeneutica-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/comentario-de-marcos-1035-exegesis-y-hermeneutica-de-la-biblia\/","title":{"rendered":"Comentario de Marcos 10:35 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia"},"content":{"rendered":"<h3 align='center'><b><i>Entonces Jacobo y Juan, hijos de Zebedeo, se acercaron a \u00e9l y le dijeron: \u2014Maestro, queremos que nos concedas lo que pidamos.<\/i><\/b><\/h3>\n<p \/> <span>10:35<\/span> \u2014 Entonces Jacobo y Juan, hijos de Zebedeo, se le acercaron, diciendo: Maestro, querr\u00edamos que nos hagas lo que pidi\u00e9remos \u2014 Porque no \u201ccomprendieron de estas cosas\u201d(<span>Luc 18:34<\/span>), y compartiendo la expectaci\u00f3n de muchos jud\u00edos de aquel tiempo del principio del reinado mesi\u00e1nico, estos dos ap\u00f3stoles, juntamente con la participaci\u00f3n de su madre (<span>Mat 20:20-21<\/span>), se acercan a Jes\u00fas para hacerle una petici\u00f3n especial. Jes\u00fas hac\u00eda poco hab\u00eda dicho a los doce que \u201cen la regeneraci\u00f3n \u201c ellos se sentar\u00edan en doce tronos (<span>Mat 19:28<\/span>), y ellos todav\u00eda est\u00e1n pensando en un reinado igual al dominio de los caudillos gentiles. No han entendido que el reino de los cielos no es de este mundo, sino espiritual (<span>Jua 18:36<\/span>; <span>Luc 17:20-21<\/span>). Su pensar equivocado contin\u00faa todav\u00eda hasta aun lo de <span>Hch 1:6<\/span>. <\/p>\n<p \/> No hac\u00eda mucho que Jes\u00fas hab\u00eda reprendido a los doce por ese concepto err\u00f3neo sobre la grandeza (9:33-37).<\/p>\n<h3 align='right'><i><b>Fuente: Comentario al Nuevo Testamento por Partain<\/b><\/i><\/h3>\n<p><b><i>Jacobo y Juan.<\/i><\/b> <span class='bible'>Mar 1:19<\/span>, <span class='bible'>Mar 1:20<\/span>; <span class='bible'>Mar 5:37<\/span>; <span class='bible'>Mar 9:2<\/span>; <span class='bible'>Mar 14:33<\/span>.<\/p>\n<p>\n<b><i>se acercaron a \u00e9l.<\/i><\/b> <span class='bible'>Mat 20:20<\/span>.<\/p>\n<p><b><i>querr\u00edamos que nos hagas lo que pidi\u00e9remos.<\/i><\/b> <span class='bible'>2Sa 14:4-11<\/span>; <span class='bible'>1Re 2:16<\/span>, <span class='bible'>1Re 2:20<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: El Tesoro del Conocimiento B\u00edblico<\/b><\/i><\/h3>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\"><span style=\"color:#008000\"><span class='bible'>Mat 20:20<\/span><\/span> dice que la madre de los\u00a0<\/span><span style=\"font-weight:bold\">hijos de Zebedeo<\/span>\u00a0busc\u00f3 a Jes\u00fas, pero probablemente sus propios hijos la animaron a hacerlo.<\/span><\/p>\n<p><\/p>\n<h3 align='right'><i><b>Fuente: Nuevo Comentario Ilustrado de la Biblia Caribe<\/b><\/i><\/h3>\n<p><b>Jacobo y Juan, hijos de Zebedeo.<\/b> <i>Vea la nota sobre<\/i> <span class='bible'>Mar 1:19<\/span>. Mateo revela que su madre los acompa\u00f1aba y habl\u00f3 primero (<span class='bible'>Mat 20:20-21<\/span>), confirmando luego su petici\u00f3n Jacobo y Juan. Si ella era t\u00eda de Jes\u00fas, los tres indudablemente pensaban en sacar provecho de los lazos familiares.<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio MacArthur<\/b><\/i><\/h3>\n<p>Este incidente revela nuevamente el fracaso de los disc\u00edpulos en entender la ense\u00f1anza de Jes\u00fas sobre la humildad (<i>vea las notas sobre<\/i> <span class='bible'>Mar 9:34<\/span><i>;<\/i> <span class='bible'>Mat 20:21<\/span>). Ignorando la instrucci\u00f3n repetida de Jes\u00fas de que se dirig\u00eda a Jerusal\u00e9n para morir (<i>vea las notas sobre los vv.<\/i><span class='bible'>Mar 10:32-34<\/span>), los disc\u00edpulos manten\u00edan la idea de que el reino se manifestar\u00eda de manera f\u00edsica prontamente y se ocupaban en determinar qui\u00e9n ocupar\u00eda qu\u00e9 lugar en \u00e9l (cp. <span class='bible'>Mat 18:1<\/span>).<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio MacArthur<\/b><\/i><\/h3>\n<p>\t10:35 &#8211;Entonces Jacobo y Juan, hijos de Zebedeo, se le acercaron, diciendo: Maestro, querr\u00edamos que nos hagas lo que pidi\u00e9remos &#8212; Porque no \u201ccomprendieron de estas cosas\u201d(Luc 18:34), y compartiendo la expectaci\u00f3n de muchos jud\u00edos de aquel tiempo del principio del reinado mesi\u00e1nico, estos dos ap\u00f3stoles, juntamente con la participaci\u00f3n de su madre (Mat 20:20-21), se acercan a Jes\u00fas para hacerle una petici\u00f3n especial. Jes\u00fas hac\u00eda poco hab\u00eda dicho a los doce que \u201cen la regeneraci\u00f3n \u201c ellos se sentar\u00edan en doce tronos (Mat 19:28), y ellos todav\u00eda est\u00e1n pensando en un reinado igual al dominio de los caudillos gentiles. No han entendido que el reino de los cielos no es de este mundo, sino espiritual (Jua 18:36; Luc 17:20-21). Su pensar equivocado contin\u00faa todav\u00eda hasta aun lo de Hch 1:6.<br \/>\n\tNo hac\u00eda mucho que Jes\u00fas hab\u00eda reprendido a los doce por ese concepto err\u00f3neo sobre la grandeza (9:33-37).<\/p>\n<h3 align='right'><i><b>Fuente: Notas Reeves-Partain<\/b><\/i><\/h3>\n<p><strong><u>LA PETICI\u00d3N DE LA AMBICI\u00d3N<\/u><\/strong><\/p>\n<\/p>\n<p><strong><span class='bible'>Marcos 10:35-40<\/span><\/strong><\/p>\n<\/p>\n<p>Santiago y Juan, los hijos de Zebedeo, se acercaron a Jes\u00fas y Le dijeron: Maestro, queremos que nos concedas lo que Te pidamos. -\u00bfQu\u00e9 quer\u00e9is que os conceda? -les pregunt\u00f3 Jes\u00fas. Y ellos Le dijeron: -Conc\u00e9denos que, en Tu gloria, nos sentemos uno a <em>Tu derecha y otro a Tu izquierda. No sab\u00e9is lo que est\u00e1is pidiendo -les dijo Jes\u00fas-. \u00bfPod\u00e9is beber el c\u00e1liz que Yo estoy bebiendo? O \u00bfpod\u00e9is pasar la experiencia que Yo estoy pasando? Podemos Le dijeron. Y Jes\u00fas les dijo: -Beber\u00e9is el c\u00e1liz que Yo estoy bebiendo, y pasar\u00e9is por la experiencia por la que Yo estoy pasando; pero el que os sent\u00e9is a Mi derecha y a Mi izquierda no Me corresponde a M\u00ed conced\u00e9roslo. Ese puesto pertenece a aquellos para los que ha sido preparado.<\/em><\/p>\n<p>Esta es una historia muy reveladora.<br \/>(i) Nos dice algo acerca de Marcos. Mateo relata esta historia <em>(<\/em><span class='bible'>Mt 20:20-23<\/span><em> ), <\/em>pero en su versi\u00f3n la petici\u00f3n de los primeros puestos no la hacen Santiago y Juan sino su madre, Salom\u00e9. Mateo tiene que haber presentido que tal solicitud era indigna de los ap\u00f3stoles; y para mantener a salvo la reputaci\u00f3n de Santiago y Juan la atribuy\u00f3 a la ambici\u00f3n natural de su madre. Esta historia nos muestra la honradez de Marcos. Se cuenta que un pintor de la corte hizo el retrato de Oliver Cromwell. Cromwell ten\u00eda unas verrugas en la cara que le afeaban bastante. Con la intenci\u00f3n de agradarle, el pintor omiti\u00f3 las verrugas en el cuadro. Pero cuando Cromwell lo vio, dijo: \u00bb \u00a1Ll\u00e9vatelo! \u00a1Y p\u00edntame con verrugas y todo!\u00bb El prop\u00f3sito de Marcos era presentarnos a los disc\u00edpulos con verrugas y todo. Y Marcos ten\u00eda raz\u00f3n, porque los Doce no eran una compa\u00f1\u00eda de \u00e1ngeles. Eran hombres normales y corrientes. Fue con personas como nosotros como Jes\u00fas emprendi\u00f3 la empresa de cambiar el mundo -\u00a1y lo hizo!<\/p>\n<p>(ii) Nos dice algo acerca de Santiago y Juan.<\/p>\n<p><em>(a) <\/em>Nos dice que eran ambiciosos. Cuando se obtuviera la victoria y el triunfo fuera completo, pretend\u00edan ser los primeros ministros de estado de Jes\u00fas. Puede que su ambici\u00f3n se incentivara por el hecho de que Jes\u00fas los hab\u00eda escogido como parte de Su c\u00edrculo \u00edntimo, los tres escogidos. Puede ser que fueran de un poco mejor posici\u00f3n que los otros. Su padre ten\u00eda una posici\u00f3n suficientemente desahogada como para tener jornaleros <em>(<\/em><span class='bible'>Mr 1:20<\/span><em> ), y puede <\/em>ser que tuvieran la presunci\u00f3n de creer que su superioridad social les daba derecho a los primeros puestos. Y, por supuesto, creer\u00edan que ten\u00edan m\u00e1s derecho que nadie por ser parientes de Jes\u00fas. En cualquier caso aparecen como hombres en cuyos corazones anidaba la ambici\u00f3n por los primeros puestos en un reino terrenal.<\/p>\n<p>(b) Nos dice que no hab\u00edan conseguido comprender a Jes\u00fas. Lo sorprendente no es el que este incidente tuviera lugar, sino <em>el momento <\/em>en que sucedi\u00f3. Es todo lo contrario del anuncio m\u00e1s definido y detallado que hizo Jes\u00fas de Su muerte, y esta petici\u00f3n es alucinante. Muestra mejor que ning\u00fan otro detalle lo poco que hab\u00edan comprendido de lo que Jes\u00fas les estaba diciendo. Sus palabras no hab\u00edan conseguido desembarazarlos de la idea de un Mes\u00edas de poder y gloria terrenales. Solamente la Cruz lo conseguir\u00eda.<\/p>\n<p>(c) Pero, una vez que hemos dicho todo lo que se puede decir en contra de Santiago y Juan, esta historia nos revela algo luminoso acerca de ellos -desconcertados y todo como estaban, <em>todav\u00eda cre\u00edan en Jes\u00fas. <\/em>Es alucinante que todav\u00eda pudieran conectar la gloria con un Carpintero galileo Que hab\u00eda incurrido en la enemistad y la oposici\u00f3n declarada de los l\u00edderes religiosos ortodoxos, y Que iba de camino a la Cruz. Hay aqu\u00ed una confianza alucinante y una alucinante lealtad. Puede que Santiago y Juan estuvieran confundidos, pero ten\u00edan el coraz\u00f3n en su sitio. Nunca pusieron en duda el triunfo final de Jes\u00fas.<\/p>\n<p>(i\u00fc) Nos dice algo acerca del baremo de grandeza de Jes\u00fas. La versi\u00f3n Reina-Valera nos da la traducci\u00f3n literal exacta de lo que dijo Jes\u00fas: \u00bb \u00bfPod\u00e9is beber del vaso que Yo bebo, o ser bautizados con el bautismo con que Yo soy bautizado?\u00bb Jes\u00fas usa aqu\u00ed dos met\u00e1foras hebreas.<br \/>Era costumbre en los banquetes reales que el rey pasara la copa a sus hu\u00e9spedes. <em>La copa <\/em>por tanto lleg\u00f3 a ser una met\u00e1fora de la vida y la experiencia que Dios comunica a los hombres. \u00bb Mi copa est\u00e1 rebosando\u00bb dec\u00eda el salmista <em>(<\/em><span class='bible'>Sal 23:5<\/span><em> ), <\/em>cuando hablaba de la vida y experiencia y felicidad que Dios le hab\u00eda dado. \u00bb En la mano del Se\u00f1or hay una copa,\u00bb dec\u00eda el salmista <em>(<\/em><span class='bible'>Sal 75:8<\/span><em> ) <\/em>cuando estaba pensando en la suerte que les est\u00e1 reservada a los malvados y desobedientes. Isa\u00edas, pensando en las desventuras que hab\u00edan sobrevenido al pueblo de Israel, las describe como haber bebido \u00bb de la mano del Se\u00f1or la copa de Su ira\u00bb <em>(<\/em><span class='bible'>Isa 51:17<\/span><em> ). La copa, o el vaso, o el <\/em>c\u00e1liz, habla de la experiencia que Dios asigna a cada persona.<\/p>\n<p>La otra frase que usa Jes\u00fas puede llevar a confusi\u00f3n en una traducci\u00f3n literal, motivo por el cual la hemos traducido m\u00e1s libremente para dar el sentido. Habla del bautismo con el que \u00c9l fue bautizado. El verbo griego <em>baptizein <\/em>significa <em>sumergir. <\/em>Su participio pasado <em>(bebaptismenos) <\/em>quiere decir <em>sumergido, <\/em>y se usa corrientemente de ser <em>sumergido en alguna experiencia, lo <\/em>mismo que en espa\u00f1ol <em>inmerso. <\/em>Por ejemplo, un manirroto se dice que est\u00e1 <em>sumergido, inmerso <\/em>en deudas. Un borracho se dice que est\u00e1 <em>sumergido <\/em>en bebida. Una persona afligida se dice que est\u00e1 <em>sumergida, inmersa <\/em>en aflicci\u00f3n. Un muchacho ante el profesor que le va a examinar se dice que est\u00e1 <em>sumergido, inmerso <\/em>en preguntas. La palabra se usa corrientemente de un barco que ha sufrido un naufragio y se <em>sumerge <\/em>bajo las olas. La met\u00e1fora est\u00e1 muy \u00edntimamente emparentada con la que usa corrientemente el salmista. En<span class='bible'> <\/span><span class='bible'>Sal 42:7<\/span>  leemos: \u00abTodas Tus ondas y Tus olas han pasado sobre m\u00ed.\u00bb En <span class='bible'>Sal 124:4<\/span>  leemos: \u00bb Entonces nos habr\u00edan anegado las aguas; sobre nuestra alma habr\u00eda pasado la avenida.\u00bb La expresi\u00f3n, como Jes\u00fas la usa aqu\u00ed, no tiene nada que ver con el Bautismo. Lo que est\u00e1 diciendo es: \u00ab\u00bfPod\u00e9is soportar pasar la terrible experiencia que Yo tengo que pasar? \u00bfPod\u00e9is sumergiros en odio y dolor y muerte como Yo?\u00bb Estaba dici\u00e9ndoles a estos dos disc\u00edpulos que sin Cruz no puede haber corona. El baremo de grandeza en el Reino es el baremo de la Cruz. Fue cierto que en d\u00edas entonces por venir ellos pasaron la experiencia de su Maestro, porque Santiago fue decapitado por Herodes Agripa <span class='bible'>Hch 12:2<\/span><em> ), y, aunque Juan probablemente no muri\u00f3 m\u00e1rtir, s\u00ed tuvo que sufrir mucho por Cristo. Ellos aceptaron el desaf\u00edo de su Maestro -aunque fuera a ciegas.<\/em><\/p>\n<p><em>(iv) Jes\u00fas les dijo que la decisi\u00f3n final pertenec\u00eda a Dios. La asignaci\u00f3n final del destino era Su prerrogativa. Jes\u00fas nunca usurp\u00f3 el lugar de Dios. Toda Su propia vida fue un largo acto de sumisi\u00f3n a la voluntad de Dios, y El sab\u00eda que esa voluntad era suprema hasta el fin.<br \/><\/em><\/p>\n<h3 align='right'><i><b>Fuente: Comentario al Nuevo Testamento<\/b><\/i><\/h3>\n<\/p>\n<p><span style=\"font-weight:bold;font-style:italic\">El privilegio del disc\u00edpulo es el servicio (<\/span><span style=\"color:#008000;text-decoration:underline\"><span class=\"bible\">Mar 10:35-45<\/span><\/span><span style=\"font-weight:bold;font-style:italic\">)<\/span><\/p>\n<p><span style=\"font-weight:bold\">An\u00e1lisis de discurso<\/span><\/p>\n<p>Esta secci\u00f3n consta de dos partes: una (vv. <span style=\"color:#008000;text-decoration:underline\"><span class=\"bible\">Mar 10:35-40<\/span><\/span>) describe la petici\u00f3n de Jacobo y Juan, y la correspondiente respuesta de Jes\u00fas; la otra (vv. <span style=\"color:#008000;text-decoration:underline\"><span class=\"bible\">Mar 10:41-45<\/span><\/span>) describe la reacci\u00f3n de los otros disc\u00edpulos y la ense\u00f1anza de Jes\u00fas sobre la verdadera importancia y privilegio del discipulado.<\/p>\n<p>Sin embargo, tambi\u00e9n se puede analizar este pasaje teniendo en cuenta los vers\u00edculos <span style=\"color:#008000;text-decoration:underline\"><span class=\"bible\">Mar 10:33-34<\/span><\/span>, cuando Jes\u00fas anuncia, por tercera vez, su pasi\u00f3n, muerte y resurrecci\u00f3n; luego, en <span style=\"color:#008000;text-decoration:underline\"><span class=\"bible\">Mar 10:45<\/span><\/span>, Jes\u00fas explica el significado de su muerte. Entre estas dos afirmaciones, en las que Jes\u00fas habla de s\u00ed mismo como el Hijo del hombre, tenemos la conversaci\u00f3n con Jacobo y Juan y la explicaci\u00f3n dirigida a todo el grupo de disc\u00edpulos sobre el verdadero valor del liderazgo.<\/p>\n<p><span style=\"font-weight:bold\">T\u00cdTULO<\/span>: Aunque la mayor\u00eda de las versiones consultadas se deciden por el t\u00edtulo \u00abLa petici\u00f3n de Santiago [o Jacobo] y de Juan\u00bb (RV95, TLA, BA, etc.), proponemos algo diferente. En efecto, la verdadera raz\u00f3n que est\u00e1 detr\u00e1s de esta petici\u00f3n es conseguir un lugar de privilegio e importancia en el reino futuro, por lo cual sugerimos t\u00edtulos que podr\u00edan relacionarse mejor con esta actitud: \u201cJes\u00fas ense\u00f1a sobre la verdadera importancia del discipulado\u201d, o \u201cEl privilegio del disc\u00edpulo es el servicio\u201d.<\/p>\n<p><span style=\"font-weight:bold\">An\u00e1lisis textual y morfosint\u00e1ctico<\/span><\/p>\n<p><\/p>\n<h3 align='right'><i><b>Fuente: Comentario para Ex\u00e9gesis y Traducci\u00f3n<\/b><\/i><\/h3>\n<p>Una solicitud mezquina (ver Mat. 20:20-28). Si no hubiese quedado impreso no podr\u00edamos haber cre\u00eddo que, despu\u00e9s de todo lo dicho, Jacobo y Juan se atrevieran a acercarse con una solicitud tan ambiciosa y mezquina. Pero demasiado bien sabemos, sin embargo, c\u00f3mo somos, y por lo tanto, podemos comprender. Si se hubieran dado cuenta del verdadero costo de tener un lugar elevado en el reino de Dios, no se hubieran atrevido a pedir, a pesar de sus palabras valerosas. Copa y bautismo (o \u201cinundaci\u00f3n\u201d) son cuadros de juicio y sufrimiento en el AT. Jes\u00fas les advirti\u00f3 que el sufrimiento en verdad llegar\u00eda para todos, pero eso no necesariamente conducir\u00eda a un lugar elevado en el reino de Dios. El lugar elevado s\u00f3lo lo da Dios.<\/p>\n<p>Los otros diez disc\u00edpulos se portaron igualmente mal como Jacobo y Juan al enojarse por la solicitud que aquellos hicieron. Sin lugar a duda \u00e9stos quer\u00edan esos lugares para s\u00ed mismos. As\u00ed que Jes\u00fas pacientemente volvi\u00f3 a explicarles las normas totalmente diferentes del reino de Dios, donde la verdadera grandeza es el servicio humilde. Jes\u00fas mismo es el gran ejemplo de esto. El vino para ser el siervo sufriente de Dios profetizado en Isa. 53 y para dar su vida en rescate por muchos (45). El uso de la palabra muchos no significa que Jes\u00fas muri\u00f3 por ciertas personas solamente, de ninguna manera; recalca m\u00e1s bien el gran n\u00famero de los redimidos por su muerte. Este es uno de los pocos lugares en Mar. donde se explica la manera en que la muerte de Jes\u00fas nos salva. Mar. tiene mucho m\u00e1s inter\u00e9s en la sencilla realidad de la salvaci\u00f3n, y no en c\u00f3mo sucede. Rescate es uno de los muchos cuadros por medio de los cuales se explica la salvaci\u00f3n en el NT. Significa pagar un precio para ser libres de la esclavitud, o la prisi\u00f3n, o la muerte pagando un precio. En nuestro d\u00eda estamos bien familiarizados con las demandas de aquellos que secuestran o asaltan. En este caso el precio ser\u00eda la muerte de Jes\u00fas.<\/p>\n<h3 align='right'><i><b>Fuente: Nuevo Comentario B\u00edblico Siglo Veintiuno<\/b><\/i><\/h3>\n<p>REFERENCIAS CRUZADAS<\/p>\n<p>m 497 Mat 10:2<\/p>\n<p>n 498 Mat 20:20<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n del Nuevo Mundo<\/b><\/i><\/h3>\n<p><p> Jacobo y Juan, los dos hijos de Zebedeo.  V\u00e9ase coment. en 3:17. <\/p>\n<p><p> que hagas&#8230;lo que te pidamos.  La petici\u00f3n es arrogante y atrevida. Seg\u00fan Mt 20:20, 21 es la madre de estos disc\u00edpulos la que hace la petici\u00f3n, pero en Mt 20:22, 23 se ve que tambi\u00e9n los hijos est\u00e1n involucrados en dicha petici\u00f3n.<\/p>\n<p><h3 align='right'><i><b>Fuente: La Biblia de las Am\u00e9ricas<\/b><\/i><\/h3>\n<p>\n35<strong> (1)<\/strong> Con respecto a los vs.35-45, v\u00e9anse las notas de Mat_20:20-28 . <\/p>\n<h3 align='right'><i><b>Fuente: Comentario Del Nuevo Testamento Versi\u00f3n Recobro<\/b><\/i><\/h3>\n<p>Marquemos en este pasaje la ignorancia de los disc\u00edpulos de nuestro Se\u00f1or. Vemos \u00e1 Santiago y \u00e1 Juan pretendiendo los primeros puestos en el reino de la  gloria, y al mismo tiempo declarar muy confiados que se encuentran capaces de beber del c\u00e1liz de su Maestro y de ser bautizados con el bautismo de su  Maestro. A pesar de todas las amonestaciones tan claras de nuestro Se\u00f1or se apegan obstinadamente \u00e1 la creencia de que el reino de Cristo sobre la tierra iba \u00e1  aparecer inmediatamente. A pesar de sus tropiezos en el servicio de Cristo, no tienen la menor duda de que podr\u00e1n sufrir todo lo que sobre ellos caiga. Con  toda su fe y su gracia, con todo su amor \u00e1 Jes\u00fas, ni conocen sus corazones, ni la aspereza del camino en que marchan. Aun sue\u00f1an con coronas temporales y  con recompensas terrestres, y no saben que clase de hombres son.<br \/>\nPocos son los verdaderos cristianos que no se parecen \u00e1 Santiago y \u00e1 Juan, cuando empiezan \u00e1 servir \u00e1 Cristo. Tenemos demasiada propensi\u00f3n \u00e1 esperar de  nuestra religi\u00f3n m\u00e1s goces inmediatos de los que el Evangelio nos autoriza \u00e1 aguardar. Estamos muy dispuestos \u00e1 olvidar la cruz y las tribulaciones y \u00e1 pensar  solo en coronas. Nos formamos una idea falsa de nuestra paciencia y de nuestro sufrimiento, y no sabemos juzgar con exactitud la fuerza real que tenemos  para resistir tentaciones y pruebas. Y el resultado es que con frecuencia compramos muy caro la sabidur\u00eda, con amarga experiencia, con muchos desenga\u00f1os, y  con no pocas ca\u00eddas.<br \/>\nQue el caso que meditamos nos ense\u00f1e lo importante que es juzgar de nuestra religi\u00f3n con calma y una raz\u00f3n s\u00f3lida. Derecho tenemos, como Santiago y Juan,  de desear los dones m\u00e1s excelentes, y comunicar \u00e1 Cristo todos nuestros deseos. Con justicia debernos creer como ellos que Jes\u00fas es Rey de reyes, y que  reinar\u00e1 Un d\u00eda sobre la tierra; pero no olvidemos, como ellos, que todo cristiano debe cargar con su cruz, y \u00abque tenemos que entrar en el reino de Dios al  trav\u00e9s de muchas tribulaciones.\u00bb Hechos 14.22. No confiemos demasiado, como ellos, en nuestras fuerzas, ni nos jactemos de poder hacer todo lo que Cristo  nos exija. Guard\u00e9monos de esa jactancia al entrar en la senda de la vida cristiana, que, esta conducta nos salvar\u00e1 de muchos tropiezos humillantes.<br \/>\nMarquemos, en segundo lugar, en este pasaje, la alabanza quo nuestro Se\u00f1or hace de la humildad, y de la consagraci\u00f3n al bien del pr\u00f3jimo. Parece que los  diez se disgustaron mucho con Santiago y Juan con motivo de la petici\u00f3n que hicieron \u00e1 su Maestro. Su ambici\u00f3n y deseo de preeminencia se volvieron \u00e1  exaltar con la idea de que alguno pudiera colocarse por encima de ellos. Nuestro Se\u00f1or comprendi\u00f3 bien cuales eran sus sentimientos, y, como m\u00e9dico h\u00e1bil,  procedi\u00f3 inmediatamente \u00e1 propinarles una medicina apropiada. Les dice que basaban sus ideas de grandeza en un cimiento falso; les repite con \u00e9nfasis  renovado la lecci\u00f3n que ya les hab\u00eda dado en el cap\u00edtulo precedente : \u00abCualquiera de vosotros que sea m\u00e1s grande, ser\u00e1 el servidor de todos.\u00bb Y apoya toda su  demostraci\u00f3n en el argumento concluyente de su propio ejemplo. \u00abAun el Hijo del hombre no ha venido para ser servido, sino para servir..<br \/>\nQue todo el que desee agradar \u00e1 Cristo, est\u00e9 en, guardia contra ese sentimiento de apreciaci\u00f3n exagerada de si mismo, y pida \u00e1 Dios en sus oraciones que lo  cure de \u00e9l; es un sentimiento que est\u00e1 arraigado profundamente en nuestros corazones. Muchos abandonaron el mundo, cargaron \u00e1 cuestas con su cruz,  profesaron prescindir de su propia justicia, y creer en Cristo, y se irritan y se afligen, cuando un hermano es m\u00e1s honrado que ellos. Esto no debe ser.<br \/>\nMeditemos siempre en estas palabras de S. Pablo: \u00abNada hag\u00e1is por contienda ni por vanagloria; antes con humildad de esp\u00edritu, estim\u00e1ndoos inferiores los  unos \u00e1 los otros.\u00bb Filip. 2.3. iBienaventurado el hombre que puede sinceramente regocijarse cuando otros son exaltados, aunque \u00e9l mismo se vea olvidado y  postergado! Sobre todo, que los que desean seguir las huellas de Cristo, se empe\u00f1en en ser \u00fatiles \u00e1 los dem\u00e1s. Prop\u00f3nganse hacer bien en sus d\u00edas y en su generaci\u00f3n.<br \/>\nVasto es el campo siempre para la beneficencia; lo que se necesita es voluntad \u00e9 inclinaci\u00f3n. No olvidemos nunca que la verdadera, grandeza no consiste en  ser almirante, general, hombre de estado, \u00f3 artista. Estriba en sacrificarnos, en consagrar cuerpo y alma y esp\u00edritu \u00e1 la obra bendita de hacer \u00e1 nuestros  pr\u00f3jimos m\u00e1s y m\u00e1s felices. Los que se ejercitan, usando los medios que la Escritura nos suministra, en aliviar los pesares y aumentar los goces de los que los  rodean, los Howards, los Wilberforces, los Martyns, los Judsons de las naciones, esos son los verdaderamente grandes \u00e1 los ojos de Dios. Mientras viven son  objetos de burlas, de desprecios, del rid\u00edculo y muchas veces de las persecuciones. Pero en el cielo est\u00e1 el recuerdo de sus hechos, all\u00ed est\u00e1 escrito su nombre,  y su alabanza es eterna. Recordemos esto, y mientras tengamos tiempo, hagamos bien \u00e1 los hombres, y seamos siervos de todos por amor de Cristo.<br \/>\nEsforc\u00e9monos por dejar el mundo mejor, m\u00e1s santo y m\u00e1s feliz que cuando nacimos. Una vida consumida de esa manera es verdaderamente imitar \u00e1 Cristo, y  lleva en s\u00ed su recompensa.<br \/>\nNotemos, por \u00faltimo, en este pasaje, el lenguaje que usa nuestro Se\u00f1or al hablar de su propia muerte. Dice, \u00abEl Hijo del hombre vino \u00e1 dar su vida en rescate  por muchos..<br \/>\nEsta es una de esas expresiones que deb\u00edan guardar como un tesoro en sus almas todos los verdaderos cristianos. Es uno de los textos que prueban de una  manera incontrovertible el car\u00e1cter expiatorio de la muerte de Cristo. Su muerte no fue una muerte com\u00fan, como la de un m\u00e1rtir, \u00fa otros santos. Fue el pago  p\u00fablico que hizo un Representante. Omnipotente de lo que deb\u00eda el hombre pecador al Dios santo. Era el rescate que un Fiador divino ofrec\u00eda para procurar la  libertad de pecadores, atados y ligados por la cadena de sus pecados. Con esa muerte Jes\u00fas dio satisfacci\u00f3n plena y completa por las transgresiones sin cuento  del hombre. En la cruz carg\u00f3 nuestros pecados sobre su cuerpo. El Se\u00f1or se cubri\u00f3 con todas nuestras iniquidades, y cuando muri\u00f3, muri\u00f3 por todos. Cuando  sufri\u00f3, sufri\u00f3 en nuestro lugar; cuando colgaba de la cruz, colgaba de ella como Sustituto nuestro, y su sangre que all\u00ed corri\u00f3, fue el precio de nuestras almas.<br \/>\nQue todos los que en Cristo conf\u00edan se consuelen al pensar que se apoyan en s\u00f3lido cimiento. Verdad es que somos  pecadores, pero Cristo carg\u00f3 sobre si nuestros pecados. Verdad es que somos deudores pobres y desvalidos, pero Cristo ha  pagado nuestras deudas. Verdad es que merecemos vernos encerrados para siempre en la prisi\u00f3n del infierno; pero, gracias  \u00e1 Dios, Cristo ha pagado por completo nuestro rescate. La puerta est\u00e1 abierta de par en par, y los prisioneros pueden salir  libres. Que todos por los. sentimientos de nuestro coraz\u00f3n tengamos la convicci\u00f3n de poseer ese privilegio, y marchemos  en la bendita libertad de los hijos de Dios.<\/p>\n<h3 align='right'><i><b>Fuente: Los Evangelios Explicados<\/b><\/i><\/h3>\n<p>MT160 Hay una distinci\u00f3n entre el verbo en voz activa \u03b1\u1f30\u03c4\u03ad\u03c9 (v. 35) y el verbo en voz media \u03b1\u1f30\u03c4\u03ad\u03bf\u03bc\u03b1\u03b9 (en el v. 38; comp. Mar 6:22). <\/p>\n<p> MT179 En este vers\u00edculo, parece que \u1f35\u03bd\u03b1 se une con \u03b8\u03ad\u03bb\u03bf\u03bc\u03b5\u03bd, en vez de usarse con sentido imperativo: queremos que.<\/p>\n<h3 align='right'><i><b>Fuente: Ayuda gramatical para el Estudio del Nuevo Testamento Griego<\/b><\/i><\/h3>\n<p> O, <i>Santiago<\/i> <\/p>\n<h3 align='right'><i><b>Fuente: La Biblia de las Am\u00e9ricas<\/b><\/i><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Entonces Jacobo y Juan, hijos de Zebedeo, se acercaron a \u00e9l y le dijeron: \u2014Maestro, queremos que nos concedas lo que pidamos. 10:35 \u2014 Entonces Jacobo y Juan, hijos de Zebedeo, se le acercaron, diciendo: Maestro, querr\u00edamos que nos hagas lo que pidi\u00e9remos \u2014 Porque no \u201ccomprendieron de estas cosas\u201d(Luc 18:34), y compartiendo la expectaci\u00f3n &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/comentario-de-marcos-1035-exegesis-y-hermeneutica-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abComentario de Marcos 10:35 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-25252","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/25252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=25252"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/25252\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=25252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=25252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=25252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}