{"id":31041,"date":"2022-06-20T14:10:55","date_gmt":"2022-06-20T19:10:55","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/comentario-de-1-pedro-213-exegesis-y-hermeneutica-de-la-biblia\/"},"modified":"2022-06-20T14:10:55","modified_gmt":"2022-06-20T19:10:55","slug":"comentario-de-1-pedro-213-exegesis-y-hermeneutica-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/comentario-de-1-pedro-213-exegesis-y-hermeneutica-de-la-biblia\/","title":{"rendered":"Comentario de 1 Pedro 2:13 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia"},"content":{"rendered":"<h3 align='center'><b><i>Estad sujetos a toda instituci\u00f3n humana por causa del Se\u00f1or; ya sea al rey como quien ejerce soberan\u00eda,<\/i><\/b><\/h3>\n<p \/> <span>2:13<\/span> \u2014 \u00abPor causa del Se\u00f1or\u00bb; es decir, porque es su voluntad y parte de nuestro servicio a \u00e9l. Comp\u00e1rese <span>Efe 6:6-7<\/span>. <\/p>\n<p \/> \u2014 \u00absometeos a toda instituci\u00f3n humana\u00bb (literalmente, a toda creaci\u00f3n humana). Dice la Ver. S.A., \u00aba toda humana criatura\u00bb. La Ver. N.M. dice, \u00aba toda creaci\u00f3n humana\u00bb. La Ver. T.A. dice, \u00aba toda humana creatura\u00bb. La Ver. NTP. dice, \u00aba toda autoridad humana\u00bb. Obviamente se hace referencia a todo lo que los hombres en autoridad crean en forma de leyes. El cristiano es ciudadano obediente o sumiso. V\u00e9ase <span>Rom 13:1-7<\/span>. Consid\u00e9rese tambi\u00e9n <span>1Ti 2:1-2<\/span>. <\/p>\n<p \/> En <span>3:22<\/span> Pedro usa la misma palabra griega, para decir \u00absujetar\u00bb, en cuanto a los \u00e1ngeles y su sujeci\u00f3n a Cristo. <\/p>\n<p \/> La sujeci\u00f3n al gobierno est\u00e1 limitada a lo que no contradiga mandamiento de Dios (<span>Hch 4:19<\/span>; <span>Hch 5:29<\/span>). <\/p>\n<p \/> \u2014 \u00abya sea&#8230; superior\u00bb. Los romanos dec\u00edan \u00abemperador\u00bb, pero los griegos y jud\u00edos, \u00abrey\u00bb. V\u00e9anse <span>Jua 19:15<\/span>; <span>Hch 17:7<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: Comentario al Nuevo Testamento por Partain<\/b><\/i><\/h3>\n<p><span class='bible'>Pro 17:11<\/span>; <span class='bible'>Pro 24:21<\/span>; <span class='bible'>Jer 29:7<\/span>; <span class='bible'>Mat 22:21<\/span>; <span class='bible'>Mar 12:17<\/span>; <span class='bible'>Luc 20:25<\/span>; <span class='bible'>Rom 13:1-7<\/span>; <span class='bible'>Efe 5:21<\/span>; <span class='bible'>1Ti 2:1<\/span>, <span class='bible'>1Ti 2:2<\/span>; <span class='bible'>Tit 3:1<\/span>; <span class='bible'>2Pe 2:10<\/span>; <span class='bible'>Jud 1:8-10<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: El Tesoro del Conocimiento B\u00edblico<\/b><\/i><\/h3>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\">Pedro ordena en\u00e9rgicamente a los cristianos que se\u00a0<\/span><span style=\"font-weight:bold\">sometan<\/span>\u00a0voluntariamente a las autoridades gobernantes. No presenta la sumisi\u00f3n como un asunto de convicci\u00f3n o de elecci\u00f3n personal. Decreta que es una obligaci\u00f3n para todos los cristianos.<\/span><\/p>\n<p> <\/p>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\"><span style=\"font-weight:bold\">toda instituci\u00f3n humana:<\/span>\u00a0Esta frase sugiere que la sumisi\u00f3n de los cristianos no es para ejercitarse s\u00f3lo en relaci\u00f3n con autoridades civiles (v.<\/span> <span style=\"color:#008000\"><span class='bible'>1Pe 2:14<\/span><\/span>), sino para con todo tipo de reglamento que los cristianos se enfrenten (<\/span><span style=\"color:#008000\"><span class='bible'>1Pe 2:18<\/span><\/span>;<\/span> <span style=\"color:#008000\"><span class='bible'>1Pe 3:1<\/span><\/span>).<\/span><\/p>\n<p> <\/p>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\"><span style=\"font-weight:bold\">Por causa del Se\u00f1or:<\/span>\u00a0el mandato de someterse ha de llevarse a cabo no de mala gana ni por obligaci\u00f3n, sino alegre y voluntariamente para la gloria de Dios. Los cristianos no deben tener una actitud de rebeli\u00f3n.<\/span><\/p>\n<p> <\/p>\n<table cellspacing=\"0\" cellpadding=\"0pt\" style=\"width:432pt;border-collapse:collapse\">\n<colgroup>\n<col width=\"288\" \/>\n<col width=\"288\" \/><\/colgroup>\n<tr align=\"left\" valign=\"top\">\n<td style=\"width:215pt;border-top: 1pt solid #000000;border-right: 1pt solid #000000;border-bottom: 1pt solid #000000;border-left: 1pt solid #000000\">\n<p lang=\"es-ES\" style=\"text-indent:0pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\">\u00a0<\/span><span style=\"font-weight:bold\">PARA VIVIRLO<\/span><\/p>\n<p> <\/td>\n<td style=\"width:215pt;border-top: 1pt solid #000000;border-right: 1pt solid #000000;border-bottom: 1pt solid #000000;border-left: 1pt solid #000000\">\n<p lang=\"es-ES\" style=\"text-indent:0pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt;font-weight:bold\">Soportar las penurias<\/p>\n<p> <\/td>\n<\/tr>\n<\/table>\n<table cellspacing=\"0\" cellpadding=\"0pt\" style=\"width:432pt;border-collapse:collapse\">\n<colgroup>\n<col width=\"576\" \/><\/colgroup>\n<tr align=\"left\" valign=\"top\">\n<td style=\"width:431pt;border-top: 1pt solid #000000;border-right: 1pt solid #000000;border-bottom: 1pt solid #000000;border-left: 1pt solid #000000\">\n<p lang=\"es-ES\" style=\"text-indent:0pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\"><span style=\"font-weight:bold\">\u00bfC<\/span>\u00f3mo deben reaccionar los cristianos a las injusticias en el lugar de trabajo? Se puede recurrir a una sana confrontaci\u00f3n. Hay momentos para reclamar los derechos propios y tambi\u00e9n para defender los derechos de los dem\u00e1s. La Biblia proporciona muchos ejemplos y directrices al respecto. Por ejemplo, Jes\u00fas dio instrucciones sobre c\u00f3mo proceder con un creyente en pecado (<\/span><span style=\"color:#008000\"><span class='bible'>Mat 18:15-17<\/span><\/span>), y Pablo apel\u00f3 al C\u00e9sar cuando percibi\u00f3 que no se le estaba tratando con justicia (<\/span><span style=\"color:#008000\"><span class='bible'>Hch 25:8-12<\/span><\/span>).<\/span><\/p>\n<p> <\/td>\n<\/tr>\n<tr align=\"left\" valign=\"top\">\n<td style=\"width:431pt;border-top: 1pt solid #000000;border-right: 1pt solid #000000;border-bottom: 1pt solid #000000;border-left: 1pt solid #000000\">\n<p lang=\"es-ES\" style=\"text-indent:0pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\">Por otra parte, tambi\u00e9n hay momentos para sufrir la injusticia silenciosamente como cuando se trata de dar testimonio, seg\u00fan indica Pedro (<\/span><span style=\"color:#008000\"><span class='bible'>1Pe 2:18-21<\/span><\/span>). Jes\u00fas le dijo lo mismo a sus seguidores (<\/span><span style=\"color:#008000\"><span class='bible'>Mat 5:38-42<\/span><\/span>), y Pablo desaprobaba los juicios entre creyentes por causa de sus testimonios (<\/span><span style=\"color:#008000\"><span class='bible'>1Co 6:7<\/span><\/span>).<\/span><\/p>\n<p> <\/td>\n<\/tr>\n<tr align=\"left\" valign=\"top\">\n<td style=\"width:431pt;border-top: 1pt solid #000000;border-right: 1pt solid #000000;border-bottom: 1pt solid #000000;border-left: 1pt solid #000000\">\n<p lang=\"es-ES\" style=\"text-indent:0pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\">Como sea, los cristianos nunca deben ignorar la injusticia. Podemos decidir retirarnos del trabajo si nuestro empleador es groseramente injusto. Pero debemos hacerlo no como un acto de cobard\u00eda o por no querer sufrir penurias, sino para honrar a Cristo, o bien para encontrar una alternativa divina constructiva en alg\u00fan otro lugar.<\/p>\n<p> <\/td>\n<\/tr>\n<\/table>\n<h3 align='right'><i><b>Fuente: Nuevo Comentario Ilustrado de la Biblia Caribe<\/b><\/i><\/h3>\n<p><b>SOMETEOS A TODA INSTITUCI\u00d3N HUMANA.<\/b> V\u00e9ase <span class=\"bible\">Rom 13:1<\/span>, nota.<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio Vida Plena<\/b><\/i><\/h3>\n<p><b>Por causa del Se\u00f1or.<\/b> Aunque la ciudadan\u00eda verdadera del cristiano est\u00e1 en el cielo (<span class='bible'>Flp 3:20<\/span>) \u00e9l debe vivir como un ciudadano obediente en este mundo para que Dios sea honrado y glorificado. La conducta rebelde de un cristiano trae deshonra y descr\u00e9dito a Cristo. <i>Vea las notas sobre<\/i> <span class='bible'>Rom 13:1-5<\/span><i>;<\/i> <span class='bible'>Tit 3:1-2<\/span>. <b>someteos.<\/b> Este es un t\u00e9rmino militar que significa \u00abdisponerse en filas bajo las \u00f3rdenes del comandante\u00bb y tiene que ver con asumir una actitud de sumisi\u00f3n y humildad. Durante su paso por el mundo bajo la ley humana y la autoridad civil, el pueblo de Dios debe vivir de forma humilde y sumisa en medio de cualquier sociedad imp\u00eda, hostil y calumniadora (cp. los vv. <span class='bible'>1Pe 2:21-23<\/span>; <span class='bible'>Pro 24:21<\/span>; <span class='bible'>Jer 29:4-14<\/span>; <span class='bible'>Mat 22:21<\/span>; <span class='bible'>Rom 13:1<\/span> ss, <span class='bible'>1Ti 2:1<\/span>; <span class='bible'>Heb 10:32-34<\/span>).<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio MacArthur<\/b><\/i><\/h3>\n<p>\t2:13 &#8212; \u00abPor causa del Se\u00f1or\u00bb; es decir, porque es su voluntad y parte de nuestro servicio a \u00e9l. Comp\u00e1rese Efe 6:6-7.<br \/>\n\t&#8211;\u00absometeos a toda instituci\u00f3n humana\u00bb (literalmente, a toda creaci\u00f3n humana). Dice la Ver. S.A., \u00aba toda humana criatura\u00bb. La Ver. N.M. dice, \u00aba toda creaci\u00f3n humana\u00bb. La Ver. T.A. dice, \u00aba toda humana creatura\u00bb. La Ver. NTP. dice, \u00aba toda autoridad humana\u00bb. Obviamente se hace referencia a todo lo que los hombres en autoridad crean en forma de leyes. El cristiano es ciudadano obediente o sumiso. V\u00e9ase Rom 13:1-7. Consid\u00e9rese tambi\u00e9n 1Ti 2:1-2.<br \/>\n\tEn 3:22 Pedro usa la misma palabra griega, para decir \u00absujetar\u00bb, en cuanto a los \u00e1ngeles y su sujeci\u00f3n a Cristo.<br \/>\n\tLa sujeci\u00f3n al gobierno est\u00e1 limitada a lo que no contradiga mandamiento de Dios (Hch 4:19; Hch 5:29).<br \/>\n\t&#8211;\u00abya sea&#8230; superior\u00bb. Los romanos dec\u00edan \u00abemperador\u00bb, pero los griegos y jud\u00edos, \u00abrey\u00bb. V\u00e9anse Jua 19:15; Hch 17:7.<\/p>\n<h3 align='right'><i><b>Fuente: Notas Reeves-Partain<\/b><\/i><\/h3>\n<p><strong><u>EL DEBER DEL CRISTIANO<br \/><\/u><\/strong><\/p>\n<p><\/p>\n<p><strong><span class='bible'>1 Pedro 2:13-15<\/span><\/strong><\/p>\n<\/p>\n<p><\/p>\n<p><em>Someteos a todas las instituciones humanas por causa del Se\u00f1or, ya sea al rey, que ocupa el primer lugar, o a los gobernadores, a los que \u00e9l env\u00eda para castigar a los que obran el mal o recompensar a los que obran el bien; porque la voluntad de Dios es que, haci\u00e9ndolo as\u00ed, le pong\u00e1is un bozal a la ignorancia de gente est\u00fapida.<br \/><\/em><\/p>\n<p><\/p>\n<p><strong>1. COMO CIUDADANO<br \/><\/strong><\/p>\n<p><\/p>\n<p>Pedro considera el deber del cristiano en las diferentes esferas de la vida; y empieza por su deber como ciudadano del pa\u00eds en el que est\u00e1 viviendo.<\/p>\n<p>Nada m\u00e1s lejos del pensamiento del Nuevo Testamento que cualquier clase de anarqu\u00eda. Jes\u00fas hab\u00eda dicho: \u00bb Por tanto, dad al c\u00e9sar lo que le pertenece; y a Dios, lo que Le pertenece\u00bb <em>(<\/em><span class='bible'>Mt 22:21<\/span><em> ). <\/em>Pablo estaba seguro de que los que gobernaban la naci\u00f3n eran enviados de Dios; ante Quien eran responsables, y no inspiraban, por tanto, terror a la persona que viv\u00eda una vida honorable <em>(<\/em><span class='bible'>Rm 13:1-7<\/span><em> ). <\/em>En las Cartas Pastorales se instruye al cristiano que debe orar por los reyes y por todos los que est\u00e1n en autoridad(] <em>Timoteo 2:2). <\/em>La ense\u00f1anza del Nuevo Testamento es que el cristiano tiene que ser un ciudadano bueno y \u00fatil del pa\u00eds en el que desarrolla su vida.<\/p>\n<p>Se ha dicho que fue el miedo el que construy\u00f3 las ciudades, y que la gente se acurrucaba detr\u00e1s de las murallas para sentirse segura. Las personas se agrupan y est\u00e1n dispuestas a vivir bajo ciertas leyes para que los buenos puedan vivir en paz y realizar su trabajo y emprender sus negocios, y a los malos se los mantenga a raya y se les impida hacer el mal. Seg\u00fan el Nuevo Testamento, la vida se supone que ha sido ordenada por Dios, y el estado ha sido ordenado por Dios para proveer y mantener ese orden.<\/p>\n<p>El punto de vista del Nuevo Testamento es perfectamente l\u00f3gico y justo. Mantiene que una persona no puede aceptar los privilegios que proporciona el estado sin aceptar al mismo tiempo las responsabilidades y los deberes que le impone. Por honor y decencia no puede limitarse exclusivamente a nada.<\/p>\n<p>\u00bfC\u00f3mo podemos traducir todo esto a nuestra situaci\u00f3n moderna? C. E. B. Cranfield ha hecho ver con toda claridad que hay una diferencia fundamental entre el estado en los tiempos del Nuevo Testamento y el estado tal como lo conocemos ahora en Europa y en muchos pa\u00edses del mundo. En los tiempos del Nuevo Testamento el estado era <em>autoritario. <\/em>El gobernador ten\u00eda un poder absoluto; y el \u00fanico deber del ciudadano era rendir una obediencia absoluta y pagar los impuestos (<span class='bible'>Rm 13:6-7<\/span> ). En estas condiciones, la nota clave no pod\u00eda por menos de ser <em>sumisi\u00f3n al estado. <\/em>Pero nosotros vivimos en un estado <em>democr\u00e1tico; <\/em>y en una democracia se hace necesaria mucho m\u00e1s que una actitud de sumisi\u00f3n incuestionable. El gobierno no es solamente el gobierno <em>del <\/em>pueblo; es tambi\u00e9n<\/p>\n<\/p>\n<p><em>por y para <\/em>el pueblo. La demanda del Nuevo Testamento es que el cristiano debe cumplir su responsabilidad para con el estado. En un estado autoritario, eso consist\u00eda exclusivamente en <em>sumisi\u00f3n. <\/em>Pero, \u00bfcu\u00e1l es esa obligaci\u00f3n en circunstancias totalmente diferentes, como las de una democracia?<\/p>\n<\/p>\n<p>En cualquier estado tiene que haber una cierta medida de sumisi\u00f3n. Como C. E. B. Cranfield lo expresa, tiene que haber cuna subordinaci\u00f3n voluntaria de la persona a los dem\u00e1s, poniendo el inter\u00e9s y el bienestar de los dem\u00e1s por encima del propio, prefiriendo dar m\u00e1s bien que recibir, servir m\u00e1s bien que ser servido.\u00bb Pero en un estado democr\u00e1tico, la nota clave debe ser, no <em>sumisi\u00f3n, <\/em>sino <em>cooperaci\u00f3n, <\/em>porque el deber del ciudadano no es s\u00f3lo someterse a que le gobiernen, sino asumir la parte que le corresponde en el gobierno. As\u00ed que, si el cristiano ha de cumplir su deber para con el estado, debe asumir su parte en el gobierno. Debe tambi\u00e9n asumir su responsabilidad en el gobierno local y en la vida del sindicato o de la asociaci\u00f3n que incluya su trabajo, profesi\u00f3n o actividad. Es tr\u00e1gico el que tan pocos cristianos realmente cumplan con su deber para con el estado y la sociedad en los que viven.<\/p>\n<p>Todav\u00eda nos falta por decir que el cristiano tiene una obligaci\u00f3n por encima aun de la que tiene para con el estado. Aunque debe darle al c\u00e9sar lo que es del c\u00e9sar, debe tambi\u00e9n darle a Dios lo que es de Dios. A veces debe dejar bien claro que tiene que guardar fidelidad a Dios m\u00e1s bien que a los hombres <em>(<\/em><span class='bible'>Hch 4:19<\/span><em> ; <\/em><span class='bible'>Hch 5:29<\/span><em> ). <\/em>Puede que haya ocasiones, por tanto, en las que el cristiano cumplir\u00e1 su obligaci\u00f3n superior para con el estado rehusando obedecerle e insistiendo en obedecer a Dios. Haci\u00e9ndolo as\u00ed, por lo menos testificar\u00e1 de la verdad; y, en el mejor de los casos, puede que dirija al estado a tomar el camino de Cristo, y en el peor, que tenga que sufrir por su actitud.<\/p>\n<h3 align='right'><i><b>Fuente: Comentario al Nuevo Testamento<\/b><\/i><\/h3>\n<p><i><b>\u2014 jefe del Estado:<\/b><\/i> Lit. rey.<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n Interconfesional HispanoAmericana<\/b><\/i><\/h3>\n<p><span class='bible'>Rom 13:1-7<\/span>; <span class='bible'>Tit 3:1<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n Interconfesional HispanoAmericana<\/b><\/i><\/h3>\n<p>Actitudes ante las autoridades del Estado. La buena conducta debe expresarse en una aceptaci\u00f3n de sumisi\u00f3n a las demandas de toda instituci\u00f3n (DHH, \u201cautoridad\u201d) humana. Es nota ble que Pedro, escribiendo probablemente en tiempos de Ner\u00f3n, a\u00fan ve el Estado como designado por Dios para el mantenimiento de los valores morales (ver Rom. 13:1-7; 1 Tim. 2:1, 2). La conducta recta de los cristianos debe ponerlos por encima de todas las calumnias o sospechas de los ignorantes (15). Los cristianos deben dar al C\u00e9sar lo que es debido (Mat. 22:21), y Pedro no insin\u00faa aqu\u00ed ninguna excepci\u00f3n, aunque \u00e9l sab\u00eda c\u00f3mo negar a las autoridades cuando pretend\u00edan para s\u00ed lo que pertenece a Dios (Hech. 4:19, 20; 5:29).<\/p>\n<p>Es sorprendente que la libertad cristiana es la de vivir como siervos de Dios, cumpliendo su voluntad (16). Por lo tanto, no es la licencia para complacerse a uno mismo, bajo el pretexto de la \u201cpermisividad\u201d. Cuatro breves mandatos resumen estos requisitos pr\u00e1cticos: todos deben ser respetados, por ser aquellos por quienes Cristo muri\u00f3 y en quienes puede ser restaurada la imagen divina; los hermanos deben ser amados; a Dios hay que acercarse en adoraci\u00f3n (i.e. temor reverente; ver Heb. 12:28, 29) y el rey debe ser tratado con respeto.<\/p>\n<p>Notas. 13 Por causa del Se\u00f1or nos recuerda tanto el ejemplo como la ense\u00f1anza de Jes\u00fas. La soberan\u00eda (BA, \u201cautoridad\u201d) es sobre las instituciones humanas. 17 Pedro cita Prov. 24:21, donde el autor usa la misma palabra para describir las actitudes hacia Dios como hacia el rey. Pedro no hace lo mismo.<\/p>\n<h3 align='right'><i><b>Fuente: Nuevo Comentario B\u00edblico Siglo Veintiuno<\/b><\/i><\/h3>\n<p>NOTAS<\/p>\n<p>(1) \u201cDel Se\u00f1or\u201d, \u05d0AB; VgcSyp: \u201cde Dios\u201d; J7,8: \u201cde Jehov\u00e1\u201d.<\/p>\n<p>REFERENCIAS CRUZADAS<\/p>\n<p>d 103 Rom 13:1; Tit 3:1<\/p>\n<p>e 104 Efe 6:5<\/p>\n<p>f 105 1Pe 2:17<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n del Nuevo Mundo<\/b><\/i><\/h3>\n<p><p> Someteos, por causa del Se\u00f1or.  Pedro exhorta a los cristianos a que obedezcan las leyes del gobierno. Deben obedecer para honrar a Dios y no s\u00f3lo para evitar el castigo, pues Dios es el que estableci\u00f3 toda autoridad (Ro 13:1).<\/p>\n<p><h3 align='right'><i><b>Fuente: La Biblia de las Am\u00e9ricas<\/b><\/i><\/h3>\n<p>\n13<strong> (1)<\/strong> Todo lo mencionado entre este vers\u00edculo y el v.20 son detalles que muestran las buenas obras de la excelente manera de vivir (v.12). <\/p>\n<\/p>\n<p>\n13<strong> (2)<\/strong> Para la expresi\u00f3n y glorificaci\u00f3n del Se\u00f1or (v.12). <\/p>\n<\/p>\n<p>\n13<strong> (3)<\/strong> Lit, creaci\u00f3n, como en Col_1:15 . Se refiere a cualquier cosa hecha, a cualquier persona, edificio, regulaci\u00f3n u ordenanza. <\/p>\n<h3 align='right'><i><b>Fuente: Comentario Del Nuevo Testamento Versi\u00f3n Recobro<\/b><\/i><\/h3>\n<p>Los cristianos han de ser ciudadanos cumplidores de las leyes. Por supuesto, si las leyes de los gobiernos humanos violan la voluntad revelada de Dios, entonces el creyente tiene que obedecer a Dios, aunque tenga que sufrir los castigos que tales leyes humanas impongan. Cp. <span class='bible'>Rom 13:1-7<\/span> y <span class='bible'>Tit 3:1-2<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio Anotada por Ryrie<\/b><\/i><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Estad sujetos a toda instituci\u00f3n humana por causa del Se\u00f1or; ya sea al rey como quien ejerce soberan\u00eda, 2:13 \u2014 \u00abPor causa del Se\u00f1or\u00bb; es decir, porque es su voluntad y parte de nuestro servicio a \u00e9l. Comp\u00e1rese Efe 6:6-7. \u2014 \u00absometeos a toda instituci\u00f3n humana\u00bb (literalmente, a toda creaci\u00f3n humana). Dice la Ver. S.A., &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/comentario-de-1-pedro-213-exegesis-y-hermeneutica-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abComentario de 1 Pedro 2:13 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-31041","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/31041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=31041"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/31041\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=31041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=31041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=31041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}