{"id":31115,"date":"2022-06-20T14:14:30","date_gmt":"2022-06-20T19:14:30","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/comentario-de-2-pedro-17-exegesis-y-hermeneutica-de-la-biblia\/"},"modified":"2022-06-20T14:14:30","modified_gmt":"2022-06-20T19:14:30","slug":"comentario-de-2-pedro-17-exegesis-y-hermeneutica-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/comentario-de-2-pedro-17-exegesis-y-hermeneutica-de-la-biblia\/","title":{"rendered":"Comentario de 2 Pedro 1:7 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia"},"content":{"rendered":"<h3 align='center'><b><i>a la devoci\u00f3n, afecto fraternal; y al afecto fraternal, amor.<\/i><\/b><\/h3>\n<p \/> <span>1:7<\/span> \u2014 \u00aba la piedad, afecto fraternal\u00bb. El nombre propio, Filadelfia, es transliteraci\u00f3n de la palabra griega (filadelfia) para decir \u00abel amor de hermanos\u00bb. V\u00e9ase <span>1Pe 1:22<\/span>, comentarios. Aparece en <span>Rom 12:10<\/span>; <span>1Ts 4:9<\/span>; <span>Heb 13:1<\/span>; <span>1Pe 1:22<\/span>, (\u00abamor fraternal\u00bb). Comp\u00e1rese <span>1Jn 5:1<\/span>. El amor hacia los hermanos es especial (<span>G\u00e1l 6:10<\/span>, \u00abmayormente a los de la familia de la fe\u00bb). Otras versiones, en lugar de afecto fraternal, dicen \u00abfraternidad\u00bb, \u00abcari\u00f1o fraternal\u00bb, y \u00abcari\u00f1o entre hermanos\u00bb. V\u00e9ase <span>Jua 13:34-35<\/span>. <\/p>\n<p \/> \u2014 \u00aby al afecto fraternal, amor\u00bb. Aqu\u00ed aparece la palabra griega, AGAPE. Significa el amor hacia el hombre como a un ser humano (<span>Mat 5:44<\/span>). La conducta que produce es el punto de Pablo en <span>1Co 13:1-13<\/span>. Algunas versiones emplean la palabra \u00abcaridad\u00bb (NTP, T.A., S.A. N.C., B.J.), pero la palabra \u00abcaridad\u00bb hoy en d\u00eda es m\u00e1s bien una sola expresi\u00f3n del amor, limitada a la beneficencia. El \u00abamor\u00bb (Agape) es mucho m\u00e1s que eso. No es natural amar al enemigo, como lo es al pariente de uno. Si amamos al enemigo, es porque Cristo nos manda hacerlo. Es amor por escogimiento. Al amar as\u00ed, somos como Dios (<span>Jua 3:16<\/span>; <span>Rom 5:8<\/span>). <\/p>\n<p \/> Un pasaje semejante a \u00e9ste de Pedro se encuentra en <span>Col 3:12-14<\/span>, palabras de Pablo (pero los dos, hablando por direcci\u00f3n del mismo Esp\u00edritu Santo). <\/p>\n<p \/> El punto de Pedro en los vv. <span>5-7<\/span> no es que importe el orden en que aparecen estas \u00abcualidades, o virtudes, cristianas\u00bb (como a veces se llaman), ni que no se puedan mencionar en otro orden, sino que el cristiano se procure suplirlas en su vida. Es lo que le toca hacer. Cualquier virtud de \u00e9stas sola no basta.<\/p>\n<h3 align='right'><i><b>Fuente: Comentario al Nuevo Testamento por Partain<\/b><\/i><\/h3>\n<p><b><i>amor fraternal.<\/i><\/b> <span class='bible'>Jua 13:34<\/span>, <span class='bible'>Jua 13:35<\/span>; <span class='bible'>Rom 12:10<\/span>; <span class='bible'>1Ts 3:12<\/span>; <span class='bible'>1Ts 4:9<\/span>, <span class='bible'>1Ts 4:10<\/span>; <span class='bible'>Heb 13:1<\/span>; <span class='bible'>1Pe 1:22<\/span>; <span class='bible'>1Pe 2:17<\/span>; <span class='bible'>1Jn 3:14<\/span>, <span class='bible'>1Jn 3:16<\/span>.<\/p>\n<p><b><i>amor.<\/i><\/b> <span class='bible'>1Co 13:1-8<\/span>; <span class='bible'>G\u00e1l 6:10<\/span>; <span class='bible'>Col 3:14<\/span>; <span class='bible'>1Ts 5:15<\/span>; <span class='bible'>1Pe 3:8<\/span>; <span class='bible'>1Jn 4:21<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: El Tesoro del Conocimiento B\u00edblico<\/b><\/i><\/h3>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\">La palabra griega traducida\u00a0<\/span><span style=\"font-weight:bold\">piedad<\/span>\u00a0la usaron los antiguos paganos para describir a un individuo religioso que se manten\u00eda en estrecha relaci\u00f3n con los dioses. Aqu\u00ed Pedro usa la palabra para hablar de la necesidad que tienen los cristianos de estar continuamente conscientes de la presencia de Dios. El hecho de saber que nuestra vida completa est\u00e1 en sus manos deber\u00eda ejercer influencia en todos los aspectos de nuestra vida. Nosotros debemos vivir para Dios y no para nosotros mismos. El\u00a0<\/span><span style=\"font-weight:bold\">afecto fraternal<\/span>\u00a0se relaciona tan estrechamente con la\u00a0<\/span><span style=\"font-style:italic\">piedad<\/span>\u00a0que<\/span> <span style=\"color:#008000\"><span class='bible'>1Jn 4:20<\/span><\/span>\u00a0dice: \u00abSi alguno dice: Yo amo a Dios, y aborrece a su hermano, es mentiroso\u00bb. Como Cristo ense\u00f1\u00f3 en<\/span> <span style=\"color:#008000\"><span class='bible'>Jua 15:12-17<\/span><\/span>, el amor involucra servirse unos a otros, compartir unos con otros y orar unos por otros.<\/span><\/p>\n<p> <\/p>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\"><span style=\"font-weight:bold\">amor<\/span>\u00a0aqu\u00ed se refiere al tipo de amor que tiene Dios, que no se origina en la persona amada, sino en el que ama. Dios ama porque \u00c9l es amor y nosotros tenemos que amar porque somos de Dios. Tal amor llega m\u00e1s all\u00e1 de la comunidad cristiana, a todo el mundo, a todo lugar; busca el bien mayor para los dem\u00e1s, incluso a costa de nosotros mismos.<\/span><\/p>\n<p><\/p>\n<h3 align='right'><i><b>Fuente: Nuevo Comentario Ilustrado de la Biblia Caribe<\/b><\/i><\/h3>\n<p><b>afecto fraternal.<\/b> Es decir, afecto fraternal y disposici\u00f3n al sacrificio mutuo (cp. <span class='bible'>1Jn 4:20<\/span>). <b>amor.<\/b> Vea <span class='bible'>1Co 13:1-13<\/span>; <span class='bible'>1Pe 4:8<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio MacArthur<\/b><\/i><\/h3>\n<p>\t1:7 &#8212; \u00aba la piedad, afecto fraternal\u00bb. El nombre propio, Filadelfia, es transliteraci\u00f3n de la palabra griega (filadelfia) para decir \u00abel amor de hermanos\u00bb. V\u00e9ase 1Pe 1:22, comentarios. Aparece en Rom 12:10; 1Ts 4:9; Heb 13:1; 1Pe 1:22, (\u00abamor fraternal\u00bb). Comp\u00e1rese 1Jn 5:1. El amor hacia los hermanos es especial (G\u00e1l 6:10, \u00abmayormente a los de la familia de la fe\u00bb). Otras versiones, en lugar de afecto fraternal, dicen \u00abfraternidad\u00bb, \u00abcari\u00f1o fraternal\u00bb, y \u00abcari\u00f1o entre hermanos\u00bb. V\u00e9ase Jua 13:34-35.<br \/>\n\t&#8211;\u00aby al afecto fraternal, amor\u00bb. Aqu\u00ed aparece la palabra griega, AGAPE. Significa el amor hacia el hombre como a un ser humano (Mat 5:44). La conducta que produce es el punto de Pablo en 1Co 13:1-13. Algunas versiones emplean la palabra \u00abcaridad\u00bb (NTP, T.A., S.A. N.C., B.J.), pero la palabra \u00abcaridad\u00bb hoy en d\u00eda es m\u00e1s bien una sola expresi\u00f3n del amor, limitada a la beneficencia. El \u00abamor\u00bb (Agape) es mucho m\u00e1s que eso. No es natural amar al enemigo, como lo es al pariente de uno. Si amamos al enemigo, es porque Cristo nos manda hacerlo. Es amor por escogimiento. Al amar as\u00ed, somos como Dios (Jua 3:16; Rom 5:8).<br \/>\n\tUn pasaje semejante a \u00e9ste de Pedro se encuentra en Col 3:12-14, palabras de Pablo (pero los dos, hablando por direcci\u00f3n del mismo Esp\u00edritu Santo).<br \/>\n\tEl punto de Pedro en los vv. 5-7 no es que importe el orden en que aparecen estas \u00abcualidades, o virtudes, cristianas\u00bb (como a veces se llaman), ni que no se puedan mencionar en otro orden, sino que el cristiano se procure suplirlas en su vida. Es lo que le toca hacer. Cualquier virtud de \u00e9stas sola no basta.<\/p>\n<h3 align='right'><i><b>Fuente: Notas Reeves-Partain<\/b><\/i><\/h3>\n<p><i><b>\u2014 el amor:<\/b><\/i> Esta lista encadenada de virtudes es un recurso literario utilizado con frecuencia en la cultura helen\u00edstica. Habitualmente, la primera y la \u00faltima (en el presente caso la fe y el amor) se consideran las m\u00e1s importantes.<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n Interconfesional HispanoAmericana<\/b><\/i><\/h3>\n<p>REFERENCIAS CRUZADAS<\/p>\n<p>t 20 1Ts 4:9<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n del Nuevo Mundo<\/b><\/i><\/h3>\n<p>\n7<strong> (1)<\/strong> La palabra griega se compone de <em> sentir afecto <\/em> y <em> un hermano por lo tanto, un afecto fraternal, un amor caracterizado por deleite y placer. En la piedad, que es la expresi\u00f3n de Dios, es necesario que este amor sea suministrado por el bien de la hermandad ( 1Pe_2:17 3:8; G\u00e1l_6:10), para que tengamos nuestro testimonio ante el mundo ( Jua_13:34-35) y para que llevemos fruto ( Jua_15:16-17). <\/p>\n<\/p>\n<p>\n7<strong> (2)<\/strong> Esta palabra griega en el Nuevo Testamento significa amor divino, el cual es Dios en Su naturaleza ( 1Jn_4:8 , 1Jn_4:16). Es un amor m\u00e1s noble que el amor humano y adorna todas las cualidades de la vida cristiana (1co 13; Rom_13:8-10 G\u00e1l_5:13-14). Es m\u00e1s fuerte y tiene m\u00e1s capacidad que el amor humano ( Mat_5:44 , Mat_5:46), a\u00fan as\u00ed un creyente que viva por la vida divina (v.3) y participe de la naturaleza divina (v.4) puede ser saturado de dicho amor y expresarlo en plenitud. Es necesario que tal amor sea desarrollado en el amor fraternal para gobernarlo y fluir en \u00e9l a fin de que Dios, quien es este amor, sea expresado plenamente. Puede considerarse que la fe es la simiente de vida y que este amor m\u00e1s noble es el fruto (v.8) en su desarrollo pleno. Los seis pasos intermedios de desarroll\u00f3 son las etapas de su crecimiento hacia la madurez. <\/p>\n<h3 align='right'><i><b>Fuente: Comentario Del Nuevo Testamento Versi\u00f3n Recobro<\/b><\/i><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>a la devoci\u00f3n, afecto fraternal; y al afecto fraternal, amor. 1:7 \u2014 \u00aba la piedad, afecto fraternal\u00bb. El nombre propio, Filadelfia, es transliteraci\u00f3n de la palabra griega (filadelfia) para decir \u00abel amor de hermanos\u00bb. V\u00e9ase 1Pe 1:22, comentarios. Aparece en Rom 12:10; 1Ts 4:9; Heb 13:1; 1Pe 1:22, (\u00abamor fraternal\u00bb). Comp\u00e1rese 1Jn 5:1. El amor &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/comentario-de-2-pedro-17-exegesis-y-hermeneutica-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abComentario de 2 Pedro 1:7 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-31115","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/31115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=31115"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/31115\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=31115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=31115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=31115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}