{"id":31256,"date":"2022-06-20T14:21:14","date_gmt":"2022-06-20T19:21:14","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/comentario-de-1-juan-53-exegesis-y-hermeneutica-de-la-biblia\/"},"modified":"2022-06-20T14:21:14","modified_gmt":"2022-06-20T19:21:14","slug":"comentario-de-1-juan-53-exegesis-y-hermeneutica-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/comentario-de-1-juan-53-exegesis-y-hermeneutica-de-la-biblia\/","title":{"rendered":"Comentario de 1 Juan 5:3 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia"},"content":{"rendered":"<h3 align='center'><b><i>Pues \u00e9ste es el amor de Dios: que guardemos sus mandamientos. Y sus mandamientos no son gravosos.<\/i><\/b><\/h3>\n<p \/> <span>5:3<\/span> <\/p>\n<p \/>\u2014 \u201cPues este es el amor a Dios,\u201d V\u00e9ase <span>2:5<\/span>, comentarios. <\/p>\n<p \/> \u2014 \u201cque guardemos sus mandamientos;\u201d V\u00e9ase <span>Jua 14:15<\/span>; <span>Jua 14:23<\/span>. El verbo griego es subjuntivo activo presente. Dice Juan que el (cristiano, hijo de Dios) que persiste habitualmente en el acto de guardar los mandamientos de Dios, prueba as\u00ed que tiene amor a Dios. El que no est\u00e1 guardando de continuo sus mandamientos, no le ama, a pesar de sus reclamaciones de labios. Aqu\u00ed la frase \u201cguardar sus mandamientos\u201d apunta a una caracter\u00edstica de vida. Sobre \u201cguardar sus mandamientos\u201d, v\u00e9ase el mismo verbo griego empleado en 2:3,4. <\/p>\n<p \/> Reclamar amar a Dios y no vivir diariamente en obediencia a los mandamientos de Dios, es mentir (1:6; 4:20). <\/p>\n<p \/> \u2014 \u201cy sus mandamientos no son gravosos.\u201d \u00bfDebemos evitar el guardar los mandamientos de Dios (de creer en la humanidad y en la deidad de Cristo, y de amar a los hermanos y a \u00e9l, quien primero nos am\u00f3 a nosotros)? \u00a1No! pues no son gravosos los mandamientos de Dios. Es un gran privilegio guardarlos y gozar de la vida eterna (<span>2:25<\/span>). Es una carga ligera obedecer al que nos salva eternamente a nosotros que no merecemos tal amor. Nuestra fe en Jesucristo hace que sean \u201cno gravosos\u201d los mandamientos de Dios, porque por esta fe vencemos al mundo (vers\u00edculo 4). Si no tuvi\u00e9ramos esta fe, ser\u00edamos ahogados por la mundanalidad y nos ser\u00edan muy gravosos sus mandamientos. <\/p>\n<p \/> Comp\u00e1rense <span>Mat 11:30<\/span>; <span>Sal 19:11<\/span>. Contr\u00e1stese <span>Mat 23:4<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: Comentario al Nuevo Testamento por Partain<\/b><\/i><\/h3>\n<p><b><i>este es el amor de Dios.<\/i><\/b> <span class='bible'>\u00c9xo 20:6<\/span>; <span class='bible'>Deu 5:10<\/span>; <span class='bible'>Deu 7:9<\/span>; <span class='bible'>Deu 10:12<\/span>, <span class='bible'>Deu 10:13<\/span>; <span class='bible'>Dan 9:4<\/span>; <span class='bible'>Mat 12:47-50<\/span>; <span class='bible'>Jua 14:15<\/span>; <span class='bible'>Jua 14:21-24<\/span>; <span class='bible'>Jua 15:10<\/span>, <span class='bible'>Jua 15:14<\/span>; <span class='bible'>2Jn 1:6<\/span>.<\/p>\n<p><b><i>y sus mandamientos.<\/i><\/b> <span class='bible'>Sal 19:7-11<\/span>; <span class='bible'>Sal 119:45<\/span>, <span class='bible'>Sal 119:47<\/span>, <span class='bible'>Sal 119:48<\/span>, <span class='bible'>Sal 119:103<\/span>, <span class='bible'>Sal 119:104<\/span>, <span class='bible'>Sal 119:127<\/span>, <span class='bible'>Sal 119:128<\/span>, <span class='bible'>Sal 119:140<\/span>; <span class='bible'>Pro 3:17<\/span>; <span class='bible'>Miq 6:8<\/span>; <span class='bible'>Mat 11:28-30<\/span>; <span class='bible'>Rom 7:12<\/span>, <span class='bible'>Rom 7:22<\/span>; <span class='bible'>Heb 8:10<\/span>. <\/p>\n<h3 align='right'><i><b>Fuente: El Tesoro del Conocimiento B\u00edblico<\/b><\/i><\/h3>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\"><span style=\"font-weight:bold\">el amor a Dios<\/span>\u00a0exige obediencia (<\/span><span style=\"color:#008000\"><span class='bible'>Jua 14:15<\/span><\/span>). Sin embargo, en vez de ser\u00a0<\/span><span style=\"font-weight:bold\">gravoso<\/span>, Dios le pide a los creyentes libres que sean las personas que originalmente fueron creadas para ser: seres santos que reflejaban claramente la imagen de Dios.<\/span><\/p>\n<p><\/p>\n<h3 align='right'><i><b>Fuente: Nuevo Comentario Ilustrado de la Biblia Caribe<\/b><\/i><\/h3>\n<p><b>sus mandamientos no son gravosos.<\/b> Por ejemplo, a diferencia de las tradiciones religiosas de fabricaci\u00f3n humana que los l\u00edderes jud\u00edos impon\u00edan como una carga pesada (<span class='bible'>Mat 23:4<\/span>) el yugo de Jes\u00fas es f\u00e1cil y su carga es ligera (<span class='bible'>Mat 11:30<\/span>).<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio MacArthur<\/b><\/i><\/h3>\n<p>\t5:3 &#8212; \u201cPues este es el amor a Dios,\u201d V\u00e9ase 2:5, comentarios.<br \/>\n\t&#8212; \u201cque guardemos sus mandamientos;\u201d V\u00e9ase Jua 14:15; Jua 14:23. El verbo griego es subjuntivo activo presente. Dice Juan que el (cristiano, hijo de Dios) que persiste habitualmente en el acto de guardar los mandamientos de Dios, prueba as\u00ed que tiene amor a Dios. El que no est\u00e1 guardando de continuo sus mandamientos, no le ama, a pesar de sus reclamaciones de labios. Aqu\u00ed la frase \u201cguardar sus mandamientos\u201d apunta a una caracter\u00edstica de vida. Sobre \u201cguardar sus mandamientos\u201d, v\u00e9ase el mismo verbo griego empleado en 2:3,4.<br \/>\n\tReclamar amar a Dios y no vivir diariamente en obediencia a los mandamientos de Dios, es mentir (1:6; 4:20).<br \/>\n\t&#8212; \u201cy sus mandamientos no son gravosos.\u201d \u00bfDebemos evitar el guardar los mandamientos de Dios (de creer en la humanidad y en la deidad de Cristo, y de amar a los hermanos y a \u00e9l, quien primero nos am\u00f3 a nosotros)? \u00a1No! pues no son gravosos los mandamientos de Dios. Es un gran privilegio guardarlos y gozar de la vida eterna (2:25). Es una carga ligera obedecer al que nos salva eternamente a nosotros que no merecemos tal amor. Nuestra fe en Jesucristo hace que sean \u201cno gravosos\u201d los mandamientos de Dios, porque por esta fe vencemos al mundo (vers\u00edculo 4). Si no tuvi\u00e9ramos esta fe, ser\u00edamos ahogados por la mundanalidad y nos ser\u00edan muy gravosos sus mandamientos.<br \/>\n\tComp\u00e1rense Mat 11:30; Sal 19:11. Contr\u00e1stese Mat 23:4.<\/p>\n<h3 align='right'><i><b>Fuente: Notas Reeves-Partain<\/b><\/i><\/h3>\n<p><strong><u>LA OBEDIENCIA IMPRESCINDIBLE<br \/><\/u><\/strong><\/p>\n<p><\/p>\n<p><strong><span class='bible'>1 Juan 5:3-4<\/span><\/strong><strong>a<\/strong><\/p>\n<\/p>\n<p><\/p>\n<p><em>Porque esto es el amor de Dios: que guardemos Sus mandamientos; y Sus mandamientos no son gravosos, porque todo lo que es nacido de Dios conquista al mundo.<br \/><\/em><\/p>\n<p><\/p>\n<p>Juan vuelve a una idea que nunca est\u00e1 muy lejos de su mente: <em>la obediencia es la \u00fanica prueba del amor. <\/em>No podemos demostrarle nuestro amor a nadie nada m\u00e1s que tratando de agradarle y de producirle satisfacci\u00f3n.<\/p>\n<p>Entonces Juan dice repentinamente una cosa de lo m\u00e1s sorprendente. Los mandamientos de Dios, dice, no son gravosos. Aqu\u00ed debemos fijarnos en dos cuestiones generales.<\/p>\n<p>Desde luego que no quiere decir que la obediencia a los mandamientos de Dios sea f\u00e1cil de alcanzar. El amor cristiano no es una cuesti\u00f3n superficial. No es nunca f\u00e1cil amar a personas que no nos gustan, o que hieren nuestros sentimientos, o que nos injurian. Nunca es f\u00e1cil resolver los problemas de la convivencia; y, cuando se convierten en el problema de vivir juntos a la altura del nivel cristiano de la vida, es una tarea de dificultad inmensa.<\/p>\n<p>Adem\u00e1s, hay en este dicho un contraste impl\u00edcito. Jes\u00fas dec\u00eda que los escribas y los fariseos ataban fardos pesados y dif\u00edciles de llevar, y se los cargaban a los dem\u00e1s <em>(<\/em><span class='bible'>Mt 23:4<\/span><em> ). <\/em>La masa de reglas y de normas de los escribas y fariseos pod\u00eda ser una carga insoportable para los hombros de cualquiera. No hay duda que Juan estaba recordando el dicho de Jes\u00fas: \u00abMi yugo es f\u00e1cil, y ligera Mi carga\u00bb <em>(<\/em><span class='bible'>Mt 11:30<\/span><em> ).<\/em><\/p>\n<\/p>\n<p>Entonces, \u00bfc\u00f3mo se puede explicar esto? \u00bfC\u00f3mo se puede decir que las tremendas demandas de Jes\u00fas no son una carga pesada? Se puede responder a esta pregunta de tres maneras.<\/p>\n<p>(i) Dios nunca le impone un mandamiento a nadie sin darle tambi\u00e9n las fuerzas para cumplirlo. Con la visi\u00f3n viene el poder; con la necesidad vienen las fuerzas. Dios no nos da Sus mandamientos y luego Se retira, dej\u00e1ndonos a nuestros escasos recursos. Sigue all\u00ed, a nuestro lado, para capacitarnos para cumplir lo que nos ha mandado. Lo que es imposible para nosotros se hace posible con Dios.<\/p>\n<p>(ii) Pero aqu\u00ed hay otra gran verdad. Nuestra respuesta a Dios debe ser la respuesta del amor; y no hay deber demasiado molesto, ni tarea demasiado pesada para el amor. Lo que no har\u00edamos nunca por un extra\u00f1o lo intentamos para alguien que nos es querido; lo que ser\u00eda un sacrificio imposible si nos lo pidiera un extra\u00f1o se convierte en una contribuci\u00f3n voluntaria cuando lo necesita ser amado.<\/p>\n<p>Hay una vieja historia que es una especie de par\u00e1bola que viene a cuento. Alguien se encontr\u00f3 una vez a un chico que iba a la escuela, en aquellos tiempos en que no hab\u00eda transporte escolar, llevando a sus espaldas a otro chico m\u00e1s peque\u00f1o que estaba impedido y no pod\u00eda andar. El extra\u00f1o le dijo al chico: \u00ab\u00bfLe llevas as\u00ed a la escuela todos los d\u00edas?\u00bb \u00bb S\u00ed,\u00bb le contest\u00f3 el muchacho. \u00abEso es una carga muy pesada para ti,\u00bb dijo el&#8217; extra\u00f1o. \u00abNo es una carga -dijo el chico-. Es mi hermano.\u00bb<\/p>\n<p>El amor hac\u00eda que la carga no lo fuera en realidad. As\u00ed debe pasar entre nosotros y Cristo. Sus mandamientos no son gravosos, sino un privilegio y una oportunidad para demostrar nuestro amor. Son dif\u00edciles, pero no son gravosos; porque Cristo nunca le impuso a nadie un mandamiento sin darle las fuerzas para cumplirlo; y un mandamiento nos provee de otra oportunidad de demostrar nuestro amor.<\/p>\n<p>Debemos dejar la tercera respuesta para la pr\u00f3xima secci\u00f3n.<\/p>\n<h3 align='right'><i><b>Fuente: Comentario al Nuevo Testamento<\/b><\/i><\/h3>\n<p><span class='bible'>Deu 30:11<\/span>; <span class='bible'>Mat 11:30<\/span>; <span class='bible'>Jua 14:15<\/span>; <span class='bible'>Jua 14:23-24<\/span>; <span class='bible'>Jua 15:10<\/span>; <span class='bible'>2Jn 1:6<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n Interconfesional HispanoAmericana<\/b><\/i><\/h3>\n<p>REFERENCIAS CRUZADAS<\/p>\n<p>f 234 Jua 14:23; 2Jn 1:6<\/p>\n<p>g 235 Deu 5:29; Deu 12:28<\/p>\n<p>h 236 Deu 30:11; Miq 6:8<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n del Nuevo Mundo<\/b><\/i><\/h3>\n<p> 3 <strong>super (1)<\/strong> V\u00e9anse las notas 5 <strong>super (2)<\/strong> y 1. 15 <strong>super (3)<\/strong> del cap.2.<\/p>\n<p> 3 <strong>super (2)<\/strong> Guardar los mandamientos de Dios constituye nuestro amor para con El y es evidencia de que le amamos.<\/p>\n<p> 3 <strong>super (3)<\/strong> Lit., pesados. Los mandamientos de Dios no son pesados para la vida divina, dado que \u00e9sta es tan capaz.<\/p>\n<h3 align='right'><i><b>Fuente: Comentario Del Nuevo Testamento Versi\u00f3n Recobro<\/b><\/i><\/h3>\n<p><i><b>que&#8230;<\/b><\/i> Por una parte <i>theo\u00fa<\/i> es genitivo (de Dios), y por la otra, la conjunci\u00f3n <i>\u00edna = para<\/i> <i>que<\/i>, sirve para expresar un t\u00e9rmino de conclusi\u00f3n; <i><b>mandamientos&#8230;<\/b><\/i> \u2192 <span style=\"color:#008000\"><span class=\"bible\">Jua 14:15<\/span><\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: Biblia Textual IV Edici\u00f3n<\/b><\/i><\/h3>\n<p>R993 Aqu\u00ed el uso apositivo de \u1f35\u03bd\u03b1 es paralelo a \u1f45\u03c4\u03b9 (comp. los vv. 9, 11 y Jua 4:34): que. <\/p>\n<h3 align='right'><i><b>Fuente: Ayuda gramatical para el Estudio del Nuevo Testamento Griego<\/b><\/i><\/h3>\n<p>Por una parte <em>theou250?<\/em> es genitivo <em>(de Dios),<\/em> y por la otra, la conjunci\u00f3n <em>ina = para que<\/em>, sirve para expresar un t\u00e9rmino de conclusi\u00f3n.<\/p>\n<p> 5.3 g <span class='bible'>Jua 14:15<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: La Biblia Textual III Edici\u00f3n<\/b><\/i><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Pues \u00e9ste es el amor de Dios: que guardemos sus mandamientos. Y sus mandamientos no son gravosos. 5:3 \u2014 \u201cPues este es el amor a Dios,\u201d V\u00e9ase 2:5, comentarios. \u2014 \u201cque guardemos sus mandamientos;\u201d V\u00e9ase Jua 14:15; Jua 14:23. El verbo griego es subjuntivo activo presente. Dice Juan que el (cristiano, hijo de Dios) que &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/comentario-de-1-juan-53-exegesis-y-hermeneutica-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abComentario de 1 Juan 5:3 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-31256","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/31256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=31256"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/31256\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=31256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=31256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=31256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}