{"id":31313,"date":"2022-06-20T14:23:55","date_gmt":"2022-06-20T19:23:55","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/comentario-de-judas-112-exegesis-y-hermeneutica-de-la-biblia\/"},"modified":"2022-06-20T14:23:55","modified_gmt":"2022-06-20T19:23:55","slug":"comentario-de-judas-112-exegesis-y-hermeneutica-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/comentario-de-judas-112-exegesis-y-hermeneutica-de-la-biblia\/","title":{"rendered":"Comentario de Judas 1:12 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia"},"content":{"rendered":"<h3 align='center'><b><i>Estos que participan en vuestras comidas fraternales son manchas, apacent\u00e1ndose a s\u00ed mismos sin temor alguno. Son nubes sin agua, llevadas de ac\u00e1 para all\u00e1 por los vientos. Son \u00e1rboles marchitos como en oto\u00f1o, sin fruto, dos veces muertos y desarraigados.<\/i><\/b><\/h3>\n<p \/> v. <span>12<\/span> \u2014 V\u00e9ase <span>2Pe 2:13<\/span>. \u00abEstos son manchas\u00bb. \u00abSon escollos\u00bb, dice la Versi\u00f3n Hispanoamericana. La palabra griega spilas significa una rosca o escollo que podr\u00eda causar naufragio por cuanto est\u00e1 escondido bajo el agua. La conducta excesiva de estos maestros, dice Judas, da\u00f1a grandemente la moralidad de los hermanos, como el escollo al barco, y trae desgracia y verg\u00fcenza al cuerpo de Cristo. Como el escollo no advierte, as\u00ed \u00e9stos no anuncian sus prop\u00f3sitos destructores y ruinosos. <\/p>\n<p \/> \u00aben vuestros \u00e1gapes\u00bb. \u00abcomidas de amor fraternal\u00bb, dice la Versi\u00f3n Hispanoamericana. La palabra \u00ab\u00e1gape\u00bb es tomada literalmente del griego, que es agapai (el plural de agape, que quiere decir \u00abamor\u00bb). Seg\u00fan el Sr. Thayer, los \u00ab\u00e1gapes\u00bb eran comidas que manifestaban el amor entre hermanos, proporcionadas por los hermanos ricos y en que participaban los m\u00e1s pobres. Eran celebradas antes de tomar la Cena del Se\u00f1or por cristianos de los primeros siglos, pero descontinuadas en el siglo cuatro, seg\u00fan el testimonio de historiadores, porque fueron convertidas en ocasiones de lascivia por tales hombres como los aqu\u00ed descritos por Judas. Pablo en <span>1Co 11:1-34<\/span> condena la pr\u00e1ctica de corromper la Cena del Se\u00f1or con tales comidas, diciendo que tenemos casas en que comer y beber. Los falsos, a los cuales se refiere Judas, corromp\u00edan estas comidas y abusaron de ellas, llegando para meter sus pr\u00e1cticas lascivas y costumbres sensuales. <\/p>\n<p \/> Hay hermanos hoy en d\u00eda que usan este pasaje para justificar la pr\u00e1ctica moderna de que iglesias de Cristo de sus fondos erijan edificios (cocinas y comedores, y a veces hasta gimnasios, etc\u00e9tera), llamados en ingl\u00e9s fellowship halls (literalmente, salones para comuni\u00f3n), en que juntarse los hermanos para comer y gozarse de una junta puramente social. Viendo muchas iglesias de Cristo que hace mucho tiempo que tienen tales cosas las iglesias sectarias, ahora quieren tambi\u00e9n tener lo mismo. Los \u00ab\u00e1gapes\u00bb de <span>Jud 1:12<\/span> les parece servir de \u00abprueba b\u00edblica\u00bb. <\/p>\n<p \/> Pero, no es as\u00ed. Notemos los siguientes puntos: <\/p>\n<p \/> 1. Las comidas sociales deben ser comidas en la casa, <span>Hch 2:46<\/span>; <span>1Co 11:22<\/span>; <span>1Co 11:34<\/span>. El prop\u00f3sito de la asamblea para culto a Dios no es social, sino espiritual. Son buenas las ocasiones sociales, pero pertenecen al hogar, a la casa. <\/p>\n<p \/> 2. Los \u00ab\u00e1gapes\u00bb no eran actividad de la colectividad (de la iglesia local, tomando dinero de las colectas semanarias para los gastos necesarios), sino de individuos. Los m\u00e1s ricos pagaban los gastos para realizar tales comidas. No hay mal alguno en que algunos hermanos preparen comidas y las sirvan gratis a hermanos m\u00e1s pobres, pero siendo actividad social de parte de individuos, debe ser guardada separada de las actividades de la colectividad (la iglesia local). Para tales comidas, dice Pablo, hay casas en que comer y beber. <\/p>\n<p \/> 3. La palabra \u00abcomuni\u00f3n\u00bb (en ingl\u00e9s fellowship, de donde viene el nombre del sitio para comer y beber \u2014 fellowship hall) no se emplea en el Nuevo Testamento en el sentido de comidas y diversas clases de entretenimiento de naturaleza puramente social. No hay \u00abcaf\u00e9 y pan dulce\u00bb en la palabra \u00abcomuni\u00f3n\u00bb, seg\u00fan usada en el Nuevo Testamento. <\/p>\n<p \/> \u00abque comiendo&#8230; a s\u00ed mismos\u00bb. Pretenden \u00e9stos ser maestros, pero en lugar de alimentar (ense\u00f1ar) a las ovejas, se alimentan a s\u00ed mismos en los \u00e1gapes al grado de ser comilones y gozar de sus concupiscencias. \u00abSe deleitan en sus enga\u00f1os mientras hacen fiesta con vosotros\u00bb, escribe Pedro (<span>2Pe 2:13<\/span>). Comp\u00e1rense <span>Ezequiel 34:2<\/span>; <span>Isa 56:11<\/span>. <\/p>\n<p \/> \u00abnubes&#8230; por los vientos\u00bb. Comp\u00e1rese <span>2Pe 2:17<\/span>. Se presenta en la Biblia la doctrina de Dios bajo la figura de lluvia (<span>Deu 32:2<\/span>). As\u00ed es que presenta Judas a estos falsos maestros como nubes sin agua, o sea, con doctrina sin provecho. e jactan \u00e9stos de grande conocimiento pero son vac\u00edos en realidad. V\u00e9ase <span>Pro 25:14<\/span>. Comp\u00e1rese tambi\u00e9n <span>Efe 4:14<\/span>. Estos son un gran hueco espiritual que prometen mucho y se jactan grandemente, como una nube que a la tierra seca promete lluvia pero pasa sin dejar nada. <\/p>\n<p \/> \u00ab\u00e1rboles&#8230; desarraigados\u00bb. Como la lluvia representa la doctrina, el fruto del \u00e1rbol representa la vida que alguno vive. Estos maestros, como tienen doctrina prometedora pero es falsa, as\u00ed tampoco producen nada bueno de vida. Con estas figuras de ret\u00f3rica, Judas est\u00e1 exponiendo la desolaci\u00f3n espiritual de estos falsos maestros que defraudan las expectaciones de otros, como la higuera maldita por Cristo (<span>Mat 21:19<\/span>; <span>Mar 11:21<\/span>). V\u00e9ase tambi\u00e9n <span>Luc 13:6<\/span>. No solamente son \u00e9stos como \u00e1rboles sin fruto, sino completamente incapaces de llevarlo: \u00abdos veces muertos y desarraigados\u00bb. Tal es el car\u00e1cter de los falsos maestros expuestos por Judas. Comp\u00e1rese <span>Isa 1:30<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: Comentario al Nuevo Testamento por Partain<\/b><\/i><\/h3>\n<p><b><i>estos son manchas.<\/i><\/b> <span class='bible'>2Pe 2:13<\/span>, <span class='bible'>2Pe 2:14<\/span>.<\/p>\n<p>\n<b><i>en vuestros convites, o \u00e1gapes.<\/i><\/b> <span class='bible'>1Co 11:21<\/span>, <span class='bible'>1Co 11:22<\/span>.<\/p>\n<p>\n<b><i>que banquetean, o comiendo imp\u00fadicamente.<\/i><\/b> <span class='bible'>Sal 78:29-31<\/span>; <span class='bible'>Isa 56:10-12<\/span>; <span class='bible'>Eze 34:8<\/span>, <span class='bible'>Eze 34:18<\/span>; <span class='bible'>Luc 12:19<\/span>, <span class='bible'>Luc 12:20<\/span>, <span class='bible'>Luc 12:45<\/span>; <span class='bible'>Luc 16:19<\/span>; <span class='bible'>Luc 21:34<\/span>; <span class='bible'>Flp 3:19<\/span>; <span class='bible'>1Ts 5:6<\/span>, <span class='bible'>1Ts 5:7<\/span>; <span class='bible'>Stg 5:5<\/span>.<\/p>\n<p>\n<b><i>nubes sin aguas.<\/i><\/b> <span class='bible'>Pro 25:14<\/span>; <span class='bible'>Ose 6:4<\/span>; <span class='bible'>2Pe 2:17<\/span>.<\/p>\n<p>\n<b><i>son llevadas de ac\u00e1 para all\u00e1.<\/i><\/b> <span class='bible'>Efe 4:14<\/span>.<\/p>\n<p>\n<b><i>\u00e1rboles oto\u00f1ales.<\/i><\/b> <span class='bible'>Sal 1:3<\/span>; <span class='bible'>Sal 37:2<\/span>; <span class='bible'>Mat 13:6<\/span>; <span class='bible'>Mat 21:19<\/span>, <span class='bible'>Mat 21:20<\/span>; <span class='bible'>Mar 4:6<\/span>; <span class='bible'>Mar 11:21<\/span>; <span class='bible'>Luc 8:6<\/span>; <span class='bible'>Jua 15:4-6<\/span>.<\/p>\n<p>\n<b><i>dos veces muertos.<\/i><\/b> <span class='bible'>1Ti 5:6<\/span>; <span class='bible'>Heb 6:4-8<\/span>; <span class='bible'>2Pe 2:18-20<\/span>.<\/p>\n<p><b><i>y desarraigados.<\/i><\/b> <span class='bible'>2Cr 7:20<\/span>; <span class='bible'>Eze 17:9<\/span>; <span class='bible'>Mat 15:13<\/span>; <span class='bible'>Mar 11:20<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: El Tesoro del Conocimiento B\u00edblico<\/b><\/i><\/h3>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\"><span style=\"font-weight:bold\">manchas en vuestros \u00e1gapes:<\/span>\u00a0El pueblo de Dios fue defraudado por gente que parec\u00eda que eran mensajeros de Dios, pero en vez de eso eran ministros de Satan\u00e1s (<\/span><span style=\"color:#008000\"><span class='bible'>2Co 11:4<\/span><\/span>,<\/span> <span style=\"color:#008000\"><span class='bible'>2Co 11:13-15<\/span><\/span>). La palabra griega\u00a0<\/span><span style=\"font-style:italic\">manchas<\/span>\u00a0se puede traducir como \u00abescollos ocultos\u00bb, y sirve como fuente de advertencia para estar en guardia contra los impostores.<\/span><\/p>\n<p> <\/p>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\"><span style=\"font-weight:bold\">nubes sin agua \u2026 \u00e1rboles sin fruto:<\/span>\u00a0Puede parecer que las nubes traer\u00e1n la lluvia, hasta que el viento las barre (<\/span><span style=\"color:#008000\"><span class='bible'>Pro 25:14<\/span><\/span>). Puede parecer que los \u00e1rboles son productivos, hasta que llega el oto\u00f1o, la \u00e9poca en que hay que recoger los frutos. Los ministros de Satan\u00e1s prometen crecimiento espiritual, pero no satisfacen el hambre de verdad del pueblo de Dios; no s\u00f3lo no tienen frutos, sino tampoco tienen ra\u00edces, por lo que son incapaces de sustentarlos, ya que no pueden aprovechar la verdadera fuente de sustento (<\/span><span style=\"color:#008000\"><span class='bible'>Sal 1:3<\/span><\/span>). Hablan de Dios, pero en verdad no tienen Dios.<\/span><\/p>\n<p> <\/p>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\"><span style=\"font-weight:bold\">fieras ondas del mar \u2026 espuman \u2026 estrellas errantes:<\/span>\u00a0Esta gente sin Dios montaba un gran espect\u00e1culo, pero carec\u00eda de sustancia alguna. Hablaban de libertad, pero pon\u00edan al pueblo de Dios en esclavitud al pecado (<\/span><span style=\"color:#008000\"><span class='bible'>2Pe 2:19<\/span><\/span>). Despu\u00e9s de que comet\u00edan sus malas acciones y lograban sus ganancias, como estrellas errantes, se iban a otros lugares para explotar nuevamente al pueblo de Dios.<\/span><\/p>\n<p> <\/p>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\"><span style=\"font-weight:bold\">eternamente la oscuridad:<\/span>\u00a0Podr\u00eda suceder que no se castigara a estos impostores por sus malas acciones en este mundo y que los cristianos no descubrieran sus acciones, pero su castigo es cierto.<\/span><\/p>\n<p><\/p>\n<h3 align='right'><i><b>Fuente: Nuevo Comentario Ilustrado de la Biblia Caribe<\/b><\/i><\/h3>\n<p><b>DOS VECES MUERTOS.<\/b> Los maestros apostatas entre los lectores de Judas est\u00e1n \u00abdos veces muertos\u00bb (literalmente: \u00abhabiendo muerto dos veces\u00bb). Los falsos maestros fueron en otro tiempo creyentes en Cristo que hab\u00edan \u00abpasado de muerte a vida\u00bb (<span class=\"bible\">Jua 5:24<\/span>) pero despu\u00e9s se separaron de Cristo para pasar de vida a muerte (cf. <span class=\"bible\">Efe 2:1<\/span>; v\u00e9ase <span class=\"bible\">Rom 8:13<\/span>, nota). El vers\u00edculo anterior da la raz\u00f3n de su muerte espiritual.<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio Vida Plena<\/b><\/i><\/h3>\n<p><b>manchas \u2026 \u00e1gapes.<\/b> <i>Vea la nota sobre<\/i> <span class='bible'>2Pe 2:13<\/span>. \u00abManchas\u00bb tambi\u00e9n se puede traducir \u00abrocas escondidas\u00bb O \u00abarrecifes\u00bb. Estos ap\u00f3statas eran manchas de mugre y suciedad en la vestimenta de la iglesia. Por medio de su presencia, convirtieron lo que Dios hab\u00eda dise\u00f1ado como un viaje placentero y edificante en un riesgo inminente de naufragio espiritual. Los \u00ab\u00e1gapes\u00bb O \u00abbanquetes de amor\u00bb eran las ocasiones regulares en las que se reun\u00eda la iglesia primitiva para participar del pan y la copa en memoria del Se\u00f1or, tras lo cual se acostumbraba tener una comida comunitaria (cp. <span class='bible'>1Co 11:20-30<\/span>). <b>nubes sin agua.<\/b> <i>Vea la nota sobre<\/i> <span class='bible'>2Pe 2:17<\/span>. Los ap\u00f3statas prometen vida espiritual pero son nubes vac\u00edas que traen la esperanza de lluvia y lo \u00fanico que producen es sequedad y muerte (cp. <span class='bible'>Pro 25:14<\/span>). Predican un evangelio falso que solo conduce al infierno. <b>\u00e1rboles \u2026 sin fruto.<\/b> Los ap\u00f3statas alegan que suministran un banquete espiritual pero en lugar de esto solo producen hambre y desnutrici\u00f3n (cp. <span class='bible'>Luc 16:6-9<\/span>). Los \u00e1rboles que mueren nunca dan fruto y a pesar de lo que digan los ap\u00f3statas, siempre ser\u00e1n est\u00e9riles porque ya han sido desarraigados de la verdad. Cp. <span class='bible'>Mat 7:17-20<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio MacArthur<\/b><\/i><\/h3>\n<p><i>Vea las notas sobre<\/i> <span class='bible'>2Pe 2:13-17<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio MacArthur<\/b><\/i><\/h3>\n<p>\tv. 12 &#8212; V\u00e9ase 2Pe 2:13. \u00abEstos son manchas\u00bb. \u00abSon escollos\u00bb, dice la Versi\u00f3n Hispanoamericana. La palabra griega spilas significa una rosca o escollo que podr\u00eda causar naufragio por cuanto est\u00e1 escondido bajo el agua. La conducta excesiva de estos maestros, dice Judas, da\u00f1a grandemente la moralidad de los hermanos, como el escollo al barco, y trae desgracia y verg\u00fcenza al cuerpo de Cristo. Como el escollo no advierte, as\u00ed \u00e9stos no anuncian sus prop\u00f3sitos destructores y ruinosos.<br \/>\n\t\u00aben vuestros \u00e1gapes\u00bb. \u00abcomidas de amor fraternal\u00bb, dice la Versi\u00f3n Hispanoamericana. La palabra \u00ab\u00e1gape\u00bb es tomada literalmente del griego, que es agapai (el plural de agape, que quiere decir \u00abamor\u00bb). Seg\u00fan el Sr. Thayer, los \u00ab\u00e1gapes\u00bb eran comidas que manifestaban el amor entre hermanos, proporcionadas por los hermanos ricos y en que participaban los m\u00e1s pobres. Eran celebradas antes de tomar la Cena del Se\u00f1or por cristianos de los primeros siglos, pero descontinuadas en el siglo cuatro, seg\u00fan el testimonio de historiadores, porque fueron convertidas en ocasiones de lascivia por tales hombres como los aqu\u00ed descritos por Judas. Pablo en 1Co 11:1-34 condena la pr\u00e1ctica de corromper la Cena del Se\u00f1or con tales comidas, diciendo que tenemos casas en que comer y beber. Los falsos, a los cuales se refiere Judas, corromp\u00edan estas comidas y abusaron de ellas, llegando para meter sus pr\u00e1cticas lascivas y costumbres sensuales.<br \/>\n\tHay hermanos hoy en d\u00eda que usan este pasaje para justificar la pr\u00e1ctica moderna de que iglesias de Cristo de sus fondos erijan edificios (cocinas y comedores, y a veces hasta gimnasios, etc\u00e9tera), llamados en ingl\u00e9s fellowship halls (literalmente, salones para comuni\u00f3n), en que juntarse los hermanos para comer y gozarse de una junta puramente social. Viendo muchas iglesias de Cristo que hace mucho tiempo que tienen tales cosas las iglesias sectarias, ahora quieren tambi\u00e9n tener lo mismo. Los \u00ab\u00e1gapes\u00bb de Jud 1:12 les parece servir de \u00abprueba b\u00edblica\u00bb.<br \/>\n\tPero, no es as\u00ed. Notemos los siguientes puntos:<br \/>\n\t1. Las comidas sociales deben ser comidas en la casa, Hch 2:46; 1Co 11:22; 1Co 11:34. El prop\u00f3sito de la asamblea para culto a Dios no es social, sino espiritual. Son buenas las ocasiones sociales, pero pertenecen al hogar, a la casa.<br \/>\n\t2. Los \u00ab\u00e1gapes\u00bb no eran actividad de la colectividad (de la iglesia local, tomando dinero de las colectas semanarias para los gastos necesarios), sino de individuos. Los m\u00e1s ricos pagaban los gastos para realizar tales comidas. No hay mal alguno en que algunos hermanos preparen comidas y las sirvan gratis a hermanos m\u00e1s pobres, pero siendo actividad social de parte de individuos, debe ser guardada separada de las actividades de la colectividad (la iglesia local). Para tales comidas, dice Pablo, hay casas en que comer y beber.<br \/>\n\t3. La palabra \u00abcomuni\u00f3n\u00bb (en ingl\u00e9s fellowship, de donde viene el nombre del sitio para comer y beber&#8211;fellowship hall) no se emplea en el Nuevo Testamento en el sentido de comidas y diversas clases de entretenimiento de naturaleza puramente social. No hay \u00abcaf\u00e9 y pan dulce\u00bb en la palabra \u00abcomuni\u00f3n\u00bb, seg\u00fan usada en el Nuevo Testamento.<br \/>\n\t\u00abque comiendo&#8230; a s\u00ed mismos\u00bb. Pretenden \u00e9stos ser maestros, pero en lugar de alimentar (ense\u00f1ar) a las ovejas, se alimentan a s\u00ed mismos en los \u00e1gapes al grado de ser comilones y gozar de sus concupiscencias. \u00abSe deleitan en sus enga\u00f1os mientras hacen fiesta con vosotros\u00bb, escribe Pedro (2Pe 2:13). Comp\u00e1rense Ezequiel 34:2; Isa 56:11.<br \/>\n\t\u00abnubes&#8230; por los vientos\u00bb. Comp\u00e1rese 2Pe 2:17. Se presenta en la Biblia la doctrina de Dios bajo la figura de lluvia (Deu 32:2). As\u00ed es que presenta Judas a estos falsos maestros como nubes sin agua, o sea, con doctrina sin provecho. e jactan \u00e9stos de grande conocimiento pero son vac\u00edos en realidad. V\u00e9ase Pro 25:14. Comp\u00e1rese tambi\u00e9n Efe 4:14. Estos son un gran hueco espiritual que prometen mucho y se jactan grandemente, como una nube que a la tierra seca promete lluvia pero pasa sin dejar nada.<br \/>\n\t\u00ab\u00e1rboles&#8230; desarraigados\u00bb. Como la lluvia representa la doctrina, el fruto del \u00e1rbol representa la vida que alguno vive. Estos maestros, como tienen doctrina prometedora pero es falsa, as\u00ed tampoco producen nada bueno de vida. Con estas figuras de ret\u00f3rica, Judas est\u00e1 exponiendo la desolaci\u00f3n espiritual de estos falsos maestros que defraudan las expectaciones de otros, como la higuera maldita por Cristo (Mat 21:19; Mar 11:21). V\u00e9ase tambi\u00e9n Luc 13:6. No solamente son \u00e9stos como \u00e1rboles sin fruto, sino completamente incapaces de llevarlo: \u00abdos veces muertos y desarraigados\u00bb. Tal es el car\u00e1cter de los falsos maestros expuestos por Judas. Comp\u00e1rese Isa 1:30.<\/p>\n<h3 align='right'><i><b>Fuente: Notas Reeves-Partain<\/b><\/i><\/h3>\n<p><strong><u>EL RETRATO DE LOS INICUOS<br \/><\/u><\/strong><\/p>\n<p><\/p>\n<p><strong><span class='bible'>Judas 1:12-16<\/span><\/strong><\/p>\n<\/p>\n<p><\/p>\n<p><em>Estas personas son rocas ocultas que amenazan hacer zozobrar vuestras Fiestas del Amor. En ellas arman juergas con sus pandillas sin el m\u00e1s m\u00ednimo remordimiento. No tienen el menor sentimiento de responsabilidad con nadie m\u00e1s que consigo mismos. Son nubes que no traen ni una gota de lluvia, sino que pasan de largo arrastradas por los vientos. Son \u00e1rboles sin fruto aun en el tiempo de la cosecha de oto\u00f1o, muertos por partida doble y desarraigados. Son fieras olas del mar que espumarajean sus propias obras desvergonzadas. Son estrellas errantes a las que esperan para siempre los abismos de la oscuridad. Fue de ellos de los que profetiz\u00f3 Henoc, el s\u00e9ptimo descendiente de Ad\u00e1n, cuando dijo:<\/p>\n<p>\u00ab\u00a1Fijaos! El Se\u00f1or ha venido con mir\u00edadas de Sus santos para dictar sentencia contra todos y para condenar a todos los imp\u00edos por todas sus acciones imp\u00edas que han cometido imp\u00edamente, y por las palabras blasfemas que los pecadores imp\u00edos han dicho contra \u00c9l. \u00ab<\/p>\n<p>Estos son quejicas que no hacen m\u00e1s que protestar lastimeramente de todo lo que Dios les ha asignado en la vida. Lo \u00fanico que gobierna su conducta son sus caprichos. No sueltan por la boca nada m\u00e1s que palabras altisonantes. Adulan a la gente para sacar partido.<br \/><\/em><\/p>\n<p><\/p>\n<p>Esta es una de las grandes invectivas del Nuevo Testamento, surgida de una indignaci\u00f3n moral al rojo vivo. Como lo expresaba Moffatt: \u00bb Se acude a los cielos, a la tierra y al mar para hacer una descripci\u00f3n del car\u00e1cter de estos hombres.\u00bb Aqu\u00ed tenemos una serie de cuadros v\u00edvidos, todos con su sentido particular. Consider\u00e9moslos uno a uno.<\/p>\n<p>(i) Son como rocas ocultas que amenazan hacer zozobrar las Fiestas de Amor de la Iglesia. Este es el \u00fanico caso en que hay dudas acerca de lo que Judas quiere decir; pero de una cosa no hay duda: los malvados son un peligro para las Fiestas del Amor. La Fiesta del Amor, el <em>Agap\u00e9, <\/em>era una de las primeras caracter\u00edsticas de la Iglesia. Era una comida fraternal que se ten\u00eda el D\u00eda del Se\u00f1or. A ella tra\u00eda cada uno lo que pod\u00eda, y todos participaban. Era una idea preciosa el que los cristianos de cada grupito casero se sentaran juntos a la mesa el D\u00eda del Se\u00f1or para comer juntos. Sin duda habr\u00eda algunos que no podr\u00edan contribuir con mucho, y algunos con nada m\u00e1s que un poquito. Para muchos de los esclavos ser\u00eda probablemente la \u00fanica comida decente de la semana.<\/p>\n<p>Pero los <em>Agap\u00e9s <\/em>empezaron a deteriorarse muy pronto. Podemos ver los problemas que se iniciaron en la iglesia de Corinto, porque Pablo declara que en sus Fiestas de Amor no hab\u00eda m\u00e1s que divisi\u00f3n. Se divid\u00edan en grupos y secciones; algunos ten\u00edan demasiado, y otros se quedaban con hambre; y la ocasi\u00f3n se hab\u00eda convertido para algunos en una juerga inmoral (<span class='bible'>1Co 11:17-22<\/span> ). A menos que el <em>Agap\u00e9 <\/em>fuera una verdadera fraternidad, era una parodia, y muy pronto empez\u00f3 a desmentir su nombre.<\/p>\n<\/p>\n<p>Los oponentes de Judas estaban convirtiendo las Fiestas del Amor en una parodia. La versi\u00f3n Reina-Valera dice que Judas los llama \u00bb manchas en vuestros \u00e1gapes\u00bb (vers\u00edculo 12); y eso coincide con el pasaje paralelo de <span class='bible'>2Pe 2:13<\/span> : \u00abinmundicias y manchas.\u00bb Hemos traducido la expresi\u00f3n de Judas por \u00bb rocas ocultas.\u00bb<\/p>\n<\/p>\n<p>Lo dif\u00edcil es que Pedro y Judas no usan la misma palabra, pero s\u00ed palabras muy parecidas. La palabra <span class='bible'>de 2<\/span> Pedro<em> <\/em>es spilos, que quiere decir incuestionablemente <em>una mancha; <\/em>pero la palabra de Judas es spil\u00e1s, que es bastante rara. Puede que quiera decir <em>una mancha, <\/em>porque en griego posterior se pod\u00eda usar para las manchas o las vetas de una piedra de \u00f3palo; pero en el griego contempor\u00e1neo su significado m\u00e1s frecuente era <em>una roca sumergida, o mediosumergida, en la que un barco pod\u00eda naufragar f\u00e1cilmente. <\/em>Creemos que el segundo significado es aqu\u00ed el m\u00e1s probable.<\/p>\n<p>En las Fiestas del Amor los miembros de la iglesia estaban muy unidos de coraz\u00f3n, y se daban el beso de la paz. Estos malvados usaban las Fiestas del Amor como ocasi\u00f3n para gratificar su concupiscencia. Es terrible que entren personas a la iglesia y usen las oportunidades que da su comuni\u00f3n para sus propios fines pervertidos. Estas personas eran como rocas ocultas en las que la comuni\u00f3n de las Fiestas del Amor corr\u00eda peligro de naufragar.<\/p>\n<p><strong><u>EL EGO\u00cdSMO DE LOS MALVADOS<br \/><\/u><\/strong><\/p>\n<p><\/p>\n<p><strong><span class='bible'>Judas 1:12-16<\/span><\/strong><strong> (continuaci\u00f3n)<\/strong><\/p>\n<\/p>\n<p><\/p>\n<p>(ii) Estos malvados arman juergas por grupos y no tienen sentimiento de responsabilidad para con nadie m\u00e1s que consigo mismos. Estas dos cosas van juntas, porque las dos subrayan su ego\u00edsmo a ultranza.<\/p>\n<p>(a) Arman juergas en sus pandillas sin el menor remordimiento. Esta era exactamente la misma situaci\u00f3n que Pablo conden\u00f3 <span class='bible'>en 1<\/span> Corintios. La Fiesta del Amor se supon\u00eda que era un acto de comuni\u00f3n; y la comuni\u00f3n se demostraba compartiendo todas las cosas. En vez de compartir, los malvados se manten\u00edan apartados en sus grupitos, y guardaban para s\u00ed todo lo que ten\u00edan. <span class='bible'>En 1<\/span> Corintios Pablo llega hasta a decir que las Fiestas del Amor se convert\u00edan para algunos en borracheras, en las que cada uno se apropiaba de todo lo que pod\u00eda (<span class='bible'>1Co 11:21<\/span> ). Ninguna persona que est\u00e9 en la iglesia para aprovecharse y mantenerse dentro de su grupito puede pretender que se ha enterado de lo que quiere decir ser miembro de la Iglesia.<\/p>\n<\/p>\n<p>(b) Hemos traducido la frase siguiente: \u00bb No tienen sentimiento de responsabilidad para con nadie m\u00e1s que consigo mismos.\u00bb El original quiere decir literalmente \u00bb pastorearse a s\u00ed mismos.\u00bb El deber de un responsable de la iglesia es ser un pastor del reba\u00f1o de Dios (<span class='bible'>Hch 20:28<\/span> ; <span class='bible'>1Pe 5:2<\/span> s). El falso pastor se cuidaba mucho m\u00e1s de s\u00ed mismo que de las ovejas que se supon\u00eda que estaban a su cuidado. Ezequiel describe a los falsos pastores, a los que deb\u00edan quitarse los privilegios: \u00ab\u00bb\u00a1Tan cierto como que Yo estoy vivo! -ha dicho el Se\u00f1or Dios-, que Mi reba\u00f1o ha estado expuesto al robo, y Mis ovejas a ser presa de todas las fieras del campo, porque no ten\u00edan pastor; porque Mis pastores no buscaron a Mis ovejas, sino que se apacentaron a s\u00ed mismos y no apacentaron a Mis oveSantiago\u00bb Por eso, pastores, o\u00edd palabra del Se\u00f1or. As\u00ed ha dicho el Se\u00f1or Dios: \u00ab\u00a1Yo estoy contra los pastores y demandar\u00e9 Mis ovejas de su mano, y har\u00e9 que dejen de apacentar Mis ovejas!\u00bb\u00bb (<span class='bible'>Ez 34:8-10<\/span> ). El hombre que no siente ninguna responsabilidad por el bienestar de nadie m\u00e1s que el de s\u00ed mismo es culpable.<\/p>\n<p>As\u00ed es que Judas condena el ego\u00edsmo que destruye la comuni\u00f3n, y la falta de sentido de responsabilidad hacia los dem\u00e1s.<\/p>\n<p>(iii) Los malvados son como nubes que el viento arrastra sin que llueva ni una gota, y como \u00e1rboles en el tiempo de la cosecha que no tienen ning\u00fan fruto. Estas dos frases van juntas, porque describen a las personas que pretenden ofrecer grandes cosas pero que son esencialmente in\u00fatiles. Hab\u00eda veces en Palestina -corito en Espa\u00f1a- que el pueblo oraba por la lluvia. Algunas veces se pod\u00edan ver pasar las nubes por el cielo despertando la esperanza de la lluvia, pero no ca\u00eda ni una gota. Las nubes pasaban volando, y la lluvia no llegaba. En cualquier tiempo de la cosecha hab\u00eda \u00e1rboles que parec\u00eda que estaban cargados de fruta, pero que, cuando los cosechadores se acercaban a ellos no encontraban ni una.<\/p>\n<p>En estos ejemplos se presenta una gran verdad. La promesa sin cumplimiento es in\u00fatil, y en el Nuevo Testamento no hay nada que se condene tanto como la inutilidad. Ning\u00fan despliegue de alarde externo o de palabras bonitas puede ocupar el lugar de la utilidad para los dem\u00e1s. Como se ha dicho: \u00bb Si uno no sirve a nadie, no sirve para nada.\u00bb<\/p>\n<p><strong><u>EL RESULTADO DE LA DESOBEDIENCIA<br \/><\/u><\/strong><\/p>\n<p><\/p>\n<p><strong><span class='bible'>Judas 1:12-16<\/span><\/strong><strong> (continuaci\u00f3n)<\/strong><\/p>\n<\/p>\n<p><\/p>\n<p>Judas pasa a hacer una descripci\u00f3n muy gr\u00e1fica de estos malvados. \u00abSon fieras olas del mar que espumarajean sus propias obras desvergonzadas.\u00bb La imagen es la siguiente. Despu\u00e9s de una tormenta, cuando las olas han estado azotando la orilla con. sus rociadas y espuma, siempre queda en la orilla una cinta de algas y de maderas de todas clases y toda clase de feos desechos del Marcos Esa es siempre una escena desagradable; pero en el caso de cierto mar lo es a\u00fan m\u00e1s que en ning\u00fan otro. Las aguas del mar Muerto pueden ser azotadas formando olas, y estas olas, tambi\u00e9n, echan desechos a la orilla; pero en este ejemplo se da una circunstancia exclusiva. Las aguas del mar Muerto est\u00e1n tan saturadas de sal que se comen la corteza de todos los troncos, que, cuando son arrojados a la orilla, relucen de puro blancos, m\u00e1s como huesos que como maderos. Las obras de los malvados son como los desechos in\u00fatiles y horripilantes que dejan las olas desperdigados sobre la orilla despu\u00e9s de una tormenta, y recuerdan las reliquias macabras de las tormentas del mar Muerto. As\u00ed retrata Judas v\u00edvidamente la fealdad de las acciones de sus oponentes.<\/p>\n<p>Judas usa otra ilustraci\u00f3n m\u00e1s. Los malvados son como estrellas errantes que se sumen en un abismo de oscuridad por su desobediencia. Esta es una figura tomada directamente del <em>Libro de Henoc. <\/em>En ese libro se identifican a veces las estrellas con los \u00e1ngeles; y hay una descripci\u00f3n del destino de las estrellas que, desobedientes a Dios, se apartaron de la \u00f3rbita que se les hab\u00eda se\u00f1alado, y fueron destruidas. En su viaje por todo el mundo, Henoe lleg\u00f3 a un lugar donde no vio \u00bb ni los cielos por arriba ni la tierra firmemente fundada, sino un lugar ca\u00f3tico y horrible.\u00bb Y prosigue: \u00bb Y all\u00ed vi siete estrellas del cielo que estaban atadas juntas, como grandes monta\u00f1as, y ardiendo con fuego. Entonces yo dije: \u00ab\u00bfPor qu\u00e9 pecado est\u00e1n atadas, y en raz\u00f3n de qu\u00e9 las han arrojado aqu\u00ed?\u00bb Y dijo Uriel, uno de los santos \u00e1ngeles, que estaba conmigo y que estaba a cargo de aquellas: \u00abHenoc, \u00bfpor qu\u00e9 preguntas y por qu\u00e9 anhelas la verdad? Este es un n\u00famero de estrellas del cielo que han transgredido el mandamiento del Se\u00f1or, y est\u00e1n atadas aqu\u00ed hasta que pasen diez mil a\u00f1os, el tiempo se\u00f1alado hasta que sus pecados hayan transcurrido.\u00bb\u00bb <em>(Henoc 21:1-6). <\/em>El destino de las estrellas errantes es caracter\u00edstico del de las personas que desobedecen los mandamientos de Dios y, como si dij\u00e9ramos, siguen su propio camino.<\/p>\n<\/p>\n<p><\/p>\n<p>Judas confirma entonces todo esto con una profec\u00eda; pero la profec\u00eda est\u00e1 tomada tambi\u00e9n de <em>Henoc. <\/em>El pasaje dice exactamente: \u00bb \u00a1Y fijaos! \u00c9l viene con mir\u00edadas de Sus santos a ejecutar juicio sobre todos, y a destruir a todos los imp\u00edos; y a condenar a toda carne por todas las obras imp\u00edas que han perpetrado imp\u00edamente; y por todas las palabras duras que los pecadores imp\u00edos han hablado contra El\u00bb <em>(Henoc 1:9).<\/em><\/p>\n<\/p>\n<p>Esta cita ha suscitado muchas preguntas con respecto a <em>Judas y Henoc. <\/em>No cabe duda que en los d\u00edas de Judas, y en los d\u00edas de Jes\u00fas, <em>Henoc <\/em>era un libro muy popular, que todos los jud\u00edos piadosos conoc\u00edan y le\u00edan. Es normal que, cuando los autores del Nuevo Testamento quer\u00edan confirmar sus palabras, echaran mano de citas del Antiguo Testamento us\u00e1ndolo como la Palabra de Dios. \u00bfHabremos de considerar <em>Henoc <\/em>como Sagrada Escritura ya que Judas lo usa exactamente como usar\u00eda cualquiera de los profetas? O \u00bfhemos de tomar el punto de vista que menciona Jer\u00f3nimo, que <em>Judas <\/em>no se puede considerar Escritura porque comete la equivocaci\u00f3n de usar como Escritura un libro que no lo es en realidad?<\/p>\n<p>No tenemos por qu\u00e9 gastar tiempo en este debate. El hecho es que Judas, un jud\u00edo piadoso, conoc\u00eda y amaba el <em>Libro de Henoc, y se <\/em>hab\u00eda criado en un c\u00edrculo en el que era considerado con respeto y hasta con reverencia; y lo cita con perfecta naturalidad, sabiendo que sus lectores lo reconocer\u00edan y respetar\u00edan. En realidad, el canon hebreo del Antiguo Testamento no se cerr\u00f3 hasta finales del siglo I despu\u00e9s de Cristo, siendo una de las razones que impulsaron a ello el hecho de que la Iglesia Cristiana usaba como Escritura libros de los jud\u00edos de la Di\u00e1spora que no se hab\u00edan escrito o se conservaban en hebreo. Judas hizo en realidad lo mismo que todos los autores del Nuevo Testamento, y que todos los escritores hacen en todas las \u00e9pocas: se dirigi\u00f3 a su audiencia en el lenguaje que se pod\u00eda reconocer y entender.<\/p>\n<p><\/p>\n<p><strong><u>CARACTER\u00cdSTICAS DE LOS MALVADOS<br \/><\/u><\/strong><\/p>\n<p><\/p>\n<p><strong><span class='bible'>Judas 1:12-16<\/span><\/strong><strong> (conclusi\u00f3n)<\/strong><\/p>\n<\/p>\n<p><\/p>\n<p>En el vers\u00edculo 16 Judas especifica tres \u00faltimas caracter\u00edsticas de los malvados.<\/p>\n<p>(i) Son protestones, permanentemente descontentos con la vida que Dios les ha asignado. En este cuadro Judas usa dos palabras, una de las cuales que les ser\u00eda muy familiar a sus lectores jud\u00edos, y la otra, a los griegos.<\/p>\n<p><em>(a) <\/em>La primera es <em>gonguyst\u00e9s. <\/em>Esta palabra describe las voces descontentas de los murmuradores y es la misma que aparece frecuentemente en la traducci\u00f3n griega del Antiguo Testamento para <em>las murmuraciones <\/em>de los israelitas contra Mois\u00e9s cuando los guiaba por el desierto <em>(<\/em><span class='bible'>Ex 15:24<\/span><em> ; <\/em><span class='bible'>Ex 17:3<\/span><em> ; <\/em><span class='bible'>Nm 14:29<\/span><em> ). <\/em>Parece reproducir onomatop\u00e9yicamente el susurro de descontento resentido que surg\u00eda del pueblo rebelde. Estos malvados del tiempo de Judas eran la contrapartida moderna de los murmuradores israelitas del desierto, personas llenas de quejas malhumoradas contra la mano guiadora de Dios.<\/p>\n<\/p>\n<p><em>(b) <\/em>La segunda es <em>memps\u00edmoiros. <\/em>Est\u00e1 formada por dos palabras griegas: <em>m\u00e9mfesthai, <\/em>que quiere decir <em>echar las culpas, y moira, la suerte o la vida de uno. <\/em>Un <em>memps\u00edmoiros <\/em>era un hombre que estaba siempre quej\u00e1ndose de la vida en general. Teofrasto, el gran maestro en la descripci\u00f3n de personajes, tiene un estudio c\u00f3mico y burlesco del <em>memps\u00edmoiros <\/em>que vale la pena citar completo:<\/p>\n<\/p>\n<p><\/p>\n<p><em>El quejumbroso es el que se pasa de quejarse indebidamente de su suerte en todos los casos. El quejumbroso le dir\u00e1 al amigo que le trae una porci\u00f3n de su propia mesa: \u00abEsto es una muestra de lo taca\u00f1o que eres conmigo, porque no has querido invitarme a comer contigo en persona.\u00bb Cuando su amante le est\u00e1 dando un beso, \u00e9l le dice: \u00abMe pregunto si me estar\u00e1s besando de coraz\u00f3n, o porque quieres algo de m\u00ed.\u00bb Est\u00e1 disgustado con<br \/><\/em><\/p>\n<p><\/p>\n<p><em>Zeus, no porque no le mande la lluvia, sino porque ha tardado algo en mand\u00e1rsela. Cuando se encuentra una cartera en la calle, se pone: \u00ab\u00a1Ah! No me encuentro nunca un tesoro que valga la pena.\u00bb Cuando ha comprado un esclavo barato despu\u00e9s de regatearle el precio al vendedor hasta agotarle, exclama: \u00ab\u00a1No ser\u00e1 una ganga cuando me lo ha dejado tan barato!\u00bb Cuando le dan la buena noticia de que le ha nacido un ni\u00f1o, entonces es que: \u00bb Si me dices que esto me va a costar la mitad de mi fortuna me habr\u00e1s dicho la verdad.\u00bb Si gana un pleito mediante un veredicto un\u00e1nime, est\u00e1 seguro de encontrarle faltas al que ha hecho su defensa por omitir muchas circunstancias que le eran favorables. Y si se ha hecho una suscripci\u00f3n a su favor entre sus amigos, y uno de ellos le dice: \u00ab\u00a1Alegra esa cara 1,\u00bb \u00e9l le responde: \u00ab\u00bfDe qu\u00e9, si se lo voy a tener que devolver a todos y el chollo ser\u00e1 para ellos?\u00bb<br \/><\/em><\/p>\n<p><\/p>\n<p>Aqu\u00ed, trazado h\u00e1bilmente por la pluma sutil de Teofrasto, tenemos el retrato de uno de esos que encuentran siempre algo de que quejarse en cada situaci\u00f3n. Puede encontrarle alguna pega al mejor d\u00e9 los negocios, al m\u00e1s amable de los gestos, al m\u00e1s redondo de los \u00e9xitos, a la buena suerte m\u00e1s voluminosa. \u00abGran ganancia es la piedad acompa\u00f1ada de contentamiento\u00bb <em>(<\/em><span class='bible'>1Co 6:6<\/span><em> ); <\/em>pero los malvados est\u00e1n siempre descontentos con la vida y con todo lo que Dios les asigna. Hay pocas personas que sean menos populares que el quejica cr\u00f3nico, y los tales har\u00edan bien en tener presente que su actitud equivale a un insulto a Dios.<\/p>\n<p>(ii) Judas reitera un detalle de estos malvados, que ya ha se\u00f1alado una y otra vez: su conducta est\u00e1 gobernada por sus deseos. Para ellos la disciplina y el dominio propio no sirven para nada. Para ellos la ley moral no es m\u00e1s_que una carga y un fastidio; el honor y el deber no les incumben; no tienen ning\u00fan deseo de servir, ni ning\u00fan sentido de responsabilidad; no valoran m\u00e1s que el placer, y su \u00fanica din\u00e1mica es el deseo. Si todo el mundo fuera as\u00ed, el mundo ser\u00eda un completo caos.<\/p>\n<p>(iii) Hablan con orgullo y arrogancia, y sin embargo al mismo tiempo est\u00e1n dispuestos a halagar a los grandes si piensan creen que pueden obtener alg\u00fan beneficio. Es perfectamente posible que una persona sea al mismo tiempo un tipo rimbombante con las personas a las que trata de impresionar, y un adulador halag\u00fce\u00f1o con las personas que considera importantes. Los oponentes de Judas se ensalzaban a s\u00ed mismos y adulaban a los dem\u00e1s seg\u00fan demandara la ocasi\u00f3n; y su progenie se encuentra a veces entre nosotros.<\/p>\n<h3 align='right'><i><b>Fuente: Comentario al Nuevo Testamento<\/b><\/i><\/h3>\n<p><span class='bible'>2Pe 3:13<\/span>; <span class='bible'>2Pe 3:17<\/span>; (ver <span class='bible'>1Co 11:21<\/span>).<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n Interconfesional HispanoAmericana<\/b><\/i><\/h3>\n<p>REFERENCIAS CRUZADAS<\/p>\n<p>s 46 2Ti 3:6; 2Pe 2:13<\/p>\n<p>t 47 Eze 34:8<\/p>\n<p>u 48 2Pe 2:17<\/p>\n<p>v 49 Efe 4:14<\/p>\n<p>w 50 Mat 15:13<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n del Nuevo Mundo<\/b><\/i><\/h3>\n<p><p> escollos ocultos en&#8230;\u00e1gapes.  La arrogancia e inmoralidad de los falsos maestros ponen en peligro el prop\u00f3sito del \u00e1gape, que generalmente inclu\u00eda la celebraci\u00f3n de la Cena del Se\u00f1or. <\/p>\n<p><p> nubes sin agua&#8230;\u00e1rboles&#8230;sin fruto.  Estos imp\u00edos enga\u00f1adores no producen ning\u00fan beneficio ni bendici\u00f3n alguna.<\/p>\n<p><h3 align='right'><i><b>Fuente: La Biblia de las Am\u00e9ricas<\/b><\/i><\/h3>\n<p>\n12<strong> (1)<\/strong> La palabra griega significa <em> una roca<\/em>. \u00abTal vez se refiera a una roca sumergida, cubierta por el mar\u00bb (Darby); por ende, escollos ocultos. La palabra griega traducida <em> manchas <\/em> en 2Pe_2:13 es muy parecida a la palabra que aqu\u00ed se traduce <em> escollos ocultos es por esto que algunas traducciones dicen <em> manchas<\/em>. En realidad, estas dos palabras se refieren a dos cosas diferentes. Las manchas son defectos en la superficie de las piedras preciosas; los escollos ocultos est\u00e1n en el fondo del agua. Los primeros herejes no solamente eran manchas en la superficie, sino tambi\u00e9n escollos ocultos en el fondo; las dos cosas perjudicaban a los que cre\u00edan en Cristo.<\/p>\n<\/p>\n<p>\n12<strong> (2)<\/strong> Banquetes de amor motivados por el amor de Dios (el amor m\u00e1s elevado, 1Jn_4:10-11 , 1Jn_4:21). En los primeros d\u00edas los creyentes a menudo com\u00edan juntos con amor para tener comuni\u00f3n y adorar a Dios ( Hch_2:46). <\/p>\n<\/p>\n<p>\nEstas reuniones eran parte de la cena del Se\u00f1or ( 1Co_11:20-21 , 1Co_11:33) y se les llamaba \u00e1gapes.<\/p>\n<\/p>\n<p>\n12<strong> (3)<\/strong> Los herejes \u00e1vidos de placeres ( 2Pe_2:13) se hac\u00edan pasar por pastores, pero en los \u00e1gapes s\u00f3lo se alimentaban a s\u00ed mismos y no se preocupaban por los dem\u00e1s. Con respecto a los dem\u00e1s, ellos eran nubes sin agua; no pod\u00edan suministrar vida.<\/p>\n<\/p>\n<p>\n12<strong> (4)<\/strong> Cfr. 2Pe_2:17 y la nota 1.<\/p>\n<\/p>\n<p>\n12<strong> (5)<\/strong> El oto\u00f1o es la estaci\u00f3n en que se cosecha la fruta. Los ap\u00f3statas ego\u00edstas parec\u00edan ser \u00e1rboles frutales en tiempo de cosecha, pero no ten\u00edan fruto para satisfacer a otros. Hab\u00edan muerto dos veces, no s\u00f3lo externamente, en apariencia, como la mayor\u00eda de los \u00e1rboles en el oto\u00f1o, sino tambi\u00e9n interiormente, en naturaleza. Estaban totalmente muertos; por consiguiente, conven\u00eda desarraigarlos. <\/p>\n<h3 align='right'><i><b>Fuente: Comentario Del Nuevo Testamento Versi\u00f3n Recobro<\/b><\/i><\/h3>\n<p><b><i>\u00e1gapes<\/i><\/b>. Estas cenas de confraternidad se com\u00edan en conexi\u00f3n con la Cena del Se\u00f1or (v\u00e9ase nota en <span class='bible'>1Co 11:20<\/span>). El orgullo, la avidez y la rebeld\u00eda compendiaban las iniquidades de los <b><i>imp\u00edos<\/i><\/b> (v. <span class='bible'>Jud 1:4<\/span>) que corromp\u00edan estos \u00e1gapes.<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio Anotada por Ryrie<\/b><\/i><\/h3>\n<p><i><b>escollos&#8230;<\/b><\/i> Gr. <i>spil\u00e1s.<\/i> Es decir, <i>peligros ocultos.<\/i> Otras versiones: <i>manchas<\/i> (gr. <i>sp\u00edlos<\/i>); <i><b>\u00e1gapes&#8230;<\/b><\/i> Es decir, <i>fiestas de amor<\/i>; <i><b> sin temor&#8230;<\/b><\/i> Esto es, <i>sin temor de Dios<\/i>.<\/p>\n<h3 align='right'><i><b>Fuente: Biblia Textual IV Edici\u00f3n<\/b><\/i><\/h3>\n<p>R704 \u039f\u1f57\u03c4\u03bf\u03b9 tiene el g\u00e9nero masculino porque se refiere a personas. <\/p>\n<h3 align='right'><i><b>Fuente: Ayuda gramatical para el Estudio del Nuevo Testamento Griego<\/b><\/i><\/h3>\n<p> O, <i>manchas ocultas<\/i> <\/p>\n<h3 align='right'><i><b>Fuente: La Biblia de las Am\u00e9ricas<\/b><\/i><\/h3>\n<p> N <em>escollos<\/em>.<\/p>\n<p> 1.12 <em>\u00e1gapes = fiestas de amor<\/em> (prob. la <em>Cena Dominical<\/em> g <span class='bible'>1Co 11:17-20<\/span>).<\/p>\n<p> 1.12 Esto es, <em> sin temor de Dios.<\/p>\n<h3 align='right'><i><b>Fuente: La Biblia Textual III Edici\u00f3n<\/b><\/i><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Estos que participan en vuestras comidas fraternales son manchas, apacent\u00e1ndose a s\u00ed mismos sin temor alguno. Son nubes sin agua, llevadas de ac\u00e1 para all\u00e1 por los vientos. Son \u00e1rboles marchitos como en oto\u00f1o, sin fruto, dos veces muertos y desarraigados. v. 12 \u2014 V\u00e9ase 2Pe 2:13. \u00abEstos son manchas\u00bb. \u00abSon escollos\u00bb, dice la Versi\u00f3n &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/comentario-de-judas-112-exegesis-y-hermeneutica-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abComentario de Judas 1:12 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-31313","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/31313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=31313"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/31313\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=31313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=31313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=31313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}