{"id":31466,"date":"2022-06-20T14:30:49","date_gmt":"2022-06-20T19:30:49","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/comentario-de-apocalipsis-811-exegesis-y-hermeneutica-de-la-biblia\/"},"modified":"2022-06-20T14:30:49","modified_gmt":"2022-06-20T19:30:49","slug":"comentario-de-apocalipsis-811-exegesis-y-hermeneutica-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/comentario-de-apocalipsis-811-exegesis-y-hermeneutica-de-la-biblia\/","title":{"rendered":"Comentario de Apocalipsis 8:11 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia"},"content":{"rendered":"<h3 align='center'><b><i>El nombre de la estrella es Ajenjo. Y la tercera parte de las aguas se convirti\u00f3 en ajenjo, y muchos hombres murieron por las aguas, porque fueron hechas amargas.<\/i><\/b><\/h3>\n<p \/> <span>8:11<\/span> \u2014 Y el nombre de la estrella es Ajenjo. Y la tercera parte de las aguas se convirti\u00f3 en ajenjo; y muchos hombres murieron a causa de esas aguas, porque se hicieron amargas <\/p>\n<p \/> \u2014 \u2014 Ajenjo \u2014 V\u00e9anse <span>Deu 29:18<\/span>; <span>Jer 9:1-26:15<\/span>,<span>16<\/span>; <span>Lamentaciones 3:19<\/span>; <span>\u00c9xo 9:22-26<\/span>. Aqu\u00ed se simboliza la amargura y tristeza de vida causadas por los juicios de Dios. La vida de rebeli\u00f3n contra Dios trae en s\u00ed la semilla de calamidad, amargura y tristeza. <\/p>\n<p \/> Muchos murieron, pero no todos. Son juicios parciales. Los malos no pueden escapar los juicios de Dios.<\/p>\n<h3 align='right'><i><b>Fuente: Comentario al Nuevo Testamento por Partain<\/b><\/i><\/h3>\n<p><b><i>Ajenjo.<\/i><\/b> <span class='bible'>Deu 29:18<\/span>; <span class='bible'>Rut 1:20<\/span>; <span class='bible'>Pro 5:4<\/span>; <span class='bible'>Jer 9:15<\/span>; <span class='bible'>Jer 23:15<\/span>; <span class='bible'>Lam 3:5<\/span>, <span class='bible'>Lam 3:19<\/span>; <span class='bible'>Am\u00f3 5:7<\/span>; <span class='bible'>Am\u00f3 6:12<\/span>; <span class='bible'>Heb 12:15<\/span>.<\/p>\n<p><b><i>muchos hombres murieron.<\/i><\/b> <span class='bible'>\u00c9xo 15:23<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: El Tesoro del Conocimiento B\u00edblico<\/b><\/i><\/h3>\n<p lang=\"es-ES\" style=\"text-indent:18pt;margin-left:0pt;margin-top:0pt;margin-bottom:0pt;margin-right:0pt\">El\u00a0<\/span><span style=\"font-weight:bold\">ajenjo<\/span>\u00a0es una planta que se encuentra en el Medio Oriente, famosa por su sabor amargo. Aqu\u00ed y en todas partes (<\/span><span style=\"color:#008000\"><span class='bible'>Lam 3:19<\/span><\/span>) el t\u00e9rmino simboliza la amargura. Normalmente, el ajenjo no es venenoso, pero la plaga de la tercera trompeta implica efectos mucho m\u00e1s potentes que el sabor amargo de una planta:\u00a0<\/span><span style=\"font-weight:bold\">muchos hombres murieron a causa de esas aguas.<\/span> La r\u00e1pida contaminaci\u00f3n de la\u00a0<\/span><span style=\"font-weight:bold\">tercera parte<\/span>\u00a0del agua del mundo provocar\u00eda una crisis ca\u00f3tica. El Se\u00f1or expondr\u00eda ahora la infidelidad del coraz\u00f3n humano de una manera inequ\u00edvoca (<\/span><span style=\"color:#008000\"><span class='bible'>Apo 9:21<\/span><\/span>).<\/span><\/p>\n<p><\/p>\n<h3 align='right'><i><b>Fuente: Nuevo Comentario Ilustrado de la Biblia Caribe<\/b><\/i><\/h3>\n<p><b>AJENJO.<\/b> \u00abAjenjo\u00bb es una planta amarga que representa el juicio de Dios y la angustia humana (v\u00e9anse <span class=\"bible\">Deu 29:18<\/span>; <span class=\"bible\">Pro 5:4<\/span>; <span class=\"bible\">Jer 9:15<\/span>; <span class=\"bible\">Am\u00f3 5:7<\/span>).<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio Vida Plena<\/b><\/i><\/h3>\n<p><b>Ajenjo.<\/b> Una sustancia amarga y venenosa que se obtiene de una ra\u00edz y que produce ebriedad y enajenaci\u00f3n hasta causar la muerte (<span class='bible'>Deu 29:18<\/span>; <span class='bible'>Pro 5:4<\/span>; <span class='bible'>Jer 9:15<\/span>; <span class='bible'>Lam 3:15<\/span>).<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio MacArthur<\/b><\/i><\/h3>\n<p>\t8:11 &#8212; Y el nombre de la estrella es Ajenjo. Y la tercera parte de las aguas se convirti\u00f3 en ajenjo; y muchos hombres murieron a causa de esas aguas, porque se hicieron amargas &#8212;<br \/>\n\t &#8211; &#8211; Ajenjo &#8212; V\u00e9anse Deu 29:18; Jer 9:1-26:15,16; Lamentaciones 3:19; \u00c9xo 9:22-26. Aqu\u00ed se simboliza la amargura y tristeza de vida causadas por los juicios de Dios. La vida de rebeli\u00f3n contra Dios trae en s\u00ed la semilla de calamidad, amargura y tristeza.<br \/>\n\tMuchos murieron, pero no todos. Son juicios parciales. Los malos no pueden escapar los juicios de Dios.<\/p>\n<h3 align='right'><i><b>Fuente: Notas Reeves-Partain<\/b><\/i><\/h3>\n<p><span class='bible'>Jer 9:15<\/span>; <span class='bible'>Am\u00f3 5:7<\/span>; <span class='bible'>Am\u00f3 6:12<\/span>.<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n Interconfesional HispanoAmericana<\/b><\/i><\/h3>\n<p><i><b>\u2014 ajenjo:<\/b><\/i> Se trata de una planta venenosa de sabor terriblemente amargo (ver <span class='bible'>Am\u00f3 6:12<\/span>).<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n Interconfesional HispanoAmericana<\/b><\/i><\/h3>\n<p>NOTAS<\/p>\n<p>(1) O: \u201cAbsintio\u201d.<\/p>\n<p>(2) O: \u201cde la humanidad\u201d.<\/p>\n<p>REFERENCIAS CRUZADAS<\/p>\n<p>v 416 Pro 25:26; Am\u00f3 5:7; Am\u00f3 6:12<\/p>\n<h3 align='right'><i><b>Fuente: Traducci\u00f3n del Nuevo Mundo<\/b><\/i><\/h3>\n<p><p> Ajenjo.  Esta es una planta que produce un l\u00edquido t\u00f3xico de sabor muy amargo; aqu\u00ed representa el castigo de Dios, que es sufrimiento para quienes lo merezcan (cp. <span>Jer 9:15<\/span>; 23:15; Lm 3:15, 19).<\/p>\n<p><h3 align='right'><i><b>Fuente: La Biblia de las Am\u00e9ricas<\/b><\/i><\/h3>\n<p> 11 <strong>super (1)<\/strong> Una planta amarga. <\/p>\n<p> 11 <strong>super (2)<\/strong> Hoy en d\u00eda los que se oponen a Dios y los que practican lo malo contra El todav\u00eda disfrutan lo que Dios cre\u00f3. Debido a la oposici\u00f3n maligna del hombre contra Dios, el agua que El cre\u00f3, la cual es crucial para la vida humana, probablemente ser\u00e1 da\u00f1ada de una manera limitada por el juicio de Dios.<\/p>\n<h3 align='right'><i><b>Fuente: Comentario Del Nuevo Testamento Versi\u00f3n Recobro<\/b><\/i><\/h3>\n<p><b><i>Ajenjo<\/i><\/b>. Se cr\u00edan en Palestina muchas especies de ajenjo, y todas tienen un sabor fuerte y amargo (pero no venenoso), lo cual es motivo para que esta planta sea tenida como s\u00edmbolo de la amargura, de la pesadumbre y de la calamidad. Esta plaga har\u00e1 que la tercera parte del suministro de agua fresca de la tierra deje absolutamente de ser potable.<\/p>\n<h3 align='right'><i><b>Fuente: Biblia de Estudio Anotada por Ryrie<\/b><\/i><\/h3>\n<p>R598 La frase prepositiva \u1f10\u03ba  \u03c4\u1ff6\u03bd \u1f51\u03b4\u03ac\u03c4\u03c9\u03bd presenta la idea de causa: a causa del agua. <\/p>\n<p> H462 \u0395\u1f30\u03c2 con el acusativo se usa en vez del predicado nominal, despu\u00e9s de \u1f10\u03b3\u03ad\u03bd\u03b5\u03c4\u03bf: una tercera parte de las aguas se convirti\u00f3 en ajenjo.<\/p>\n<h3 align='right'><i><b>Fuente: Ayuda gramatical para el Estudio del Nuevo Testamento Griego<\/b><\/i><\/h3>\n<p>\u2021 En griego, \u201cAjenjo\u201d es sin\u00f3nimo de \u201camargo\u201d.<\/p>\n<h3 align='right'><i><b>Fuente: Versi\u00f3n Biblia Libre del NuevoTestamento<\/b><\/i><\/h3>\n<p>\u00a7 Aqu\u00ed se usa una palabra distinta \u201chacer amargo o \u00e1cido,\u201d pero debido a sus efectos, probablemente la mejor traducci\u00f3n sea \u201cvenenoso\u201d.<\/p>\n<h3 align='right'><i><b>Fuente: Versi\u00f3n Biblia Libre del NuevoTestamento<\/b><\/i><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>El nombre de la estrella es Ajenjo. Y la tercera parte de las aguas se convirti\u00f3 en ajenjo, y muchos hombres murieron por las aguas, porque fueron hechas amargas. 8:11 \u2014 Y el nombre de la estrella es Ajenjo. Y la tercera parte de las aguas se convirti\u00f3 en ajenjo; y muchos hombres murieron a &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/comentario-de-apocalipsis-811-exegesis-y-hermeneutica-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abComentario de Apocalipsis 8:11 &#8211; Ex\u00e9gesis y Hermen\u00e9utica de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-31466","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/31466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=31466"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/31466\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=31466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=31466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=31466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}