{"id":31747,"date":"2022-07-16T03:02:07","date_gmt":"2022-07-16T08:02:07","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-genesis-131-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T03:02:07","modified_gmt":"2022-07-16T08:02:07","slug":"estudio-biblico-de-genesis-131-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-genesis-131-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de G\u00e9nesis 1:31 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Gn 1:31<\/span><\/p>\n<p><em>Y vio Dios todo lo que hab\u00eda hecho, y he aqu\u00ed que era muy bueno<\/em><\/p>\n<p><strong>La creaci\u00f3n muy buena<\/strong><\/p>\n<p><strong><br \/>I .<\/strong><\/p>\n<p>\u00bfPor qu\u00e9 fue muy bueno? <\/p>\n<p><strong>1.<\/strong> Era la descendencia de la sabidur\u00eda infinita y el poder y el amor. <\/p>\n<p><strong>2.<\/strong> Porque guiado a la existencia por Jes\u00fas. <\/p>\n<p><strong>3.<\/strong> Porque no hab\u00eda maldad en ello. <\/p>\n<p><strong>4.<\/strong> Porque era como Dios. <\/p>\n<p><strong><br \/>II.<\/strong> \u00bfQU\u00c9 fue muy bueno? Todo lo que \u00c9l hab\u00eda hecho. <\/p>\n<p><strong><br \/>III.<\/strong> \u00bfQu\u00e9 tan buenos son? En s\u00ed mismos, en sus prop\u00f3sitos, en sus arreglos. <\/p>\n<p><strong><br \/>IV.<\/strong> \u00bfEST\u00c1 TODO MUY BIEN TODAV\u00cdA? Dios est\u00e1 sacando cosas muy buenas de la aparente frustraci\u00f3n de su plan. \u00c9l est\u00e1 restaurando lo que ahora es muy malo para que sea muy bueno. (<em>J. Bolton.<\/em>)<\/p>\n<\/p>\n<p><strong>La buena creaci\u00f3n<\/strong><\/p>\n<p>Nadie nos puede probar que Dios hizo el mundo; pero la fe, que es m\u00e1s fuerte que todos los argumentos, nos da certeza de ello. <\/p>\n<p><strong>1.<\/strong> Todo lo que Dios ha hecho es bueno, como \u00c9l lo es, y, por lo tanto, si algo en el mundo parece ser malo, una de dos cosas debe ser cierta de eso. <\/p>\n<p><strong>(1)<\/strong> O no es malo, aunque a nosotros nos lo parezca, y Dios sacar\u00e1 de ello bien a su debido tiempo; o <\/p>\n<p><strong>(2)<\/strong> si la cosa es realmente mala, entonces Dios no la hizo. Debe ser una enfermedad, un error, un fracaso de la malta del hombre, o de la creaci\u00f3n de alguna persona, pero no de la creaci\u00f3n de Dios. Porque todo lo que ha hecho lo ve eternamente, y he aqu\u00ed, es muy bueno. <\/p>\n<p><strong>2.<\/strong> Dios nos cre\u00f3 a cada uno de nosotros buenos en Su propia mente, de lo contrario no nos habr\u00eda creado en absoluto. \u00bfPor qu\u00e9 parece haber fracasado el pensamiento de Dios sobre nosotros, el prop\u00f3sito de Dios sobre nosotros? No sabemos, y no necesitamos saber. Sea cual sea el pecado que heredamos de Ad\u00e1n, Dios nos mira ahora, no como somos en Ad\u00e1n, sino como somos en Cristo. Dios no mira la vieja naturaleza corrupta que heredamos de Ad\u00e1n, sino la nueva y buena gracia que Dios ha destinado para nosotros desde toda la eternidad, que Cristo nos ha dado ahora. <\/p>\n<p><strong><br \/>III.<\/strong> Lo bueno que hay en nosotros lo ha hecho Dios; \u00c9l cuidar\u00e1 de lo que ha hecho, porque lo ama. Todo lo que es malo en nosotros no lo ha hecho Dios, y por tanto lo destruir\u00e1; porque \u00c9l odia todo lo que \u00c9l no ha hecho, y no lo tolerar\u00e1 en Su mundo. Antes de todos los mundos, desde la misma eternidad, Dios dijo: \u201cHagamos al hombre a nuestra semejanza\u201d, y nada puede obstaculizar la palabra de Dios sino el hombre mismo. Si un hombre ama su naturaleza ca\u00edda m\u00e1s que la noble, justa y amorosa gracia de Dios, y se entrega voluntariamente a la semejanza de las bestias que perecen, s\u00f3lo entonces el prop\u00f3sito de Dios para con \u00e9l puede quedar sin efecto. (<em>C. Kingsley, MA<\/em>)<\/p>\n<\/p>\n<p><strong>Dios en la naturaleza; o, lecciones de primavera<\/strong><\/p>\n<p><strong><br \/>I.<\/strong> ASPECTOS DE LA NATURALEZA DIVINA. <\/p>\n<p><strong>1.<\/strong> La incesante e infinita energ\u00eda de Dios. <\/p>\n<p><strong>2.<\/strong> La bienaventuranza y la belleza de Dios. <\/p>\n<p><strong><br \/>II.<\/strong> LECCIONES ACERCA DE LA VIDA HUMANA. Es una comparaci\u00f3n antigua, pero verdadera, de esta vida con las estaciones del a\u00f1o. La primavera siempre ha sugerido la naturaleza refrescante, prometedora, transitoria y cambiante de los primeros d\u00edas de la vida. Pero n\u00f3tese, especialmente, la mejora de la vida. Primavera, la temporada de cultivo. Condicional. La primavera descuidada, el oto\u00f1o muestra campos yermos. Precario. Los brotes, etc. pueden arruinarse. Necesidad de velar, etc. <\/p>\n<p><strong><br \/>III.<\/strong> SUGERENCIAS SOBRE EL DESTINO HUMANO. En primavera \u201ctodas las cosas se hacen nuevas\u201d. Ser \u201cjoven otra vez\u201d ha sido el sue\u00f1o de todos los tiempos. La prueba clara de la juventud inmortal m\u00e1s all\u00e1 de la tumba la da \u00fanicamente Cristo, \u201cel Primog\u00e9nito de los muertos\u201d. (<em>J. Foster, BA<\/em>)<\/p>\n<\/p>\n<p><strong><br \/>I.<\/strong> LAS VERDADES NATURALES AFIRMADAS. <\/p>\n<p><strong>La aprobaci\u00f3n de Dios de sus obras<\/strong><\/p>\n<p><strong>1.<\/strong> El verdadero origen de todas las cosas. <\/p>\n<p><strong>2.<\/strong> La perfecci\u00f3n original de todas las cosas. <\/p>\n<p><strong>(1)<\/strong> Muy bien, por estar bien adaptado para responder a su intenci\u00f3n particular.<\/p>\n<p><strong>(2)<\/strong> Muy bien, como bien calculada para promover la gloria de su Hacedor. <\/p>\n<p><strong>(3)<\/strong> Muy bueno, por ser conducente a la perfecci\u00f3n y al bienestar de todos <\/p>\n<p><strong>3.<\/strong> Aprobaci\u00f3n de Dios de Sus trabajos. <\/p>\n<p><strong><br \/>II.<\/strong> LAS VERDADES MORALES SUGERIDAS. <\/p>\n<p><strong>1.<\/strong> Viendo que Dios hab\u00eda hecho por el hombre todo lo que su caso admit\u00eda, tanto en cuanto a s\u00ed mismo como al mundo que le rodeaba, cuyas bendiciones le fueron dadas ricamente para disfrutar, se sigue que el hombre estaba bajo las mayores obligaciones posibles, en sus circunstancias presentes entonces. <\/p>\n<p><strong>2.<\/strong> El pecado es a la vez la injusticia m\u00e1s vil y la ingratitud m\u00e1s vil que se pueda imaginar <span class='bible'>Isa 1:2; <span class='bible'>Mal 1:6<\/span>). <\/p>\n<p><strong>3.<\/strong> La persistencia en el pecado es la imprudencia m\u00e1s atrevida. Seg\u00fan esa constituci\u00f3n de las cosas que era \u201cmuy buena\u201d, la santidad y la felicidad iban juntas. El pecado, al violar esa constituci\u00f3n, \u201ctrajo la muerte al mundo con todos nuestros males\u201d. <\/p>\n<p><strong>4.<\/strong> La reforma es agradable a Dios. Aprobaba las cosas en su estado original. \u00c9l es inmutable. <\/p>\n<p><strong>5.<\/strong> El texto sugiere una lecci\u00f3n de humildad. \u201c\u00a1C\u00f3mo se oscurece el oro!\u201d la imagen divina borrada I La humildad se convierte en toda criatura racional, a causa de su deuda y de su dependencia. <\/p>\n<p><strong>6.<\/strong> El texto proporciona un terreno de esperanza y aliento. Proclama la bondad de Aquel con quien tenemos que ver; y por eso nos anima a esperar en su misericordia. Recordemos, sin embargo, que es con el evangelio que estamos en deuda para convertir la esperanza en seguridad (<span class='bible'>Rom 8:32<\/span>). (<em>Bosquejos de sermones.<\/em>)<\/p>\n<\/p>\n<p><strong>La aprobaci\u00f3n de Dios de sus obras<\/strong><\/p>\n<p>Consideremos- &#8211;<\/p>\n<p><strong><br \/>I.<\/strong> Las verdades naturales afirmadas por nuestro texto. Entre estos est\u00e1n&#8211;<\/p>\n<p><strong>1.<\/strong> El verdadero origen de todas las cosas&#8211;\u201cDios vio todo lo que hab\u00eda hecho.\u201d <\/p>\n<p><strong>2.<\/strong> La perfecci\u00f3n original de todas las cosas \u00abmuy buenas\u00bb, \u00abmuy buenas\u00bb, como siendo&#8211;<\/p>\n<p><strong>(1)<\/strong> Bien adaptado para responder a su intenci\u00f3n particular. <\/p>\n<p><strong>(2)<\/strong> Conduce a la perfecci\u00f3n del todo. <\/p>\n<p><strong>(3)<\/strong> Bien calculado para promover la gloria del Creador. <\/p>\n<p><strong>3.<\/strong> La aprobaci\u00f3n de Dios de Su obra. Lo vio muy bien. <\/p>\n<p><strong><br \/>II.<\/strong> Las verdades morales sugeridas. <\/p>\n<p><strong>1.<\/strong> Agradecimiento. <\/p>\n<p><strong>2.<\/strong> Odio al pecado. <\/p>\n<p><strong>3.<\/strong> La interrupci\u00f3n de todo mal. <\/p>\n<p><strong>4.<\/strong> Reforma y retorno a la virtud. <\/p>\n<p><strong>5.<\/strong> Humildad. <\/p>\n<p><strong>6.<\/strong> Un terreno de esperanza y aliento. <\/p>\n<p><strong>Todo en especie se perfeccion\u00f3 a la vez en la creaci\u00f3n<\/strong><\/p>\n<p>Todos los artistas, en lo que hacen, tienen sus dudas (y esas suelen ser los mejores); como, por ejemplo, un relojero se pone a trabajar (siendo la primera vez que los hombres sol\u00edan llevar un pasatiempo en los bolsillos), pero, despu\u00e9s de haberlo considerado mejor, hace otro, y un tercero, algunos ovaladas, algunas redondas, algunas cuadradas, todas agregando brillo y perfecci\u00f3n a la primera invenci\u00f3n, mientras que, hasta ahora, eran m\u00e1s bien como sartenes calientes, para cansarnos, que piezas de advertencia, para advertirnos sobre c\u00f3mo pasaba el tiempo. Lo mismo puede decirse del famoso arte de la imprenta, la pintura y dem\u00e1s, superando todas ellas a las primeras copias que se propusieron. Pero no fue as\u00ed con Dios en la creaci\u00f3n de las diversas especies de la naturaleza; Los hizo todos perfectos, <em>simul et semel, <\/em>a la vez, todo <em>pondere et mensura, <\/em>tan justo, tan proporcionado en las partes, tan elemental armon\u00eda, tal simetr\u00eda en los cuerpos de los animales, tal correspondencia de los vegetales, que nada es defectuoso, ni se puede a\u00f1adir nada a su perfecci\u00f3n. (<em>J. Spencer.<\/em>)<\/p>\n<\/p>\n<p><strong>El amor por la belleza: en la naturaleza<\/strong><\/p>\n<p>En estos palabras m\u00e1s simples y misteriosas se nos dice claramente que en el principio el Creador de este mundo se deleit\u00f3 en la belleza de su forma exterior. La aprob\u00f3 no s\u00f3lo como apta para el desarrollo material que hab\u00eda dise\u00f1ado para ella, apta para las eras de cambio, el curso de la historia que deber\u00eda ser promulgada en ella, sino tambi\u00e9n como exteriormente deleitable. Vio su obra, y he aqu\u00ed, a la vista era muy buena. Aparte de todos los usos a los que servir\u00eda, su aspecto exterior estaba en armon\u00eda con una cierta ley divina: y por este Dios Todopoderoso juzg\u00f3 que era muy bueno. Si los hombres miraran con franqueza el primer cap\u00edtulo del G\u00e9nesis, sin timidez ni injusticia, seguramente parecer\u00eda muy extra\u00f1o encontrar esta anticipaci\u00f3n simple y completa de un pensamiento que, aunque ha estado en movimiento en el mundo durante muchos siglos, ha s\u00f3lo en los \u00faltimos a\u00f1os recibi\u00f3 su debido \u00e9nfasis y su l\u00f3gica fuerza. Me refiero al pensamiento de que nuestro deleite en la belleza visible de este mundo s\u00f3lo puede explicarse por la creencia de que el mundo ha sido hecho de alguna manera para darnos este deleite por un Ser que \u00c9l mismo sabe lo que es la belleza: y que la belleza de La naturaleza es una comunicaci\u00f3n real que se nos hace sobre la mente y la voluntad que est\u00e1n detr\u00e1s de la naturaleza. . . Entonces tenemos derecho a decir que la cualidad o el car\u00e1cter que puede hablar y apelar a nuestro esp\u00edritu debe haber sido engendrado en este mundo visible por un Ser espiritual capaz y dispuesto a entrar en comuni\u00f3n con nosotros, y sabiendo lo que afectar\u00eda y elevar\u00eda. nuestros pensamientos. Cuando recibimos y leemos una carta, estamos seguros de que ha venido de alguien que conoc\u00eda nuestro idioma y sab\u00eda escribirlo. Cuando escuchamos una hermosa pieza musical, estamos seguros de que el compositor ten\u00eda un conocimiento te\u00f3rico o al menos pr\u00e1ctico de las leyes y los efectos de la armon\u00eda. Y cuando a la vista de un gran paisaje, rico y tranquilo en la casta gloria del oto\u00f1o, o alegre con la brillante promesa, la intr\u00e9pida libertad de la primavera, todo nuestro coraz\u00f3n se llena de felicidad, y todos los sentidos parecen conmovidos por algo. de un placer que estaba destinado a \u00e9l, y todas las palabras son absolutamente demasiado pobres para elogiar la vista, entonces seguramente, con un argumento tan bueno, debemos decir que, a trav\u00e9s de cualquier forma y medio, el mundo recibi\u00f3 su aspecto exterior por el voluntad de alg\u00fan ser que conoc\u00eda la ley y la verdad de la belleza. No importa, en lo que se refiere a esta inferencia, c\u00f3mo se ha llegado al resultado, o cu\u00e1ntas edades y miles de causas secundarias se remontan entre el comienzo de la obra y su aspecto actual: es hermoso ahora: ahora habla a nosotros en un idioma que nuestros esp\u00edritus entienden: y, por mucho tiempo que haya pasado, y de la manera que sea, s\u00f3lo un ser espiritual podr\u00eda haberlo ense\u00f1ado por as\u00ed decirlo. Cualquiera que sea el significado de la creaci\u00f3n, el mundo fue creado por Aquel que pod\u00eda deleitarse en la belleza: cada vez que su Autor mir\u00f3 Su obra, debe haber visto que era muy buena. Por \u00faltimo, pero sobre todo, si vamos a recibir de la belleza visible de la mundo todo lo que puede revelarnos acerca de Aquel que lo hizo y lo alab\u00f3, debemos acercarnos a \u00e9l con atenta obediencia a su propia condici\u00f3n para tan grande bendici\u00f3n: \u201cBienaventurados los de limpio coraz\u00f3n, porque ellos ver\u00e1n a Dios\u201d. El fundador de la ciencia inductiva dijo noblemente que para entrar en el reino del conocimiento, como para entrar en el reino de los cielos, los hombres deben volverse como ni\u00f1os peque\u00f1os. Deben acercarse con corazones libres y humildes si han de entrar en los misterios de la ciencia natural: no deben dictar a la Naturaleza, ni afirmarse en su presencia: deben acercarse a ella con afectuosa atenci\u00f3n para esperar su revelaci\u00f3n. . (<em>F. Paget, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Admiraci\u00f3n por la obra terminada<\/strong><\/p>\n<p>\u201cEl Se\u00f1or se regocija en sus obras.\u201d \u00a1Qu\u00e9 frase tan maravillosa es esa! Ese hombre debe haber sido inspirado cuando dijo que Dios descans\u00f3 de Sus trabajos, y mir\u00f3 Sus obras, y las declar\u00f3 buenas. De todas las alegr\u00edas, esa es la m\u00e1s grande y sublime, revisar el propio trabajo y declararlo bueno. No hay pasaje en ingl\u00e9s mucho m\u00e1s hermoso que el que describe al autor de esa gran obra sobre \u201cFalling Rome\u201d (Gibbon) cuando acababa de llegar a la conclusi\u00f3n de su tarea. Caminando all\u00ed bajo los \u00e1rboles de Lausana, \u00e9l, como un verdadero artista, retrocedi\u00f3 y admir\u00f3 su obra terminada. Y ten\u00eda raz\u00f3n. Porque hay momentos en que un hombre puede mirar su trabajo y decir: \u00ab\u00a1Eso es genial!\u00bb Cuando Swift estaba empezando a hacer, tom\u00f3 de un estante uno de sus propios trabajos y exclam\u00f3: \u00ab\u00a1Qu\u00e9 genio debo haber tenido cuando hice eso!\u00bb (<em>G. Dawson.<\/em>)<\/p>\n<\/p>\n<p><strong>Perfecci\u00f3n de la naturaleza<\/strong><\/p>\n<p>He visto la parte de atr\u00e1s de una pintura espl\u00e9ndida, y all\u00ed, en el lienzo polvoriento, hab\u00eda manchas y manchas de color: los experimentos del pincel del pintor. \u00a1No hay nada que responda a eso en las obras de Dios! He visto el final de una pieza de terciopelo costoso; y aunque el hombre hab\u00eda imitado bastante el capullo de la fruta y el terciopelo de las flores, hab\u00eda un orillo com\u00fan, sin labrar, sin valor, un orillo tosco y antiest\u00e9tico. \u00a1No hay orillo en las obras de Dios! (<em>H. Wonnacott.<\/em>)<\/p>\n<\/p>\n<p><strong>Un mundo bonito<\/strong><\/p>\n<p>Yo una vez, escribe Joaqu\u00edn Miller , paseaba por un m\u00edsero pueblo mexicano. Las sombras se arrastraban sobre las caba\u00f1as, donde las mujeres entraban y sal\u00edan en silencio, y los hombres fumaban sentados a las puertas de las caba\u00f1as, mientras los ni\u00f1os jugaban en enjambres junto al agua. El aire era como un soplo de Dios, y toda la naturaleza parec\u00eda tan sagrada como el descanso para un hombre cansado. Una anciana negra, encorvada, toda manchada de la cabeza a los pies, con la cabeza helada y medio ciega, sali\u00f3 canturreando con una maceta rota atada, en la que hab\u00eda plantado una flor que crec\u00eda junto a su puerta. Me detuve, la vi dejarlo y arreglarlo; y luego, no queriendo mirar con rudeza a esta vieja criatura encorvada, dije: \u201cBuenas noches, t\u00eda; es una buena tarde. Lentamente se enderez\u00f3, me mir\u00f3, desvi\u00f3 la mirada hacia la luz del sol que se desvanec\u00eda en las colinas y dijo suavemente: \u00ab\u00a1Oh, es un mundo hermoso, ama!\u00bb La anciana era una poetisa, una profetisa. Ten\u00eda un alma para ver la belleza, la poes\u00eda sobre ella. \u00ab\u00a1Oh, es un mundo bonito, masa!\u00bb No ten\u00eda otra forma de expresi\u00f3n, pero eso fue suficiente. La suya era la contrase\u00f1a de la naturaleza. \u201cY vio Dios todo lo que hab\u00eda hecho, y he aqu\u00ed que era muy bueno\u201d.<\/p>\n<p><strong> <br \/><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gn 1:31 Y vio Dios todo lo que hab\u00eda hecho, y he aqu\u00ed que era muy bueno La creaci\u00f3n muy buena I . \u00bfPor qu\u00e9 fue muy bueno? 1. Era la descendencia de la sabidur\u00eda infinita y el poder y el amor. 2. Porque guiado a la existencia por Jes\u00fas. 3. Porque no hab\u00eda maldad &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-genesis-131-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de G\u00e9nesis 1:31 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-31747","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/31747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=31747"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/31747\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=31747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=31747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=31747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}