{"id":31751,"date":"2022-07-16T03:02:17","date_gmt":"2022-07-16T08:02:17","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-genesis-25-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T03:02:17","modified_gmt":"2022-07-16T08:02:17","slug":"estudio-biblico-de-genesis-25-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-genesis-25-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de G\u00e9nesis 2:5 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Gen 2:5<\/span><\/p>\n<p><em>Toda planta de el campo<\/em><\/p>\n<p><strong>La hoja<\/strong><\/p>\n<p>Una de las m\u00e1s bellas generalizaciones cient\u00edficas fue el resultado, no de las pacientes, perseverantes investigaciones del naturalista , sino del ensue\u00f1o so\u00f1ador de un compa\u00f1ero.<\/p>\n<p>En la mente meditativa de Goethe en una ocasi\u00f3n amaneci\u00f3 la brillante idea de que la flor de una planta no es, como com\u00fanmente se supone, un \u00f3rgano a\u00f1adido o separado , sino s\u00f3lo el desarrollo m\u00e1s alto, o m\u00e1s bien la transformaci\u00f3n de sus hojas, que todas las partes de una planta, desde la semilla hasta la flor, son meras modificaciones de una hoja. Esta sola idea ha hecho m\u00e1s para levantar el velo del misterio de la naturaleza, y para interpretar los planes y prop\u00f3sitos del Creador, que todos los trabajos anteriores de los bot\u00e1nicos. Nos muestra el orden en medio de la confusi\u00f3n; sencillez en medio de una complejidad aparentemente inextricable; unidad de plan en medio de una infinita diversidad de formas. Thoreau, observando las frondosas expansiones de la vegetaci\u00f3n helada en el cristal de la ventana y en las briznas de hierba, declar\u00f3 que \u00abel Hacedor de esta tierra patent\u00f3 una hoja\u00bb. Traz\u00f3 el patr\u00f3n de la hoja a lo largo de todos los reinos de la Naturaleza. Lo vio en las brillantes plumas de los p\u00e1jaros; en las lustrosas alas de los insectos; en las escamas nacaradas de los peces; en la palma de venas azules de la mano humana; y en la concha de marfil del o\u00eddo humano. La tierra misma, seg\u00fan \u00e9l, no es m\u00e1s que una vasta hoja veteada con r\u00edos y arroyos de plata, con irregularidades de superficie formadas por monta\u00f1as y valles, y variados matices de verde en bosques y campos, y grandes espacios brillantes de mar y lago. Esto, sin embargo, es una mera idea trascendental cuando se aplica as\u00ed a todos los departamentos de la naturaleza; es verdad cient\u00edfica s\u00f3lo cuando se limita al reino vegetal. Pero la unidad de la que habla se puede rastrear en todas partes. Todos los recientes descubrimientos de la ciencia, tanto en lo que se refiere a las formas como a las fuerzas de la materia, tienen una evidente tendencia a simplificar mucho el esquema de la naturaleza ya reducir sus fen\u00f3menos a la operaci\u00f3n de unas pocas leyes simples; y en este sentido tienen un significado teol\u00f3gico profundo. En medio de estas brillantes generalizaciones, no podemos detenernos en seco hasta que hayamos alcanzado la m\u00e1s alta y sublime generalizaci\u00f3n, y la naturaleza nos haya conducido por tan grandes escalones de altar hasta el Dios de la naturaleza. La teor\u00eda de la hoja, como base del reino vegetal, requiere una explicaci\u00f3n m\u00e1s particular. Todas las plantas se producen a partir de semillas o brotes; el uno libre, el otro adjunto; uno extendiendo la planta geogr\u00e1ficamente, el otro aumentando su tama\u00f1o individual. Examinada cuidadosamente, la semilla, o el punto de partida en la vida de una planta, se compone de una hoja enrollada y alterada en tejido y contenido, para adaptarse a sus nuevos requisitos. El verdadero car\u00e1cter de una semilla puede verse en la germinaci\u00f3n de un frijol, cuando las dos hojas que lo componen aparecen en los l\u00f3bulos carnosos o cotiledones que primero se elevan sobre la tierra y proporcionan alimento al embri\u00f3n. El capullo, o ep\u00edtome de la planta, que est\u00e1 fisiol\u00f3gicamente coordinado con la semilla, tambi\u00e9n consta de hojas plegadas de una manera peculiar y cubiertas de duras escamas cori\u00e1ceas para protegerlas del fr\u00edo del invierno; y en primavera desarrolla el tallo, las hojas y el fruto, en una palabra, toda estructura que procede de la semilla. Adem\u00e1s, todos los ap\u00e9ndices del tallo, como escamas, hojas, br\u00e1cteas, flores y frutos, son modificaciones de este tipo com\u00fan. Las flores, la gloria del mundo vegetal, son meras hojas, dispuestas para proteger los \u00f3rganos vitales dentro de ellas, y coloreadas para atraer insectos para esparcir el polen fertilizante, y para reflejar o absorber la luz y el calor del sol para madurando la semilla. Los estambres y pistilos pueden ser convertidos por la habilidad del jardinero en p\u00e9talos, y las flores as\u00ed producidas se llaman dobles y, por lo tanto, son necesariamente est\u00e9riles. La rosa silvestre, por ejemplo, tiene una sola corola; pero cuando se cultiva en un suelo f\u00e9rtil, sus numerosos estambres amarillos se transforman en las hojas rojas de la rosa de la col. Que todas las partes de la flor, c\u00e1liz, corola, estambres y pistilos, son hojas modificadas, lo prueba el hecho de que no es raro que una planta produzca hojas en lugar de ellas. Pasamos luego al fruto, que, en todas sus asombrosas variedades de textura, color y forma, es tambi\u00e9n una hoja modificada; y es uno de los estudios m\u00e1s interesantes de la historia natural, para rastrear la correspondencia entre las diferentes partes de estructuras tan alteradas y el tipo original. En el melocot\u00f3n, por ejemplo, el hueso es la piel superior de una hoja endurecida para proteger la semilla o semilla; la pulpa es el tejido celular de una hoja expandido y dotado de propiedades nutritivas para el sustento del embri\u00f3n vegetal; y la hermosa piel suave en el exterior es la cut\u00edcula inferior de la hoja con una flor de sol sobre ella, la l\u00ednea hueca en un lado de la fruta marca la uni\u00f3n entre los dos bordes de la hoja. As\u00ed tambi\u00e9n en la manzana; el n\u00facleo apergaminado es la superficie superior de la hoja, y la pulpa es el tejido celular muy hinchado; en la naranja, los labios jugosos que encierran las semillas son las distintas secciones de la hoja desarrolladas de manera extraordinaria; mientras que a trav\u00e9s de la piel transparente de la grosella madura, vemos las ramificaciones de las nervaduras de las hojas, probando de manera concluyente su origen. Entonces, en todas las partes y \u00f3rganos de la planta, desde la semilla hasta el fruto, hemos encontrado que la hoja es el tipo o patr\u00f3n seg\u00fan el cual se han construido; y esas modificaciones de estructura, color y composici\u00f3n que exhiben, son para prop\u00f3sitos especiales en la econom\u00eda de la planta en primer lugar, y en \u00faltima instancia para los servicios necesarios para la creaci\u00f3n animal, e incluso para el hombre mismo, a quien la dulzura del fruto y la belleza de la flor deben haber tenido referencia en las intenciones llenas de gracia de Aquel que los cre\u00f3 a ambos. En la hoja misma se puede leer, tan inequ\u00edvocamente como en una p\u00e1gina impresa, su significado morfol\u00f3gico. As\u00ed como el arquitecto dibuja en un plano el plano de un edificio, as\u00ed el Divino Artista ha grabado en la hoja el plano del organismo, del cual es el \u00fanico ap\u00e9ndice t\u00edpico esencial. Cada hoja en forma y formaci\u00f3n puede considerarse como una imagen en miniatura, un modelo de toda la planta en la que crece. El contorno de un \u00e1rbol en pleno follaje de verano puede verse representado en el contorno de cualquiera de sus hojas; el tejido celular uniforme que compone la superficie plana de la hoja equivale a la masa redonda e irregular del follaje. De hecho, las c\u00e9lulas verdes que revisten las nervaduras de la hoja y llenan todos sus espacios intermedios pueden considerarse an\u00e1logas a las hojas verdes que revisten las ramas del \u00e1rbol: y aunque la hoja est\u00e9 en un plano, hay muchos \u00e1rboles, como la playa, cuyo follaje, cuando se mira desde cierto punto de vista, tambi\u00e9n se ve que est\u00e1 en un plano. Los \u00e1rboles altos y piramidales tienen hojas angostas, como vemos en las agujas del pino; mientras que los \u00e1rboles de gran extensi\u00f3n, por otro lado, tienen hojas anchas, como se puede observar en las del olmo o sic\u00f3moro. En todos los casos, la correspondencia entre la forma de la hoja individual y la masa total del follaje es notablemente exacta, incluso en los m\u00e1s m\u00ednimos detalles, y no puede dejar de asombrar a cualquiera que la observe por primera vez. Examinando la hoja m\u00e1s detenidamente, encontramos que las venas fibrosas que se ramifican sobre su superficie se parecen mucho a la ramificaci\u00f3n del tronco y las ramas del \u00e1rbol padre; ambos se desprenden en los mismos \u00e1ngulos, y son tan exactamente iguales en su complejidad o simplicidad, que a partir de una sola hoja podemos predicar con la mayor certeza la apariencia de todo el \u00e1rbol del que cay\u00f3, al igual que el h\u00e1bil anatomista puede. construir en la imaginaci\u00f3n, a partir de un solo hueso o diente, todo el organismo animal del que formaba parte. En relaci\u00f3n con este car\u00e1cter t\u00edpico general de la hoja, puede verse su significado t\u00edpico particular, como representante de las tres grandes clases en que se ha dividido el reino vegetal. Que sea posible determinar a partir de la hoja sola, o incluso del fragmento m\u00e1s peque\u00f1o de ella, qu\u00e9 posici\u00f3n asignar a cualquier planta dada en nuestros sistemas de clasificaci\u00f3n, se debe seguramente al hecho de que el plan de la hoja es la base sobre que toda la vegetaci\u00f3n, como un tipo distinto de vida, ha sido construida. La diversidad de formas que deja la exhibici\u00f3n no tiene fin; casi todas las especies de plantas tienen un tipo diferente de hoja. Pero casi nunca se nos ocurre preguntarnos el objeto de esta variaci\u00f3n de forma. Lo consideramos como algo natural, o lo referimos a esa variedad ilimitada que caracteriza todas las obras de la naturaleza, en acomodaci\u00f3n, suponemos orgullosa pero tontamente, al odio del hombre por la uniformidad. Pero la observaci\u00f3n y la reflexi\u00f3n nos convencer\u00e1n de que hay una raz\u00f3n especial para ello; que las formas de las hojas no son caprichosas ni accidentales, sino formadas seg\u00fan una ley invariable, el consejo de Su voluntad \u201ccon quien no hay mudanza ni sombra de variaci\u00f3n\u201d. En primer lugar hay una raz\u00f3n morfol\u00f3gica para ello. La forma de las hojas depende de la distribuci\u00f3n de las venas, y la distribuci\u00f3n de las venas sobre el modo de ramificaci\u00f3n en la planta, y el modo de ramificaci\u00f3n en la planta a su car\u00e1cter t\u00edpico como ex\u00f3genos o end\u00f3genos, y su car\u00e1cter t\u00edpico trae nosotros de nuevo a la hoja. Cuando la hoja es simple, la ramificaci\u00f3n del tallo y de las flores es simple; y cuando la hoja es compuesta, todas las partes de la planta tambi\u00e9n lo son. Pero adem\u00e1s de esta raz\u00f3n morfol\u00f3gica de la inmensa variedad de formas de las hojas, tambi\u00e9n existen razones teleol\u00f3gicas y geogr\u00e1ficas. Las hojas se adaptan no solo al car\u00e1cter t\u00edpico de toda la planta, sino tambi\u00e9n al car\u00e1cter de la situaci\u00f3n en la que crece. Est\u00e1n, adem\u00e1s, construidas exactamente para dar sombra y cobijo, o exponer libremente a la luz y al aire, las plantas sobre las que se encuentran, y para transmitir el roc\u00edo y la lluvia que caen sobre ellas a las j\u00f3venes ra\u00edces absorbentes. Aquel que estudie atenta y reverentemente las numerosas y maravillosas modificaciones en forma y estructura que experimenta la hoja t\u00edpica, para adaptarse a las variadas circunstancias de las plantas, ser\u00e1 llevado por este estudio, m\u00e1s de cerca que cualquier cosa fuera de la Biblia, a la presencia personal de Aquel que dijo: \u201cMi Padre hasta ahora trabaja, y yo trabajo\u201d. A menudo he tenido un tren de reflexiones de la clase m\u00e1s provechosa que se han despertado en mi mente simplemente mirando el ran\u00fanculo de agua com\u00fan, cuyas flores blancas cubren la superficie de muchos de nuestros tranquilos riachuelos en junio, y observando que las hojas flotan o la parte superior del agua eran redondos y anchos, mientras que los inferiores, sumergidos en la corriente, estaban divididos en un gran n\u00famero de segmentos lineales, para no obstaculizar la corriente ni ser desgarrados por su fuerza. Incluso al contemplar la aulaga com\u00fan o el chirrido de nuestras laderas -una planta, aparte de la gloria dorada con la que el verano la aureola, no muy atractiva para el amante de la belleza- me ha sorprendido a menudo la misma adaptaci\u00f3n a la naturaleza. corrientes tempestuosas del aire, en sus hojas y tallos afilados como agujas, prueba del cuidado de Dios sobre la cosa m\u00e1s sencilla, dando m\u00e1s honor a lo que carec\u00eda de ella. Pero a\u00fan despertar\u00e1n sentimientos de mayor inter\u00e9s las adaptaciones m\u00e1s maravillosas que vemos en las plantas tropicales que crecen en nuestros conservatorios. La mimosa, peculiarmente expuesta a heridas, sensiblemente deja caer sus hojas al menor contacto; la planta de c\u00e1ntaro, sosteniendo sus copas de hojas llenas de agua para refrescarse en el desierto sediento; la hoja de la trampa para moscas de Venus de Am\u00e9rica del Norte, que se cierra sobre su presa girando sobre su nervadura central como si fuera una bisagra; la hoja del cactus que crece en las secas mesetas de M\u00e9xico, carnosa y jugosa, y sin poros de evaporaci\u00f3n en su piel, de modo que retiene la humedad absorbida por la ra\u00edz; la hoja gigantesca del nen\u00fafar real de Am\u00e9rica del Sur, provista en el env\u00e9s de sobresalientes venas de gran profundidad, haciendo de tantas costillas de sost\u00e9n: estos y otros mil casos casi igualmente notables, que cabr\u00eda aludir, atraen a los m\u00e1s descuidados ojo, y en sus extra\u00f1as variaciones de la forma t\u00edpica, revelan abundante prueba de dise\u00f1o ben\u00e9fico. Los colores, as\u00ed como las formas de las hojas, est\u00e1n maravillosamente diversificados, aunque el verde es el matiz predominante, y cada matiz variado de ese color, desde el m\u00e1s oscuro al m\u00e1s claro, se exhibe, y muy bellamente, por ejemplo, en el verdor. de primavera; sin embargo, toda la escala crom\u00e1tica puede verse ilustrada en el follaje de las plantas. De hecho, donde es posible ver crecer juntos espec\u00edmenes de todo el reino vegetal, un bosque oto\u00f1al no exhibir\u00eda mayores variedades de follaje coloreado. En algunas plantas, las hojas son tan hermosas como las flores de otras plantas: y ahora se cultivan y agrupan con gran efecto en nuestros conservatorios. Un invernadero lleno de plantas bellamente foliadas es tan atractivo como uno repleto de alegres flores. Es una circunstancia notable que cuando las hojas est\u00e1n vestidas con un esplendor carmes\u00ed brillante, dorado o plateado, las flores son casi invariablemente de un tono sombr\u00edo e insignificantes en forma y tama\u00f1o. Para qu\u00e9 prop\u00f3sitos pueden servir hojas tan hermosas en la econom\u00eda de la vegetaci\u00f3n, no podemos averiguarlo satisfactoriamente en todos los casos. Puede ser para absorber o reflejar la luz y el calor del sol de una manera peculiar, o para proteger los \u00f3rganos vitales de lesiones desviando la atenci\u00f3n de ellos. En las orqu\u00eddeas y otras plantas, las flores tienen un color magn\u00edfico y una forma peculiar para atraer a los insectos, sin cuya intervenci\u00f3n la especie no podr\u00eda fertilizarse ni propagarse. Pero en las plantas donde el follaje es grande y hermoso, y la flor diminuta y sombr\u00eda, parece como si la Naturaleza quisiera ocultar sus procesos vitales, para que no fueran frustrados o da\u00f1ados por los animales. Probablemente, tambi\u00e9n, la misma ley de compensaci\u00f3n puede ilustrarse en el caso de hojas coloreadas, como en la corola irregular de las flores, donde el p\u00e9talo impar tiene un color diferente y mucho m\u00e1s brillante, como en el pensamiento com\u00fan. Estas curiosas plantas, que entre sus hojas de luz no tienen necesidad de flores, \u00bfno se asemejan a esas seductoras plantas humanas, que desarrollan todas las bellezas de la mente y el car\u00e1cter a una edad excepcionalmente temprana, y r\u00e1pidamente maduran para la tumba? No viven para producir las flores y el fruto de la flor vigorosa de la vida; y por eso Dios convierte su follaje en flores, corona la etapa inicial con las glorias de la final, y embellece sus mismas hojas. Por la transfiguraci\u00f3n de su gracia, por la luz que nunca hubo en el mar ni en la tierra, \u00c9l adorna incluso sus tiernos a\u00f1os con toda la hermosura que en otros casos s\u00f3lo llega con la plena madurez. (<em>H. Macmillan, LL. D.<\/em>)<\/p>\n<\/p>\n<p><strong>No hab\u00eda hombre para labrar la tierra<\/strong>&lt;\/p <\/p>\n<p><strong>La tierra sin hombre<\/strong><\/p>\n<p><strong><br \/>I.<\/strong> LA INDEPENDENCIA MUNDIAL DEL HOMBRE. El globo terr\u00e1queo, engastado en esos cielos maravillosos y lleno de todas las especies de vida vegetal y animal, exist\u00eda antes de que apareciera el hombre. <\/p>\n<p><strong>1.<\/strong> El mundo puede prescindir de \u00e9l. Los cielos ser\u00edan tan brillantes, la tierra tan hermosa, las olas del oc\u00e9ano tan sublimes, el canto de los p\u00e1jaros tan dulce; ya no somos hombre. <\/p>\n<p><strong>2.<\/strong> No puede prescindir del mundo. Necesita cielos brillantes, r\u00edos caudalosos, suelo productivo, etc. Es la m\u00e1s dependiente de todas las criaturas. <\/p>\n<p><strong><br \/>II.<\/strong> LA INCOMPLETITUD DEL MUNDO SIN EL HOMBRE. Sin el hombre, el mundo ser\u00eda una escuela sin alumno, un teatro sin espectador, una mansi\u00f3n sin residente, un templo sin adorador. Aprende de este tema&#8211;<\/p>\n<p><strong>1.<\/strong> La lecci\u00f3n de adorar la gratitud al Creador. Ad\u00f3ralo por el hecho, las capacidades y la esfera de tu existencia. <\/p>\n<p><strong>2.<\/strong> La lecci\u00f3n de profunda humildad. El mundo puede prescindir de ti, hermano m\u00edo; ha hecho sin ti; y har\u00e9 sin ti. <\/p>\n<p><strong><br \/>III.<\/strong> EL RECLAMO DEL MUNDO SOBRE EL HOMBRE. \u201c\u00c9l ha dado la tierra a los hijos de los hombres\u201d. La naturaleza de este don proclama la obligaci\u00f3n del receptor. <\/p>\n<p><strong>1.<\/strong> El mundo est\u00e1 lleno de tesoros materiales; desarrollarlos y usarlos. <\/p>\n<p><strong>2.<\/strong> El mundo es f\u00e9rtil en lecciones morales; interpretarlos y aplicarlos. <\/p>\n<p><strong>3.<\/strong> El mundo est\u00e1 lleno de la presencia de Dios; caminar con reverencia. (<em>Homil\u00eda.<\/em>)<\/p>\n<\/p>\n<p><strong>Observaciones<\/strong><\/p>\n<p><strong><br \/>I.<\/strong> TODA HIERBA Y PLANTA SOBRE LA TIERRA ES CRIATURA DE DIOS. <\/p>\n<p><strong><br \/>II.<\/strong> NO S\u00d3LO LA MISERICORDIA DE DIOS ES GENERAL, SINO QUE TODA BENDICI\u00d3N EN PARTICULAR DEBE SER CONSIDERADA COMO PROCEDENTE DE DIOS. <\/p>\n<p><strong><br \/>III.<\/strong> LO QUE SE REALIZA SIN MEDIOS ORDINARIOS, NECESITA SER REALIZADO POR LA MANO Y EL PODER DEL MISMO DIOS. <\/p>\n<p><strong><br \/>IV.<\/strong> NO PUEDE HABER LLUVIA SOBRE LA TIERRA A MENOS QUE DIOS LA ENV\u00cdE. <\/p>\n<p><strong><br \/>V.<\/strong> ES POR LA LLUVIA DEL CIELO QUE TODAS LAS HIERBAS Y PLANTAS SOBRE LA FAZ DE LA TIERRA CRECEN Y SE NUTRIN. <\/p>\n<p><strong><br \/>VI.<\/strong> AUNQUE A DIOS LE COMPLACE UTILIZARSE DEL TRABAJO DEL HOMBRE PARA PRODUCIR Y CUIDAR LOS FRUTOS DE LA TIERRA, PUEDE AUMENTARLOS Y CONSERVARLOS SIN \u00c9L. <\/p>\n<p><strong><br \/>VII.<\/strong> AUNQUE LOS FRUTOS DE LA TIERRA PROVIENE SOLO POR LA BENDICI\u00d3N DE DIOS, SIN EMBARGO SE REQUIERE EL TRABAJO DEL HOMBRE COMO MEDIO ORDINARIO PARA PROMOVERLO. (<em>J. White.<\/em>)<\/p>\n<\/p>\n<p><strong>Observaciones<\/strong><\/p>\n<p><strong><br \/>I .<\/strong> DIOS NO QUIERE VARIEDAD DE MEDIOS PARA EFECTUAR LO QUE QUIERA. <\/p>\n<p><strong><br \/>II.<\/strong> DIOS PUEDE, Y MUCHAS VECES LO HACE, HACER QUE LAS COSAS SUCEDAN SIN NING\u00daN MEDIO. <\/p>\n<p><strong><br \/>III.<\/strong> EL PODER DE DIOS PARA EFECTUAR TODAS LAS COSAS NUNCA ES CLARAMENTE DESCUBIERTO HASTA QUE TODO MEDIO SEA QUITADO. <\/p>\n<p><strong><br \/>IV.<\/strong> TODA CRIATURA DEBE SER \u00daTIL DE MANERA ESPECIAL A AQUEL DE DONDE SE PRODUCE. (<em>J. White.<\/em>)<\/p>\n<\/p>\n<p><strong>Se busca un jardinero<\/strong><\/p>\n<p>Aqu\u00ed comienza ese gran sistema de Cooperaci\u00f3n divina y humana que todav\u00eda est\u00e1 en progreso. Hab\u00eda \u00e1rboles, plantas, hierbas y flores, pero se necesitaba un jardinero para sacar de la tierra todo lo que la tierra pod\u00eda producir. Al plantar, trasplantar y volver a plantar, puede convertir un \u00e1rbol tosco en un raro esp\u00e9cimen bot\u00e1nico, puede refinarlo mediante el desarrollo. \u00a1As\u00ed que el hombre obtuvo algo para sus propios dolores y se convirti\u00f3 en una especie de creador secundario! Esto tambi\u00e9n fue demasiado para \u00e9l. Empez\u00f3 a pensar que casi todo lo hab\u00eda hecho \u00e9l mismo, olvidando por completo qui\u00e9n le dio los g\u00e9rmenes, las herramientas, la habilidad y el tiempo. \u00a1Es tan f\u00e1cil para ustedes, socios menores en firmas de la ciudad vieja, pensar que la \u00abcasa\u00bb no habr\u00eda estado en ninguna parte si no se hubieran asociado! Pero real y verdaderamente, por extra\u00f1o que parezca, hab\u00eda una \u201ccasa\u201d antes de que la tomaras y la glorificaras. \u00a1Qu\u00e9 oportunidad tuvo el hombre de comenzar su vida como jardinero! \u00a1Comenzando la vida al aire libre y soleado, sin siquiera un invernadero para probar su temperamento! Seguramente deber\u00eda haber hecho algo mejor de lo que hizo. El aire era puro, el clima era brillante, el suelo era amable: no hab\u00eda m\u00e1s que \u00abhacerle cosquillas con una pala y re\u00eda en flores\u00bb. \u00a1Y un r\u00edo en los terrenos! \u00a1Ay de los que tienen el agua lejos para ir a buscarla! Pero aqu\u00ed en el jard\u00edn est\u00e1 el arroyo, tan ancho que en el momento en que es liberado del lugar sagrado se divide en cuatro evangelistas, llevando por todas partes los olores del Ed\u00e9n y la oferta de una bondadosa ayuda. Seguramente, entonces, el hombre estaba bien alojado para empezar. \u00c9l no comenz\u00f3 su vida como un mendigo. Cultiv\u00f3 su propia tierra dada por Dios, sin enfermedades, incapacidades o impuestos que lo preocuparan; sin embargo, \u00bfqu\u00e9 hizo \u00e9l con la herencia fruct\u00edfera? \u00bfSe convirtieron las ra\u00edces en veneno en su boca, y las flores agacharon sus cabezas avergonzadas cuando su sombra cay\u00f3 sobre ellas? Ya veremos. (<em>J. Parker, DD<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gen 2:5 Toda planta de el campo La hoja Una de las m\u00e1s bellas generalizaciones cient\u00edficas fue el resultado, no de las pacientes, perseverantes investigaciones del naturalista , sino del ensue\u00f1o so\u00f1ador de un compa\u00f1ero. En la mente meditativa de Goethe en una ocasi\u00f3n amaneci\u00f3 la brillante idea de que la flor de una planta &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-genesis-25-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de G\u00e9nesis 2:5 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-31751","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/31751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=31751"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/31751\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=31751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=31751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=31751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}