{"id":31765,"date":"2022-07-16T03:02:52","date_gmt":"2022-07-16T08:02:52","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-genesis-313-21-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T03:02:52","modified_gmt":"2022-07-16T08:02:52","slug":"estudio-biblico-de-genesis-313-21-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-genesis-313-21-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de G\u00e9nesis 3:13-21 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Gn 3,13-21<\/span><\/p>\n<p> <em>\u00bfQu\u00e9 es esto que has hecho?<\/em><\/p>\n<p>&#8212;<\/p>\n<p><strong>Los resultados generales de la Ca\u00edda<\/strong><\/p>\n<p> &gt;<strong><br \/>I.<\/strong> ETERNA ENEMIGO ENTRE SATAN\u00c1S Y LA HUMANIDAD (<span class='bible'>Gn 3,14<\/span>). <\/p>\n<p><strong>1.<\/strong> Esta maldici\u00f3n fue pronunciada en referencia a Satan\u00e1s. <\/p>\n<p><strong>2.<\/strong> Este discurso es diferente al que se hizo a Ad\u00e1n y Eva. <\/p>\n<p><strong>3.<\/strong> Comenzar\u00eda una severa enemistad y conflicto entre Satan\u00e1s y la raza humana. <\/p>\n<p><strong>(1)<\/strong> Esta enemistad ha existido desde las edades tempranas de la historia del mundo.<\/p>\n<p><strong>(2)<\/strong> Esta enemistad es buscando la destrucci\u00f3n de los intereses superiores del hombre. <\/p>\n<p><strong>(3)<\/strong> Esta enemistad est\u00e1 inspirada en la pasi\u00f3n m\u00e1s diab\u00f3lica. <\/p>\n<p><strong>(4)<\/strong> Esta enemistad, aunque infligir\u00e1 da\u00f1o, est\u00e1 sujeta a la conquista final del hombre. <\/p>\n<p><strong><br \/>II.<\/strong> EL DOLOR Y SUJECI\u00d3N DE LA VIDA FEMENINA. <\/p>\n<p><strong>1.<\/strong> El dolor de la mujer como consecuencia de la Ca\u00edda. <\/p>\n<p><strong>2.<\/strong> La sujeci\u00f3n de la mujer como consecuencia de la Ca\u00edda. <\/p>\n<p><strong>3.<\/strong> La sujeci\u00f3n de la mujer como consecuencia de la Ca\u00edda no respalda la forma degradante en que se la trata en los pa\u00edses paganos. <\/p>\n<p><strong><br \/>III.<\/strong> EL TRABAJO ANSIOSO DEL HOMBRE Y LA IMPRODUCTIVIDAD COMPARATIVA DE SU TRABAJO. <\/p>\n<p><strong>1.<\/strong> El angustioso y doloroso trabajo del hombre como consecuencia de la Ca\u00edda. <\/p>\n<p><strong>2.<\/strong> La relativa improductividad del suelo como consecuencia de la Ca\u00edda. <\/p>\n<p><strong>3.<\/strong> La triste partida del hombre de la tierra por la muerte como consecuencia de la Ca\u00edda. <\/p>\n<p><strong><br \/>IV.<\/strong> LA GRANDIOSA Y MISERICORDIOSA INTERPOSICI\u00d3N DE JESUCRISTO SE HIZO NECESARIA POR LA CA\u00cdDA. Lecciones: <\/p>\n<p><strong>1.<\/strong> Las terribles influencias del pecado sobre la vida de un individuo. <\/p>\n<p><strong>2.<\/strong> Las influencias del pecado sobre las grandes comunidades del mundo. <\/p>\n<p><strong>3.<\/strong> La severa devastaci\u00f3n del pecado. <\/p>\n<p><strong>4.<\/strong> El amor de Dios la gran influencia sanadora del dolor del mundo. <\/p>\n<p><strong>5.<\/strong> Cu\u00e1n benignamente Dios mezcla la esperanza con el castigo. (<em>JS Exell, MA<\/em>)<\/p>\n<\/p>\n<p><strong>El primer pecado<\/strong><\/p>\n<p><strong><br \/>I.<\/strong> EL REGISTRO ANTE NOSOTROS ES LA HISTORIA DEL PRIMER PECADO. No necesit\u00f3 revelaci\u00f3n para decirnos que el pecado es, que la humanidad es pecaminosa. Fuera, dentro, alrededor y dentro de nosotros, est\u00e1 el hecho, la experiencia, la evidencia, la presencia del pecado. Es el pecado el que complica la vida y da el aguij\u00f3n a la muerte. La revelaci\u00f3n de la Ca\u00edda habla de una entrada, de una irrupci\u00f3n del mal en un mundo todo bien, en un ser creado recto; habla, por tanto, de una naturaleza capaz de pureza, de un enemigo que puede ser expulsado y de un la santidad es posible porque es natural. De la ca\u00edda del hombre inferimos una ca\u00edda anterior a\u00fan y m\u00e1s misteriosa. Una vez el pecado no existi\u00f3; y cuando entr\u00f3 en el mundo del hombre, entr\u00f3 bajo una influencia independiente, no inherente. <\/p>\n<p><strong><br \/>II.<\/strong> EL PRIMER PECADO ES TAMBI\u00c9N EL PECADO ESPEC\u00cdMEN. Es en este sentido, tambi\u00e9n, el pecado original, que todos los dem\u00e1s pecados son copias de \u00e9l. Primero la incredulidad, luego la desobediencia; luego corrupci\u00f3n, luego autoexcusaci\u00f3n; luego la maldici\u00f3n y la expulsi\u00f3n. \u00a1Pasa la p\u00e1gina y encontrar\u00e1s un asesinato! <\/p>\n<p><strong><br \/>III.<\/strong> EL PECADO ORIGINAL ES TAMBI\u00c9N EL PECADO INFECCIOSO. Ning\u00fan hombre de toda la progenie de Ad\u00e1n ha respirado por primera vez o por \u00faltima vez en una atm\u00f3sfera pura y saludable. Antes, detr\u00e1s, alrededor y arriba ha existido la herencia de la debilidad, la presencia y la presi\u00f3n de una influencia en gran parte maligna. Hijos ca\u00eddos de un antepasado ca\u00eddo, Dios debe hacer descender Su mano desde lo alto si queremos ser rescatados alguna vez de estas aguas profundas y turbias. (<em>Dean Vaughan.<\/em>)<\/p>\n<\/p>\n<p><strong>Los resultados morales y renales de la Ca\u00edda<\/strong><\/p>\n<p><strong><br \/>I.<\/strong> SUS RESULTADOS MORALES. <\/p>\n<p><strong>1.<\/strong> Separaci\u00f3n de la naturaleza (<span class='bible'>Gen 3:7<\/span>). Las cosas naturalmente inocentes y puras se contaminan con el pecado. La peor miseria que un hombre puede acarrearse a s\u00ed mismo por el pecado es que aquellas cosas que a las mentes puras no traen m\u00e1s que placer, se conviertan para \u00e9l en combustible para los malos deseos y pasiones, y enciendan las llamas del infierno dentro de su alma. <\/p>\n<p><strong>2.<\/strong> Separaci\u00f3n de Dios (<span class='bible'>Gn 3:8<\/span>). Que el esc\u00e9ptico disfrute de su alegr\u00eda. Para nosotros hay algo de lo m\u00e1s conmovedor en la afirmaci\u00f3n de que a nuestros primeros padres en la hora m\u00e1s sagrada de todo el d\u00eda la voz de Dios les parec\u00eda el trueno de la ira divina. Un ni\u00f1o podr\u00eda interpretar eso correctamente para s\u00ed mismo. Cuando ha hecho algo malo, tiene miedo, no se atreve a o\u00edr un sonido; un ruido com\u00fan, en la tr\u00e9mula inseguridad en que vive, le parece la voz del trueno de Dios. Para los ap\u00f3stoles el terremoto de Filipos fue una promesa de liberaci\u00f3n de la prisi\u00f3n; al carcelero pecador, cosa de juicio e ira: \u201cSe\u00f1ores, \u00bfqu\u00e9 debo hacer para ser salvo?\u201d <\/p>\n<p><strong>3.<\/strong> Ego\u00edsmo (<span class='bible'>G\u00e9n 3:12-13<\/span>). Los culpables est\u00e1n completamente ocupados con sus propios corazones; cada uno niega la culpa que le corresponde a cada uno; cada uno echa la culpa sobre el otro. El agricultor distingue entre dos tipos de ra\u00edces: las que penetran profundamente en la tierra sin dividirse y las que se dividen en interminables fibrillas y brotes. El ego\u00edsmo es como el \u00faltimo tipo; es la gran ra\u00edz del pecado de donde brotan otros: la falsedad, la cobard\u00eda, etc. <\/p>\n<p><strong><br \/>II.<\/strong> LAS CONSECUENCIAS PENALES. <\/p>\n<p><strong>1.<\/strong> Las infligidas al hombre. <\/p>\n<p><strong>(1)<\/strong> La tierra fue maldita por su causa (<span class='bible'>Gn 3:18- 19<\/span>). <\/p>\n<p><strong>(2)<\/strong> Muerte. <\/p>\n<p><strong>2.<\/strong> Los infligidos a la mujer. Con dolor iba a dar a luz hijos, y su deseo era ser para su marido, y \u00e9l la gobernar\u00eda. Esta pena de sufrir por los dem\u00e1s, que es el triunfo mismo de la Cruz, \u00bfno conocemos su bendici\u00f3n? No sabemos que en la medida en que sufrimos unos por otros amamos a ese otro; que en la medida en que la madre sufre por su hijo, ella es recompensada por ese amor? \u00bfNo sabemos que esa sujeci\u00f3n que el hombre llama restricci\u00f3n de la libertad es de hecho una concesi\u00f3n de la libertad, de esa libertad evang\u00e9lica que nace de la obediencia a una regla que los hombres veneran y aman? (<em>FW Robertson, MA<\/em>)<\/p>\n<\/p>\n<p><strong>Lecciones de la ca\u00edda<\/strong><\/p>\n<p><strong>1<\/strong><strong><em>.<\/em><\/strong><em> <\/em>Es profundamente significativo que esta narraci\u00f3n rastrea el primer pecado a un tentador externo. El mal no brota espont\u00e1neamente en el coraz\u00f3n no ca\u00eddo. El pecado no es, como algunos pretenden, un paso necesario en el desarrollo del hombre, ni brota de su propia naturaleza; es una importacion. <\/p>\n<p><strong>2.<\/strong> M\u00e1s all\u00e1 de lo que pueda ense\u00f1ar la forma de serpiente del tentador, podemos considerarlo con seguridad como una especie de par\u00e1bola de la naturaleza del mal. El reptil es un s\u00edmbolo tanto de la tentaci\u00f3n como del pecado. Sus colores, a veces brillantes, pero siempre extra\u00f1os; sus movimientos \u00e1giles e insinuantes; su huella viscosa, su salto repentino; su aguij\u00f3n tan delgado, y dejando un pinchazo tan diminuto, pero tan mortal; su veneno, que mata, no por laceraci\u00f3n espantosa, como en el desgarramiento de un le\u00f3n, sino por pasar la gota fatal a la misma sangre vital: todos estos puntos tienen sus paralelos en los acercamientos sinuosos, las fascinaciones horribles, las heridas inadvertidas, y el veneno fatal del pecado. Si volvemos a la historia, encontramos que se divide en tres partes. <\/p>\n<p><strong><br \/>I.<\/strong> LOS SUTILES APROXIMAMIENTOS DE LA TENTACI\u00d3N. N\u00f3tese que aqu\u00ed tenemos, sin embargo, una imagen de la forma en que se alej\u00f3 una naturaleza pura. El camino recorrido con uno que ya ha ca\u00eddo puede ser mucho m\u00e1s corto. Entonces no hay necesidad de enfoques elaborados y graduales, pero a menudo es suficiente para mostrar el anzuelo, y el coraz\u00f3n pecador se lanza sobre \u00e9l. Aqu\u00ed se debe tener m\u00e1s precauci\u00f3n. <\/p>\n<p><strong>1.<\/strong> Primero viene una pregunta aparentemente inocente, \u00ab\u00bfEs as\u00ed que Dios ha dicho: No comer\u00e9is?\u00bb El tentador bien podr\u00eda haber preguntado si el sol brillaba al mediod\u00eda. Enturbiar la clara luz del deber con la niebla de la duda es el comienzo de la ca\u00edda. Un pecado que salta con \u00edmpetu y con estruendo es menos peligroso que uno que se desliza sin darse cuenta. Cuando las restricciones de la ley comienzan a parecer duras y comenzamos a preguntarnos: \u00ab\u00bfEs realmente el caso que se nos proh\u00edben todas estas cosas sobre el seto all\u00ed?\u00bb la cu\u00f1a se ha introducido bastante. Cuidado con alterar las claras restricciones del deber reconocido, y de pensar que la duda puede ser admisible en cuanto a ellas. <\/p>\n<p><strong>2.<\/strong> El pr\u00f3ximo discurso del tentador se atreve m\u00e1s. El cuestionamiento da lugar a la afirmaci\u00f3n. Hay una mentira fiat, que el tentador sabe que es una mentira, para empezar. Hay una verdad en la afirmaci\u00f3n de que sus ojos se abrir\u00e1n para conocer el bien y el mal, aunque el conocimiento no ser\u00e1, como \u00e9l quiere que Eva crea, una bendici\u00f3n, sino una miseria. As\u00ed que su misma verdad es m\u00e1s una mentira que una verdad. Y hay una tercera mentira, peor que todas, en pintar el amor perfecto de Dios, que se deleita m\u00e1s en hacer a los hombres como \u00c9l, como en rega\u00f1arles un gozo, y guard\u00e1rselo para \u00c9l. En todos estos puntos tenemos aqu\u00ed un cuadro de los acercamientos del pecado a la voluntad d\u00f3cil. Es extra\u00f1o que trucos tan antiguos, y descubiertos con tanta frecuencia, a\u00fan tengan el poder de enga\u00f1arnos para nuestra ruina. Pero as\u00ed es, y miles de hombres y mujeres j\u00f3venes hoy est\u00e1n escuchando estas viejas mentiras gastadas como si fueran gloriosas verdades nuevas, \u00a1aptas para ser las estrellas polares de la vida! <\/p>\n<p><strong><br \/>II.<\/strong> EL HECHO FATAL. La avalancha abrumadora del apetito, que ciega toda consideraci\u00f3n excepto la gratificaci\u00f3n presente de los sentidos, se presenta maravillosamente en la breve narraci\u00f3n del pecado. Los motivos se exponen en toda su extensi\u00f3n. El \u00e1rbol era \u201cbueno para comer\u201d; ese es un sentido satisfecho. Era \u201cagradable a los ojos\u201d; ese es otro Si retenemos la traducci\u00f3n de las Versiones Autorizadas y Revisadas, era \u201cde desear hacerse sabio\u201d; que apelaba a un deseo m\u00e1s sutil. Pero la confluencia de todas estas corrientes hizo tal corriente que arras\u00f3 con la voluntad d\u00e9bil; y ciega, aturdida, ensordecida por el torrente de la corriente, Eva fue llevada sobre las cataratas, como lo ser\u00eda un hombre sobre el Ni\u00e1gara. Esta es la terrible experiencia de todos los que han cedido a la tentaci\u00f3n. Por un momento se olvidan todas las consecuencias, se silencian todas las obligaciones, se rompen todas las restricciones como cuerdas podridas. No importa lo que Dios haya dicho, no importa el mal que venga, no importa la conciencia o la raz\u00f3n; \u00a1que se vayan todos! El anhelo tir\u00e1nico que se ha apoderado del hombre lo apremia ciegamente. Todo lo que le importa es su propia satisfacci\u00f3n. Lo que de remordimiento o miseria pueda venir despu\u00e9s no es nada. <\/p>\n<p><strong><br \/>III.<\/strong> LAS TR\u00c1GICAS CONSECUENCIAS. Estos son dos: <\/p>\n<p><strong>(1)<\/strong> La designaci\u00f3n del trabajo como ley de vida; <\/p>\n<p><strong>(2)<\/strong> la pena de muerte f\u00edsica. <\/p>\n<p><strong>1.<\/strong> El cambio en el mundo f\u00edsico que sigui\u00f3 al pecado del hombre es una doctrina distinta tanto del Antiguo como del Nuevo Testamento, y est\u00e1 estrechamente relacionada con las profec\u00edas del futuro en ambos. . Aqu\u00ed aparece s\u00f3lo como implicando la necesidad de una vida de arduo conflicto con el suelo est\u00e9ril y lleno de malas hierbas. S\u00f3lo se contempla aqu\u00ed la vida sencilla del labrador, pero la ley establecida es amplia como el mundo. <\/p>\n<p><strong>2.<\/strong> La sentencia de muerte se repite en t\u00e9rminos inequ\u00edvocos. Las palabras significan la muerte f\u00edsica y nada m\u00e1s. Obs\u00e9rvese el significativo silencio sobre lo que ser\u00e1 de la otra parte del hombre. Las palabras claramente se refieren a <span class='bible'>Gn 2:7<\/span>, pero nada se dice ahora en cuanto al alma viviente. La maldici\u00f3n de la muerte est\u00e1 marcadamente limitada al cuerpo. El mismo silencio es un indicio velado de inmortalidad. <\/p>\n<p><strong>(1)<\/strong> Aprende que la muerte f\u00edsica es el resultado del pecado. Sin duda la vida animal tiende a la muerte; pero no se sigue que, si el hombre hubiera sido sin pecado, la tendencia hubiera sido tolerada para cumplirse. Sea como fuere, todo lo que conocemos como muerte, que contiene mucho m\u00e1s dolor y terror que el mero proceso f\u00edsico, es claramente el resultado del pecado. <\/p>\n<p><strong>(2)<\/strong> Aprenda, tambi\u00e9n, la analog\u00eda entre la muerte del cuerpo y la condici\u00f3n del esp\u00edritu que se entrega al pecado. La muerte es una par\u00e1bola, una imagen en el mundo material de lo que el pecado le hace al alma. La separaci\u00f3n de <\/p>\n<p>Dios es muerte. Cuando retira Su mano del cuerpo, \u00e9ste muere; cuando el alma se aparta de \u00c9l, muere. <\/p>\n<p><strong>3.<\/strong> Finalmente, la tentaci\u00f3n en el jard\u00edn nos recuerda la tentaci\u00f3n en el desierto. Cristo tuvo una tentaci\u00f3n m\u00e1s dolorosa que Ad\u00e1n. El uno no necesitaba nada; el otro estaba hambriento. El uno no ten\u00eda nada de terror o dolor pendiendo sobre \u00e9l, del cual escapar\u00eda rindi\u00e9ndose; el otro ten\u00eda Su elecci\u00f3n entre ganar Su reino por medio de la cruz y gobernar por el camino f\u00e1cil de tomar el mal por Su bien. El uno cay\u00f3 y, como ahora predican los cient\u00edficos m\u00e1s imp\u00edos, transmiti\u00f3 necesariamente una naturaleza depravada a su descendencia. El otro se mantuvo firme, venci\u00f3 y da de Su esp\u00edritu a todos los que conf\u00edan en \u00c9l. (<em>A. Maclaren, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Observaciones<\/strong><\/p>\n<p><strong><br \/> I.<\/strong> NING\u00daN ACTOR DE NING\u00daN PECADO PUEDE ESCAPAR AL DESCUBRIMIENTO DE DIOS. <\/p>\n<p><strong>1.<\/strong> \u00c9l es capaz de escudri\u00f1ar los secretos m\u00e1s profundos, viendo que todas las cosas est\u00e1n desnudas ante sus ojos (<span class='bible'>Hebreos 4:13<\/span>). <\/p>\n<p><strong>2.<\/strong> A \u00c9l le concierne hacerlo, para que el Juez de todo el mundo aparezca y se sepa que hace justicia, para lo cual necesariamente debe tener conocimiento distinto, tanto de los ofensores como de la calidad y medida de sus delitos, para que el juicio de cada uno sea proporcionado en n\u00famero, peso y medida, seg\u00fan sus hechos. <\/p>\n<p><strong><br \/>II.<\/strong> LOS PECADOS DE LOS HOMBRES DEBEN Y SER\u00c1N MANIFESTADOS EN LA MEDIDA QUE PUEDAN CONDUCIR AL AVANCE DE LA GLORIA DE DIOS. Que sea nuestro cuidado&#8211;<\/p>\n<p><strong>1.<\/strong> Cuidarnos de deshonrar a Dios al cometer cualquier pecado. <\/p>\n<p><strong>2.<\/strong> Si por flaqueza humana caemos en alg\u00fan pecado por el cual el nombre de Dios pueda ser blasfemado o menoscabado su honor, procuremos quitar la deshonra hecha a \u00c9l ech\u00e1ndonos toda la verg\u00fcenza sobre nosotros mismos. <\/p>\n<p><strong><br \/>III.<\/strong> EL CORAZ\u00d3N DE UN BUEN HOMBRE DEBE ESTAR PROFUNDA Y TERNAMENTE AFECTADO CON EL SENTIDO DEL PROPIO PECADO. Tal manera de afectar el coraz\u00f3n por el sentido del pecado&#8211;<\/p>\n<p><strong>1.<\/strong> Trae mucho honor a Dios. <\/p>\n<p><strong>2.<\/strong> Proclama nuestra propia inocencia (<span class='bible'>2Co 7:11<\/span>). <\/p>\n<p><strong>3.<\/strong> Mueve a Dios a la compasi\u00f3n hacia nosotros (<span class='bible'>Joe 2:17<\/span>).<\/p>\n<p><strong>4.<\/strong> Fomenta nuestra reforma. <\/p>\n<p><strong>5.<\/strong> Nos hace m\u00e1s atentos a nuestros caminos para el tiempo por venir. <\/p>\n<p><strong><br \/>IV.<\/strong> EL SEDUCIR, ESPECIALMENTE A LOS AMIGOS M\u00c1S CERCANOS, ES UNA FALTA, Y DEBE SER UN PECADO DESAGRADABLE. <\/p>\n<p><strong><br \/>V.<\/strong> EL PECADO Y SUS TENTACIONES SON PELIGROSOS ENGA\u00d1OS Y AS\u00cd SER\u00c1N AL \u00daLTIMO. Ahora bien, este enga\u00f1o del pecado es doble. En primer lugar, al proponer el mal bajo el nombre de bien, llamando a la luz tinieblas y a las tinieblas luz (<span class='bible'>Is 5,20<\/span>), o al menos a las sombras de bueno, en lugar de lo que es real y verdaderamente bueno, como el paso del bronce dorado por el oro perfecto. En segundo lugar, al proponernos una recompensa por el mal camino, que nunca encontraremos (ver <span class='bible'>Pro 1:13<\/span>; <span class=' biblia'>Pro 1:18<\/span>), ya que son justamente considerados enga\u00f1adores que prometen a los hombres en gran parte lo que nunca cumplen. (<em>J. White, MA<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gn 3,13-21 \u00bfQu\u00e9 es esto que has hecho? &#8212; Los resultados generales de la Ca\u00edda &gt;I. ETERNA ENEMIGO ENTRE SATAN\u00c1S Y LA HUMANIDAD (Gn 3,14). 1. Esta maldici\u00f3n fue pronunciada en referencia a Satan\u00e1s. 2. Este discurso es diferente al que se hizo a Ad\u00e1n y Eva. 3. Comenzar\u00eda una severa enemistad y conflicto entre &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-genesis-313-21-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de G\u00e9nesis 3:13-21 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-31765","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/31765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=31765"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/31765\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=31765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=31765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=31765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}