{"id":38451,"date":"2022-07-16T08:14:48","date_gmt":"2022-07-16T13:14:48","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-zacarias-105-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:14:48","modified_gmt":"2022-07-16T13:14:48","slug":"estudio-biblico-de-zacarias-105-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-zacarias-105-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Zacar\u00edas 10:5 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Zac 10:5<\/span><\/p>\n<p><em>Porque el Se\u00f1or est\u00e1 con ellos <\/em><\/p>\n<p><strong>Jehov\u00e1 con su pueblo<\/strong><\/p>\n<p>No hay nada que marque tan enf\u00e1ticamente y que describa tan indudablemente al pueblo del Dios vivo como Su propia presencia con ellos.<\/p>\n<\/p>\n<p><strong>1. <\/strong>El Se\u00f1or est\u00e1 relativamente con Su Iglesia. Es s\u00f3lo una tercera parte, y quiz\u00e1s una peque\u00f1a tercera parte. Podr\u00edamos dividir nuestra propia tierra en un tercio de enemigos declarados, un tercio de falsos profesantes y un tercio de verdaderos cristianos. S\u00f3lo la tercera parte son caracteres realmente espirituales, que tienen la bendici\u00f3n de la piedad vital. Estos permanecer\u00e1n; ser\u00e1n \u201cdejados\u201d. Dios est\u00e1 con ellos relativamente, es decir, est\u00e1 con ellos en pacto de uni\u00f3n eternamente.<\/p>\n<p><strong>2. <\/strong>El Se\u00f1or est\u00e1 con Su Iglesia de manera experimental. Dios siempre ha estado con Su Iglesia, como cuerpo, y con los miembros individuales.<\/p>\n<p><strong>3. <\/strong>El Se\u00f1or est\u00e1 con Su Iglesia perpetuamente. Es Su promesa, \u201cYo estar\u00e9 con vosotros todos los d\u00edas, hasta el fin del mundo.\u201d<\/p>\n<p>Considera c\u00f3mo este hecho de que Jehov\u00e1 est\u00e1 con Su pueblo, explica algunos misterios. \u201c<em>Porque<\/em> el Se\u00f1or est\u00e1 con<em> <\/em>ellos.\u201d<\/p>\n<p><strong>1. <\/strong>Luego luchar\u00e1n victoriosamente y con \u00e9xito. Esto explica por qu\u00e9 sus enemigos no pueden destruirlos.<\/p>\n<p><strong>2. <\/strong>Por eso mismo debe triunfar la verdad de Dios. Tenga en cuenta el car\u00e1cter distintivo de la Iglesia y su destino, como se establece en este texto. La Vida Divina es prenda de vida eterna. Dios sea contigo, tu religi\u00f3n es cosa de la vida. El s\u00ed y el am\u00e9n de Dios est\u00e1n estampados en Su pueblo. (<em>Joseph Irons.<\/em>)<\/p>\n<\/p>\n<p><strong>Victoria, unificaci\u00f3n y bienaventuranza para los buenos<\/strong><\/p>\n<p>Yo. <\/strong>Victoria. Esta victoria fue&#8211;<\/p>\n<p><strong>1. <\/strong>Completa. Los enemigos fueron pisoteados como \u201clodo en las calles\u201d.<\/p>\n<p><strong>2. <\/strong>Divino. \u201cPorque el Se\u00f1or est\u00e1 con ellos.\u201d<\/p>\n<p><strong>3. <\/strong>Revigorizante. \u201cFortalecer\u00e9 la casa de Jud\u00e1\u201d. Ser\u00edan fortalecidos por su victoria, no s\u00f3lo en riqueza y seguridad, sino tambi\u00e9n en coraje.<\/p>\n<p><strong>4. <\/strong>Amplia. \u201cY los de Efra\u00edn ser\u00e1n como un valiente, y su coraz\u00f3n se regocijar\u00e1 como por el vino: s\u00ed, sus hijos lo ver\u00e1n, y se alegrar\u00e1n; su coraz\u00f3n se regocijar\u00e1 en el Se\u00f1or.\u201d \u201cEl profeta\u201d, dice Hengstenberg, \u201cse ocup\u00f3 primero de Jud\u00e1, el centro del pueblo de Dios\u201d. En <span class='bible'>Zacar\u00edas 10:6<\/span> procede a hablar de Jud\u00e1 y Efra\u00edn juntos. En este vers\u00edculo, y en los que siguen, \u00e9l fija su atenci\u00f3n particularmente en Efra\u00edn, que en los d\u00edas del profeta parec\u00eda una rama seca que hab\u00eda sido cortada de la vid. Primero promete que los descendientes de los ciudadanos del antiguo reino de las diez tribus tambi\u00e9n tomar\u00e1n parte en el glorioso conflicto, y luego anuncia el regreso de las diez tribus de su exilio, que ser\u00eda la condici\u00f3n para participar en la batalla. . Ahora bien, todos estos hechos relacionados con esta victoria se aplican a esa victoria, la m\u00e1s grandiosa de todas: la victoria de todas las almas verdaderas sobre el error y la injusticia.<\/p>\n<p><strong><br \/>II. <\/strong>Unificaci\u00f3n. \u201cLos silbar\u00e9 y los juntar\u00e9\u201d, etc. Observe&#8211;<\/p>\n<p><strong>1. <\/strong>La facilidad con que se efectuar\u00e1 el triunfo de la reunificaci\u00f3n. \u201cVoy a silbar [o silbar] para ellos\u201d. Se entiende que la palabra se refiere a un silbido particular que usa el pastor para llamar a su reba\u00f1o disperso, o los que tienen el cuidado de las abejas, para traerlas a la colmena. \u201cAs\u00ed como las ovejas se juntan al conocido llamado del pastor, como las abejas siguen en enjambres la nota aguda del abejero, as\u00ed el Se\u00f1or, por Sus propios medios, debe reunir a Su pueblo disperso de sus dispersiones, por muy lejos que est\u00e9n, y traerlos a s\u00ed mismo y a su heredad.\u201d Con qu\u00e9 facilidad Dios hace Su obra; \u00a1una simple mirada, un soplo, una palabra!<\/p>\n<p><strong>2. <\/strong>Las regiones a las que se extender\u00e1 la reuni\u00f3n. \u201cY los sembrar\u00e9 entre los pueblos,\u201d\u2014o, como debe traducirse, \u201caunque los he esparcido entre las naciones,\u201d\u2014\u201cy se acordar\u00e1n de M\u00ed en pa\u00edses lejanos [regiones distantes]; vivir\u00e1n con sus hijos, y volver\u00e1n.\u201d Hab\u00edan sido esparcidos, no s\u00f3lo por Egipto y Asiria. No dice que todos los jud\u00edos regresar\u00e1n, pero implica una gran multitud.<\/p>\n<p><strong>3. <\/strong>El escenario en el que tendr\u00e1 lugar la reuni\u00f3n. \u201cTambi\u00e9n los har\u00e9 volver de la tierra de Egipto\u201d, etc.<\/p>\n<p><strong>4. <\/strong>Las cat\u00e1strofes nacionales que implicar\u00e1 el reencuentro. \u201cY \u00e9l pasar\u00e1 por el mar con aflicci\u00f3n, y herir\u00e1 las olas en el mar, y todas las profundidades del r\u00edo se secar\u00e1n\u201d. Evidentemente, aqu\u00ed hay una alusi\u00f3n a su primera liberaci\u00f3n de Egipto; y significa que algo similar a ese evento ocurrir\u00e1 en el curso de su reuni\u00f3n (ver <span class='bible'>Exo 24:4-14<\/span>) . \u201cY la soberbia de Asiria ser\u00e1 abatida, y el cetro de Egipto ser\u00e1 quitado\u201d. La idea probablemente sea que as\u00ed como \u201clas jactancias altivas de Senaquerib y el poder del cetro de Fara\u00f3n resultaron igualmente d\u00e9biles e in\u00fatiles contra el poder de Jehov\u00e1 en d\u00edas pasados, as\u00ed deber\u00eda resultar toda la oposici\u00f3n combinada de los enemigos m\u00e1s empedernidos en los d\u00edas venideros\u201d. . Delante de \u00c9l, cuando \u00c9l ten\u00eda un prop\u00f3sito que cumplir, o una promesa que cumplir a Su pueblo, todo orgullo deb\u00eda ser abatido, todo poder frustrado, todo consejo convertido en necedad\u201d. Ahora bien, hay una unificaci\u00f3n, de la cual esto no es m\u00e1s que un d\u00e9bil emblema: la unificaci\u00f3n del bien de todas las edades. \u201cVendr\u00e1n del oriente y del occidente, del norte y del sur, y se sentar\u00e1n con Isaac y con Jacob\u201d. \u00a1Qu\u00e9 uni\u00f3n tan bendita es esta!<\/p>\n<p><strong><br \/>III. <\/strong>Bendici\u00f3n. Aqu\u00ed est\u00e1 la fuerza m\u00e1s alta. \u201cY yo los fortalecer\u00e9 en el Se\u00f1or,\u201d<\/p>\n<p><strong>1. <\/strong>Ya sea que esto se refiera a su fuerza nacional, su seguridad en su propio pa\u00eds, o fuerza moral, &#8211; fuerza de fe en \u00c9l, &#8211; o todo, una cosa es clara, que ser fortalecidos en el Se\u00f1or es el mayor fuerza que podemos obtener. La mayor bendici\u00f3n de la vida es la fuerza: la fuerza f\u00edsica, para hacer con facilidad y para soportar con paciencia. Fuerza intelectual, fuerza para dominar con soltura todos los grandes problemas de la vida, y para llegar a una teor\u00eda del ser en la que el entendimiento pueda reposar libre de toda duda inquietante. Estas fortalezas son bendiciones; pero la fuerza moral, la fuerza para resistir el mal, para perseguir el bien, para servir al Dios Todopoderoso con aceptaci\u00f3n y para bendecir a la raza con influencias ben\u00e9ficas, esta es ciertamente la perfecci\u00f3n de nuestra bienaventuranza. \u201cFortal\u00e9cete en el Se\u00f1or, y en el poder de Su fuerza\u201d, dice Pablo. \u201c\u00c9l da fuerzas a los d\u00e9biles, ya los que no tienen fuerzas les da m\u00e1s fuerzas.\u201d<\/p>\n<p><strong>2. <\/strong>Aqu\u00ed est\u00e1 el ejercicio m\u00e1s elevado. \u201cAndar\u00e1n arriba y abajo en Su nombre, dice el Se\u00f1or.\u201d<\/p>\n<p><strong>(1)<\/strong> Todos los hombres vivos deben caminar por el camino que es \u201carriba y abajo\u201d. La vida humana se compone de \u201caltibajos\u201d; el camino no es liso ni llano, sino escabroso y monta\u00f1oso, a veces hacia arriba y a veces hacia abajo: arriba hoy y abajo ma\u00f1ana.<\/p>\n<p><strong>(2)<\/strong> Este camino solo puede ser recorrido felizmente por caminarlo en el \u201cnombre\u201d del Se\u00f1or. Un reconocimiento pr\u00e1ctico de Su presencia y de Sus derechos a nuestra suprema reverencia y adoraci\u00f3n. (<em>Homil\u00eda.<\/em>)<\/p>\n<\/p>\n<p><strong>Jud\u00e1 y Jos\u00e9<\/strong><\/p>\n<p>No puede haber duda de que la paulatina El desarrollo de los grandes principios de la Reforma ha llevado al correspondiente descubrimiento del deber y la obligaci\u00f3n de los cristianos hacia el antiguo pueblo de Dios. Pero nuestro inter\u00e9s en la cuesti\u00f3n jud\u00eda debe basarse en s\u00f3lidos principios b\u00edblicos. Si limitamos nuestra visi\u00f3n exclusivamente a las esperanzas que presenta la profec\u00eda incumplida, estaremos en peligro de permitirnos especulaciones inconsistentes con la historia del pasado e irreconciliables con el deber presente. Si limitamos la atenci\u00f3n al aspecto actual del pueblo jud\u00edo, con exclusi\u00f3n de la consideraci\u00f3n de la profec\u00eda, descendemos a la arena de la conveniencia pol\u00edtica. Los destinos del mundo est\u00e1n inseparablemente ligados al pueblo jud\u00edo. Al hacer cualquier esfuerzo por la evangelizaci\u00f3n del jud\u00edo, hay tres puntos que exigen atenci\u00f3n.<\/p>\n<p><strong><br \/>I. <\/strong>Las personas a las que dirigimos nuestros esfuerzos. En el texto tenemos una direcci\u00f3n a las dos grandes divisiones de la naci\u00f3n: Jud\u00e1 y Jos\u00e9 o Israel; y una bendici\u00f3n com\u00fan a ambos se asegura en virtud de la relaci\u00f3n de pacto en la que Dios se mantiene mutuamente. \u201cYo soy el Se\u00f1or su Dios\u201d, si podemos encontrar rastros de Jud\u00e1, y ninguno de Jos\u00e9, probablemente estos \u00faltimos est\u00e1n en reserva, y tarde o temprano entrar\u00e1n en el disfrute de la misericordia prometida. Se objeta que las palabras del texto se cumplieron con la restauraci\u00f3n de los jud\u00edos despu\u00e9s del cautiverio en Babilonia. Pero la profec\u00eda de Zacar\u00edas fue entregada al remanente que hab\u00eda regresado. Si Zacar\u00edas predice bendiciones m\u00e1s plenas que las que se hab\u00edan disfrutado hasta el per\u00edodo de la restauraci\u00f3n de Babilonia, \u00bfcu\u00e1ndo se disfrutaron? Si las dos divisiones o familias de Israel regresaron despu\u00e9s del cautiverio babil\u00f3nico, la distinci\u00f3n entre Jud\u00e1 y Efra\u00edn hab\u00eda terminado; y las condiciones del pacto nacional con Abraham, Isaac y Jacob, en lo que se refiere a la tierra, la ciudad y la posesi\u00f3n de la herencia, deben haberse cumplido. Pero los hechos del caso no se corresponden con ninguna de las disposiciones principales del pacto.<\/p>\n<p><strong>1. <\/strong>En lugar de un aumento, hubo una disminuci\u00f3n de la poblaci\u00f3n.<\/p>\n<p><strong>2. <\/strong>La extensi\u00f3n del territorio habitado por los jud\u00edos despu\u00e9s del cautiverio era a\u00fan m\u00e1s limitada que la que hab\u00eda sido repartida a las tribus por Josu\u00e9, y mucho menor que la prometida a Abraham.<\/p>\n<p><strong>3. <\/strong>Su pol\u00edtica civil no correspond\u00eda a la promesa (<span class='bible'>Eze 37:22-24<\/span>; <span class=' biblia'>Os 1:11<\/span>).<\/p>\n<p><strong>4. <\/strong>Si el regreso de Babilonia fue una restauraci\u00f3n, y los profetas hablan de una sola restauraci\u00f3n, entonces, \u00bfc\u00f3mo podemos explicar la declaraci\u00f3n completa en nuestro texto: \u00abSer\u00e1n como si no los hubiera desechado\u00bb? \u00bfD\u00f3nde est\u00e1n las mir\u00edadas de israelitas que en su escondite han existido y se han ido multiplicando, por lo que sabemos, desde los d\u00edas de Shahnaneser hasta ahora? El peque\u00f1o remanente que reside en estas partes occidentales del mundo solo puede considerarse como emigrantes de una naci\u00f3n vasta y poblada, cuya localidad a\u00fan es desconocida y no visitada por nosotros.<\/p>\n<p><strong><br \/>II . <\/strong>Los motivos para suponer que alg\u00fan \u00e9xito acompa\u00f1ar\u00e1 a nuestros esfuerzos. Podemos asumir que la naci\u00f3n de Israel no ha perdido su lugar en el prop\u00f3sito Divino. Aunque sea secreta y oscuramente para nosotros, los jud\u00edos ocupan una posici\u00f3n tan importante e influyente en referencia a otras naciones del mundo como en los d\u00edas de anta\u00f1o. Las fortunas de Israel siempre han estado ligadas a los destinos de las naciones; y no tenemos raz\u00f3n para suponer que esta regla universal de la administraci\u00f3n divina ha sido o ser\u00e1 apartada de ella. Los jud\u00edos han sido y son el \u00edndice de la profec\u00eda. Autentificamos la cronolog\u00eda y equilibramos la precisi\u00f3n hist\u00f3rica con referencia a este maravilloso pueblo. Si, bajo la dispensaci\u00f3n del Antiguo Testamento, los reinos de los gentiles realizaron su curso designado alrededor del centro visible de Israel, tambi\u00e9n debemos creer que bajo el Nuevo Testamento, que es un complemento del Antiguo, los imperios del mundo ahora est\u00e1n girando alrededor del mismo centro, aunque oscurecido e invisible.<\/p>\n<p><strong><br \/>III. <\/strong>El privilegio de participar en estos esfuerzos.<\/p>\n<p><strong>1. <\/strong>Es un privilegio tener la gracia de la fe y la oraci\u00f3n ejercida continuamente. El esfuerzo por el bien de Israel es una obra de fe de principio a fin. Ninguna ventaja temporal o internacional puede entrar en su consideraci\u00f3n; ning\u00fan motivo mundano o ego\u00edsta puede atribuirse a quienes se dedican a ello. El amigo de Israel camina por fe, no por vista. \u00a1Qu\u00e9 est\u00edmulo se presenta ahora en los resultados del trabajo para los jud\u00edos! Pero la misericordia para Israel es misericordia para el mundo. Dios ha declarado Su voluntad con respecto a \u201clos preciosos hijos de Si\u00f3n\u201d. Es un privilegio saber que la verdad de la Palabra de Dios es probada por Su fidelidad a Israel. Lo que se promete a los individuos se promete a la naci\u00f3n. Si las promesas (como <span class='bible'>Isa 24:1-23<\/span>; <span class='bible'>Isa\u00edas 25:1-12<\/span>; <span class='bible'>Isa\u00edas 26:1-21<\/span>.; Os 13:14; <span class='bible'>1 Cor 15:54<\/span>; <span class='bible'>Mat 23:39 <\/span>, etc.) no pertenecen a la naci\u00f3n, no nos pertenecen a nosotros. Ser\u00eda una extra\u00f1a inconsistencia para nosotros como gentiles emplear estos pasajes como fundamento de nuestra esperanza de una resurrecci\u00f3n, y negarlos a la naci\u00f3n jud\u00eda, que los ley\u00f3 literalmente como una promesa a sus padres (<span class='biblia'>Hechos 23:6<\/span>; <span class='bible'>Hechos 24:21<\/span>; <span class='bible'>Hechos 26:6-7<\/span>). \u00bfEsperamos el regreso de Cristo? Entonces reconciliemos la existencia contempor\u00e1nea de la Jerusal\u00e9n terrenal y celestial. Jes\u00fas, la luz de los gentiles, es la gloria de su pueblo Israel. La plenitud de los gentiles y la gloria de Israel fluir\u00e1n juntas. Como el estallido repentino de dos fuentes, unir\u00e1n sus corrientes vivas, y llenar\u00e1n hasta rebosar los canales preparados desde hace mucho tiempo, e inundar\u00e1n el universo con bendiciones, y el \u201cconocimiento de la gloria del Se\u00f1or cubrir\u00e1 la tierra como las aguas cubren la tierra\u201d. mar.\u00bb (<em>WR Fremantle, MA<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zac 10:5 Porque el Se\u00f1or est\u00e1 con ellos Jehov\u00e1 con su pueblo No hay nada que marque tan enf\u00e1ticamente y que describa tan indudablemente al pueblo del Dios vivo como Su propia presencia con ellos. 1. El Se\u00f1or est\u00e1 relativamente con Su Iglesia. Es s\u00f3lo una tercera parte, y quiz\u00e1s una peque\u00f1a tercera parte. Podr\u00edamos &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-zacarias-105-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Zacar\u00edas 10:5 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38451","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/38451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=38451"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/38451\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=38451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=38451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=38451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}