{"id":38650,"date":"2022-07-16T08:23:49","date_gmt":"2022-07-16T13:23:49","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-mateo-920-22-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:23:49","modified_gmt":"2022-07-16T13:23:49","slug":"estudio-biblico-de-mateo-920-22-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-mateo-920-22-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Mateo 9:20-22 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Mateo 9:20-22<\/span><\/p>\n<p> <em>Y toc\u00f3 el borde de su manto.<\/em><\/p>\n<\/p>\n<p><strong>Tocando a Jes\u00fas<\/strong><\/p>\n<p><strong><br \/>Yo. <\/strong>Cu\u00e1ntos males ha tra\u00eddo el pecado al mundo.<\/p>\n<p><strong><br \/>II. <\/strong>Estamos demasiado dispuestos a buscar ayuda humana en lugar de ir directamente a Dios.<\/p>\n<p><strong><br \/>III. <\/strong>Por profunda y desesperada que sea la condici\u00f3n de salud del alma, el Salvador puede ayudarnos.<\/p>\n<p><strong><br \/>IV. <\/strong>El secreto con el que la mujer afligida buscaba la ayuda de Jes\u00fas.<\/p>\n<p><strong><br \/>V. <\/strong>La impresi\u00f3n que la mujer sufriente se hab\u00eda formado de Jes\u00fas. (<em>JH Norton.<\/em>)<\/p>\n<\/p>\n<p><strong>Cristo el Sanador<\/strong><\/p>\n<p>El pecador y el Salvador.<\/p>\n<p><strong><br \/>Yo. <\/strong>La forma en que estos dos se juntan. Como decimos por casualidad esta mujer se cruza en su camino; fue un encargo del Hijo del Hombre.<\/p>\n<p><strong><br \/>II. <\/strong>La ocasi\u00f3n de su reuni\u00f3n. Es la incurabilidad de su enfermedad por la habilidad terrenal lo que la arroja sobre el M\u00e9dico celestial. El fracaso del hombre lo lleva a Uno que no puede fallar.<\/p>\n<p><strong><br \/>III. <\/strong>El punto de conexi\u00f3n entre ellos.<\/p>\n<p><strong><br \/>IV. <\/strong>La necesidad de la mujer de Cristo.<\/p>\n<p><strong><br \/>V. <\/strong>La necesidad de Cristo de la mujer. El sol necesita de la tierra tan verdaderamente como la tierra necesita del sol. Usted puede decir, \u00bfQu\u00e9 ser\u00eda de la tierra sin el sol? S\u00ed; pero \u00bfqu\u00e9 ser\u00eda del sol sin una tierra sobre la que brillar? \u00bfQu\u00e9 ser\u00eda de su resplandor? Todo desperdiciado. Brillar\u00eda en vano. As\u00ed que Cristo necesitaba objetos para el ejercicio de Su habilidad, amor y poder. El Se\u00f1or nos necesita.<\/p>\n<p><strong><br \/>VI. <\/strong>Los pensamientos de la mujer acerca de Cristo. Ella es modesta, seria, humilde; tan llena de fe que ella considera que un toque es suficiente. Como el jard\u00edn, \u00c9l no puede dejar de dar Su fragancia. La forma m\u00e1s simple de conexi\u00f3n con \u00c9l lograr\u00e1 la cura. (<em>A. Bonar, DD<\/em>)<\/p>\n<\/p>\n<p><strong>El acercamiento de la fe a Cristo<\/strong><\/p>\n<p><strong><br \/>I. <\/strong>La fe viene con una profunda desesperaci\u00f3n de toda otra ayuda excepto la de Cristo.<\/p>\n<p><strong><br \/>II. <\/strong>La fe tiene un poder divino para descubrir a Cristo.<\/p>\n<p><strong><br \/>III. <\/strong>La fe viene con una confianza impl\u00edcita en Cristo.<\/p>\n<p><strong><br \/>IV. <\/strong>La fe busca para su consuelo el contacto cercano con Cristo.<\/p>\n<p><strong><br \/>V. <\/strong>La fe, con todas sus imperfecciones, es aceptada por Cristo.<\/p>\n<p><strong><br \/>VI. <\/strong>La fe siente un cambio por el toque de Cristo. (<em>J. Ker, DD<\/em>)<\/p>\n<\/p>\n<p><strong>El paciente de muchos m\u00e9dicos<\/strong><\/p>\n<p><strong> <br \/>Yo. <\/strong>Uno que toca a muchos que presionan a Jes\u00fas. Hab\u00eda suficiente amor, poder y cercan\u00eda para toda la multitud, pero solo uno toc\u00f3 a Cristo para sanar. Estamos cerca de Cristo en la casa de Dios y en la santa mesa, pero tal vez no lo toquemos por fe.<\/p>\n<p><strong><br \/>II. <\/strong>Su caso es el peor de todos.<\/p>\n<p><strong>1. <\/strong>Ella es la m\u00e1s d\u00e9bil de toda la multitud, pero se esfuerza hasta llegar a Jes\u00fas. Nuestra incapacidad es una lecci\u00f3n necesaria, pero la seriedad es un poder. Por gracia somos salvos. Siempre hay una multitud entre Cristo y el alma inquisitiva: una multitud de pecados pasados, malos esp\u00edritus, etc.<\/p>\n<p><strong>2. <\/strong>Ella es la m\u00e1s vil de todas, la m\u00e1s inapropiada para tocar al Santo, porque su mismo toque contamina. Cristo es limpieza de los viles.<\/p>\n<p><strong>3. <\/strong>Su llegada es la peor de todas las aplicaciones; estaba fuera de temporada. Estaba en medio de otro caso. El que viene a destiempo no se niega.<\/p>\n<p><strong>4. <\/strong>Su llegada parece ser de la peor manera; ning\u00fan otro parece haber venido tan enfermo. Viene sigilosamente.<\/p>\n<p><strong><br \/>III. <\/strong>Su curaci\u00f3n inmediata.<\/p>\n<p><strong>1. <\/strong>Su venida para ser sanada es tard\u00eda, pero inmediata; tarde en referencia al pasado, inmediato en la prisa de esta tarde. La raz\u00f3n humillante, porque ella ha gastado todo. El pecador no viene a Cristo primero, sino despu\u00e9s de que todos los dem\u00e1s refugios han fallado.<\/p>\n<p><strong>2. <\/strong>Su curaci\u00f3n es inmediata, completa, consciente.<\/p>\n<p><strong>3. <\/strong>No puede partir sana sin confesar a Cristo Sanador. El acu\u00f1ador no necesita, pero el seguidor debe llevar la cruz de Cristo; es m\u00e1s ligero de soportar despu\u00e9s. (<em>AM Stuart.<\/em>)<\/p>\n<\/p>\n<p><strong>El asunto de la sangre san\u00f3<\/strong><\/p>\n<p><strong><br \/>Yo. <\/strong>La condici\u00f3n de la mujer, y el tacto, y el cubo.<\/p>\n<p><strong>1. <\/strong>Su condici\u00f3n representa la de todo pecador.<\/p>\n<p><strong>(1)<\/strong> Enferma.<\/p>\n<p><strong>(2)<\/strong> Inmunda y separado de la comuni\u00f3n de dios y su pueblo.<\/p>\n<p><strong>(3)<\/strong> Sin esperanza de recibir ayuda de los m\u00e9dicos terrenales.<\/p>\n<p><strong>2. <\/strong>Diferencia entre su toque y el de la multitud.<\/p>\n<p><strong>3. <\/strong>Su fe exitosa, aunque imperfecta y mezclada con error.<\/p>\n<p><strong><br \/>II. <\/strong>\u00bfPor qu\u00e9 Jes\u00fas no dej\u00f3 a la mujer en el escondrijo que buscaba?<\/p>\n<p><strong>1. <\/strong>Para que ella pueda confesar y glorificar a Cristo ante los dem\u00e1s.<\/p>\n<p><strong>2. <\/strong>Para que \u00c9l la confiese y confirme su fe, y le confiera mayores y mayores bendiciones.<\/p>\n<p><strong>(1)<\/strong> \u00c9l la confiesa.<\/p>\n<p><strong>(2)<\/strong> \u00c9l aprueba y confirma su fe.<\/p>\n<p><strong>3. <\/strong>Agrega una bendici\u00f3n m\u00e1s espiritual: \u201cVe en paz\u201d. Esta es una palabra de poder. (<em>TM Macdonald, MA<\/em>)<\/p>\n<\/p>\n<p><strong>El verdadero sanador lo intent\u00f3 por \u00faltima vez<\/strong><\/p>\n<p>No era lo mismo lucha vista en el caso de Lutero, dando tambi\u00e9n como resultado el mismo resultado? Esa celda en Erfurth escuch\u00f3 sonidos y vio im\u00e1genes de conflicto y dolor lo suficiente como para hacer sangrar nuestros corazones. \u00a1Qu\u00e9 l\u00e1grimas derram\u00f3 ese monje, qu\u00e9 oraciones ofreci\u00f3, qu\u00e9 laceraciones infligi\u00f3 en su carne para ahuyentar sus deseos, qu\u00e9 hambre soport\u00f3 para poder someter sus apetitos al hambre, hasta que casi mata el cuerpo al tratar de matar sus pecados, \u00a1y fue encontrado una y otra vez casi sin vida en el suelo! Pero \u00bfqu\u00e9 hay de sus pecados? Eran tan vigorosos como siempre. Acosados por muchos m\u00e9dicos, no cedieron; el flagelo, el hambre, la sed, las vigilias nocturnas, todo fall\u00f3; y hab\u00eda gastado casi todo lo que ten\u00eda, y estaba \u00abnada mejor, sino m\u00e1s bien peor\u00bb. Casi todo, digo, porque a\u00fan le quedaba un poco. Un m\u00e9dico m\u00e1s que no hab\u00eda probado, y esa era la ciudad eterna de Roma, que deb\u00eda ver; y all\u00ed, en medio de sus santidades y milagros, debe y una curaci\u00f3n perfecta. Debe subir sobre sus rodillas desnudas las maravillosas escaleras de la Santa Scala, y all\u00ed la carga rodar\u00e1 de su alma para siempre. Pero la carga aprieta m\u00e1s a medida que sube; y en el momento de su m\u00e1s negra desesperaci\u00f3n, un texto recordado resuena en sus o\u00eddos como m\u00fasica desde la puerta del cielo: \u00abEl justo por la fe vivir\u00e1\u00bb, y sale corriendo de la escena regocij\u00e1ndose en Cristo Jes\u00fas, y sin confiar en la carne. As\u00ed es que los hombres deben desesperarse antes de poder tener esperanza. (<em>E. Mellor, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Una fe imperfecta no es un obst\u00e1culo para la cura moral<\/strong><\/p>\n<p> El sol puede enviar algo de su luz y calor a trav\u00e9s de cielos muy turbios, y el Sol de Justicia puede hacer lo mismo, e incluso m\u00e1s. (<em>E. Mellor, DD<\/em>)<\/p>\n<\/p>\n<p>Puede haber mucha basura terrenal en el alma que viene a Cristo; pero si hay en ella un grano reluciente del oro de la fe, Cristo recibir\u00e1 esa alma con toda su basura; porque \u00c9l sabe bien que a su debido tiempo todo lo que es in\u00fatil desaparecer\u00e1, que el ojo de la fe barrer\u00e1 un horizonte m\u00e1s vasto de verdad de d\u00eda en d\u00eda, hasta que seamos luz en el Se\u00f1or y no andemos en tinieblas. (<em>E. Mellor, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Curaci\u00f3n moral buscada por deseo ego\u00edsta<\/strong><\/p>\n<p>La mayor\u00eda de la religi\u00f3n de la humanidad comienza en lo que puede verse como ego\u00edsmo, y luego se transforma en amor. \u00bfLa mayor parte de la religi\u00f3n dije? Podr\u00eda haber dicho, la vida natural de cada uno de nosotros desde la ni\u00f1ez ha seguido la misma ley. \u00bfD\u00f3nde est\u00e1 el ni\u00f1o que comenz\u00f3 la vida con amor? La vida comienza con el hambre y otras necesidades. El infante es un haz de imperiosas y constantes necesidades. No ama a nadie, no puede amar a nadie. El amor hay que engendrarlo, despertarlo poco a poco a medida que transcurren los meses, y el ni\u00f1o en expansi\u00f3n aprende qui\u00e9n es el que lo alimenta y lo acaricia, de qui\u00e9n son los brazos que lo envuelven, de qui\u00e9n es el rostro que refleja en \u00e9l el mismo luz del cielo. \u00bfPuede haber algo m\u00e1s ego\u00edsta que los llantos del ni\u00f1o que busca alimento y consuelo, sin importarle de qui\u00e9n vienen si vienen? Pero, \u00bfpuede algo ser m\u00e1s desinteresado que el amor que finalmente surge en el alma? Un amor que hace del nombre de madre el nombre m\u00e1s dulce y querido de la tierra; un amor que atravesar\u00e1 mares y no se enfriar\u00e1 con la distancia, y que siente que no son demasiadas las l\u00e1grimas que se derraman sobre la tumba donde descansa en paz. No podemos <em>comenzar nuestra <\/em>vida cristiana en el punto m\u00e1s alto, o con los motivos m\u00e1s altos, como tampoco nuestra vida natural. (<em>E. Mellor, DD <\/em>)<\/p>\n<\/p>\n<p><strong>La idea de la mujer al tocar el dobladillo<\/strong><\/p>\n<p>La Las nociones que la mujer ten\u00eda de Cristo eran muy confusas. Era t\u00edmida y encogida, una mujer probablemente de un temperamento sensible, su sistema nervioso posiblemente da\u00f1ado por su enfermedad; pero s\u00f3lo la ignorancia y la superstici\u00f3n podr\u00edan haber sugerido la idea de un toque furtivo de las vestiduras de nuestro Se\u00f1or. (<em>H. Allen, DD<\/em>)<\/p>\n<\/p>\n<p><strong>El sentido ayuda a la fe<\/strong><\/p>\n<p>Algunos instrumentos para conectar la fe de nuestras almas en Cristo la necesitamos todos, quiz\u00e1s. Sin ella, la fe incluso de los m\u00e1s fuertes podr\u00eda tener dificultades para realizar a Cristo. El sentido es el ministro del alma. Nos aferramos mejor a Cristo cuando la mano de la fe espiritual descansa sobre las cosas sensibles; s\u00f3lo asegur\u00e9monos de que es el Cristo que capta nuestro esp\u00edritu, y no la mera cosa sensible. (<em>H. Allen, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Figuras de bronce en Cesarea de Filipo<\/strong><\/p>\n<p>Esta mujer era natural de Cesarea. A las puertas de su casa, sobre una piedra elevada, se encuentra una imagen de bronce de una mujer sobre su rodilla vendada, con las manos extendidas ante ella, como quien suplica. Frente a esta hay otra imagen de un hombre erguido, de los mismos materiales, decorosamente vestido con un manto, y tendiendo la mano a la mujer. Ante sus pies, y sobre el mismo pedestal, crece cierta planta extra\u00f1a, que, alz\u00e1ndose hasta el borde del manto de bronce, es una especie de ant\u00eddoto contra toda clase de enfermedades. Esta figura es una estatua de Jesucristo, y ha permanecido hasta nuestros d\u00edas, de modo que nosotros mismos la vimos mientras est\u00e1bamos en esa ciudad. (<em>Eusebio.<\/em>)<\/p>\n<\/p>\n<p><strong>Curar inmediatamente<\/strong><\/p>\n<p>La mujer no tuvo que pasar por un tedioso proceso , pero se cur\u00f3 de inmediato. Los m\u00e9dicos requieren tiempo y deben utilizar los medios adecuados. Te hacen un m\u00e9dico y te hacen dieta, y as\u00ed te curan gradualmente. El Redentor nunca fisicaliz\u00f3 ni hizo dieta a Sus pacientes. Los cur\u00f3 enseguida. (<em>JC Jones.<\/em>)<\/p>\n<\/p>\n<p>La cura fue perfecta, no mejor, pero completa, hasta el \u00faltimo \u00e1pice. Todos los rastros de la enfermedad desaparecieron. Completo-perfecto. (<em>JC Jones.<\/em>)<\/p>\n<\/p>\n<p><strong>La fe de los enemigos de Cristo<\/strong><\/p>\n<p>\u00bfPuedes decir por qu\u00e9 la aguja tiembla al polo? \u00bfLos capullos se abren paso a tientas hacia la primavera? Flores a la luz del sol? Est\u00e1n hechos para ella, y las almas est\u00e1n hechas as\u00ed para Cristo. (<em>Dr. J. Ker.<\/em>)<\/p>\n<\/p>\n<p><strong>\u201cSi me permite:\u201d<\/strong><\/p>\n<p>Yo. <\/strong>\u201csi puedo\u201d se permite.<\/p>\n<p><strong>1. <\/strong>No hay nada que proh\u00edba que vengas y descanses tu alma culpable en Cristo.<\/p>\n<p><strong>2. <\/strong>La naturaleza misma del Se\u00f1or Jesucristo debe prohibir que plantees dudas acerca de que se te permita acercarte y tocar el borde de su manto.<\/p>\n<p><strong>3. <\/strong>Piense en la plenitud del poder de Cristo para salvar y haga un peque\u00f1o argumento al respecto.<\/p>\n<p><strong>4. <\/strong>Supongamos que vienes, no le har\u00e1s da\u00f1o.<\/p>\n<p><strong>5. <\/strong>Preferir\u00e1s beneficiarlo que da\u00f1arlo.<\/p>\n<p><strong>6. <\/strong>Otros como t\u00fa se han aventurado a \u00c9l, y no han sido rechazados.<\/p>\n<p><strong><br \/>II. <\/strong>\u00bfPero puedo? La fe en Cristo es la acci\u00f3n m\u00e1s simple que cualquiera pueda realizar.<\/p>\n<p><strong><br \/>III. <\/strong>\u201cSer\u00e9 sanado\u201d. (<em>CH Spurgeon.<\/em>)<\/p>\n<\/p>\n<p><strong>Timidez confiada<\/strong><\/p>\n<p><strong><br \/>I . <\/strong>Discretamente.<\/p>\n<p><strong>1. <\/strong>\u201cDijo dentro de s\u00ed misma\u201d, etc.<\/p>\n<p><strong>2. <\/strong>Vino detr\u00e1s de Cristo.<\/p>\n<p><strong><br \/>II. <\/strong>Sin ceremonias.<\/p>\n<p><strong>1. <\/strong>Vino cuando Cristo estaba comprometido.<\/p>\n<p><strong>2. <\/strong>Toc\u00f3 Su dobladillo.<\/p>\n<p><strong><br \/>III. <\/strong>Sin duda. \u201cSer\u00e9 completo\u201d. Su fe era indudable, por lo tanto fuerte para vencer las dificultades.<\/p>\n<p><strong>1. <\/strong>Dificultad subjetiva.<\/p>\n<p><strong>2. <\/strong>Dificultad del objetivo.<\/p>\n<p><strong>3. <\/strong>Indudables, por lo tanto, fuertes para obtener bendiciones de Cristo. (<em>JS Swan.<\/em>)<\/p>\n<\/p>\n<p><strong>La fe en sus manifestaciones<\/strong><\/p>\n<p>Podemos considerar el acto de esta mujer como expresi\u00f3n de su fe.<\/p>\n<p><strong>1. <\/strong>La fe es una cosa simple como un acto. Lo ejercita cuando consulta a su m\u00e9dico. En la experiencia religiosa los actos de fe son simples, pero detr\u00e1s de ellos hay un estado mental, misterioso y sublime.<\/p>\n<p><strong>2. <\/strong>Una gran fe es compatible con una gran modestia. Puede haber mucha fe ante Dios, pero temor ante los hombres.<\/p>\n<p><strong>3. <\/strong>Una gran fe es compatible con una gran ignorancia.<\/p>\n<p><strong>4. <\/strong>La fe salva y luego se convierte en incentivo para la santidad. (<em>FCPolton, DD<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mateo 9:20-22 Y toc\u00f3 el borde de su manto. Tocando a Jes\u00fas Yo. Cu\u00e1ntos males ha tra\u00eddo el pecado al mundo. II. Estamos demasiado dispuestos a buscar ayuda humana en lugar de ir directamente a Dios. III. Por profunda y desesperada que sea la condici\u00f3n de salud del alma, el Salvador puede ayudarnos. IV. El &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-mateo-920-22-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Mateo 9:20-22 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38650","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/38650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=38650"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/38650\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=38650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=38650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=38650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}