{"id":38764,"date":"2022-07-16T08:28:56","date_gmt":"2022-07-16T13:28:56","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-mateo-1513-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:28:56","modified_gmt":"2022-07-16T13:28:56","slug":"estudio-biblico-de-mateo-1513-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-mateo-1513-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Mateo 15:13 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Mat 15:13<\/span><\/p>\n<p><em>Toda planta, que mi Padre celestial no plant\u00f3, ser\u00e1n desarraigadas.<\/em><\/p>\n<\/p>\n<p><strong>Las plantas que Dios no plant\u00f3<\/strong><\/p>\n<p> 1. <\/strong>Qu\u00e9 se entiende por plantas.<\/p>\n<p><strong>(a) <\/strong>Toda doctrina:<\/p>\n<p><strong>(b) <\/strong>Toda pr\u00e1ctica: <\/p>\n<p><strong>(c) <\/strong>Toda persona.<\/p>\n<p><strong>2. <\/strong>Algunas plantas que Dios nunca plant\u00f3.<\/p>\n<p><strong>(a) <\/strong>\u00bfQu\u00e9 significa plantar? Plantar es colocar o poner cosas en el suelo, como \u00e1rboles, hierbas, flores. As\u00ed que la plantaci\u00f3n m\u00edstica denota el trasplante (de una manera espiritual) de tal o cual persona, de un curso de blasfemia abierta a una profesi\u00f3n visible.<\/p>\n<p><strong>(b) <\/strong>Qui\u00e9n es el que planta personas en la Iglesia del evangelio? Dios, y los ministros del evangelio.<\/p>\n<p><strong>3. <\/strong>Ejecute un paralelo entre una plantaci\u00f3n externa; y una plantaci\u00f3n espiritual.<\/p>\n<p><strong>(a) <\/strong>Un plantador, como alguien instruido en el misterio de ese arte, tiene sabidur\u00eda y habilidad para plantar que otros no tienen; as\u00ed que un ministro de Cristo es aquel a quien Dios le ha ense\u00f1ado los misterios del evangelio.<\/p>\n<p><strong>(b) <\/strong>Un plantador debe tener un llamamiento del due\u00f1o de la vi\u00f1a; por lo tanto, todo ministro debe ser llamado y autorizado regularmente.<\/p>\n<p><strong>(c) <\/strong>Un plantador debe tener instrumentos aptos y apropiados para su trabajo.<\/p>\n<p><strong>( d) <\/strong>Un plantador no sabe infaliblemente la diferencia que hay en las plantas.<\/p>\n<p><strong>(e) <\/strong>Un plantador h\u00e1bil sabe que un \u00e1rbol salvaje e ingrato nunca da buenos frutos .<\/p>\n<p><strong>(f) <\/strong>Un plantador observa la temporada adecuada para plantar.<\/p>\n<p><strong>(g) <\/strong>\u00c9l no s\u00f3lo planta, sino que sino agua.<\/p>\n<p><strong>(h) <\/strong>Se regocija mucho al ver sus plantas crecer, prosperar y dar mucho fruto.<\/p>\n<p>En cuanto a las plantas.<\/p>\n<p><strong>(a) <\/strong>Deben estar bien enraizadas.<\/p>\n<p><strong>(b) <\/strong>Deben podarse y purgarse.<\/p>\n<p><strong>(c) <\/strong>Algunas plantas, que promet\u00edan bien, resultan est\u00e9riles y no sirven para nada.<\/p>\n<p><strong>(d) <\/strong>Las plantas que resultan totalmente est\u00e9riles, son arrancar o talar.<\/p>\n<p><strong>4. <\/strong>\u00bfPor qu\u00e9 toda planta que Dios no plant\u00f3 ser\u00e1 desarraigada?<\/p>\n<p><strong>(a) <\/strong>Porque son plantas silvestres.<\/p>\n<p><strong>( b) <\/strong>Porque todas las plantas que Dios no ha plantado, no tienen derecho a ser plantadas en su vi\u00f1a.<\/p>\n<p><strong>(c) <\/strong>Porque estorban la tierra. <\/p>\n<p><strong>(d) <\/strong>Porque no sirven para nada m\u00e1s que para el fuego.<\/p>\n<p>Las plantas que Dios mismo plant\u00f3 permanecer\u00e1n y nunca ser\u00e1n arrancadas.<\/p>\n<p><strong>(a) <\/strong>Porque est\u00e1n destinados a dar fruto:<\/p>\n<p><strong>(b) <\/strong>Son plantados en Cristo:<\/p>\n<p><strong>(c) <\/strong>El amor de Dios por ellos es eterno e inmutable. (<em>B. Keach.<\/em>)<\/p>\n<\/p>\n<p><strong>Sobre la eficacia del Evangelio en la extirpaci\u00f3n del error<\/strong><\/p>\n<p><strong><br \/>Yo. <\/strong>\u00bfHasta qu\u00e9 punto se ha cumplido ya esta declaraci\u00f3n prof\u00e9tica?<\/p>\n<p><strong><br \/>II. <\/strong>Hay ciertas circunstancias que han impedido el progreso del cristianismo y suspendido su influencia moral y santificadora.<\/p>\n<p><strong><br \/>III. <\/strong>Tenemos razones para creer que el resultado final del reino evang\u00e9lico ser\u00e1 ciertamente muy glorioso, y que la predicci\u00f3n del texto entonces se cumplir\u00e1, en un sentido hasta ahora desconocido para el mundo. (<em>Habakkuk Crabbe.<\/em>)<\/p>\n<\/p>\n<p><strong>Desarraigar las plantas<\/strong><\/p>\n<p><strong><br \/> YO. <\/strong>Que es la propia mano del Padre celestial la que planta toda planta que debe crecer y prosperar.<\/p>\n<p><strong><br \/>II. <\/strong>Que toda planta que sea plantada por cualquier otra mano o poder, no prosperar\u00e1, sino que ser\u00e1 desarraigada.<\/p>\n<p><strong><br \/>III. <\/strong>Que los que no ven las cosas as\u00ed, y no pueden dejarlas a Dios, se traen sobre s\u00ed mismos muchos problemas e inquietudes. (<em>John Webster.<\/em>)<\/p>\n<\/p>\n<p><strong>Reglas de conducta dif\u00edciles y cuestionables<\/strong><\/p>\n<p>Cuando hablamos de principios y reglas de vida, que todos conocen y todos creen, por los cuales se rigen los j\u00f3venes y los viejos, los eruditos y los ignorantes, el pr\u00edncipe y el trabajador, y estos principios y reglas de vida son falsos, o s\u00f3lo cierto en parte, el da\u00f1o que de ah\u00ed se deriva es incalculable, es inmenso. Estas son \u201cplantas que el Padre celestial no plant\u00f3\u201d.<\/p>\n<p><strong><br \/>I. <\/strong>La mayor\u00eda de los hombres opinan que no podemos pasar un d\u00eda sin pecar y actuar malvadamente.<\/p>\n<p><strong><br \/>II. <\/strong>Pensamos que no podemos ser perfectos; y con esto excusamos no pocas veces todos los pecados y errores que cometemos, por diversos y graves que sean.<\/p>\n<p><strong><br \/>III. <\/strong>Sostenemos que debemos disfrutar alegremente de la vida, en particular de la juventud, que pasa tan r\u00e1pidamente; no debemos amargarlo con una gravedad intempestiva, con penas o cuidados innecesarios. Esto puede ser cierto, pero las consecuencias que de ello se derivan con referencia a la virtud y la religi\u00f3n son falsas.<\/p>\n<p><strong><br \/>IV. <\/strong>Nosotros decimos, Somos despu\u00e9s de todo, seres d\u00e9biles y corruptos por naturaleza, de quienes no se puede esperar mucho, y a quienes Dios, en Su misericordia, no juzgar\u00e1 con rigor.<\/p>\n<p><strong> <br \/>V. <\/strong>Nosotros decimos, No debemos ser particulares; no debemos aspirar a ser m\u00e1s sabios y mejores que los dem\u00e1s. Debemos regularnos por las personas y las sociedades, en las que y con las que vivimos.<\/p>\n<p><strong><br \/>VI. <\/strong>Tenemos falsas concepciones acerca del arrepentimiento diario. Con qu\u00e9 frecuencia o\u00edmos decir: \u201cSi peco todos los d\u00edas, sin embargo, me arrepiento todos los d\u00edas, y en todo caso debemos arrepentirnos todos los d\u00edas\u201d. VIII. Se imagina que cierta devoci\u00f3n, o m\u00e1s bien, ciertos actos de culto divino pueden suplir el defecto de una vida virtuosa, o expiar la vida desordenada que llevamos y los pecados que cometemos. O,<\/p>\n<p><strong><br \/>VIII.<\/strong> Confiamos en la gracia divina, y por ella esperamos ser salvos, aunque no somos tan virtuosos y santos como deber\u00edamos ser. (<em>Zollikoper.<\/em>)<\/p>\n<\/p>\n<p><strong>El deshierbe del jard\u00edn<\/strong><\/p>\n<p><strong><br \/>Yo. <\/strong>Plantas que Dios no plant\u00f3.<\/p>\n<p><strong>1. <\/strong>Algunos han sido plantados por la mano del ministro. Algunas conversiones son de origen humano, no divino.<\/p>\n<p><strong>2. <\/strong>Algunos fueron plantados por sus padres y madres. Tienen una especie de religi\u00f3n familiar.<\/p>\n<p><strong>3. <\/strong>Muchos profesores de religi\u00f3n son autoimpuestos.<\/p>\n<p><strong><br \/>II. <\/strong>Su desarraigo. A veces viene en esta vida.<\/p>\n<p><strong><br \/>III. <\/strong>El trabajo de autoexamen. \u00bfSoy una planta plantada por Dios?<\/p>\n<p><strong>1. <\/strong>Si soy del plant\u00edo del Se\u00f1or, hubo un tiempo en que tuve que ser sacado del lugar donde una vez crec\u00ed.<\/p>\n<p><strong>2. <\/strong>Si plantados por Dios habr\u00e1 tristeza de que alguna vez fu\u00e9ramos otra cosa.<\/p>\n<p><strong>3. <\/strong>Hemos aprendido nuestra total impotencia.<\/p>\n<p><strong>4. <\/strong>Todos estamos plantados en un suelo y, de hecho, en una roca. (<em>CH Spurgeon.<\/em>)<\/p>\n<\/p>\n<p><strong>Las plantas de Dios crecen en todas partes<\/strong><\/p>\n<p>Otras plantas que el \u201cCelestial Padre no plant\u00f3\u201d tienen sus zonas de vegetaci\u00f3n, y mueren fuera de ciertos grados de latitud, pero la semilla del reino es como el ma\u00edz, un lugar ex\u00f3tico en ninguna parte, porque dondequiera que viva el hombre crecer\u00e1, y sin embargo ex\u00f3tico en todas partes, porque descendi\u00f3 del cielo. (<em>Dr. Maclaren.<\/em>)<\/p>\n<\/p>\n<p><strong>Las plantas no plantadas por Dios son muy hermosas<\/strong><\/p>\n<p>Si <em> <\/em>vas al campo, hay muchas plantas que crecen all\u00ed que son tan bonitas como las del jard\u00edn. Mira la dedalera y el rosal silvestre; mira muchas de las flores por las que pasamos como insignificantes, son realmente hermosas; pero no son plantas que hayan sido plantadas jam\u00e1s. Ahora, cu\u00e1ntos tenemos en nuestras congregaciones que son realmente hermosos; sin embargo, no son hombres y mujeres plantados por Dios cuyo car\u00e1cter sea recto, cuyos modales sean amables, cuya vida sea irreprochable. No son inmorales, ni enga\u00f1an ni mienten; pero son ejemplares; su disposici\u00f3n es amable, tierna y afectuosa. S\u00ed, pero debe haber algo m\u00e1s que esto, porque Jes\u00fas dice: \u201cToda planta que no plant\u00f3 mi Padre celestial, ser\u00e1 desarraigada\u201d. Aunque sea una hermosa planta, aunque parezca ser una hermosa flor externamente, sin embargo, dado que su ra\u00edz ha succionado su alimento de los desiertos salvajes del pecado, ya sea de infidelidad o de iniquidad, es mala a los ojos de Dios. , y debe ser arrancado. (<em>CH Spurgeon.<\/em>)<\/p>\n<\/p>\n<p><strong>Plantas silvestres fruct\u00edferas<\/strong><\/p>\n<p>Adem\u00e1s, \u00bfcu\u00e1ntas hay de nuestras plantas silvestres de madera que incluso dan fruto. El escolar en el campo puede decirnos que el bosque es un huerto, y que a menudo ha tenido muchas comidas deliciosas con las frutas silvestres que crec\u00edan all\u00ed. Sin embargo, f\u00edjense bien, aunque las aves puedan venir y saciar su hambre con esos frutos silvestres, y aunque las semillas puedan ser en el invierno el granero del gorri\u00f3n y el almac\u00e9n del pardillo, sin embargo, no est\u00e1n plantadas, y no caen bajo la tierra. descripci\u00f3n del texto-plantas que se han plantado. As\u00ed tambi\u00e9n, puede haber algunos de ustedes que realmente hagan algo bueno en el mundo. Sin ti, las necesidades de una madre podr\u00edan no ser satisfechas; de tu mesa se alimentan muchos de los pobres. \u00a1Vaya! esto es bueno, esto es bueno; Me gustar\u00eda que todos ustedes hicieran m\u00e1s, pero les ruego que recuerden que esto no es suficiente; debe haber una plantaci\u00f3n de Dios en ti, o de lo contrario los frutos que produzcas ser\u00e1n frutos ego\u00edstas. Ser\u00e9is como Israel que fue denunciado como una vid vac\u00eda, porque, en verdad, dio fruto para s\u00ed mismo. La caridad es buena. \u00a1Noble caridad, s\u00e9 honrada entre los hombres! Pero debe haber fe, y si no tenemos fe en Cristo, aunque demos nuestros cuerpos para ser quemados, y entreguemos nuestros bienes para alimentar a los pobres, donde est\u00e1 Cristo, ciertamente nunca podremos ir. (<em>CH Spurgeon.<\/em>)<\/p>\n<\/p>\n<p><strong>Muchas de esas plantas silvestres tienen ra\u00edces muy fuertes<\/strong><\/p>\n<p>Si Si tuviera que ir y tratar de desenterrarlos, tendr\u00eda una tarea delante de usted que no ser\u00eda f\u00e1cil de realizar. Mira el muelle salvaje: \u00bfbuscaste levantarlo? Pedazo tras pedazo se desprende, y tienes que hundir profundamente en la tierra alg\u00fan instrumento afilado antes de que puedas arrancarlo de ra\u00edz, e incluso entonces, si queda s\u00f3lo un pedazo, brota y prospera de nuevo. \u00a1Oh, cu\u00e1ntos hay que tienen tanta tenacidad de vida en su falsa confianza, como la hay en el banquillo\u2014en su ra\u00edz! Algunos de ustedes no pueden temblar. \u201cNunca tengo una duda\u201d, dijo uno, \u201cnunca tuve una duda o un recelo\u201d. Recuerde que Robert Hall dijo: \u00abPerm\u00edtame dudar por usted, se\u00f1or\u00bb, porque sab\u00eda que el hombre era un enfermo del h\u00edgado. Y as\u00ed tenemos algunos: no est\u00e1n en problemas como los otros hombres, ni son azotados como los otros hombres; hablan con aire de satisfacci\u00f3n: su lenguaje suena a seguridad, pero es presunci\u00f3n; parece confianza en Cristo, pero es confianza en s\u00ed mismos. Y los tales echar\u00e1n ra\u00edces muy profundas, y ser\u00e1n verdaderamente muy fuertes, de modo que no los podr\u00e9is sacudir; sin embargo, \u00a1ay de ellos! no son plantas plantadas a la diestra del Se\u00f1or, y por lo tanto se dicta la sentencia; y antes de que pase mucho tiempo ser\u00e1 ejecutado sin piedad: \u201cser\u00e1n desarraigados\u201d. (<em>CH Spurgeon.<\/em>)<\/p>\n<\/p>\n<p><strong>Plantas arrancadas<\/strong><\/p>\n<p><strong>1. <\/strong>Ese sistema de filosof\u00eda que ignora la Verdad Divina, o contradice las claras declaraciones de la Palabra de Dios, no puede perdurar.<\/p>\n<p><strong>2. <\/strong>En los diversos departamentos de la ciencia, aquellos puntos de vista que son fruto de conceptos err\u00f3neos flagrantes o de hip\u00f3tesis inciertas, necesariamente poseen el elemento de caducidad.<\/p>\n<p><strong>3. <\/strong>Se puede aplicar un curso de razonamiento similar a las diferentes religiones del mundo. Considera algunas de las plantas que plant\u00f3 el Padre:-<\/p>\n<p><strong>1. <\/strong>Cada disc\u00edpulo de Cristo.<\/p>\n<p><strong>2. <\/strong>La Iglesia.<\/p>\n<p><strong>3. <\/strong>La Biblia.<\/p>\n<p><strong>4. <\/strong>En el jard\u00edn hay tambi\u00e9n muchas plantitas tiernas que, aunque no llaman la atenci\u00f3n, son igualmente objeto de la solicitud del Padre.<\/p>\n<p><strong>5. <\/strong>Dios se comprometi\u00f3 a establecer el bien ya erradicar el mal. La rosa no siempre tendr\u00e1 su espina. (<em>JT Lamont.<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mat 15:13 Toda planta, que mi Padre celestial no plant\u00f3, ser\u00e1n desarraigadas. Las plantas que Dios no plant\u00f3 1. Qu\u00e9 se entiende por plantas. (a) Toda doctrina: (b) Toda pr\u00e1ctica: (c) Toda persona. 2. Algunas plantas que Dios nunca plant\u00f3. (a) \u00bfQu\u00e9 significa plantar? Plantar es colocar o poner cosas en el suelo, como \u00e1rboles, &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-mateo-1513-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Mateo 15:13 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38764","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/38764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=38764"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/38764\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=38764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=38764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=38764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}