{"id":38771,"date":"2022-07-16T08:29:14","date_gmt":"2022-07-16T13:29:14","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-mateo-161-5-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:29:14","modified_gmt":"2022-07-16T13:29:14","slug":"estudio-biblico-de-mateo-161-5-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-mateo-161-5-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Mateo 16:1-5 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Mateo 16:1-5<\/span><\/p>\n<p> <em>Oh hip\u00f3critas, pod\u00e9is discernir la faz del cielo.<\/em><\/p>\n<p><em> <\/em><\/p>\n<p><strong>Se\u00f1ales de los tiempos<\/strong><\/p>\n<p>La correcta observancia de estos signos. Son celestiales y, por lo tanto, deben verse en un coraz\u00f3n que busca las cosas espirituales.<\/p>\n<p><strong>1. <\/strong>La se\u00f1al del d\u00eda. Otro d\u00eda se ha ido. El d\u00eda del Se\u00f1or est\u00e1 m\u00e1s cerca. \u00bfEstoy mejor preparado para ello?<\/p>\n<p><strong>2. <\/strong>La se\u00f1al de la cruz de su Salvador. \u00bfHa crucificado todo mal afecto?<\/p>\n<p><strong>3. <\/strong>La se\u00f1al del ejemplo de su Salvador.<\/p>\n<p><strong>4. <\/strong>Las se\u00f1ales de los tiempos en que est\u00e1 viviendo, y considera c\u00f3mo son los presagios del \u00faltimo d\u00eda, y c\u00f3mo debe comportarse en consecuencia.<\/p>\n<p><strong>5. <\/strong>Y la pregunta con el hombre de Dios es, \u00bfqu\u00e9 presagian estas se\u00f1ales? \u00bfPrueban que ha avanzado en el derrotero cristiano? Entonces los cielos se ti\u00f1en de rojo con alegres signos para el ma\u00f1ana.<\/p>\n<p><strong>6. <\/strong>El rojo del cielo de la tarde puede enga\u00f1ar, como todos sabemos; estos signos nunca pueden.<\/p>\n<p><strong>7. <\/strong>Todo lo que presagian las se\u00f1ales del cielo, no lo podemos alterar; pero podemos alterar aquello que est\u00e1 amenazado por las se\u00f1ales del mundo espiritual.<\/p>\n<p><strong>8. <\/strong>El verdadero cristiano observar\u00e1 las se\u00f1ales de la ma\u00f1ana al levantarse como si fuera de la muerte a la vida otra vez, y se preparar\u00e1 para el d\u00eda venidero. \u00bfEst\u00e1 rojo y abatido con las tormentas de prueba y tentaci\u00f3n que se avecinan? entonces se preparar\u00e1 para enfrentarlo.<\/p>\n<p><strong>9. <\/strong>El cristiano no desea m\u00e1s se\u00f1ales del cielo. Cuanto m\u00e1s vigilante es, m\u00e1s descubre que ya lo ha hecho, y m\u00e1s evidentes y ciertos son. El \u00faltimo ha sido dado, el Hijo del hombre ha resucitado de entre los muertos.<\/p>\n<p><strong>10. <\/strong>La Escritura est\u00e1 llena de exhortaciones a la vigilancia cristiana.<\/p>\n<p><strong>11. <\/strong>La reprensi\u00f3n que nuestro Se\u00f1or administr\u00f3 a estos buscadores de se\u00f1ales de mente mundana: \u00abY \u00e9l los dej\u00f3 y se fue\u00bb. (<em>RW Evades, BD<\/em>)<\/p>\n<\/p>\n<p><strong>Se\u00f1ales<\/strong><\/p>\n<p>Las cosas que les suceden a las naciones y a los hombres son, en el sentido m\u00e1s propio de la palabra, \u201cse\u00f1ales del cielo\u201d del gobierno divino y su consejo.<\/p>\n<p><strong><br \/>I. <\/strong>Signos personales para instrucci\u00f3n de cada hombre, ense\u00f1a a cada uno, bajo su propio peligro, a no despreciar las profec\u00edas. Leemos en la diligencia, la bondad moral del muchacho, la naturaleza y la historia del hombre venidero. Decimos: \u201cHar\u00e1 buen tiempo\u201d. Estas son se\u00f1ales del cielo. En familiar, cuando brilla la tarde, la ma\u00f1ana est\u00e1 bien; donde hay afecto y piedad, pronosticamos \u201cbuen tiempo\u201d. Eres una se\u00f1al del cielo, si no perdonas, una se\u00f1al de tormenta que se avecina.<\/p>\n<p><strong><br \/>II. <\/strong>Los signos populares siempre tienen el n\u00famero y la fuerza suficientes para darnos una idea del car\u00e1cter del futuro. La vida, la predicaci\u00f3n del Bautista era un signo de cambio inminente. El car\u00e1cter de nuestro Se\u00f1or fue una se\u00f1al del cuidado de Dios por Sus hijos. (<em>B. Kent.<\/em>)<\/p>\n<\/p>\n<p><strong>Injusticia en el tratamiento de la religi\u00f3n<\/strong><\/p>\n<p>Es una humillante hecho de que hombres sensatos traten los grandes hechos de la religi\u00f3n de una manera que, en cualquier otro aspecto de la investigaci\u00f3n humana, se reconocer\u00eda como il\u00f3gico o absurdo.<\/p>\n<p><strong><br \/>I. <\/strong>Tome un ejemplo de la historia registrada, los hombres tratan a Jesucristo con un escepticismo que no hacen con Napole\u00f3n Bonaparte.<\/p>\n<p><strong><br \/>II. <\/strong>Toma ciencia. El cristianismo es una ciencia tan verdaderamente como la qu\u00edmica. Sus hechos fundamentales est\u00e1n determinados por miles de experimentos. Pero cu\u00e1ntos aceptan el testimonio de los cient\u00edficos y rechazan el de los religiosos. La verdadera religi\u00f3n tiene sus dificultades, \u00bfpero la ciencia tiene menos?<\/p>\n<p><strong><br \/>III. <\/strong>Respecto a la biblia. En los asuntos temporales los hombres investigan lo que se relaciona con su seguridad; pero cuando est\u00e1 en juego la seguridad eterna, los hombres no dan tiempo a su consideraci\u00f3n.<\/p>\n<p><strong><br \/>IV. <\/strong>Al igual que con el Libro de Dios, tambi\u00e9n con los testigos de Dios. En un tribunal de justicia los hombres aceptan la evidencia, pero luchan contra ella en la religi\u00f3n. Los hombres no rechazan los billetes de banco porque algunos sean falsificados; pero rechazan el cristianismo por causa de un falso profesante.<\/p>\n<p><strong><br \/>V. <\/strong>Solo en las matem\u00e1ticas puras los hombres insisten en la certeza matem\u00e1tica. Toda la conducta de la vida se basa en una preponderancia de probabilidades. Sobre este principio aran y plantan, compran y construyen, trabajan y esperan. \u00bfEs probable que todos los frutos generosos y nobles est\u00e9n basados en la superstici\u00f3n?<\/p>\n<p><strong><br \/>VI. <\/strong>Cuando de dos formas de proceder una es absolutamente segura y la otra llena de peligros, todos los hombres eligen el camino de la seguridad. Es seguro ser cristiano; sin embargo, la seguridad es rechazada. Que un hombre sea honesto, se haga justicia y le d\u00e9 al cristianismo un juego limpio. (<em>PS Henson, DD<\/em>)<\/p>\n<\/p>\n<p><strong>La demanda de la incredulidad<\/strong><\/p>\n<p>Esta demanda de los jud\u00edos era-<\/p>\n<p><strong><br \/>I. <\/strong>Impulsado por motivos equivocados-\u201cy tentador\u201d. Esta fue una tentaci\u00f3n de dos filos.<\/p>\n<p><strong>1. <\/strong>Supongamos que no debe dar la se\u00f1al, ya sea por rechazo o por fracaso. Entonces esperaban destruir Su influencia e impresionar a la gente de que \u00e9l era un falso Mes\u00edas.<\/p>\n<p><strong>2. <\/strong>Pero si hubiera obrado un milagro, habr\u00eda cedido a sus bajas ideas de su Mesianismo y de su evidencia. Los escribas y los fariseos eran enemigos ac\u00e9rrimos entre s\u00ed, pero se combinaron para derrocar a Cristo: y qu\u00e9 gran parte de la investigaci\u00f3n religiosa moderna se debe a la enemistad y el ego\u00edsmo de los corazones humanos. La discusi\u00f3n con frecuencia est\u00e1 dise\u00f1ada no para arreglar sino para perturbar la fe. Hay hombres que hablan plausiblemente y con aparente sinceridad sobre estos asuntos, quienes en sus corazones estar\u00edan complacidos por la destrucci\u00f3n del cristianismo. Una vez m\u00e1s, hay hombres que usan temas evang\u00e9licos como teatro sobre el cual desplegar su poder intelectual. Exigen pruebas ni posibles ni razonables. Esto es diferente del humilde buscador que, caminando en la oscuridad, pregunta por el camino de la luz y de la vida.<\/p>\n<p><strong><br \/>II. <\/strong>Esta demanda era presuntuosa: \u00abDesde el cielo\u00bb. Limitaron a Cristo en cuanto al m\u00e9todo en el que \u00c9l deber\u00eda mostrar Su divinidad. Hay personas que determinan en su propia mente la forma en que Dios se revelar\u00e1; la verdad debe fluir a trav\u00e9s de los canales que han cavado, o la rechazar\u00e1n.<\/p>\n<p><strong><br \/>III. <\/strong>Esta demanda se debi\u00f3 a su ciega incredulidad. Se negaron a reconocer la fuerza de la evidencia que ya se les hab\u00eda dado (<span class='bible'>Mat 11:5<\/span>). Los hombres vituperan contra la Biblia que nunca la leyeron. Claman por agua y se niegan a sacarla de las abundantes fuentes de salvaci\u00f3n que los rodean.<\/p>\n<p><strong><br \/>IV. <\/strong>Esta petici\u00f3n llev\u00f3 a su deserci\u00f3n por parte de Cristo. El esp\u00edritu manifestado por estos jud\u00edos demostr\u00f3 que era in\u00fatil permanecer m\u00e1s tiempo con ellos.<\/p>\n<p><strong>1. <\/strong>\u00c9l les neg\u00f3 m\u00e1s manifestaciones de Su poder: \u00abNo se dar\u00e1 ninguna se\u00f1al\u00bb.<\/p>\n<p><strong>2. <\/strong>Cristo se apart\u00f3 de ellos. Esto lo hizo<\/p>\n<p><strong>(1)<\/strong> con tristeza;<\/p>\n<p><strong>(2)<\/strong> pronto;<\/p>\n<p><strong> &gt;(3)<\/strong> Finalmente. Este incidente parece haber cerrado Su ministerio en Galilea. (<em>WH Williams.<\/em>)<\/p>\n<\/p>\n<p><strong>Las se\u00f1ales de los tiempos<\/strong><\/p>\n<p><strong><br \/>Yo. <\/strong>Algunos de los signos de los tiempos. Cada \u00e9poca tiene sus peculiares desarrollos-signos. Vivimos en una \u00e9poca que est\u00e1 repleta de estos indicadores morales, y al son de ellos llamamos la atenci\u00f3n.<\/p>\n<p><strong>1. <\/strong>La difusi\u00f3n casi universal del conocimiento es uno de los signos de los tiempos.<\/p>\n<p><strong>2. <\/strong>El alcance de sus nuevos descubrimientos e inventos.<\/p>\n<p><strong>3. <\/strong>El poder creciente y la posici\u00f3n de mando de la raza anglosajona.<\/p>\n<p><strong>4 <\/strong>La decadencia y disoluci\u00f3n inminente de los gobiernos paganos.<\/p>\n<p><strong> &gt;<br \/>II. <\/strong>\u00bfQu\u00e9 indican estos signos? Estas se\u00f1ales indican claramente el r\u00e1pido progreso del reino del Mes\u00edas.<\/p>\n<p><strong><br \/>III. <\/strong>\u00bfCu\u00e1l es nuestro deber ante estos signos de los tiempos?<\/p>\n<p><strong>1. <\/strong>Con raz\u00f3n para discernirlas.<\/p>\n<p><strong>2. <\/strong>Buscar una entrada en el reino de Cristo sin demora.<\/p>\n<p><strong>3. <\/strong>Trabajad y orad por su llegada con mayor poder y gloria. (<em>PM Brett, DD<\/em>)<\/p>\n<\/p>\n<p>Demasiados signos de los tiempos nos rodean por todos lados para que sea correcto, sabio o seguro. o felices de pasar desapercibidos.<\/p>\n<p><strong><br \/>I. <\/strong>Procuremos comprender claramente qu\u00e9 se entiende por signo. Puede ser milagroso o moral.<\/p>\n<p><strong><br \/>II. <\/strong>\u00bfCu\u00e1les fueron en particular aquellas se\u00f1ales que nuestro se\u00f1or reprendi\u00f3 a los fariseos y saduceos por no haberlas observado?<\/p>\n<p><strong><br \/>III. <\/strong>Pregunte si el orden de las cosas en la profec\u00eda en comparaci\u00f3n con el aspecto de nuestros propios tiempos no puede brindarnos alguna instrucci\u00f3n. Es un deber cristiano discernir los signos, vigilar el aspecto moral de los tiempos en que vivimos. As\u00ed aprenderemos m\u00e1s sobre las intenciones y el <em>car\u00e1cter<\/em> del Ser Divino. (<em>JP Dunn.<\/em>)<\/p>\n<\/p>\n<p><strong>Ideas humanas y divinas de la revelaci\u00f3n<\/strong><\/p>\n<p><strong><br \/>I. <\/strong>El humano. Desde tiempos remotos los hombres han exigido una \u201cse\u00f1al del cielo\u201d.<\/p>\n<p><strong><br \/>II. <\/strong>La idea divina de una revelaci\u00f3n.<\/p>\n<p><strong>1. <\/strong>El ateo dice: \u201cSi hay un Dios, que se manifieste\u201d. Cu\u00e1n silenciosa, pero majestuosamente, en la tierra y en el cielo se est\u00e1 revelando Dios.<\/p>\n<p><strong>2. <\/strong>Los jud\u00edos exigieron a Jes\u00fas una se\u00f1al. Sin embargo, hizo \u201cprodigios y se\u00f1ales\u201d entre ellos.<\/p>\n<p><strong>3. <\/strong>Dios se revela en las palabras de los profetas y evangelistas.<\/p>\n<p><strong><br \/>III. <\/strong>El contraste en las dos ideas de la revelaci\u00f3n.<\/p>\n<p><strong>1. <\/strong>La revelaci\u00f3n del hombre debe dirigirse a sus sentidos, a su imaginaci\u00f3n, y al despliegue maravilloso, algo irregular, terrible; Dios se revela s\u00f3lo a lo <em>espiritual, es decir, <\/em>a lo m\u00e1s profundo del hombre.<\/p>\n<p><strong>2. <\/strong>Las revelaciones de Dios llegan a la experiencia de los hombres. (<em>Dr. Chase.<\/em>)<\/p>\n<\/p>\n<p><strong>Los obst\u00e1culos a Su obra por la Iglesia<\/strong><\/p>\n<p>Es es necesario tener en cuenta el car\u00e1cter de la mente a la que tiene que dirigirse, as\u00ed como la naturaleza de la verdad que tiene que decir. \u00a1Cu\u00e1n r\u00e1pido, extenso y radical fue el cambio durante el \u00faltimo medio siglo! \u00bfHasta qu\u00e9 punto este nuevo esp\u00edritu est\u00e1 frenando el progreso de la verdad, y de qu\u00e9 manera podemos enfrentarlo?<\/p>\n<p><strong><br \/>I. <\/strong>Algunas de las tendencias intelectuales que act\u00faan contra la fe. La ciencia del d\u00eda. El esp\u00edritu inquieto que engendra. La incertidumbre con respecto a las grandes verdades del cristianismo se considera una justificaci\u00f3n de la neutralidad. La influencia de esta tendencia generalizada es claramente hostil a la aceptaci\u00f3n del evangelio ya la cultura de la piedad vital. El escepticismo est\u00e1 en el aire, y hay quienes deben estar a la moda del momento. Nuestras congregaciones est\u00e1n llenas de este sentimiento. \u00a1Dios no permita que nos desesperemos o que incluso miremos dubitativos hacia el futuro! Pero nos corresponde a nosotros cuidar que nuestro trabajo se haga sabiamente, bien y verdaderamente. El evangelio todav\u00eda tiene un poder que se afirmar\u00e1 a s\u00ed mismo.<\/p>\n<p><strong><br \/>II. <\/strong>Algunos indicios sobre el modo en que los cristianos deben hacer frente a estas dificultades.<\/p>\n<p><strong>1. <\/strong>No para que nos sentemos a lamentarnos por los males, como si fueran irreparables.<\/p>\n<p><strong>2. <\/strong>Una pol\u00edtica de supresi\u00f3n nunca ha tenido \u00e9xito, y mucho menos es probable que tenga \u00e9xito en una \u00e9poca emocionada con toda la energ\u00eda de la vida, y fuerte hasta la vehemencia en la afirmaci\u00f3n de su propia independencia y libertad. No deber\u00eda tener \u00e9xito. Los protestantes, de todos los hombres, no pueden tener satisfacci\u00f3n en la contemplaci\u00f3n de lo que ser\u00eda una mera fantas\u00eda de una fe viva. La libertad debe tener su obra perfecta, y una verdadera fe no tendr\u00e1 miedo a las consecuencias.<\/p>\n<p><strong>3. <\/strong>El verdadero modo de tratar con la mente esc\u00e9ptica de la \u00e9poca es detenerse en puntos de acuerdo en lugar de diferencia. La ciencia a\u00fan no ha aquietado el anhelo del coraz\u00f3n por Dios, y no ha podido satisfacerlo. (<em>JG Rogers, BS<\/em>)<\/p>\n<\/p>\n<p><strong>Los signos de los tiempos<\/strong><\/p>\n<p>Las peculiaridades m\u00e1s llamativas de la \u00e9poca actual.<\/p>\n<p><strong><br \/>I. <\/strong>El gran aumento del esfuerzo mental. Algunos per\u00edodos han estado marcados por la inacci\u00f3n intelectual e incluso por el retroceso. Tal fue aquel per\u00edodo en que, tras la decadencia de la filosof\u00eda plat\u00f3nica, Arist\u00f3teles rein\u00f3 en todas las escuelas y fue idolatrado como \u201cel secretario de la naturaleza que moja la pluma en el intelecto\u201d. Desde esa \u00e9poca se han producido los mayores avances en todos los campos de la ciencia, m\u00e1s especialmente durante el \u00faltimo siglo, etc.<\/p>\n<p><strong><br \/>II. <\/strong>Una mayor atenci\u00f3n a la instrucci\u00f3n de las clases bajas.<\/p>\n<p><strong><br \/>III. <\/strong>El estado mejorado de la predicaci\u00f3n, y la provisi\u00f3n m\u00e1s abundante de los medios p\u00fablicos de gracia. En nuestro propio pa\u00eds y en otros.<\/p>\n<p><strong><br \/>IV. <\/strong>El avance de la Biblia como el gran y \u00fanico est\u00e1ndar de la fe y la pr\u00e1ctica cristianas.<\/p>\n<p><strong><br \/>V. <\/strong>La creciente armon\u00eda que prevalece entre los aut\u00e9nticos disc\u00edpulos de Jesucristo.<\/p>\n<p><strong><br \/>VI. <\/strong>La extensi\u00f3n de la libertad civil y religiosa. (<em>Robert Hall, AM<\/em>)<\/p>\n<\/p>\n<p><strong>Las se\u00f1ales de los tiempos<\/strong><\/p>\n<p><strong><br \/>I. <\/strong>La naturaleza de estos signos que deben ser considerados como indicaciones designadas del futuro.<\/p>\n<p><strong><br \/>II. <\/strong>Los signos que presentan los tiempos actuales, con los deberes que sugieren.<\/p>\n<p><strong>1. <\/strong>Esp\u00edritu de investigaci\u00f3n.<\/p>\n<p><strong>2. <\/strong>Esp\u00edritu de empresa activa.<\/p>\n<p><strong>3. <\/strong>Cuid\u00e9monos de que la emoci\u00f3n de los acontecimientos pasajeros no desv\u00ede nuestra atenci\u00f3n de nuestra propia prosperidad espiritual. (<em>J. West.<\/em>)<\/p>\n<\/p>\n<p><strong>Se describe la astucia del malvado para atrapar al pueblo de Dios<\/strong><\/p>\n<p>Yo. <\/strong>La exigencia de un signo.<\/p>\n<p><strong>1. <\/strong>Observar los eficientes o causas de ello- Fariseos y Saduceos.<\/p>\n<p><strong>2. <\/strong>El fin por el cual la desearon, y fue para tentarlo.<\/p>\n<p><strong><br \/>II. <\/strong>El rechazo de nuestro salvador a esta demanda.<\/p>\n<p><strong>1. <\/strong>La reprensi\u00f3n que les da a ellos ya sus personas.<\/p>\n<p><strong>2. <\/strong>La base de su reprensi\u00f3n hacia ellos, y esa es una convicci\u00f3n de su disposici\u00f3n a creer cosas m\u00e1s inciertas sobre un terreno menos cre\u00edble de lo que creer\u00edan que \u00c9l es el Mes\u00edas enviado de Dios sobre los terrenos m\u00e1s ciertos y evidentes. (<em>John Cotton.<\/em>)<\/p>\n<\/p>\n<p><strong>Buen tiempo, porque el cielo est\u00e1 rojo<\/strong><\/p>\n<p>Un palestino pron\u00f3stico, que puede o no ser aplicable a otros pa\u00edses. El Salvador, al referirse a \u00e9l, no pretende ponerle un sello de aprobaci\u00f3n cient\u00edfica. Fue suficiente para Su prop\u00f3sito que el pron\u00f3stico fuera aceptado por los sabios del tiempo en Palestina. Sin duda, al menos como regla general, ser\u00eda un pron\u00f3stico verdadero; pues indicaba, suponemos, que en la regi\u00f3n contigua de la atm\u00f3sfera en la que descend\u00eda o hab\u00eda descendido el sol al ponerse, no hab\u00eda una densa acumulaci\u00f3n de nubes que amenazaran con una tormenta de lluvia venidera. Si hubiera habido tales nubes, el resplandor dorado del sol habr\u00eda sido absorbido e interceptado, y por lo tanto no habr\u00eda habido enrojecimiento del cielo vespertino. (<em>J. Morison, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Signos<\/strong><\/p>\n<p>Los<em> <\/em>\u00a1Los hijos de este mundo son en su generaci\u00f3n m\u00e1s sabios que los hijos de la luz! \u00a1A todas las cosas que conciernen a sus intereses temporales, cu\u00e1n intensamente est\u00e1n vivos los hombres! Meditar\u00e1n, observar\u00e1n, inferir\u00e1n y actuar\u00e1n sobre sus inferencias. El agricultor observa cuidadosamente las pr\u00f3ximas alteraciones del tiempo; el pol\u00edtico observa la corriente del sentimiento popular y los estados de \u00e1nimo de los hombres; el investigador cient\u00edfico dedica todas sus energ\u00edas a la observaci\u00f3n de los hechos que le permitir\u00e1n arrancarle a la naturaleza sus secretos; el especulador est\u00e1 constantemente a la expectativa de los primeros s\u00edntomas de una alteraci\u00f3n en los precios. Sin embargo, \u00a1cu\u00e1n a menudo estos mismos hombres se niegan a interesarse por el m\u00e1s elevado de todos los temas, la relaci\u00f3n de Dios con el hombre, alegando que es demasiado vago e incierto para una consideraci\u00f3n pr\u00e1ctica! Exigen que esto se les presente mediante alguna prueba externa visible que sea imposible de disputar antes de que reconozcan sus derechos sobre ellos. Est\u00e1n ciegos a los signos que est\u00e1n siempre a su alrededor y dentro de ellos, y que exigen por lo menos tanto inter\u00e9s e investigaci\u00f3n como los signos del mundo exterior que absorben su atenci\u00f3n. (<em>VW Hutton, MA<\/em>)<\/p>\n<\/p>\n<p><strong>Las se\u00f1ales de los tiempos<\/strong><\/p>\n<p><strong><br \/>I. <\/strong>La dificultad de satisfacer a personas impracticables.<\/p>\n<p><strong><br \/>II. <\/strong>Los peligros de una sagacidad medio educada.<\/p>\n<p><strong><br \/>III. <\/strong>La exigencia del cristianismo de ser juzgado por una amplia inducci\u00f3n de hechos. (<em>G\u00e9rmenes del p\u00falpito.<\/em>)<\/p>\n<\/p>\n<p><strong>Cambios en la opini\u00f3n teol\u00f3gica un signo de los tiempos; no hay que temer<\/strong><\/p>\n<p>\u00bfPor qu\u00e9 mis multitudinarios \u00e1rboles arrojaron sus hojas el oto\u00f1o pasado? \u00bfEra el hecho de que los arrojaran fuera una se\u00f1al de que se estaban muriendo? No arrojaron una sola hoja hasta que tuvieron una hoja peque\u00f1a envuelta y colocada a lo largo de la rama. Se despojaron de las vestiduras del a\u00f1o pasado, y hoy se est\u00e1n poniendo las vestiduras de este a\u00f1o. Entonces, con respecto a ellos, el cambio era crecimiento y preparaci\u00f3n para el crecimiento. \u00bfPor qu\u00e9 muere el grano de trigo? Si un esc\u00e9ptico moderno, despu\u00e9s de que la semilla ha estado en el suelo durante unos d\u00edas c\u00e1lidos, recorre el campo busc\u00e1ndola, rastrill\u00e1ndola y encontr\u00e1ndola podrida en su mano, dir\u00eda: \u00ab\u00bfNo percibes que \u00bfLa agricultura es todo un mito? La cosa est\u00e1 muerta. Pero debe morir si quiere vivir. La raz\u00f3n de su descomposici\u00f3n es que su sustento puede ser absorbido por la ra\u00edz y el tallo, y darles nueva vida; y cuando un solo grano parece morir, no es m\u00e1s que un dolor de parto para cien granos que cobran vida. Por lo tanto, est\u00e1n ocurriendo cambios en la Iglesia. Hay muchas cosas en \u00e9l que deben decaer, para que otras cosas puedan crecer. El esp\u00edritu del cristianismo no est\u00e1 cambiando, pero su entorno cambiar\u00e1 m\u00e1s o menos o ser\u00e1 desechado, para que pueda desarrollarse. El cristianismo es como un faro sobre cuyo cristal el guardi\u00e1n ha permitido que las ara\u00f1as tejan sus telas, o en el que los insectos se han juntado hasta que el cristal es tan tenue que la luz, aunque brilla intensamente en el interior, apenas se ve en el exterior. Estas obstrucciones deben ser limpiadas, la basura debe ser quitada del camino, para que la luz brille. Hay miles de cosas en las interpretaciones de la religi\u00f3n que son oscurecimientos. (<em>HW Beecher.<\/em>)<\/p>\n<\/p>\n<p><strong>Se\u00f1ales del cielo<\/strong><\/p>\n<p><strong><br \/> I.<\/strong><em> <\/em>Una petici\u00f3n hip\u00f3crita.<\/p>\n<p><strong><br \/>II. <\/strong>Una reprensi\u00f3n fulminante.<\/p>\n<p><strong><br \/>III. <\/strong>Una negaci\u00f3n indignada.(<em>Esbozos expositivos.<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mateo 16:1-5 Oh hip\u00f3critas, pod\u00e9is discernir la faz del cielo. Se\u00f1ales de los tiempos La correcta observancia de estos signos. Son celestiales y, por lo tanto, deben verse en un coraz\u00f3n que busca las cosas espirituales. 1. La se\u00f1al del d\u00eda. Otro d\u00eda se ha ido. El d\u00eda del Se\u00f1or est\u00e1 m\u00e1s cerca. \u00bfEstoy mejor &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-mateo-161-5-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Mateo 16:1-5 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38771","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/38771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=38771"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/38771\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=38771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=38771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=38771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}