{"id":38773,"date":"2022-07-16T08:29:19","date_gmt":"2022-07-16T13:29:19","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-mateo-1612-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:29:19","modified_gmt":"2022-07-16T13:29:19","slug":"estudio-biblico-de-mateo-1612-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-mateo-1612-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Mateo 16:12 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Mateo 16:6<\/span>; <span class='bible'>Mateo 16:12<\/span><\/p>\n<p><em>Mirad y guardaos de la levadura de los fariseos y de los saduceos.<\/em><\/p>\n<\/p>\n<p><strong>La levadura de los fariseos y de los saduceos<\/strong><\/p>\n<p><strong><br \/>I. <\/strong>La levadura de los fariseos. La secta m\u00e1s numerosa y popular entre los jud\u00edos. Sus corrupciones pueden, en aras de la distinci\u00f3n, resumirse en tres encabezados.<\/p>\n<\/p>\n<p><strong>1. <\/strong>Eran r\u00edgidos predestinarios, o creyentes en lo que el lenguaje moderno llama necesidad filos\u00f3fica. Ten cuidado.<\/p>\n<p><strong>2. <\/strong>Rechazaron la Palabra escrita de Dios como la \u00fanica y suficiente norma de verdad religiosa, y la gu\u00eda de la pr\u00e1ctica religiosa; y observaron la tradici\u00f3n de los ancianos, que a menudo hicieron esta ley escrita de efecto de nodo. Mirad, y guardaos de la misma levadura.<\/p>\n<p><strong>3. <\/strong>Su justicia, aunque estricta en su tipo, era meramente externa; que consiste principalmente en una multitud de pr\u00e1cticas ceremoniosas. \u00bfCu\u00e1ntos hay como ellos? \u00a1Cuidado!<\/p>\n<p><strong><br \/>II. <\/strong>La levadura de los saduceos. Su herej\u00eda tambi\u00e9n puede describirse bajo tres encabezados.-<\/p>\n<p><strong>1. <\/strong>Negaron el estado ca\u00eddo y depravado de la humanidad; disput\u00f3 la doctrina de la corrupci\u00f3n hereditaria; y sosten\u00eda que la voluntad del hombre es, por naturaleza, y sin gracia especial de Dios, tan libre para el bien como para el mal<\/p>\n<p><strong>2. <\/strong>No solo rechazaron las tradiciones de los ancianos, sino que explicaron gran parte del Antiguo Testamento y, por lo tanto, invalidaron sus ense\u00f1anzas.<\/p>\n<p><strong>3. <\/strong>Negaron la existencia de \u00e1ngeles y esp\u00edritus, la resurrecci\u00f3n de los muertos y un estado futuro de premios y castigos. \u00a1Preste atenci\u00f3n y tenga cuidado!<em> <\/em>(<em>J. Bunting, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Las doctrinas err\u00f3neas son como la levadura <\/strong><\/p>\n<p>en los siguientes aspectos:-<\/p>\n<p><strong>1. <\/strong>Son, al principio, leves y sin importancia en apariencia.<\/p>\n<p><strong>2. <\/strong>Se insin\u00faan en el alma de forma inconsciente y silenciosa, y son dif\u00edciles de detectar.<\/p>\n<p><strong>3. <\/strong>Act\u00faan gradualmente.<\/p>\n<p><strong>4. <\/strong>Act\u00faan con toda certeza.<\/p>\n<p><strong>5. <\/strong>Invadir\u00e1n toda el alma y pondr\u00e1n todas las facultades bajo su control. (<em>A. Barnes.<\/em>)<\/p>\n<\/p>\n<p><strong>La influencia de la doctrina del mal pasa desapercibida, pero es da\u00f1ina para nuestro bienestar futuro<\/strong>&lt;\/p <\/p>\n<p>El arzobispo Whately ha hecho referencia al hecho notable de que las orugas de polillas y mariposas a menudo son atacadas por moscas ichneumon, que perforan sus pieles y depositan sus huevos en el cuerpo de la oruga. No se sigue ning\u00fan resultado inmediato, y no parece que se haya producido ning\u00fan da\u00f1o hasta el per\u00edodo en que la oruga se convierte en cris\u00e1lida. En lugar de una hermosa polilla o mariposa que emerge de este \u00faltimo, solo aparecen los insectos par\u00e1sitos. La mariposa escondida ha sido destruida en silencio. El sugerente comentario del Arzobispo es: \u201cNo puede un hombre tener una especie de enemigo secreto dentro de s\u00ed mismo, destruyendo su alma sin interferir con su bienestar durante la etapa presente de su existencia, y cuya presencia nunca puede ser detectada hasta que llegue el momento en que el el \u00faltimo gran cambio<em> <\/em>debe tener lugar.\u201d<\/p>\n<p><strong>La levadura de los fariseos y saduceos<\/strong><\/p>\n<p><strong><br \/> YO. <\/strong>En esta advertencia, se observar\u00e1, se identifican las tendencias farisaicas y saducicas. Jes\u00fas no habla de las levaduras, sino de una com\u00fan a ambas sectas, como si fueran dos especies de un g\u00e9nero, dos ramas de un mismo tallo. Superficialmente, las dos partes eran diversas: una estricta, la otra f\u00e1cil, en moral. Pero aqu\u00ed los extremos se encuentran. Todos eran hostiles al reino Divino. As\u00ed, para ser cristiano no basta con diferir superficialmente de los fariseos o de los saduceos, sino de diferir radicalmente de ambos. Una verdad de peso a\u00fan no comprendida. Para evitar el rigor farisaico y la superstici\u00f3n, los hombres caen en el escepticismo saducaico, ambos igualmente alejados de la verdad. El esp\u00edritu de incredulidad que reinaba en la sociedad jud\u00eda, Jes\u00fas lo describi\u00f3 como levadura, con especial referencia a su difusi\u00f3n.<\/p>\n<p><strong><br \/>II. <\/strong>Jes\u00fas luego encontr\u00f3 un nuevo motivo de disgusto en la estupidez de los amigos. Los disc\u00edpulos malinterpretaron la palabra de advertencia. \u201cEs porque no tenemos pan\u201d. Si hubieran pose\u00eddo m\u00e1s fe y espiritualidad, no habr\u00edan puesto el significado terrenal en las palabras. \u00a1Cu\u00e1n vano es hablar de cosas divinas a hombres cuyas mentes est\u00e1n ocupadas con preocupaciones terrenales! La levadura les hace pensar en panes. (<em>AB Bruce, DD<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mateo 16:6; Mateo 16:12 Mirad y guardaos de la levadura de los fariseos y de los saduceos. La levadura de los fariseos y de los saduceos I. La levadura de los fariseos. La secta m\u00e1s numerosa y popular entre los jud\u00edos. Sus corrupciones pueden, en aras de la distinci\u00f3n, resumirse en tres encabezados. 1. Eran &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-mateo-1612-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Mateo 16:12 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38773","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/38773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=38773"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/38773\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=38773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=38773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=38773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}