{"id":38866,"date":"2022-07-16T08:33:22","date_gmt":"2022-07-16T13:33:22","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-mateo-2451-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:33:22","modified_gmt":"2022-07-16T13:33:22","slug":"estudio-biblico-de-mateo-2451-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-mateo-2451-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Mateo 24:51 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Mateo 24:45<\/span>; <span class='bible'>Mateo 24:51<\/span><\/p>\n<p>\u00bfQui\u00e9n es, pues, el siervo fiel y prudente? <\/p>\n<p><strong><br \/>Yo. <\/strong>La relaci\u00f3n particular en la que estamos representados aqu\u00ed con el que est\u00e1 por encima de nosotros.<\/p>\n<p><strong><br \/>II. <\/strong>La representaci\u00f3n que aqu\u00ed se da de aquella actitud en que se encuentra el siervo que es obediente a su Se\u00f1or. Se utilizan t\u00e9rminos particularmente descriptivos de la conducta del individuo.<\/p>\n<p><strong>1. <\/strong>Fidelidad.<\/p>\n<p><strong>2. <\/strong>La sabidur\u00eda est\u00e1 asociada con la fidelidad: \u00abfiel y sabio\u00bb.<\/p>\n<p><strong>3. <\/strong>Continuidad habitual y perseverante en el bien hacer.<\/p>\n<p><strong><br \/>III. <\/strong>La bienaventuranza que se incluye en esta bendici\u00f3n del Maestro.<\/p>\n<p><strong>1. <\/strong>Bienaventurados en la aparici\u00f3n de Cristo, tambi\u00e9n mientras viva, en su actividad presente.<\/p>\n<p><strong>2. <\/strong>Recompensa positiva.<\/p>\n<p><strong>3. <\/strong>Contraste el enga\u00f1o del siervo malo. (<em>T. Binney, DD<\/em>)<\/p>\n<\/p>\n<p><strong>El siervo fiel y su recompensa<\/strong><\/p>\n<p><strong><br \/>Yo. <\/strong>El car\u00e1cter del siervo fiel.<\/p>\n<p><strong>1. <\/strong>El servidor fiel es aquel cuyo servicio es sincero.<\/p>\n<p><strong>2. <\/strong>El siervo fiel es aquel cuyo servicio no tiene reservas, limitado \u00fanicamente por su capacidad.<\/p>\n<p><strong>3. <\/strong>Su servicio es uniforme.<\/p>\n<p><strong>4. <\/strong>Su servicio est\u00e1 de acuerdo con la regla prescrita, \u00abSi un hombre lucha por dominios, no es coronado, a menos que luche legalmente\u00bb.<\/p>\n<p><strong>5. <\/strong>Su servicio es el de la fe: la fe viva del coraz\u00f3n en la verdad de Dios revelada a nosotros en Jesucristo.<\/p>\n<p><strong><br \/>II. <\/strong>Su recompensa. Aqu\u00ed se hace depender la recompensa de que el siervo se halle ocupando el puesto que se le ha asignado, con toda fidelidad, \u201ccuando venga su Se\u00f1or\u201d. No debemos inferir que el siervo fiel no es bendito antes de la venida de su Se\u00f1or, en la hora de la muerte. Sus onerosos deberes no disminuyen, sino que contribuyen a la bienaventuranza del siervo fiel. Tiene que sufrir, es verdad; pero estos ministran a su bienaventuranza. El amo promueve a su sirviente al m\u00e1s alto puesto de honor debido a su fidelidad en una posici\u00f3n inferior. \u00c9l es hecho un \u00abgobernante\u00bb. Estos placeres ser\u00e1n internamente progresivos. La recompensa, sin embargo, no ser\u00e1 igual en grado. Es un asunto de primera importancia determinar si somos de hecho y de verdad siervos de Cristo. (<em>R. Scott.<\/em>)<\/p>\n<\/p>\n<p><strong>La actividad de servicio<\/strong><\/p>\n<p>La partida de Cristo de esta tierra no es raz\u00f3n para la inacci\u00f3n de Su Iglesia, sino la fuente de su actividad. Lejos de retirar de la tierra los intereses de Su Iglesia con Su retiro, \u00c9l la dota de energ\u00edas m\u00e1s eficaces, de mayores capacidades de acci\u00f3n. Ella puede hacer m\u00e1s en la tierra, y no menos, ahora que \u00c9l se ha ido. \u00c9l muestra esto por imagen tras imagen. Nos dice que debemos ser una sociedad cuidadosamente y astutamente organizada, y esta organizaci\u00f3n debe formarse con miras al trabajo, la producci\u00f3n, el fruto. Debemos ser organizados con miras a nuestras capacidades, para ser dispuestos de manera que sirvan mejor para la utilidad pr\u00e1ctica directa, presente aqu\u00ed en la tierra; seremos como una casa que ha dejado un padre de familia, en la cual cada uno est\u00e1 en su lugar, cada uno seg\u00fan su don; y en esta casa habr\u00e1 una provisi\u00f3n cuidadosa, para que cada uno tenga su comida a su debido tiempo; la comida le ser\u00e1 tra\u00edda preparada por manos de oficiales designados para ese servicio, mientras que a la puerta se sentar\u00e1 siempre el portero, quien tendr\u00e1 el oficio. de mirar mientras los dem\u00e1s trabajan. \u00a1Qu\u00e9 cuidado, qu\u00e9 orden est\u00e1 todo! Sin cambios sueltos para llenar un intervalo. Ninguna indiferencia en cuanto a lo que se pueda hacer en el largo tiempo de espera. Su ida no destruye ni disminuye la seriedad o el cuidado con que se ha de organizar el intervalo. Qu\u00e9 ocupado es estar todo. \u00a1Qu\u00e9! \u00bfnos imaginamos que la prisa y la urgencia de los asuntos mundanos entrar\u00edan en conflicto con la solemnidad de velar por el Se\u00f1or? Pues, este reino Suyo debe ser, durante todo el tiempo de espera, como una casa de negocios. Ser\u00e1 como una casa de mercaderes, en la que todos est\u00e1n empe\u00f1ados en hacer todo lo que puedan con el dinero que se les da. No da ninguna imagen de una Iglesia de rodillas en alg\u00fan santuario silencioso, orando por un tiempo lejano. \u00c9l prev\u00e9 un cuerpo de hombres ocupados y decididos, absortos en el uso pr\u00e1ctico de sus dones, empe\u00f1ados en convertir cinco talentos en diez o dos en cuatro. (<em>Canon Scott-Holland.<\/em>)<\/p>\n<\/p>\n<p><\/p>\n<p><strong><br \/><\/strong> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mateo 24:45; Mateo 24:51 \u00bfQui\u00e9n es, pues, el siervo fiel y prudente? Yo. La relaci\u00f3n particular en la que estamos representados aqu\u00ed con el que est\u00e1 por encima de nosotros. II. La representaci\u00f3n que aqu\u00ed se da de aquella actitud en que se encuentra el siervo que es obediente a su Se\u00f1or. Se utilizan t\u00e9rminos &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-mateo-2451-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Mateo 24:51 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38866","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/38866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=38866"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/38866\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=38866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=38866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=38866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}