{"id":38872,"date":"2022-07-16T08:33:40","date_gmt":"2022-07-16T13:33:40","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-mateo-2546-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:33:40","modified_gmt":"2022-07-16T13:33:40","slug":"estudio-biblico-de-mateo-2546-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-mateo-2546-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Mateo 25:46 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Mat 25:46<\/span><\/p>\n<p><em>Y estos ser\u00e1n vete al castigo eterno.<\/em><\/p>\n<\/p>\n<p><strong>El estado final de los santos en el cielo<\/strong><\/p>\n<p>Hay un estado de felicidad en que entran los esp\u00edritus de los justos inmediatamente despu\u00e9s de su separaci\u00f3n del cuerpo, pero despu\u00e9s de la resurrecci\u00f3n y del juicio general, entonces los justos ir\u00e1n a la vida eterna.<\/p>\n<p><strong><br \/> YO. <\/strong>El estado de felicidad en s\u00ed mismo. Es evidente que los hombres buenos gozar\u00e1n de un estado de felicidad en el mundo venidero.<\/p>\n<p><strong>1. <\/strong>Desde la luz de la naturaleza y la raz\u00f3n. Noci\u00f3n general entre los paganos m\u00e1s sabios. Deseo universal en la humanidad. La distribuci\u00f3n desigual de las cosas en el estado actual.<\/p>\n<p><strong>2. <\/strong>De la revelaci\u00f3n divina.<\/p>\n<p><strong><br \/>II. <\/strong>La eternidad de esta felicidad. Testimonio de la Escritura. (<em>Esbozos de sermones.<\/em>)<\/p>\n<\/p>\n<p><strong><br \/>I.<\/strong><em> <\/em>Las partes sentenciaron .<\/p>\n<p><strong><br \/>II. <\/strong>Las sanciones impuestas.<\/p>\n<p><strong>1. <\/strong>Imposici\u00f3n positiva.<\/p>\n<p><strong>2. <\/strong>Pasiones incitadas.<\/p>\n<p><strong>3. <\/strong>Amarga reflexi\u00f3n.<\/p>\n<p><strong>4. <\/strong>Asociaciones dolorosas.<\/p>\n<p><strong>5. <\/strong>Reconocimiento mutuo.<\/p>\n<p><strong><br \/>III. <\/strong>La perpetuidad determinada.<\/p>\n<p><strong>1. <\/strong>Necesario.<\/p>\n<p><strong>2. <\/strong>Solo.<\/p>\n<p><strong>3. <\/strong>Cierto. (<em>J. Blackburn.<\/em>)<\/p>\n<\/p>\n<p><strong>Para siempre<\/strong><\/p>\n<p>Tu opini\u00f3n sobre \u201cpara siempre\u201d no puede tener ning\u00fan efecto sobre la realidad de ese \u201cpara siempre\u201d. Un grupo de barqueros en el r\u00edo Ni\u00e1gara puede tener una opini\u00f3n muy fuerte cuando son atrapados por los r\u00e1pidos, que es muy agradable remar; pero ni sus gritos ni su jolgorio alterar\u00e1n el hecho: que la catarata del mundo est\u00e1 cerca. Tienes una fuerte opini\u00f3n de que el fuego del infierno es un enga\u00f1o; que son supersticiosos, crueles e ignorantes quienes les piden que se detengan, despierten y se preparen para esta venida, esta retribuci\u00f3n continua; pero vuestras opiniones no tendr\u00e1n la menor, la m\u00e1s remota, la m\u00e1s m\u00ednima influencia en el tremendo hecho. (<em>Reynolds.<\/em>)<\/p>\n<\/p>\n<p><strong>Cielo e infierno<\/strong><\/p>\n<p><strong><br \/>I . <\/strong>El estado eterno de los justos. Constar\u00e1 de:<\/p>\n<p><strong>(1)<\/strong> Conocimiento perfecto;<\/p>\n<p><strong>(2)<\/strong>Amor perfecto;<\/p>\n<p><strong>(3)<\/strong> Perfecta pureza;<\/p>\n<p><strong>(4)<\/strong> Perfecta felicidad.<\/p>\n<p><strong><br \/>II . <\/strong>El estado eterno de los imp\u00edos. Incluye:<\/p>\n<p><strong>1. <\/strong>La privaci\u00f3n del bien infinito.<\/p>\n<p><strong>(1)<\/strong> Han perdido el cielo y toda su bienaventuranza a la vez.<\/p>\n<p><strong>(2 )<\/strong> Son ajenos a los cari\u00f1os y consuelos de la amistad.<\/p>\n<p><strong>(3)<\/strong> Ni existe el menor descanso del dolor.<\/p>\n<p>2. <\/strong>La imposici\u00f3n del mal infinito. Atormentadores en el infierno:<\/p>\n<p><strong>(1)<\/strong> Conciencia;<\/p>\n<p><strong>(2)<\/strong> Satan\u00e1s;<\/p>\n<p><strong>(3)<\/strong> Compa\u00f1ero maldito;<\/p>\n<p><strong>(4)<\/strong>El que sufre ser\u00e1 su propio verdugo;<\/p>\n<p><strong>(5 )<\/strong> Memoria;<\/p>\n<p><strong>(6)<\/strong> Anticipaci\u00f3n. (<em>T. Raffles.<\/em>)<\/p>\n<\/p>\n<p><strong>La naturaleza de la verdadera rectitud<\/strong><\/p>\n<p>La<em> <\/em>Los siguientes cuatro detalles son necesarios para tener derecho a la denominaci\u00f3n y el car\u00e1cter de hombres justos.<\/p>\n<p><strong><br \/>I. <\/strong>El establecimiento en nosotros de buenos principios, y actuar a partir de ellos.<\/p>\n<p><strong><br \/>II. <\/strong>La eficacia superior de tales principios dentro de nosotros a la eficacia de todos los dem\u00e1s principios.<\/p>\n<p><strong><br \/>III. <\/strong>La manifestaci\u00f3n de su superioridad evitando toda culpa habitual, y practicando todos los deberes conocidos; y<\/p>\n<p><strong><br \/>IV. <\/strong>Un esfuerzo constante por crecer mejor. (<em>Richard Price.<\/em>)<\/p>\n<\/p>\n<p><strong>Vida eterna<\/strong><\/p>\n<p><strong><br \/>I . <\/strong>La vida eterna, lo que es.<\/p>\n<p><strong>1. <\/strong>Es la vida en la existencia m\u00e1s perfecta.<\/p>\n<p><strong>2. <\/strong>Es la vida en su m\u00e1ximo disfrute. El intelecto en sus m\u00e1s altos vuelos, la voluntad en su m\u00e1s completo sometimiento, y los afectos, ser\u00e1n all\u00ed plenamente disfrutados.<\/p>\n<p><strong>3. <\/strong>Es la vida en su duraci\u00f3n eterna.<\/p>\n<p><strong><br \/>II. <\/strong>Las personas que han de disfrutar de la vida eterna: \u201clos justos\u201d. Han sido despojados de su propia justicia, y est\u00e1n revestidos de la justicia de Cristo. (<em>JH Evans, MA<\/em>)<\/p>\n<\/p>\n<p><\/p>\n<p><strong><br \/><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mat 25:46 Y estos ser\u00e1n vete al castigo eterno. El estado final de los santos en el cielo Hay un estado de felicidad en que entran los esp\u00edritus de los justos inmediatamente despu\u00e9s de su separaci\u00f3n del cuerpo, pero despu\u00e9s de la resurrecci\u00f3n y del juicio general, entonces los justos ir\u00e1n a la vida eterna. &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-mateo-2546-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Mateo 25:46 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38872","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/38872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=38872"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/38872\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=38872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=38872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=38872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}