{"id":38881,"date":"2022-07-16T08:34:04","date_gmt":"2022-07-16T13:34:04","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-mateo-2640-45-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:34:04","modified_gmt":"2022-07-16T13:34:04","slug":"estudio-biblico-de-mateo-2640-45-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-mateo-2640-45-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Mateo 26:40-45 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Mateo 26:40-45<\/span><\/p>\n<p> <em>Velad y orad, para que no entr\u00e9is en tentaci\u00f3n <\/em><\/p>\n<p><strong>Advertencia cristiana<\/strong><\/p>\n<p>Quien<em> <\/em>duerme por un cargador de p\u00f3lvora necesita cuidarse hasta de las chispas.<\/p>\n<p>Quien camina sobre hielo, que no vaya mirando las estrellas, sino que mire a sus pies, y cu\u00eddese de caer. \u201cVelad y orad, para que no entr\u00e9is en tentaci\u00f3n\u201d, es una advertencia que ning\u00fan hombre bueno deber\u00eda desatender. (<em>Tesoro del Maestro Dominical.<\/em>)<\/p>\n<\/p>\n<p><strong>Velando en oraci\u00f3n<\/strong><\/p>\n<p>Cuando el arquero dispara su flecha en una marca, le gusta ir y ver si la ha acertado o qu\u00e9 tan cerca ha estado de ella. Cuando ha escrito y enviado una carta a un amigo, espera que alg\u00fan d\u00eda el cartero llame a la puerta con una respuesta. Cuando un ni\u00f1o le pide algo a su padre, lo mira a la cara, incluso antes de hablar, para ver si est\u00e1 complacido, y lee aceptaci\u00f3n en sus ojos. Pero es de gran temor que muchas personas sientan, cuando terminan sus oraciones, como si ya hubieran terminado con ellas; su \u00fanica preocupaci\u00f3n era que se dijeran. Un viejo poeta pagano habla de J\u00fapiter lanzando ciertas oraciones a los vientos, dispers\u00e1ndolas en el aire vac\u00edo. Es triste pensar que tan a menudo hacemos eso por nosotros mismos. \u00bfQu\u00e9 pensar\u00edas de un hombre que ha escrito, doblado, sellado y dirigido una carta, arroj\u00e1ndola a la calle y sin pensar m\u00e1s en ella? Los marineros de barcos que se hunden a veces entregan notas en botellas selladas a las olas, por la posibilidad de que alg\u00fan d\u00eda sean arrastradas a alguna orilla. Los compa\u00f1eros de sir John Franklin entre las nieves y el capit\u00e1n Allen Gardiner, muri\u00e9ndose de hambre en su cueva, escribieron palabras que no estaban seguros de que nadie pudiera leer jam\u00e1s. Pero no necesitamos pensar en nuestras oraciones como mensajes aleatorios. Por lo tanto, debemos buscar una respuesta a ellos y velar para obtenerla. (<em>Dr. Edmond.<\/em>)<\/p>\n<\/p>\n<p><strong>C\u00f3mo tratar la tentaci\u00f3n<\/strong><\/p>\n<p>Un centinela publicado en el muros, cuando percibe el avance de un grupo hostil, no intenta atacarlos \u00e9l mismo, sino que informa a su oficial al mando de la aproximaci\u00f3n del enemigo, y lo deja para que tome las medidas apropiadas contra el enemigo. As\u00ed que el cristiano no intenta luchar contra la tentaci\u00f3n con sus propias fuerzas. Su vigilancia consiste en observar su acercamiento, y en dec\u00edrselo a Dios por medio de la oraci\u00f3n. (<em>W. Mason.<\/em>)<\/p>\n<\/p>\n<p><strong>Observar y orar: el peligro acecha en bagatelas<\/strong><\/p>\n<p>No s\u00f3lo (dice Manton) los grandes pecados arruinan el alma, pero las faltas menores har\u00e1n lo mismo. Darle vueltas a la tentaci\u00f3n lleva a tristes consecuencias. C\u00e9sar fue asesinado con punzones. Una daga dirigida al coraz\u00f3n producir\u00e1 una herida tan mortal como una enorme espada a dos manos, y un peque\u00f1o pecado del que no se arrepienta ser\u00e1 tan fatal como una transgresi\u00f3n grave. Brutus y Cassius y el resto de los conspiradores no podr\u00edan haber terminado con la vida de C\u00e9sar con lanzas m\u00e1s seguramente que con dagas. La muerte puede esconderse en una gota y cabalgar en una bocanada de aire. Nuestros mayores peligros se esconden en las cosas peque\u00f1as. Milton representa a miles de esp\u00edritus malignos amontonados en una sala; y en verdad el menor pecado puede ser un verdadero pandem\u00f3nium, en el que una multitud de males pueden estar ocultos, una colmena populosa de travesuras, cada una de las cuales almacena la muerte. Creyente, aunque seas un peque\u00f1o C\u00e9sar en tu propia esfera, ten cuidado con los pinchazos de tus enemigos. Vela y ora, no sea que caigas poco a poco. Se\u00f1or, s\u00e1lvame de los pecados que se llaman peque\u00f1os. (<em>CH Spurgeon.<\/em>)<\/p>\n<\/p>\n<p><strong>Todos los pecados son peligrosos<\/strong><\/p>\n<p>Todas las conciencias, como todos los est\u00f3magos, no son iguales Cu\u00e1ntos vemos digerir esos pecados con facilidad, que otros no pueden bajar luchando. Uno cuela un mosquito, mientras que otro se traga un camello. El que quiera mantenerse alejado de los grandes pecados debe hacer conciencia de todos. No tendr\u00e9 por peque\u00f1o ning\u00fan pecado, porque el m\u00e1s peque\u00f1o pone en peligro mi alma; y todo es lo mismo si vendo a mi Salvador por treinta denarios con Judas, o por la mitad que valgo con Anan\u00edas; si voy al infierno por un pecado, o por muchos. (<em>Obispo Henshaw.<\/em>)<\/p>\n<\/p>\n<p><strong>Conflicto de carne y esp\u00edritu<\/strong><\/p>\n<p>Anselm, Arzobispo de Canterbury , al pasar por el camino, divis\u00f3 a un ni\u00f1o con un p\u00e1jaro atado con una cuerda a una piedra; el ave todav\u00eda estaba levantando el vuelo para alejarse, pero la popa la manten\u00eda agachada. El hombre santo hizo buen uso de esta visi\u00f3n y, rompiendo en l\u00e1grimas, dijo: \u201cAun as\u00ed es entre la carne y el esp\u00edritu; el esp\u00edritu est\u00e1 dispuesto a subir en pensamientos y contemplaciones celestiales, pero la carne lo retiene y, si es posible, no admitir\u00eda el menor pensamiento del cielo. (<em>Spencer.<\/em>)<\/p>\n<\/p>\n<p><strong>Conflicto del esp\u00edritu con la carne<\/strong><\/p>\n<p>El hombre es una trinidad formado por cuerpo, alma y esp\u00edritu. La palabra <em>alma,<\/em> en el lenguaje de las Escrituras, no se usa en su significado moderno. Representa esa parte de nuestra naturaleza que tenemos en com\u00fan con los brutos que perecen. El <em>esp\u00edritu<\/em> del mismo modo, en el lenguaje del Antiguo y del Nuevo Testamento, representa esa naturaleza inteligente en el hombre que los brutos no tienen. El esp\u00edritu es el asiento de la voluntad, porque est\u00e1 escrito, \u201cel esp\u00edritu est\u00e1 dispuesto\u201d. El esp\u00edritu es la facultad perceptiva y reflexiva del hombre, porque \u201cnadie sabe las cosas del hombre, sino el esp\u00edritu del hombre que est\u00e1 en \u00e9l\u201d. El texto nos sugiere que aunque el esp\u00edritu del hombre est\u00e9 iluminado por el Esp\u00edritu de Dios, la debilidad de la carne puede derribarlo. La palabra \u201ccarne\u201d, en el lenguaje b\u00edblico, significa algo muy diferente de \u201ccuerpo\u201d. Se\u00f1ala la naturaleza del hombre como dotada de todas sus maravillosas adaptaciones al mundo en el que vive, adaptaciones que en verdad suplen su m\u00e1s fuerte tentaci\u00f3n de olvidar a Dios. Satan\u00e1s anda con los pies encapuchados, buscando a quien devorar. As\u00ed como en el mundo natural hay influencias sutiles en el trabajo, en el poder de la electricidad por ejemplo, que podemos medir pero no podemos ver, as\u00ed hay \u00e1ngeles buenos y malos, el que ministra a esa mente de la carne que es la muerte. , los otros a esa preocupaci\u00f3n del esp\u00edritu que es vida y paz. Las influencias celestiales comienzan con el esp\u00edritu, afectan la naturaleza inferior o an\u00edmica y, a trav\u00e9s de ella, regulan las acciones del cuerpo. (<em>JG Pilkington.<\/em>)<\/p>\n<\/p>\n<p><strong>Dormir ahora, etc.<\/strong><\/p>\n<p>Lutero lee las palabras indicativamente, ya modo de pregunta, as\u00ed: \u00a1Ah! \u00bfDuermen ahora y descansan? \u00bfQuer\u00e9is, con el borracho de Salom\u00f3n, dormir sobre un m\u00e1stil? tomar una siesta sobre una veleta? As\u00ed, esta \u00c1guila celestial, aunque ama mucho a Sus cr\u00edas, las pincha y las saca del nido a golpes. Los mejores (como las abejas) son asesinados con la miel de la adulaci\u00f3n, pero vivificados con el vinagre de la reprensi\u00f3n. (<em>John Trapp.<\/em>)<\/p>\n<\/p>\n<p><strong>El esp\u00edritu dispuesto y la carne d\u00e9bil<\/strong><\/p>\n<p><strong> <br \/>Yo. <\/strong>Una caracter\u00edstica del cristiano: un esp\u00edritu dispuesto.<\/p>\n<p><strong>1. <\/strong>Esto es cierto para cada uno de los verdaderos disc\u00edpulos de Cristo en la tierra.<\/p>\n<p><strong>2. <\/strong>No debemos poner l\u00edmites al grado de voluntad del cristiano.<\/p>\n<p><strong>3. <\/strong>Cristo lo prob\u00f3 constantemente. \u201cVende todo lo que tienes.\u201d<\/p>\n<p><strong><br \/>II. <\/strong>La enfermedad del cristiano. \u201cLa carne es d\u00e9bil.\u201d<\/p>\n<p><strong>1. <\/strong>Verdad en la oraci\u00f3n.<\/p>\n<p><strong>2. <\/strong>Cierto en la lectura de la Biblia.<\/p>\n<p><strong>3. <\/strong>Cierto en el esfuerzo cristiano.<\/p>\n<p><strong>4. <\/strong>Ciertos en nuestras p\u00e9rdidas y aflicciones.<\/p>\n<p><strong>5. <\/strong>Debemos esperar experimentar m\u00e1s y m\u00e1s de esta debilidad de nuestra naturaleza mortal a medida que avanza la vida.<\/p>\n<p><strong><br \/>III. <\/strong>La compasi\u00f3n de nuestro se\u00f1or por el cristiano en su enfermedad. La reprensi\u00f3n pronto es seguida por la compasi\u00f3n. Ahora estaba abrumado por la miseria; pero el sufrimiento no lo hizo ego\u00edsta.<\/p>\n<p><strong><br \/>IV. <\/strong>La conducta que debemos seguir bajo nuestras debilidades. \u00bfDebemos permitir que la carne d\u00e9bil haga lo que quiera? Debemos velar y orar. (<em>C. Bradley.<\/em>)<\/p>\n<\/p>\n<p><strong>El centinela y el arsenal<\/strong><\/p>\n<p><strong><br \/>I. <\/strong>El cristiano es un centinela; su capit\u00e1n es Cristo; y la palabra de mando es \u201cvelar\u201d<\/p>\n<p><strong>1. <\/strong>Estar alerta implica vigilia.<\/p>\n<p><strong>2. <\/strong>La vigilancia implica discriminaci\u00f3n. Un centinela debe distinguir entre un enemigo y un amigo.<\/p>\n<p><strong>3. <\/strong>Un centinela escudri\u00f1ar\u00e1 y probar\u00e1 el car\u00e1cter.<\/p>\n<p><strong><br \/>II. <\/strong>No es suficiente contratar un centinela para vigilar la invasi\u00f3n del enemigo: tampoco es suficiente que sea fiel y d\u00e9 la se\u00f1al de alarma cuando sea necesario. El arsenal es necesario; sin esto el centinela ser\u00eda d\u00e9bil e in\u00fatil. \u201cPero en M\u00ed se encuentra tu ayuda.\u201d<\/p>\n<p><strong><br \/>III. <\/strong>La relaci\u00f3n inseparable de la vigilia y la oraci\u00f3n. As\u00ed somos salvos de <em>entrar<\/em> en la tentaci\u00f3n, ya que cuando el hombre est\u00e1 completamente en ella, termina la vigilia y la indisposici\u00f3n para orar. (<em>GH Jackson.<\/em>)<\/p>\n<\/p>\n<p><strong>Velando con Cristo<\/strong><\/p>\n<p>No continuar\u00e9 con esta historia , excepto para desarrollar este hecho \u00fanico: la necesidad que nuestro Dios tiene de nuestro afecto, y nuestra simpat\u00eda, y nuestra presencia con \u00c9l. No s\u00e9 c\u00f3mo es contigo, pero es precisamente esto lo que me hace amar a Dios. Es solo esta necesidad de ser amado en <em>Dios, <\/em>y este sentimiento de soledad sin ella, lo que provoca mi afecto por \u00c9l. El poder puede ser venerable y la sabidur\u00eda puede ser admirable; pero s\u00f3lo el afecto es amable. Es una maravilla, si es verdad -y bendito sea Dios, es verdad- que si bien no podemos hacer nada a la estatura divina, y si bien no podemos hacer nada a la sabidur\u00eda divina, est\u00e1 en el poder de un coraz\u00f3n que sabe amar, hacer mucho por la felicidad divina. Porque no debemos decir que Dios es perfecto en el sentido de que nunca m\u00e1s pueda sentir. Eso es llevar la filosof\u00eda a la locura. Todo coraz\u00f3n que ama a Dios le hace experimentar una alegr\u00eda divina. Toda alma que se eleva a la presencia de Dios con adoraci\u00f3n de amor, lo hace m\u00e1s feliz. Y ahora, adem\u00e1s, \u00bfno hay una relaci\u00f3n de esta escena con nuestras relaciones en esta vida y con nuestras experiencias? \u00bfEst\u00e1 Cristo todav\u00eda sobre la tierra en alg\u00fan sentido tal que pueda decirse que estamos velando con \u00c9l aqu\u00ed? Observo que la vida de Cristo se desarrolla en este mundo; que se est\u00e1 desarrollando aqu\u00ed, casi dir\u00eda en algunos aspectos m\u00e1s maravilloso\/y, que en el cielo mismo. En otras palabras, la siguiente representaci\u00f3n es que Cristo ha mezclado Su esp\u00edritu con los corazones de la raza; que por su vida y ejemplo est\u00e1 ense\u00f1ando a los hombres. Y, sobre todo, por sus influencias espirituales, Cristo est\u00e1 germinando en la raza su propia naturaleza, y est\u00e1 obligado a llevar a la raza por encima de sus condiciones animales y hacia la esfera trascendente donde \u00c9l mismo est\u00e1. Dondequiera, pues, en toda la tierra, hay quienes necesitan gu\u00eda; dondequiera que haya quienes necesiten instrucci\u00f3n; dondequiera que est\u00e9n los que buscan el camino ascendente y buscan a alguien que los gu\u00ede, all\u00ed est\u00e1 el Salvador con ellos. \u00c9l, entonces, est\u00e1 velando con Cristo, si estas son verdades, que vela con el Salvador en sus ministerios terrenales. Los que est\u00e1n en medio del resplandor y del crecimiento de las cosas materiales en esta vida, y se identifican, no obstante, con lo interior, con lo espiritual, con los asuntos religiosos de los hombres, bien puede decirse que velan con Cristo. A\u00fan m\u00e1s, especialmente aquellos que est\u00e1n velando como Cristo ense\u00f1\u00f3 que debemos velar, son aquellos que velan por las almas de los hombres, y no solo por Cristo. Un hombre puede velar con Cristo en sus propias experiencias, as\u00ed como en las experiencias de los dem\u00e1s. (<em>HW Beecher.<\/em>)<\/p>\n<\/p>\n<p><strong>Vigilancia y oraci\u00f3n<\/strong><\/p>\n<p>Como toda guerra debe llevarse a cabo en parte por nuestra propia fuerza y en parte por la de los aliados y auxiliares llamados en nuestra ayuda y asistencia, as\u00ed en esta guerra cristiana las cosas que responden apropiadamente a esos dos son la vigilancia y la oraci\u00f3n: por cuanto en la vigilancia ejercemos y empleamos nuestra propia fuerza , y por la oraci\u00f3n nos comprometemos con Dios; y si alguna vez la victoria y el \u00e9xito nos acompa\u00f1an en estos encuentros, estos dos deben unir sus fuerzas, el cielo y la tierra deben estar confederados, y donde lo est\u00e9n, el mismo diablo, tan fuerte como es, y tan invencible como monarca como lo ser\u00eda. que se piensa que es, a\u00fan puede verse obligado a partir con un <em>pluribus impar, <\/em>y abandonar el campo con una frustraci\u00f3n y una batalla. (<em>R. Sur, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Viendo<\/strong><\/p>\n<p><strong><br \/> YO. <\/strong>Importa un sentido fuerte, vivo y persuasivo y una persuasi\u00f3n de la sobremanera grandeza del mal, que observamos y contra el cual luchamos.<\/p>\n<p><strong><br \/>II. <\/strong>Importa una consideraci\u00f3n diligente y un estudio de nuestras propias fortalezas y debilidades en comparaci\u00f3n con las de nuestro enemigo.<\/p>\n<p><strong><br \/>III. <\/strong>La vigilancia implica una consideraci\u00f3n cuidadosa y minuciosa de las diversas formas en que la tentaci\u00f3n ha prevalecido en cualquier momento sobre nosotros mismos o sobre otros.<\/p>\n<p><strong>1. <\/strong>Para s\u00ed mismo. Todo hombre debe conocer las plagas de su propio coraz\u00f3n, y qu\u00e9 pasos en falso ha dado en los varios giros y per\u00edodos de su curso cristiano, por qu\u00e9 medios cay\u00f3, y sobre qu\u00e9 rocas se parti\u00f3.<\/p>\n<p>2. <\/strong>Que el cristiano vigilante lleve su mirada de s\u00ed mismo a los dem\u00e1s, y observe con qu\u00e9 truco y artificio ha practicado el tentador con ellos.<\/p>\n<p><strong><br \/>IV. <\/strong>La vigilancia implica una intenci\u00f3n continua y real<em> <\/em>de la mente sobre la gran preocupaci\u00f3n y el peligro que tenemos ante nosotros, en <em>oposici\u00f3n <\/em>a la pereza, la ociosidad y la negligencia.<\/strong> p&gt;<\/p>\n<p><strong><br \/>V. <\/strong>Velar implica una templanza constante y severa en oposici\u00f3n a todas las alegr\u00edas del jolgorio y la intemperancia. (<em>R. South, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Oraci\u00f3n en tiempo de tentaci\u00f3n<\/strong><\/p>\n<p>No es en el poder del hombre para asegurarse o defenderse contra la tentaci\u00f3n, algo por encima de \u00e9l debe hacerlo por \u00e9l, as\u00ed como muy a menudo por \u00e9l; y la oraci\u00f3n es ese bendito mensajero entre el cielo y la tierra, que mantiene una correspondencia con ambos mundos y, mediante una relaci\u00f3n feliz y un transporte seguro, satisface las necesidades del uno y hace descender las bondades del otro. Para que la oraci\u00f3n sea frecuente y eficaz, se requieren estas dos cualidades:<\/p>\n<p><strong>1. <\/strong>Fervor o importunidad.<\/p>\n<p><strong>2. <\/strong>Constancia o perseverancia. Con demasiada frecuencia, los hombres dividen entre velar y orar, y as\u00ed usan y conf\u00edan en estos deberes por separado, que no pueden hacer nada m\u00e1s que en conjunto. Porque la vigilancia sin oraci\u00f3n es presunci\u00f3n, y la oraci\u00f3n sin vigilancia es burla. Por el primero, el hombre invade la parte de Dios en esta gran obra, y por el segundo, descuida la suya propia. La oraci\u00f3n no asistida por la pr\u00e1ctica es pereza, y contradicha por la pr\u00e1ctica es hipocres\u00eda; es ciertamente de gran fuerza y utilidad dentro de su \u00e1mbito adecuado, pero nunca fue dise\u00f1ado para proporcionar el lugar de la vigilancia, o para hacer que el deseo est\u00e9 en lugar del esfuerzo. (<em>R. South, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Prepararse para la tentaci\u00f3n<\/strong><\/p>\n<p>Sabio<em> <\/em>los combatientes medir\u00e1n las espadas antes de enfrentarse. Y una persona discreta aprender\u00e1 sus propias debilidades m\u00e1s por reflexi\u00f3n que por experiencia. Pues conocerse d\u00e9bil s\u00f3lo por ser vencido es sin duda la peor especie de convicci\u00f3n. (<em>R. Sur, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Peligro de dormir en tiempos de tentaci\u00f3n<\/strong><\/p>\n<p>Otra Me he encontrado con un ejemplo en la historia de un cierto general, que recorriendo su campamento en la noche, y encontrando a la guardia profundamente dormida en el suelo, lo clava en el lugar donde yac\u00eda con su propia espada, usando adem\u00e1s esta expresi\u00f3n: \u201cLo encontr\u00e9 muerto y lo dej\u00e9 as\u00ed\u201d. (<em>R. South, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Labio-devoci\u00f3n<\/strong><\/p>\n<p>Labio-devoci\u00f3n no servir el turno. Subestima las mismas cosas por las que ora. De hecho, es la petici\u00f3n de una negaci\u00f3n, y ciertamente ser\u00e1 respondida en lo que pide. (<em>R. Sur, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Esp\u00edritu dispuesto, carne d\u00e9bil<\/strong><\/p>\n<p><strong> <br \/>Yo. <\/strong>D\u00e9 una explicaci\u00f3n de las palabras.<\/p>\n<p><strong><br \/>II. <\/strong>Mostrar que nuestro estado actual es imperfecto, y siempre habr\u00e1 defectos-defectos en nuestro marco espiritual, defectos en nuestra obediencia, defectos en nuestro acercamiento a Dios en nuestros deberes religiosos.<\/p>\n<p><strong><br \/>III. <\/strong>Si el esp\u00edritu est\u00e1 dispuesto, y verdaderamente lamentamos nuestras debilidades y velamos y oramos contra ellas, Dios nos aceptar\u00e1 con gracia, aprobar\u00e1 nuestros deseos y esfuerzos sinceros y perdonar\u00e1 nuestras faltas.<\/p>\n<p> <strong><br \/>IV. <\/strong>Que esta gracia de Dios y Redentor es motivo de gran consuelo para el cristiano sincero, un apoyo para \u00e9l en el sentido de su debilidad e indignidad, y un est\u00edmulo para comprometerse en deberes solemnes, particularmente en la celebraci\u00f3n de la ordenanza de la Cena del Se\u00f1or, con prontitud y alegr\u00eda, y sin pavor ni terror que distraigan y asombren. (<em>John Whitty.<\/em>)<\/p>\n<\/p>\n<p><strong>Oraci\u00f3n<\/strong><\/p>\n<p><strong><br \/>I. <\/strong>Explicar la naturaleza de la oraci\u00f3n y ponerla en su verdadera luz, despoj\u00e1ndola de todas las circunstancias ajenas y superfluas. Para comprender la naturaleza de la oraci\u00f3n, notemos que los actos internos de la mente y del coraz\u00f3n que se ejercen en ella, de los cuales deben fluir las expresiones externas y por los cuales deben ser animadas, son principalmente estos tres siguientes:&lt;\/p <\/p>\n<p>1. <\/strong>Una persuasi\u00f3n viva e \u00edntima de que somos completamente insuficientes para nuestra propia felicidad, y que dependemos de nuestro Hacedor para todo lo que poseemos aqu\u00ed o esperamos disfrutar en el m\u00e1s all\u00e1.<\/p>\n<p><strong>2. <\/strong>El segundo acto del alma ejercido en la oraci\u00f3n, es elevarla con sumo ardor al m\u00e1s grande y mejor de los seres que nos trajo a la vida, y nos asign\u00f3 nuestro lugar en ella.<\/p>\n<p>3. <\/strong>El tercer acto mental es una creencia firme y una confianza segura en ese Dios a quien oramos y de quien dependemos.<\/p>\n<p><strong><br \/>II. <\/strong>Reivindicar la oraci\u00f3n de las objeciones com\u00fanmente formuladas contra ella.<\/p>\n<p><strong>1. <\/strong>Que un Dios omnisciente ya sabe lo que queremos antes de que se lo pidamos. Respuesta: El prop\u00f3sito real de la oraci\u00f3n es, en primer lugar, expresar, bajo una impresi\u00f3n viva de la presencia de Dios, el sentido que tenemos de nuestra dependencia de \u00c9l; y, en segundo lugar, expresar nuestros fervientes deseos de teniendo todos aquellos sentimientos y disposiciones piadosas que nos es propio abrigar y cultivar.<\/p>\n<p><strong>2. <\/strong>Que siendo Dios infinito en bondad, siempre est\u00e1 dispuesto a dar a sus criaturas lo que les conviene, y siendo infinito en sabidur\u00eda, escoger\u00e1 siempre los tiempos m\u00e1s adecuados y la mejor manera de dar. Respuesta: La oraci\u00f3n no est\u00e1 dise\u00f1ada para mover los afectos de Dios, obra su efecto en nosotros, ya que contribuye a cambiar el temperamento de nuestras mentes.<\/p>\n<p><strong>3. <\/strong>La oraci\u00f3n no puede tener importancia, porque todas las cosas ya est\u00e1n establecidas por un decreto inalterable de Dios. Respuesta: Nadie sostuvo que Dios ha determinado que los eventos sucedan sin ning\u00fan medio, y las oraciones son el medio apropiado para obtener bendiciones espirituales.<\/p>\n<p><strong><br \/>III. <\/strong>Las ventajas que se derivan del cumplimiento sincero y constante de este deber.<\/p>\n<p><strong>1. <\/strong>Como un descanso en nuestra vida mundana.<\/p>\n<p><strong>2. <\/strong>Como inspir\u00e1ndonos con el amor, y anim\u00e1ndonos a la pr\u00e1ctica, de cada virtud.<\/p>\n<p><strong>3. <\/strong>Ponernos en el mejor estado de \u00e1nimo y situaci\u00f3n mental para recibir las influencias de la luz y la gracia celestiales.<\/p>\n<p><strong>4. <\/strong>Elevar el alma humana a un nivel poco com\u00fan de grandeza y elevaci\u00f3n.<\/p>\n<p><strong>5. <\/strong>Dando una maravillosa fuerza y firmeza al alma que est\u00e1 bajo su pleno poder e influencia. Siendo, pues, la oraci\u00f3n una cosa razonable en s\u00ed misma, debe ser tanto nuestro deber como nuestro inter\u00e9s continuar en ella instant\u00e1neamente. (<em>W. Leechman.<\/em>)<\/p>\n<\/p>\n<p><strong>Entrar en tentaci\u00f3n<\/strong><\/p>\n<p>Tentar es en general no m\u00e1s que probar, y un estado de tentaci\u00f3n es un estado de prueba; orar, por tanto, para que no seamos puestos en estado de tentaci\u00f3n, es orar para salir de este mundo, que fue dise\u00f1ado por Dios para un estado de prueba a fin de otro mundo. Por lo tanto, cuando oramos para no ser inducidos a la tentaci\u00f3n, el significado es que Dios, por su sabia providencia, nos guardar\u00e1 de tales pruebas que, de acuerdo con las medidas ordinarias de la gracia, dif\u00edcilmente podr\u00edamos soportar. Porque, aunque sea posible para aquellos a quienes Dios da ayuda extraordinaria, no s\u00f3lo resistir la tentaci\u00f3n, sino vencerla, y sacudirse las tentaciones como San Pablo hizo con la v\u00edbora de su mano, sin embargo, considerando la fragilidad de naturaleza humana, y que Dios no est\u00e1 obligado a dar asistencia en casos dif\u00edciles, es una petici\u00f3n sabia y adecuada para nosotros a nuestro Padre celestial, que no nos deje caer de esta manera en la tentaci\u00f3n. (<em>E. Stillingfleet.<\/em>)<\/p>\n<\/p>\n<p><strong>Las atracciones de dos mundos<\/strong><\/p>\n<p>Es el amor de este mundo, es decir, de las riquezas y honores de \u00e9l, que hacen tan plausibles y prevalecientes los pecados de la ambici\u00f3n y la codicia entre los que profesan creer en otro mundo. Sus almas son como un trozo de hierro entre dos imanes de distinta magnitud y distancia; el uno es mucho m\u00e1s grande y tiene m\u00e1s fuerza en s\u00ed mismo para atraer, pero est\u00e1 colocado a una distancia mucho mayor; el otro es mucho menor, pero muy cercano, y por lo tanto puede atraer m\u00e1s poderosamente que el que es m\u00e1s fuerte pero m\u00e1s lejano. (<em>E. Stillingfleet.<\/em>)<\/p>\n<\/p>\n<p><strong>Importancia de la resoluci\u00f3n,<\/strong><\/p>\n<p>Uno de los mejores medios en el mundo para resistir las tentaciones de pecar, porque-<\/p>\n<p><strong>1. <\/strong>Mantiene la mente firme y fija, y por lo tanto lista para resistir la tentaci\u00f3n cuando se presente.<\/p>\n<p><strong>2. <\/strong>Porque quita los falsos colores y apariencias de las cosas; porque todo puede representarse plausiblemente para una mente indecisa. (<em>E. Stillingfleet.<\/em>)<\/p>\n<\/p>\n<p><strong>Pecados de voluntad y pecados de debilidad<\/strong><\/p>\n<p>\u00bfPor qu\u00e9 ciertas reglas podemos proceder para juzgar qu\u00e9 pecados son voluntariosos y presuntuosos, y cu\u00e1les son los pecados de debilidad, o los que provienen de la debilidad de la carne. Tenemos dos formas de juzgar.<\/p>\n<p><strong>1. <\/strong>De la naturaleza de las acciones morales.<\/p>\n<p><strong>2. <\/strong>De las Escrituras, declarando qu\u00e9 pecados son incompatibles con el estado de salvaci\u00f3n.<\/p>\n<p>Porque hay dos clases de enfermedades:<\/p>\n<p><strong>1. <\/strong>Las que pertenecen a acciones particulares.<\/p>\n<p><strong>2. <\/strong>Las que pertenecen a nuestro estado y condici\u00f3n.<\/p>\n<p>Hay tres cosas que alteran y discriminan mucho la naturaleza de las acciones morales.<\/p>\n<p><strong>1. <\/strong>La elecci\u00f3n y consentimiento de la voluntad.<\/p>\n<p><strong>2. <\/strong>El tiempo y la deliberaci\u00f3n al respecto.<\/p>\n<p><strong>3. <\/strong>La forma de cometerlo. (<em>E. Stillingfleet.<\/em>)<\/p>\n<\/p>\n<p><strong>\u00bfQu\u00e9 es la vigilancia?<\/strong><\/p>\n<p>Es un cuidado constante de nosotros mismos y de las acciones. Caminamos como sobre precipicios, y por lo tanto ten\u00edamos necesidad de mirar a nuestra posici\u00f3n, cuando vemos personas que caen por todos lados. (<em>E. Stillingfleet.<\/em>)<\/p>\n<\/p>\n<p><strong>La defensa de la oraci\u00f3n<\/strong><\/p>\n<p>La oraci\u00f3n, cuando se realiza debidamente , no s\u00f3lo desv\u00eda, levanta y serena la mente, y as\u00ed quebranta la fuerza de una tentaci\u00f3n presente, pero cuando se pone un asedio cercano, mantiene el paso abierto para los suministros del cielo, y derriba los apoyos que pueden permitirnos para soportar. (<em>E. Stillingfleet.<\/em>)<\/p>\n<\/p>\n<p><strong>Pecados de enfermedad<\/strong><\/p>\n<p><strong><br \/>Yo. <\/strong>\u00bfCu\u00e1l es el sentido b\u00edblico de la enfermedad?<\/p>\n<p><strong>1. <\/strong>El estado de la naturaleza humana es tal que est\u00e1 sujeto a muchos dolores, enfermedades y, finalmente, a la muerte. En este sentido se dice que Cristo lleva nuestras enfermedades, estando sujeto por la ley de su naturaleza a la misma debilidad: hambre, sed, sue\u00f1o, temor al dolor.<\/p>\n<p><strong>2. <\/strong>Los hombres no son m\u00e1s d\u00e9biles en sus cuerpos que en sus mentes, ni m\u00e1s expuestos a los dolores corporales que a las impresiones del pecado, que es nuestra enfermedad espiritual.<\/p>\n<p><strong>3. <\/strong>Junto a este sentido general de enfermedad vienen las enfermedades particulares incluidas en \u00e9l. Se apremia en defensa de que estas pasiones son naturales; tambi\u00e9n que son inherentes. Que una pasi\u00f3n natural tiene el mismo autor que la naturaleza, y nos pertenece como hombres, por lo que no debe evitarse. Ninguno de estos tiene enfermedad suficiente para ser una excusa para el pecado.<\/p>\n<p><strong><br \/>II. <\/strong>Qu\u00e9 clase de pecados son los que admitir\u00e1n excusa a causa de la debilidad de la que proceden. Hay una imperfecci\u00f3n en la obediencia del mejor de los hombres: frialdad en la devoci\u00f3n, pensamientos errantes, lo cual es una debilidad que debe ser perdonada. La \u00fanica manera de darnos derecho a la s\u00faplica es esforz\u00e1ndonos sincera y universalmente por obedecer la voluntad de Dios. (<em>T. Sherlock, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Los disc\u00edpulos en Getseman\u00ed<\/strong><\/p>\n<p><strong><br \/>I. <\/strong>La necesidad de reprensi\u00f3n.<\/p>\n<p><strong><br \/>II. <\/strong>El m\u00e9todo de Cristo; la reprensi\u00f3n es templada y limitada. La carne debe ser reprendida por su debilidad, el esp\u00edritu alabado y fortalecido por su disposici\u00f3n. Si Cristo hubiera sido del esp\u00edritu de algunos, no habr\u00eda permitido tal paliaci\u00f3n de su debilidad. C\u00f3mo Cristo puso su conocimiento del hombre en el otro lado de la balanza: \u00ab\u00c9l sab\u00eda lo que hab\u00eda en el hombre\u00bb. Imag\u00ednese la desilusi\u00f3n con la que los disc\u00edpulos se despertaron al descubrir que sus firmes resoluciones se hab\u00edan desvanecido. Estas palabras de Cristo muestran m\u00e1s bien su intenso aprecio por toda la voluntad oculta de los hombres que cualquier deseo de agravar su fracaso. \u00c9l us\u00f3 Su conocimiento para su ayuda, no para herirlos. \u00c9l ve el brillo redentor. Fomentar la voluntad de esp\u00edritu.<\/p>\n<p><strong><br \/>III. <\/strong>Por \u00faltimo, lo que puede hacer una voluntad fortalecida y bien dirigida; c\u00f3mo puede elevarse por encima de la carne. Lo vemos en las actividades mundanas. Cu\u00e1n ansiosamente persigue un hombre una idea cuando domina su voluntad. La vida religiosa ideal es s\u00f3lo una nueva ambici\u00f3n con la ayuda Divina para alcanzarla. (<em>CJ Proctor.<\/em>)<\/p>\n<\/p>\n<p><strong>Tentaci\u00f3n<\/strong><\/p>\n<p><strong><br \/>I. <\/strong>Las fuentes de la tentaci\u00f3n.<\/p>\n<p><strong>1. <\/strong>Temperamento y disposici\u00f3n.<\/p>\n<p><strong>2. <\/strong>Las circunstancias de que se rodea un hombre y la educaci\u00f3n en que ha sido criado.<\/p>\n<p><strong><br \/>II. <\/strong>Pasando de las fuentes de la tentaci\u00f3n, perm\u00edtanme hablar de la necesidad de velar contra ella.<\/p>\n<p><strong>1. <\/strong>Una raz\u00f3n es nuestra ignorancia de nosotros mismos.<\/p>\n<p><strong>2. <\/strong>Se necesita vigilancia porque la prueba del car\u00e1cter del hombre dura toda la vida.<\/p>\n<p><strong>3. <\/strong>La vigilancia del esp\u00edritu tendr\u00e1 mucho efecto, pero ser\u00e1 de gran ayuda si se combina con un esp\u00edritu de devoci\u00f3n. Le da fuerza que en un sentido es suya, pero en un sentido m\u00e1s verdadero y superior no es suya. Un sentido de responsabilidad religiosa hacia Dios fortalece el sentido del bien contra el mal. Cuando resiste la tentaci\u00f3n, no lucha solo, sino que tiene la ley eterna y la voluntad de Dios de su lado. En cada encuentro ayuda mucho a un hombre saber que no est\u00e1 soltero. (<em>A. Watson, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Mira nuestra fuerza<\/strong><\/p>\n<p>Los hombres pueden estar en sus precavidos contra sus enfermedades, pero incautos donde se consideran fuertes. Y as\u00ed como todo lector de historia est\u00e1 familiarizado con las historias que cuentan c\u00f3mo las fortalezas y los castillos fueron tomados por el enemigo, no en su lado d\u00e9bil y bien protegido, sino en el lado donde se consideraban inexpugnables, y donde la vigilancia se consideraba in\u00fatil, as\u00ed ha sido mil veces en la historia de la mente y la vida humana. El fiel Abraham cay\u00f3 en la desconfianza; el manso Mois\u00e9s se turb\u00f3 de esp\u00edritu; el sabio Salom\u00f3n fue sobrepasado por actos que podr\u00eda haber resistido; el valiente Pedro, incluso cuando fue advertido por Cristo, fue arrastrado a un acto de cobard\u00eda. As\u00ed que a menudo lo vemos en la vida com\u00fan. Vemos al hombre de gran entendimiento desprevenido y haciendo locuras; el hombre \u00edntegro, por alg\u00fan impulso, se apart\u00f3 del camino recto. (<em>A. Watson, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Vigilancia cristiana<\/strong><\/p>\n<p><strong><br \/>Yo. <\/strong>Mostrar la importancia y la necesidad de la vigilancia cristiana. De-<\/p>\n<p><strong>1. <\/strong>Los mandamientos y exhortaciones de la Escritura.<\/p>\n<p><strong>2. <\/strong>El enga\u00f1o y la depravaci\u00f3n del coraz\u00f3n humano. Las ilusiones que practica sobre s\u00ed mismo. Como un ingenioso abogado cuyo objeto es colorear y recomendar una mala causa, emplea los m\u00e1s enga\u00f1osos sofismas; y el pecado es astutamente defendido por varios motivos de constituci\u00f3n, costumbre, conveniencia y necesidad.<\/p>\n<p><strong>3. <\/strong>Las tentaciones a las que estamos expuestos.<\/p>\n<p><strong>(1)<\/strong> Las tentaciones del mundo.<\/p>\n<p><strong>(2)<\/strong> Satan\u00e1s.<\/p>\n<p><strong>4. <\/strong>Los pecados en que muchos del pueblo de Dios han ca\u00eddo por su descuido. No\u00e9, David, Ezequ\u00edas y Pedro. No se puede depender de una posici\u00f3n elevada, piedad o experiencia. Ad\u00e1n cay\u00f3 cuando todo era hermoso.<\/p>\n<p><strong>5. <\/strong>Revise su propia experiencia y vea la necesidad de vigilancia.<\/p>\n<p><strong><br \/>II. <\/strong>La naturaleza del deber impuesto.<\/p>\n<p><strong>1. <\/strong>Una profunda y permanente convicci\u00f3n de peligro.<\/p>\n<p><strong>2. <\/strong>Uso diligente de los medios se\u00f1alados. Evita todas las ocasiones de pecado; observa los comienzos del pecado; vigila tu pecado que te acosa; vigila tus pensamientos; vigila tu empresa; vigila tus actividades; velar en dependencia de Dios.<\/p>\n<p><strong><br \/>III. <\/strong>Las personas a las que deba exigirse especialmente este deber.<\/p>\n<p><strong>1. <\/strong>A los ministros ya todos los que ocupan cargos oficiales en la Iglesia de Dios.<\/p>\n<p><strong>2. <\/strong>Se aplica a los ancianos. No est\u00e1n fuera del alcance de la tentaci\u00f3n.<\/p>\n<p><strong>3. <\/strong>Se aplica a los j\u00f3venes.<\/p>\n<p><strong>4. <\/strong>Se aplica a los jefes de familia.<\/p>\n<p><strong><br \/>IV. <\/strong>Para hacer cumplir la observancia de este deber.<\/p>\n<p><strong>1. <\/strong>Piensa en la salvaci\u00f3n del alma.<\/p>\n<p><strong>2. <\/strong>Piensa en las consecuencias que se derivan del incumplimiento de este deber.<\/p>\n<p><strong>3. <\/strong>Piensa en la gloria de Dios. (<em>TH Walker.<\/em>)<\/p>\n<\/p>\n<p><strong>Vigila las ocasiones de pecado<\/strong><\/p>\n<p>Evita todas las ocasiones de pecado . Boston justamente comenta que, \u201ccomo quien lleva p\u00f3lvora no desear\u00eda estar donde vuelan las chispas, para no ser destruido; por lo tanto, debemos evitar cuidadosamente los lugares y la compa\u00f1\u00eda que pueden conducir al pecado\u201d. (<em>TH Walker.<\/em>)<\/p>\n<\/p>\n<p><strong>Mira los comienzos del pecado<\/strong><\/p>\n<p>Todos<em> <\/em>sin avanza a pasos r\u00e1pidos y seductores; y una vez cedida a su influencia, \u00bfqui\u00e9n puede determinar todas las posibles declinaciones de la rectitud que pueden seguir despu\u00e9s? En su primera aproximaci\u00f3n, puede parecer completamente inofensivo; puede que no sea m\u00e1s que un pensamiento. La chispa puede parecer inofensiva; pero encender\u00e1 una conflagraci\u00f3n que resistir\u00e1, por su violencia, la sabidur\u00eda y el poder unidos del hombre. La concha puede parecer insignificante, pero contiene una sustancia que, cuando madure, ser\u00e1 \u201cuna serpiente junto al camino, o una v\u00edbora junto al camino, que muerde el tal\u00f3n del caballo, de modo que el jinete cae hacia atr\u00e1s\u201d. El riachuelo que se desliza silenciosamente sobre el c\u00e9sped puede parecer trivial; pero multiplicar\u00e1 sus aguas, hasta que se burle del hombre que diga: \u201cAqu\u00ed se detendr\u00e1n tus ondas soberbias\u201d. (<em>TH Walker.<\/em>)<\/p>\n<\/p>\n<p><strong>La consideraci\u00f3n de Cristo por la debilidad de sus seguidores<\/strong><\/p>\n<p>Aplicando el sujetos a nosotros mismos.<\/p>\n<p><strong><br \/>I. <\/strong>\u00bfEst\u00e1 dispuesto el esp\u00edritu? \u00bfEstamos dispuestos, en el sentido de estar decididos y empe\u00f1ados en hacer la voluntad de Dios, siguiendo la santidad y mostrando simpat\u00eda por Cristo al llevar la cruz por Su causa? Sin embargo-<\/p>\n<p><strong><br \/>II. <\/strong>La carne puede ser d\u00e9bil.<\/p>\n<p><strong>1. <\/strong>En ejercicios religiosos.<\/p>\n<p><strong>2. <\/strong>En las tareas y deberes de nuestra vida cristiana.<\/p>\n<p><strong>3. <\/strong>Sobre todo en el sufrimiento y la prueba.<\/p>\n<p><strong><br \/>III. <\/strong>El consuelo y el uso de las palabras de gracia de Cristo para nosotros en tiempos como estos.<\/p>\n<p><strong>1. <\/strong>Es una palabra de disculpa amable.<\/p>\n<p><strong>2. <\/strong>Tiene un tono de advertencia.<\/p>\n<p><strong>3. <\/strong>Nuestro deber, por lo tanto, es hacer todo lo posible para mantenernos despiertos y mantener la comuni\u00f3n con nuestro Se\u00f1or. \u201cVelad y orad.\u201d<\/p>\n<p><strong><br \/>IV. <\/strong>Espere una vida mejor. (<em>TGHerren.<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mateo 26:40-45 Velad y orad, para que no entr\u00e9is en tentaci\u00f3n Advertencia cristiana Quien duerme por un cargador de p\u00f3lvora necesita cuidarse hasta de las chispas. Quien camina sobre hielo, que no vaya mirando las estrellas, sino que mire a sus pies, y cu\u00eddese de caer. \u201cVelad y orad, para que no entr\u00e9is en tentaci\u00f3n\u201d, &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-mateo-2640-45-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Mateo 26:40-45 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38881","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/38881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=38881"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/38881\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=38881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=38881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=38881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}