{"id":39128,"date":"2022-07-16T08:44:57","date_gmt":"2022-07-16T13:44:57","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-marcos-141-9-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:44:57","modified_gmt":"2022-07-16T13:44:57","slug":"estudio-biblico-de-marcos-141-9-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-marcos-141-9-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Marcos 14:1-9 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Mar 14:1-9<\/span><\/p>\n<p> <em>Y estando en Betania en casa de Sim\u00f3n el leproso.<\/em><\/p>\n<\/p>\n<p><strong>Trabajando para Cristo<\/strong><\/p>\n<p> El hogar de Mar\u00eda, Marta y L\u00e1zaro en Betania, a unas dos millas de Jerusal\u00e9n al otro lado del Monte de los Olivos, hab\u00eda sido el escenario de algunos de los momentos m\u00e1s tranquilos y felices de la vida de nuestro Se\u00f1or. Conocemos algo de la dulzura de un hogar tranquilo despu\u00e9s del trabajo y la ansiedad y la preocupaci\u00f3n: el trabajador lo sabe, el hombre de negocios lo sabe. Por lo tanto, podemos comprender cu\u00e1n tranquilas fueron para el Se\u00f1or Jes\u00fas, despu\u00e9s de aquellas escenas de ira que se hab\u00edan reunido alrededor de \u00c9l todo el d\u00eda en el templo, las noches tranquilas de esta semana en la casa de Betania. Hay dos cosas que debemos notar acerca de ese hogar mientras seguimos a Jes\u00fas all\u00ed.<\/p>\n<p><strong>I. <\/strong>Era un hogar de verdadero amor familiar, o Jes\u00fas no habr\u00eda buscado su refugio con tanta frecuencia como lo hizo. \u00a1Qu\u00e9 tiernos recuerdos se agolpan en torno a la infancia pasada en un hogar as\u00ed! \u00a1Qu\u00e9 anticipo del hogar m\u00e1s all\u00e1 de la tumba, el refugio donde estar\u00edamos!<\/p>\n<p><strong>II. <\/strong>Era un hogar donde Jes\u00fas siempre era un hu\u00e9sped bienvenido, donde era llamado en cada dificultad, donde era el Compa\u00f1ero, el Gu\u00eda y el Amigo familiar. \u00bfNuestras casas son as\u00ed? \u00bfSe siente y se reconoce como el Due\u00f1o de la casa? el Invitado invisible en cada comida? el Oidor invisible de toda conversaci\u00f3n? \u00bfSe pide Su bendici\u00f3n en cada comida, en cada empresa, en cada evento? Pero ahora, mientras estamos con Jes\u00fas en Betania, miren lo que le est\u00e1 haciendo una de las hermanas mientras se sienta a la mesa, ya sea en su propia casa, o en una de un tipo similar donde no se siente menos en casa. \u201cEntonces tom\u00f3 Mar\u00eda una libra de ung\u00fcento de nardo, muy costoso, y ungi\u00f3 los pies de Jes\u00fas\u201d. Amados, \u00bfno hay algo as\u00ed que podamos hacer por Jes\u00fas en esta Semana Santa? \u00bfNo hay algo que podamos traer y poner a Sus pies mientras velamos con \u00c9l durante las horas de Su Pasi\u00f3n? \u00bfAlgo que ser\u00e1 una prenda de nuestro amor, alg\u00fan pecado secreto al que realmente nos costar\u00eda algo renunciar? \u00bfY no podemos encontrar algo, tambi\u00e9n, en nuestra vida familiar, o en el papel que tenemos que desempe\u00f1ar en ella? \u00bfNo hay alg\u00fan nuevo punto de partida que podamos tomar por causa de Jes\u00fas, para hacer que nuestros hogares sean un poco menos indignos de ser Su morada? (<em>Henry S. Miles, MA<\/em>)<\/p>\n<\/p>\n<p><strong>Mar\u00eda ungiendo a Cristo<\/strong><\/p>\n<p>Lo que ella dice haber hecho. Este est\u00e1ndar para nuestro servicio es, como se percibe, a la vez estimulante y alentador. Es estimulante, porque nunca debemos pensar que hemos hecho lo suficiente mientras haya algo m\u00e1s que podamos hacer; y es alentador, porque nos dice que aunque podamos hacer muy poco, ese poco ser\u00e1 aceptado, m\u00e1s a\u00fan, considerado por nuestro bondadoso Maestro como suficiente. No debemos condenarnos a nosotros mismos, ni lamentarnos, porque no podemos hacer m\u00e1s. Pero algo m\u00e1s debe notarse aqu\u00ed.<\/p>\n<p><strong>I. <\/strong>Mary hizo m\u00e1s de lo que sab\u00eda que estaba haciendo. Es una circunstancia conmovedora, hermanos, que dondequiera que estuvo nuestro Se\u00f1or, y sin embargo ocupado, Su muerte parece haber estado siempre en Su mente. Estaba en Su mente aqu\u00ed en una comida social, y lo que deber\u00edamos haber llamado una feliz, con aquellos a quienes m\u00e1s amaba en la tierra a su alrededor, y con el amor de algunos de ellos hacia \u00c9l en el ejercicio m\u00e1s vivo. Es una verdad alentadora, hermanos, que nunca podremos medir el uso que un Salvador lleno de gracia puede dar a nuestras pobres obras. As\u00ed como sus designios en nuestras aflicciones a menudo son m\u00e1s profundos de lo que podemos penetrar, tambi\u00e9n lo son sus designios en los servicios a los que nos incita. Hacemos esto y hacemos aquello, y lamentamos que sea tan poco, y que de ello resulte tan poco bien para nuestros semejantes y tan poco honor para nuestro Dios; pero no sabemos qu\u00e9 resultar\u00e1 de ello. Esa cosita est\u00e1 en la mano de un Dios grande y omnipotente, <\/em>y Su brazo poderoso puede doblarla y girarla sin saber c\u00f3mo ni hacia d\u00f3nde.<\/p>\n<p><strong>II. <\/strong>Debemos preguntarnos ahora cu\u00e1les fueron probablemente los motivos de Mar\u00eda en este acto extraordinario.<\/p>\n<p><strong>1. <\/strong>Quiz\u00e1s el m\u00e1s fuerte de ellos fue un sentimiento de amor agradecido por su bendito Se\u00f1or. Acababa de resucitar a su hermano de entre los muertos; acababa de mostrar una simpat\u00eda y un afecto por s\u00ed misma y por Martha que bien podr\u00eda asombrarla; hab\u00eda puesto un honor en su familia que ella debe haber sentido que era abrumadoramente grande. \u201cGracias\u201d, tal vez dijo dentro de s\u00ed misma, \u201cno pude cuando sali\u00f3 L\u00e1zaro. No puedo ahora. Mi lengua no se mover\u00e1, y si lo hiciera, las palabras son demasiado pobres para agradecerle. \u00bfPero que puedo hacer? Los reyes y los grandes hombres a veces son ungidos en sus espl\u00e9ndidos banquetes. Mi Se\u00f1or estar\u00e1 en la fiesta de Sim\u00f3n. Ir\u00e9 y comprar\u00e9 el ung\u00fcento m\u00e1s precioso que ofrece Jerusal\u00e9n, y en esa fiesta lo ungir\u00e9. No ser\u00e1 nada para \u00c9l, pero si \u00c9l lo sufre, ser\u00e1 mucho para m\u00ed\u201d. Haz algo para demostrar que est\u00e1s agradecido por las bendiciones, aunque ese algo sea poco.<\/p>\n<p><strong>2. <\/strong>Mar\u00eda probablemente tambi\u00e9n fue influenciada por otro motivo: el deseo de honrar a Cristo. \u201cQue otros lo odien y lo desprecien\u201d, debe haber dicho, \u201cOh, por alguna oportunidad de mostrar c\u00f3mo lo honro\u201d. Es cosa f\u00e1cil, hermanos, honrar a Cristo cuando otros lo honran, pero el verdadero amor se deleita en honrarlo cuando nadie m\u00e1s lo har\u00e1.<\/p>\n<p><strong>III. <\/strong>Pasemos ahora al juicio que los hombres emitieron sobre la conducta de Mar\u00eda. Lo censuraron, y en\u00e9rgicamente. Los hombres generalmente se enfurecen por cualquier acto de amor por Cristo que se eleva por encima de su propia norma, por encima de sus propias ideas del amor que se le debe. Por lo general, tambi\u00e9n pueden encontrar algo en la conducta del cristiano afectuoso que d\u00e9 color a su descontento. \u201c\u00bfPor qu\u00e9 se hizo este desperdicio de ung\u00fcento?\u201d Era una pregunta plausible; parec\u00eda razonable. Y obs\u00e9rvese tambi\u00e9n que los hombres generalmente pueden asignar alg\u00fan buen motivo en s\u00ed mismos para censurar a los dem\u00e1s. Y observe, tambi\u00e9n, que los verdaderos disc\u00edpulos de Cristo a veces se unir\u00e1n a otros para censurar al cristiano celoso. \u201cHubo algunos que ten\u00edan indignaci\u00f3n\u201d. Pero una vez m\u00e1s, las censuras pasadas al siervo de Cristo tienen a menudo su origen en alg\u00fan hombre hip\u00f3crita y malo. \u00bfQui\u00e9n comenz\u00f3 esta cavilaci\u00f3n, esta murmuraci\u00f3n contra Mar\u00eda? Volvemos al Evangelio de San Juan, y nos dice que fue Judas-Judas Iscariote, el traidor. Rastree hasta su fuente las amargas censuras con las que muchos cristianos fieles son atacados por un tiempo, a menudo lo encontrar\u00e1 en la bajeza secreta e impensada de alg\u00fan hombre bajo e hip\u00f3crita.<\/p>\n<p><strong>IV. <\/strong>La historia ahora trae ante nosotros el aviso que nuestro Se\u00f1or tom\u00f3 de la conducta de esta mujer. \u00c9l, primero, lo reivindic\u00f3. Y observa c\u00f3mo \u00c9l vindica a Mar\u00eda, con una dulzura maravillosa hacia aquellos que la hab\u00edan culpado. La lecci\u00f3n pr\u00e1ctica es, hermanos, adorar al bendito Jes\u00fas por tomarnos a nosotros y a nuestra conducta bajo su protecci\u00f3n, y obrando por su gracia como \u00c9l quiere que nos sintamos seguros, y m\u00e1s que seguros, en sus manos. \u201cEl que os toca\u201d, dice, \u201ctoca la ni\u00f1a de Mi ojo\u201d. Pero esto no es todo: nuestro Salvador recompensa a esta mujer agradecida y la vindica. \u201cDondequiera\u201d, dice \u00c9l, \u201cque se predique este evangelio, en todo el mundo, tambi\u00e9n se hablar\u00e1 de lo que ella ha hecho, para memoria de ella\u201d. Nuestro Se\u00f1or hab\u00eda dicho mucho antes: \u201cBienaventurados ser\u00e9is cuando los hombres os injurien, y os persigan, y digan toda clase de mal contra vosotros con mentira, por causa de m\u00ed. Gozaos y alegraos mucho, porque grande es vuestra recompensa en los cielos.\u201d Pero aqu\u00ed \u00c9l anticipa esto; Hay una recompensa para esta mujer en la tierra, y una grande y grande. Y ahora, apart\u00e1ndonos de Mar\u00eda y de su conducta, pensemos en nosotros y en nuestra conducta. \u00bfQu\u00e9 hemos hecho por Cristo? \u201cLe amamos porque \u00c9l nos am\u00f3 primero\u201d: ah\u00ed est\u00e1 el secreto de la obediencia cristiana, la abnegaci\u00f3n cristiana, la devoci\u00f3n cristiana. (<em>C. Bradley, MA<\/em>)<\/p>\n<\/p>\n<p><strong>La caja de pomada<\/strong><\/p>\n<p><strong>I .<\/strong><strong><em> <\/em><\/strong>La naturaleza del acto. Fue hecho para Cristo. Fue inspirado por un sentimiento correcto. Si le damos todo lo que poseemos a Cristo, todav\u00eda es menos de lo que \u00c9l merece. Su pesar no es que haya dado tanto, sino tan poco.<\/p>\n<p><strong>II. <\/strong>Las lecciones. Una acci\u00f3n es precisamente del valor del motivo por el cual ha sido accionada. Adem\u00e1s, debemos tener en cuenta la diferencia de posiciones y tendencias mentales. La buena intenci\u00f3n, que no es otra cosa que el amor, puede enga\u00f1arse a s\u00ed misma, sin duda, pero no siempre se enga\u00f1a a s\u00ed misma. En la llama divina que enciende el Esp\u00edritu, la luz es inseparable del calor. El que busca hacer la voluntad de Dios conocer\u00e1 la mente de Dios. Incluso al dar a los pobres es posible cometer errores graves. La verdadera caridad no abre el coraz\u00f3n sin expandir la mente. (<em>Alexander Finer, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Un memorial de mujer<\/strong><\/p>\n<p>Exhibe bien, en un \u00fanica ilustraci\u00f3n, la conveniencia, el motivo, la medida y la recompensa del celo cristiano (<span class='bible'>Mar 14:3-9<\/span>) .<\/p>\n<p><strong>Yo. <\/strong>Partimos de un reconocimiento, por nuestra parte, de una regla de actividad establecida. Se espera que todos los amigos de Cristo hagan algo por \u00c9l.<\/p>\n<p><strong>1. <\/strong>El trabajo y el sacrificio no est\u00e1n re\u00f1idos ni con la m\u00e1s alta espiritualidad, leer esta es la misma Mar\u00eda cuya otra historia nos es tan familiar a todos. Ella era la que se sentaba a los pies de Jes\u00fas (<span class='bible'>Luk 10,39<\/span>) en toda la quietud serena de la comuni\u00f3n con su Se\u00f1or; sin embargo, ahora, \u00bfqui\u00e9n dir\u00eda que Mar\u00eda a la cabeza del Maestro podr\u00eda no ser un tema tan bueno para el l\u00e1piz del artista? La piedad es pr\u00e1ctica, y la piedad pr\u00e1ctica no es menos pintoresca y atractiva porque en tal caso se haya vuelto demostrativa.<\/p>\n<p><strong>2. <\/strong>Nuestro Se\u00f1or siempre necesit\u00f3 ayuda mientras estuvo en la tierra. Entre aquellos a quienes hab\u00eda ayudado hab\u00eda mujeres ricas, de cuyas generosas manos recibi\u00f3 dinero (<span class='bible'>Lc 8,2-3<\/span>) . Y Su causa necesita ayuda ahora.<\/p>\n<p><strong>3. <\/strong>Es una mera tentaci\u00f3n del diablo afirmar que la obra de uno por Jesucristo est\u00e1 viciada por la alegr\u00eda plena que siente en ella un alma amorosa. Algunos creyentes t\u00edmidos y desconfiados de s\u00ed mismos tropiezan con el temor de que sus sacrificios por nuestro bendito Maestro no tengan m\u00e9rito porque disfrutan haci\u00e9ndolos. Sol\u00eda ensayarse una vieja leyenda de una anciana profetisa que pasaba entre la multitud con un incensario de fuego en una mano y un c\u00e1ntaro de agua en la otra. Cuando se le pregunt\u00f3 por qu\u00e9 llevaba una carga tan singular, respondi\u00f3: \u00abEste fuego es para quemar el cielo y esta agua para apagar el infierno: para que los hombres puedan servir a Dios en lo sucesivo sin deseo de recompensa ni temor de retribuci\u00f3n\u00bb. Tal discurso puede parecer apropiado para la expresi\u00f3n de un mero devoto; pero no hay justificaci\u00f3n para algo as\u00ed en la Biblia. Se ofrece el cielo para alentarnos en el celo (<span class='bible'>Rom 2,7<\/span>). A menudo se exhibe el infierno para que se le tema (<span class='bible'>Mateo 10:28<\/span>).<\/p>\n<p><strong>II. <\/strong>Adem\u00e1s, la historia de esta caja de alabastro sugiere una lecci\u00f3n sobre el motivo que subyace a toda verdadera actividad cristiana.<\/p>\n<p><strong>1. <\/strong>En el caso de esta mujer, se nos dice que su acci\u00f3n surgi\u00f3 de su agradecido afecto por su Se\u00f1or. Cada gesto muestra su ternura; ella le sec\u00f3 los pies con su propio cabello (<span class='bible'>Juan 12:3<\/span>). Esto fue lo que le dio a su oferta su valor supremo.<\/p>\n<p><strong>2. <\/strong>Aqu\u00ed radica el principio que tiene la aplicaci\u00f3n m\u00e1s amplia para todas las edades. No es tanto lo que hacemos por nuestro Salvador, ni la forma en que lo hacemos, sino el sentimiento que nos impulsa a hacer cualquier cosa que reciba Su bienvenida. Es el afecto que impregna el celo lo que hace que el celo sea precioso.<\/p>\n<p><strong>3. <\/strong>Se puede esperar que la bondad que procede del amor puro a veces encuentre una mala interpretaci\u00f3n. A los que miran el celo mucho m\u00e1s all\u00e1 del suyo propio en el afecto desinteresado, con frecuencia se les escuchar\u00e1 emitir juicios err\u00f3neos poco caritativos al respecto. Encontramos (<span class='bible'>Juan 12:4-6<\/span>) que fue solo Judas Iscariote despu\u00e9s de todo, en esta ocasi\u00f3n, quien tom\u00f3 la plomo en asignar motivos equivocados a la mujer, y \u00e9l no se preocup\u00f3 tanto por los pobres como por su propia bolsa de tesoros. No importa cu\u00e1nto se burlen de nuestros humildes esfuerzos por honrar a nuestro Se\u00f1or Jes\u00fas, ser\u00e1 \u00fatil recordar que \u00c9l los aprecia plenamente.<\/p>\n<p><strong>4. <\/strong>Este es el principio que eleva y ennoblece incluso el celo com\u00fan Cuando el amor verdadero y honesto es el motivo, \u00bfno estamos todos de acuerdo en que son los peque\u00f1os servicios m\u00e1s que los grandes esfuerzos conspicuos los que tocan el coraz\u00f3n de quien los recibe? Cuanto m\u00e1s desapercibidas a todos los ojos menos a los nuestros, m\u00e1s queridas son las miradas de ternura que recibimos. Es la delicadeza, no el volumen, de la amabilidad lo que constituye su encanto.<\/p>\n<p><strong>IV. <\/strong>La lecci\u00f3n final de esta historia se refiere a la recompensa del celo cristiano. Nunca se pronunci\u00f3 mayor elogio que el que esta mujer recibi\u00f3 del Maestro.<\/p>\n<p><strong>1. <\/strong>Fue Jes\u00fas quien dio la aprobaci\u00f3n. \u00a1Componga eso en contra de la cr\u00edtica de Judas! Si cumplimos con nuestro deber, tenemos derecho a apelar a cualquiera que se queje. Cuando Cristo justifica, \u00bfqui\u00e9n es el que condena? Algunos de nosotros hemos le\u00eddo sobre el antiguo orador cl\u00e1sico que, sin tener favor en el teatro, entraba en el templo y gesticulaba ante las estatuas de los dioses; dijo que lo entend\u00edan mejor. As\u00ed los creyentes calumniados pueden retirarse del mundo que los juzga mal y consolarse con el reconocimiento de Jes\u00fas.<\/p>\n<p><strong>2. <\/strong>Jes\u00fas dijo que esta mujer deber\u00eda ser recordada ampliamente, dondequiera que vaya el evangelio. Los hombres saben lo que es bueno y est\u00e1 bien cuando lo ven. Y est\u00e1n listos para elogiarlo. Incluso Lord Byron tuvo el ingenio suficiente para ver que-<\/p>\n<p>\u201cEl secado de una sola l\u00e1grima tiene m\u00e1s<\/p>\n<p>De fama honesta, que derramar mares de sangre.\u201d<\/p>\n<p> &gt;Algunas de las vidas m\u00e1s grandiosas de la historia han tenido poco espect\u00e1culo que hacer. Mujeres cargadas de cuidados, inv\u00e1lidos en los lechos, hijos del trabajo mal vestidos y mal alimentados, sirvientas, sirvientes, aprendices y jornaleros con pocas horas libres, corazones t\u00edmidos, mentes sin educaci\u00f3n, marineros retenidos en barcos, soldados retenidos en guarniciones: estos , con pocas posibilidades, han hecho tal servicio que el mundo los recuerda con su m\u00e1s amplio renombre (<span class='bible'>Sal 112:5-6<\/a>).<\/p>\n<p><strong>3. <\/strong>Fue precisamente esta par\u00e1bola de Jes\u00fas la que se convirti\u00f3 en el memorial de Mar\u00eda. Una palabra a veces dura m\u00e1s que una losa de m\u00e1rmol. Debemos aprender a contentarnos con la aprobaci\u00f3n de Dios y de nuestra propia conciencia. Nunca se olvidar\u00e1 nada que valga la pena registrar en el libro de Dios. Aquellos que mueren en el Se\u00f1or encontrar\u00e1n que sus obras los siguen, y la fama digna queda atr\u00e1s: \u201cLa memoria de los justos es bendita; pero el nombre de los imp\u00edos se pudrir\u00e1.\u201d S\u00f3lo debemos recordar que s\u00f3lo el amor da car\u00e1cter y valor a todo celo. Ese fue un comentario muy sugerente del viejo Tom\u00e1s de Kempis: \u201cMucho hace quien mucho ama; y tambi\u00e9n hace mucho el que hace el bien.\u201d (<em>CS Robinson, DD<\/em>)<\/p>\n<\/p>\n<p><strong>El sacrificio del amor<\/strong><\/p>\n<p><strong>I. <\/strong><strong><em> <\/em><\/strong>El sacrificio del amor. Observa-<\/p>\n<p><strong>1. <\/strong>Lo que Mar\u00eda dio. El alabastro de ung\u00fcento precioso y perfumado. Raro y costoso. El amor no mide su ofrenda por una mera utilidad; ni por reclamaci\u00f3n judicial.<\/p>\n<p><strong>2. <\/strong>Lo que hizo Mar\u00eda. Ungido con este precioso ung\u00fcento. Las cosas dignas de nuestros usos m\u00e1s altos son honradas cuando se usan en los usos m\u00e1s bajos de la religi\u00f3n. Lo que es digno de nuestra cabeza, honrado al ser puesto a los pies del Maestro.<\/p>\n<p><strong>II. <\/strong>La reprensi\u00f3n de la codicia. La cr\u00edtica de Judas.<\/p>\n<p><strong>1. <\/strong>\u00a1Desperdicio! porque su plan no fue adoptado. No pensaba en el bien que se hac\u00eda, sino en lo que se pod\u00eda haber hecho.<\/p>\n<p><strong>2. <\/strong>Ten\u00eda una excusa. \u00a1Los pobres! Era de los que siempre est\u00e1n \u201cmirando a casa\u201d; que lo hacen con los ojos cerrados; que ven poco y hacen menos.<\/p>\n<p><strong>III. <\/strong>El argumento de la sabidur\u00eda.<\/p>\n<p><strong>1. <\/strong>No estar\u00e9 aqu\u00ed mucho tiempo. Jes\u00fas no est\u00e1 mucho -en esta vida- con ninguno de nosotros. Hagamos mucho de este invitado. Hacer lo que podamos ahora.<\/p>\n<p><strong>2. <\/strong>Siempre tendr\u00e1s a los pobres. A estos Jes\u00fas amaba y escuchaba. Este legado no fue olvidado (<span class='bible'>Hch 4:31-37<\/span>). Tampoco se olvida a los espiritualmente pobres.<\/p>\n<p>Aprenda-<\/p>\n<p><strong>1. <\/strong>Amar a Jes\u00fas y demostrarlo.<\/p>\n<p><strong>2. <\/strong>Que ning\u00fan don consagrado a Jes\u00fas sea desperdiciado.<\/p>\n<p><strong>3. <\/strong>El mejor regalo es un coraz\u00f3n quebrantado, cuyo perfume de penitencia y fe es agradable al Se\u00f1or. (<em>JC Gray.<\/em>)<\/p>\n<\/p>\n<p><strong>Profusi\u00f3n, no desperdicio<\/strong><\/p>\n<p><strong>I. <\/strong>Un motivo. Mary sin duda ten\u00eda buenas intenciones. Su correcta intenci\u00f3n dif\u00edcilmente habr\u00eda sido cuestionada por los mismos disc\u00edpulos que murmuraban. Cualquier cosa que se pueda decir de su trabajo, nada se puede decir de su motivo sino que fue pura y completamente bueno. Ahora bien, el motivo es de primera importancia en la estimaci\u00f3n que hacemos de cualquier acto, peque\u00f1o o grande. Debe haber un motivo de alg\u00fan tipo, o el acto no puede ser moral; se vuelve meramente mec\u00e1nico. El motivo tambi\u00e9n debe ser bueno, o el acto no puede ser sino malo. Sin embargo, no es necesario que lo parezca, y con frecuencia no lo es. Las palabras no son necesariamente el ropaje de la verdad, ni las apariencias los signos y prendas de realidades correspondientes. Por muy bueno que sea el motivo, no se sigue que el acto como tal sea igualmente bueno. Es decir, puede haber algo m\u00e1s y superior en el motivo de lo que aparece en el acto. Esto puede surgir de la ignorancia, de no saber c\u00f3mo hacer mejor el acto; o puede resultar de la naturaleza del acto mismo, siendo esencialmente humilde y com\u00fan. Pero una causa m\u00e1s profunda se encuentra en nuestra incapacidad para hacer lo que quisi\u00e9ramos. Parece que hacemos lo mejor que podemos, ponemos y esforzamos nuestros recursos al m\u00e1ximo y, sin embargo, despu\u00e9s de todo, nos quedamos cortos, ya veces tristemente cortos, de nuestros deseos y esperanzas preconcebidas. Sin embargo, hay otro lado m\u00e1s brillante de esto. Nuestro trabajo no se considera absolutamente en s\u00ed mismo. El motivo que la inspira cuenta algo, puede serlo mucho.<\/p>\n<p><strong>II. <\/strong>Del motivo de este acto pasemos al acto mismo, con especial referencia a la impresi\u00f3n que produce en quienes lo presencian. Mar\u00eda ten\u00eda buenas intenciones, ya lo he dicho: ella tambi\u00e9n lo hizo ciertamente bien. Esto se desprende en parte de lo que ya se ha dicho, pero el hecho merece y compensar\u00e1 a\u00fan m\u00e1s exposici\u00f3n. \u201cHizo lo que pudo\u201d, es el testimonio dado por el Salvador mismo acerca de su conducta, que por s\u00ed solos eran suficientes elogios, ya que implica que ella hab\u00eda actuado en toda la medida de su capacidad. Pero a esto a\u00f1ade: \u201cBuena obra ha hecho en m\u00ed\u201d, ampliando y realzando as\u00ed grandemente el elogio, especialmente porque el t\u00e9rmino traducido \u201cbueno\u201d significa lo que es noble y hermoso. Su obra fue, pues, buena porque fue el desbordamiento espont\u00e1neo de un afecto profundamente agradecido por la restituci\u00f3n de su hermano L\u00e1zaro a la vida. Fue as\u00ed bueno porque fue en efecto un acto de completo abandono y entrega amorosa de todo su ser a Cristo como su \u00fanico Salvador. Sin duda hubo algo extraordinario en la forma que tom\u00f3 esta declaraci\u00f3n; pero entonces hab\u00eda algo extraordinario en la sensibilidad de la naturaleza de Mar\u00eda. Pero si Judas fue el primero y el jefe, pronto fue seguido por otros; porque el mal es igualmente contagioso y confederado. Quejarse es f\u00e1cil, y tambi\u00e9n contagioso, ya menudo algunos lo practican como si fuera una virtud. F\u00edjate, entonces, en la respuesta de nuestro Se\u00f1or a su protesta com\u00fan: \u201cD\u00e9jala en paz; \u00bfPor qu\u00e9 la molest\u00e1is? etc. Una econom\u00eda restrictiva, virtualmente nos dice, una utilidad desnuda y r\u00edgida no es en ning\u00fan momento la caracter\u00edstica distintiva de lo m\u00e1s puro y noble en la conducta humana. La utilidad tiene su propia esfera. La econom\u00eda es un deber aun cuando no sea una necesidad. Pero hay regiones enteras del pensamiento y de la acci\u00f3n en las que ni el uno ni el otro pueden entrar o, al entrar, pueden reinar solos. Debe haber belleza adem\u00e1s de utilidad, debe haber generosidad adem\u00e1s de econom\u00eda, debe haber esplendor, magnificencia, profusi\u00f3n, incluso aparente derroche, o la vida humana perder\u00e1 gran parte de su encanto. La misma profusi\u00f3n se ve en la Palabra de Dios como en Sus obras. \u00bfSer\u00e1n entonces los hombres, en el servicio de la fe y la piedad, tan diferentes a Dios como para confinarse dentro del estrecho margen de una econom\u00eda definida, o sujetarse a las exigencias estrictas y positivas de una utilidad rigurosa? \u00bfEs esto lo que hacen con respecto a cualquier otro tipo de servicio y con referencia a intereses que son puramente seculares y materiales? \u00bfSe llamar\u00e1 desperdicio por amor vehemente y abnegado derramar perfumes costosos sobre la cabeza y los pies de un Redentor adorado, y sin embargo no consumirlos diariamente en la gratificaci\u00f3n de un sentido corporal? Nadie inspirado s\u00f3lo por lo que se llama el \u201centusiasmo de la humanidad\u201d lo dir\u00e1. Menos a\u00fan lo har\u00e1 cualquiera que pueda profesar en las palabras del ap\u00f3stol, como dando el principio animador e impulsor de toda su vida, \u00abEl amor de Cristo me constri\u00f1e\u00bb. Pero, en verdad, la utilidad tiene un \u00e1mbito mucho m\u00e1s amplio de lo que habitualmente se le asigna. Esa no es la \u00fanica cosa \u00fatil que simplemente ayuda a un hombre a existir; ni es, visto comparativamente con otras cosas, ni siquiera lo m\u00e1s \u00fatil. El mismo principio se aplica a la fe y al amor, especialmente a este \u00faltimo; mientras que de este \u00faltimo se puede decir adem\u00e1s que su utilidad es mayor cuando la utilidad es el motivo menor para su ejercicio. No es amor el que mira directamente al provecho personal, y sabe regular su fervor por consideraciones prudenciales de ganancia y p\u00e9rdida.<\/p>\n<p><strong>III. <\/strong>Recompensa de Mar\u00eda.<\/p>\n<p><strong>1. <\/strong>Cristo reivindic\u00f3 su conducta frente a las airadas quejas de sus disc\u00edpulos.<\/p>\n<p><strong>2. <\/strong>\u00c9l hizo m\u00e1s: acept\u00f3 y elogi\u00f3 su trabajo como \u201cbueno\u201d, como verdadera y noblemente hermoso. Esto en s\u00ed mismo ser\u00eda suficiente recompensa para ella. No pod\u00eda ni desear\u00eda nada m\u00e1s ni nada mejor. \u00bfQu\u00e9 m\u00e1s y mejor, en efecto, se puede desear, para cualquier obra, que el aplauso \u201cbien hecho\u201d de Jes\u00fas?<\/p>\n<p><strong>3. <\/strong>A\u00fan m\u00e1s hab\u00eda en su caso. Recibi\u00f3 la seguridad de una reputaci\u00f3n y un honor eternos. Aqu\u00ed hab\u00eda una distinci\u00f3n maravillosa e inigualable, a ning\u00fan acto de criatura meramente humana se le prometi\u00f3 jam\u00e1s un renombre tan grande. Y aunque este renombre podr\u00eda por s\u00ed solo a\u00f1adir muy poco a su futura felicidad, sin embargo, la promesa de ello, como indicaci\u00f3n de lo que el Salvador pensaba de su obra, debe haber sido para ella una fuente profunda e inagotable de la m\u00e1s santa satisfacci\u00f3n y deleite. Por supuesto, nada de este tipo es posible para nosotros; ni es necesario que lo deseemos. Sin embargo, podemos aprender de ella, o m\u00e1s bien de ambas formas de la recompensa de Mar\u00eda combinadas, que todo lo que se haga por Cristo no ser\u00e1 en vano, ni siquiera para nosotros.<\/p>\n<p><strong>4. <\/strong>Con una graciosa recompensa, tambi\u00e9n hubo un resultado natural. \u201cLa casa\u201d, dice un evangelista, \u201cse llen\u00f3 del olor del ung\u00fcento\u201d. Mar\u00eda logr\u00f3 m\u00e1s de lo que pretend\u00eda, ungiendo no solo a Jes\u00fas, sino a todos los que estaban con \u00c9l, e incluso a la casa misma. El hecho es muy sugerente, d\u00e1ndonos al mismo tiempo una lecci\u00f3n tanto de amonestaci\u00f3n como de aliento. La continuidad y la difusi\u00f3n marcan todo lo que hacemos. El pensamiento es estupendamente solemne, y debe ser puesto solemnemente en el coraz\u00f3n. Es uno para inspirarnos una esperanza gozosa, o para llenarnos de una terrible consternaci\u00f3n. (<em>Prof. J. Stacey, DD<\/em>)<\/p>\n<\/p>\n<p><strong>El jarr\u00f3n roto<\/strong><\/p>\n<p>La cari\u00f1osa Mar\u00eda , en la devota prodigalidad de su amor, dio, no una parte, sino la totalidad de los preciosos contenidos, y no perdon\u00f3 el vaso mismo, en el que estaban, y que fue roto en el servicio de Cristo. Ella dio todo a Cristo, y s\u00f3lo a \u00c9l. As\u00ed tambi\u00e9n ella cuid\u00f3, en su reverencia a Cristo, que el nardo y la vasija (cosas de precioso valor, y de uso frecuente en los banquetes y placeres festivos de este mundo para la gratificaci\u00f3n y el lujo del hombre) ahora se usaron para este servicio sagrado. de ungir el cuerpo de Cristo, nunca debe aplicarse a ning\u00fan otro prop\u00f3sito menos santo. Este acto de Mar\u00eda, siempre que lo que as\u00ed ha sido consagrado a la unci\u00f3n del cuerpo de Cristo, nunca se emplee despu\u00e9s en usos seculares, es ejemplar para nosotros; y el mismo esp\u00edritu de reverencia parece haber guiado a la Iglesia al apartar de todo uso profano y com\u00fan, por consagraci\u00f3n, lugares y cosas para el servicio del cuerpo m\u00edstico de Cristo, y para el entretenimiento de Su presencia; y este mismo esp\u00edritu reverencial parece animarla tambi\u00e9n a consumir en la Mesa del Se\u00f1or lo que queda de los elementos consagrados en la Comuni\u00f3n de Su Cuerpo y Sangre. (<em>Obispo Christopher Wordsworth.<\/em>)<\/p>\n<\/p>\n<p><strong>Ofrendas costosas aceptables para Dios<\/strong><\/p>\n<p>Solo hay una principio que recorre toda la ense\u00f1anza de los dos Testamentos acerca de lo que los hombres hacen por su Hacedor, y es que Dios no quiere, y no puede sino estimar a la ligera lo que no nos cuesta nada, y que el valor de cualquier servicio o sacrificio que que rendimos por Su causa, es que cualquiera que sea su mezquindad o miseria intr\u00ednseca, es, como de nosotros, lo mejor que tenemos, no dado a la ligera, a bajo precio o sin pensar, sino con cuidado y costo y crucifixi\u00f3n de nuestra autocomplacencia; y luego nuevamente, que son tales dones, ya sean el adorno del templo o la caja de alabastro, que estos son dones en los que Dios se deleita por igual y siempre. (<em>Obispo HC Potter.<\/em>) <\/p>\n<\/p>\n<p><strong>Cosas rotas \u00fatiles a Dios<\/strong><\/p>\n<p>De grano molido se alimenta el hombre; es por las plantas magulladas que recupera la salud. Gede\u00f3n triunf\u00f3 gracias a los c\u00e1ntaros rotos; fue de un tonel desperdiciado y de una vasija vac\u00eda que se sustent\u00f3 el profeta; fue sobre tablas y pedazos rotos de la nave que se salvaron Pablo y sus compa\u00f1eros. Fue en medio de los fragmentos de la humanidad rota que se dio la promesa de una vida superior; aunque ning\u00fan hueso de \u00c9l fue quebrado, sin embargo, es por la vida quebrantada de Cristo que Su pueblo vivir\u00e1 eternamente; fue por la dispersi\u00f3n de los jud\u00edos que los gentiles fueron tra\u00eddos; fue por los cuerpos magullados y desgarrados de los santos que la verdad triunf\u00f3 de tal manera que se convirti\u00f3 en un dicho, que \u00abla sangre de los m\u00e1rtires es la semilla de la Iglesia\u00bb. Es por esta caja rota, que por todo el ancho mundo se proclama cu\u00e1n bendito y glorioso es hacer todo por Cristo. Cuando se conozca la verdadera historia de todas las cosas, entonces se ver\u00e1 cu\u00e1n preciosas a los ojos de Dios, cu\u00e1n poderosas fueron en Sus manos muchas cosas rotas. Se hallar\u00e1 que las esperanzas terrenales rotas han sido necesarias para traer la mejor esperanza que permanece para siempre. Se encontrar\u00e1 que las constituciones corporales rotas han sido necesarias en algunos casos para alcanzar esa tierra donde el cuerpo estar\u00e1 cansado y dolorido nunca m\u00e1s; fortunas terrenales rotas, para ganar la riqueza m\u00e1s all\u00e1 del alcance del \u00f3xido, la polilla y el ladr\u00f3n; honor terrenal quebrantado, al ser coronado con la diadema que no se desvanece. \u00a1S\u00ed! incluso para lo que tenemos que lograr aqu\u00ed, a menudo es necesario que seamos quebrantados en la impotencia personal antes de que podamos lograr algo; para que la excelencia del poder no sea del hombre sino de Dios. Es por un cauce estropeado y, dir\u00edamos, sin valor, por donde corre el precioso ung\u00fcento. Por lo tanto, cuando alguien del pueblo de Dios sea quebrantado y estropeado, que piense en esta caja rota, y c\u00f3mo de ella fluy\u00f3 el ung\u00fcento que ungi\u00f3 a Jes\u00fas para Su sepultura, y c\u00f3mo proporcion\u00f3 los materiales para la historia que todo evangelio debe contar. . (<em>PB Power.<\/em>)<\/p>\n<\/p>\n<p><strong>Ella rompi\u00f3 la caja<\/strong><\/p>\n<p>Si se necesitaban reliquias para el instrucci\u00f3n de la Iglesia de Dios, bien podemos comprender c\u00f3mo entre los m\u00e1s selectos de ellos se encontrar\u00edan los restos de esta caja de alabastro. Esta vasija rota no s\u00f3lo ser\u00eda un monumento de amor, sino un predicador de variada elocuencia; a la vez pat\u00e9tico y pr\u00e1ctico, tierno y hasta severo; apelando al sentimiento y, sin embargo, tronando contra el mero sentimentalismo; sus bordes dentados predicando \u201chechos\u201d en este mundo que los hombres siempre nos dicen que es un mundo de hechos; y diciendo: \u201cLa religi\u00f3n es un hecho-hecho de Dios al hombre, y de nuevo del hombre a Dios\u201d. Puede ser que, al estudiar estos pobres fragmentos del pasado, nuestras mentes pasen de las severas ense\u00f1anzas de esos bordes dentados al dulce aroma que se difundi\u00f3 de ellos; y as\u00ed, impalpables e invisibles como ese olor, los pensamientos de dulce sabor podr\u00edan infiltrarse en los rincones secretos de nuestro ser, y podr\u00edamos ser ganados para una acci\u00f3n m\u00e1s decidida para nuestro Se\u00f1or. Podemos entender la vasija rota siendo llevada a la bolsa, la casa de contabilidad y la tienda, y un hombre retrocediendo ante ella al escuchar su historia, y otro derramando su oro cuando su profundidad y poder penetraron profundamente en su alma. Podemos imagin\u00e1rnoslo sobre la mesa del fil\u00f3sofo, como con su l\u00e1mpara de medianoche al lado, \u00e9l se sienta a contemplarlo con las manos extendidas sobre las sienes, y se levanta de su estudio fr\u00edo y profano, incapaz de entender por qu\u00e9 la mujer hizo esto. hecho, y por qu\u00e9 ahora alguien deber\u00eda ser llamado a hacer algo similar; y podemos imaginarlo ahora cautivando con su forma rota, ahora seduciendo incluso con el recuerdo de su perfume, alg\u00fan intelecto fuerte, que anhela conocer la realidad de las cosas, y se inclina ante la majestad y la sustancia del amor verdadero tal como se ofrece y acepta aqu\u00ed. . Podemos entender c\u00f3mo har\u00eda de \u00e9ste un misionero, cuyas obras ser\u00edan conocidas por todos, y de otro por causa de Cristo, un solitario vigilante de medianoche de los enfermos, cuyas obras no ser\u00edan conocidas por nadie, desde la luz del amor que brilla de esta vasija rota, mientras las l\u00e1mparas brillaban en los c\u00e1ntaros rotos de Gede\u00f3n, podemos ver a miles huyendo, como los murci\u00e9lagos y las lechuzas ante el sol de la ma\u00f1ana; y otros, abri\u00e9ndose y expandi\u00e9ndose como las flores que florecen y perfuman. Si fueran necesarias reliquias para la conversi\u00f3n del hombre de su ego\u00edsmo, de su tibieza, de su ignorancia del poder del amor, primero sobre todas las cosas llevar\u00edamos por el mundo la cruz del calvario y su corona de espinas, y junto a ellas este alabastro caja. (<em>PB Power.<\/em>)<\/p>\n<\/p>\n<p><strong>Unci\u00f3n<\/strong><\/p>\n<p>La unci\u00f3n se empleaba en Oriente para varios prop\u00f3sitos : primero, por placer, siendo un gran lujo en aquel clima; y los ung\u00fcentos se preparaban a partir de aceites con gran dificultad. Representaban la mejor fragancia que se pod\u00eda componer. Fueron utilizados por una persona sobre s\u00ed misma; y fue un acto significativo de estima cuando un ung\u00fcento fue presentado de amigo a amigo. Los ung\u00fcentos tambi\u00e9n se usaban en la coronaci\u00f3n y ordenaci\u00f3n de reyes y sacerdotes; y as\u00ed llegaron a significar sacralidad a trav\u00e9s de la reverencia. Los ung\u00fcentos se usaron adem\u00e1s en el entierro de los muertos, y as\u00ed llegaron a significar el dolor del amor. Pero en todos los casos, ya sea por regalos, por placer, o por usos sagrados de consagraci\u00f3n o entierro, no era el valor intr\u00ednseco del ung\u00fcento, sino el pensamiento que lo acompa\u00f1aba, lo que le daba significado. Representaba el sentimiento profundo del coraz\u00f3n, la lealtad; profunda consagraci\u00f3n religiosa; pena y esperanza. Estos diversos sentimientos, a los que se les concede muy poca expresi\u00f3n, eligen s\u00edmbolos; y estos s\u00edmbolos casi pierden su significado original y toman este segundo significado atributivo. (<em>HW Beecher.<\/em>)<\/p>\n<\/p>\n<p><strong>Una caja de alabastro de ung\u00fcento: el regalo de Mar\u00eda<\/strong><\/p>\n<p>En climas donde la piel se pone febril con el polvo, el uso de aceite para ungir a la persona es todav\u00eda una pr\u00e1ctica com\u00fan. Es as\u00ed en la India; as\u00ed fue en la antigua Grecia y Roma. Mantiene la piel fresca y la calma, y se considera saludable. En climas m\u00e1s c\u00e1lidos, los sentidos son m\u00e1s delicados y los olores a menudo m\u00e1s fuertes y desagradables, por lo que los olores dulces tienen una gran demanda. En Egipto hoy en d\u00eda, los invitados ser\u00edan perfumados al ser fumigados con un incienso fragante; y como las especias todav\u00eda se usan para dar al aliento, a la piel, a las vestiduras, un olor agradable, as\u00ed era entonces. En cualquier casa, el Salvador habr\u00eda tenido Su cabeza ungida con aceite. Era como el lavatorio de los pies, un refrigerio. En la India, estas unciones con aceites fragantes y perfumes se practican mucho despu\u00e9s del ba\u00f1o, y especialmente en las fiestas y bodas, de modo que el acto de Mar\u00eda no fue algo vergonzoso y peculiar, sino solo la forma m\u00e1s alta de un servicio esperado y bienvenido. Pero, en lugar de la unci\u00f3n con aceite, que probablemente habr\u00eda costado menos que el \u00f3bolo de la viuda, ella ha provisto un rico aceite de unci\u00f3n. Judas estim\u00f3 su valor en trescientos peniques; Plinio dice que generalmente se vend\u00eda a trescientos peniques la libra de doce onzas. Era algo del mismo tipo que el aceite de rosas; hecho principalmente recolectando el aceite esencial de las hojas de una planta india, el nardo, descrito por Diosc\u00f3rides, hace 1.800 a\u00f1os, que crece en el Himalaya, y todav\u00eda se encuentra all\u00ed, y se usa hoy en d\u00eda en la preparaci\u00f3n de perfumes costosos. Excepto en gotas, por supuesto, solo lo usaban los reyes y las clases m\u00e1s ricas; fue lo suficientemente costoso como para ser un regalo real. Trescientos peniques valdr\u00edan tanto en esas arcillas como 60 libras esterlinas en Inglaterra hoy. Mar\u00eda debe haber sido una mujer de bienes para poder traer tal aceite de santa unci\u00f3n; a menos que, como es igualmente probable, esta cantidad fuera el total de sus humildes ahorros, y ella con su regalo real, como la viuda con su humilde ofrenda, da todo lo que ten\u00eda. Si no hay nadie m\u00e1s que lo unja, ella no permitir\u00e1 que a Su sagrada cabeza le falte el honor que puede traer. Y si algunos lo rechazan, les aclarar\u00e1 que para hacerle el menor y m\u00e1s transitorio honor vale, a su juicio, el sacrificio de todo lo que tiene. Y as\u00ed, con maravillosa prodigalidad de amor generoso, compra y trae a la fiesta el costoso ung\u00fcento. Est\u00e1 encerrado en un jarr\u00f3n o ampolla de alabastro, como algunos que se pueden ver hoy en el Museo Brit\u00e1nico, con miles de a\u00f1os de antig\u00fcedad, y no muy diferente de los jarrones de alabastro que todav\u00eda se fabrican en grandes cantidades y se venden en jugueter\u00edas y ferias por un precio de pocos peniques; la blandura de la piedra permit\u00eda entonces, como ahora, tornearla f\u00e1cilmente en un torno. (<em>R. Glover.<\/em>)<\/p>\n<\/p>\n<p>No hay una palabra para \u201ccaja\u201d en el original; y no hay raz\u00f3n para suponer que el recipiente en el que estaba contenido el perfume ser\u00eda de la naturaleza o forma de una caja. Sin duda, las damas utilizar\u00edan cajas de alabastro para guardar sus joyas, cosm\u00e9ticos, perfumes, etc.; pero, muy probablemente, ser\u00eda en una especie de diminutas botellas donde se guardar\u00edan los propios aromas vol\u00e1tiles. La expresi\u00f3n en el original es simplemente, \u201cteniendo ung\u00fcento de alabastro\u201d. Plinio dice expresamente que los perfumes se conservan mejor en alabastros. La vasija, por estar hecha de alabastro, se llamaba alabastro, as\u00ed como, entre nosotros, una prenda particular, por estar hecha de material impermeable, se llama impermeable. Y un peque\u00f1o vaso de vidrio para beber se llama, gen\u00e9ricamente, vaso. Herodoto usa la expresi\u00f3n id\u00e9ntica empleada por el evangelista. Dice que los icti\u00f3fagos fueron enviados por Cambises a los et\u00edopes, \u00abllevando, como regalo, un manto de p\u00farpura, un collar de oro, un alabastro de perfume y un tonel de vino de palma\u00bb. (<em>J. Morison, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Aroma desperdiciado<\/strong><\/p>\n<p>Tan pronto como estas personas vieron el ung\u00fcento derramado sobre la cabeza de Cristo, dijeron: \u201c\u00bfPor qu\u00e9 este desperdicio? \u00a1Pues, ese ung\u00fcento podr\u00eda haber sido vendido y dado a los pobres!\u201d \u00a1Hip\u00f3critas! \u00bfQu\u00e9 les importaban los pobres? No creo que ninguno de los que hicieron la denuncia haya dado nunca un centavo a los pobres. Creo que Judas estaba muy indignado y vendi\u00f3 a su Maestro por treinta piezas de plata. No hay nada que enoje tanto a un hombre taca\u00f1o como ver la generosidad en los dem\u00e1s. Si esta mujer del texto hubiera tra\u00eddo una caja vieja y gastada, con alg\u00fan perfume rancio, y se la hubiera dado a Cristo, podr\u00edan haberlo soportado; pero que trajera un recipiente en el que se hab\u00eda empleado la destreza de h\u00e1biles artesanos y que conten\u00eda perfume que normalmente se hab\u00eda reservado para uso palaciego y real, no pudieron soportarlo. Y as\u00ed sucede a menudo en las comunidades y en las iglesias que son los hombres m\u00e1s impopulares los que dan m\u00e1s. Judas no puede soportar ver la caja de alabastro rota a los pies de Cristo. Hay un hombre que da mil d\u00f3lares a la causa misionera. Los hombres gritan: \u201c\u00a1Qu\u00e9 desperdicio! \u00bfDe qu\u00e9 sirve enviar Nuevos Testamentos y misioneros, y gastar su dinero de esa manera? \u00bfPor qu\u00e9 no env\u00eda arados, trilladoras de ma\u00edz, locomotoras y tel\u00e9grafos? \u00bfPero es un desperdicio? Preguntad a las naciones que se han salvado; \u00bfNo han precedido siempre las bendiciones religiosas a las bendiciones financieras? Mu\u00e9strame una comunidad donde triunfe el evangelio de Cristo, y yo te mostrar\u00e9 una comunidad pr\u00f3spera en un sentido mundano. \u00bfEs un desperdicio consolar a los afligidos, instruir a los ignorantes, rechazar la inmoralidad, capturar para Dios las innumerables huestes de hombres que con pies \u00e1giles estaban hollando el camino al infierno? Si un hombre compra acciones ferroviarias, es posible que disminuyan. Si un hombre invierte en un banco, el cajero puede fugarse. Si un hombre se asocia, su socio puede hundir la tienda. \u00a1Ay, para el hombre que no tiene nada mejor que \u00abbilletes verdes\u00bb y valores gubernamentales! Dios de vez en cuando hace estallar la caja fuerte del dinero, y con un hurac\u00e1n de desastre marino desarbola a los barcos mercantes, y desde los cielos ennegrecidos lanza a la Bolsa los rayos sibilantes de Su ira. La gente llora esta inversi\u00f3n y llora la otra; pero yo os digo que no hay inversi\u00f3n segura sino la que se hace en el banco del cual Dios tiene las llaves. El inter\u00e9s en eso siempre se est\u00e1 pagando, y hay dividendos eternos. \u00a1Dios cambiar\u00e1 ese oro en coronas que nunca perder\u00e1n su brillo, y en cetros que ondear\u00e1n para siempre sobre una tierra donde el habitante m\u00e1s pobre es m\u00e1s rico que todas las riquezas de la tierra arrojadas en una moneda reluciente! As\u00ed que, si me presento esta ma\u00f1ana ante hombres que ahora son de escasos recursos, pero que una vez fueron muy pr\u00f3speros, y que en los d\u00edas de su prosperidad fueron ben\u00e9volos, perm\u00edtanme pedirles que se sienten y cuenten sus inversiones. Todas las hogazas de pan que alguna vez diste a los hambrientos, son tuyas todav\u00eda; todos los zapatos que alguna vez diste a los descalzos, son tuyos todav\u00eda; todos los d\u00f3lares que alguna vez dio a iglesias, escuelas y universidades, todav\u00eda son suyos. Los empleados bancarios a veces cometen errores acerca de los dep\u00f3sitos; pero Dios lleva un registro infalible de todos los dep\u00f3sitos cristianos; y, aunque en el gran juicio, puede haber una \u201ccorrida\u201d en esa orilla, diez mil veces diez mil hombres recuperar\u00e1n todo lo que alguna vez dieron a Cristo; recuperar todo, amontonar, apretar, sacudir y rebosar. Una joven cristiana comienza a instruir a los libertos del Sur, con un libro de ortograf\u00eda en una mano y una Biblia en la otra. Ella sube a bordo de un barco de vapor para Savannah. A trav\u00e9s de d\u00edas, meses y a\u00f1os ella se afana entre los libertos del Sur; y un d\u00eda sale un aliento venenoso del pantano, y la fiebre hiere su frente, y lejos de casa, observada con l\u00e1grimas en los ojos por aquellos a quienes ha venido a salvar, cae en una tumba temprana. \u201c\u00a1Oh, qu\u00e9 desperdicio! Desperdicio de belleza, desperdicio de talento, desperdicio de cari\u00f1o, desperdicio de todo\u201d, grita el mundo. \u201cPues, ella podr\u00eda haber sido el gozo de la casa de su padre; podr\u00eda haber sido el orgullo del sal\u00f3n\u201d. Pero, en el d\u00eda en que se den recompensas por el ferviente trabajo cristiano, su herencia har\u00e1 insignificante todo el tesoro de Creso. No en vano, sus dulces palabras; no desperdiciada, su enfermedad del hogar; no desperdiciada, le duele el coraz\u00f3n; no desperdiciadas, sus l\u00e1grimas de soledad; no desperdiciados, los dolores de su \u00faltima hora; no desperdiciado, el sudor en su almohada moribunda. El liberto pens\u00f3 que era el aliento de la magnolia en la espesura; el plantador pens\u00f3 que era la dulzura de la acacia que brotaba del seto. \u00a1No! \u00a1no! era la fragancia de un vaso de alabastro derramado sobre la cabeza de Cristo. Un d\u00eda nuestro mundo se quemar\u00e1. Tan grandes han sido sus abominaciones y des\u00f3rdenes, que uno pensar\u00eda que al tocarlo las llamas un hedor horrible rodar\u00eda por los cielos; las minas de carb\u00f3n se consumen, las impurezas de las grandes ciudades se queman, uno podr\u00eda pensar que un esp\u00edritu perdido del pozo retroceder\u00eda tambale\u00e1ndose ante el olor repugnante. Pero no. Supongo que ese d\u00eda una nube de incienso rodar\u00e1 por los cielos, todo el desierto de flores tropicales en llamas, las monta\u00f1as de incienso, la s\u00e1bana blanca de los nen\u00fafares, los millones de matas de heliotropo, los enrejados de madreselva, los muros de \u00abgloria de la ma\u00f1ana\u00bb. La tierra ser\u00e1 un incensario ardiente, sostenido ante el trono de Dios con todos los olores de los hemisferios. Pero ese d\u00eda, un vendaval m\u00e1s dulce flotar\u00e1 en los cielos. Surgir\u00e1 de los siglos pasados, de los altares de devoci\u00f3n, y de las chozas de pobreza, y de los lechos de dolor, y de las estacas del martirio, y de todos los lugares donde los buenos hombres y mujeres han sufrido por Dios y han muerto por la verdad. Ser\u00e1 la fragancia de diez mil cajas de alabastro, que, a lo largo de los siglos, fueron derramadas sobre la cabeza de Cristo. (<em>Dr. Talmage.<\/em>)<\/p>\n<\/p>\n<p><strong>Influencia cegadora del prejuicio<\/strong><\/p>\n<p>Un hombre le dijo al Sr. Dawson, \u201cMe gustan mucho sus sermones, pero los de despu\u00e9s de las reuniones los desprecio. Cuando comienza la reuni\u00f3n de oraci\u00f3n, siempre subo a la galer\u00eda y miro hacia abajo, y estoy disgustado\u201d. \u00abBueno\u00bb, respondi\u00f3 el Sr. Dawson, \u00abla raz\u00f3n es que subes a la parte superior de la casa de tu vecino y miras por la chimenea para examinar el fuego y, por supuesto, \u00a1solo te entra humo en los ojos!\u00bb<\/p>\n<p><strong>La unci\u00f3n en Betania<\/strong><\/p>\n<p><strong>I.<\/strong><strong><em> <\/em><\/strong>Esta profec\u00eda de Cristo ha sido cumplido.<\/p>\n<p><strong>1. <\/strong>Por improbable que parezca que el simple acto de devoci\u00f3n aqu\u00ed mencionado deber\u00eda ser conocido en todo el mundo, literalmente ha sucedido. Se cuenta en todos los lenguajes de los hombres, hasta que apenas hay una mancha de coral en el ancho mar lo suficientemente grande para que un hombre se pare sobre este incidente y no se sabe. Debe aumentar nuestra confianza en todas las promesas de nuestro Se\u00f1or. Es un testimonio de que el resto se encontrar\u00e1 cierto cuando llegue su momento.<\/p>\n<p><strong>2. <\/strong>Dondequiera que se ha contado esta historia, ha recibido el elogio de quienes la han escuchado. El juicio del Se\u00f1or ha sido confirmado: no el de aquellos que \u201cten\u00edan indignaci\u00f3n dentro de s\u00ed mismos\u201d, y consideraban el ung\u00fcento perdido.<\/p>\n<p><strong>II. <\/strong>\u00bfPor qu\u00e9 esta mujer pudo hacer un acto tan digno de alabanza? \u00bfC\u00f3mo sab\u00eda ella mucho mejor que los dem\u00e1s que Cristo iba a morir, y que este era un acto apropiado en vista de Su muerte?<\/p>\n<p><strong>1. <\/strong>Ella hab\u00eda prestado atenci\u00f3n a sus palabras. Ella era una buena oyente. Su o\u00eddo era sencillo, y toda su mente estaba llena de verdad.<\/p>\n<p><strong>2. <\/strong>Su acto fue el resultado de su car\u00e1cter y sentimiento, no de su razonamiento. Ella le dio a \u00c9l, porque ella era Mar\u00eda y \u00c9l era Cristo. Fue el impulso del amor. (<em>Alex. McKenzie, DD<\/em>)<\/p>\n<\/p>\n<p><strong>La ofrenda de devoci\u00f3n<\/strong><\/p>\n<p>Llegar\u00e1 el momento cuando hacer algo por Cristo y que \u00c9l lo acepte ser\u00e1 trabajo y logro suficiente. Si \u00c9l est\u00e1 complacido, no nos preocuparemos de mirar m\u00e1s all\u00e1 en busca de recompensa. Si el nardo le es agradable, no pediremos que la casa se llene de su fragancia. Pero la fragancia llenar\u00e1 la casa. Los pobres son mejor atendidos donde se sirve mejor a Cristo. La virtud es m\u00e1s fuerte donde la piedad es m\u00e1s pura. Que \u00c9l est\u00e9 satisfecho y el mundo sea bendito. Rompamos a sus pies el alabastro que contiene nuestra vida, para que el nardo lo unja. Sal y p\u00e1rate ante los hombres y abre la caja de piedra. Entonces los hombres se sentir\u00e1n atra\u00eddos hacia ti y hacia tu devoci\u00f3n. Pronto los reyes balancear\u00e1n el incensario de oro, y las naciones esparcir\u00e1n incienso sobre las brasas, y el perfume endulzar\u00e1 el aire: mientras muchas voces de la tierra y del cielo se mezclan en el canto de adoraci\u00f3n a Aquel que nos am\u00f3. (<em>Alex. McKenzie, DD<\/em>)<\/p>\n<\/p>\n<p><strong>La unci\u00f3n en Betania<\/strong><\/p>\n<p>En esta narraci\u00f3n de la buena obra de Mar\u00eda y la indignaci\u00f3n de los ap\u00f3stoles, tenemos ejemplo de todas aquellas opiniones y todos esos juicios que tienen su fundamento en el principio predilecto del utilitarismo, y que tantas veces se aplica falsamente para herir los corazones piadosos, y para la obst\u00e1culo para ese culto justificado en la Iglesia de Cristo, que busca expresar dignamente el sentimiento de reverencia y de amor, y que es en s\u00ed mismo productor de la m\u00e1s alta bendici\u00f3n.<br \/>I. <\/p>\n<p><strong>(1)<\/strong> En Mar\u00eda hemos puesto ante nosotros una imagen de amor ardiente;<\/p>\n<p><strong>(2)<\/strong> en Judas un ejemplo de gran hipocres\u00eda;<\/p>\n<p><strong>(3)<\/strong> en el resto de los ap\u00f3stoles un ejemplo de la facilidad con la que incluso los buenos hombres a menudo se escandalizan cuando el prop\u00f3sito de Dios difiere del suyo propio preconceptos.<\/p>\n<p>II. <\/p>\n<p><strong>(1)<\/strong> En la aceptaci\u00f3n de la ofrenda del ung\u00fcento de Mar\u00eda, tenemos la misericordia de Dios desplegada al recibir y santificar el don del hombre cuando se le otorga;<\/p>\n<p><strong>(2)<\/strong> en el rechazo de Judas, que impenitentemente se endureci\u00f3 ante la devoci\u00f3n de Mar\u00eda, se nos da un ejemplo del justo juicio del Todopoderoso contra el pecador. (<em>W. Denton, MA<\/em>)<\/p>\n<\/p>\n<p><strong>El verdadero principio del gasto cristiano<\/strong><\/p>\n<p>Es com\u00fanmente se argumenta que cualquiera que haya sido la adecuaci\u00f3n de esa devoci\u00f3n anterior que construy\u00f3 y embelleci\u00f3 el templo, ahora es anticuada, inapropiada e incluso (como algunos nos dicen) injustificada. Esos esplendores costosos y casi b\u00e1rbaros, se dice, eran apropiados para una raza en su infancia y para una religi\u00f3n en germen. Pero el templo y el ritual del juda\u00edsmo han florecido en el santuario y el servicio de la Iglesia de Cristo. Ni al monte Gerizim ni a Jerusal\u00e9n es necesario que los hombres viajen para adorar al Padre, dice el mismo Fundador de esa Iglesia. \u201cDios es Esp\u00edritu, y los que le adoran, en esp\u00edritu y en verdad es necesario que adoren.\u201d Si uno mostrara su devoci\u00f3n a \u00c9l, dice este mismo Maestro, \u201cvende todo lo que tienes y d\u00e1selo a los pobres\u201d. No es para adornar templos y adornar lugares santos como se llama el cristianismo hoy en d\u00eda, sino para levantar hospitales, albergar a los hu\u00e9rfanos y alimentar a los hambrientos. Es cosa m\u00e1s divina enviar pan a una casa hambrienta, o ministrar en alguna plaga asolada por Menfis o Nueva Orleans, a alg\u00fan febril que sufre, que construir todos los altares y adornar todos los santuarios que jam\u00e1s se hayan levantado. \u00a1No! no es, ni una pizca de adivino, noble y semejante a Cristo, como ciertamente lo es ese servicio. Lleguemos a un claro entendimiento aqu\u00ed en cuanto a un tema respecto del cual, en la mente popular, hay mucha confusi\u00f3n y mucho m\u00e1s malentendido. Si se pregunta: \u00bfNo hay un orden y una secuencia en los que cosas igualmente excelentes se pueden hacer sabia y correctamente?, la respuesta es bastante clara. Si alguien est\u00e1 hambriento, sin hogar o hu\u00e9rfano, lo primero que debe hacer es alimentarlo, darle cobijo y socorrerlo. Y mientras tal trabajo se deshaga, sabiamente podemos posponer otro trabajo, igualmente meritorio y honorable. Pero debe entenderse claramente que si en algunas \u00e9pocas se ha dedicado una cantidad desproporcionada de tiempo, dinero y atenci\u00f3n a la est\u00e9tica de la religi\u00f3n, en otras la misma desproporci\u00f3n ha caracterizado la que se ha dedicado a lo que con justicia puede llamarse el sentimentalismo de la religi\u00f3n. religi\u00f3n. Una enorme cantidad de limosnas indiscriminadas, tanto en nuestra generaci\u00f3n como en otras, solo ha engendrado holgazaner\u00eda, indolencia, falta de econom\u00eda e incluso francas rivalidades. \u00a1Dios no permita que cerremos apresuradamente nuestra mano o nuestro coraz\u00f3n contra cualquier hermano m\u00e1s necesitado! Pero Dios, sobre todo, no permita que lo arrojemos a una condici\u00f3n de pauperismo cr\u00f3nico por la facilidad desenfrenada y ego\u00edsta con la que compramos nuestro privilegio de que \u00e9l nos deje solos c\u00f3modamente con una limosna o un subsidio. Mejor mil veces que nuestros dones enriquezcan una catedral ya tres veces adornada, y arropen sus paredes ya colgadas con gemidos de profusi\u00f3n de enriquecimiento, porque as\u00ed, al menos, alguien que venga despu\u00e9s de nosotros se sienta incitado a ver y reconocer que, cualquiera que sea la falta de gusto. o la congruencia puede ofenderlo, no ha habido edificaci\u00f3n y embellecimiento sin costo y sacrificio. Esos maravillosos hombres de una generaci\u00f3n anterior trabajaron individualmente y supremamente para dar a Dios lo mejor de s\u00ed mismos, y gastar su arte y esfuerzo donde, a menudo, si no ordinariamente, es necesario. no pod\u00eda ser visto, pose\u00eddo y apreciado adecuadamente por ning\u00fan otro ojo que el Suyo. Esto, sostengo, es el \u00fanico motivo suficiente para el costo y la belleza, e incluso para los desembolsos generosos, en la construcci\u00f3n y el adorno de la Casa de Dios. Bien podemos regocijarnos y estar agradecidos cuando cualquier disc\u00edpulo cristiano se esfuerza en cualquier lugar por hacer algo que le diga a Dios y a los hombres, ya sea en madera, piedra, oro o piedras preciosas, que tal persona quisiera consagrarle lo mejor y lo mejor. m\u00e1s costoso que las manos humanas pueden traer. Cuando cualquier pobre penuria clama por tal desembolso, \u00ab\u00bfPara qu\u00e9 sirve este despilfarro?\u00bb la lastimosa objeci\u00f3n es silenciada por aquella respuesta del Maestro a la que quebrant\u00f3 siempre Sus pies el vaso de alabastro del ung\u00fcento preci\u00edsimo, \u201cDe cierto os digo,\u201d etc. \u00bfY por qu\u00e9 hab\u00eda de decirlo? para la difusi\u00f3n de su fama? No, sino por la inculcaci\u00f3n de su ejemplo. (<em>Obispo HC Potter.<\/em>)<\/p>\n<\/p>\n<p><strong>Contraste entre Mar\u00eda y Judas <\/strong><\/p>\n<p>\u201cEl Mes\u00edas, aunque yendo a la muerte, d\u00e9jame prodigar mi todo en \u00c9l\u201d, fue el pensamiento de Mar\u00eda; \u201cYendo a la muerte, y por lo tanto no al Mes\u00edas, d\u00e9jame hacer lo que pueda con \u00c9l\u201d, fue el pensamiento de Judas. (<em>TM Lindsay, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Dones costosos aceptables para Cristo<\/strong><\/p>\n<p>Hay una gran principio envuelto en la ofrenda de esta mujer, o m\u00e1s bien en la aceptaci\u00f3n de la misma por parte de nuestro Se\u00f1or, que es este, que podemos dar lo que es costoso para adornar y embellecer el santuario de Dios y su adoraci\u00f3n. Dios mismo orden\u00f3 a los jud\u00edos que hicieran un tabern\u00e1culo de adoraci\u00f3n con materiales tales como oro, p\u00farpura, lino fino y piedras preciosas; y el hombre conforme al coraz\u00f3n de Dios reuni\u00f3 un vasto tesoro de oro y materiales costosos para construir y embellecer un templo que ser\u00eda sumamente magn\u00edfico. Pero desde entonces se ha dado una nueva dispensaci\u00f3n, que tuvo su fundamento en la m\u00e1s profunda humillaci\u00f3n -en el pesebre de Bel\u00e9n- en los viajes de un pobre hombre sin hogar, con los sencillos campesinos sus compa\u00f1eros -terminando en la cruz y en el sepulcro . \u00bfHay lugar en tal reino para que hombres y mujeres generosos prodiguen cosas preciosas en Sus santuarios y los acompa\u00f1amientos de Su adoraci\u00f3n? Ahora bien, este incidente al final de la vida del Se\u00f1or, junto con el de su comienzo, cuando los hombres dirigidos por Dios le ofrecieron regalos de oro, incienso y mirra, nos ense\u00f1a que la hay. As\u00ed como esta mujer fue impulsada por un instinto divino a prodigar sobre su persona lo costoso y fragante, as\u00ed la Iglesia, por el mismo instinto divino, ha sido impulsada a derramar a sus pies los tesoros m\u00e1s ricos de las naciones que ha sometido a sus pies. fe. La Iglesia ha hecho lo que ha podido. Al menos sus fieles hijos e hijas lo han hecho. Al principio, en sus d\u00edas de persecuci\u00f3n, s\u00f3lo pod\u00eda adorar en las catacumbas, y en sus d\u00edas de pobreza s\u00f3lo pod\u00eda ofrecer lo que era rudo; pero cuando someti\u00f3 a sus perseguidores y sali\u00f3 de su pobreza, entonces tambi\u00e9n hizo lo que pudo. Los m\u00e1s grandiosos esfuerzos de la habilidad arquitect\u00f3nica se han elevado al honor de Cristo, la mayor parte construida en la forma de la cruz en la que \u00c9l colg\u00f3 para redimirnos. Las pinturas m\u00e1s nobles son de Sus actos y sufrimientos; y los acordes m\u00e1s elevados de la m\u00fasica son acompa\u00f1amientos de Su adoraci\u00f3n. Demasiado es verdad que han tomado parte en estos oficios muchos que no se han sentado, como Mar\u00eda, a sus pies, y elegido la parte buena; pero lo que ahora nos interesa es si este incidente justifica que aquellos que primero se han entregado a \u00c9l ofrezcan en y para Su adoraci\u00f3n lo que ha costado trabajo, tesoro y habilidad. (<em>MFSadler, MA<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mar 14:1-9 Y estando en Betania en casa de Sim\u00f3n el leproso. Trabajando para Cristo El hogar de Mar\u00eda, Marta y L\u00e1zaro en Betania, a unas dos millas de Jerusal\u00e9n al otro lado del Monte de los Olivos, hab\u00eda sido el escenario de algunos de los momentos m\u00e1s tranquilos y felices de la vida de &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-marcos-141-9-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Marcos 14:1-9 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39128","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=39128"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39128\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=39128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=39128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=39128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}