{"id":39145,"date":"2022-07-16T08:45:41","date_gmt":"2022-07-16T13:45:41","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-marcos-1432-36-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:45:41","modified_gmt":"2022-07-16T13:45:41","slug":"estudio-biblico-de-marcos-1432-36-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-marcos-1432-36-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Marcos 14:32-36 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Mar 14:32-36<\/span><\/p>\n<p> <em>Que se llam\u00f3 Getseman\u00ed.<\/em><\/p>\n<\/p>\n<p><strong>El conflicto en Getseman\u00ed<\/strong><\/p>\n<p><strong>I.<\/strong><strong><em> <\/em><\/strong>El lugar del conflicto requiere un breve aviso.<\/p>\n<p><strong>II. <\/strong>La historia del conflicto. Su intensidad es el primer hecho de la historia que nos llama la atenci\u00f3n. \u201cSu sudor era como grandes gotas de sangre que ca\u00edan a tierra\u201d. Este conflicto arranc\u00f3 del Salvador un gran grito. \u00bfQu\u00e9 era? \u201cPadre m\u00edo, si es posible, pase de m\u00ed esta copa; pero no sea como yo quiero, sino como t\u00fa.\u201d Tenemos una vislumbre del conflicto llevado a cabo por Cristo por nosotros, sin ayuda de nadie.<\/p>\n<p><strong>III. <\/strong>El sue\u00f1o de los disc\u00edpulos mientras se desarrollaba este conflicto. (<em>Charles Stanford, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Getseman\u00ed<\/strong><\/p>\n<p><strong>I. <\/strong>Getseman\u00ed sugiere a la fe reverente el anhelo de nuestro bendito Redentor por la simpat\u00eda humana.<\/p>\n<p><strong>II. <\/strong>Nos recuerda la sacralidad del dolor humano y la comuni\u00f3n divina.<\/p>\n<p><strong>III. <\/strong>Revela la abrumadora plenitud del dolor del Redentor.<\/p>\n<p><strong>IV. <\/strong>Nos recuerda la voluntad de Cristo rendida a la voluntad del Padre.<\/p>\n<p><strong>V. <\/strong>Tiene lecciones e influencias para nuestros propios corazones. (<em>El Predicador<\/em>&#8216;<em>s Monthly.<\/em>)<\/p>\n<\/p>\n<p><strong>Jes\u00fas en Getseman\u00ed<\/strong><\/p>\n<p><strong>I.<\/strong><strong><em> <\/em><\/strong>La copa m\u00e1s amarga del ay debe tomarse cuando es el medio de mayor utilidad. El sufrimiento desperdiciado es el cl\u00edmax del sufrimiento. El calor del horno de la aflicci\u00f3n pierde sus punzadas m\u00e1s agudas para aquellos que pueden ver la forma de Uno como el Hijo del Hombre caminando con ellos con el ejemplo, y saben que est\u00e1n ministrando al verdadero gozo y vida del mundo, en cierto grado, como lo hizo \u00c9l. <\/p>\n<p><strong>II. <\/strong>Del ejemplo de nuestro Se\u00f1or aprendemos la utilidad en el dolor de confiar en la compa\u00f1\u00eda humana y divina combinadas. Pero hacer ambas cosas en la debida proporci\u00f3n no es f\u00e1cil. Algunos se esconden tanto de la tierra como del cielo tanto como sea posible. Otros se apoyan totalmente en apoyos humanos; otros, sin embargo, se vuelven a Dios en una reclusi\u00f3n en la que los oficios m\u00e1s tiernos de los amigos no son bienvenidos. La divinidad de nuestro Se\u00f1or a menudo aparece m\u00e1s clara en su uni\u00f3n sim\u00e9trica de rasgos, principalmente notables por su combinaci\u00f3n. Era a la vez el m\u00e1s humilde y el m\u00e1s audaz de los hombres; el m\u00e1s alejado del pecado y el m\u00e1s compasivo con el pr\u00f3digo que regresa; el m\u00e1s manso y el m\u00e1s dominante. As\u00ed, en la agon\u00eda del huerto, se apoy\u00f3 en apoyos humanos y divinos; uno tan indispensable como el otro. Cualquiera que sea la situaci\u00f3n, no debemos actuar como reclusos. Los c\u00edrculos de la vida nos necesitan y nosotros los necesitamos a ellos. Tampoco debemos olvidar al Padre que est\u00e1 en los cielos. Las tormentas y las pruebas solo aumentan Su pronta simpat\u00eda y socorro.<\/p>\n<p><strong>III. <\/strong>La obediencia crucial de nuestro Se\u00f1or en la agon\u00eda del huerto refleja la majestad de la voluntad humana y su posible dominio de cada prueba en perfecta obediencia a la voluntad divina. Por muy sobrehumano que fuera el sufrimiento de Jes\u00fas, en \u00e9l era enteramente humano. Ten\u00eda todas nuestras facultades y las us\u00f3 como nosotros podemos usar las nuestras. No es un est\u00edmulo peque\u00f1o que el Hombre t\u00edpico nos d\u00e9 un ejemplo de obediencia perfecta, a un costo desconocido antes o despu\u00e9s. En las relaciones mutuas de las voluntades humana y Divina se logra todo m\u00e9rito y se construye todo car\u00e1cter. Los eruditos autores se ocupan con merecido inter\u00e9s de las \u201cbatallas decisivas\u201d del mundo, los ejes del destino. El futuro del alma por el tiempo y la eternidad gira en torno a concursos en los que la voluntad est\u00e1 al mando principal. Participan el intelecto y la sensibilidad, pero siempre subordinados. Fue \u00fatil tener esto en cuenta en cada exposici\u00f3n. Que la pregunta sea r\u00e1pida y constante: \u00bfQu\u00e9 dice el testamento? \u00bfEs constante e inquebrantable?<\/p>\n<p><strong>IV. <\/strong>El alma de Jes\u00fas pudo haber estado \u201cdolorida hasta la muerte\u201d solo porque sus sufrimientos fueron vicarios. Siempre fue sublimemente heroico. \u00bfPor qu\u00e9 tanta agon\u00eda ahora? Era algo mucho m\u00e1s mort\u00edfero que la muerte. Era la carga y el misterio del pecado del mundo. El Cordero de Dios fue inmolado por nosotros en agon\u00eda del alma en lugar de dolor f\u00edsico. Su alma form\u00f3 el alma de sus sufrimientos.<\/p>\n<p><strong>V. <\/strong>La oscuridad de Getseman\u00ed pinta la culpa y la ruina del pecado con un color fiel y duradero. Es f\u00e1cil pensar a la ligera del pecado. Como nunca conoci\u00f3 la culpa, Cristo se encontr\u00f3 con las mismas ocultaciones del rostro divino que los culpables. Esta fue la desobediencia del hombre en su relaci\u00f3n con la ley y el juicio de Dios.<\/p>\n<p><strong>VI. <\/strong>Getseman\u00ed arroja una luz portentosa sobre el dolor de las almas perdidas. Sufri\u00f3 excepcionalmente, pero tambi\u00e9n fue un sufridor t\u00edpico; toda alma tiene posibilidades m\u00e1s all\u00e1 de nuestra imaginaci\u00f3n; y terrible el destino cuando estas posibilidades se cumplen en la direcci\u00f3n a la que apunta Getseman\u00ed.<\/p>\n<p><strong>VII.<\/strong> Nuestra lecci\u00f3n da un \u00e9nfasis terrible al hecho y la seriedad de las imposibilidades con Dios. Nuestro tiempo tiende fuertemente hacia nociones laxas del car\u00e1cter y la ley divina y de las condiciones de la salvaci\u00f3n. La voluntad y la fantas\u00eda erigen sus propios estandartes. La religi\u00f3n y la obediencia deben ser resueltas seg\u00fan nociones individuales, un asunto subjetivo. Las palabras agonizantes de nuestro Se\u00f1or, \u00abSi es posible\u00bb, establecen la rigidez y el car\u00e1cter absoluto de las condiciones gubernamentales y espirituales. La voluntad y los planes de Dios son realidades objetivas; tienen una direcci\u00f3n y demandas definidas y de suma importancia. El hombre no debe pensar en ser una ley para s\u00ed mismo ni en su conducta ni en sus creencias; y menos que nada debe juzgar la Palabra revelada, imaginando que cualquier cantidad o tipo de luz interior es una prueba verdadera y suficiente de su legitimidad y autoridad. Pero, qu\u00e9 in\u00fatiles son todos los intentos de comprender las lecciones de Getseman\u00ed. (<em>HLB Speare.<\/em>)<\/p>\n<\/p>\n<p><strong>Cristo en Getseman\u00ed<\/strong><\/p>\n<p><strong>I.<\/strong><strong><em> <\/em><\/strong>Getseman\u00ed vio la agon\u00eda de Cristo a causa del pecado.<\/p>\n<p><strong>II. <\/strong>Getseman\u00ed fue testigo de la devoci\u00f3n de Cristo en la hora de la angustia.<\/p>\n<p><strong>III. <\/strong>Getseman\u00ed fue testigo de la renuncia de Cristo a la voluntad de Dios.<\/p>\n<p><strong>IV. <\/strong>Getseman\u00ed fue testigo de la simpat\u00eda y el afecto de Cristo por sus probados seguidores. (<em>JH Hitchens.<\/em>)<\/p>\n<\/p>\n<p><strong>La oraci\u00f3n en Getseman\u00ed<\/strong><\/p>\n<p><strong>I. <\/strong>Notemos, de entrada, la s\u00fabita experiencia que condujo a este acto de s\u00faplica. Empez\u00f3 a estar \u201casombrado y apesadumbrado\u201d. Evidentemente algo nuevo le hab\u00eda llegado; ya sea una revelaci\u00f3n de un nuevo juicio, o una violencia de dolor inusual debajo de \u00e9l. Aqu\u00ed es conmovedor encontrar en nuestro Divino Se\u00f1or tanto de reconocida y sencilla naturaleza humana que deseaba estar solo, pero planeaba tener a su alcance a alguien a quien amaba y en quien confiaba. Su dolor era demasiado agobiante para el abandono total. De ah\u00ed vino la demanda de simpat\u00eda que hizo, y la persistencia en la reserva que mantuvo, las cuales son tan bienvenidas e instructivas. Porque aqu\u00ed enf\u00e1ticamente, como quiz\u00e1s en ning\u00fan otro lugar, estamos \u201ccon \u00c9l en el jard\u00edn\u201d. \u00a1Oh, cu\u00e1n apasionadamente anhelantes de ayuda, y sin embargo cu\u00e1n majestuosamente rechazan la impertinente condolencia, son algunos de estos momentos que tenemos en nuestro duelo, \u201ccuando nuestras almas se retiran sobre sus reservas, y abrir\u00e1n sus m\u00e1s profundos recovecos solo a Dios! Nuestro secreto no se comparte, nuestra lucha no se revela a los hombres. Sin embargo, amamos a quienes nos aman tanto como siempre. Es \u00fatil encontrar que incluso nuestro Se\u00f1or Jes\u00fas ten\u00eda algunos sentimientos que no pod\u00eda decirle a Juan. \u00c9l \u201cse fue\u201d (<span class='bible'>Mateo 26:44<\/span>).<\/p>\n<p><strong>II. <\/strong>Pregunt\u00e9monos, en segundo lugar, por el sentido exacto de esta singular s\u00faplica. En esas tres intensas oraciones, \u00bfel Salvador simplemente tem\u00eda a la muerte? \u00bfFue eso lo que nuestra versi\u00f3n hace que el ap\u00f3stol Pablo diga que \u00c9l \u201ctem\u00eda\u201d? \u00bfEstaba simplemente suplicando all\u00ed debajo de los olivos permiso para despojarse de la forma humana ahora, renunciar a la \u201csemejanza de los hombres\u201d (<span class='bible'>Filipenses 2:7 -8<\/span>), que hab\u00eda tomado sobre s\u00ed, se deslizara de regreso al cielo discretamente por alg\u00fan tipo de traducci\u00f3n que lo quitar\u00eda del poder de Pilato, de modo que cuando Judas hubo hecho su encargo \u00abr\u00e1pidamente\u00bb y lleg\u00f3 con los soldados, Jes\u00fas estar\u00eda misteriosamente desaparecido, y el traidor no encontrar\u00eda nada m\u00e1s que tres camaradas inofensivos dormidos sobre la hierba? Es decir, \u00bfestamos dispuestos a admitir que nuestro Se\u00f1or y Maestro se propuso seriamente volver al seno de su Divino Padre en esta coyuntura, dejando incumplidas las profec\u00edas, inconclusa la redenci\u00f3n, mancillado con un fracaso el mismo honor de Jehov\u00e1? \u00bfOfrece alguna ayuda al tratar con tal conjetura insistir en que este fue solo un momento de debilidad en Su \u00abnaturaleza humana\u00bb? \u00bfHar\u00eda esto alguna diferencia de hecho para que Satan\u00e1s descubriera que, despu\u00e9s de todo, solo hab\u00eda estado compitiendo con otro Ad\u00e1n? \u00bfSe regocijar\u00edan menos los \u00e1ngeles perdidos por la feliz noticia de una derrota celestial porque supieran que la \u00absimiente de la mujer\u00bb no hab\u00eda logrado herir la cabeza de la serpiente debido a Su propia alarma al final? \u00a1Oh, no: seguro que no! Jes\u00fas hab\u00eda dicho, cuando en los remotos concilios de la eternidad se hizo el pacto de la redenci\u00f3n: \u201cHe aqu\u00ed que vengo: me deleito en hacer tu voluntad, oh Dios m\u00edo\u201d (<span class='bible'>Sal 40:7-8<\/span>). No podr\u00eda haber tenido ning\u00fan prop\u00f3sito ahora, podemos estar cada vez m\u00e1s seguros, de retirar la oferta de s\u00ed mismo para sufrir por los hombres. No puede haber duda de que la \u201ccopa\u201d que nuestro Se\u00f1or deseaba que \u201cpasara\u201d de Sus labios, y sin embargo estaba dispuesto a beber si no pod\u00eda liberarse de ella, fue la ira judicial de Dios descargada sobre \u00c9l como culpable vicariamente. ante la ley, recibiendo la terrible maldici\u00f3n debida al pecado humano. Rechazamos toda noci\u00f3n de mera enfermedad o agotamiento f\u00edsico as\u00ed como toda conjetura de mera soledad sentimental bajo el abandono de amigos. En ese momento supremo cuando descubri\u00f3 que \u00c9l, sin pecado en cada detalle y grado, deb\u00eda ser considerado culpable, y de modo que el rostro y el favor de Su Padre celestial deb\u00edan ser retirados de \u00c9l al menos por un tiempo, \u00c9l fue, a pesar de todos Sus valiente preparaci\u00f3n, sorprendido y casi asustado al descubrir cu\u00e1nto su propia alma comenzaba a estremecerse y retroceder ante el contacto con cualquier tipo de pecado, aunque s\u00f3lo fuera imputado. Evidentemente, a Su naturaleza infinitamente pura le parec\u00eda horrible ser puesto en una posici\u00f3n, por falsa que fuera, de que Su adorable Padre se viera obligado a cubrir Su rostro con el manto. Esto lo conmocion\u00f3 indescriptiblemente. Retrocedi\u00f3 consternado cuando vio que deb\u00eda volverse repugnante a los ojos del cielo debido a la \u201ccosa abominable\u201d que Dios odiaba (<span class='bible'>Jer 44:4<\/a>). Por lo tanto, concebimos que la oraci\u00f3n cubri\u00f3 solo eso. Lo que al principio parece una rendici\u00f3n sorprendente de la redenci\u00f3n en su totalidad, no es m\u00e1s que una petici\u00f3n para ser liberado de lo que \u00c9l esperaba que no se considerara parte necesaria de la maldici\u00f3n que estaba cargando por otros. Anhelaba, al entrar en una oscuridad inusual, solo recibir la luz habitual. Era como si le hubiera dicho a su Padre celestial: \u201cEl dolor lo entend\u00ed, la maldici\u00f3n por la que vine. Verg\u00fcenza, oprobio, muerte, no me importan nada. Solo retrocedo de estar tan cargado de pecados extra\u00f1os que no se me puede considerar con ninguna concesi\u00f3n. Estoy alarmado cuando pienso en el pr\u00edncipe de este mundo que viene y encuentra algo en m\u00ed, cuando hasta ahora no ten\u00eda nada. Soy derramado como agua, y todos mis huesos se dislocan, mi coraz\u00f3n es como cera, cuando pienso en la burla de que el Se\u00f1or en quien confiaba ya no se complace en M\u00ed; esto es como burlarse de Dios. \u00bfNo est\u00e1 permitida la discriminaci\u00f3n entre un verdadero pecador y un sustituto s\u00f3lo contado como tal ante la ley en este particular? Todas las cosas son posibles contigo; \u00a1Haz posible ahora que veas a Tu Hijo y, sin embargo, no parezcas ver la culpa imputada que \u00c9l carga! Sin embargo, aun esto soportar\u00e9, si es necesario para que yo pueda cumplir toda justicia; \u00a1H\u00e1gase Tu voluntad, no la M\u00eda!\u201d<\/p>\n<p><strong>III. <\/strong>Otra vez, observemos cuidadosamente el extraordinario alcance que tom\u00f3 esta oraci\u00f3n en el jard\u00edn. Ni siquiera vale la pena dar la impresi\u00f3n de estar jugando con una colocaci\u00f3n accidental de palabras en la narraci\u00f3n sagrada; pero \u00bfpor qu\u00e9 deber\u00eda afirmarse que las palabras inspiradas son accidentales? Toda la historia de los sufrimientos de Emmanuel en esa terrible noche no contiene ning\u00fan incidente m\u00e1s sorprendentemente sugestivo que el registro de la distancia que \u00c9l mantuvo entre S\u00ed mismo y Sus disc\u00edpulos. Es tanto el acto como el lenguaje lo que es significativo. Mark dice: \u201cSe adelant\u00f3 un poco\u201d. Lucas dice: \u201cSe apart\u00f3 de ellos como al este de una piedra\u201d. Mateo dice: \u201cFue un poco m\u00e1s lejos\u201d. As\u00ed que ahora sabemos que esta \u00fanica petici\u00f3n de nuestro Se\u00f1or fue el \u00faltimo, secreto y supremo susurro de lo m\u00e1s profundo de Su coraz\u00f3n. El alcance de tal oraci\u00f3n abarcaba toda Su naturaleza. Agot\u00f3 todo Su ser. Cubr\u00eda la humanidad que representaba. En esto por S\u00ed mismo y por nosotros \u201c\u00c9l fue un poco m\u00e1s lejos\u201d de lo que jam\u00e1s hab\u00eda ido antes en Su s\u00faplica. Un augusto monarca gobierna este mundo ca\u00eddo y tiene todos los corazones humanos bajo su dominio. Su nombre es Dolor. Su imagen y inscripci\u00f3n est\u00e1 sobre cada moneda que pasa corriente en esta vida mortal. Reclama lealtad de toda la raza humana. Y, tarde o temprano, una, dos o cien veces, como quiera el rey, y no como quiera el s\u00fabdito, cada alma ha de ponerse su vestidura negra, ir serena y sufriente en su triste viaje para pagar su fiel tributo. , precisamente como Jos\u00e9 y Mar\u00eda fueron obligados a subir a Bel\u00e9n para ser gravados. Cuando este tirano Dolor nos convoca a venir a cumplir con su deber, es el m\u00e1s r\u00e1pido de los instintos humanos el que nos impulsa a buscar la soledad. Esa parece ser la regla universal (<span class='bible'>Zac 12:12-14<\/span>). Pero ahora descubrimos a partir de esta imagen simb\u00f3lica que, cada vez que un cristiano se aleja de otros disc\u00edpulos y se adentra m\u00e1s en las soledades de su propio Getseman\u00ed, casi de inmediato se acerca al Salvador que necesita. Porque nuestro Se\u00f1or hace un momento \u201cse adelant\u00f3 un poco\u201d. \u00a1All\u00ed est\u00e1 \u00c9l, delante de todos nosotros en experiencia! Es simple y maravillosamente cierto de Jes\u00fas siempre, no importa cu\u00e1n severo sea el sufrimiento al que por disciplina de ellos conduce a Sus elegidos, \u00c9l mismo ha tomado Su posici\u00f3n antes que ellos. Ninguna suerte humana estuvo nunca tan desamparada, tan cargada de dolor, tan desolada, como la de la Gran Vida dada para redimirla. Ning\u00fan camino jam\u00e1s lleg\u00f3 tan lejos a la regi\u00f3n de la agon\u00eda de prueba del coraz\u00f3n como para no ver todav\u00eda al incomparable Cristo de Dios \u201ccomo a un tiro de piedra\u201d m\u00e1s all\u00e1, arrodillado en algunas sombras m\u00e1s profundas de los Suyos. Ning\u00fan creyente se adentr\u00f3 tanto en su solitario Getseman\u00ed sin encontrar a su Maestro que hab\u00eda ido \u201cun poco m\u00e1s lejos\u201d.<\/p>\n<p>\u201cCristo no envi\u00f3, sino que vino \u00c9l mismo a salvar;<\/p>\n<p>El precio del rescate no lo prest\u00f3, sino que lo dio;<br \/>Cristo muri\u00f3, el Pastor de las ovejas,<\/p>\n<p>Nosotros s\u00f3lo nos dormimos.\u201d<\/p>\n<p><strong>IV .<\/strong> Por \u00faltimo, indaguemos por los resultados supremos de esta s\u00faplica de nuestro Se\u00f1or.<\/p>\n<p><strong>1. <\/strong>Considere al Sumo Sacerdote de nuestra profesi\u00f3n (<span class='bible'>Heb 12:2-4<\/span>). \u00bfDe qu\u00e9 servir\u00eda orar, si la oraci\u00f3n de Cristo no tuvo \u00e9xito?<\/p>\n<p><strong>2. <\/strong>\u00bfPero fue respondida? Ciertamente (<span class='bible'>Heb 5:7-9<\/span>). La copa se qued\u00f3 (<span class='bible'>Juan 18:11<\/span>), pero obtuvo la aquiescencia (<span class='bible'>Mat 26:42<\/span>), y fuerza (<span class='bible'>Luk 22:43<\/span>).<\/p>\n<p><strong> 3. <\/strong>\u00bfHemos estado \u201ccon \u00c9l en el jard\u00edn\u201d? Entonces hemos encontrado una copa semejante\u201d (<span class='bible'>Mar 10:38-39<\/span>). (<em>CS Robinson, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Compa\u00f1erismo en el dolor<\/strong><\/p>\n<p>Es una delicia estar con Jes\u00fas en el monte de la transfiguraci\u00f3n, donde se ven visitantes celestiales y se escucha una voz celestial. Ser\u00eda bueno estar siempre ah\u00ed. Pero aquellos que quieran seguir a Jes\u00fas a trav\u00e9s de esta vida terrenal, deben estar con \u00c9l tambi\u00e9n en el mar embravecido en la noche sombr\u00eda; y de nuevo deben venir con \u00c9l al valle de sombra de muerte. Hay arcillas brillantes y alegres para el creyente cristiano, cuando la fe, la esperanza y el amor son fuertes. Pero tambi\u00e9n hay d\u00edas de prueba y dolor, cuando parece que la fe debe fallar, y la esperanza debe morir, y el amor mismo debe cesar. Una cosa es para una pareja joven estar juntos en la luz y la alegr\u00eda, rodeados de amigos, en la recepci\u00f3n de su matrimonio, o compartir el placer del otro en la gira de su boda. Otra cosa es que una pareja de casados vigile juntos durante la noche cansada a un ni\u00f1o enfermo y que sufre, y cierre los ojos de su amado en su sue\u00f1o de muerte, en el gris de la ma\u00f1ana sombr\u00eda. Sin embargo, las nubes est\u00e1n tan seguras como la luz del sol en el camino de cada disc\u00edpulo elegido de Jes\u00fas que sigue a su Maestro sin desviarse; y el que nunca viene con Jes\u00fas a un lugar llamado Getseman\u00ed, ha escogido para s\u00ed mismo otro camino que el que el Salvador lleva. (<em>H. Clay Trumbull.<\/em>)<\/p>\n<\/p>\n<p><strong>Cristo, nuestro portador del pecado<\/strong><\/p>\n<p><strong> I.<\/strong><strong><em> <\/em><\/strong>Con respecto a la posici\u00f3n en la que estaba nuestro Se\u00f1or, \u00c9l se par\u00f3 all\u00ed como el gran Portador del Pecado. Aqu\u00ed, amados, vemos cu\u00e1l fue la carga que llev\u00f3 nuestro Se\u00f1or: fueron nuestros pecados.<\/p>\n<p><strong>II. <\/strong>Pero ahora observa, en segundo lugar, el gran peso de esta carga. \u00bfQui\u00e9n puede declararlo? (<em>JH Evans, MA<\/em>)<\/p>\n<\/p>\n<p><strong>Los sufrimientos de los buenos<\/strong><\/p>\n<p>Mi vida ha sido para m\u00ed un misterio de amor. S\u00e9 que la educaci\u00f3n de Dios para cada hombre es en perfecta justicia. S\u00e9 que los mejores de la tierra han sido los que m\u00e1s sufrieron, porque fueron los mejores, y como el oro pudieron soportar el fuego y ser purificados por \u00e9l. Yo s\u00e9 esto, y mucho m\u00e1s, y sin embargo, la misericordia de Dios para m\u00ed es un misterio tal que he estado tentado a pensar que era totalmente indigno de sufrir. \u00a1Dios ten piedad de mis pensamientos! Puede que no pueda soportar el sufrimiento. No s\u00e9. Pero me postro a Tus pies y digo: &#8216;No es que est\u00e9 preparado, sino que T\u00fa eres bueno y sabio, y me preparar\u00e1s&#8217;\u201d. (<em>Norman Macleod.<\/em>)<\/p>\n<\/p>\n<p><strong>Renuncia<\/strong><\/p>\n<p>De todas las misiones inglesas m\u00e1s peque\u00f1as, Livingstone Congo destaca por su desbordante celo, vida y promesa; y de todos sus agentes, el joven M&#8217;Call era el m\u00e1s brillante; pero fue derribado en medio del trabajo. Sus \u00faltimas palabras fueron grabadas por un extra\u00f1o que lo visit\u00f3. Que cada uno de nosotros las ponga en nuestro coraz\u00f3n. \u201cSe\u00f1or, me entregu\u00e9 en cuerpo, mente y alma a Ti, consagr\u00e9 toda mi vida y mi ser a Tu servicio; y ahora, si te place tomarme a m\u00ed mismo, en lugar del trabajo que yo har\u00eda por ti, \u00bfqu\u00e9 me importa a m\u00ed? H\u00e1gase tu voluntad.\u201d (<em>RN Cust.<\/em>)<\/p>\n<\/p>\n<p><strong>La tristeza y el abandono de Cristo<\/strong><\/p>\n<p>Est\u00e1 m\u00e1s all\u00e1 de nuestro poder determinar la cantidad precisa de sufrimiento sufrido por nuestro Se\u00f1or; pues un misterio rodea necesariamente a la persona de Jes\u00fas, en el que se combinan dos naturalezas. Este misterio puede impedirnos saber c\u00f3mo Su humanidad fue sostenida por Su divinidad. Aun as\u00ed, indudablemente, la representaci\u00f3n general de las Escrituras llevar\u00eda a la conclusi\u00f3n de que, aunque \u00c9l era Dios absoluto, con todos los poderes y prerrogativas de la Deidad, Cristo, como hombre, era abandonado a los mismos conflictos y depend\u00eda de las mismas ayudas que \u00e9l. cualquiera de sus seguidores. Se diferenci\u00f3, de hecho, inconmensurablemente, en que fue concebido sin la mancha del pecado original, y por lo tanto estaba libre de nuestras malas propensiones: vivi\u00f3 la vida de fe que \u00c9l mismo labr\u00f3, y la vivi\u00f3 para ganar para nosotros una lugar en el reino de Su Padre. Aunque en realidad iba a hacer frente a la aflicci\u00f3n como un hombre, se qued\u00f3 sin ning\u00fan apoyo externo desde arriba. Esto se muestra muy notablemente en Su agon\u00eda en el jard\u00edn, cuando un \u00e1ngel fue enviado para fortalecerlo. \u00a1Maravilloso que una persona Divina haya anhelado asistencia, y que \u00c9l no recurri\u00f3 a Sus propios recursos inagotables! Pero fue como un hombre que luch\u00f3 con los poderes de las tinieblas, como un hombre que no pod\u00eda recibir ayuda celestial. Y, si esta es una interpretaci\u00f3n verdadera del modo en que nuestro Se\u00f1or enfrent\u00f3 la persecuci\u00f3n y la muerte, debemos tener raz\u00f3n al compararlo con los m\u00e1rtires, cuando afirmamos una diferencia inconmensurable entre sus sufrimientos y los de los hombres que han muerto noblemente por ellos. la verdad: de \u00c9l se retir\u00f3 la luz del rostro del Padre, mientras que a ellos se les mostr\u00f3 conspicuamente. Esto puede explicar por qu\u00e9 Cristo estaba confundido y abrumado, donde otros hab\u00edan estado serenos e impert\u00e9rritos. Sin embargo, surge la pregunta: \u00bfPor qu\u00e9 Cristo fue as\u00ed abandonado del Padre? \u00bfPor qu\u00e9 le negaron esos consuelos y apoyos que con frecuencia han sido concedidos a sus seguidores? Sin duda es un espect\u00e1culo tan sorprendente como lastimoso el de nuestro Se\u00f1or retrocediendo ante la angustia de lo que le ha de sobrevenir, mientras otros han afrontado la muerte, en sus formas m\u00e1s espantosas, con imperturbable serenidad. Nunca se puede dar cuenta de esto, excepto reconociendo que nuestro Se\u00f1or no era un hombre ordinario, que encontr\u00f3 la muerte como un mero testigo de la verdad, sino que en realidad fue una ofrenda por el pecado; llevando el peso de las iniquidades del mundo. Su agon\u00eda, Sus llantos lastimeros, Su sudoraci\u00f3n, como si fueran grandes gotas de sangre; estos no deben explicarse sobre la suposici\u00f3n de que \u00c9l es simplemente un hombre inocente, perseguido por enemigos feroces e implacables. Si \u00c9l hubiera sido s\u00f3lo esto, \u00bfpor qu\u00e9 habr\u00eda de ser aparentemente tan superado en confianza y compostura por una larga l\u00ednea de m\u00e1rtires y confesores? Cristo fajo m\u00e1s que esto. Aunque no hab\u00eda cometido pecado, estaba en el lugar de los pecadores, soportando el peso de la indignaci\u00f3n divina y haci\u00e9ndole sentir los terrores de la ira divina. \u00a1Inocente, fue tratado como culpable! Se hab\u00eda hecho a s\u00ed mismo el sustituto de los culpables, de ah\u00ed su angustia y terror. Tenga en cuenta que la v\u00edctima que exhibe, como podr\u00eda pensar, mucha menos compostura y firmeza de lo que han demostrado muchos cuando se le pidi\u00f3 que muriera por la verdad, tenga en cuenta que a esta v\u00edctima se le ha impuesto la iniquidad de un mundo. sus hombros; que Dios ahora est\u00e1 tratando con \u00c9l como el representante del hombre ap\u00f3stata, y exigi\u00e9ndole las penas debidas a innumerables transgresiones; y dejar\u00e1s de asombrarte, aunque todav\u00eda casi te estremecer\u00e1s ante las palabras, tan expresivas de agon\u00eda: \u201cMi alma est\u00e1 muy triste, hasta la muerte\u201d. (<em>H. Melvill, BD<\/em>)<\/p>\n<\/p>\n<p><strong>La agon\u00eda del alma de Cristo<\/strong><\/p>\n<p>Est\u00e1 en el sufrimientos del alma que quisi\u00e9ramos fijar vuestra atenci\u00f3n; porque estas, no lo dudamos, fueron las poderosas resistencias del Redentor; estas lo persiguieron hasta sus \u00faltimos momentos, hasta que pag\u00f3 el \u00faltimo fragmento de nuestras deudas. Percibir\u00e1s que fue en el alma y no en el cuerpo que nuestro bendito Salvador hizo expiaci\u00f3n por la transgresi\u00f3n. Se hab\u00eda puesto en el lugar del criminal, en la medida en que era posible que un hombre inocente asumiera la posici\u00f3n del culpable; y poni\u00e9ndose en el lugar del criminal, con la culpa imputada a \u00c9l, tuvo que soportar el castigo en que hab\u00edan incurrido las fechor\u00edas. Deb\u00e9is ser conscientes de que la angustia del alma m\u00e1s que del cuerpo es la porci\u00f3n eterna de los pecadores; y aunque, por supuesto, no podemos pensar que nuestro Se\u00f1or soport\u00f3 precisamente lo que los pecadores merec\u00edan, porque no pod\u00eda haber sabido nada de los aguijones y los cuerpos de la conciencia bajo los cuales deb\u00edan retorcerse eternamente, sin embargo, puesto que estaba agotando su maldici\u00f3n, una maldici\u00f3n que iba a llevar la ruina a su alma as\u00ed como a atormentar el cuerpo con un dolor indescriptible, bien podr\u00edamos esperar que la angustia del alma por una garant\u00eda o un sustituto se sintiera a\u00fan m\u00e1s que la del cuerpo: y que la aflicci\u00f3n externa, por vasta y acumulada que fuera, ser\u00eda comparativamente menor en su rigor o acompa\u00f1amientos, que Su angustia interna, que no se puede medir ni imaginar. Esta expectativa es ciertamente confirmada por las declaraciones de las Escrituras, si se las considera cuidadosamente. De hecho, es muy observable que cuando nuestro Se\u00f1or se presenta ante nosotros mostrando signos de angustia y aflicci\u00f3n, no hubo sufrimiento corporal alguno, ninguno excepto el que fue causado mentalmente. Me refiero, como deben saber, a la escena en el jard\u00edn, inmediatamente relacionada con nuestro texto, cuando el Redentor manifest\u00f3 el dolor y el horror m\u00e1s intensos, siendo Su sudor como grandes gotas de sangre, una escena que insensible apenas puede encontrar: en este caso no hubo clavo, ni lanza. S\u00ed, aunque exist\u00eda la perspectiva de la cruz, apenas hab\u00eda miedo. Fue el pensamiento de morir como un malhechor lo que venci\u00f3 tanto al Redentor, que necesit\u00f3 la fuerza de un \u00e1ngel del cielo. Que fue eso lo que arranc\u00f3 la conmovedora exclamaci\u00f3n: \u201cMi alma est\u00e1 muy triste\u201d. Est\u00e1 mucho m\u00e1s all\u00e1 de nosotros decirles cu\u00e1les fueron las resistencias espirituales que tanto angustiaron y abrumaron al Redentor. Hay un velo sobre la angustia del Dios encarnado que ninguna mano mortal puede intentar quitar. Solo puedo suponer que, siendo santo, incapaz de pecar de pensamiento o de hecho, ten\u00eda un sentido penetrante y abrumador de la criminalidad del pecado, de la deshonra que atribu\u00eda al mundo, de la ruina que estaba trayendo al hombre. Debe haber sentido como ning\u00fan otro ser pod\u00eda, el poderoso temor del pecado, vinculado por igual con Dios y con el hombre, los hermanos de los pecadores, y el ser contra el cual se pec\u00f3. \u00bfQui\u00e9n puede dudar de que, al llevar nuestras transgresiones en nuestra naturaleza, debe haber sido herido como con una espada de dos filos, lacer\u00e1ndolo con un filo porque estaba celoso de la gloria divina, y con el otro porque anhelaba la felicidad humana? Aunque no podemos explicar lo que pas\u00f3 en el alma del Redentor, queremos inculcarles la verdad de que fue en el alma y no en el cuerpo donde se soportaron esos terribles dolores que agotaron la maldici\u00f3n denunciada contra el pecado. Que nadie piense que la mera angustia corporal equival\u00eda a las miserias y las torturas que deb\u00edan ser eternamente exigidas a todo ser humano. Quitar\u00eda mucho de la terrible condenaci\u00f3n futura de los impenitentes representar esos sufrimientos como s\u00f3lo, o principalmente, corporales. Los hombres argumentar\u00e1n la naturaleza del destino, no la naturaleza de la capacidad de sufrimiento en su lugar. Y, ciertamente, un infierno sin agon\u00eda mental, ser\u00eda un para\u00edso en comparaci\u00f3n con lo que creemos que es el pandem\u00f3nium, donde el alma es el potro y la conciencia el verdugo. \u00a1No os vay\u00e1is del Calvario pensando en nada m\u00e1s que sufrir una muerte al ser clavados en una cruz y dejados morir despu\u00e9s de una larga tortura! Vete, m\u00e1s bien pensando en el horror que se hab\u00eda apoderado del alma de la v\u00edctima abandonada; y mientras llevas contigo un recuerdo del doloroso espect\u00e1culo, y te golpeas el pecho al pensar en Su lastimero grito, un grito m\u00e1s sobrecogedor que el estruendo del terremoto que anunci\u00f3 Su muerte, toma en serio Sus inimaginables resistencias que extorsionan a los clamar: \u201cMi alma est\u00e1 muy triste, hasta la muerte\u201d. (<em>H. Melvill, BD<\/em>)<\/p>\n<\/p>\n<p><strong>Bendiciones por la agon\u00eda del alma de Cristo<\/strong><\/p>\n<p>Es esto muerte: este trabajo del alma, que desde el principio hasta el final de una vida cristiana est\u00e1 efectuando o produciendo esa criatura m\u00e1s santa que finalmente se presentar\u00e1 sin mancha ni arruga, id\u00f3nea para la herencia de los santos en luz. Es en las angustias del alma que siente la influencia renovadora del Esp\u00edritu Santo, realizada en el nacimiento del car\u00e1cter cristiano, que en cualquier \u00e9poca del mundo recupera la imagen desfigurada de su Dios. Pienso que da una preciosidad a todos los medios de gracia, considerarlos as\u00ed como producidos por las agon\u00edas del Redentor. Ser\u00eda muy lejos, si se tuviera esto en cuenta, defenderlo contra la resistencia o el descuido, si se les inculcara que no hay una sola bendici\u00f3n de la que sean conscientes, que no surja de este dolor, este dolor para muerte del alma del Redentor. \u00bfPodr\u00edas tomar a la ligera, como tal vez lo haces ahora, esas advertencias y amonestaciones secretas que no sabes de d\u00f3nde vienen, incit\u00e1ndote a abandonar ciertos pecados y prestar atenci\u00f3n a ciertos deberes, si estuvieras impresionado de que fue a trav\u00e9s del alma misma de estando el Redentor \u201cmuy triste, hasta la muerte\u201d, que se os obtuvo el privilegio de acceder a Dios por medio de la oraci\u00f3n, o que se os hicieran ofrendas de perd\u00f3n y reconciliaci\u00f3n? \u00bfCrees que podr\u00edas arrodillarte irreverente o formalmente, o que podr\u00edas tratar la ordenanza de la predicaci\u00f3n como una mera instituci\u00f3n humana, respecto de la cual poco importaba si hablabas en serio o no? El recuerdo de que el alma de Cristo se afan\u00f3 en agon\u00eda para procurarte esas bendiciones -que, por ser abundantes, puedes sentirte tentado a subestimar- impartir\u00eda necesariamente una preciosidad al conjunto. No pod\u00edas ser indiferente al amargo llanto; no pod\u00edas mirar l\u00e1nguidamente la escena mientras ve\u00edas la cruz. Esto es un hecho; fue s\u00f3lo por el dolor, el dolor hasta la muerte del alma del Redentor, que cualquiera de los medios ordinarios de gracia, esos medios que est\u00e1is disfrutando diariamente, han sido adquiridos. \u00bfVas a pensar poco en esos medios? \u00bfLos descuidar\u00e1s? \u00bfJugar\u00e1s con ellos? \u00bfNo preferir\u00e1s sentir que lo que cuesta tanto comprar, debe ser fatal despreciarlo? Tampoco, como dijimos, valen s\u00f3lo los medios de gracia para que aprend\u00e1is del gran dolor con que fueron comprados; es tambi\u00e9n tu propio valor, el valor de tu propia alma. Cuando hablamos del alma y tratamos de impresionar a los hombres con un sentido de su valor, podemos esforzarnos por establecer la naturaleza de sus propiedades, sus poderes, sus capacidades, sus destinos, pero podemos avanzar muy poco; mostramos poco m\u00e1s que nuestra ignorancia, pues buscar c\u00f3mo queremos el alma es un misterio; es como la Deidad, de la cual es la chispa; se esconde por su propia luz; y elude deslumbrando al que pregunta. Recordar\u00e1s, que nuestro Se\u00f1or pregunt\u00f3 enf\u00e1ticamente: \u201c\u00bfQu\u00e9 dar\u00e1 el hombre a cambio de su alma?\u201d Est\u00e1 impl\u00edcito en la pregunta, que si el mundo entero fuera ofrecido en trueque -el mundo, con todos sus honores y sus riquezas- \u00e9l ser\u00eda el m\u00e1s tonto de los tontos que consentir\u00eda en el intercambio, y ser\u00eda un perdedor hasta cierto punto. m\u00e1s all\u00e1 del pensamiento, al tomar la creaci\u00f3n y entregar su alma. Entonces te escucho decir: \u201c\u00a1Todo esto es una teor\u00eda!\u201d Puede ser as\u00ed. \u201c\u00a1El mundo en una escala, no es m\u00e1s que una part\u00edcula de polvo para el alma en la otra! Nos gustar\u00eda ver un intercambio real: esto podr\u00eda asegurarnos el valor incalculable que desea demostrar\u201d. Y, hermanos m\u00edos, ver\u00e9is un alma humana puesta de un lado y el equivalente del otro. \u00a1Ver\u00e1s un intercambio! No el intercambio, \u00a1el repugnante intercambio que es diario, s\u00ed, cada hora! hecho-el cambio del alma por una chucher\u00eda, por una sombra; un intercambio, del que incluso aquellos que lo hacen se asustar\u00edan si pensaran en lo que est\u00e1n haciendo, se asustar\u00edan si supieran hasta qu\u00e9 punto son perdedores y no ganadores por el trato. El intercambio que tenemos que exhibir es un intercambio justo. Lo que se da por el alma es lo que vale el alma. \u00a1Ven con nosotros y esfu\u00e9rzate por contemplar las glorias del Dios invisible, Aquel que se ha entristecido en el alma, \u201cporque se despoj\u00f3 a s\u00ed mismo, y se despoj\u00f3 a s\u00ed mismo\u201d, para que el alma pudiera ser salva! \u00a1Ven con nosotros al establo de Bel\u00e9n! \u00a1Ven con nosotros al Calvario! La asombrosa acumulaci\u00f3n de la que eres espectador, el terrible dolor que apenas te atreves a mirar, la agon\u00eda de Aquel que no cometi\u00f3 pecado, la agon\u00eda de Aquel que era el Se\u00f1or de la gloria, la muerte de Aquel que era el Pr\u00edncipe. de Luz-esto fue dado para el alma; por esta acumulaci\u00f3n se efectu\u00f3 la redenci\u00f3n. \u00bfNo hay aqu\u00ed un intercambio, un intercambio realmente hecho, con el cual podr\u00edamos demostrar que es imposible sobrestimar el valor del alma? Si lees la forma de la pregunta: \u201c\u00bfQu\u00e9 dar\u00e1 el hombre a cambio de su alma?\u201d ver\u00e1s que implica que no est\u00e1 dentro del imperio de la riqueza comprar el alma. Pero esto no puede asumir la forma de otra pregunta: \u00bfQu\u00e9 dar\u00eda Dios a cambio del alma? Aqu\u00ed tenemos una respuesta, no de suposici\u00f3n, sino de hecho: les decimos lo que Dios ha dado, \u00c9l se ha dado a s\u00ed mismo. (<em>H. Melvill, BD<\/em>)<\/p>\n<\/p>\n<p><strong>Renuncia total<\/strong><\/p>\n<p>Un ministro, siendo solicitado por un amigo, durante su \u00faltima enfermedad, ya sea que se creyera moribundo, respondi\u00f3: \u201cEn verdad, amigo, no me importa si lo estoy o no. Si muero, estar\u00e9 con Dios; y, si vivo, Dios estar\u00e1 conmigo.\u201d<\/p>\n<p><strong>Instancia de renuncia<\/strong><\/p>\n<p>Durante el sitio de Barcelona, en 1705, el Capit\u00e1n Carleton presenci\u00f3 la siguiente incidente conmovedor, que relata en sus memorias: \u201cVi a un anciano oficial, teniendo a su \u00fanico hijo con \u00e9l, un buen joven de unos veinte a\u00f1os, entrando en su tienda para cenar. Mientras estaban cenando, un tiro le cort\u00f3 la cabeza al hijo. El padre se levant\u00f3 de inmediato, y primero mirando hacia abajo a su hijo sin cabeza, y luego levantando los ojos al cielo, mientras las l\u00e1grimas corr\u00edan por sus mejillas, solo dijo: &#8216; \u00a1H\u00e1gase tu voluntad!&#8217;\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mar 14:32-36 Que se llam\u00f3 Getseman\u00ed. El conflicto en Getseman\u00ed I. El lugar del conflicto requiere un breve aviso. II. La historia del conflicto. Su intensidad es el primer hecho de la historia que nos llama la atenci\u00f3n. \u201cSu sudor era como grandes gotas de sangre que ca\u00edan a tierra\u201d. Este conflicto arranc\u00f3 del Salvador &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-marcos-1432-36-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Marcos 14:32-36 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39145","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=39145"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39145\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=39145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=39145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=39145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}