{"id":39146,"date":"2022-07-16T08:45:44","date_gmt":"2022-07-16T13:45:44","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-marcos-1438-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:45:44","modified_gmt":"2022-07-16T13:45:44","slug":"estudio-biblico-de-marcos-1438-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-marcos-1438-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Marcos 14:38 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Mar 14:38<\/span><\/p>\n<p><em>El esp\u00edritu verdaderamente est\u00e1 lista, pero la carne es d\u00e9bil.<\/em><\/p>\n<\/p>\n<p>1. Pienso, dir\u00e1n algunos, que mi pecado es un pecado de enfermedad porque es peque\u00f1o. Pero si miras en <span class='bible'>1Sa 15:1-35<\/span>, puedes leer que el pecado de Sa\u00fal, por el cual el Se\u00f1or lo rechaz\u00f3, no era de gran volumen exterior; porque perdon\u00f3 a los engordados para poder sacrificarlos. Una gran cantidad de pecados peque\u00f1os pueden hacer un bulto tan grande como un pecado grave; s\u00ed, posiblemente haya mucha pecaminosidad y maldad al cometer un pecado peque\u00f1o; porque como entre los hombres, es la mayor descortes\u00eda romper con otro por un asunto menor; as\u00ed con Dios, romper con Dios por una cosa peque\u00f1a; y se puede ver mucha habilidad en un trabajo peque\u00f1o; un peque\u00f1o reloj, etc. Para que su habilidad en el pecado se vea en un peque\u00f1o pecado; Nunca es peque\u00f1o su pecado el que lo piensa peque\u00f1o.<\/p>\n<p><strong>2. <\/strong>Pero creo que mi pecado es un pecado de enfermedad porque soy tentado a \u00e9l y porque otros me atraen. Pero, ruego, \u00bfno fue tentado Ad\u00e1n por Eva a comer del fruto prohibido? \u00bfY no fue Eva tentada por Satan\u00e1s? \u00bfY llamar\u00e1s a eso un pecado de enfermedad que conden\u00f3 a todo el mundo como lo hizo el pecado de Ad\u00e1n?<\/p>\n<p><strong>3. <\/strong>Pero creo que mi pecado es un pecado de enfermedad porque lucho contra \u00e9l. Y, ruego, \u00bfno luch\u00f3 Pilato contra la crucifixi\u00f3n de Cristo? Posiblemente, por tanto, un hombre puede luchar contra su pecado, y sin embargo el pecado no es pecado de enfermedad.<\/p>\n<p><strong>4. <\/strong>Pero mi pecado es un pecado de debilidad porque estoy angustiado despu\u00e9s de \u00e9l. \u00bfY no se turb\u00f3 Esa\u00fa despu\u00e9s de haber vendido su primogenitura por un plato de lentejas; \u00bfNo la busc\u00f3 con l\u00e1grimas? Yo lucho contra ella, y aunque me angustio tras ella, puede que no sea pecado de debilidad.<\/p>\n<p>Pero como algunos se extrav\u00edan con la mano izquierda, pensando que sus pecados son pecados de debilidad, cuando en verdad no lo son: por lo que otros de la derecha se equivocan, y piensan que sus pecados no son pecados de flaqueza, sino de peor naturaleza, cuando en verdad lo son: y que por estas razones:<\/p>\n<p>1. <\/strong>Oh, dice uno, temo que mi pecado no es un pecado de enfermedad, porque peco a sabiendas y con deliberaci\u00f3n; Peco contra mi conocimiento y contra mi conciencia, y por lo tanto mi pecado no puede ser pecado de enfermedad. Pero para responder a esto, debes saber que una cosa es que un hombre peque a sabiendas, y otra cosa es que un hombre peque por conocimiento, o contra su conocimiento. Un hombre peca por ignorancia cuando la ignorancia es la \u00fanica compa\u00f1era de su pecado: un hombre peca por ignorancia, cuando la ignorancia es la \u00fanica causa de su pecado, y no la \u00fanica compa\u00f1era.<\/p>\n<p><strong>2. <\/strong>Oh, pero temo que mi pecado no sea un pecado de enfermedad, porque una y otra vez caigo en \u00e9l, y me acuesto en \u00e9l. \u00bfPero sab\u00e9is lo que es mentir en el pecado? Hay mucho error acerca de mentir en el pecado. Ahora bien, si as\u00ed te mantienes y mientes en tu pecado, \u00bfpor qu\u00e9 te quejas tanto? esta tu queja argumenta que hay algo de purga, y por lo tanto no mientes en el pecado.<\/p>\n<p><strong>3. <\/strong>Oh, pero me temo que mi pecado no puede ser un pecado de enfermedad, porque caigo en \u00e9l despu\u00e9s de haber sido advertido de su maldad. A eso no digo m\u00e1s, pero deseo que consideren el ejemplo que est\u00e1 aqu\u00ed ante ustedes. Los disc\u00edpulos se durmieron, nuestro Se\u00f1or y Salvador Cristo viene y los despierta; s\u00ed, y \u00c9l los reprende tambi\u00e9n: \u201c\u00bfQu\u00e9 (dice \u00c9l) no pod\u00e9is velar Conmigo una hora Yo vigilo y oro\u201d? y sin embargo volvieron a aplaudir: y \u00c9l viene y los despierta de nuevo, y los amonesta de nuevo, y sin embargo se durmieron de nuevo. Es posible, por lo tanto, que un hombre pueda caer en el mismo pecado una y otra vez, s\u00ed, incluso despu\u00e9s de la amonestaci\u00f3n, y sin embargo puede ser un pecado de debilidad. Sin embargo, cu\u00e1ntas pobres almas hay, que se equivocan aqu\u00ed en la mano derecha, y piensan que sus pecados no son pecados de enfermedad, cuando en verdad lo son. Pero si hay tales errores, \u00bfc\u00f3mo entonces sabremos si nuestros pecados son pecados de enfermedad<\/p>\n<p><strong>1. <\/strong>Negativamente, Que no es pecado de enfermedad, que es un pecado grosero, inmundo, escandaloso, cometido con deliberaci\u00f3n y consulta.<\/p>\n<p><strong>2. <\/strong>Si el pecado es un cabecilla de otros pecados inmundos, no es pecado de enfermedad. El pecado principal es el pecado m\u00e1s atroz. Y ves c\u00f3mo es entre los hombres; si hay rebeli\u00f3n o insurrecci\u00f3n, toman al cabecilla y lo golpean, porque dicen: Este es el gran transgresor, porque \u00e9l es el cabecilla. As\u00ed que entre los pecados, el gran pecado es el cabecilla; y por lo tanto, si tu pecado es un cabecilla de otros pecados inmundos, no es un pecado de debilidad.<\/p>\n<p><strong>3. <\/strong>Un pecado de presunci\u00f3n no es un pecado de debilidad. Los pecados de presunci\u00f3n y los pecados de debilidad se oponen entre s\u00ed en <span class='bible'>N\u00fam 15,1-41<\/span> y <span class='biblia'>Sal 19:1-14<\/span>. Y cuando un hombre peca, por tanto, m\u00e1s bien porque Dios es misericordioso, o porque el pecado no es m\u00e1s que un pecado de debilidad, o porque espera arrepentirse despu\u00e9s, o porque su pecado puede permanecer con la gracia; esto es pecado de presunci\u00f3n, y no es pecado de debilidad: los pecados de presunci\u00f3n no son pecados de debilidad.<\/p>\n<p><strong>4. <\/strong>Adem\u00e1s, si el pecado es un pecado que reina, entonces no es pecado de debilidad, porque cuando el pecado reina, la gracia no; por eso dice el ap\u00f3stol (<span class='bible'>Rom 6,1-23<\/span>), \u201cQue el pecado no se ense\u00f1oree de vosotros, porque no sois bajo la ley sino bajo la gracia\u201d; y cuando el pecado reina, est\u00e1 en toda su fuerza.<\/p>\n<p>\u00bfPero c\u00f3mo sabremos, entonces, afirmativamente, si nuestro pecado es pecado de enfermedad?<\/p>\n<p><strong>1. <\/strong>As\u00ed: Si procede simplemente de la falta de edad en el cristianismo, entonces es, sin duda, un pecado de enfermedad. Los beb\u00e9s son d\u00e9biles y est\u00e1n llenos de debilidades.<\/p>\n<p><strong>2. <\/strong>Si no es otro pecado que el incidente de todos los santos, entonces es un pecado de enfermedad; porque el pecado que cometen todos los santos, no es pecado reinante, sino pecado mortificado.<\/p>\n<p><strong>3. <\/strong>Si es un pecado que no puedes evitar, que irrumpe en ti antes de que te des cuenta, incluso antes de que puedas pedir ayuda a tu raz\u00f3n y consideraci\u00f3n, y que la inclinaci\u00f3n general y la estructura de tu coraz\u00f3n y el alma est\u00e1 en contra, entonces es un pecado de debilidad, porque entonces surge de la falta de fuerza para resistir, y no de la voluntad de cometer. Este fue el caso de Pablo (<span class='bible'>Rom 7,1-25<\/span>)<em> <\/em>cuando el mal estaba presente con \u00e9l, estando en contra de la inclinaci\u00f3n general y el marco de su alma; porque dice: \u201cMe deleito en la ley de Dios seg\u00fan el hombre interior, y sin embargo lo que no quiero hacer, eso hago.\u201d<\/p>\n<p><strong>4. <\/strong>Una enfermedad dif\u00edcilmente se reconocer\u00e1 a s\u00ed misma como un pecado de enfermedad; pero la persona en quien est\u00e1, teme que sea peor. Si su pecado surge principalmente de alguna causa externa, es un pecado de enfermedad; porque no es tanto por la voluntad de cometer, como por la falta de fuerza para resistir. El pecado del que habla el ap\u00f3stol (<span class='bible'>Gal 6,1<\/span>) es un pecado de enfermedad, y el que lo comete se dice que es vencido . Ahora bien, cuando un hombre est\u00e1 en su viaje de viaje y es alcanzado por otra persona, su inclinaci\u00f3n y disposici\u00f3n internas no era para encontrarse con el otro: as\u00ed cuando un hombre es alcanzado por el pecado, se argumenta que su pecado procede de alguna causa externa; y cuando procede de alguna causa externa, entonces se dice verdaderamente que es alcanzado por ella.<\/p>\n<p><strong>5. <\/strong>La enfermedad ama la amonestaci\u00f3n: quiero decir, la persona que peca debido a la enfermedad, ama la amonestaci\u00f3n, toma la amonestaci\u00f3n amablemente y bendice a Dios por ello.<\/p>\n<p><strong>6. <\/strong>La enfermedad descubre el bien, aunque sea en s\u00ed misma mala; es un pecado malo, pero una buena se\u00f1al. El cardo es una mala hierba, sin embargo, encuentra una grasa y una buena venta; el humo enferma, pero descubre el fuego.<\/p>\n<p><strong>7. <\/strong>Los pecados de las enfermedades son siervos y sacadores de agua para vuestras gracias; aunque en s\u00ed mismos son malos, sin embargo, a trav\u00e9s de la mano dominante de la gracia de Dios, te har\u00e1n m\u00e1s misericordioso de otra manera. Vosotros sab\u00e9is lo que ocurre con un joven comerciante, que tiene pocas existencias; mantiene su tienda diligentemente y no gastar\u00e1 como los dem\u00e1s. Si le preguntas la raz\u00f3n, diciendo: Tales y tales hombres son de tu oficio, y gastar\u00e1n su chel\u00edn con nosotros, y su tiempo con nosotros; \u00bfPor qu\u00e9 no vas a hacer como ellos? Responde enseguida: Cierto, as\u00ed lo hacen, y pueden hacerlo, su patrimonio lo soportar\u00e1; pero en cuanto a m\u00ed, mi ganado es peque\u00f1o, muy peque\u00f1o, por lo tanto, no puedo hacer como ellos, pero debo ser diligente y un buen marido; No soy m\u00e1s que un joven principiante y tengo poca habilidad en el oficio, por lo que me corresponde ser diligente. Su misma debilidad es la causa de su diligencia. As\u00ed que aqu\u00ed, cuantas m\u00e1s enfermedades sufra un alma llena de gracia, m\u00e1s diligente ser\u00e1; y si le preguntas, \u00bfPor qu\u00e9 te esfuerzas tanto en seguir los medios y cosas por el estilo? \u00e9l responde: \u00a1Ay, soy una pobre criatura d\u00e9bil! Hay tal o cual persona que tiene una excelente memoria, todo lo que lee u oye es suyo; pero mi memoria es nula, mi cabeza y mi coraz\u00f3n son nulos, y por lo tanto, por la gracia de Dios, me esforzar\u00e9 m\u00e1s en seguir a Cristo. As\u00ed, su misma debilidad es una provocaci\u00f3n a toda su diligencia.<\/p>\n<p><strong>8. <\/strong>La enfermedad mantiene constantemente el coraz\u00f3n del hombre abatido, abatido y humilde. Si uno tiene una debilidad en su habla, no estar\u00e1 tan dispuesto a hablar como los dem\u00e1s; pero siendo consciente de su propia debilidad, siempre est\u00e1 abatido y temeroso de hablar. As\u00ed espiritualmente. Pero supongamos que mi pecado no sea otro que un pecado de enfermedad, \u00bfentonces qu\u00e9? El tercero te responde. Entonces, siendo vuestro pecado s\u00f3lo una enfermedad, Cristo nunca os dejar\u00e1 por ello, ni os abandonar\u00e1 por ello; pero si duermes, \u00c9l te despertar\u00e1; y si vuelves a dormir, \u00c9l te despertar\u00e1 de nuevo. Oh, qu\u00e9 dulce gracia es esta. \u00bfNo hay mal entonces en este pecado de enfermedad? S\u00ed, mucho, mucho: porque aunque sea un caj\u00f3n de agua para vuestra gracia, sin embargo, es un gabaonita, un nativo, un cananeo, que en todas las ocasiones estar\u00e1 listo para traicionaros y abrir la puerta a ladrones mayores. , y siempre ser\u00e1 una espina y un aguij\u00f3n en vuestros costados; y aunque no apague tu luz, es un ladr\u00f3n en tu vela, que puede manchar mucho de tu comodidad y manchar tu deber. Vosotros sab\u00e9is c\u00f3mo es con una buena pluma de escribir; si hay un peque\u00f1o cabello en \u00e9l, aunque el cabello nunca sea tan peque\u00f1o, sin embargo, si no se arranca, a veces manchar\u00e1 y da\u00f1ar\u00e1 toda la escritura. As\u00ed lo haga el pecado de la enfermedad; todo tu deber puede ser borrado y manchado por este peque\u00f1o cabello, y aunque Dios puede y hace uso de tus debilidades para guardar tus gracias, sin embargo, no son m\u00e1s que tus heces y heces, mientras que tus gracias deber\u00edan ser todas refinadas. \u00a1Oh, qu\u00e9 cosa tan mala es, pues, que un hombre no sea refinado! Y aunque Cristo no te desechar\u00e1 por un pecado de debilidad, sin embargo, puedes provocarlo para que te reprenda y se enoje contigo. La incredulidad de los disc\u00edpulos no era m\u00e1s que su enfermedad, sin embargo, Cristo los reprendi\u00f3 por su incredulidad. En tercer lugar, aunque haya mucho mal en este pecado, Cristo no te desechar\u00e1 por \u00e9l. Porque es una honra para el hombre pasar por delante de las enfermedades, dice Salom\u00f3n; mucho m\u00e1s es para el honor de Cristo pasar por alto las enfermedades de su pueblo. Los santos y el pueblo de Dios est\u00e1n en pacto con Dios por medio de Jesucristo, y ese pacto es un pacto conyugal (<span class='bible'>Os 2:1-23<\/a>). Pero, \u00bfqu\u00e9 marido repudiar\u00e1 a su mujer por sus enfermedades? Ese pacto es un pacto paternal, y \u00bfqu\u00e9 padre arrojar\u00e1 a su hijo fuera de la casa por sus enfermedades? Un ni\u00f1o, aunque deforme, es m\u00e1s agradable al padre, porque el ni\u00f1o es suyo, que otro hermoso ni\u00f1o que no es suyo. Si un amo rechazara a su sirviente por cada falla y debilidad, \u00bfqui\u00e9n lo servir\u00eda? Ahora bien, dice Lutero, \u00bfqu\u00e9 hombre se cortar\u00eda la nariz porque tiene suciedad? s\u00ed, aunque la nariz sea el fregadero del cerebro, sin embargo, porque es un miembro, el hombre no la cortar\u00e1. \u00bfY Cristo cortar\u00e1 uno de Sus miembros, porque hay inmundicia en \u00e9l, o alguna debilidad y enfermedad en \u00e9l? \u00bfQu\u00e9 padre golpear\u00e1 a su hijo en la cabeza, porque le crece una verruga en la frente? Estas enfermedades en los santos y el pueblo de Dios son sus verrugas, que crecen en la cara de su conversaci\u00f3n: los mismos benditos m\u00e1rtires ten\u00edan estas verrugas: Hierom de Praga ten\u00eda una gran verruga, Cranmer otra, Jewel otra; s\u00ed, si nos fijamos en ese peque\u00f1o gancho de Cr\u00f3nicas, me refiero a <span class='bible'>Heb 11:1-40<\/span>, qu\u00e9 santo se menciona all\u00ed seg\u00fan consta, pero ten\u00eda una verruga u otra? \u00bfNo tuvo Abraham su verruga al decir que Sara era su hermana? \u00bfNo hab\u00eda Sarah la suya al re\u00edrse? \u00bfNo ten\u00edan Jacob, Isaac y Jos\u00e9 los suyos? Mois\u00e9s, Rahab, Sans\u00f3n, Jeft\u00e9 y David de ellos? Lutero tuvo la suya, y nuestros reformadores la suya; sin embargo, Dios los reconoci\u00f3, los us\u00f3 y los honr\u00f3. Ciertamente, pues, aunque haya mucho mal en el pecado de la enfermedad, especialmente si uno cae en \u00e9l una y otra vez; sin embargo, Cristo no dejar\u00e1 a un hombre, ni lo abandonar\u00e1 por eso. Si estas cosas son ciertas, entonces qu\u00e9 necesidad hay sobre nosotros, y qu\u00e9 gran causa tenemos para examinarnos a nosotros mismos y considerar seriamente qu\u00e9 tipo de pecados son esos pecados bajo los cuales trabajamos.<\/p>\n<p>Pero es parece que todos los pecados de los piadosos no son pecados de enfermedad, y Dios no desechar\u00e1 a un hombre piadoso por ning\u00fan pecado: \u00bfqu\u00e9 ventaja, por lo tanto, tiene este pecado de enfermedad sobre otros pecados? o \u00bfen qu\u00e9 desventaja trabajan los otros pecados de los piadosos, que este pecado de enfermedad no hace?<\/p>\n<p><strong>1. <\/strong>Mucho, mucho: porque aunque mi pecado sea grande; pero si es un pecado de enfermedad, no impedir\u00e1 la presente aceptaci\u00f3n de mi deber.<\/p>\n<p><strong>2. <\/strong>Aunque mi pecado sea grande, aunque s\u00f3lo sea una enfermedad, no impedir\u00e1 el sentido de mi justificaci\u00f3n.<\/p>\n<p><strong>3. <\/strong>Aunque mi pecado sea grande, sin embargo, si no es m\u00e1s que una enfermedad, hay un perd\u00f3n que est\u00e1 en curso para \u00e9l; y aunque es bueno arrepentirse de cada pecado, con un arrepentimiento distinto y particular, sin embargo, no es necesario que haya un arrepentimiento particular por cada pecado de enfermedad.<\/p>\n<p><strong>4. <\/strong>Aunque el pecado de un hombre sea grande, pero si es solamente una enfermedad, nunca traer\u00e1 un azote sobre su familia. Y aunque mi pecado sea grande, aunque sea un pecado de debilidad, nunca echar\u00e1 a perder mis dones, ni los har\u00e1 in\u00fatiles: si un hombre tiene muchos dones, orando, ejercitando dones, y su vida es escandalosa, \u00bfqu\u00e9 dice el \u00bfmundo? Pero supongamos que despu\u00e9s de la debida investigaci\u00f3n y examen, descubro que mi pecado no es otro que un pecado de debilidad, el cual no me desechar\u00e1, aunque por mi debilidad, s\u00ed caiga en \u00e9l una y otra vez, \u00bfentonces qu\u00e9?&lt;\/p <\/p>\n<p>Luego siguen varios deberes, y en consecuencia debes tomar estas y otras resoluciones de gracia similares.<\/p>\n<p><strong>1. <\/strong>Si mi pecado es un pecado de enfermedad, y no otro, entonces por la gracia observar\u00e9 cu\u00e1l es el designio de Dios, al sufrir y dejar en m\u00ed tales enfermedades, y trabajar\u00e9 lo que pueda y pueda, para promover y hacer avanzar ese dise\u00f1o.<\/p>\n<p><strong>2. <\/strong>Si mi pecado no es m\u00e1s que un pecado de enfermedad, y Dios no me desecha por ello, entonces, por la gracia de Dios, nunca creer\u00e9 estos informes falsos de Cristo, y esas tergiversaciones de \u00c9l que Satan\u00e1s quiere poner. sobre \u00c9l, por lo que me persuadir\u00eda a m\u00ed ya otros, que nuestro Se\u00f1or Cristo es un maestro duro.<\/p>\n<p><strong>3. <\/strong>Si el Se\u00f1or Cristo no me desecha por mis pecados de enfermedad, entonces, por la gracia de Dios, no cuestionar\u00e9 mi estado espiritual y mi condici\u00f3n por cada pecado; Me afligir\u00e9 por cada pecado de enfermedad porque es un pecado, pero no cuestionar\u00e9 mi condici\u00f3n, porque no es m\u00e1s que un pecado de enfermedad.<\/p>\n<p><strong>4. <\/strong>Entonces no me desechar\u00e9 a m\u00ed mismo ya los dem\u00e1s por los pecados de las debilidades. \u00bfEl ojo de Cristo ser\u00e1 bueno y el m\u00edo ser\u00e1 malo?<\/p>\n<p><strong>5. <\/strong>Entonces, \u00bfno desechar\u00e9 las cosas de Cristo a causa de cualquier enfermedad que pueda adherirse a ellas, o la dispensaci\u00f3n de ellas? Cuando Cristo tom\u00f3 nuestra naturaleza sobre \u00c9l, Su deidad fue velada bajo nuestra humanidad, Su excelencia bajo nuestra debilidad. As\u00ed ahora, Su gracia y Sus dispensaciones est\u00e1n veladas bajo la debilidad de nuestras administraciones: como por ejemplo: la predicaci\u00f3n es una ordenanza de Cristo, sin embargo, el serm\u00f3n puede ser entregado de tal manera, con tanta debilidad del orador, que la ordenanza de Cristo puede estar velada bajo mucha debilidad.<\/p>\n<p><strong>6. <\/strong>Y si el Se\u00f1or no me desecha por mis debilidades, entonces, por la gracia, nunca ser\u00e9 desalentado en el cumplimiento de ning\u00fan deber. Orar\u00e9 como pueda y oir\u00e9 como pueda, y aunque no pueda orar como quisiera, orar\u00e9 como pueda; y aunque no soy capaz de examinar mi propio coraz\u00f3n como quisiera, sin embargo, har\u00e9 lo que pueda, porque el Se\u00f1or no me desechar\u00e1 por las enfermedades, y por lo tanto no abandonar\u00e9 mis deberes a causa de ellas.<\/p>\n<p>7. <\/strong>Y, por \u00faltimo, si el Se\u00f1or Jesucristo no me desecha por mis debilidades, nunca pecar\u00e9 porque el pecado es un pecado de debilidad. (<em>W. Bridge, MA<\/em>)<\/p>\n<\/p>\n<p><strong>Velar y orar<\/strong><\/p>\n<p>Dos puntos reclaman especialmente nuestra atenci\u00f3n aqu\u00ed.<\/p>\n<p><strong>I. <\/strong>El mandato dado: \u00abVelar y orar\u00bb.<\/p>\n<p><strong>1. <\/strong>Mira. La palabra es muy simple. Un m\u00e9dico observa a un hombre enfermo. Un portero vigila un edificio. Un centinela vigila en la muralla de una ciudad.<\/p>\n<p><strong>(1)<\/strong> Velar implica no estar ocupado con otras cosas.<\/p>\n<p><strong>(2) <\/strong> Vigilar implica esperar la aproximaci\u00f3n del enemigo.<\/p>\n<p><strong>(3)<\/strong> Vigilar tambi\u00e9n incluye un examen de los puntos de ataque. El m\u00e9dico observar\u00e1 qu\u00e9 curso est\u00e1 tomando la enfermedad, qu\u00e9 \u00f3rganos es probable que toque. As\u00ed vela.<\/p>\n<p><strong>2. <\/strong>Orar.<\/p>\n<p><strong>(1)<\/strong> Esto parece referirse a un h\u00e1bito de oraci\u00f3n. No es un grito salvaje en peligro o dolor.<\/p>\n<p><strong>(2)<\/strong> Tambi\u00e9n se implica una oraci\u00f3n especial con referencia a la tentaci\u00f3n. Oraci\u00f3n para ser librado de la presencia de la tentaci\u00f3n, oraci\u00f3n por la victoria en la tentaci\u00f3n.<\/p>\n<p><strong>II. <\/strong>La adecuaci\u00f3n del mandamiento a los expuestos a la tentaci\u00f3n.<\/p>\n<p><strong>1. <\/strong>Las dos partes juntas forman la protecci\u00f3n. Watching suministra materiales para la oraci\u00f3n. La oraci\u00f3n hace que la vigilancia sea eficaz. Rezar s\u00f3lo es presunci\u00f3n. Mirar solo es depender de uno mismo.<\/p>\n<p><strong>2. <\/strong>El mando tambi\u00e9n nos conviene por la sutileza del enemigo. Necesitamos descubrir sus artima\u00f1as observando. Oramos por sabidur\u00eda para discernir sus enga\u00f1osos ataques.<\/p>\n<p><strong>3. <\/strong>Y por nuestra propia debilidad. (Compare los vers\u00edculos 29, 31, con 67, 68)<em>.<\/em><\/p>\n<p><strong>4. <\/strong>Tambi\u00e9n es adecuado en consecuencia de la designaci\u00f3n de nuestro Se\u00f1or. La batalla es suya. \u00c9l establece sus leyes. Y \u00c9l ha dicho: \u201cVelad y orad\u201d. El mandamiento habla as\u00ed a los verdaderos disc\u00edpulos. \u00bfQu\u00e9 les dice a aquellos que son descuidados e incr\u00e9dulos? (<em>WS Bruce, MA<\/em>)<\/p>\n<\/p>\n<p><strong>Oraci\u00f3n completa<\/strong><\/p>\n<p>La oraci\u00f3n no es solo una petici\u00f3n hecha a Dios, pero conversamos con \u00c9l. Es la expresi\u00f3n del deseo hacia \u00c9l para suplirlo, del prop\u00f3sito para estabilizarlo, de la esperanza para iluminarlo. Es sacar el coraz\u00f3n de uno a la luz del sol, para que, como una planta, su vida interior pueda prosperar para un desarrollo exterior\u201d. Es la s\u00faplica del mejor yo de uno contra el yo m\u00e1s d\u00e9bil. Expresa des\u00e1nimo para poder obtener confianza. Es la expresi\u00f3n y el ejercicio del amor por todo lo que es bueno y verdadero. Es una lucha con el mal en presencia de la Bondad Suprema. Es la ascensi\u00f3n del alma por encima del tiempo a la libertad de la eternidad. (<em>P\u00falpito del mundo cristiano.<\/em>)<\/p>\n<\/p>\n<p><strong>La necesidad de vigilancia<\/strong><\/p>\n<p>Parece como si hubiera no hab\u00eda palabra de tan largo alcance como la palabra \u201cvigilar\u201d. La vigilancia es el precio de todo lo bueno y grande en la tierra o en el cielo. Fue por su fiel vigilancia que la memoria del centinela pompeyano queda embalsamada en poes\u00eda y registrada en la historia. Nada sino una vigilancia incesante puede mantener el coraz\u00f3n en armon\u00eda con el coraz\u00f3n de Dios. Era una noche tormentosa y bulliciosa. Las nubes oscuras se cern\u00edan sobre nosotros y el viento soplaba con una furia multiplicada por diez. El mar se agitaba en las monta\u00f1as, y el orgulloso barco parec\u00eda un juguete en medio de esas tremendas olas. Muy arriba en el m\u00e1stil, mirando hacia afuera, se escuch\u00f3 al marinero gritar: \u00abUn iceberg en la proa de estribor\u00bb. \u201c\u00a1Un iceberg en la amura de babor!\u201d El oficial de cubierta llam\u00f3 al timonel: \u201c\u00a1Por babor el tim\u00f3n firmemente!\u201d y los marineros al tim\u00f3n oyeron y obedecieron. Los oficiales se despertaron, porque hab\u00eda peligro a bordo para trescientas almas preciosas. El capit\u00e1n pas\u00f3 una noche sin dormir, paseando por la cubierta o la cabina. Gigantescos icebergs ven\u00edan contra el nav\u00edo, y la eterna vigilancia era el precio de nuestra seguridad en aquel mar del norte. Y as\u00ed es a lo largo de la vida humana. (<em>Anon.<\/em>)<\/p>\n<\/p>\n<p><strong>Vigilancia<\/strong><\/p>\n<p>La vigilancia nunca es un trabajo agradable; a ning\u00fan soldado le gusta mucho. Los hombres prefieren incluso la emoci\u00f3n y el peligro del campo de batalla a las largas semanas de paciente vigilancia, que, sin embargo, pueden hacer tanto como una batalla victoriosa para decidir los resultados de una campa\u00f1a. Ahora es as\u00ed en la guerra espiritual. Las fuerzas de la civilizaci\u00f3n hicieron de nuestros soldados m\u00e1s que un rival para todo el valor b\u00e1rbaro de sus enemigos morenos, siempre y cuando solo con una vigilancia constante estuvieran en condiciones de utilizar esas fuerzas; y aun as\u00ed, la omnipotencia de Dios hace que el verdadero cristiano sea m\u00e1s que un rival para todas las fuerzas del infierno, con tal de que \u00e9l tambi\u00e9n sea lo suficientemente vigilante para detectar el acercamiento del enemigo, y lo suficientemente sabio para enfrentarlo con el coraje de la fe cuando su se detecta el acercamiento; pero si camina descuidadamente, o no ejerce la debida vigilancia, la batalla se perder\u00e1 casi antes de que se perciba el peligro, y Faith perder\u00e1 su victoria solo porque no estaba lista para desplegar todos los poderes sobrenaturales que puede dominar. Lo es, \u00a1ay! No es raro encontrarse con almas cristianas que parecen saber algo de la vida de fe y, sin embargo, para su gran sorpresa, se ven superadas cuando menos lo esperan. Observamos a veces un cierto tono de petulancia en estas admisiones de fracaso, como si en el fondo de sus corazones se arrojara alguna implicaci\u00f3n sobre la fidelidad de Dios, aunque rehusar\u00edan expresarlo en tantas palabras. Ahora bien, claramente la causa de todos esos fracasos debe residir en nosotros, y ser\u00e1 nuestra sabidur\u00eda esforzarnos por descubrirla; mientras que es la peor de las locuras acusar a Dios de infidelidad. \u00bfPara qu\u00e9 estamos en este mundo? Obviamente, para que podamos ser entrenados y desarrollados para nuestra posici\u00f3n futura al exponernos a las fuerzas del mal. Si estuvi\u00e9ramos tan protegidos del mal que no hubiera necesidad de una vigilancia constante, perder\u00edamos el beneficio moral que induce el h\u00e1bito de la vigilancia constante. Sabemos que es una ley de la naturaleza que las facultades que nunca se emplean perecen por desuso; y, por otro lado, las facultades que se emplean completa y frecuentemente adquieren una capacidad maravillosa. \u00bfNo es esto igualmente cierto en el mundo espiritual? Estamos siendo entrenados probablemente para un alto y sagrado servicio dentro de poco, en el cual necesitaremos todas esas facultades que ahora est\u00e1n siendo vivificadas y entrenadas por nuestro contacto con el peligro y nuestra exposici\u00f3n a condiciones de existencia aparentemente hostiles. Debemos ser entrenados, aprendiendo la rapidez de percepci\u00f3n del peligro aqu\u00ed, para ejercitar la rapidez de percepci\u00f3n en el ministerio y el servicio voluntario m\u00e1s all\u00e1. Adem\u00e1s, la Vigilancia proporciona continuamente oportunidades para la fe, y tiende a acercarnos m\u00e1s y a mantenernos m\u00e1s cerca de Aquel por quien solo estamos. Si fu\u00e9ramos tan salvados del mal por un solo acto, que ya no tuvi\u00e9ramos m\u00e1s necesidad de Vigilancia, \u00bfno deber\u00edamos perder mucho de lo que ahora nos hace sentir nuestra dependencia de Aquel que es nuestra seguridad constante? \u00bfNo tenemos que agradecer a Dios por las mismas dagas que nos obligan a mantenernos tan cerca de \u00c9l si queremos estar a salvo? Se\u00f1alemos lo que no es Vigilancia antes de pasar a considerar qu\u00e9 es. Y<\/p>\n<p><strong>Yo. La vigilancia es algo muy distinto de la timidez nerviosa y de la aprensi\u00f3n morbosa: la condici\u00f3n de un hombre que ve un enemigo en cada matorral y es torturado por mil alarmas y todos los recelos de la incredulidad. David no se mostr\u00f3 vigilante, sino infiel, cuando exclam\u00f3: \u201cAhora un d\u00eda perecer\u00e9 por las manos de Sa\u00fal\u201d; y no nos mostramos vigilantes cuando seguimos nuestro camino temblando, deprimidos con todo tipo de presagios de desastre. Perm\u00edtanme ofrecer una ilustraci\u00f3n hogare\u00f1a de lo que quiero decir. Me divirti\u00f3 el otro d\u00eda escuchar el relato de un soldado sobre un susto terrible que tuvo durante la \u00e9poca del susto feniano hace unos a\u00f1os. A \u00e9l le toc\u00f3 en suerte una noche oscura actuar como centinela en los recintos de un importante arsenal, que se supon\u00eda com\u00fanmente podr\u00eda ser el escenario de una gran explosi\u00f3n en cualquier noche. La fortaleza estaba rodeada por un campo com\u00fan y, por lo tanto, era f\u00e1cil que personas malintencionadas se acercaran a ella. La noche, como ya he dicho, era tan oscura como puede ser una noche, y \u00e9l estaba completamente solo y lleno de temores de peligro. Se qued\u00f3 inm\u00f3vil por un momento imaginando que o\u00eda algo movi\u00e9ndose cerca de \u00e9l, y luego retrocedi\u00f3 unos pasos, cuando de repente sinti\u00f3 que entraba en contacto violento con algo, que de inmediato concluy\u00f3 que deb\u00eda ser un feniano agazapado. \u201cNunca estuve tan asustado\u201d, dijo, \u201cni antes ni despu\u00e9s en mi vida, y para decirte la verdad, ca\u00ed de espaldas. Imagina mis sentimientos cuando descubr\u00ed que lo que me hab\u00eda aterrorizado m\u00e1s all\u00e1 de toda descripci\u00f3n era solo una oveja inofensiva que se hab\u00eda quedado dormida demasiado cerca de mi ronda\u201d. Ahora, queridos amigos, creo que el p\u00e1nico rid\u00edculo, pero muy excusable, de este soldado puede servir para ilustrar la experiencia de muchos cristianos t\u00edmidos y aprensivos. Viven en un estado de p\u00e1nico cr\u00f3nico, esperando siempre ser asaltados por alguna influencia hostil, a la que se mostrar\u00e1n totalmente incapaces de resistir. Si prev\u00e9n la proximidad de cualquier circunstancia que pueda poner a prueba su religi\u00f3n, inmediatamente deciden que el <em>fiasco<\/em> y el derrocamiento son inevitables; y cuando de repente se ven confrontados por lo que parece una influencia adversa, o promete ser una severa tentaci\u00f3n, est\u00e1n listos para abandonarlo todo en la desesperaci\u00f3n. Olvidan que nuestro Se\u00f1or nos ha ense\u00f1ado a no preocuparnos por el d\u00eda de ma\u00f1ana, y nos ha asegurado que es suficiente para el d\u00eda su mal.<\/p>\n<p><strong>II. <\/strong>Tampoco consiste la vigilancia en una introspecci\u00f3n morbosa, o en una disposici\u00f3n a acusarnos de todo tipo de formas imaginarias del mal. Para su morbosa sensibilidad todo tiene depravaci\u00f3n; las buenas y generosas acciones s\u00f3lo brotan del ego\u00edsmo; todo afecto natural es desordenado; toda gratificaci\u00f3n com\u00fan es un amor al placer m\u00e1s que a Dios. Seguramente es posible, cr\u00e9anme, queridos amigos cristianos, emular las haza\u00f1as de un Don Quijote en nuestra vida religiosa, y ejecutar una inclinaci\u00f3n en cualquier n\u00famero de molinos de viento espirituales, pero esto no es vigilancia. Un hermano cl\u00e9rigo m\u00edo, alarmado de su sue\u00f1o por un polic\u00eda que inform\u00f3 que su iglesia estaba abierta, imagin\u00f3 que hab\u00eda capturado a un ladr\u00f3n por el pelo de su cabeza en la torre de su iglesia, cuando solo hab\u00eda puesto manos violentas en la oscuridad sobre la fregona de la iglesia! Es muy posible convertir un trapeador en un ladr\u00f3n en nuestras propias experiencias espirituales. S\u00f3lo una vez m\u00e1s perm\u00edtanme pedirles que tengan en cuenta que la Vigilancia no consiste en, y no es id\u00e9ntica a, una afectaci\u00f3n severa de solemnidad, agregue una aversi\u00f3n piadosa a cualquier cosa como la alegr\u00eda natural o la hilaridad alegre. Tengo ante mis ojos en este momento el recuerdo de un querido y honrado hermano, quien, cuando se hab\u00eda contado algo divertido en su mesa, de repente se irgui\u00f3 cuando estaba comenzando a unirse a la carcajada cordial, y me observ\u00f3 con mucha seriedad, \u201csiempre tengo miedo de perder la comuni\u00f3n dando paso a la ligereza\u201d. Confieso que admir\u00e9 la escrupulosidad del buen hombre, que estoy seguro que era perfectamente sincera, pero no pude evitar pensar que se confund\u00eda entre la sobriedad y la sobriedad.<\/p>\n<p><strong>III. <\/strong>Pero habiendo se\u00f1alado ciertas formas o h\u00e1bitos de conducta que no se confunden con Vigilancia, aunque a menudo lo son, procedamos a investigar qu\u00e9 es la vigilancia; hemos visto lo que no es. Y aqu\u00ed puede ser bueno notar que dos palabras distintas, o tal vez deber\u00eda decir conjuntos de palabras, en el griego, se traducen en nuestra versi\u00f3n por la palabra reloj. Un conjunto de t\u00e9rminos indica la necesidad de protegerse contra el sue\u00f1o, y el otro la necesidad de protegerse contra cualquier forma de embriaguez e insomnio moral. Ambas ideas se nos presentan juntas en un solo pasaje en la primera Ep\u00edstola a los Tesalonicenses: \u201cNo durmamos como los dem\u00e1s; pero velemos y seamos sobrios. Porque los que duermen, de noche duermen; y los que se embriagan, de noche se embriagan\u201d. Aqu\u00ed los dos peligros que surgen, uno del sue\u00f1o y el otro de la embriaguez, se nos presentan a la vez; y las dos palabras, cada una de las cuales suele traducirse por la palabra inglesa watch, se emplean para protegernos contra estos peligros. \u201cVelemos y seamos sobrios\u201d. Estos peligros parecen ser, en algunos aspectos, opuestos entre s\u00ed: uno surge de la pesadez y el aburrimiento de disposici\u00f3n, y el otro de una excitabilidad indebida. Uno es el peligro especial inherente a la rutina mon\u00f3tona y un nivel muerto de tranquila regularidad, el otro es el peligro inherente a una vida llena de agitaci\u00f3n y bullicio, una vida donde las preocupaciones y los placeres, los \u00e9xitos y los fracasos, las empresas importantes y las decepciones sorprendentes, trayendo consigo experiencias alternas de j\u00fabilo o depresi\u00f3n, son demasiado propensos a resultar absorbentes y a excluir el sentido v\u00edvido de las realidades eternas. Uno de los peligros, naturalmente, amenazar\u00e1 especialmente al hombre de temperamento flem\u00e1tico y disposici\u00f3n ecu\u00e1nime, el otro asaltar\u00e1 m\u00e1s f\u00e1cilmente al hombre cuyo sistema nervioso est\u00e1 muy tenso, ya sea de h\u00e1bitos sangu\u00edneos o melanc\u00f3licos. En el presente pasaje, el llamado a velar se combina con la exhortaci\u00f3n a orar, y de manera similar, San Pedro nos advierte \u201cser sobrios y velar en oraci\u00f3n\u201d. Esto nos sugiere que la Vigilancia necesita ante todo exorcizarse en el mantenimiento de nuestras relaciones adecuadas con Dios. Si estos se conservan intactos, es seguro que todo lo dem\u00e1s nos ir\u00e1 bien; pero donde algo parecido a la frialdad se asienta en nuestras relaciones con Dios, la reca\u00edda ya ha comenzado, y a menos que sea reprimida, estaremos a merced de nuestro enemigo. \u00a1Oh, alma cristiana, cu\u00eddate con celoso cuidado de los primeros comienzos de apat\u00eda y frialdad e irrealidad en tu trato con Dios! No menos, tal vez incluso m\u00e1s, necesitamos vigilar en el otro sentido que, como he se\u00f1alado, lleva la palabra en las Escrituras del Nuevo Testamento. No s\u00f3lo manteng\u00e1monos despiertos, sino seamos sobrios. Necesitamos recordar que estamos en tierra enemiga, y que a menos que estemos constantemente respirando la atm\u00f3sfera del cielo, la atm\u00f3sfera de la tierra, que es todo lo que nos queda, pronto se vuelve venenosa y debe producir una especie de intoxicaci\u00f3n moral. \u00a1Cu\u00e1ntas veces he visto a un cristiano olvidarse completamente de s\u00ed mismo bajo la influencia de la excitaci\u00f3n social! Pero me apresuro a decir: No caigamos en el error de suponer que s\u00f3lo los alegres y amantes del placer deben ser advertidos contra el peligro de embriagarse por las influencias mundanas. Los cuidados e incluso las ocupaciones de la vida pueden tener sobre nosotros un efecto tan delet\u00e9reo a este respecto como los placeres. Muchos hombres de negocios est\u00e1n tan intoxicados con las excitaciones diarias que surgen de las fluctuaciones del mercado o de la Bolsa de Valores, y tan cegados a las cosas m\u00e1s elevadas por los intereses absorbentes relacionados con ganar o perder dinero como el devoto de el placer puede estar en el hip\u00f3dromo o en el sal\u00f3n de baile. Una vez m\u00e1s, la Vigilancia debe mostrarse no solo en el mantenimiento de nuestras relaciones con Dios, en resistir cualquier disposici\u00f3n a estar somnolientos y en protegerse contra la influencia embriagadora de la excitaci\u00f3n mundana; tambi\u00e9n se debe mostrar al detectar el primer acercamiento de la tentaci\u00f3n, o los primeros levantamientos de un deseo profano. El general cuidadoso siente a su enemigo por medio de sus exploradores, y as\u00ed est\u00e1 preparado para tratar con \u00e9l cuando tenga lugar el ataque. Aun as\u00ed, a menudo se puede resistir la tentaci\u00f3n con facilidad cuando se discierne su primer acercamiento; pero adquiere a veces un poder casi irresistible, si se le permite acercarse demasiado. Pero habl\u00e9 hace unos momentos de la importancia de velar, no solo contra el comienzo de la tentaci\u00f3n externa, sino tambi\u00e9n contra cualquier disposici\u00f3n a aceptar la tentaci\u00f3n interna. Aqu\u00ed, estoy convencido, reside, en la mayor\u00eda de los casos, la causa secreta del fracaso. Balaam anhelaba interiormente la casa llena de plata y oro en el mismo momento en que fingi\u00f3 despreciarla. Pero hay un peligro al otro lado, contra el cual debemos protegernos con igual vigilancia. Y es el peligro de una autocomplacencia incipiente. (<em>WH Aitken.<\/em>)<\/p>\n<\/p>\n<p><strong>Ventaja de conocer el punto d\u00e9bil<\/strong><\/p>\n<p>Es el inter\u00e9s de cada hombre de no esconder de s\u00ed mismo su dolencia. \u00bfQu\u00e9 pensar\u00edas de un hombre que estaba enfermo e intentaba hacerse creer que era su pie el que estaba enfermo, cuando era su coraz\u00f3n? Supongamos que un hombre viniera a ver a su m\u00e9dico y le hiciera examinar el ojo equivocado y pagara la receta del m\u00e9dico, basado en la creencia de que su ojo estaba levemente da\u00f1ado, pero no mucho, y se marchara diciendo: \u00abSoy mucho m\u00e1s\u00bb. m\u00e1s feliz de lo que estaba\u201d, aunque el m\u00e9dico no hab\u00eda mirado el ojo enfermo en absoluto? Si un hombre tuviera un c\u00e1ncer, o una llaga mortal, en un brazo, y se negara a que el m\u00e9dico lo viera, pero le mostrara el brazo sano, imitar\u00eda lo que hacen los hombres que usan todos los enga\u00f1os y enga\u00f1os para ocultar su llagas morales y debilidades y faltas, en la medida de lo posible, de s\u00ed mismos, de todas las personas, y luego congratularse de no estar en peligro. La vigilancia requiere que un hombre sea honesto y sepa d\u00f3nde est\u00e1 y d\u00f3nde est\u00e1 su peligro. Deje que otros configuren su reloj donde lo necesiten y usted configure el suyo donde lo necesite. La vigilancia de cada hombre debe estar de acuerdo con su temperamento y constituci\u00f3n. (<em>HW Beecher.<\/em>)<\/p>\n<\/p>\n<p><strong>Observando-una figura militar<\/strong><\/p>\n<p>Sin duda se trata de un militar figura; aunque mirar puede ser una figura dom\u00e9stica, por lo general es militar. Una torre, un castillo, un fuerte, no se contenta simplemente con la solidez de sus murallas y sus diversas defensas. Se colocan centinelas alrededor de ella, y caminan de d\u00eda y de noche, y miran por todos lados para detectar cualquier peligro que se acerque, para que los soldados que est\u00e1n dentro se pongan inmediatamente en condiciones de recibir un ataque. A\u00fan m\u00e1s son un ej\u00e9rcito en movimiento vigilante, ya sea en la marcha o en el campamento. Echan guardias avanzados. El piquete se establece de noche y de d\u00eda. Los hombres est\u00e1n apartados para vigilar a prop\u00f3sito para que ning\u00fan enemigo los tome desprevenidos; que puedan estar constantemente preparados para cualquier incursi\u00f3n que las posibilidades de guerra puedan traer sobre ellos. Aqu\u00ed se da por sentado que estamos haciendo una campa\u00f1a a trav\u00e9s de la vida. La suposici\u00f3n en todo momento es que estamos en terreno enemigo, y que estamos rodeados, o corremos el riesgo de estar rodeados, de adversarios que se abalanzar\u00e1n sobre nosotros y nos tomar\u00e1n cautivos desprevenidos. Se nos ordena, por lo tanto, que hagamos lo que hacen los soldados, ya sea en un fuerte o en un campamento: estar siempre alerta, siempre preparados. (<em>HW Beecher.<\/em>)<\/p>\n<\/p>\n<p><strong>Cada uno para protegerse de sus propias tentaciones<\/strong><\/p>\n<p>Tu<em> <\/em>el exceso de disposici\u00f3n, tu fuerza de pasi\u00f3n y tu tentabilidad no son las mismas que las de tu pr\u00f3jimo. Por lo tanto, es bastante tonto de tu parte mirar como mira tu pr\u00f3jimo. Todo hombre debe ajustar su reloj de acuerdo con su propia disposici\u00f3n, y conocer su propia disposici\u00f3n mejor que nadie. Si un fuerte est\u00e1 situado de modo que el lado m\u00e1s d\u00e9bil est\u00e9 al este, el comandante, si es prudente, pondr\u00e1 all\u00ed su guardia. Dice: \u201cCreo que si defiendo este punto, nada me puede hacer da\u00f1o\u201d, y pone all\u00ed su reloj. \u00a1Pero supongamos que el comandante de un fuerte, cuyo lugar d\u00e9bil est\u00e1 en el lado oeste, debe poner toda su fuerza en el otro lado! Si pudiera defender su fuerte con \u00e9xito, deber\u00eda poner a sus soldados donde es d\u00e9bil. He aqu\u00ed un hombre que vela contra el orgullo; pero vuestra tentaci\u00f3n est\u00e1 del lado de la vanidad. No ser\u00e1 bueno que te cuides del orgullo, porque el orgullo no es tu pecado que te acosa. Hay muchos hombres que se jactan de que debido a que su pr\u00f3jimo ha corregido sus faltas al obtener una victoria sobre el orgullo, todo lo que \u00e9l mismo necesita hacer es obtener una victoria sobre el orgullo. No tiene dificultad en eso, porque no es tentado en su orgullo. Es muy f\u00e1cil mirar contra un enemigo que no existe. Es muy f\u00e1cil obtener una victoria donde no hay adversario. (<em>HW Beecher.<\/em>)<\/p>\n<\/p>\n<p><strong>Cuidado con los tiempos de tentaci\u00f3n<\/strong><\/p>\n<p>Todo hombre debe saber lo que son las circunstancias, los tiempos y las estaciones en las que est\u00e1 sujeto a pecar. Para hacer este asunto enteramente pr\u00e1ctico, hay muchos que descuidan la vigilancia hasta que hayan pasado el tiempo y las estaciones apropiados para la vigilancia. \u00bfY si tu culpa es de la lengua? Sup\u00f3n que tu temperamento toma eso como un medio para darse aire y explosi\u00f3n. Con un hombre es cuando se levanta por la ma\u00f1ana, y antes del desayuno est\u00e1 peculiarmente nervioso y susceptible. Es entonces cuando est\u00e1 irritable. Es entonces cuando las cosas no pintan bien. Y es entonces cuando su lengua, por as\u00ed decirlo, chasquea y arroja chispas de fuego. Con otro hombre es al anochecer, cuando est\u00e1 hastiado y fatigado por los cuidados y el trabajo del d\u00eda. Se ha vaciado de excitaci\u00f3n nerviosa y s\u00f3lo ha dejado excitabilidad. Y luego es el momento en que es probable que se derrumbe de varias maneras. Los hombres deben poner su reloj en el momento en que el enemigo est\u00e1 acostumbrado a venir. Los indios suelen atacar a las tres o cuatro de la ma\u00f1ana, cuando los hombres duermen m\u00e1s profundamente; y ese es el momento de mirar contra los indios. De nada sirve hacerlo a las diez de la ma\u00f1ana. Entonces no vienen. Si es cuando est\u00e1s enfermo cuando est\u00e1s m\u00e1s sujeto a pasiones malignas, entonces ese es el momento en que debes poner tu reloj. O, si es cuando est\u00e1s bien que la marea de sangre te sube demasiado febrilmente, entonces ese es el momento en que debes poner tu reloj. Si, en un momento del d\u00eda m\u00e1s que en otro, la experiencia ha demostrado que est\u00e1 expuesto a ser tentado, entonces en esa parte del d\u00eda debe estar en guardia. Todo el mundo tiene sus horas, sus tiempos y sazones, y sus circunstancias; y cada hombre debe aprenderlos por s\u00ed mismo; y cada hombre debe poner su reloj en ese momento y lugar. Y con frecuencia, si miras en el momento adecuado, puedes pasar f\u00e1cilmente el resto del d\u00eda. (<em>HW Beecher.<\/em>)<\/p>\n<\/p>\n<p><strong>El peligro de perder el tiempo con la tentaci\u00f3n<\/strong><\/p>\n<p>Existe tal cosa como juguetear con la tentaci\u00f3n. Muchas doncellas se dejar\u00e1n conducir insensiblemente, y paso a paso, a cosas que, si no est\u00e1n mal, est\u00e1n tan cerca de ellas que yacen en su misma penumbra y ella est\u00e1 todo el tiempo excusandose tales permisos y tales coqueteos. , Aullando, \u201cNo tengo la intenci\u00f3n de hacer nada malo; Me recuperar\u00e9 a su debido tiempo. Hay muchos hombres que toman la serpiente en su mano, porque es \u00e1gil, graciosa, bru\u00f1ida y hermosa, y juegan con eso que en alg\u00fan momento de descuido lo golpear\u00e1 con sus colmillos venenosos; y es una pobre excusa, cuando este coqueteo lo ha llevado al mismo borde de la tentaci\u00f3n, y le ha infundido el veneno fatal, para que \u00e9l diga: \u00abNo fue mi intenci\u00f3n\u00bb. El mal est\u00e1 hecho. La condenaci\u00f3n est\u00e1 por venir. Y es un pobre consuelo decir: \u201cNo fue mi intenci\u00f3n\u201d. Pase por \u00e9l; no te acerques a \u00e9l; al\u00e9jate de ella, y entonces estar\u00e1s a salvo. Pero no es seguro para la virtud inocente, o inexperta, o inconsciente, o Desconsiderada, acercarse, por placer, a cosas que llevan en ellas el mismo veneno de Satan\u00e1s. \u00bfQu\u00e9 deber\u00edas pensar de un hombre que, viniendo a Nueva York, deber\u00eda decir: \u201cHe tenido una gran experiencia esta ma\u00f1ana. Estuve en uno de los tugurios donde estaban matando; y los vi derribar bueyes, y los vi degollar, y vi la sangre correr a torrentes de las grandes heridas. Pas\u00e9 medio d\u00eda entero all\u00ed, mirando a los hombres matando, matando y matando\u201d. \u00bfQu\u00e9 dir\u00edas de un hombre que dijera: \u201cHe estado arrastr\u00e1ndome por las alcantarillas debajo de la calle; porque quiero saber qu\u00e9 hay en el fondo de las cosas en esta ciudad? \u00bfQu\u00e9 tipo de curiosidad ser\u00eda esa? \u00bfQu\u00e9 pensar\u00edais de un hombre que fuera a donde pudiera ver los desechos de los hospitales y las salas de disecci\u00f3n, y se revolcara en la podredumbre y la enfermedad, porque quer\u00eda aumentar su conocimiento de las cosas en general? Y, sin embargo, aqu\u00ed hay hombres que toman cosas m\u00e1s feculentas, m\u00e1s f\u00e9tidas, m\u00e1s sucias, m\u00e1s condenables y peligrosas: las enfermedades, las \u00falceras, las llagas y la inmundicia de los apetitos y las pasiones; e ir\u00e1n vadeando y mirando cosas a las que un hombre deber\u00eda cerrar los ojos si providencialmente se las arrojaran ante \u00e9l. Vaya, hay algunas cosas que es un pecado mirar dos veces. \u00a1Y sin embargo, hay hombres que los cazan! Por otra parte, hay hombres que viven tan cerca del enga\u00f1o que, aunque no tienen la intenci\u00f3n de enga\u00f1ar, las circunstancias no pueden doblegarlos sin derribarlos. Hay muchos hombres que son como un manzano en mi jard\u00edn, cuyo tronco y ra\u00edces, y las dos terceras partes de las ramas, est\u00e1n en el jard\u00edn, y la tercera parte de las ramas est\u00e1n fuera del muro del jard\u00edn. Y hay muchos hombres cuyo tronco y ra\u00edces est\u00e1n del lado de la honestidad y la rectitud, pero que viven tan cerca del muro del jard\u00edn que arrojan sus ramas por la calzada donde las iniquidades pisotean, y son libres. Nunca es seguro para un hombre correr tan cerca de la l\u00ednea del bien y del mal, que si perdiera una rueda, se volcar\u00eda. Es como viajar por un camino de monta\u00f1a cerca de un precipicio. Debes mantenerte tan lejos del precipicio, que si tu carro se rompe, haya suficiente espacio entre t\u00fa y el precipicio. De lo contrario, no puedes estar seguro. (<em>HWBeecher.<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mar 14:38 El esp\u00edritu verdaderamente est\u00e1 lista, pero la carne es d\u00e9bil. 1. Pienso, dir\u00e1n algunos, que mi pecado es un pecado de enfermedad porque es peque\u00f1o. Pero si miras en 1Sa 15:1-35, puedes leer que el pecado de Sa\u00fal, por el cual el Se\u00f1or lo rechaz\u00f3, no era de gran volumen exterior; porque perdon\u00f3 &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-marcos-1438-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Marcos 14:38 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39146","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=39146"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39146\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=39146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=39146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=39146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}