{"id":39157,"date":"2022-07-16T08:46:10","date_gmt":"2022-07-16T13:46:10","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-marcos-1461-62-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:46:10","modified_gmt":"2022-07-16T13:46:10","slug":"estudio-biblico-de-marcos-1461-62-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-marcos-1461-62-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Marcos 14:61-62 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Mar 14:61-62<\/span><\/p>\n<p> <em>Pero call\u00f3.<\/em><\/p>\n<\/p>\n<p><strong>Silencio elocuente<\/strong><\/p>\n<p>Hay un silencio que muchas veces m\u00e1s elocuente que el habla, significa m\u00e1s que cualquier palabra y habla diez veces m\u00e1s poderosamente al coraz\u00f3n. Tal, por ejemplo, es el silencio cuando el coraz\u00f3n est\u00e1 demasiado lleno para hablar, y los \u00f3rganos del habla son ahogados por la abrumadora marea de la emoci\u00f3n. La visi\u00f3n de un gran hombre tan conmocionado y temblando de emoci\u00f3n que la lengua no puede dar voz a lo que siente el coraz\u00f3n es la m\u00e1s poderosa de todas las ret\u00f3ricas humanas. Tal es tambi\u00e9n el silencio de un sabio desafiado a hablar por aquellos a quienes siente indignos de sus palabras. El hombre que puede soportar y escuchar el lenguaje de la ignorancia impasible, la intolerancia venenosa y el insulto personal, dirigido a \u00e9l con un esp\u00edritu ofensivo, y no ofrece respuesta, ejerce un poder mucho mayor sobre las mentes de sus agresores, que lo que podr\u00eda por palabras por contundentes que sean. Su silencio refleja una majestad moral, ante la cual el coraz\u00f3n de sus agresores dif\u00edcilmente dejar\u00e1 de encogerse. Tal fue el silencio que Cristo ahora mantuvo en esta sala. (<em>Homil\u00eda.<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mar 14:61-62 Pero call\u00f3. Silencio elocuente Hay un silencio que muchas veces m\u00e1s elocuente que el habla, significa m\u00e1s que cualquier palabra y habla diez veces m\u00e1s poderosamente al coraz\u00f3n. Tal, por ejemplo, es el silencio cuando el coraz\u00f3n est\u00e1 demasiado lleno para hablar, y los \u00f3rganos del habla son ahogados por la abrumadora marea &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-marcos-1461-62-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Marcos 14:61-62 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39157","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=39157"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39157\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=39157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=39157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=39157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}