{"id":39164,"date":"2022-07-16T08:46:28","date_gmt":"2022-07-16T13:46:28","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-marcos-151-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:46:28","modified_gmt":"2022-07-16T13:46:28","slug":"estudio-biblico-de-marcos-151-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-marcos-151-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Marcos 15:1 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Mar 15:1<\/span><\/p>\n<p><em>Y at\u00f3 a Jes\u00fas .<\/em><\/p>\n<\/p>\n<p><strong>El Cordero de Dios<\/strong><\/p>\n<p>Es interesante observar la notable semejanza que se encuentra que existe en varios detalles entre el ceremonial del sacrificio diario del cordero en el altar del Templo y el sacrificio del verdadero e inmaculado Cordero de Dios. Despu\u00e9s de que el cordero hab\u00eda estado bajo vigilancia durante cuatro d\u00edas, y hab\u00eda sido examinado por una inquisici\u00f3n de los sacerdotes la noche anterior, para asegurarse de que no ten\u00eda mancha ni defecto, lo sacaban temprano en la ma\u00f1ana tan pronto como era ligero En el canto del gallo, el altar hab\u00eda sido barrido de cenizas para prepararlo para la v\u00edctima. Entonces \u201cel presidente dijo a los otros sacerdotes: &#8216;Salgan y vean si es hora de sacrificar el cordero&#8217;. Si lo fuera, el observador dijo: &#8216;Hay brillantes rayos de luz en el este&#8217;. El presidente pregunt\u00f3: &#8216;\u00bfSe extienden hasta Hebr\u00f3n?&#8217; Si respond\u00eda que as\u00ed era, entonces dec\u00eda: &#8216;Id, y traed el cordero de la c\u00e1rcel del cordero.'\u00bb Ahora, de la misma manera, al cuarto d\u00eda despu\u00e9s de que Jes\u00fas hab\u00eda venido a Jerusal\u00e9n para ser ofrecido como \u00bb el Cordero de Dios que quita el pecado del mundo\u201d, cuando lleg\u00f3 la ma\u00f1ana despu\u00e9s de la inquisici\u00f3n de la noche sobre la inocencia del Cordero de Dios, \u00c9l es sacado de Su prisi\u00f3n para ser reexaminado y ordenado para ser sacrificado. El cordero del sacrificio diario, antes de ser puesto sobre el altar, era atado. \u201cAquellos sacerdotes\u201d, leemos, \u201ca quienes les corresponde ocuparse de los pedazos (con miras a ponerlos sobre el altar) tomaron el cordero y lo ataron\u201d. Entonces, en el Antitipo, \u201catan a Jes\u00fas y se lo llevan\u201d. Cristo est\u00e1 atado cuando est\u00e1 en las manos, el poder, de los hombres. As\u00ed es siempre con el mundo. Quiere tener un Jes\u00fas no libre, sino atado. As\u00ed como los sirvientes cubrieron Su rostro, as\u00ed el mundo desea tener un Dios que no todo lo ve. El mundo se esfuerza por emanciparse de los lazos de la obediencia a la voluntad de Dios. Rompamos, dicen, las ataduras que el Se\u00f1or Dios y su Cristo nos pusieron; e incluso las mismas cuerdas de amor por las que nos atraigan, echemos fuera. Hay un grito de libertad. La libertad es la bendici\u00f3n m\u00e1s perfecta que el hombre puede tener. \u00bfLibertad de qu\u00e9? \u00bfLibertad para hacer qu\u00e9? Entre los muchos, el deseo es liberarse de las responsabilidades causadas por el deber y hacer su propia voluntad sin restricciones por ninguna obligaci\u00f3n. Ese es, en verdad, el gran clamor del d\u00eda. Todos los deberes son fastidiosos, todas las obligaciones intolerables. Ning\u00fan hombre puede desarrollar su individualidad sino en absoluta libertad. Pero al mismo tiempo que el mundo busca liberarse de las ataduras de Cristo, trata de imponer ataduras a Cristo. La providencia debe estar sujeta a las leyes. La ciencia impone reglas al Alt\u00edsimo y establece principios por los cuales Dios debe actuar -si es que hay un Dios- o la ciencia prescindir\u00e1 de \u00c9l. Se declara que la oraci\u00f3n no tiene valor, porque el hombre no puede alterar el curso de la Naturaleza. Dios est\u00e1 encadenado por leyes autoimpuestas. No es un agente libre. No s\u00f3lo eso, sino que la Iglesia de Dios no debe ser libre. Tambi\u00e9n debe ser estorbada y restringida en todos los sentidos, impedida de hacer todo lo que pueda por la causa de Cristo. (<em>S. Baring Gould, MA<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mar 15:1 Y at\u00f3 a Jes\u00fas . El Cordero de Dios Es interesante observar la notable semejanza que se encuentra que existe en varios detalles entre el ceremonial del sacrificio diario del cordero en el altar del Templo y el sacrificio del verdadero e inmaculado Cordero de Dios. Despu\u00e9s de que el cordero hab\u00eda estado &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-marcos-151-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Marcos 15:1 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39164","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=39164"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39164\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=39164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=39164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=39164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}