{"id":39194,"date":"2022-07-16T08:47:44","date_gmt":"2022-07-16T13:47:44","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-marcos-169-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:47:44","modified_gmt":"2022-07-16T13:47:44","slug":"estudio-biblico-de-marcos-169-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-marcos-169-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Marcos 16:9 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Mar 16:9<\/span><\/p>\n<p><em>Cuando Jes\u00fas resucit\u00f3.<\/em><\/p>\n<\/p>\n<p><strong>Evidencia del hecho de la resurrecci\u00f3n de Cristo<\/strong><\/p>\n<p>La tumba vac\u00eda de Jes\u00fas recuerda un evento que est\u00e1 tan bien atestiguado como cualquier otro en la historia. Est\u00e1 tan atestiguado que deja fuera de discusi\u00f3n la idea de lo que se llama \u201cilusi\u00f3n\u201d. El fin principal, el primer deber, del ministerio apost\u00f3lico era dar testimonio del hecho de que Cristo hab\u00eda resucitado. Los ap\u00f3stoles no ense\u00f1aron la resurrecci\u00f3n como una verdad revelada, como ense\u00f1aron, <em>por ejemplo, <\/em>la doctrina de la justificaci\u00f3n; ense\u00f1aban la resurrecci\u00f3n como un hecho de la experiencia, un hecho del cual ellos mismos hab\u00edan tenido experiencia. Y es por eso que los diferentes evangelistas no reportan las mismas apariciones de nuestro Se\u00f1or resucitado. Cada uno relata lo que \u00e9l mismo presenci\u00f3, o lo que fue presenciado por el testigo ocular con cuya autoridad escribe. Ponga las diversas atestaciones juntas, y la evidencia es irresistible. Lo que atestiguan estos testigos debe ser cierto, a menos que hayan conspirado para enga\u00f1arnos, o se hayan enga\u00f1ado ellos mismos. La idea de que est\u00e1n enga\u00f1ados, sin embargo, no puede ser abrigada por ning\u00fan hombre que comprenda el car\u00e1cter humano; la idea de que ellos mismos fueron enga\u00f1ados es inconsistente con el car\u00e1cter del testimonio que dan. Sin duda hay estados de alucinaci\u00f3n, estados de tensi\u00f3n mental, en los que un hombre puede imaginar que ve algo que de hecho no se presenta a sus sentidos. La imaginaci\u00f3n por el momento es tan en\u00e9rgica como para imponer a los sentidos una impresi\u00f3n que corresponde a la que, sea lo que sea, crea una emoci\u00f3n dentro del alma. M\u00e1s a\u00fan, el mismo Nuevo Testamento habla de revelaciones internas, a veces durante el sue\u00f1o, a veces durante las horas de vigilia, como fue ese rapto del que escribi\u00f3 San Pablo, en \u201cel tercer cielo, si en el cuerpo no puedo decir, o si fuera\u201d. del cuerpo no puedo decirlo, Dios lo sabe\u201d. Pero los relatos de las apariciones de nuestro Se\u00f1or resucitado no admiten en absoluto ninguna de estas explicaciones. Si \u00c9l hubiera sido visto solo por un momento pasajero, solo por uno o dos individuos por separado, solo en un conjunto de circunstancias, bajo un conjunto de condiciones repetidas una y otra vez, entonces habr\u00eda cabida para la sospecha de una alucinaci\u00f3n morbosa, o al menos de una visi\u00f3n interior. Pero, \u00bfcu\u00e1l es el estado real del caso? El Resucitado fue visto cinco veces el d\u00eda que resucit\u00f3 de entre los muertos; Fue visto una semana despu\u00e9s; Lo vieron m\u00e1s de un mes despu\u00e9s de eso; y frecuentemente, en muchas ocasiones, durante el intervalo; Fue visto solo por mujeres, solo por hombres, por grupos de dos y tres, por disc\u00edpulos reunidos en c\u00f3nclave, por multitudes de hombres, quinientos a la vez; Se le vio en un jard\u00edn, en una v\u00eda p\u00fablica, en un aposento alto, en un monte de Galilea, a la orilla del lago, en la aldea donde habitaban sus amigos. Ense\u00f1\u00f3 como antes de su muerte, instruy\u00f3, anim\u00f3, reprendi\u00f3, bendijo, pronunci\u00f3 discursos prolongados que fueron recordados, que fueron registrados; Explic\u00f3 pasajes de las Escrituras, revel\u00f3 grandes doctrinas, dio mandatos enf\u00e1ticos, hizo grandes y nuevas promesas, comunic\u00f3 poderes ministeriales; y los que se apretujaron a Su alrededor sab\u00edan que Su cuerpo resucitado no era una forma fantasmal, porque \u00c9l com\u00eda y beb\u00eda delante de ellos tal como en los d\u00edas de anta\u00f1o, y ellos podr\u00edan, si hubieran querido, haber presionado sus propios dedos en las heridas frescas de Su manos y pies y costado. En resumen, dej\u00f3 en un grupo de mentes, muy diferentes entre s\u00ed, una impresi\u00f3n profunda e imborrable, que hab\u00edan visto y vivido con Uno que hab\u00eda muerto en verdad y hab\u00eda resucitado, y que este hecho era en s\u00ed mismo y en su importancia tan precioso, tan pre\u00f1ado de significado y de bendici\u00f3n para la raza humana, que arrojaba en sus mentes todos los dem\u00e1s hechos a una relativa insignificancia; val\u00eda la pena vivir, val\u00eda la pena morir. (<em>Canon Liddon.<\/em>)<\/p>\n<\/p>\n<p><strong>Se apareci\u00f3 primero a Mar\u00eda Magdalena<\/strong><\/p>\n<p>Primera aparici\u00f3n del Salvador despu\u00e9s de la resurrecci\u00f3n fue a una mujer. Por todo lo que hab\u00eda muerto. Pero \u00c9l no se manifiesta a un mundo reunido ahora que se ha levantado victorioso sobre la tumba; no a los \u00e1ngeles, ni a los ap\u00f3stoles; ni al fiel Jos\u00e9, ni al sincero Nicodemo; sino a una mujer!<\/p>\n<p><strong>I. <\/strong>El car\u00e1cter de la persona a quien se le apareci\u00f3 Cristo. Una mujer, y habitante de un pueblo lejano y sin importancia aleda\u00f1o a la frontera de los gentiles, que hab\u00eda estado endemoniada, hasta que Cristo le tendi\u00f3 la mano de misericordia.<\/p>\n<p><strong>II. <\/strong>Las circunstancias en las que se le apareci\u00f3. La llam\u00f3 por su nombre.<\/p>\n<p><strong>III. <\/strong>La gran verdad aqu\u00ed ilustrada.<\/p>\n<p><strong>1. <\/strong>No fue un mero encuentro casual. Habiendo Cristo ya salido de la tumba, debi\u00f3 ocultarse deliberadamente de todos sus disc\u00edpulos excepto de aquel a quien quer\u00eda ver y consolar.<\/p>\n<p><strong>2. <\/strong>Jes\u00fas se revel\u00f3 a ella, sin compa\u00f1\u00eda de nadie. No hay ej\u00e9rcitos de \u00e1ngeles: Cristo era \u201ctodo en todos\u201d.<\/p>\n<p><strong>3. <\/strong>La manifestaci\u00f3n se brind\u00f3 en un jard\u00edn a una mujer. Ed\u00e9n: Eva. (<em>George Venabbes.<\/em>)<\/p>\n<\/p>\n<p><strong>El poder del evangelio para restaurar a los ca\u00eddos<\/strong><\/p>\n<p>El huid de la gracia del evangelio, y de la santidad que produce, distinguidlo de cualquier otro sistema. Justifica y santifica. En su m\u00e9todo de justificaci\u00f3n, da gloria a Dios y trae paz al hombre. En su m\u00e9todo de santificaci\u00f3n, muestra la plenitud de la gracia y libra del poder de Satan\u00e1s.<\/p>\n<p><strong>I. <\/strong>Aquellos que est\u00e1n m\u00e1s bajo la influencia sat\u00e1nica, a\u00fan est\u00e1n al alcance del Evangelio.<\/p>\n<p><strong>1. <\/strong>El poder de los esp\u00edritus malignos se ejercer\u00eda sobre el cuerpo y el alma, si no estuvieran refrenados por un poder mayor. Tal como est\u00e1n las cosas, Satan\u00e1s ciega la mente; obra poderosamente en el coraz\u00f3n de los hijos de desobediencia; pone en el coraz\u00f3n de los hombres el traicionar al mejor de los Maestros y mentir contra el mejor Amigo. Todos los pecados, ya sea contra Dios o contra los hombres, se cometen a consecuencia de su tentaci\u00f3n.<\/p>\n<p><strong>2. <\/strong>Ning\u00fan poder puede contrarrestar esta mala influencia sino el Divino. En los pa\u00edses paganos, Satan\u00e1s reina sin control; en los pa\u00edses cristianos se revelan sus artima\u00f1as, se frustra toda su malicia, se derriba su reino.<\/p>\n<p><strong>3. <\/strong>El evangelio no solo libera a los hombres de la influencia sat\u00e1nica, sino que los exalta a los caracteres m\u00e1s santos.<\/p>\n<p><strong>II. <\/strong>El Evangelio puede efectuar la reforma de los m\u00e1s abandonados. Tan pronto como Mar\u00eda Magdalena fue despose\u00edda, se dedica al servicio de su Se\u00f1or. Lo mismo ocurre con todos los que abrazan de coraz\u00f3n la religi\u00f3n de Cristo. El poder del pecado en ellos es destruido, la influencia de Satan\u00e1s se disuelve y se convierten en cautivos voluntarios del amor de Cristo. Justin Martyr, en una de sus disculpas, dice: \u201cOh Emperador; nosotros, que antes \u00e9ramos ad\u00falteros, ahora somos castos; nosotros, que us\u00e1bamos amuletos m\u00e1gicos, ahora dependemos del Dios inmortal; nosotros, que am\u00e1bamos el dinero, ahora contribuimos alegremente a las necesidades de todos; nosotros, que no quer\u00edamos sentarnos con los que no eran de la misma tribu que nosotros, ahora nos sentamos alegremente y oramos por la conversi\u00f3n de los que nos odian, y persuadirlos a vivir de acuerdo con los excelentes preceptos de Cristo.\u201d<\/p>\n<p>1. <\/strong>Aprendamos cu\u00e1n admirablemente se adapta el evangelio al estado actual de la naturaleza humana. Nos encuentra culpables y nos revela la misericordia soberana de Dios en Cristo. Subyuga el coraz\u00f3n corrupto; convierte a los hombres de las tinieblas a la luz, etc.<\/p>\n<p><strong>2. <\/strong>Vea qu\u00e9 base ofrece esto para el esfuerzo, incluso en los casos m\u00e1s desesperados. (<em>W. Marsh, MA<\/em>)<\/p>\n<\/p>\n<p><strong>Jes\u00fas se aparece a Mar\u00eda Magdalena<\/strong><\/p>\n<p><strong> Yo.<\/strong><strong><em> <\/em><\/strong>Qui\u00e9n era ella. Cristo se revel\u00f3 primero a una mujer. Una mujer de la que hab\u00eda echado siete demonios. Ella hab\u00eda sido un trofeo especial del poder liberador de Cristo. En su poderosa gracia hab\u00eda probado su poder. Se hab\u00eda convertido en una asistente constante del Salvador. Ella gast\u00f3 sus bienes en aliviar Sus deseos.<\/p>\n<p><strong>II. <\/strong>C\u00f3mo ella busc\u00f3. Muy temprano en la ma\u00f1ana. Con una audacia muy grande. Muy fielmente: estuvo en el sepulcro. Muy fervientemente llorando. Perseverantemente. Busc\u00f3 a Cristo solamente. Hab\u00eda mucha ignorancia, muy poca fe, pero mucho amor.<\/p>\n<p><strong>III. <\/strong>C\u00f3mo lo encontr\u00f3. Jesucristo le fue descubierto por una palabra. Su coraz\u00f3n pose\u00eda lealtad por otra palabra. Su siguiente impulso fue buscar un compa\u00f1erismo cercano. Entonces ella entr\u00f3 a Su servicio. (<em>CH Spurgeon.<\/em>)<\/p>\n<\/p>\n<p><strong>Mar\u00eda Magdalena<\/strong><\/p>\n<p><strong>I.<\/strong><strong><em> <\/em><\/strong>Un melanc\u00f3lico ejemplo de poder sat\u00e1nico.<\/p>\n<p><strong>II. <\/strong>Un glorioso trofeo de la gracia divina. La cura no fue buscada por ella. Mar\u00eda resisti\u00f3 la mano sanadora. Ella fue sanada por una palabra. Ella fue sanada instant\u00e1neamente.<\/p>\n<p><strong>III. <\/strong>Ardiente seguidor de Cristo.<\/p>\n<p><strong>IV. <\/strong>Fiel adherente a su Maestro en toda prueba.<\/p>\n<p><strong>V. <\/strong>Uno de los contempladores m\u00e1s favorecidos de Cristo.<\/p>\n<p><strong>VI. <\/strong>Un mensajero de honor de Cristo a los ap\u00f3stoles. (<em>CH Spurgeon.<\/em>)<\/p>\n<\/p>\n<p><strong>La mujer primero<\/strong><\/p>\n<p>\u00bfNo era m\u00e1s agradable que una mujer debe ver primero al Salvador resucitado. Ella fue la primera en la transgresi\u00f3n, que sea la primera en la justificaci\u00f3n. En ese jard\u00edn ella fue la primera en trabajar nuestro dolor; que ella en ese otro jard\u00edn sea la primera en ver a Aquel que hace nuestro bien. Ella toma la manzana de ese \u00e1rbol amargo que nos trae todas nuestras penas; sea ella la primera en ver al Jardinero Poderoso, que ha plantado un \u00e1rbol que da fruto para vida eterna. (<em>CH Spurgeon.<\/em>)<\/p>\n<\/p>\n<p><strong>Magdalena<\/strong><\/p>\n<p>Mar\u00eda Magdalena representa a aquellos que han venido bajo el poder atormentador y perturbador de Satan\u00e1s, y cuya l\u00e1mpara de alegr\u00eda se apaga en la noche multiplicada por diez. Est\u00e1n aprisionados no tanto en las cuevas del pecado como en las mazmorras del dolor; no tan criminales como miserables; no tan depravados como desolados. (<em>CH Spurgeon.<\/em>)<\/p>\n<\/p>\n<p><strong>Demente<\/strong><\/p>\n<p>Las personas pose\u00eddas por demonios eran infelices; encontraron en la penumbra del sepulcro su lugar m\u00e1s agradable. Eran antisociales y solitarios. Si se les permit\u00eda, romp\u00edan con todas aquellas queridas asociaciones del c\u00edrculo familiar que daban la mitad de los encantos a la vida; se deleitaba en vagar por lugares \u00e1ridos, buscando descanso y sin encontrarlo; eran im\u00e1genes de miseria, im\u00e1genes de aflicci\u00f3n. As\u00ed era la siete veces infeliz Magdalena, porque en ella hab\u00eda entrado toda una banda de demonios. Estaba abrumada por siete mares de agon\u00eda, cargada con siete grilletes de desesperaci\u00f3n, rodeada por siete muros de fuego. Ni el d\u00eda ni la noche le permit\u00edan descansar, su cerebro ard\u00eda y su alma espumeaba como un caldero hirviendo. (<em>CH Spurgeon.<\/em>)<\/p>\n<\/p>\n<p><strong>Demente<\/strong><\/p>\n<p>Para resumir mucho en pocas palabras, hay No hay duda de que Mar\u00eda Magdalena habr\u00eda sido considerada por nosotros como una demente; ella era, pr\u00e1cticamente, una man\u00edaca. La raz\u00f3n fue desembarcada, y Satan\u00e1s estaba al tim\u00f3n en lugar de la raz\u00f3n, y la pobre barca fue llevada de aqu\u00ed para all\u00e1 bajo la gu\u00eda de los demonios. (<em>CH Spurgeon.<\/em>)<\/p>\n<\/p>\n<p><strong>Una ilustraci\u00f3n moderna<\/strong><\/p>\n<p>Recuerdo a un hombre de excelente car\u00e1cter , muy querido por su familia y estimado por sus vecinos, que estuvo durante veinte a\u00f1os envuelto en una tristeza indecible. Dej\u00f3 de asistir a la casa de Dios, porque dijo que era in\u00fatil; y aunque siempre estaba dispuesto a ayudar en toda buena obra, ten\u00eda la convicci\u00f3n permanente de que, personalmente, no ten\u00eda parte ni suerte en este asunto, y nunca podr\u00eda tenerla. Cuanto m\u00e1s le hablabas, peor se pon\u00eda; incluso la oraci\u00f3n parec\u00eda excitarlo a un abatimiento m\u00e1s espantoso. En la providencia de Dios, fui llamado a predicar la Palabra en su vecindario; fue inducido a asistir y, por el poder de la gracia de Dios, bajo el serm\u00f3n obtuvo una gozosa libertad. Despu\u00e9s de veinte a\u00f1os de angustias e inquietudes, termin\u00f3 su peregrinar cansado al pie de la cruz, para asombro de sus vecinos, alegr\u00eda de sus amigos y gloria de Dios. (<em>CH Spurgeon.<\/em>)<\/p>\n<\/p>\n<p><strong>Esperar lo peor<\/strong><\/p>\n<p>Hasta que la puerta del infierno sea cerrado sobre un hombre, no debemos dejar de orar por \u00e9l; y si lo vemos abrazado a los mismos postes de la puerta de la condenaci\u00f3n, debemos ir al propiciatorio y suplicar al brazo de la gracia que lo arranque de su peligrosa posici\u00f3n. El caso de Mar\u00eda Magdalena es un espejo en el que pueden verse muchas almas, estrujadas por la angustia. (<em>CH Spurgeon.<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mar 16:9 Cuando Jes\u00fas resucit\u00f3. Evidencia del hecho de la resurrecci\u00f3n de Cristo La tumba vac\u00eda de Jes\u00fas recuerda un evento que est\u00e1 tan bien atestiguado como cualquier otro en la historia. Est\u00e1 tan atestiguado que deja fuera de discusi\u00f3n la idea de lo que se llama \u201cilusi\u00f3n\u201d. El fin principal, el primer deber, del &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-marcos-169-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Marcos 16:9 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39194","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=39194"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39194\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=39194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=39194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=39194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}