{"id":39214,"date":"2022-07-16T08:48:34","date_gmt":"2022-07-16T13:48:34","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-117-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:48:34","modified_gmt":"2022-07-16T13:48:34","slug":"estudio-biblico-de-lucas-117-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-117-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Lucas 1:17 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Lc 1,17<\/span><\/p>\n<p><em>El coraz\u00f3n de los padres a los hijos<\/em><\/p>\n<p><strong>Dibujar un rel\u00e1mpago<\/strong><\/p>\n<p>La ciencia nos dice que la mejor defensa contra los rel\u00e1mpagos en una tormenta se encuentra, no en el desaf\u00edo de ella, pero en una descarga silenciosa de ella.<\/p>\n<p>Ac\u00e9rcate sin miedo a ella con un alambre de plantina puntiagudo, y seguir\u00e1 una ley fija de dispersi\u00f3n inofensiva. \u00bfHay alguna manera de atraer el poder de una de las maldiciones de Dios para evitar el terrible golpe de la ira divina? Dejanos ver. Este texto nos remite directamente a la \u00faltima declaraci\u00f3n del Antiguo Testamento. Hay cuatro libros en la Biblia que terminan con una maldici\u00f3n: Malaqu\u00edas, Lamentaciones, Isa\u00edas y Eclesiast\u00e9s. Los escribas hebreos sol\u00edan repetir siempre el verso justo antes del \u00faltimo en estos casos, para cerrar la lectura con algo m\u00e1s que una maldici\u00f3n. No es f\u00e1cil ver c\u00f3mo eso ayuda al asunto en el presente caso, porque la predicci\u00f3n anterior parece haber sido pronunciada simplemente para introducir la advertencia. Y tal vez sea igualmente provechoso creer que la mejor manera de evitar los juicios de Dios es guardarse cuidadosamente de merecerlos. Despu\u00e9s de que el \u00faltimo vidente de la antigua dispensaci\u00f3n hubo pronunciado las palabras que cita el evangelista, los cielos se cerraron durante cuatrocientos a\u00f1os. Jehov\u00e1 no ten\u00eda otro mensaje que enviar. Su pueblo lo hab\u00eda ofendido. La justicia sale casi ferozmente y cierra la puerta de la revelaci\u00f3n, porque los ni\u00f1os son despreciados. Y no hasta que cuatro siglos de silencio hubieran dado tiempo para el arrepentimiento, esos cerrojos ser\u00edan retirados. Incluso entonces es un ni\u00f1o peque\u00f1o el que avanza para girar la llave maciza. La historia vaga tristemente en confusi\u00f3n entre los cautiverios y las usurpaciones macabeas. S\u00f3lo un infante puede unirse a los Testamentos. Luke es el pr\u00f3ximo hombre a Malachi. El m\u00e1s severo de todos los profetas de Israel reaparece en el m\u00e1s severo de todos los heraldos de la Iglesia&#8230; Una amenaza salvaje, de cuatrocientos a\u00f1os de antig\u00fcedad, se disipa repentinamente en un destello de bendici\u00f3n. La maldici\u00f3n de Malaqu\u00edas se omite en Lucas: se dibuja el rel\u00e1mpago. El evangelio cumple la ley cuando acepta a los ni\u00f1os. Dios recibe de nuevo a los padres en el favor y la comuni\u00f3n, cuando sus corazones se vuelven hacia su descendencia&#8230; \u00bfCu\u00e1nto est\u00e1s haciendo en este d\u00eda de privilegio evang\u00e9lico para traer los corazones de los padres de vuelta a sus hijos? \u00bfNecesitamos otro profeta, con su vestidura de pelo y su cinto de cuero, que salga del desierto? (<em>CS Robinson, DD<\/em>)<\/p>\n<\/p>\n<p><strong>El pionero del evangelio<\/strong><\/p>\n<p>Mientras que Mateo y Marcos present\u00f3 a Juan Bautista a la atenci\u00f3n de sus lectores en el per\u00edodo avanzado de su predicaci\u00f3n en el desierto de Judea y el bautismo de sus seguidores en el Jord\u00e1n, Lucas comienza con la genealog\u00eda y el nacimiento del Bautista, y establece muchos detalles relacionados con su historia temprana, que , aunque hab\u00edan sido mucho menos notables en s\u00ed mismos, habr\u00edan sido interesantes en referencia a uno que luego se hizo tan conspicuo, pero que son particularmente importantes como evidencias adicionales de la misi\u00f3n divina e ilustraciones adicionales del oficio del mismo Bautista, y de ese ilustre Libertador y Rey ante quien deb\u00eda proceder como pionero para despejar el camino. (<em>James Foote, MA<\/em>)<\/p>\n<\/p>\n<p><strong>La gente preparada<\/strong><\/p>\n<p>Toda la vida es una preparaci\u00f3n para conocer a Dios. Esta es la clave del laberinto de la vida. Los preparativos son a menudo cosas confusas. Son tiempos de inquietud, llenos de ruido y desorden, y de aparente contradicci\u00f3n; hasta que llega el final, y lo explica todo. As\u00ed que este mundo est\u00e1 hecho de cosas extra\u00f1as, que se mueven sobre nosotros y dentro de nosotros, y parecen tener poco prop\u00f3sito y ning\u00fan concierto. Se extienden salvajemente. Hay comienzos sin finales; y hay finales sin comienzos. Muchas cosas no encajan. Es dif\u00edcil saber qu\u00e9 significa todo esto. Es un pensamiento agradable recordar que tu preparaci\u00f3n, a medida que avanza, d\u00eda a d\u00eda, es solo un reflejo de lo que est\u00e1 sucediendo en el otro mundo. All\u00ed, tambi\u00e9n, todo es preparaci\u00f3n. Los santos y los \u00e1ngeles est\u00e1n todos ocupados prepar\u00e1ndose. Los preparativos de la tierra deben encontrarse con los preparativos del cielo. Ha preparado Su misericordia, y ha preparado Su verdad. Es un cielo preparado; es un reino preparado; una ciudad preparada; un trono preparado; un asiento preparado. Y cuando ambas preparaciones est\u00e1n completas, un alma preparada y un cielo preparado, \u00a1qu\u00e9 perfecci\u00f3n! \u00a1qu\u00e9 amor! que descanso! \u00a1Qu\u00e9 tranquilidad! \u00bfY si viniera el Puro y encontrara impureza? \u00bfY si el Santo viniera y encontrara la irreverencia? \u00bfY si viene el Esp\u00edritu y no encuentra sino carne? \u00bfY si viene la Sabidur\u00eda, y encuentra la ignorancia? \u00bfQu\u00e9 pasa si viene Amor y encuentra ego\u00edsmo y crueldad? Primero, debes estar preparado para conocer a tu Se\u00f1or cuando venga. Esto Juan ense\u00f1\u00f3 muy expresamente. Puso a la gente en una posici\u00f3n en la que deb\u00edan conocer y reconocer a Cristo cuando llegara. Debes haberlo le\u00eddo en las profec\u00edas; debes haber caminado con \u00c9l en el evangelio; debes haberte sentado con \u00c9l en todas las manifestaciones de Su gracia; debes haberlo rastreado en Sus reflexiones sobre el universo. debe haber sentido Su morada interior en usted por el Esp\u00edritu Santo. Entonces \u00c9l no ser\u00e1 un Cristo nuevo y extra\u00f1o para ti cuando venga. Y si quieres estar \u201cpreparado para el Se\u00f1or\u201d, debes tener un profundo sentido del pecado. \u201cArrepent\u00edos, porque el reino de los cielos se ha acercado\u201d. Nadie debe pararse all\u00ed que no haya aprendido a inclinarse muy bajo. En tercer lugar, debe ser exacto, fiel, diligente en sus deberes diarios, haciendo todo lo que hace de coraz\u00f3n, un hombre de gran caridad, un hombre de h\u00e1bitos altruistas, un hombre de estricta integridad en los negocios, un hombre de autogobierno, un hombre de moderaci\u00f3n, un hombre de contenido, un hombre de humildad. \u201cEl que tiene dos t\u00fanicas, d\u00e9 al que no tiene; y el que tiene comida, que haga lo mismo.\u201d \u201cNo exijas m\u00e1s de lo que te est\u00e1 se\u00f1alado\u201d. En cuarto lugar, deb\u00e9is ser bautizados, no s\u00f3lo con el bautismo de agua, sino con el bautismo del Esp\u00edritu; y no con el bautismo de agua y del Esp\u00edritu solamente, sino con el bautismo de verg\u00fcenza, de escarnio, de sufrimiento, de muerte: \u201cbautizados en Esp\u00edritu Santo y fuego\u201d. Y en quinto lugar, debes estar muy en el uso de las ordenanzas, amando las sombras hasta que venga la sustancia. (<em>J. Vaughan, MA<\/em>)<\/p>\n<\/p>\n<p><strong>El esp\u00edritu y el poder del Bautista<\/strong><\/p>\n<p>El el esp\u00edritu y el poder de El\u00edas reposaron sobre el Bautista, y nosotros necesitamos el mismo don ahora. Porque, \u00bfcu\u00e1l es el fin y el prop\u00f3sito de toda la actividad religiosa que vemos en el exterior y en el interior, sino volver el coraz\u00f3n de la gente a la sabidur\u00eda, para preparar un pueblo preparado para el Se\u00f1or? Veamos, entonces, \u00bfcu\u00e1l fue este esp\u00edritu y poder que hizo que el Bautista tuviera tanto \u00e9xito? Y noten, para empezar, no fue nada maravilloso, nada fuera del camino. Se nos dice expresamente que \u201cJuan no hizo ning\u00fan milagro\u201d. El esp\u00edritu y el poder del Bautista es, por tanto, un don al alcance de cada uno de nosotros. <\/p>\n<p><strong><br \/>Yo. <\/strong>OBSERVAR, PRIMERO, SU DECISI\u00d3N POR DIOS. Sin titubeos entre dos opiniones. El Bautista no era \u201cuna ca\u00f1a sacudida por el viento\u201d, sino alguien que hab\u00eda considerado bien las cosas y llegaba a una decisi\u00f3n firme con respecto a la salvaci\u00f3n de Dios. <\/p>\n<p><strong><br \/>II. <\/strong>NOTA, A CONTINUACI\u00d3N, SU SEPARACI\u00d3N DEL MUNDO. Vivi\u00f3 lo m\u00e1s posible en retiro, comulgando con su propia alma y con Dios. Mientras estuvo en el mundo, nunca fue del mundo. <\/p>\n<p><strong><br \/>III. <\/strong>CONSIDERE, UNA VEZ M\u00c1S, SU TESTIMONIO AUDAZ Y CONSISTENTE DE LA VERDAD. <\/p>\n<p><strong>1.<\/strong> Ante todas las clases de sus compatriotas, desde los m\u00e1s bajos hasta los m\u00e1s altos. <\/p>\n<p><strong>2.<\/strong> A pesar de la oposici\u00f3n y la persecuci\u00f3n. Conclusi\u00f3n: Cualidades como estas hicieron del Bautista un poder para el bien, y as\u00ed fue en el esp\u00edritu y poder de El\u00edas. <\/p>\n<p>\u00bfEstamos siguiendo sus pasos? Deben encontrarse en nosotros estas mismas cualidades, si nuestra vida ha de ser un \u00e9xito moral tan grandioso como lo fue la suya. <\/p>\n<p><strong>1.<\/strong> La misma decisi\u00f3n. La tibieza no sirve para nada en lo que concierne al alma. <\/p>\n<p><strong>2.<\/strong> La misma falta de mundanalidad. No necesariamente separaci\u00f3n del mundo, eso es para unos pocos; sino (lo que muchos encuentran que es una cosa mucho m\u00e1s dif\u00edcil) vivir en el mundo, haciendo sus deberes fielmente y bien, y al mismo tiempo viviendo la vida superior que est\u00e1 escondida con Cristo en Dios, y esperando el nuevo cielo y la nueva tierra en la que mora la justicia. <\/p>\n<p><strong>3.<\/strong> El mismo que da testimonio constante de la verdad. <\/p>\n<p><strong>(1)<\/strong> En el coraz\u00f3n. <\/p>\n<p><strong>(2)<\/strong> En palabra. <\/p>\n<p><strong>(3)<\/strong> En acci\u00f3n. <\/p>\n<p>Una vida recta y honesta es el mejor testimonio del esp\u00edritu y poder en que nos movemos, y nos llevar\u00e1 triunfantes sobre cada obst\u00e1culo y dificultad que encontremos, hasta llegar al remanso de paz donde desear\u00edamos ser, y disfrutar del sol perpetuo de la presencia de Dios. (<em>George Low, MA<\/em>)<\/p>\n<\/p>\n<p><strong>La sabidur\u00eda de los justos<\/strong><\/p>\n<p>Probemos la sabidur\u00eda de la elecci\u00f3n religiosa por la felicidad que le sigue. <\/p>\n<p><strong><br \/>Yo. <\/strong>Hay un contenido y satisfacci\u00f3n en la mente, desde la misma conciencia y recuerdo de haber escuchado la voz del cielo. <\/p>\n<p><strong><br \/>II. <\/strong>Observo a continuaci\u00f3n, que el evangelio trae felicidad a todo creyente sincero, d\u00e1ndole la bendici\u00f3n de la paz en la seguridad del perd\u00f3n. <\/p>\n<p><strong><br \/>III. <\/strong>La sabidur\u00eda de los justos, por m\u00e1s que se la cuestione, por m\u00e1s que se la denigre, por parte de hombres inconversos o imp\u00edos, que no pueden apreciarla ni entenderla, se manifiesta a lo largo de todo el curso de la vida del creyente. \u201cEl que camina en integridad, camina con seguridad\u201d. \u201cEl camino de los imp\u00edos es como las tinieblas; no saben en qu\u00e9 tropiezan: \u201cEl mal los rodea continuamente, sin saber la causa ni el remedio. \u201cPero el camino de los justos es como la luz brillante, que va brillando m\u00e1s y m\u00e1s hasta el d\u00eda perfecto\u201d. <\/p>\n<p><strong><br \/>IV. <\/strong>Pero la sabidur\u00eda de los justos no debe ser plenamente conocida de este lado de la tumba. Llegar\u00e1 un d\u00eda, en que aparecer\u00e1 incluso al m\u00e1s lento de creer, sin sombra y sin duda. \u201cCuando el Se\u00f1or venga a preparar Sus joyas\u201d, la preciosidad de esas joyas, y el gozo de estar reunidos entre ellas, ser\u00e1n perfectamente manifiestos, tanto para amigos como para enemigos; a uno, por su admisi\u00f3n en Su reino celestial; al otro, por ser desechados. (<em>J. Slade, MA<\/em>)<\/p>\n<\/p>\n<p><strong>El esp\u00edritu y poder de Elias<\/strong><\/p>\n<p>a quien John se parec\u00eda mucho a-<\/p>\n<p><strong>1.<\/strong> Las dotes de su mente. <\/p>\n<p><strong>2.<\/strong> Los h\u00e1bitos de su vida. <\/p>\n<p><strong>3.<\/strong> El ejercicio de su ministerio. (<em>C. Sime\u00f3n.<\/em>)<\/p>\n<\/p>\n<p>\u00bfC\u00f3mo y en qu\u00e9 sentido se cumpli\u00f3 en Juan el Bautista la predicci\u00f3n de Malaqu\u00edas sobre el Mensajero? A esta pregunta el Nuevo Testamento da una respuesta singularmente completa y abundante. Realmente parece como si, no s\u00f3lo la mente del Bautista, sino tambi\u00e9n las mentes de todos los que hablan de \u00e9l, estuvieran empapadas en la profec\u00eda de Malaqu\u00edas, y saturadas con ella. Dif\u00edcilmente hay una palabra dicha por \u00e9l que no adquiera un nuevo significado y fuerza tan pronto como la leemos a la luz de la l\u00e1mpara de Malaqu\u00edas. En el Evangelio de San Mateo (cap. 3), tenemos nuestro relato m\u00e1s completo de la aparici\u00f3n y el ministerio del Bautista. All\u00ed se nos dice que su primera palabra, su palabra maestra, fue \u201cArrepent\u00edos, porque el reino de los cielos se ha acercado\u201d; es decir, \u201cAdoptar una nueva perspectiva; obtener una nueva mente; pensar; piensa en tus h\u00e1bitos y formas, y enmendarlos; porque el Rey, prometido desde hace mucho tiempo a vuestros padres, est\u00e1 a punto de aparecer. Esta fue la mism\u00edsima misi\u00f3n que Malaqu\u00edas atribuy\u00f3 al mensajero del Se\u00f1or. El peculiar modo de vida de Juan, como se describe en el mismo cap\u00edtulo, tiende a la misma conclusi\u00f3n (<span class='bible'>Mat 3:4<\/span>). Sin duda, Juan asumi\u00f3 estas se\u00f1ales externas de semejanza con el gran tisbita, para llamar la atenci\u00f3n sobre la semejanza interna entre ellos como una se\u00f1al de que hab\u00eda venido \u201cen el esp\u00edritu y el poder de El\u00edas\u201d. La misma raz\u00f3n de una vida triste y austera existi\u00f3 en ambos casos. El \u201cpredicador del arrepentimiento\u201d debe ser \u00e9l mismo un penitente. El\u00edas y Juan, cada uno en su turno, se presentaron como una personificaci\u00f3n del arrepentimiento, mostrando al pueblo, en su propia conducta, cu\u00e1l deb\u00eda ser su conducta. Estas dos voces austeras del desierto llamaron a los hombres al arrepentimiento, ambas buscaban \u201cvolver el coraz\u00f3n de los hombres de nuevo\u201d a Dios. (<em>Samuel Cox, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Un padre reconciliado con su hijo<\/strong><\/p>\n<p>Una madre en Nueva York, cuyo hijo hab\u00eda adquirido h\u00e1bitos disipados y abandonados, despu\u00e9s de repetidas protestas y amenazas, fue expulsado por su padre, y se fue jurando que nunca regresar\u00eda a menos que su padre se lo pidiera, lo que el padre dijo que nunca suceder\u00eda. El dolor por su hijo pronto llev\u00f3 a la madre a su lecho de muerte, y cuando su esposo le pregunt\u00f3 si no hab\u00eda nada que \u00e9l pudiera hacer por ella antes de que partiera de esta vida, ella dijo: \u00abS\u00ed, puedes enviar a buscar a mi hijo\u00bb. El padre al principio no estaba dispuesto, pero al final, al verla tan cerca de su fin, mand\u00f3 llamar a su hijo. Lleg\u00f3 el joven y, al entrar en la habitaci\u00f3n del enfermo, su padre le dio la espalda. Mientras la madre se hund\u00eda r\u00e1pidamente, los dos se pararon en lados opuestos de su cama, todo amor y tristeza por ella, pero sin intercambiar una palabra entre ellos. Ella le pidi\u00f3 al padre que perdonara al <em>ni\u00f1o;<\/em> no, no lo har\u00eda hasta que el hijo se lo pidiera. Volvi\u00e9ndose hacia \u00e9l, le rog\u00f3 que le pidiera perd\u00f3n a su padre; no, su orgulloso coraz\u00f3n no le dejar\u00eda dar el primer paso. Despu\u00e9s de repetidos intentos fracas\u00f3, pero como estaba a punto de expirar, con un \u00faltimo esfuerzo agarr\u00f3 la mano del padre con una mano y la de su hijo con la otra, y haciendo uso de todas sus d\u00e9biles fuerzas, junt\u00f3 sus manos y, con una \u00faltima mirada suplicante, ella se hab\u00eda ido. Sobre su cad\u00e1ver se reconciliaron, pero fue necesaria la muerte de la madre para lograrlo. Entonces, \u00bfno ha hecho Dios un gran sacrificio para que podamos ser reconciliados, incluso la muerte de Su propio Hijo amado? (<em>DL Moody.<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lc 1,17 El coraz\u00f3n de los padres a los hijos Dibujar un rel\u00e1mpago La ciencia nos dice que la mejor defensa contra los rel\u00e1mpagos en una tormenta se encuentra, no en el desaf\u00edo de ella, pero en una descarga silenciosa de ella. Ac\u00e9rcate sin miedo a ella con un alambre de plantina puntiagudo, y seguir\u00e1 &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-117-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Lucas 1:17 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39214","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=39214"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39214\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=39214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=39214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=39214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}