{"id":39229,"date":"2022-07-16T08:49:16","date_gmt":"2022-07-16T13:49:16","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-167-79-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:49:16","modified_gmt":"2022-07-16T13:49:16","slug":"estudio-biblico-de-lucas-167-79-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-167-79-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Lucas 1:67-79 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Lc 1,67-79<\/span><\/p>\n<p> <em>Y su padre Zacar\u00edas fue lleno del Esp\u00edritu Santo<\/em><\/p>\n<p><strong>El c\u00e1ntico de Zacar\u00edas<\/strong><\/p>\n<p>I.<\/p>\n<p>Cuestiones preliminares. En la parte inicial del Evangelio de San Lucas, hay una definici\u00f3n de tiempo, lugar y circunstancia que nos hace sentir que no estamos respirando el aire o mirando a trav\u00e9s de la luz enga\u00f1osa de la leyenda. No estamos viajando en el pa\u00eds de los sue\u00f1os, porque podemos medir distancias. Las objeciones que se han hecho en tiempos modernos a esta declaraci\u00f3n se derivan de dos elementos en la narraci\u00f3n:<\/p>\n<p><strong>(1)<\/strong> del relato de varias apariciones angelicales; <\/p>\n<p><strong>(2)<\/strong> de las r\u00e1fagas grabadas de canciones ext\u00e1ticas o prof\u00e9ticas. <\/p>\n<p><strong>1.<\/strong> En cuanto a la aparici\u00f3n angelical en estos primeros cap\u00edtulos. Incuestionablemente, aqu\u00ed, como en todas partes, en todo y hasta sus confines, San Lucas es el Evangelio de los santos \u00e1ngeles. La existencia oh! \u00e1ngeles descansa sobre el mismo testimonio que toda la vida sobrenatural. Debe haber algo de idoneidad en los tiempos de su manifestaci\u00f3n, y en las personas a quienes se dan a conocer. En una era material dejan de aparecer. Debe haber una cierta clarividencia santa, algo angelical en el \u00e1ngel visto. Todo depende del punto de vista inicial. De nosotros no es incre\u00edble, sino m\u00e1s bien probable, que Gabriel haya venido a Zacar\u00edas y Mar\u00eda; que los cantos de aclamaci\u00f3n deber\u00edan haber resonado sobre Bel\u00e9n. Hemos venido a una compa\u00f1\u00eda innumerable de \u00e1ngeles. Bueno, tambi\u00e9n, qued\u00e9monos impresionados por la gravedad y la reserva del relato b\u00edblico de las apariciones angelicales. El hombre no recibe ninguna invitaci\u00f3n al azar a una intimidad descuidada por un lado; a una herej\u00eda sociniana del \u00e1ngel <em>cultus<\/em> por el otro. De todas las innumerables huestes del cielo, la Escritura se digna darnos a conocer solo dos por nombre: Gabriel y Michael. <\/p>\n<p><strong>2.<\/strong> Pero, en referencia a estas escenas iniciales del Evangelio de San Lucas, se ha objetado adem\u00e1s que estos cantos sagrados, estos estallidos de poes\u00eda hebraica, son inequ\u00edvocamente como arte. , o leyenda; que el cr\u00edtico se siente irresistiblemente impulsado a verlos en una obra elegante, como las canciones de \u00abQueen Mary\u00bb de Tennyson. Hay algunas consideraciones que eliminan este obstinado prejuicio de la cr\u00edtica moderna. Si el trabajo y el genio son los \u00fanicos creadores posibles de cualquier forma de literatura, estas canciones, por supuesto, dif\u00edcilmente pueden ser genuinas. Pero si, de hecho, existe la profec\u00eda; si Jesucristo es su tema principal y central, es natural que, despu\u00e9s de un intervalo de 400 a\u00f1os, despierte de nuevo, justo cuando estaba a punto de visitar la tierra; que el padre del siervo escogido de Dios, que iba a ir como mensajero ante el rostro del Mes\u00edas, fuera lleno del Esp\u00edritu Santo y profetizara. <\/p>\n<p><strong>(1)<\/strong> El Benedictus se form\u00f3, sin duda, en el coraz\u00f3n de Zacar\u00edas durante los largos meses de mutismo forzado, cuando estaba mudo y sin poder hablar. Despu\u00e9s de nueve meses de silencio sali\u00f3 a raudales como el metal fundido cuando se le da salida. <\/p>\n<p><strong>(2)<\/strong> El piadoso hebreo no tendr\u00eda tales dificultades materiales como las que se han sugerido anteriormente. Pues la poes\u00eda hebrea no estaba encadenada por las leyes de una prosodia inexorable. No exigi\u00f3 la modulaci\u00f3n exquisita y severa de la escansi\u00f3n cl\u00e1sica. Los acordes de los salmos se precipitaron espont\u00e1neamente a los labios de aquellos que viv\u00edan en el c\u00edrculo de los escritos del Antiguo Testamento, y hablaban su idioma. Adem\u00e1s, y esto es lo m\u00e1s importante de todo, toda la sustancia y el tenor del Benedictus muestran que no fue moldeado por el arte; que no guarda la misma relaci\u00f3n con la historia del evangelio que los discursos de Pericles o An\u00edbal con las narraciones de Tuc\u00eddides y Tito Livio. \u00bfDesde qu\u00e9 punto de vista debe haber hablado Zaeharias? La visi\u00f3n de Cristo que disfrut\u00f3 fue mucho m\u00e1s clara que la de cualquiera de los salmistas. Sin embargo, el cuadro que dibuj\u00f3 debe haber sido pintado con colores hebreos y colocado en un marco jud\u00edo. Un escritor posterior, en una \u00e9poca preeminentemente sin tacto cr\u00edtico ni sutileza, nunca se habr\u00eda contentado con poner estas declaraciones oraculares en labios de Zacar\u00edas. Sin duda, la Iglesia cristiana, casi desde el principio, ha utilizado estos cantos en el culto diario. Al hacerlo, las interpreta de Jes\u00fas. Pero la cuesti\u00f3n no es, en lo m\u00e1s m\u00ednimo, c\u00f3mo entiende la Iglesia cristiana este y los otros c\u00e1nticos, cuando han estado permanentemente comprometidos con la escritura. La pregunta es si, despu\u00e9s de la cruz y la resurrecci\u00f3n, despu\u00e9s de que todas las cosas se cumplieron, \u00bfpodr\u00eda ella, por alg\u00fan autocontrol concebible, haber logrado escribirlas en tal tensi\u00f3n? Estas canciones hubieran sido m\u00e1s bien como los acordes apocal\u00edpticos, \u201cDigno es el Cordero que fue inmolado\u201d. La mente que escribi\u00f3 el Benedietus, bajo la condici\u00f3n de un pleno conocimiento hist\u00f3rico del evangelio, debe haber sido una mente seria o enga\u00f1osa. Para una mente seria, tal reserva sobre los temas que estaban en la primera fila de sus afectos, habr\u00eda sido antinatural; para una mente enga\u00f1osa hubiera sido, <em>ex hypothesi, <\/em>imposible. As\u00ed, el Benedictus es imposible en una fecha anterior o posterior a la que le asigna el tercer evangelista. Tales visiones de la luz que reci\u00e9n amanec\u00eda, tal concepci\u00f3n del car\u00e1cter general de la redenci\u00f3n que se acercaba, con tal reserva, m\u00e1s bien tal silencio, en cuanto al modo en que se llevar\u00eda a cabo en detalle; tal brillo de plata en el borde de la niebla, tal oscuridad en su coraz\u00f3n; tan extra\u00f1a elocuencia y reserva, s\u00f3lo podr\u00eda haber venido de alguien que se encontraba en la delgada l\u00ednea fronteriza entre las dos dispensaciones, en el espacio infinitesimal entre las dos vastas cadenas anteriores y posteriores. Un poco m\u00e1s, y la canci\u00f3n hubiera sido puramente cristiana; un poco menos, y habr\u00eda sido puramente jud\u00edo. <\/p>\n<p><strong><br \/>II. <\/strong>Procedemos a extraer algunas ense\u00f1anzas de la propia canci\u00f3n. <\/p>\n<p><strong>1.<\/strong> Es bueno recordar qui\u00e9n y qu\u00e9 era Zacar\u00edas. Zacharias fue un sacerdote santo y religioso. El empleo de Zacharias era el de un ministro de un ritual divinamente ordenado. Ahora bien, la verdadera revelaci\u00f3n no trata mec\u00e1nicamente con el esp\u00edritu del hombre. El pensamiento y la expresi\u00f3n toman el molde y el color de la mente, que el esp\u00edritu usa libremente. La forma de la revelaci\u00f3n se adapta a las tendencias naturales ya la condici\u00f3n total de quien es la voz o pluma del Esp\u00edritu Santo. El profeta sacerdote Ezequiel ve a la Iglesia bajo la imagen que naturalmente se le ocurrir\u00eda a alguien que ha sido entrenado en tal elemento: la imagen de un templo. El sacerdote profeta Zacar\u00edas considera la vida de todos los hijos de Dios emancipados como una adoraci\u00f3n continua, un servicio sacerdotal sin fin: \u201cPara que nosotros, sin temor, habiendo sido librados una vez para siempre de la mano de los enemigos, le adoremos continuamente. En santidad y justicia delante de El todos los d\u00edas que tenemos.\u201d Esta es la esencia y el uso de todo el verdadero ritualismo de Dios. Una palabra resumi\u00f3 todo el significado y prop\u00f3sito de la vida sacerdotal de Zacar\u00edas: servir a Dios, adorarlo. Esta palabra, este <em>Ich Dien<\/em> del sacerdocio fiel, \u00e9l hace el <em>Ich Dien<\/em> de todo hijo de Dios. El \u00fanico sacerdote verdadero, cuya venida est\u00e1 tan cerca, permitir\u00e1 a todo el pueblo redimido realizar el verdadero servicio de los sacerdotes, para celebrar el culto de Dios en la larga fiesta de una libertad perpetua. El lema del reino sacerdotal de Cristo sale acertadamente de los labios de un sacerdote inspirado. El significado del ritual del Antiguo Testamento lo da, seg\u00fan conven\u00eda a la conveniencia de las cosas, uno que era \u201cdel orden de Abia\u201d. Estas palabras se cantan en cientos de iglesias. Es bueno que se ense\u00f1e a los cantores a cantar al Se\u00f1or con \u201cgracia\u201d, as\u00ed como con todo el coraz\u00f3n. Pero tanto los coros como las congregaciones deben tener siempre presentes las palabras de Zacar\u00edas: \u201cHacedle sin temor la adoraci\u00f3n y el servicio de una vida\u201d. <\/p>\n<p><strong>2.<\/strong> El lugar que ocupa el Benedictus en el Libro de Oraci\u00f3n reformado es significativo e interesante. Se coloca inmediatamente despu\u00e9s de la segunda lecci\u00f3n en el servicio de la ma\u00f1ana, que siempre es de uno de los Evangelios, Ep\u00edstolas o Apocalipsis. Zacharias fue el primer profeta del Nuevo Testamento; y este es casi el primer himno evang\u00e9lico. La voz y el canto de tal persona pueden escucharse inmediatamente despu\u00e9s de nuestra primera lectura del Nuevo Testamento. No parece, quiz\u00e1s, una mera fantas\u00eda ver en el contenido del Benedictus una referencia a la obra del ministerio cristiano. Zacharias era padre adem\u00e1s de sacerdote. Se vuelve, con un estallido de alegr\u00eda, que no era meramente natural, hacia su beb\u00e9, y lo coloca entre la buena compa\u00f1\u00eda de los profetas: \u201cY t\u00fa tambi\u00e9n, ni\u00f1o, ser\u00e1s llamado profeta del Alt\u00edsimo. Porque adelante, ir\u00e1s delante del Se\u00f1or, para preparar Sus caminos; Para dar conocimiento de salvaci\u00f3n a Su pueblo.\u201d Pero lo que deb\u00eda hacer el hijo de Zacar\u00edas debe ser hecho por los ministros de Cristo, quienes \u201cpreparan y preparan un pueblo para su segunda venida\u201d. Y la lectura simple del evangelio simple en la segunda lecci\u00f3n es un esp\u00e9cimen, por as\u00ed decirlo, y el ep\u00edtome de todo este trabajo. <\/p>\n<p><strong><br \/>III. <\/strong>Esta declaraci\u00f3n de Zacharias es algo m\u00e1s que una canci\u00f3n o un poema. Es un tratado sobre la salvaci\u00f3n. <\/p>\n<p><strong>1.<\/strong> Su autor: \u00abBendito sea el Se\u00f1or, Dios de Israel, porque nos ha suscitado una salvaci\u00f3n fuerte\u00bb. <\/p>\n<p><strong>2.<\/strong> Su causa: \u201cPor la tierna misericordia de nuestro Dios\u201d. <\/p>\n<p><strong>3.<\/strong> Su esencia: \u201cLa salvaci\u00f3n, que consiste en la remisi\u00f3n de los pecados\u201d. <\/p>\n<p><strong>4.<\/strong> Sus bendiciones y privilegios: \u201cSiendo librados de la mano de nuestros enemigos, para servirle sin temor\u201d. <\/p>\n<p><strong>5.<\/strong> Su consecuencia: \u201cEn santidad y justicia delante de \u00c9l todos nuestros d\u00edas\u201d. Todos los que alguna vez hayan entendido el grito profundamente pat\u00e9tico del salmista: \u201cHaz pasar por alto el oprobio que temo\u201d, tambi\u00e9n comprender\u00e1n la preciosidad del privilegio. Concluimos citando la imagen con la que concluye la canci\u00f3n. Se deriva de una caravana que se ha extraviado, cuando los caminantes \u201cse sientan\u201d en la oscuridad, que es como la sombra de la muerte, para perecer en su impotencia. Entonces, en los altos cielos, una estrella gloriosa hace su Epifan\u00eda. Siempre que cantemos este himno con verdadera adoraci\u00f3n espiritual, con el coraz\u00f3n lleno del sentido de esa salvaci\u00f3n que consiste en la remisi\u00f3n de los pecados, el c\u00e1ntico antiguo puede estar tan lleno de vida y alegr\u00eda como cualquier himno nuevo. El Himno de Zacar\u00edas es la tensi\u00f3n de los \u00abPeregrinos de la Noche\u00bb. (<em>Obispo Willliam Alexander.<\/em>)<\/p>\n<\/p>\n<p><strong>C\u00e1ntico de Zacar\u00edas<\/strong><\/p>\n<p><strong>1.<\/strong> Observe que tan pronto como Zacar\u00edas se recuper\u00f3 y recuper\u00f3 su habla, \u00e9l canta las alabanzas de su Redentor y ofrece acci\u00f3n de gracias a Dios. La mejor recompensa que podemos dar a Dios por el uso de nuestra lengua, por dar o restaurar nuestro habla, es publicar la alabanza de nuestro Creador, defender Su causa y vindicar Su honor. <\/p>\n<p><strong>2.<\/strong> El tema de la canci\u00f3n de Zachary. \u00bfCu\u00e1l es la misericordia particular y especial por la que \u00c9l alaba y bendice a Dios? No es por su misericordia particular y privada, a saber, la recuperaci\u00f3n de su habla, aunque sin duda estaba muy agradecido a Dios por esa misericordia; pero bendice y alaba a Dios por las misericordias cat\u00f3licas y universales otorgadas a su Iglesia y pueblo. <\/p>\n<p><strong>3.<\/strong> En este himno evang\u00e9lico hay una predicci\u00f3n prof\u00e9tica, tanto sobre Cristo como sobre Juan. <\/p>\n<p><strong>(1)<\/strong> En cuanto a Cristo, declara que Dios Padre le hab\u00eda enviado por su gratuita misericordia y rica gracia, pero en cumplimiento de su verdad y fidelidad, y seg\u00fan su promesa y juramento que hab\u00eda hecho a Abraham y a los padres del Antiguo Testamento. Donde nota&#8211;<\/p>\n<p><strong>(a)<\/strong> \u00c9l bendice a Dios por la bendici\u00f3n integral del Mes\u00edas&#8211;\u201cvisit\u00f3\u201d, es decir,<em>, en <\/em>la encarnaci\u00f3n de Jes\u00fas. <\/p>\n<p><strong>(b)<\/strong> El fruto y beneficio especial de esta visita llena de gracia y misericordia: la redenci\u00f3n de un mundo perdido. <\/p>\n<p><strong>(c)<\/strong> El car\u00e1cter dado a este Salvador y Redentor: \u00abcuerno de salvaci\u00f3n\u00bb, es decir, <em>, <\/em>un rey y glorioso, fuerte y poderoso , Salvador de Su Iglesia y pueblo. El cuerno en la Escritura significa gloria y dignidad, fuerza y poder; como la hermosura, as\u00ed la fuerza de la bestia reside en su cuerno; ahora Cristo, siendo llamado un cuerno de salvaci\u00f3n, insin\u00faa que \u00c9l mismo es un Salvador real y principesco, y que la salvaci\u00f3n que \u00c9l trae es grande y abundante, gloriosa y poderosa. <\/p>\n<p><strong>(d)<\/strong> La naturaleza y calidad de esa salvaci\u00f3n y liberaci\u00f3n que el Hijo de Dios vino a realizar por nosotros. No una liberaci\u00f3n temporal, como esperaban los jud\u00edos, del poder de los romanos; pero espiritual, de las manos del pecado y de Satan\u00e1s, de la muerte y del infierno; Su dise\u00f1o fue comprar una libertad espiritual para nosotros, para que podamos servirle sin temor, es decir, <em>, <\/em>sin el temor servil y ofensivo de un esclavo, sino con el temor obediente e ingenuo de un ni\u00f1o Aprended, pues, que los creyentes, que eran esclavos de Satan\u00e1s, son hechos por Cristo hombres libres de Dios; y, como tales, deben a Dios un servicio voluntario, alegre y deleitable sin temor, y un servicio constante y perseverante todos los d\u00edas de su vida. <\/p>\n<p><strong>(e)<\/strong> La fuente y la fuente de la cual este glorioso Salvador y gracia de salvaci\u00f3n surgi\u00f3 y brot\u00f3, a saber, de la misericordia y fidelidad de Dios. <\/p>\n<p><strong>(2)<\/strong> Con respecto a Juan, \u00e9l profetiza&#8211;<\/p>\n<p><strong>(a)<\/strong> La naturaleza de Su oficio. <\/p>\n<p><strong>(b)<\/strong> La calidad de su trabajo. Deb\u00eda ser heraldo y heraldo del Alt\u00edsimo; como la estrella de la ma\u00f1ana, prediciendo el glorioso amanecer del Sol de Justicia. <\/p>\n<p><strong>4.<\/strong> Zacar\u00edas, despu\u00e9s de haber dicho algunas palabras acerca de su hijo, vuelve instant\u00e1neamente a celebrar las alabanzas del Salvador, compar\u00e1ndolo con el sol naciente, que brillaba en el resplandor del evangelio para iluminar los rincones oscuros del mundo. (<em>W. Burkitt, MA<\/em>)<\/p>\n<\/p>\n<p><strong>Liberaci\u00f3n a la mano<\/strong><\/p>\n<p>Cuando una guarnici\u00f3n inglesa, durante el mot\u00edn indio, fue sitiada en Lucknow, y casi moment\u00e1neamente esperaba la ca\u00edda de la ciudad, una mujer enferma se despert\u00f3 de su sue\u00f1o, gritando: \u201c\u00a1Estamos salvados! \u00bfNo escuchas la m\u00fasica? \u00a1Ellos vienen! \u00a1Ellos vienen!\u00bb Nadie m\u00e1s pod\u00eda escuchar esa m\u00fasica; sin embargo, en unas pocas horas lleg\u00f3 una fuerza de socorro y la guarnici\u00f3n se salv\u00f3. Esta profec\u00eda de Zacar\u00edas es como la m\u00fasica lejana de la salvaci\u00f3n venidera. Comp\u00e1rese en la \u201cRep\u00fablica holandesa\u201d de Motley el relato del alivio de Leyden. El estado del mundo antes de la venida de Cristo puede compararse con el de los n\u00e1ufragos aferrados a una roca en medio del mar. No hay seguridad para ellos donde est\u00e1n, y no hay seguridad en s\u00ed mismos. \u00a1Con qu\u00e9 ojos de alegr\u00eda contemplan una barca que viene en su rescate desde la tierra lejana! Entonces, en el caso de la humanidad perdida, hab\u00eda que traer la salvaci\u00f3n. Un hombre que cruzaba un p\u00e1ramo una noche oscura cay\u00f3 en un pozo. Trat\u00f3 en vano de salir, pidiendo ayuda en voz alta todo el tiempo. Pronto la gente se reuni\u00f3 en su ayuda y le bajaron una cuerda. Lo agarr\u00f3 y fue arrastrado hacia la luz. As\u00ed que la humanidad no puede ser levantada del abismo del pecado, excepto por la salvaci\u00f3n tra\u00edda desde arriba. (<em>Sunday School Times.<\/em>)<\/p>\n<\/p>\n<p><strong>La fidelidad de Dios<\/strong><\/p>\n<p>Como el canto de Mar\u00eda, este la profec\u00eda de Zacar\u00edas habla de la fidelidad de Dios en sus promesas. En la antig\u00fcedad hab\u00eda un hermoso rito de hospitalidad. Los amigos que resid\u00edan en diferentes pa\u00edses se entregaban emblemas, en cuya presentaci\u00f3n cada uno pod\u00eda reclamar la hospitalidad del otro. Y cuando ambos estuvieran muertos, el hijo de uno podr\u00eda llamar al hijo del otro para la misma hospitalidad presentando su emblema. Las promesas hechas al padre se cumplieron al hijo. As\u00ed, a lo largo de los siglos, los jud\u00edos esperaron el cumplimiento de las promesas hechas a Abraham. Pero a nosotros nos es dado ver con una luz m\u00e1s clara su cumplimiento completo, y c\u00f3mo eso no lleg\u00f3 ni demasiado tarde ni demasiado pronto. (<em>Sunday School Times.<\/em>)<\/p>\n<\/p>\n<p><strong>La canci\u00f3n de Zacharias<\/strong><\/p>\n<p><strong><br \/>Yo. <\/strong>Un\u00e1monos a Zacar\u00edas en su canto de alabanza por esa gran liberaci\u00f3n de la cual Juan fue el presagio. Las bendiciones aqu\u00ed celebradas no se limitaron a los jud\u00edos, sino que son comunes a todo el \u201cpueblo\u201d de Dios. La salvaci\u00f3n es siempre la misma en sustancia, y muy parecida en su forma y medios. <\/p>\n<p><strong><br \/>II. <\/strong>Nos conviene estar agradecidos de que la luz del evangelio haya visitado nuestra propia tierra en particular. Por la misericordia de Dios hemos sido sacados de la idolatr\u00eda, la impureza y la miseria, al conocimiento de la verdad. Veamos que la \u201cluz\u201d est\u00e1 brillando en nuestros corazones y que estamos caminando en ella. <\/p>\n<p><strong><br \/>III. <\/strong>Liberaci\u00f3n de los enemigos por medio del evangelio. Salvado del pecado; sacado del poder de nuestros enemigos espirituales. <\/p>\n<p><strong><br \/>IV. <\/strong>Servir a Dios sin temor. <\/p>\n<p><strong>1.<\/strong> Paz y seguridad exterior. <\/p>\n<p><strong>2.<\/strong> Estado de \u00e1nimo interno producido por la religi\u00f3n. en paz con Dios; deleit\u00e1ndonos en \u00c9l como Padre y Amigo. (<em>James Foote, MA<\/em>)<\/p>\n<\/p>\n<p><strong>La relaci\u00f3n parental<\/strong><\/p>\n<p>Hay hombres y mujeres conocidos en la historia principalmente por su relaci\u00f3n con sus hijos. Eran hombres y mujeres piadosos; hombres y mujeres de capacidad y utilidad en su d\u00eda; pero su lugar preeminente en el mundo es como padres. Este hecho debe ser un est\u00edmulo y una fuente de esperanza para todos los padres. Independientemente de lo que un padre o una madre hayan hecho o dejado de hacer hasta el momento presente, hay que cuidar, amar y cuidar a ese ni\u00f1o, educarlo y orar por \u00e9l, tener fe en su nombre. En ese ni\u00f1o puede residir la esperanza y el gozo de multitudes, y tambi\u00e9n la esperanza y el gozo de los padres. C\u00f3mo esto deber\u00eda animarnos y animarnos mientras nos afanamos y oramos por el hijo de nuestro coraz\u00f3n. Que el ni\u00f1o se levante para llamarnos bienaventurados y, por su causa, todas las generaciones nos llamen bienaventurados. Es para nosotros cumplir con nuestro deber por nuestros hijos. Puede ser que tengamos una recompensa en ellos m\u00e1s all\u00e1 de todas las dem\u00e1s recompensas que tenemos en y para nuestro curso terrenal. Eres el padre o la madre de ese ni\u00f1o. \u00bfCu\u00e1nto de bueno le presagia eso? \u00a1Cu\u00e1nto bien puede presagiaros! (<em>HCTrumbull.<\/em>)<\/p>\n<\/p>\n<p><strong>La fuente del verdadero poder<\/strong><\/p>\n<p>\u201cLlenos del Esp\u00edritu Santo \u201d\u2014eso era apto para alabar a Dios aceptablemente, y para proclamar Su verdad aceptablemente, en los d\u00edas de Zacar\u00edas. No es que Zacharias estuviera lleno de entusiasmo, lleno de seriedad, lleno de conocimiento, lleno de fervor po\u00e9tico; sino que fue lleno del Esp\u00edritu Santo. Eso le dio poder a sus palabras y, por ese hecho, sus palabras est\u00e1n hoy en nuestros o\u00eddos y en nuestros labios. No hay otra fuente de verdadero poder en el servicio de Dios en esta era ni en ninguna otra. Para ser un buen padre, un buen maestro, un buen predicador, un buen estudiante de la Biblia, un buen hombre o una buena mujer, uno necesita estar lleno del Esp\u00edritu Santo; No hay sustituto para esto. (<em>HCTrumbull.<\/em>)<\/p>\n<\/p>\n<p><strong>Canciones compuestas bajo el estr\u00e9s de un sentimiento profundo<\/strong><\/p>\n<p>La noche anterior su ejecuci\u00f3n, Mary Queen of Scots compuso una breve oraci\u00f3n y la cant\u00f3 sola porque no pod\u00eda dormir. Las palabras son muy musicales en el lat\u00edn que ella us\u00f3, expresando el deseo apasionado de un cautivo por escapar: <\/p>\n<p>\u201c\u00a1Oh Se\u00f1or Dios Todopoderoso! \u00a1Mi esperanza est\u00e1 en Ti!<\/p>\n<p>\u00a1Oh Jes\u00fas amado, ahora l\u00edbrame!<br \/>En la duraci\u00f3n m\u00e1s triste, en las ataduras m\u00e1s severas&#8211;<br \/>\u00a1Mi deseo es para Ti!<br \/> Suspirando y llorando, arrodillada y acostada,<\/p>\n<p>Yo adoro, \u00a1te imploro que me liberes!\u201d<\/p>\n<p>Cuando Madame Guyon y su fiel doncella fueron encarceladas, ella compuso canciones para su consuelo. \u201cY luego\u201d, dice ella, \u201clas cantamos juntos, \u00a1alabanzas a Ti, oh Dios nuestro! \u00a1A veces me parec\u00eda como si yo fuera un pajarito, a quien el Se\u00f1or hab\u00eda puesto en una jaula, y que ahora no ten\u00eda nada que hacer sino cantar!\u201d <\/p>\n<p><strong>Valor religioso del canto<\/strong><\/p>\n<p>El obispo Jewel, escribiendo a Pedro M\u00e1rtir, marzo de 1560, dice: \u201cLa religi\u00f3n ahora est\u00e1 un poco m\u00e1s establecida de lo que estaba. La gente est\u00e1 en todas partes sumamente inclinada a la mejor parte. La m\u00fasica eclesi\u00e1stica y popular ha conducido mucho a este resultado. Tan pronto como comenzaron a cantar p\u00fablicamente en una sola iglesia peque\u00f1a en Londres, inmediatamente no solo las otras iglesias vecinas, sino incluso las ciudades distantes, comenzaron a competir entre s\u00ed en la misma pr\u00e1ctica. A veces se puede ver en la Cruz de Pablo, despu\u00e9s del serm\u00f3n, seis mil personas, viejos y j\u00f3venes, de ambos sexos, cantando juntos y alabando a Dios. Esto entristece tristemente a los sacerdotes y al demonio, porque ven que por este medio los discursos sagrados penetran m\u00e1s profundamente en la mente de los hombres, y que su reino se estremece y se hace a\u00f1icos a casi cada nota.\u201d <\/p>\n<p><strong>El c\u00e1ntico de Zacar\u00edas<\/strong><\/p>\n<p>Es enf\u00e1ticamente el c\u00e1ntico de un hombre cuya lengua est\u00e1 desatada; quien por primera vez ha entrado en el significado de los libros que ha estado leyendo desde su ni\u00f1ez, de los servicios en los que se ha ocupado desde que se convirti\u00f3 en sacerdote. Se puede inventar un discurso con tolerable \u00e9xito para un general en v\u00edsperas de una batalla, aunque los que realmente nos han llegado agitan mucho m\u00e1s la sangre; pero la m\u00edmica de este tipo de sentimiento debe haber sido odiosa y despreciable. No s\u00e9 d\u00f3nde podr\u00edas encontrar el sello del fraude m\u00e1s claro e imborrable que en un documento que lo intent\u00f3. Si las palabras de Zacharias han perdurado hasta nuestros d\u00edas, y han sido aceptadas por hombres de diferentes razas como palabras vitales y verdaderas, como palabras que hablan y expresan el coraz\u00f3n humano dentro de ellos, no puedo persuadirme de que tengan ese significado. sello de falta de sinceridad. (<em>FD Maurice, MA<\/em>)<\/p>\n<\/p>\n<p><strong>Canto espiritual espont\u00e1neo<\/strong><\/p>\n<p>Uno no puede evitar pensar que la mente y el coraz\u00f3n de Zacharias durante todos esos nueve meses se hab\u00edan estado llenando con esta canci\u00f3n. Y ahora brota de inmediato, como brota de repente una flor donde ayer no hab\u00eda m\u00e1s que un toro de vaina verde. Este canto es tan espont\u00e1neo como el de una alondra, y tan l\u00edrico. As\u00ed como David encontr\u00f3 una oraci\u00f3n en su <span class='bible'>2Sa 7:27<\/span>), Zacar\u00edas encontr\u00f3 una canci\u00f3n en la suya. (<em>ABGrosart, DD<\/em>)<\/p>\n<\/p>\n<p>Es una escena maravillosa en la casa del anciano sacerdote Zacharias que se nos permite presenciar. Los labios del sacerdote llevaban mucho tiempo sellados. En silencio hab\u00eda esperado el cumplimiento de la promesa divina. Su lengua no deb\u00eda ser desatada hasta que se cumpliera la palabra del Se\u00f1or, para que su primera expresi\u00f3n fuera alabanza a Dios por sus obras maravillosas. Era manifiesto que comenzaba una nueva era: la era de la tan esperada redenci\u00f3n de Israel. Este es el tono del himno de alabanza de Zacar\u00edas. As\u00ed como un arroyo de monta\u00f1a, que, despu\u00e9s de haber sido encerrado durante mucho tiempo, finalmente encuentra una salida, salta con tumultuosa alegr\u00eda, as\u00ed la emoci\u00f3n reprimida durante mucho tiempo del coraz\u00f3n de Zacar\u00edas fluye en un \u00e9xtasis de alabanza: \u00abBendito sea el Se\u00f1or\u201d, etc. Sentimos que esta no es la expresi\u00f3n simplemente de su propia alegr\u00eda personal y paternal. Es el c\u00e1ntico de j\u00fabilo de todos los que esperaban la redenci\u00f3n en Israel, encontrando as\u00ed expresi\u00f3n a trav\u00e9s de \u00e9l. Observamos que fue&#8211;<\/p>\n<p><strong><br \/>I. <\/strong>Un \u00e1rbol DE CUMPLIMIENTO (vers\u00edculos 67-70), y&#8211;<\/p>\n<p><strong><br \/>II. <\/strong>UN TIEMPO DE SALVACI\u00d3N (vers\u00edculos 71-79). (<em>Profesor Luthardt.<\/em>)<\/p>\n<\/p>\n<p><strong>Emoci\u00f3n que se convierte en discurso<\/strong><\/p>\n<p><em>A <\/em>una emoci\u00f3n v\u00edvida de amor y gratitud es muy propensa a estallar en el habla, ya sea en la forma de un testimonio p\u00fablico de Cristo, o en la voz de un canto. He conocido una reuni\u00f3n de oraci\u00f3n, en un momento de despertar, para volverse como un aviario, porque Dios hab\u00eda puesto un c\u00e1ntico nuevo en decenas de bocas. (<em>TL Cuyler.<\/em>)<\/p>\n<\/p>\n<p><strong>Cambiados por el Esp\u00edritu<\/strong><\/p>\n<p>Ning\u00fan hombre o mujer entre vosotros sabe lo que podr\u00eda ser si estuviera lleno del Esp\u00edritu. \u00bfQu\u00e9 es ese rudo Luther? Solo es apto para haber sido un matador de bueyes o un talador de robles en el bosque; pero llena a Lutero del Esp\u00edritu Santo y \u00bfqu\u00e9 es \u00e9l? \u00a1Toma el toro de Roma por los cuernos, mata a las bestias salvajes del error en el gran escenario del evangelio, y es m\u00e1s que vencedor por el poder que mora en \u00e9l! Tomemos a Juan Calvino, apto naturalmente para ser un abogado astuto, cortando y dividiendo puntos agradables, juzgando este precedente y aquel, desperdiciando su tiempo en sutilezas inmateriales; pero ll\u00e9nalo con el Esp\u00edritu Santo y Juan Calvino se convierte en el poderoso maestro de la gracia, el reflejo de la sabidur\u00eda de todas las edades pasadas, y una gran luz para derramar un rayo brillante incluso hasta que amanezca el Milenio. Jefe, pr\u00edncipe y rey. de todos los maestros no inspirados, el poderoso vidente de Ginebra, lleno del Esp\u00edritu de Dios, ya no es Juan Calvino, \u00a1sino un \u00e1ngel de las Iglesias enviado por Dios! (<em>CHSpurgeon.<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lc 1,67-79 Y su padre Zacar\u00edas fue lleno del Esp\u00edritu Santo El c\u00e1ntico de Zacar\u00edas I. Cuestiones preliminares. En la parte inicial del Evangelio de San Lucas, hay una definici\u00f3n de tiempo, lugar y circunstancia que nos hace sentir que no estamos respirando el aire o mirando a trav\u00e9s de la luz enga\u00f1osa de la &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-167-79-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Lucas 1:67-79 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39229","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=39229"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39229\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=39229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=39229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=39229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}