{"id":39236,"date":"2022-07-16T08:49:36","date_gmt":"2022-07-16T13:49:36","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-178-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:49:36","modified_gmt":"2022-07-16T13:49:36","slug":"estudio-biblico-de-lucas-178-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-178-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Lucas 1:78 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Lc 1,78<\/span><\/p>\n<p><em>Por la ternura misericordia de nuestro Dios<\/em><\/p>\n<p><strong>Advenimiento de Cristo<\/strong><\/p>\n<p><strong><br \/>I.<\/strong><\/p>\n<p>UNA VISTA MUY CONMOVEDORA DEL ESTADO DE LA HUMANIDAD ANTES DE LA VENIDA DE CRISTO. \u201cOscuridad y sombra de muerte\u201d. <\/p>\n<p><strong>1.<\/strong> Ignorante del car\u00e1cter moral de Dios. <\/p>\n<p><strong>2.<\/strong> Ignorantes de la pureza de la ley de Dios. <\/p>\n<p><strong>3.<\/strong> Ignorante en cuanto a la naturaleza maligna y las terribles consecuencias del pecado. <\/p>\n<p><strong>4.<\/strong> Ignorar la verdadera fuente de la felicidad. <\/p>\n<p><strong>5.<\/strong> Ignorante respecto al estado futuro. <\/p>\n<p><strong><br \/>II. <\/strong>UNA DESCRIPCI\u00d3N MUY INTERESANTE DEL SALVADOR. \u00abLa aurora\u00bb. <\/p>\n<p><strong>1.<\/strong> La gran fuente de luz; <\/p>\n<p><strong>(1)<\/strong> Naturales; <\/p>\n<p><strong>(2)<\/strong> intelectual; <\/p>\n<p><strong>(3)<\/strong> racional; <\/p>\n<p><strong>(4)<\/strong> espiritual. <\/p>\n<p><strong>2.<\/strong> La aurora es gradual y progresiva. <\/p>\n<p><strong>(1)<\/strong> La revelaci\u00f3n se ha despertado cada vez m\u00e1s y m\u00e1s a lo largo de los siglos. <\/p>\n<p><strong>(2)<\/strong> La creciente iluminaci\u00f3n de los individuos. <\/p>\n<p><strong>3.<\/strong> La aurora es cierta e irresistible. Las nubes morales m\u00e1s oscuras eventualmente deben sucumbir a los rayos brillantes que arroja el Sol de Justicia. <\/p>\n<p><strong>4.<\/strong> La aurora es libre y com\u00fan a todos. <\/p>\n<p><strong><br \/>III. <\/strong>UNA REPRESENTACI\u00d3N MUY ALENTADORA DEL DISE\u00d1O DE LA MISI\u00d3N DE CRISTO. <\/p>\n<p><strong>1.<\/strong> Alumbrar. se ha manifestado <\/p>\n<p><strong>(1)<\/strong> en la dignidad de su persona; <\/p>\n<p><strong>(2)<\/strong> en la perfecci\u00f3n de Su expiaci\u00f3n; <\/p>\n<p><strong>(3)<\/strong> en la plenitud de Su gracia; <\/p>\n<p><strong>(4)<\/strong> en la voluntad de salvar que ha manifestado; <\/p>\n<p><strong>(5)<\/strong> en el descubrimiento que ha hecho de los medios de limpieza de la culpa moral. <\/p>\n<p><strong>2.<\/strong> Dar paz. <\/p>\n<p><strong>(1)<\/strong> Paz con Dios;<\/p>\n<p><strong>(2)<\/strong>paz con nuestros semejantes;<\/p>\n<p><strong>(3)<\/strong> paz con nosotros mismos. <\/p>\n<p>Nota en conclusi\u00f3n: <\/p>\n<p><strong>1.<\/strong> La infinita condescendencia de Jehov\u00e1 al interponerse en nuestro favor. <\/p>\n<p><strong>2.<\/strong> El deber y el privilegio del cristiano. <\/p>\n<p><strong>(1)<\/strong> Su deber es confiar en el Se\u00f1or en tiempo de oscuridad. <\/p>\n<p><strong>(2)<\/strong> Su privilegio a veces es caminar a la luz del rostro de Dios.<\/p>\n<p><strong>3.<\/strong> El estado miserable de aquellos que escuchan las buenas noticias y, sin embargo, se mantienen apartados. <\/p>\n<p><strong>4.<\/strong> Si los placeres de la religi\u00f3n son tan grandes en la tierra, \u00bfcu\u00e1l debe ser el disfrute de los creyentes en el mundo superior? (<em>Dr. Scott.<\/em>)<\/p>\n<\/p>\n<p><strong>La tierna misericordia de nuestro Dios<\/strong><\/p>\n<p>El original es , \u201cLa misericordia del coraz\u00f3n de nuestro Dios\u201d. Esto parece significar no solo ternura, sino mucho m\u00e1s. La misericordia del coraz\u00f3n de Dios es, por supuesto, la misericordia de su gran ternura, la misericordia de su infinita dulzura y consideraci\u00f3n; pero otros pensamientos tambi\u00e9n salen de la expresi\u00f3n, como abejas de una colmena. Significa la misericordia del alma misma de Dios. El coraz\u00f3n es asiento y centro de la vida, y la misericordia es para Dios como Su propia vida. La misericordia es de esencia divina; no hay Dios aparte de Su coraz\u00f3n, y la misericordia yace en el coraz\u00f3n de Dios. Esto no es todo; la misericordia del coraz\u00f3n de Dios significa Su cordial misericordia, Su cordial deleite en la misericordia. La remisi\u00f3n de los pecados es un negocio en el que el Se\u00f1or pone Su coraz\u00f3n. Perdona con intensidad de voluntad y prontitud de alma. Dios hizo el cielo y la tierra con Sus dedos, pero dio a Su Hijo con Su coraz\u00f3n para que pudiera salvar a los pecadores. El Dios eterno ha puesto toda su alma en la tarea de redimir a los hombres. <\/p>\n<p><strong><br \/>Yo. <\/strong>Dios muestra Su tierna misericordia en que SE DIGNA A VISITARNOS. No s\u00f3lo se compadeci\u00f3 de nosotros desde la distancia y nos envi\u00f3 socorro por medio de la escalera que vio Jacob, sino que \u00c9l mismo nos visit\u00f3. <\/p>\n<p><strong>1.<\/strong> La gran visita de Dios a nosotros es la encarnaci\u00f3n de nuestro bendito Se\u00f1or y Salvador Jesucristo. <\/p>\n<p><strong>2.<\/strong> La proclamaci\u00f3n del evangelio en una naci\u00f3n, oa cualquier individuo, es una visita de la misericordia de Dios. <\/p>\n<p><strong>3.<\/strong> Ha visitado a algunos de nosotros de una manera a\u00fan m\u00e1s notable, porque por el Esp\u00edritu Santo ha entrado en nuestros corazones y ha cambiado la corriente de nuestras vidas. \u00c9l ha vuelto nuestros afectos hacia lo que es correcto al iluminar nuestros juicios. \u00c9l nos ha llevado a la confesi\u00f3n del pecado, nos ha tra\u00eddo a la aceptaci\u00f3n de Su misericordia a trav\u00e9s de la sangre expiatoria; y as\u00ed \u00c9l verdaderamente nos ha salvado. <\/p>\n<p><strong><br \/>II. <\/strong>Dios muestra Su tierna misericordia en que NOS VISITA COMO EL AMANECER DESDE LO ALTO No viene a nosotros en Cristo, o por Su Esp\u00edritu, como una tempestad, como cuando vino de Par\u00e1n, con diez mil de Sus santos, en toda la pompa de Su ley de fuego; pero \u00c9l nos ha visitado como la ma\u00f1ana sonriente, que en dulce gloria inunda el mundo de alegr\u00eda. \u00c9l ha venido, adem\u00e1s, no como un resplandor que pronto se extinguir\u00e1, sino como una luz que durar\u00e1 nuestro d\u00eda, s\u00ed, durar\u00e1 para siempre. Despu\u00e9s de la larga noche oscura y fr\u00eda de nuestra miseria, el Se\u00f1or viene de la manera m\u00e1s adecuada y eficaz; ni como un rel\u00e1mpago, ni una vela, ni un meteoro llameante, sino como el sol que comienza el d\u00eda. <\/p>\n<p><strong>1.<\/strong> La visitaci\u00f3n del Se\u00f1or sobre nosotros es como la aurora, porque conviene a nuestros ojos. El d\u00eda, cuando amanece por primera vez en el este, no tiene el resplandor del mediod\u00eda abrasador a su alrededor; pero asoma como una luz gris, que aumenta gradualmente. As\u00ed vino Cristo; oscuramente, por as\u00ed decirlo, al principio, en Bel\u00e9n, pero poco a poco aparecer\u00e1 en toda la gloria del Padre. As\u00ed el Esp\u00edritu de Dios viene a nosotros en un progreso gradual. La revelaci\u00f3n de Dios a cada individuo se hace en forma y modo tiernamente conformes a la condici\u00f3n y capacidad del favorecido. \u00c9l nos muestra tanto de s\u00ed mismo como para deleitarnos sin abrumarnos por completo con el exceso de brillo. <\/p>\n<p><strong>2.<\/strong> Las visitas de Dios son como la aurora, porque acaban con nuestras tinieblas. Nuestra noche termina de una vez por todas cuando contemplamos a Dios visit\u00e1ndonos en Cristo Jes\u00fas. Nuestro d\u00eda puede nublarse, pero la noche no volver\u00e1. <\/p>\n<p><strong>3.<\/strong> La venida de Cristo al mundo es como la luz de la ma\u00f1ana, porque viene con tal grandeza de bendici\u00f3n presente. \u00c9l es la Luz que alumbra a todo hombre. Hay otra luz. <\/p>\n<p><strong>4.<\/strong> La venida de Cristo es como la aurora, porque nos trae la esperanza de una mayor gloria por venir. La aurora no es el mediod\u00eda, pero es su segura garant\u00eda; y as\u00ed el Primer Advenimiento es la prenda de la gloria que ser\u00e1 revelada. <\/p>\n<p><strong><br \/>III. <\/strong>Hay otro ejemplo de gran ternura en esto, que EL SE\u00d1OR NOS VISITA EN NUESTRO ESTADO M\u00c1S BAJA. Dios viene a nosotros como la ma\u00f1ana, que no espera al hombre, ni se demora a los hijos de los hombres. Da con alegr\u00eda a los que no tienen ning\u00fan m\u00e9rito (<span class='bible'>Rom 5:6<\/span>; <span class='bible'>Rom 5:8<\/span>). \u00c9l viene a nosotros cuando estamos&#8211;<\/p>\n<p><strong>1.<\/strong> En nuestros pecados. <\/p>\n<p><strong>2.<\/strong> En la oscuridad. <\/p>\n<p><strong>3.<\/strong> En ruina. <\/p>\n<p><strong><br \/>IV. <\/strong>Nuestro Dios muestra Su tierna misericordia, en que NOS VISITA CON TAN MARAVILLOSOS Y GOZOSOS RESULTADOS. Imagine una caravana en el desierto, que se ha perdido hace mucho tiempo y est\u00e1 hambrienta. El sol se ha puesto hace mucho tiempo, y la oscuridad ha hecho que el coraz\u00f3n de todos decaiga. A su alrededor hay un desierto de arena y una oscuridad egipcia. All\u00ed deben permanecer y morir a menos que puedan encontrar la pista. Se sienten en un caso terrible, porque hambrientos y sedientos, su alma desfallece en ellos. Ni siquiera pueden dormir por miedo. M\u00e1s y m\u00e1s pesada cae la noche, y las humedades est\u00e1n sobre las tiendas, helando las almas de los viajeros. \u00bfLo que se debe hacer? \u00a1C\u00f3mo miran! \u00a1Ay, ninguna estrella los consuela! Por fin los centinelas gritan: \u201c\u00a1Llega la ma\u00f1ana!\u201d Rompe sobre el mar de arena y, lo que es mejor, revela un mont\u00f3n que se hab\u00eda puesto como se\u00f1al, y los viajeros han encontrado la pista. La aurora los ha salvado de una r\u00e1pida destrucci\u00f3n al descubrir el camino de la paz. Conclusi\u00f3n: Si la tierna misericordia de Dios nos ha visitado; mostremos tierna misericordia en nuestro trato con nuestros semejantes. (<em>CHSpurgeon.<\/em>)<\/p>\n<\/p>\n<p><strong>El desarrollo gradual de la redenci\u00f3n<\/strong><\/p>\n<p>Nuestro tema es el desarrollo de la redenci\u00f3n, como el sol, \u201cbrillando m\u00e1s y m\u00e1s hasta el d\u00eda perfecto\u201d. <\/p>\n<p><strong><br \/>Yo. <\/strong>HAY UNA GRADUALIDAD EN TODAS LAS OBRAS DE DIOS. En la esfera f\u00edsica, el desarrollo gradual es una ley universal. Al principio todo era un caos de materia sin vida, luego apareci\u00f3 la vida vegetal, luego formas bajas de vida bruta, luego el mam\u00edfero y luego el hombre. El mundo no alcanz\u00f3 su estado actual en unos pocos segundos, el caos no se convirti\u00f3 en un cosmos en una hora. En el trabajo del primer d\u00eda solo vemos poder; pero en el trabajo del segundo d\u00eda vemos sabidur\u00eda; y en el trabajo del tercer d\u00eda vemos bondad; y as\u00ed avanzamos paso a paso, hasta que el sexto d\u00eda trae la gloria suprema, el hombre, el se\u00f1or de la creaci\u00f3n, lleno de las armon\u00edas de los cielos. La creaci\u00f3n no es el crecimiento de un hongo, sino un crecimiento gradual del roble. En las esferas intelectual y moral hay gradualidad. Incluso nuestra conciencia se desarrolla. La conciencia natural se desarrolla gradualmente, y la conciencia reflexiva del pensador profundo es s\u00f3lo un desarrollo posterior de lo natural. Crecemos paso a paso. Nuestra educaci\u00f3n procede gradualmente. El pr\u00edncipe y el pobre deben comenzar con el alfabeto y la tabla de multiplicar, y luego en adelante, \u201cl\u00ednea por l\u00ednea y precepto por precepto\u201d. Nuestros grandes descubrimientos han sido graduales. \u00a1Con qu\u00e9 lentitud se convirti\u00f3 la astrolog\u00eda de los antiguos en nuestra astronom\u00eda del siglo XIX! \u00a1Cu\u00e1n gradualmente se convirti\u00f3 la alquimia de los padres en la qu\u00edmica moderna de un Faraday! Y, nuevamente, en la esfera moral hay un desarrollo gradual. El nuevo hombre en Cristo Jes\u00fas no alcanza la plena estatura de una sola vez. Por un tiempo, es \u201cun peque\u00f1o en Cristo\u201d, luego \u201ccrece en la gracia\u201d y, finalmente, alcanza \u201cla medida de la estatura de la plenitud de Cristo\u201d. <\/p>\n<p><strong><br \/>II. <\/strong>RAZONAMOS POR ANALOG\u00cdA QUE LA GRADUALIDAD QUE ENCONTRAMOS EN LA NATURALEZA Y EL HOMBRE TAMBI\u00c9N SE PUEDE ESPERAR EN EL PROGRESO DE LA REDENCI\u00d3N, PORQUE DIOS ES AUTOR DE AMBOS. El Dios de la roca y la estrella es tambi\u00e9n el Dios de la Biblia, y no nos sorprende encontrar este desarrollo gradual en Apocalipsis, cuatro mil a\u00f1os transcurridos entre la ca\u00edda del primer Ad\u00e1n y el advenimiento del segundo Ad\u00e1n. La redenci\u00f3n creci\u00f3 a medida que crec\u00eda el mundo, creci\u00f3 a medida que crec\u00eda la gracia humana, lentamente. Hasta donde sabemos, Dios fue lo suficientemente poderoso para traer la redenci\u00f3n m\u00e1s pronto; pero por alg\u00fan sabio prop\u00f3sito, dej\u00f3 el mundo a la tenue luz de las estrellas durante cuarenta siglos. \u00bfPor qu\u00e9 esta lentitud? \u00c9l nunca tiene prisa, porque \u201cve el fin desde el principio\u201d. La marcha de los hebreos desde Egipto hasta Cana\u00e1n, si hubieran tomado una ruta directa, s\u00f3lo les habr\u00eda ocupado unos pocos meses; pero el Se\u00f1or los mantuvo en el desierto solitario durante cuarenta a\u00f1os. Lo Divino nunca tiene prisa. Jesucristo pas\u00f3 treinta a\u00f1os en la tierra antes de realizar un milagro, \u00a1no hay prisa! Y, de hecho, nos regocijamos en esta gradualidad. Agradecemos cordialmente a Dios por ello. \u00bfY por qu\u00e9? Simplemente porque una revelaci\u00f3n completa a la vez nos abrumar\u00eda. Si el sol natural llegara a su meridiano de una vez, el verde tierno de la tierra se reducir\u00eda a cenizas. \u201cOh Dios, cu\u00e1n misericordioso eres al revelarte gradualmente a nosotros de una manera adaptada a nuestras d\u00e9biles capacidades. No es un castigo negarnos estos poderosos misterios, sino una misericordia\u201d. Y, adem\u00e1s, amigos, no nos conformar\u00edamos con un Cristo peque\u00f1o, que podr\u00eda revelarse total y completamente en un siglo o dos. Somos grandes pecadores, y necesitamos un gran Cristo que nos salve, un Cristo que demande, no seis mil a\u00f1os, sino todos los incontables a\u00f1os de la eternidad para revelarlo plenamente. Y, bendito sea Dios, que Cristo se encuentra en nuestro glorioso evangelio. Y no pensemos que el desarrollo de la relaci\u00f3n ha llegado todav\u00eda a su fin. No, lejos de eso. <\/p>\n<p><strong><br \/>III. <\/strong>EL DESARROLLO DE LA REDENCI\u00d3N DE ETAPA A ETAPA. (<em>JODavies.<\/em>)<\/p>\n<\/p>\n<p><strong>Esperando la aurora<\/strong><\/p>\n<p>Muchos videntes canosos anhelaban el la aurora, pero no la vio. Un dulce evangelista gal\u00e9s tiene una ilustraci\u00f3n muy llamativa sobre este punto. Alrededor de la \u00e9poca de Navidad, se espera que John, el hermano mayor, regrese de Londres en el tren de medianoche. Todos los ni\u00f1os m\u00e1s peque\u00f1os est\u00e1n en \u00e9xtasis y todos desean quedarse despiertos hasta su llegada. \u201cOre, padre, qued\u00e9monos despiertos para esperar a Juan en casa\u201d, es la petici\u00f3n universal. Pero la respuesta es: \u201cNo, queridos m\u00edos, ser\u00e1 demasiado tiempo para que esperen; debes ir a descansar; ver\u00e1s a John por la ma\u00f1ana, no antes. Amigos, los antiguos profetas esperaban un Salvador: su Hermano Mayor, Jes\u00fas. Cu\u00e1n encantados estar\u00edan de verlo en la carne; pero se vieron obligados a entrar en el lecho fr\u00edo de la tumba antes de Su llegada. David clam\u00f3: \u201cPadre, d\u00e9jame ver el Cuerno de la Salvaci\u00f3n del cual cant\u00e9 tan bien\u201d. \u201cNo, hija M\u00eda, debes retirarte.\u201d Job implor\u00f3: \u201cPadre, d\u00e9jame ver a mi Redentor viviente\u201d. \u201cNo, hija M\u00eda, debes retirarte; pero t\u00fa lo ver\u00e1s despu\u00e9s de que despiertes en la ma\u00f1ana de la resurrecci\u00f3n.\u201d Malaqu\u00edas clam\u00f3: \u201cPadre, soy casi el \u00faltimo de todos ellos; d\u00e9jame ver el Sol de Justicia al que cant\u00e9 tan dulcemente\u201d. \u201cNo, hija M\u00eda, debes retirarte a descansar; ser\u00e1 demasiado tiempo para que usted espere. Y se retiraron en silencio a sus fr\u00edas tumbas para descansar. Pero al fin, el canoso Sime\u00f3n avanz\u00f3 e implor\u00f3 fervientemente: \u201c\u00a1Oh! Padre m\u00edo, el tren est\u00e1 por salir, seg\u00fan la tabla de mi hermano Daniel; d\u00e9jame quedarme despierto para ver el Consuelo de Israel.\u201d \u201cS\u00ed, hija M\u00eda, tu petici\u00f3n es concedida\u201d, dijo el Padre, y al viejo santo se le permiti\u00f3 ver el amanecer, y tan encantado qued\u00f3 con su esplendor, que or\u00f3 por la muerte&#8211;(\u00a1qu\u00e9 fuerte santo!)- -\u201cSe\u00f1or, ahora deja que tu siervo se vaya en paz, porque han visto mis ojos tu salvaci\u00f3n, la cual has preparado en presencia de todos los pueblos, \u00a1una luz para iluminaci\u00f3n de las naciones y la gloria de tu pueblo Israel! \u201c\u00a1Gracias al cielo, el Sol ha salido y el mundo ahora est\u00e1 envuelto en un d\u00eda glorioso! (<em>JO Davies.<\/em>)<\/p>\n<\/p>\n<p><strong>La misericordia de Dios<\/strong><\/p>\n<p><em>Un <\/em>sentido vivo de la tierna misericordia de Dios debe impulsarnos en el camino del deber, y en el camino al cielo. En qu\u00e9 aspectos se manifiesta la tierna misericordia de Dios hacia sus criaturas. <\/p>\n<p><strong><br \/>Yo. <\/strong>EN EL CAR\u00c1CTER QUE DIOS HA CONCRETO ADJUDICAR PARA CON SUS CRIATURAS DEPENDIENTES. \u00c9l se siente hacia nosotros como un padre para su descendencia. \u00bfQui\u00e9n sino un padre hubiera ideado tal plan de redenci\u00f3n? <\/p>\n<p><strong><br \/>II. <\/strong>EN EL BIEN TEMPORAL SE MANIFIESTA SU TIERNA MISERICORDIA. El arreglo misericordioso que marca el curso de la vida humana. Por ejemplo, un beb\u00e9 depende m\u00e1s de la ayuda de los dem\u00e1s que cualquier otra criatura; para satisfacer esta necesidad, Dios en su gracia ha hecho que el m\u00e1s fuerte de todos los instintos humanos sea el del afecto de una madre por su hijo. Aqu\u00ed Su tierna misericordia se muestra abundantemente. Una vez m\u00e1s, a medida que avanzamos en la vida, la misericordia de Dios no se muestra menos. Era necesario que \u00c9l marcara Su desaprobaci\u00f3n del pecado con lo que se llama una maldici\u00f3n. En lugar de deformidad corporal y dolor constante, la maldici\u00f3n era que deb\u00edamos <em>trabajar, <\/em>que es a la vez una gran fuente de salud y felicidad. Incluso la muerte se nos presenta de tal manera que, al acercarse, deja de tener el aspecto del rey de los terrores, y se la considera como un amable amigo que viene a aliviarnos del cansancio y el dolor. La misericordia de Dios es evidente en los afectos incidentales a la vida; santos, ap\u00f3stoles y m\u00e1rtires han experimentado la bienaventuranza del sufrimiento. Luego piensa en las bendiciones <em>positivas<\/em> con las que Dios, en Su misericordia, ha elegido para endulzar la copa de la existencia mortal. Nacemos en tierra cristiana; salud, etc. C\u00f3mo el mejoramiento de nuestras almas debe ser una consideraci\u00f3n correcta de las misericordias divinas. (<em>A. Garry, MA<\/em>)<\/p>\n<\/p>\n<p><strong>La misericordia de Dios hacia un mundo oscuro<\/strong><\/p>\n<p><strong> &gt;<br \/>Yo. <\/strong>LA CONDICI\u00d3N DEL MUNDO ANTERIOR A LA VENIDA DE CRISTO. <\/p>\n<p><strong>1.<\/strong> Un estado de ignorancia. <\/p>\n<p><strong>2.<\/strong> Estado de peligro. <\/p>\n<p><strong><br \/>II. <\/strong>LA MISERICORDIA DE DIOS HACIA EL MUNDO EN ESA CONDICI\u00d3N. <\/p>\n<p><strong>1.<\/strong> Inmerecido. <\/p>\n<p><strong>2.<\/strong> No solicitado. <\/p>\n<p><strong>3.<\/strong> Condimentada. <\/p>\n<p><strong><br \/>III. <\/strong>LA MANERA EN QUE SE MANIFEST\u00d3 LA MISERICORDIA DE DIOS. <\/p>\n<p><strong>1.<\/strong> Envi\u00f3 a su hijo para iluminarla en su ignorancia. <\/p>\n<p><strong>2.<\/strong> Envi\u00f3 a su hijo para guiarlo en su peligro. (<em>G. Brooks.<\/em>)<\/p>\n<\/p>\n<p><strong>Oscuridad y peligro<\/strong><\/p>\n<p>Hay debajo de los suburbios de la antigua ciudad de Roma muchos pasajes oscuros y estrechos, excavados en la piedra blanda. Estos se llaman las catacumbas, y fueron utilizados como lugares de entierro por los primeros cristianos. Estos pasadizos son much\u00edsimos, se cruzan y se vuelven a cruzar entre s\u00ed, y se extienden por una inmensa distancia bajo tierra de la manera m\u00e1s desconcertante. Tan complicado y desconcertante es este laberinto de galer\u00edas subterr\u00e1neas que es sumamente peligroso explorarlas sin un gu\u00eda. Una vez, un joven artista se aventur\u00f3 a visitarlos <em>solo<\/em>, llev\u00e1ndose consigo algunas velas y asegur\u00e1ndose de regresar a salvo con un ovillo de cordel, uno de cuyos extremos at\u00f3 de forma segura afuera. Al cabo de un rato, se sent\u00f3 a dibujar en uno de los sombr\u00edos recovecos, ya que, seg\u00fan cre\u00eda, hab\u00eda puesto a salvo el extremo de la pista bajo una piedra. Pero levant\u00e1ndose de repente para alterar su dibujo, volc\u00f3 y apag\u00f3 su vela. Se apresur\u00f3 a encender una cerilla, pero descubri\u00f3 que por alg\u00fan olvido s\u00f3lo quedaban dos o tres, y en su prisa nerviosa no logr\u00f3 que se encendieran. Ahora busc\u00f3 apresuradamente la l\u00ednea para guiarlo de regreso a la entrada, pero no pudo encontrarla por ninguna parte. Se hab\u00eda deslizado de su lugar. En vano lo busc\u00f3; arroj\u00e1ndose al suelo, lo busc\u00f3 en todas direcciones, pero no pudo encontrarlo en ninguna parte. Desesperaba de volver a alcanzar la luz del d\u00eda; pens\u00f3 que deb\u00eda morir de hambre, vagando por el laberinto desesperado de aquellos pasadizos oscuros; pero justo cuando se arroj\u00f3 una vez m\u00e1s a la tierra con total des\u00e1nimo, sinti\u00f3 algo debajo de su mano. \u00a1Era el cordel, y \u00e9l estaba a salvo! As\u00ed los gentiles \u201cse sentaron en tinieblas\u201d; as\u00ed el mundo pagano busc\u00f3 a tientas la verdad. Estaban perdidos en los oscuros recovecos de la ignorancia y la duda. Pero las buenas nuevas de un Redentor llegaron como una pista que los condujo al calor, la luz y el sol del cristianismo. (<em>W. Hardman, LL. D.<\/em>)<\/p>\n<\/p>\n<p><strong>La necesidad y gloria de Cristo<\/strong><\/p>\n<p>La aurora significa el sol. La adoraci\u00f3n del sol era la mayor de las adoraciones paganas. \u00a1Qu\u00e9 glorioso es el sol! \u00a1Qu\u00e9 necesario! Un emblema apto de la necesidad y la gloria de Cristo. Sin \u00c9l no podr\u00edamos tener control, ni conciencia, y por lo tanto, ni paz, ni confianza. Pero entonces, si Cristo es tan necesario, \u00bfc\u00f3mo es que los hombres pueden vivir en su ignorancia? \u00bfNo hay ciegos en el mundo? Son im\u00e1genes muy acertadas de los incr\u00e9dulos. El sol hace brotar ma\u00edz y frutos para ellos como para nosotros. Sienten su calor y lo buscan, no para verlo, sino porque es m\u00e1s c\u00e1lido. As\u00ed los hombres del mundo son ayudados y consolados por las virtudes de los cristianos, y lo que pasa sin que ellos mismos lo vean. Y entonces son honestos, etc., porque es la mejor pol\u00edtica y arroja un brillo soleado sobre sus vidas. Y todo el tiempo nunca lo han visto ni conocido, y solo han o\u00eddo hablar de \u00c9l con el o\u00eddo. Los ciegos no ven el sol en verano elev\u00e1ndose m\u00e1s alto en los cielos; solo sienten que hace m\u00e1s calor. As\u00ed que estos no ven el reino de Cristo ensanch\u00e1ndose, sino que solo se regocijan de que hay m\u00e1s honestidad y bondad en el exterior. As\u00ed el mundo siente y sabe que es mejor para la venida de Cristo. Muy diferente es con aquellos cuyos ojos est\u00e1n abiertos y que realmente ven. Saben en qui\u00e9n han cre\u00eddo. Son guiados por el camino de la paz. (<em>Obispo E. Steere.<\/em>)<\/p>\n<\/p>\n<p><strong>La aurora desde lo alto<\/strong><\/p>\n<p>Podemos notar tres cosas en el texto:&#8211;<\/p>\n<p><strong><br \/>I. <\/strong>UNA DECLARACI\u00d3N DE UN HECHO MUY BENDITO: \u201cLa aurora nos visit\u00f3 desde lo alto\u201d. <\/p>\n<p><strong><br \/>II. <\/strong>LA FUENTE Y EL ORIGEN DE ESE HECHO BENDITO \u201cPor la tierna misericordia de nuestro Dios\u201d. <\/p>\n<p><strong><br \/>III. <\/strong> SUS DIVINOS FRUTOS Y CONSECUENCIAS.\u201d PARA dar luz a los que habitan en tinieblas y en sombra de muerte; para encaminar nuestros pasos por el camino de la paz\u201d. <\/p>\n<p><strong><br \/>Yo. <\/strong>Al observar estos tres puntos conectados con el texto y que surgen del mismo, m\u00e1s bien invertir\u00e9 su orden; y considere, primero, el manantial original y la fuente de las bendiciones mencionadas en el texto. Esto se establece en las palabras: \u201cPor la tierna misericordia de nuestro Dios\u201d. La misericordia es la fuente y manantial de todas nuestras bendiciones espirituales. Pero, \u00bfqu\u00e9 es la misericordia? Abarca varios detalles. <\/p>\n<p><strong>1.<\/strong> Abarca un sentimiento de piedad y compasi\u00f3n. Pero la piedad y la compasi\u00f3n no llenan toda la idea de misericordia; porque leemos que las \u201ctiernas misericordias de Dios est\u00e1n sobre todas sus obras\u201d (<span class='bible'>Sal 145:9<\/span>). As\u00ed, el Se\u00f1or, al perdonar a N\u00ednive, \u201cse acord\u00f3 incluso del ganado (<span class='bible'>Jon 4,11<\/span>). Y cuando hizo que las aguas del diluvio apaciguaran fue porque \u201cse acord\u00f3 de No\u00e9, y de todo ser viviente, y de todo el ganado que estaba con \u00e9l en el arca\u201d (<span class='biblia'>G\u00e9n 8:1<\/span>). Hay en el seno de su Creador misericordia y piedad incluso para la creaci\u00f3n bruta. Como lleno de misericordia, \u00c9l tambi\u00e9n \u201calivia al hu\u00e9rfano ya la viuda\u201d (<span class='bible'>Sal 146:9<\/span>); y \u201cama al extranjero, d\u00e1ndole comida y vestido\u201d (<span class='bible'>Dt 10:18<\/span>). <\/p>\n<p><strong>2.<\/strong> Debemos, por tanto, a\u00f1adir a la idea de piedad y compasi\u00f3n, otra marca, la del perd\u00f3n, para mostrar lo que es la misericordia extendida a la familia de Dios. Porque el pueblo del Se\u00f1or son pecadores; y como tales, siendo transgresores de la santa ley de Dios, necesitan perd\u00f3n y perd\u00f3n. <\/p>\n<p><strong>3.<\/strong> Pero para completar la descripci\u00f3n completa de la misericordia, debemos verla siempre como fluyendo a trav\u00e9s de la sangre y la obediencia de Emanuel. La misericordia no fue, como la creaci\u00f3n, una mera exhibici\u00f3n de un atributo de Jehov\u00e1. Si puedo usar la expresi\u00f3n, le cost\u00f3 un precio a la Deidad: \u201cPor precio hab\u00e9is sido comprados\u201d (<span class='bible'>1Co 6:20<\/span>). Pero hay una expresi\u00f3n en el texto que realza y arroja una dulce luz sobre esta misericordia. All\u00ed se llama tierna misericordia; literalmente, como est\u00e1 en el margen, \u201centra\u00f1as de misericordia\u201d. No mera misericordia; sino \u201ctierna misericordia\u201d. No misericordia fr\u00eda y desnuda; sino misericordia que brota de las entra\u00f1as de la compasi\u00f3n divina. Ahora nada m\u00e1s que la \u201ctierna misericordia\u201d podr\u00eda jam\u00e1s mirar con compasi\u00f3n a los hijos de los hombres, o sacar de las profundidades de la ca\u00edda a tales miserables arruinados. Pero para ver la misericordia en su verdadero car\u00e1cter, debemos ir al Calvario. <\/p>\n<p><strong><br \/>II. <\/strong>Pero pasamos a considerar esa declaraci\u00f3n solemne, ese hecho bendito contenido en las palabras: \u201cPor lo cual nos visit\u00f3 desde lo alto la aurora\u201d. Hay una conexi\u00f3n, observar\u00e1, entre la \u201ctierna misericordia de Dios\u201d y la visita de \u201cla aurora desde lo alto\u201d. La \u201ctierna misericordia de Dios\u201d es la fuente, y la \u201cvisita de la aurora desde lo alto\u201d es el arroyo. Esforc\u00e9monos, pues, si Dios nos lo permite, a desplegar la mente del Esp\u00edritu en las palabras. Primero. \u00bfQu\u00e9 significa la expresi\u00f3n \u201caurora\u201d? Por \u00abamanecer\u00bb se entiende el amanecer, el heraldo del sol naciente, el cambio de la oscuridad a la luz, el primer acercamiento de la ma\u00f1ana; en una palabra, la primavera del d\u00eda. Pero, \u00bfqu\u00e9 es esta \u201caurora\u201d espiritualmente? Es la insinuaci\u00f3n de la salida del Sol de Justicia. No es lo mismo que el Sol de Justicia; pero es el heraldo de Su acercamiento; los rayos que el sol naciente arroja sobre el mundo en la oscuridad, anunciando la venida de Jes\u00fas, \u201cel Rey en su hermosura\u201d. Esta expresi\u00f3n fue singularmente aplicable en boca de Zacar\u00edas. El Se\u00f1or de la vida y de la gloria no se hab\u00eda aparecido entonces; Todav\u00eda estaba en el vientre de la Virgen Mar\u00eda. Pero Su precursor, Juan, hab\u00eda aparecido como el precursor, el heraldo de Su llegada, y fue enviado para anunciar que el Sol de Justicia estaba por salir. Pero hay otro significado experimental relacionado con las palabras. \u201cLa aurora de lo alto\u201d no debe limitarse al acercamiento del Hijo de Dios en la carne; pero puede extenderse para significar la aparici\u00f3n del Hijo de Dios en el coraz\u00f3n. Ahora bien, \u201cla aurora de lo alto\u201d visita el alma con la primera insinuaci\u00f3n divina ca\u00edda en la conciencia respecto a la Persona, obra, amor y sangre del Hijo de Dios. Hasta que este amanecer brilla sobre el alma, en su mayor parte ignora el camino por el cual un pecador debe ser salvado. Pero la primera \u201caurora de lo alto\u201d que suele visitar el alma es vista por la fe preciosa de la gloriosa persona de Emanuel. Hasta que veamos con el ojo de la fe a la gloriosa Persona de \u201cEmanuel, Dios con nosotros\u201d, no habr\u00e1 amanecer en el coraz\u00f3n. Pero, al mirar a la gloriosa Persona del Hijo de Dios, captamos la visi\u00f3n de la fe de Su sangre expiatoria, y vemos que tiene una dignidad infinita. As\u00ed tambi\u00e9n con respecto a la gloriosa justicia de Emanuel. Pero qu\u00e9 dulzura hay en la expresi\u00f3n, \u201c\u00a1nos visit\u00f3!\u201d Lo que transmite Una idea contenida en \u00e9l es que es el acto de un amigo. Si tengo un amigo y lo visito, mi visita es una se\u00f1al de mi amistad y cari\u00f1o. Pero otra idea relacionada con la palabra \u00abvisita\u00bb es la de lo inesperado. \u00bfNo es as\u00ed a veces naturalmente? Tenemos una visita inesperada. Es posible que hayamos estado buscando a nuestro amigo para llamar; pero el tiempo pasa, y no se oye ning\u00fan golpe conocido en nuestra puerta. Nos preguntamos por qu\u00e9 nuestro amigo retrasa tanto su llegada. Pero quiz\u00e1s, cuando menos lo esperamos, aparece la forma de nuestro amigo. As\u00ed espiritualmente. Podemos estar anhelando y languideciendo, esperando y aguardando la visita de la aurora desde lo alto;\u201d pero no aparece; el Se\u00f1or demora Su venida; no hay indicios de Su aparici\u00f3n, ni mete Su mano por el agujero de la puerta, ni mira a trav\u00e9s de la celos\u00eda, ni vislumbra ni ve Su hermoso semblante, Pero quiz\u00e1s, cuando menos se espera y menos se anticipa; cuando la mente est\u00e1 tan hundida que apenas se atreve a esperar, tan encerrada en la incredulidad que apenas puede dar un suspiro, \u201cla aurora de lo alto\u201d visitar\u00e1 el alma, y ser\u00e1 tanto m\u00e1s preciosa por venir tan repentinamente e inesperadamente. <\/p>\n<p><strong><br \/>III. <\/strong>Pero esta \u201caurora de lo alto\u201d visita el alma para producir ciertos efectos. Dos de ellos se especifican en el texto. \u201cPara dar luz a los que moran en tinieblas y en sombra de muerte;\u201d esa es una: \u201cpara encaminar nuestros pies por el camino de la paz\u201d; ese es el otro <\/p>\n<p><strong>1.<\/strong> \u201cPara dar luz a los que habitan en tinieblas y en sombra de muerte.\u201d \u00bfEs esto lo que \u201cla aurora de lo alto\u201d nos visitar\u00e1? \u00bfNo debemos entonces saber algo de la experiencia aqu\u00ed descrita para ser bendecidos con la visita? Pero veamos las palabras un poco m\u00e1s de cerca. \u201cA los que moran en tinieblas.\u201d \u00bfDe qu\u00e9 se habla aqu\u00ed de la oscuridad? \u00bfEs simplemente lo que puedo llamar oscuridad moral? \u00bfOscuridad natural? No; no es la oscuridad de la falta de regeneraci\u00f3n; no es la oscuridad del pecado y la blasfemia; ni es la oscuridad de una mera profesi\u00f3n vac\u00eda. Estas cosas son en verdad tinieblas, densas tinieblas; pero aquellos que est\u00e1n as\u00ed cegados por el dios de este mundo nunca se sientan experimentalmente en la oscuridad. Son como los jud\u00edos de la antig\u00fcedad, que dec\u00edan: \u201cVemos; por tanto, su pecado permanece.\u201d \u201c\u00bfNosotros oscuros? nosotros ignorantes? despreciamos la idea. Tal es el lenguaje de la profesi\u00f3n vac\u00eda. Bat <\/p>\n<p>La propia familia vivificada y de coraz\u00f3n tierno del Se\u00f1or a menudo sabe dolorosamente lo que es sentarse en la oscuridad. Pero \u00bfde d\u00f3nde surge esta oscuridad? Por extra\u00f1o que parezca, surge de la luz. La oscuridad como la oscuridad nunca se ve. La oscuridad como oscuridad nunca se siente. Se necesita luz para ver la oscuridad; se requiere vida para sentir la oscuridad. Hay ni\u00f1os en Hungr\u00eda nacidos y criados en el fondo de una mina. \u00bfSabr\u00e1n alguna vez estos ni\u00f1os lo que es la oscuridad, como alguien que desciende de la plena luz del d\u00eda? Si no se les dijera que arriba hab\u00eda un sol, si no llegaran a sus o\u00eddos algunas noticias de la luz del d\u00eda, podr\u00edan vivir y morir ignorando que hab\u00eda un sol en los cielos. As\u00ed espiritualmente. El hombre, nacido y criado en las profundidades de la mina de la naturaleza, no sabe que es oscuro; mas cuando la luz Divina entra en su alma, eso le descubre sus tinieblas; porque es la luz que manifiesta todas las cosas; como dice el ap\u00f3stol, \u201cPero todas las cosas que son reprobadas son puestas de manifiesto por la luz; porque todo lo que manifiesta es luz\u201d (<span class='bible'>Ef 5:13<\/span>). As\u00ed, es la luz de la ense\u00f1anza de Dios en la conciencia del hombre la que le hace conocer sus tinieblas; y la vida divina en su alma lo hace sentir. Pero, \u00bfqu\u00e9 implica la oscuridad? La ausencia de todo lo que trae luz y paz al coraz\u00f3n. Pero hay una palabra en el texto que transmite mucho a mi mente, es decir, \u00absentarse en la oscuridad\u00bb. No se representan de pie; eso podr\u00eda implicar una mera transici\u00f3n moment\u00e1nea de la luz a la oscuridad. No se representan corriendo; eso podr\u00eda implicar que pronto saldr\u00edan de la oscuridad. No se representan acostados; eso podr\u00eda llevar a suponer que estaban satisfechos con su oscuridad. Pero se les representa como sentados en la oscuridad. Entonces seguro que no est\u00e1n muertos. Ni se sientan a gusto y en reposo; pero est\u00e1n en esa postura, porque no pueden moverse hacia atr\u00e1s o hacia adelante, ni volverse ni a la derecha ni a la izquierda. En antiguas medallas que fueron acu\u00f1adas cuando Jerusal\u00e9n fue llevada cautiva por los romanos, se la representa sentada en el suelo. Lo mismo se insin\u00faa en <span class='bible'>Sal 137:1-2<\/span>. \u201cJunto a los r\u00edos de Babilonia, all\u00ed nos sentamos; s\u00ed, lloramos cuando nos acordamos de Si\u00f3n. Colgamos nuestras arpas en los sauces en medio de ella\u201d. Sentarse era para los antiguos la postura del duelo. Job \u201cse sent\u00f3 entre las cenizas\u201d; (<span class='bible'>Job 2:8<\/span>); y sus amigos \u201cse sentaron con \u00e9l en tierra\u201d (vers\u00edculo 13). \u201cSus puertas,\u201d dice Isa\u00edas <span class='bible'>Is 3:26<\/span>), \u201cse lamentar\u00e1n y lamentar\u00e1n; y ella, desolada, se sentar\u00e1 en tierra.\u201d Sentarse implica tambi\u00e9n una permanencia en el estado; una espera, una observaci\u00f3n, un deseo, una espera de la luz por venir. Pero otra vez. Hay otra palabra a\u00f1adida, que arroja luz sobre el car\u00e1cter de aquellos que son visitados de vez en cuando con \u201cla aurora de lo alto\u201d. No solo se sientan en la oscuridad, sino tambi\u00e9n en la sombra de la muerte. Cu\u00e1n expresiva es esta palabra: \u201c\u00a1la sombra de la muerte!\u201d Hay varias ideas, en mi mente, conectadas con la palabra. Veremos, primero, la idea contenida en la expresi\u00f3n \u201cmuerte\u201d. La muerte con respecto a la familia de Dios tiene dos aspectos. Hay muerte experimental en sus corazones, es decir, muerte en sus marcos; y est\u00e1 la muerte temporal: la separaci\u00f3n del alma del cuerpo. Cada uno de estos tipos de muerte proyecta a veces una sombra sombr\u00eda sobre las almas del pueblo de Dios. La palabra es muy expresiva. No est\u00e1n sentados en la muerte: si estuvieran sentados all\u00ed, estar\u00edan muertos por completo; pero ellos est\u00e1n sentados en la sombra de la muerte. Observen, la muerte ha perdido su realidad para ellos; ahora s\u00f3lo puede arrojar una sombra, a menudo una sombra sombr\u00eda, sobre sus almas; pero no hay sustancia. La vivificaci\u00f3n del Esp\u00edritu de Dios en ellos ha destruido espiritualmente la sustancia de la muerte; y la muerte y resurrecci\u00f3n de Jes\u00fas ha destruido la sustancia de la muerte naturalmente. Sin embargo, aunque el monstruo sombr\u00edo, la muerte del alma, y ese horrible rey de los terrores, la muerte del cuerpo, han sido desarmados y destruidos por \u201cEmanuel, Dios con nosotros\u201d; sin embargo, cada uno de ellos proyecta a veces una sombra sombr\u00eda y oscura sobre las almas de los que temen a Dios. \u00bfNo se fatiga tu alma, pobre hija de Dios, de vez en cuando con esta muerte interior? \u00bfMuerte en la oraci\u00f3n, muerte en la lectura de la palabra, muerte en escuchar la verdad, muerte en los deseos por el Se\u00f1or, muerte para todo, santo, espiritual, celestial y divino? \u00bfNo sientes un letargo, un entumecimiento, una carnalidad, una mundanalidad, que parecen congelar a veces todos los deseos de tu alma? Hago. \u00a1Oh, c\u00f3mo este fr\u00edo y pegajoso monstruo de la muerte parece rodear con sus brazos entumecedores el alma de un hombre! He le\u00eddo acerca de un viajero que, mientras buscaba conchas en una roca del desierto, fue repentinamente atrapado en los brazos de un enorme p\u00f3lipo, un monstruo marino. La sensaci\u00f3n repugnante producida por este monstruo fr\u00edo y pegajoso que lo aprieta con sus enormes ventosas y lo atrae hacia sus fauces para devorarlo, lo describe como indecible, y solo fue salvado por el capit\u00e1n que acudi\u00f3 en su ayuda con un cuchillo. Puedo comparar, tal vez, nuestra frecuente muerte del alma abrazando cada deseo de nuestro coraz\u00f3n, con el apret\u00f3n de este pobre hombre en los brazos h\u00famedos del monstruo marino. \u00a1C\u00f3mo adormece y paraliza cada respiraci\u00f3n de nuestra alma hacia Dios! \u00a1C\u00f3mo toda oraci\u00f3n, todo deseo anhelante, todo afecto l\u00e1nguido, toda espiritualidad y celestialidad, toda adoraci\u00f3n s\u00f3lida, toda confianza filial, todos los frutos y gracias del Esp\u00edritu son arruinados y marchitos por la muerte que sentimos tan continuamente! <\/p>\n<p><strong>2.<\/strong> Pero hay otra palabra a\u00f1adida, otro resultado de la visita de \u201cla aurora desde lo alto\u201d: \u201cpara encaminar nuestros pies por el camino de la paz\u201d. \u00bfEl camino de la paz? \u00bfEso no lo comprende todo? \u00bfLos que temen a Dios quieren algo m\u00e1s que paz? \u00bfQu\u00e9 queremos? \u00bfEl camino de la guerra, de la enemistad, de la rebeli\u00f3n, de la inquietud? No. Queremos el camino de la paz. Pero, \u00bfqu\u00e9 implica la expresi\u00f3n? La paz implica dos cosas. Implica, primero, la reconciliaci\u00f3n de un estado de enemistad; y en segundo lugar, el goce sentido de esta reconciliaci\u00f3n en el coraz\u00f3n. Pero queremos guiarnos en el camino. Y cuando \u201cla aurora de lo alto\u201d visita el alma, encamina los pies por el camino. Hay algo muy dulce en la expresi\u00f3n. No conduce, no fuerza, pero abre una puerta y permite que el alma entre; descubre el camino, y da fe al alma para andar por \u00e9l. (<em>JC Philpot.<\/em>)<\/p>\n<\/p>\n<p><strong>La ternura de Dios<\/strong><\/p>\n<p>Dios no solo es en\u00e9rgico, pero tierno tambi\u00e9n en acci\u00f3n. \u00c9l es el Dios de las gotas de roc\u00edo, as\u00ed como el Dios de los truenos; el Dios de la tierna brizna de hierba, tanto como del roble del monte. Leemos de grandes m\u00e1quinas que pueden triturar barras de hierro y, sin embargo, pueden tocar tan suavemente que no rompen la c\u00e1scara del huevo m\u00e1s peque\u00f1o; como sucede con ellos, as\u00ed sucede con la mano del Alt\u00edsimo: \u00c9l puede aplastar un mundo y, sin embargo, vendar una herida. Y gran necesidad tenemos de ternura en nuestro bajo estado; una cosa peque\u00f1a nos aplastar\u00eda; tenemos almas tan magulladas y d\u00e9biles que, a menos que tengamos a Alguien que nos trate con ternura, pronto seremos destruidos. Hay muchas enfermedades del alma que s\u00f3lo una mano tierna puede curar; as\u00ed como hay muchos estados del cuerpo que necesitan atenci\u00f3n tierna y paciente, y que de otro modo no pueden ser tratados con \u00e9xito, ni siquiera con mucha habilidad. Esta ternura la vemos continuamente en acci\u00f3n, en los servicios de la mujer en la vida ordinaria. Su voz tiene notas m\u00e1s dulces y suaves que las que se pueden destilar de cualquier instrumento musical; su mano tiene un toque m\u00e1s delicado y fino que nunca el soplo de cualquier brisa de verano; es a ella a quien el hombre lleva las historias de sus penas; es ella la que tiene que calmar su cabeza pesada y dolorida; as\u00ed como cree que puede prescindir de ella, en las escenas m\u00e1s emocionantes de la vida, descubre que no es independiente cuando llega el momento del sufrimiento y la pena. \u00bfY qu\u00e9 hace a la mujer capaz de soportar la pesada carga que se le echa encima? \u00bfC\u00f3mo llega la hiedra a poder sostener la encina en torno a la cual sol\u00eda colgarse, adorn\u00e1ndola, mientras pose\u00eda su se\u00f1or\u00edo y fuerza? Todo lo hace en poder de la ternura de su naturaleza; \u00e1spera y tosca ser\u00eda la vida si se retirara tal ternura. Pero pasa a las cosas divinas: de la mujer, al que naci\u00f3 de mujer, \u00bfy qu\u00e9 encontramos en \u00e9l sino ternura de acci\u00f3n? Esa ternura que en cualquiera de los hombres no es m\u00e1s que una chispa del fuego, es perfecta en Su seno; su plenitud est\u00e1 all\u00ed; y continuamente se les muestra. (<em>PB Power, MA<\/em>)<\/p>\n<\/p>\n<p><strong>Explicaci\u00f3n de las im\u00e1genes<\/strong><\/p>\n<p>Una caravana pierde el camino , y se pierde en el desierto; los desdichados peregrinos, sorprendidos por la noche, est\u00e1n sentados en medio de esta espantosa oscuridad, esperando la muerte. De repente, una estrella brillante se eleva en el horizonte e ilumina la llanura: los viajeros, tomando valor ante esta vista, se levantan y, a la luz de esta estrella, encuentran el camino que los lleva al final de su viaje. (<em>F. Godet, DD<\/em>)<\/p>\n<\/p>\n<p><strong>La noche de la humanidad<\/strong><\/p>\n<p>Puede parecer extra\u00f1o que debemos llamar a la condici\u00f3n de nuestra raza antes de la aparici\u00f3n de Cristo <em>noche&#8211;tinieblas<\/em>y sombra de muerte. Pero, \u00bfcu\u00e1l es el significado de que sea de noche? Es la noche donde falta la luz que ilumina nuestro camino, en cuyo brillo somos capaces de distinguir y comprender el valor de las cosas que nos rodean; esa luz que nos muestra d\u00f3nde hay caminos por recorrer, los fines que debemos perseguir y los medios por los cuales podemos alcanzarlos. Donde hay tal certeza de conocimiento y trabajo hay d\u00eda; donde falta eso, la luz s\u00f3lo puede ser tenue; incluso con los ojos abiertos, todo conocimiento es solo fantas\u00eda, todo trabajo solo es tantear en la oscuridad. All\u00ed ninguna vida puede dar fruto; puede estar lleno de toda clase de sue\u00f1os hermosos, pero s\u00f3lo de sue\u00f1os; pero al sue\u00f1o le sigue un despertar con un dolor m\u00e1s amargo cuanto m\u00e1s hermosos eran los sue\u00f1os. \u00bfEra realmente de noche sobre la tierra, antes de que viniera el Salvador? S\u00ed, no nos atrevemos a juzgar de otro modo: era de noche. De hecho, los hombres hab\u00edan intentado hacer luz artificial, pero en realidad no iluminaba. Faltaba el foco en el que al fin deb\u00edan converger todos los rayos para mostrarse como verdad. Era realmente de noche, una noche fr\u00eda, oscura y desagradable. (<em>R. Rothe, DD<\/em>)<\/p>\n<\/p>\n<p><strong>La aurora desde lo alto: Cristo como el amanecer<\/strong><\/p>\n<p>Esta espl\u00e9ndida figura ret\u00f3rica se toma desde el amanecer de la ma\u00f1ana en la noche. Y para comprender cabalmente la fuerza de la ret\u00f3rica, debemos tener en cuenta uno de los fen\u00f3menos naturales de aquellas regiones orientales. Tan pura es la atm\u00f3sfera all\u00ed, tan al sur, que las nubes en el cielo no son habituales salvo en la estaci\u00f3n lluviosa. Realmente parece que no hay nada que impida la puesta del sol, nada que se interponga en el camino de su salida de nuevo. Cuando se pone, va abruptamente detr\u00e1s de la colina adyacente; cuando se levanta, lo hace sin previo aviso, y en un instante est\u00e1 completamente listo para su trabajo diario; es decir, no hay crep\u00fasculo, como lo describimos, en esas latitudes. En el instante en que el d\u00eda llega a su final natural, el sol parece deslizarse por el cielo sin despedirse. As\u00ed cuando comienza el amanecer. Cuando el monarca de ayer se despide a s\u00ed mismo, y es hora de que el de hoy lo suceda, all\u00ed est\u00e1 \u00e9l, sin anunciarse y serenamente sin prisas, sentado tranquilamente en su brillante pabell\u00f3n de claro, el Sr. Zacharias se apodera de esta asombrosa figura y la convierte en cuenta. Durante cuatro siglos hab\u00eda estado oscuro, oscuro por el pecado, la ignorancia, la opresi\u00f3n, y ahora, en un emocionante instante de revelaci\u00f3n, el Sol de Justicia se hab\u00eda levantado con sanidad en Sus alas. Con raz\u00f3n su coraz\u00f3n estaba lleno; \u00a1No es de extra\u00f1ar que su mutismo cediera y su voz alegre entonara tal canci\u00f3n! Sigamos cantando, y cantando siempre sobre la aurora de lo alto que nos ha visitado. La luz del evangelio es un destello de la luz del cielo. Oh, \u00bfcu\u00e1l ser\u00e1 el pleno esplendor del mediod\u00eda dentro de poco? Cuando los galos probaron el vino de Italia, comenzaron a preguntar d\u00f3nde crec\u00edan las uvas, y nunca se callaron hasta que llegaron all\u00ed. (<em>CSRobinson, DD<\/em>)<\/p>\n<\/p>\n<p><strong>El sol un emblema de Cristo<\/strong><\/p>\n<p>El sol es el fuente de luz a este mundo inferior. D\u00eda tras d\u00eda se eleva sobre nosotros con sus rayos de alegr\u00eda, y con el retorno de la luz se conecta el sentido de poder vivificador en nosotros mismos; salud y alegr\u00eda vigorizadas; aplicaci\u00f3n renovada y dispuesta a los deberes asignados. Dios mismo lo ha hecho el gobernante sobre el d\u00eda. Toda la naturaleza parece poseer su influencia. Las flores que caen o cierran sus hojas durante la noche, se expanden nuevamente cuando sale el sol. Los vistosos colores con que ahora se iluminan las nubes que antes eran oscuras, anuncian el regreso del rey ausente; y las nubes mismas se dispersan a su llegada. Las criaturas repugnantes o salvajes que aman la oscuridad ahora \u201cll\u00e9venlas juntas, y acu\u00e9stense en sus guaridas. El hombre sale a su trabajo y a su labor hasta la tarde.\u201d Cristo es para el mundo moral lo que el sol es para el mundo natural; la fuente de vida, salud y movimiento. \u00c9l es el \u201cSol de justicia\u201d, porque el manto de justicia en el que Su pueblo \u201cbrilla\u201d es la luz de \u00c9l que ellos reflejan; y por eso se dice que Su Iglesia est\u00e1 \u201cvestida del sol\u201d. Y la justicia interior tambi\u00e9n, en la que son creados de nuevo a imagen de Dios, se deriva de Su presencia iluminadora en sus corazones. Y se levanta sobre nosotros \u201ccon sanidad en sus alas\u201d, porque trae consigo, d\u00eda a d\u00eda, salud espiritual a los enfermos del alma, consuelo a los que lloran, descanso a los cansados y agobiados. El mundo hab\u00eda permanecido durante mucho tiempo en tinieblas y sombras de muerte, esperando con ferviente expectativa las primeras se\u00f1ales de la \u201caurora de lo alto\u201d, incluso como viajeros en una noche sin estrellas, o como aquellos que velan en soledad y cansancio, esperan con ansiedad. ansioso anhelo por el estallido de la ma\u00f1ana. Finalmente, el Sol de Justicia se levant\u00f3, cuando Aquel que estaba con el Padre desde toda la eternidad naci\u00f3 en Bel\u00e9n, y tom\u00f3 nuestra naturaleza sobre \u00c9l. Y as\u00ed como la luz del sol de la ma\u00f1ana viaja con una velocidad inconcebible a los rincones m\u00e1s remotos de la tierra y penetra en los rincones m\u00e1s oscuros, as\u00ed la luz del Sol de Justicia penetr\u00f3 en los lugares oscuros de la tierra. Disip\u00f3 las nieblas de la ignorancia y el pecado, e hizo brotar del jard\u00edn de la Iglesia de Dios aquellos frutos y flores que de otro modo nunca habr\u00eda podido dar. Su poder para sanar y consolar tampoco disminuye con el transcurso de los a\u00f1os. As\u00ed como el sol en los cielos tiene el mismo poder vivificador y animador sobre el mundo material, como el d\u00eda en que Dios lo form\u00f3 por primera vez y lo coloc\u00f3 en los cielos; as\u00ed los rayos del Sol de Justicia tienen la misma eficacia para sanar la conciencia herida y consolar el alma afligida, como cuando brillaron por primera vez sobre Sus humildes seguidores. (<em>Bishop Trower.<\/em>)<\/p>\n<\/p>\n<p><strong>Seguridad a la luz del d\u00eda<\/strong><\/p>\n<p>Una banda de fugitivos estaban cruzando un desierto del este. La noche era oscura, pero decidieron seguir adelante. Pronto se perdieron y tuvieron que pasar la noche con ansiedad y miedo. Parec\u00eda que la noche nunca pasar\u00eda. Pero casi de repente sali\u00f3 el sol, trayendo la luz del d\u00eda y mostrando el camino de la seguridad. Ninguno de ellos olvid\u00f3 nunca ese amanecer. De modo que para nosotros, en nuestro andar errante, ha surgido la Aurora, indic\u00e1ndonos el camino de la seguridad. Ilustrad con el caso de un hombre en un bote abierto, o de un viajero que atraviesa un p\u00e1ramo de noche, y no est\u00e1 seguro de su camino. Una nube pasa del cielo y se ve la estrella polar. Entonces conoce el camino de la seguridad. (<em>Sunday School Times.<\/em>)<\/p>\n<\/p>\n<p><strong>Cristo nuestra Aurora<\/strong><\/p>\n<p>Cu\u00e1n pertinente es esa pregunta de el Todopoderoso como se rompe del torbellino, \u00ab\u00bfHas mandado t\u00fa a la ma\u00f1ana desde tus d\u00edas, y has hecho que la aurora conozca su lugar?\u00bb Aquel que ha ajustado los movimientos de todos los orbes de luz, trae el resplandor del d\u00eda reci\u00e9n nacido para alegrar a los que esperan la oscuridad que se retira. Cristo, nuestra aurora, irrumpi\u00f3 sobre el mundo en el per\u00edodo prof\u00e9tico del arreglo divino. Nuestro amanecer espiritual, tan esperado, vino para el destierro del pecado y la introducci\u00f3n de toda justicia. Cristo es la \u00fanica aurora de luz para el alma oscurecida. La creaci\u00f3n visible, que transmite mediante s\u00edmbolos y manifestaciones materiales los pensamientos de Dios, puede traer descanso a un alma en la que hay una lucha constante entre la conciencia y la pasi\u00f3n. Los aspectos pol\u00edticos de la sociedad dar\u00e1n poca esperanza; el \u00e9xito en las medidas de reforma parecer\u00e1 dif\u00edcilmente lo suficientemente valioso para compensar su desembolso de esfuerzo, la ciencia, en todos sus departamentos, aparecer\u00e1 como un laberinto desconcertante, hasta que nuestra aurora, conociendo su lugar en los consejos de la Sabidur\u00eda Infinita, se vea por encima de ellos. todo, anunciando los esplendores de la redenci\u00f3n. El agnosticismo ser\u00eda la triste herencia de todos, solo llev\u00e1ndonos a saber que no podemos saber; que los secretos del universo jam\u00e1s podr\u00e1n ser explicados; que nosotros mismos no ser\u00edamos m\u00e1s que perplejidades y contradicciones, si nuestra aurora, que brilla por encima de toda ciencia, de todas las necesidades e industrias humanas, de toda ignorancia, voluntad y orgullo humanos, no pudiera ser vista por la fe, verificada por los hechos y confiada por experiencia. (<em>John Waugh.<\/em>)<\/p>\n<\/p>\n<p><strong>La tierna misericordia de Dios<\/strong><\/p>\n<p>Mi proclamaci\u00f3n te certifica, oh coraz\u00f3n tembloroso, que esta misericordia es tierna misericordia. Tus huesos est\u00e1n rotos esta noche, tu coraz\u00f3n est\u00e1 herido, tu esp\u00edritu est\u00e1 seco y est\u00e1s a punto de desesperarte; pero yo te digo que Dios tiene tierna misericordia para los que eres como t\u00fa. Mientras estaba sentado en el hospital, ayer, y vi los muchos casos de extremidades mutiladas y heridas que chorreaban, no pod\u00eda sino pensar cu\u00e1n tiernas deber\u00edan ser las enfermeras y cu\u00e1n suave deber\u00eda ser el dedo del cirujano cuando coloca el hueso roto o venda. el dolor Sin duda hay algunas personas que tienen ligaduras de hierro y corazones duros, y as\u00ed, mientras est\u00e1n deshuesando o vendando heridas, lo hacen con rudeza y causan mucho dolor al paciente. Pero, oh pecador, en esto se manifiesta la tierna misericordia de nuestro Dios, que, como una aurora desde lo alto, nos ha visitado; \u201cLa ca\u00f1a cascada no quebrar\u00e1, ni apagar\u00e1 el pabilo que humea\u201d. \u00c9l nos corona con bondades amorosas y tiernas misericordias; \u00c9l venda a los quebrantados de coraz\u00f3n, y cura todas sus heridas. Como una madre consuela a sus hijos, as\u00ed consuela el Se\u00f1or a su pueblo, y como un padre se compadece de sus hijos, as\u00ed se compadece el Se\u00f1or de los que le temen. Mi Se\u00f1or es tan misericordioso en la manera de Su misericordia como en el asunto de ella. \u00a1Gloria sea a Su nombre! Oh pecador, ven al dulce Jes\u00fas y vive. (<em>CH Spurgeon.<\/em>)<\/p>\n<\/p>\n<p><strong>Sunshine<\/strong><\/p>\n<p>Creemos que toda la gente de nuestra ciudad deber\u00eda de alguna manera obtener cada semana unas cuantas horas bajo el sol claro y puro mientras el Se\u00f1or lo derrama desde los cielos. El s\u00e1bado pasado fue un d\u00eda de deberes inusuales, y el lunes por la ma\u00f1ana, con el trabajo ruidoso a nuestro alrededor, dijimos que nuestra llamada de esta ma\u00f1ana es a los campos. Hicimos una carrera audaz y, a una velocidad que nadie se atrevi\u00f3 a detener, pronto estuvimos m\u00e1s all\u00e1 de los l\u00edmites de la ciudad. Mientras pas\u00e1bamos a toda prisa, un hermano cl\u00e9rigo grit\u00f3: \u00ab\u00bfAd\u00f3nde?\u00bb. Respondimos: \u201c\u00a1En busca de la luz del sol!\u201d \u00bfY hubo alguna vez un lujo m\u00e1s brillante? La taza de la ma\u00f1ana hab\u00eda sido lavada por una ducha; las hojas, convertidas en oto\u00f1o, estremec\u00edan su ardiente esplendor a trav\u00e9s del camino; el murmullo de la ciudad se hizo m\u00e1s d\u00e9bil y encontramos lo que busc\u00e1bamos flotando en el lago, enredado en los arbustos, ondulando entre la hierba verde, goteando del cielo: la luz del sol. \u00a1Glorioso sol! Con ella nos llenamos los p\u00e1rpados, la boca, las manos. Abrimos toda nuestra capacidad f\u00edsica para acogerlo. Sacamos nuestra alma y la saturamos en la luz exuberante. Lo absorbimos por todos nuestros poros y lo enrollamos alrededor de nuestros nervios; y despu\u00e9s de que no pudimos contener m\u00e1s adentro, levantamos la cara y la mantuvimos tan inclinada que nos cubri\u00f3: la luz del sol. \u00bfQu\u00e9 hacen los ciegos sin verlo? \u00bfC\u00f3mo pueden los empleados de la f\u00e1brica seguir adelante sin sentirlo? Que todo el ministerio del lunes por la ma\u00f1ana se convierta en eso. Para la noche del s\u00e1bado siguiente madurar\u00e1 toda la acidez de los sermones. El mundo quiere m\u00e1s sol en su disposici\u00f3n, en sus negocios, en sus obras de caridad, en su teolog\u00eda. Por diez mil de los dolores, molestias e irritaciones de hombres y mujeres, recomendamos la luz del sol. Calma mejor que la morfina. Estimula m\u00e1s que el champ\u00e1n. Es el mejor emplasto para una herida. El buen samaritano derram\u00f3 en la herida del viajero ca\u00eddo m\u00e1s de esto que de vino y aceite. Florence Nightingale lo us\u00f3 en los campos de batalla de Crimea. Ll\u00e9vala a todos los callejones, a bordo de todos los barcos, junto a todos los lechos de enfermos. No una redoma llena, ni una copa llena, ni una garrafa llena, sino un alma llena. Es bueno para el bazo, para las dolencias del h\u00edgado, para la neuralgia, para el reumatismo, para la mala fortuna, para la melancol\u00eda. Sospechamos que el cielo mismo es solo m\u00e1s sol. (<em>Dr. Talmage.<\/em>)<\/p>\n<\/p>\n<p><strong>Filosof\u00eda y cristianismo<\/strong><\/p>\n<p>Filosof\u00eda, en la noche de El paganismo, era como la luci\u00e9rnaga de los tr\u00f3picos haci\u00e9ndose visible, pero sin irradiar la oscuridad. Pero el cristianismo, al revelar el Sol de Justicia, derrama m\u00e1s que la plena luz del sol de esos tr\u00f3picos sobre todo lo que necesitamos ver, ya sea por el tiempo o por la eternidad. (<em>Coleridge.<\/em>)<\/p>\n<\/p>\n<p><strong>Contemplando el sol<\/strong><\/p>\n<p>He le\u00eddo que cerca del Polo Norte , la noche que dura meses y meses, cuando la gente espera que el d\u00eda est\u00e9 por amanecer, unos mensajeros suben al punto m\u00e1s alto para velar; y cuando ven la primera raya del d\u00eda, se ponen su ropa m\u00e1s brillante posible, se abrazan y gritan: \u201c\u00a1Mira el sol!\u201d y el clamor recorre toda la tierra: \u201c\u00a1He aqu\u00ed el sol!\u201d Algunos de ustedes han estado caminando penosamente en la oscuridad del pecado. Ha sido una noche larga y fatigosa para tu alma; pero ahora clamo: \u201c\u00a1He aqu\u00ed el Sol de Justicia que se levanta con sanidad en Sus alas!\u201d o, para citar el cap\u00edtulo que le\u00ed al principio, \u201cLa aurora nos visit\u00f3 desde lo alto para dar luz a los que est\u00e1n en tinieblas\u201d. \u00a1He aqu\u00ed el sol! \u00a1He aqu\u00ed el sol! \u00a1Quiera Dios que todos los ojos ciegos puedan verlo ahora! (<em>Dr. Talmage.<\/em>)<\/p>\n<\/p>\n<p><strong>Una luz en un lugar oscuro<\/strong><\/p>\n<p>Un barco de vapor estaba una vez transportando una carga de pasajeros por uno de los r\u00edos occidentales. Era una noche muy oscura. Las aguas estaban oscuras, el suelo era negro y no se ve\u00eda una estrella. El aire estaba lleno de aguanieve y neblina, y en conjunto formaba una noche en la que \u201cse pod\u00eda sentir la oscuridad\u201d. El barco de vapor se hab\u00eda topado con un obst\u00e1culo, estaba goteando muy r\u00e1pido y comenzaba a hundirse. El capit\u00e1n la llev\u00f3 inmediatamente a tierra y la amarr\u00f3 a la orilla. Se empuj\u00f3 la tabla y se pidi\u00f3 a todos que desembarcaran lo m\u00e1s r\u00e1pido posible. Se pens\u00f3 que si todos pudieran aligerar el bote, podr\u00edan salvarlo, mientras que si todos permanec\u00edan a bordo, pronto se hundir\u00edan todos juntos. Pero estaba tan oscuro que los pasajeros no pod\u00edan ver ni el tabl\u00f3n ni la orilla. La aguanieve ca\u00eda espesa y lo cubr\u00eda todo con hielo. Las aguas fr\u00edas y salvajes del r\u00edo corr\u00edan por debajo y no ofrec\u00edan una recepci\u00f3n muy c\u00e1lida a cualquiera que pudiera caerse. As\u00ed que la compa\u00f1\u00eda se qued\u00f3 quieta, sin atreverse a moverse. Al igual que Pablo, optaron por \u201cquedarse en el barco\u201d. Parec\u00edan sentir que era mejor quedarse y compartir el destino del barco que zarpar: no sab\u00edan d\u00f3nde; \u201cmejor soportar los males que ten\u00edan, que volar a aquellos de los que no conoc\u00edan\u201d. El capit\u00e1n estaba tan perplejo como la gente. Animarlos a que se apresuren puede producir p\u00e1nico y hacer que se apresuren y se empujen unos a otros al r\u00edo. Sin embargo, sab\u00eda que no pod\u00edan permanecer mucho tiempo en cubierta sin peligro. Pero estuvo a la altura de la emergencia. Llam\u00e1ndolos desde la cubierta superior, les dijo que se callaran y esperaran, y que los llevar\u00eda a salvo a tierra. Luego salt\u00f3 a la orilla con algunos de sus hombres y, tomando una canasta de carb\u00f3n de brea y coloc\u00e1ndola en un lugar adecuado, encendi\u00f3 una cerilla y la encendi\u00f3. En unos momentos brill\u00f3 brillante y claro, y, en palabras de John Hay. <\/p>\n<p>\u00abHizo un agujero en la noche\u00bb.<\/p>\n<p>Toda la ladera, la orilla, el barco y el r\u00edo brillaban con el brillo. Era una escena salvaje pero hermosa: oscuridad por todas partes menos all\u00ed donde necesitaban luz. Toda emoci\u00f3n y temor ces\u00f3, y la gente pas\u00f3 tranquila y segura uno por uno sobre el tabl\u00f3n hacia la orilla s\u00f3lida. Nunca la luz pareci\u00f3 tan agradecida y tan hermosa como cuando se dispar\u00f3 all\u00e1 arriba en ese lugar oscuro. La expresi\u00f3n, \u00abluz en un lugar oscuro\u00bb, gan\u00f3 un nuevo significado para todos los que sintieron su bendici\u00f3n en esa noche oscura y peligrosa. La Biblia habla de Cristo como una \u201cluz para los que moran en tinieblas\u201d, y Su verdad como una \u201cluz que alumbra en un lugar oscuro\u201d. Hay muchos lugares oscuros en nuestra vida, pero no hay lugar m\u00e1s oscuro que nuestros pecados. Todo el mundo ha estado preocupado por esto, y nadie nunca supo qu\u00e9 hacer con ellos. Mucha gente no piensa nada acerca de ellos. As\u00ed que esos hombres en ese barco de vapor podr\u00edan haberse acostado y ido a dormir. Podr\u00edan decir: \u00abNo podemos ver el camino a seguir, y es mejor que nos relajemos\u00bb. As\u00ed que los hombres a menudo olvidan sus pecados y se sienten tranquilos con ellos. Pero cada vez que piensan en ellos, est\u00e1n preocupados y no saben qu\u00e9 hacer con ellos. No saben c\u00f3mo deshacerse de ellos, y los hombres m\u00e1s sabios han estado tan a oscuras como los m\u00e1s ignorantes. Este siempre ha sido un lugar muy oscuro. El r\u00edo es muy salvaje, la orilla no se ve y el camino hacia \u00e9l es desconocido. Mucha gente se ha parado aqu\u00ed, como esos hombres en el barco de vapor, esperando la luz y sin saber qu\u00e9 hacer. Cristo deja que la luz brille justo en este lugar oscuro. Muestra c\u00f3mo los hombres pueden deshacerse de sus pecados y ser perdonados. \u00c9l nos muestra el camino. \u00c9l es el camino. El r\u00edo es tan profundo y la orilla est\u00e1 tan alejada como antes, pero podemos verlo todo y encontrar el camino hacia un lugar seguro y s\u00f3lido. Cuando llegamos a ver lo terrible que es estar en la oscuridad y no saber qu\u00e9 hacer, entonces podemos saber lo hermoso y agradecido que es tener una \u00abluz que brilla en un lugar oscuro\u00bb. (<em>R. Cordley, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Nos damos cuenta entonces<\/strong><\/p>\n<p><strong><br \/>Yo. <\/strong>EL ORIGEN DE NUESTRA REDENCI\u00d3N: \u201cla entra\u00f1able misericordia de nuestro Dios\u201d. Pero si bien es cierto que todos los atributos de Dios estuvieron involucrados en la planificaci\u00f3n y ejecuci\u00f3n de la obra de nuestra redenci\u00f3n, debe observarse que la misericordia de Dios aparece con mucho como la m\u00e1s conspicua. \u00bfCu\u00e1l es su naturaleza? La misericordia es la piedad del coraz\u00f3n; que creo ser\u00e1 admitida por todos como una interpretaci\u00f3n justa y correcta de la palabra. \u00bfNo hay suficiente miseria por parte del hombre para excitar la misericordia y la compasi\u00f3n de Dios? Preguntamos, nuevamente, \u00bfhasta qu\u00e9 punto se ejerci\u00f3 la misericordia de Dios en la obra de la redenci\u00f3n humana? Se extiende hasta los l\u00edmites m\u00e1s extremos de la familia humana. La misericordia entonces, origin\u00f3 el plan de salvaci\u00f3n humana. Consideremos&#8211;<\/p>\n<p><strong><br \/>II. <\/strong>SU PROGRESO. Este plan no se desarroll\u00f3 todo de una vez; fue comunicado bajo diferentes dispensaciones y por grados progresivos, a medida que las mentes de los hombres se preparaban para recibirlo. Ha llegado la aurora de lo alto, la gran luz, la gran luminaria de nuestro mundo. Ahora bien, la luz es notable por el poder de la comunicaci\u00f3n: todo, ya sabes, est\u00e1 te\u00f1ido e irradiado por la luz del sol. La luz que emite el sol, como el gran medio de luz, se difunde por todas partes; y aqu\u00ed tenemos una justa representaci\u00f3n del poder de comunicaci\u00f3n que posee Jesucristo, en referencia al conocimiento que es esencial para la felicidad del hombre; porque dondequiera que El est\u00e1, hay luz; donde est\u00e1 su palabra, all\u00ed est\u00e1 la verdad; y se dice de esta palabra suya, \u201csu entrada alumbra\u201d. La luz, nuevamente, es notable por la rapidez de su vuelo. Muestre un cirio resplandeciente en la cima de una monta\u00f1a, y alcanza el ojo, colocado a cualquier distancia dada, en un momento. Y aqu\u00ed podemos recordar la rapidez del vuelo de la misericordia, para encontrar la miseria del hombre. Y podemos recordar aqu\u00ed, tambi\u00e9n, otro hecho importante, relacionado con esta parte de nuestro tema: la disposici\u00f3n que siempre hay, de parte del Salvador, para enfrentar el caso de un pobre pecador arrepentido, o un creyente afligido. . Pero nuevamente, la luz es notable por su pureza y su agradecida influencia. La influencia de la luz es la m\u00e1s agradable, no obstante la velocidad con que se mueve, para el m\u00e1s delicado de todos nuestros \u00f3rganos, el ojo. Es una cosa agradable contemplar el sol. Cuando esta luz os condujo al Cordero de Dios, y cuando, en el ejercicio de vuestra fe, os aprovechasteis de los beneficios resultantes de sus actos redentores, \u00a1cu\u00e1n agradecida fue su influencia! Comunic\u00f3 luz a vuestro entendimiento, y paz y gozo inefables a vuestros corazones. Pero el texto nos dice que vino \u201cde lo alto\u201d. Bueno, entonces, Jesucristo mismo debe haber existido antes de venir a este mundo; y si existi\u00f3 antes de venir al mundo, debe haber existido como Dios Todopoderoso. Ahora, que este fue el caso, est\u00e1 muy claro, de varias partes de la Escritura. \u201cEn el principio era el Verbo, y el Verbo estaba con Dios, y el Verbo era Dios: el mismo estaba en el principio con Dios. Todas las cosas fueron hechas por \u00c9l, y sin \u00c9l nada de lo que ha sido hecho, fue hecho.\u201d Pero, en el texto, leemos de \u00c9l con respecto a Su naturaleza humana. La aurora de lo alto asumi\u00f3 la naturaleza del hombre de abajo, y en esa naturaleza se convirti\u00f3 en el sustituto del sufrimiento del hombre. \u00c9l vino de lo alto\u2014\u00c9l nos visit\u00f3 con este prop\u00f3sito. Dije antes, y ahora debo recurrir a ello, que la luz a la que alude nuestro texto, fue gradual en su comunicaci\u00f3n. Hubo un rayo de \u00e9l para brillar sobre los patriarcas, un rayo m\u00e1s brillante a\u00fan brillaba sobre las mentes de los profetas; pero fue cuando los tipos recibieron su cumplimiento en las llanuras de Bel\u00e9n, que las palabras de este texto fueron literalmente verificadas. \u201cLa aurora nos visit\u00f3 desde lo alto\u201d, viniendo a este mundo nuestro para difundir Su luz y vida, y libertad, y salvaci\u00f3n, de un extremo a otro de la tierra. <\/p>\n<p><strong><br \/>III. <\/strong>EL GRAN DISE\u00d1O DE ESTE EVENTO INCRE\u00cdBLE: \u201cPara dar luz\u201d, dice el escritor inspirado, \u00bfa qui\u00e9n? \u201ca los que habitan en tinieblas y en sombra de muerte\u201d. Por esta oscuridad debemos entender la ignorancia que es com\u00fan al hombre; y por muerte hemos de entender aquella muerte moral que reina en la mente y el esp\u00edritu de los hombres, juntamente con aquella muerte eterna, a la cual, como pecadores, estamos expuestos. Ahora bien, donde hay una sombra, la sustancia no puede estar lejos. No necesitamos entrar aqu\u00ed en el estado del mundo pagano, en el momento del advenimiento de nuestro Salvador, porque debe ser generalmente conocido por todos los que ahora me escuchan: era en verdad un estado de oscuridad y muerte; ni en el estado del pueblo jud\u00edo, porque tambi\u00e9n era un estado de ignorancia. Pero, \u00bfsobre qu\u00e9 temas ilumina a los hombres? En primer lugar, tocar el ser y las perfecciones de Dios. Si examinas los registros de los m\u00e1s sabios y mejores de los fil\u00f3sofos paganos, ya sea de Egipto, Grecia o Roma, no encuentras ninguna revelaci\u00f3n clara y distinta que exista con respecto a Dios. A continuaci\u00f3n, vino a iluminar a los hombres con respecto a su propio estado y condici\u00f3n moral. . Ahora, que no todo est\u00e1 bien con el hombre debe ser obvio. \u00bfEs el hombre feliz? \u00c9l no es\u2014\u00e9l es tan miserable como malvado. Bueno, entonces, debe haber algo mal; algo debe haberle sucedido a nuestro mundo. Demos, pues, gracias a Dios que, en medio de las tinieblas y la miseria, tenemos la gran luz brillando sobre nosotros, dici\u00e9ndonos c\u00f3mo entr\u00f3 el pecado en nuestro mundo, a qu\u00e9 fin conducir\u00eda y hasta qu\u00e9 punto prevalecer\u00eda. , si no fu\u00e9ramos librados de su poder. Pero vino a dar luz sobre otro tema: vino a dar la luz de la salvaci\u00f3n. Si simplemente nos hubiera descubierto nuestra enfermedad y nos hubiera dejado perecer en ella, habr\u00edamos sido peores, en lugar de ser mejorados, por nuestro conocimiento. Pero venimos, hermanos, a la luz; y aqu\u00ed encontramos la misericordia y la verdad reunidas, y la justicia y la paz abraz\u00e1ndose: la verdad inflexible como una roca, y la misericordia, tierna como las l\u00e1grimas de un padre, anhel\u00e1ndote con infinita compasi\u00f3n. Vino a dar luz sobre otro tema, a saber, la regla de nuestro deber. \u00bfCu\u00e1l, entonces, debe ser la regla? T\u00f3malo, primero, en referencia a Dios, nos ordena amarlo supremamente; t\u00f3menlo en referencia al hombre, y nos ordena tanto: \u201cTodo lo que quer\u00e1is que los hombres hagan con vosotros, as\u00ed tambi\u00e9n haced vosotros con ellos; porque esta es la ley y los profetas.\u201d Pero Cristo vino a dar luz sobre otro tema: un estado futuro. Pero Jesucristo vino a dar m\u00e1s que luz: vino a dar paz, \u00abpara encaminar nuestros pies por el camino de la paz\u00bb. Aqu\u00ed s\u00f3lo puedo mencionar detalles. Procurar la paz fue el gran objetivo del advenimiento de nuestro Salvador. Deb\u00eda ser llamado \u201cel reparador de portillos, el restaurador de calzadas para habitar\u201d. Y as\u00ed como vino a procurar la paz, tambi\u00e9n vino a aplicarla. F\u00e1cilmente percibir\u00e1 una diferencia entre la paz obtenida y la paz aplicada. \u00c9l vino a dar paz\u2014\u00c9l vino tambi\u00e9n a mantenerla en los corazones de Su pueblo, haci\u00e9ndola crecer y aumentar m\u00e1s y m\u00e1s, hasta que el tema de ella, finalmente, sea llevado a s\u00ed mismo para ser uno con el Se\u00f1or. . Entonces, \u00bfnuestra salvaci\u00f3n se origin\u00f3 en la misericordia de Dios? Aprendamos de ello una lecci\u00f3n de humildad. Pero, de nuevo, \u00bffueron graduales los desarrollos de esta misericordia? \u00bfNo brill\u00f3 todo a la vez? \u00bfQu\u00e9 lecci\u00f3n debemos sacar de esta circunstancia? Marca esto, entonces; vuestro cristianismo debe ser progresivo, m\u00e1s puro, y tener m\u00e1s principios hoy que ayer; y m\u00e1s de principios, pureza y desinter\u00e9s ma\u00f1ana que hoy. Debe ser gradual y progresivo en su progreso, tanto en principio como en la pr\u00e1ctica. Por \u00faltimo: \u00bfEsta luz fue enviada para el bien de todo el mundo? Entonces, esforc\u00e9monos por difundirlo universalmente por todo el mundo.(<em>W. Toase.<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lc 1,78 Por la ternura misericordia de nuestro Dios Advenimiento de Cristo I. UNA VISTA MUY CONMOVEDORA DEL ESTADO DE LA HUMANIDAD ANTES DE LA VENIDA DE CRISTO. \u201cOscuridad y sombra de muerte\u201d. 1. Ignorante del car\u00e1cter moral de Dios. 2. Ignorantes de la pureza de la ley de Dios. 3. Ignorante en cuanto a &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-178-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Lucas 1:78 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39236","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=39236"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39236\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=39236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=39236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=39236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}