{"id":39251,"date":"2022-07-16T08:50:18","date_gmt":"2022-07-16T13:50:18","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-220-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:50:18","modified_gmt":"2022-07-16T13:50:18","slug":"estudio-biblico-de-lucas-220-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-220-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Lucas 2:20 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Lc 2,20<\/span><\/p>\n<p><em>Y los pastores volvieron<\/em><\/p>\n<p><strong>Dignificando la vida en com\u00fan<\/strong><\/p>\n<p>Y luego volvieron a sus campos, a sus reba\u00f1os, a su vida ordinaria; dando as\u00ed un hermoso ejemplo de piadosa diligencia y fidelidad en su vocaci\u00f3n.<\/p>\n<p>Se les ha concedido un privilegio extraordinario. No los eleva al orgullo, la pretensi\u00f3n, la autosuficiencia y la ociosidad. Son animados por ella en su trabajo com\u00fan. Este es todo el evangelio que algunos de ellos escuchar\u00edan en la tierra. Morir\u00edan, probablemente, como viv\u00edan, cuidando sus ovejas, antes de que apareciera abiertamente el Buen Pastor. En su ejemplo, santifican, glorifican, lo que llamamos vida com\u00fan. Ellos dignifican el deber, puede ser el trabajo pesado del d\u00eda. Pero, \u00bfqu\u00e9 es, despu\u00e9s de todo, la vida com\u00fan? Es una frase relativa. La vida com\u00fan de estos pastores es el cuidado de las ovejas en los mismos campos donde David fue pastor antes que ellos, donde Rut espig\u00f3 despu\u00e9s de los segadores. La vida com\u00fan a los \u00e1ngeles reside en las esferas celestiales, sirviendo a las \u00f3rdenes del Rey. Esta visita a la tierra, en tal misi\u00f3n, es una notable excepci\u00f3n a su experiencia ordinaria. Es, si podemos usar la frase, un punto de alto romance en su historia. (<em>Dr. Raleigh.<\/em>)<\/p>\n<\/p>\n<p>As\u00ed es como todos los indagadores sinceros y de coraz\u00f3n sencillo han regresado de sus investigaciones cristianas. Es cuestionable si alg\u00fan hombre alguna vez cerr\u00f3 la Biblia en un estado de insatisfacci\u00f3n que la abri\u00f3 con reverente determinaci\u00f3n para saber cu\u00e1n lejos era un testimonio del cielo. La investigaci\u00f3n cristiana no termina hasta que ha tra\u00eddo al coraz\u00f3n un gozo sin precedentes. La mera letra nunca trae alegr\u00eda. Los cr\u00edticos y los que discuten han encontrado poco en la Biblia sino un gran desperdicio de palabras; pero los arrepentidos y fervorosos indagadores han regresado de su examen con el coraz\u00f3n rebosante de un gozo nuevo e imperecedero. (<em>J. Parker, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Pastores glorificando a Dios por el nacimiento de un Salvador<\/strong><\/p>\n<p>Contemplaremos las cosas por las cuales y la manera en que glorificaron a Dios, y entremezclaremos algunas reflexiones pr\u00e1cticas. <\/p>\n<p><strong><br \/>Yo. <\/strong>CONSIDERAREMOS LOS ASUNTOS POR LOS CUALES GLORIFICARON Y ALABARON A DIOS. Estas eran las cosas que hab\u00edan o\u00eddo y visto. <\/p>\n<p><strong>1.<\/strong> Glorificaron a Dios porque el Salvador prometido ya hab\u00eda nacido. Parecen haber sido algunas de esas personas piadosas que buscaban la redenci\u00f3n en Israel. <\/p>\n<p><strong>2.<\/strong> Se regocijaron porque les hab\u00eda nacido este Salvador. El \u00e1ngel dice: \u201cOs ha nacido hoy un Salvador\u201d. Conscientes de su impotencia e indignidad, sintieron su necesidad de un Salvador, y consideraron que era motivo de gran gozo que viniera a traerles salvaci\u00f3n. Sin duda admiraron la distinguida gracia de Dios al visitarlos en primer lugar con las gloriosas nuevas. <\/p>\n<p><strong>3.<\/strong> Los pastores se regocijaron de que el Salvador fuera cuerno para los dem\u00e1s, as\u00ed como para ellos mismos. \u201cOs traigo buenas nuevas\u201d, dice el \u00e1ngel, \u201cque ser\u00e1n para todo el pueblo\u201d. <\/p>\n<p><strong>4.<\/strong> Los pastores glorificaron a Dios por lo que hab\u00edan visto, as\u00ed como por lo que hab\u00edan o\u00eddo. <\/p>\n<p><strong><br \/>II. <\/strong>CONSIDERA LA MANERA EN QUE LO GLORIFICARON. <\/p>\n<p><strong>1.<\/strong> Glorificaban a Dios por la fe en el Salvador que hab\u00eda enviado. Ellos creyeron el mensaje celestial. Por la fe en el Redentor damos gloria a Dios. <\/p>\n<p><strong>2.<\/strong> Glorificaron a Dios con una pronta obediencia. Siendo informados por un mensajero celestial donde yac\u00eda el Salvador, acudieron a \u00c9l de prisa. No se demoraron, sino que inmediatamente obedecieron la indicaci\u00f3n Divina. La fe opera en forma de alegre obediencia. <\/p>\n<p><strong>3.<\/strong> Glorificaban a Dios confesando y difundiendo el nombre del Salvador. \u201cCuando lo vieron, dieron a conocer lo que les hab\u00eda sido dicho acerca del Ni\u00f1o\u201d. No se avergonzaron de reconocerlo como el Mes\u00edas, incluso en su estado infantil. Ves que la fe verdadera te impulsar\u00e1 a honrar a Cristo ante los hombres. <\/p>\n<p><strong>4.<\/strong> Ellos glorificaron a Dios por una asistencia en los medios de la fe. El \u00e1ngel que anunci\u00f3 el nacimiento del Salvador les dio una se\u00f1al para que pudieran conocerlo. \u201cEsto os ser\u00e1 una se\u00f1al. Hallar\u00e9is al ni\u00f1o envuelto en pa\u00f1ales, acostado en un pesebre. Y vinieron de prisa, y hallaron como les hab\u00eda dicho.\u201d Dios les dio un signo particular para la confirmaci\u00f3n de su fe; y \u00c9l ha designado medios permanentes para fortalecer y animar los nuestros. Jesucristo se nos muestra en Su Palabra, en Su santuario y en Su mesa. Aqu\u00ed estamos para buscarlo y conversar con \u00c9l, para que podamos aumentar nuestra fe y calentar nuestro amor. <\/p>\n<p><strong>5.<\/strong> Glorificaban a Dios con voz de alabanza. (<em>J. Lathrop, DD<\/em>)<\/p>\n<\/p>\n<p><strong>El mundo cambiado<\/strong><\/p>\n<p>El d\u00eda despu\u00e9s del nacimiento de Cristo Era un nuevo d\u00eda en la historia del mundo. La vieja era hab\u00eda pasado, la nueva hab\u00eda comenzado; y s\u00f3lo los \u00e1ngeles sab\u00edan qu\u00e9 revoluci\u00f3n hab\u00eda sido forjada por el poder silencioso de Dios. La maravilla ha crecido con los a\u00f1os. El cristianismo ha sido un milagro creciente de la presencia del Se\u00f1or en la tierra. Ese canto, que escucharon unos pocos pastores, se ha entonado en el pensamiento del mundo, y es la nota clave y la armon\u00eda de toda paz y buena voluntad en la tierra. <\/p>\n<p><strong><br \/>Yo. <\/strong>EL CAMBIO CRISTIANO DE LA HISTORIA DEL MUNDO ES UN HECHO. El influjo a trav\u00e9s de Cristo de un nuevo poder en la vida de la humanidad es un hecho conocido de la experiencia, tan cierto como la batalla de Gettysburg, o el amanecer del d\u00eda. Este hecho del nuevo poder en el mundo, por el nacimiento de Cristo, pertenece a una serie de hechos. La religi\u00f3n de la Biblia presenta una sucesi\u00f3n continua y revela un orden exaltado de hechos. El cristianismo es una religi\u00f3n positiva de hechos hist\u00f3ricos desde Mois\u00e9s hasta Cristo, desde Cristo hasta la \u00faltima Iglesia organizada y la \u00faltima mesa de comuni\u00f3n servida. <\/p>\n<p><strong><br \/>II. <\/strong>LA NATURALEZA Y SIGNIFICADO REAL DE ESTE HECHO. <\/p>\n<p><strong>1.<\/strong> En el cristianismo respiramos un aire diferente. A mitad de camino por el paso de Simplon, el viajero se detiene para leer en una piedra la sola palabra \u00abItalia\u00bb. En este punto pasa un l\u00edmite en vivo, y cada paso deja m\u00e1s claro cu\u00e1n grande ha sido el cambio de Suiza a Italia. El aire se vuelve c\u00e1lido y fragante, y las vides bordean el camino, y abajo, envuelto en verdor, el lago Maggiore se expande ante \u00e9l. Mientras ese viajero descansa al atardecer, reconoce que la entrada a un nuevo mundo estaba marcada por la palabra \u00abItalia\u00bb sobre la piedra del paso. La humanidad ha cruzado una l\u00ednea fronteriza: arriba a Bel\u00e9n, sombr\u00edo y fr\u00edo, abajo de Bel\u00e9n, otro tiempo m\u00e1s feliz. <\/p>\n<p><strong>2.<\/strong> Este nuevo poder transformador era, para los disc\u00edpulos, el mismo Jes\u00fas. Hizo todas las cosas nuevas para ellos. <\/p>\n<p><strong>3.<\/strong> Jes\u00fas ha sido para el mundo una nueva revelaci\u00f3n de Dios. Dios es esencial y eternamente semejante a Cristo. <\/p>\n<p><strong>4.<\/strong> Jes\u00fas es tambi\u00e9n una nueva revelaci\u00f3n del hombre. El hombre es en Cristo otro hombre. Te cruzas con un hombre en las calles y sol\u00edas sentir que no quer\u00edas conocer ni ayudar a una criatura tan pobre: viv\u00eda debajo de tu mundo y su nombre no se encontraba en tu libro de la vida. Ahora es diferente, porque hab\u00e9is sido bautizados en el nombre de Cristo, en quien existe toda nuestra humanidad com\u00fan, redimida y capaz de una gran salvaci\u00f3n. CONCLUSI\u00d3N: Terminamos pregunt\u00e1ndonos: \u201c\u00bfEstoy viviendo, por fe en el Hijo de Dios, en este mundo cambiado?\u201d \u00bfEs, en la historia de mi alma, el d\u00eda anterior, o el mejor d\u00eda despu\u00e9s de Navidad? (<em>Newman Smyth, DD<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lc 2,20 Y los pastores volvieron Dignificando la vida en com\u00fan Y luego volvieron a sus campos, a sus reba\u00f1os, a su vida ordinaria; dando as\u00ed un hermoso ejemplo de piadosa diligencia y fidelidad en su vocaci\u00f3n. Se les ha concedido un privilegio extraordinario. No los eleva al orgullo, la pretensi\u00f3n, la autosuficiencia y la &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-220-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Lucas 2:20 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39251","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=39251"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39251\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=39251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=39251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=39251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}