{"id":39252,"date":"2022-07-16T08:50:21","date_gmt":"2022-07-16T13:50:21","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-221-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:50:21","modified_gmt":"2022-07-16T13:50:21","slug":"estudio-biblico-de-lucas-221-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-221-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Lucas 2:21 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Lc 2,21<\/span><\/p>\n<p><em>Para los que circuncidan del Ni\u00f1o<\/em><\/p>\n<p><strong>Circuncisi\u00f3n y bautismo<\/strong><\/p>\n<p>La ense\u00f1anza de la circuncisi\u00f3n jud\u00eda se asemeja a la ense\u00f1anza del bautismo cristiano.<\/p>\n<p> Ambos exhiben la eliminaci\u00f3n de las inmundicias de la carne; el primero por una herida en el cuerpo (que recuerda acertadamente la severidad de la dispensaci\u00f3n mayor); el segundo por un lavado exterior. Esto, que puede llamarse el alcance pr\u00e1ctico de la presente fiesta (Circuncisi\u00f3n de Cristo, 1 de enero), se destaca en la colecta del d\u00eda, en la que suplicamos a Dios que nos conceda \u201cla verdadera circuncisi\u00f3n del esp\u00edritu\u201d. Y vale la pena observar que esto se vio, desde el principio, como la ense\u00f1anza m\u00edstica del rito. As\u00ed Mois\u00e9s, en el libro de Deuteronomio (que abunda en la clase m\u00e1s alta de doctrina), habla claramente (<span class='bible'>Dt 10:16<\/span>; <span class='bible'>Dt 10:16<\/span>; =&#8217;bible&#8217; refer=&#8217;#b5.30.6&#8242;&gt;Dt 30,6<\/span>) de circuncidar el coraz\u00f3n; y los profetas (<span class='bible'>Jer 4,4<\/span>) usan la misma expresi\u00f3n. El lenguaje de San Esteban, cuando se dirigi\u00f3 a sus compatriotas por \u00faltima vez (\u201cTercos de cerviz e incircuncisos de coraz\u00f3n y de o\u00eddos,\u201d <span class='bible'>Hch 7:51<\/a>), parece mostrar que este continu\u00f3 a lo largo de toda la historia del pueblo jud\u00edo como el significado bien entendido del rito; mientras que el testimonio de san Pablo al respecto (<span class='bible'>Rom 2,28-29<\/span>) es expreso. Es interesante observar cu\u00e1n estrechamente relacionada esta observancia con el santo bautismo, adem\u00e1s de ser t\u00edpica del sacramento cristiano, y, de hecho, una especie de anticipaci\u00f3n de \u00e9l: un rito realizado en la infancia, y que dio lugar a otorgar un nuevo nombre. (<em>Dean Burgon.<\/em>)<\/p>\n<\/p>\n<p><strong>Naturaleza espiritual de la circuncisi\u00f3n<\/strong><\/p>\n<p>La circuncisi\u00f3n era el sello de la pacto evang\u00e9lico hecho por Dios con Abraham (<span class='bible'>G\u00e9n 17:2<\/span>; <span class='bible'>G\u00e9n 17:4<\/span>; <span class='bible'>Gn 17:9<\/span>); la cual la ley, a\u00f1adida\u2014como ense\u00f1a el ap\u00f3stol (<span class='bible'>G\u00e1l 3,17<\/span>)\u2014cuatrocientos treinta a\u00f1os despu\u00e9s, no pudo anularla. Este fue un pacto de fe, bastante distinto del pacto de obras (<span class='bible'>Exo 24:8<\/span>) hecho a trav\u00e9s de Mois\u00e9s; era un pacto evang\u00e9lico, no legal. Y prefigur\u00f3 lo que suceder\u00eda en los \u00faltimos d\u00edas, aunque la gente no lo sab\u00eda, no lo sabr\u00eda. Confiaban en ser descendientes naturales de Abraham, y no prestaron atenci\u00f3n a la declaraci\u00f3n de nuestro Salvador de que, si fueran <\/p>\n<p>verdaderamente hijos de Abraham, har\u00edan las obras de Abraham (<span class='bible'>Juan 8:39<\/span>); en otras palabras, que la promesa de Dios a la simiente del patriarca fue una promesa espiritual, cumplida a todos los que mostraron la misma fe con \u00e9l <span class='bible'>G\u00e1l 3:7<\/a>; <span class='bible'>G\u00e1latas 3:29<\/span>). Si bien, por lo tanto, la sumisi\u00f3n de nuestro Salvador a ser circuncidado, por lo cual, en un aspecto, cumpli\u00f3 con toda justicia, transmite una lecci\u00f3n obvia de obediencia y conformidad con las leyes de la Iglesia, a la cual pertenecemos; el cumplimiento evang\u00e9lico que Cristo dio a ese rito sagrado, y a la alianza con Abraham de la cual fue sello y prenda, trae a la mente la elevada ense\u00f1anza espiritual de todas sus leyes antiguas, cuyo prop\u00f3sito era guiar el coraz\u00f3n del hombre a el futuro Mes\u00edas. La antigua ley de Dios era completamente espiritual; no es letra muerta, sino una realidad viva, que pone a prueba el coraz\u00f3n y las riendas. (<em>Dean Burgon.<\/em>)<\/p>\n<\/p>\n<p><strong>La circuncisi\u00f3n de nuestro Se\u00f1or<\/strong><\/p>\n<p>No hay parte de la vida de nuestro Salvador sin inter\u00e9s, o que no producir\u00e1 instrucci\u00f3n. Preguntamos, entonces, \u00bfpor qu\u00e9 se someti\u00f3 a la circuncisi\u00f3n? <\/p>\n<p><strong>1.<\/strong> Cristo fue circuncidado para cumplir la ley. Por su perfecta obediencia a todos sus preceptos, aboli\u00f3 su fuerza y poder condenatorio sobre toda transgresi\u00f3n. Por nosotros fue circuncidado y bautizado; \u00c9l exhibi\u00f3 por nosotros una obediencia legal completa, para que \u00c9l pudiera ponernos bajo el pacto tierno, misericordioso y alentador del evangelio, al \u201ccumplir toda justicia\u201d. <\/p>\n<p><strong>2.<\/strong> La circuncisi\u00f3n de Cristo fue necesaria para obtener para \u00c9l una audiencia entre Su propio pueblo. Los jud\u00edos consideraban inmundos a todos los incircuncisos. Cristo no podr\u00eda haber tenido acceso a ellos sin someterse a esta ceremonia. Para manifestarse como descendiente de Abraham, para satisfacer a este respecto las exigencias de Su naci\u00f3n, para corroborar Sus pretensiones de ser el Mes\u00edas de ellos, y privarlos de lo que habr\u00eda sido una s\u00faplica incontestable por rechazarlo, se dign\u00f3 amablemente soportar esta rito doloroso. \u00a1Qu\u00e9 ejemplo nos ha dado \u00c9l de la excelencia de someterse a las privaciones y dolores para promover la felicidad de nuestros semejantes! \u00bfJes\u00fas llev\u00f3 las marcas de un rito de humillaci\u00f3n en Su propio cuerpo precioso, para que Su propio pueblo, cuando \u00c9l viniera a ellos, no se ofendiese en \u00c9l; \u00bfY no cederemos a todos los inocentes acatamientos de los h\u00e1bitos y sentimientos de los dem\u00e1s, que pueden facilitar nuestra utilidad para ellos, y soportaremos con satisfacci\u00f3n los trabajos y cruces, abnegaciones, gastos y cuidados que puedan ser necesarios para promover su \u00bfsalvaci\u00f3n o felicidad? <\/p>\n<p><strong>3.<\/strong> La instituci\u00f3n de esta ceremonia, y el cumplimiento de Cristo por ella, nos sugiere la propiedad y eficacia de los ritos y sacramentos visibles. Aqu\u00ed hab\u00eda un sello de un pacto establecido por Dios. Deb\u00eda ser una se\u00f1al para distinguir a los fieles, una se\u00f1al de limpieza de la contaminaci\u00f3n y una garant\u00eda de bendici\u00f3n de parte de Jehov\u00e1. Sin alg\u00fan rito visible, es dif\u00edcilmente concebible c\u00f3mo esta o cualquier Iglesia podr\u00eda conservarse distinta. Alg\u00fan sacramento es necesario y, si es necesario, obligatorio para todos los que quieren apoyar a la Iglesia, por la cual es santificada, y disfrutan de todos sus privilegios. En consecuencia, todos los sistemas de religi\u00f3n han tenido sus ritos, misterios, s\u00edmbolos. Lo que la circuncisi\u00f3n era para los jud\u00edos, el bautismo lo es para los cristianos. Ambos de designaci\u00f3n divina, significativos de la incorporaci\u00f3n a la Iglesia de Dios, que requieren fe, representan la purificaci\u00f3n de las contaminaciones del pecado e implican la consiguiente abnegaci\u00f3n, santidad y obediencia. <\/p>\n<p><strong>4.<\/strong> En la circuncisi\u00f3n de Cristo se nos ense\u00f1a de manera sorprendente la conveniencia de someternos a todos los preceptos e instituciones de la revelaci\u00f3n bajo la cual vivimos. Cristo fue hecho bajo la ley, por lo tanto, la ley ten\u00eda autoridad sobre \u00e9l. Con singular verdad, podr\u00eda haber preguntado: \u00ab\u00bfPuedo ser beneficiado por este rito y por estas sencillas ceremonias?\u00bb Con peculiar fuerza \u00c9l pudo haber preguntado, \u201c\u00bfQu\u00e9 conexi\u00f3n puede haber entre estas formas externas y Mi esp\u00edritu; \u00bfQu\u00e9 eficacia pueden tener sobre Mi coraz\u00f3n?\u201d Con m\u00e1s decoro que cualquier mortal, podr\u00eda haber dicho: \u201cPuedo estar seguro y perfecto sin todo esto\u201d. Pero no dej\u00f3 de escr\u00fapulos su utilidad; \u00c9l no encontr\u00f3 fallas en su naturaleza. Fueron ordenados por el Ser que estableci\u00f3 la ley bajo la cual \u00c9l viv\u00eda. Esto fue suficiente para \u00c9l. Y as\u00ed a lo largo de Su vida. \u00c9l guard\u00f3 la pascua; Observ\u00f3 el s\u00e1bado; Sub\u00eda a las fiestas; No descuid\u00f3 ning\u00fan precepto de la revelaci\u00f3n que sab\u00eda que ven\u00eda de Dios, y ten\u00eda autoridad hasta que fue reemplazada por Su nueva y mejor dispensaci\u00f3n. En esta conducta de Su vida, nuestro Salvador ha puesto un ejemplo, excelente en s\u00ed mismo, y digno de que Sus disc\u00edpulos lo reverencien. Nos se\u00f1ala la necesidad de obedecer todos los preceptos y observar todos los ritos a los que el evangelio da el sello de la autoridad divina. Descuidar el bautismo o la sagrada comuni\u00f3n porque, como piensan los hombres, pueden ser igualmente buenos y seguros sin ellos, o porque no pueden ver su eficacia, es tomar un terreno que el perfecto Hijo de Dios fue demasiado modesto para asumir. Si los hombres pueden salvarse sin estos medios, c\u00f3mo efect\u00faan lo que se les atribuye, si son los mejores que podr\u00edan haber sido elegidos, son puntos en los que no tenemos nada que ver. Las preguntas que nos preocupan son si Cristo instituy\u00f3 el bautismo y la eucarist\u00eda; y, si lo hizo, si sus mandatos nos obligan o no? Sobre esta sencilla base, todo hombre puede formar f\u00e1cilmente una determinaci\u00f3n justa acerca de la conveniencia de observar todos los preceptos e instituciones de la revelaci\u00f3n bajo la cual vive. Su observancia de ellos debe ser un simple acto de fe y obediencia, por el cual debe dar testimonio tanto de Dios como de los hombres. (<em>Obispo Dehon.<\/em>)<\/p>\n<\/p>\n<p><strong>Sufrimiento temprano<\/strong><\/p>\n<p>As\u00ed de temprano Jes\u00fas sufri\u00f3 dolor por nuestros para ense\u00f1arnos la circuncisi\u00f3n espiritual, la circuncisi\u00f3n de todos nuestros sentidos corporales. Como el oriente toma al atardecer los colores del occidente, as\u00ed Bel\u00e9n es preludio del Calvario, y hasta la cuna del Ni\u00f1o se ti\u00f1e de un reflejo carmes\u00ed de la cruz del Redentor. (<em>Archidi\u00e1cono Farrar.<\/em>)<\/p>\n<\/p>\n<p><strong>La circuncisi\u00f3n de Cristo<\/strong><\/p>\n<p>(Primer domingo despu\u00e9s de Navidad. ) <\/p>\n<p><strong><br \/>Yo. <\/strong>EL RITO DE LA CIRCUNCISI\u00d3N QUE, COMO EN ESTE D\u00cdA, FUE ADMINISTRADO AL NI\u00d1O JES\u00daS TEN\u00cdA UN DOBLE SIGNIFICADO. <\/p>\n<p><strong>1.<\/strong> Su existencia fue un testimonio de que la humanidad est\u00e1 ca\u00edda y necesita purificaci\u00f3n. <\/p>\n<p><strong>2.<\/strong> La circuncisi\u00f3n no era solo un acto de humildad, tambi\u00e9n era un acto de obediencia a la ley de Dios. <\/p>\n<p><strong><br \/>II. <\/strong>LA CIRCUNCISI\u00d3N DE JES\u00daS NOS REVELA AS\u00cd LOS FUNDAMENTOS SOBRE LOS QUE FUE CONSTRUIDA SU VIDA HUMANA, ES DECIR, LA HUMILDAD Y LA OBEDIENCIA. \u00bfPuede haber fundamentos m\u00e1s verdaderos para cualquier vida humana que estos? \u00bfNo es el ideal mismo de la infancia cristiana? la humildad, que es la expresi\u00f3n de nuestra propia insuficiencia; obediencia, que es el reconocimiento de nuestra dependencia de Dios. <\/p>\n<p><strong><br \/>III. <\/strong>Bien ha se\u00f1alado muchos devotos pensadores cristianos que LA VIDA HUMANA QUE VIVI\u00d3 EN LA CARNE EL HIJO DE DIOS ES MISMA A LA VIDA QUE VIVI\u00d3 EN NOSOTROS; se produce de la misma manera y progresa de acuerdo con la misma ley. Despu\u00e9s de Su nacimiento espiritual en nosotros viene nuestra circuncisi\u00f3n espiritual (<span class='bible'>Col 2:11<\/span>). A medida que esta vida crece en nosotros, encontraremos que tiene tambi\u00e9n su epifan\u00eda, su bautismo, su tentaci\u00f3n, su ministerio activo, su pasi\u00f3n, su cruz, su resurrecci\u00f3n. Suficiente para que hoy consideremos su circuncisi\u00f3n. No sin raz\u00f3n rezamos en las letan\u00edas: \u201cPor tu santa natividad y circuncisi\u00f3n, buen Se\u00f1or, l\u00edbranos\u201d. <\/p>\n<p><strong><br \/>IV. <\/strong>La circuncisi\u00f3n se distingui\u00f3 de todos los dem\u00e1s actos de humillaci\u00f3n de nuestro Se\u00f1or EN QUE NO TEN\u00cdA NINGUNA GLORIA COMPENSADORA, y fue aceptada por \u00c9l sin ninguna protesta de Dios ni del hombre, declarando que no la necesitaba por Su propio bien. Sin embargo, incluso en Su circuncisi\u00f3n se le otorg\u00f3 una gloria que los hombres no pudieron reconocer en ese momento, pero que ha resultado ser el mayor de todos los honores de Su vida encarnada. FUE ENTONCES QUE SE LE CONCEDI\u00d3 EL NOMBRE DE JES\u00daS, Dios nuestro Salvador. El nombre que le fue dado en Su humillaci\u00f3n se ha convertido en el nombre con el que ha triunfado sobre Sus enemigos, el nombre que ha sido bendecido por millones de pecadores arrepentidos y adorado en \u00e9xtasis por diez mil de Sus santos. <\/p>\n<p><strong><br \/>V. <\/strong>Temblorosos, ansiosos, MIRAMOS HACIA LA INCERTIDUMBRE DE UN NUEVO A\u00d1O. Si comenzamos el a\u00f1o en el esp\u00edritu de Aquel que comenz\u00f3 Su vida terrenal en humildad y obediencia, podemos saber que, por muy irritante que sea para nuestra voluntad natural no renovada la humildad que es lo \u00fanico que nos conviene, por dif\u00edcil que sea la obediencia que Dios demanda. de nosotros, a\u00fan debe manifestarse una gloria que exalte, en comparaci\u00f3n con la cual las pruebas de esta vida presente son como nada. (<em>Canon V. Hutton, MA<\/em>)<\/p>\n<\/p>\n<p>El a\u00f1o comienza contigo,<\/p>\n<p>Y t\u00fa comienzas con aflicci\u00f3n, <br \/>Para que el mundo de los pecadores vea<br \/>Que la sangre por el pecado debe fluir.<br \/>Tu Ni\u00f1o llora, oh Se\u00f1or,<br \/>Tus l\u00e1grimas sobre el pecho,<br \/>No bastan &#8211;la espada legal<br \/>Debe hacer su severo mandato.<br \/>Como vino de sacrificio<br \/>Vertido sobre la cabeza de una v\u00edctima<br \/>Son estas pocas gotas preciosas de Thin,<br \/>Ahora primero a la ofrenda conducida.<br \/>Son prenda y sello<br \/>De la fe inquebrantable de Cristo<br \/>Dados a Su Padre, nuestras almas para sanar,<\/p>\n<p>Aunque cueste Su muerte.<\/p>\n<p><strong>\u201cJes\u00fas\u201d, la consigna<\/strong><\/p>\n<p><strong><br \/>I. <\/strong>POR LA IGLESIA Y POR EL HOGAR. <\/p>\n<p><strong><br \/>II. <\/strong>PARA EL GOZO Y EL DOLOR. <\/p>\n<p><strong><br \/>III. <\/strong>PARA VIDA Y PARA MUERTE. (<em>Dr. Gerok.<\/em>)<\/p>\n<\/p>\n<p><strong>La circuncisi\u00f3n y el nombramiento del Ni\u00f1o<\/strong><\/p>\n<p>Los ni\u00f1os eran circuncidados ocho d\u00edas despu\u00e9s de su nacimiento. La tradici\u00f3n dec\u00eda que se escog\u00eda este d\u00eda porque la madre dejaba de ser inmunda al s\u00e9ptimo d\u00eda si hab\u00eda dado a luz un var\u00f3n. El que circuncid\u00f3 al ni\u00f1o us\u00f3 las siguientes palabras: \u201cBendito sea el Se\u00f1or nuestro Dios, que nos santific\u00f3 como por sus preceptos, y nos dio la circuncisi\u00f3n\u201d. El padre del ni\u00f1o continu\u00f3: \u201cQuien nos ha <em>santificado<\/em> con sus preceptos, y nos ha concedido introducir a nuestro hijo en el pacto de Abraham nuestro padre\u201d. El ni\u00f1o recibi\u00f3 su nombre el mismo d\u00eda, porque se dec\u00eda que Dios cambi\u00f3 los nombres de Abraham y Sara cuando dio el pacto de la circuncisi\u00f3n. (<em>E. Stapler, DD<\/em>)<\/p>\n<\/p>\n<p><strong>La circuncisi\u00f3n de Cristo<\/strong><\/p>\n<p><strong>1 .<\/strong> Significa purificaci\u00f3n. Cristo no cometi\u00f3 pecado, sino que defendi\u00f3 al hombre pecador. <\/p>\n<p><strong>2.<\/strong> Significaba obediencia (<span class='bible'>G\u00e9n 17:12<\/span>). Fue \u201checho bajo la ley\u201d <span class='bible'>Gal 4:4<\/span>). <\/p>\n<p><strong>3.<\/strong> Significaba consagraci\u00f3n. Esta ordenanza era parte del pacto entre Dios y la naci\u00f3n jud\u00eda, por la cual ser\u00edan considerados \u201cun tesoro especial\u201d para Dios \u201csobre todos los pueblos\u201d (<span class='bible'>Exo 19:5<\/span>). (<em>D. Hughes, MA<\/em>)<\/p>\n<\/p>\n<p><strong>D\u00eda de A\u00f1o Nuevo<\/strong><\/p>\n<p><strong><br \/>Yo. <\/strong>LA CIRCUNCISI\u00d3N ERA UN RITO QUE HABLABA DE UN PASADO MAL MEJORADO. El primer relato se da en la historia de Abraham, en cuyo caso Pablo dice que fue dada como se\u00f1al y sello de la justicia que se obtiene por la fe (<span class='bible'> Rom 4,11<\/span>). El estado de incircuncisi\u00f3n era as\u00ed un estado de injusticia. Pablo tambi\u00e9n les dice a los colosenses que hab\u00edan estado muertos en sus pecados y en la incircuncisi\u00f3n de su carne (<span class='bible'>Col 2:13<\/span>). La circuncisi\u00f3n, por lo tanto, tra\u00eda consigo el recuerdo y el reconocimiento de un pasado malo e insatisfactorio. Hablaba de la alienaci\u00f3n de Dios, y de faltas de fe e infidelidades. Llevaba consigo una retrospectiva del fracaso y el pecado. Incluso la circuncisi\u00f3n del \u00absanto ni\u00f1o Jes\u00fas\u00bb fue un reconocimiento de la condici\u00f3n ca\u00edda de la raza, con la que se identific\u00f3 a s\u00ed mismo, en su humillaci\u00f3n, para poder convertirse en su perfecto Salvador. <\/p>\n<p><strong><br \/>II. <\/strong>LA CIRCUNCISI\u00d3N ERA UNA SE\u00d1AL DE LA CORTABILIDAD Y ELIMINACI\u00d3N DEL PECADO. La incisi\u00f3n carnal era se\u00f1al de una espiritual, que consist\u00eda en la separaci\u00f3n de la impureza moral y el mal (<span class='bible'>Rom 2:29<\/span>). <\/p>\n<p><strong><br \/>III. <\/strong>SINO LA CIRCUNCISI\u00d3N APARTADA PARA LA OBEDIENCIA, AS\u00cd COMO SEPARADA DE LA IMPUREZA. Era la ceremonia de iniciaci\u00f3n en el pacto, y compromet\u00eda al s\u00fabdito a obedecerlo. Era parte de la obra redentora de Cristo obedecer la ley. <\/p>\n<p><strong><br \/>IV. <\/strong>LA CIRCUNCISI\u00d3N CONFIERE Y FIJ\u00d3 A CRISTO SU VERDADERO NOMBRE DESCRIPTIVO. <\/p>\n<p><strong><br \/>V. <\/strong>Pero, para aliento de los que sienten sus carencias y miserias, hay todav\u00eda otro particular relacionado con el texto. EL QUE DIOS HA CONSTITUIDO PARA SER NUESTRO JUEZ, TOM\u00d3 EL NOMBRE DE JES\u00daS. \u00c9l es un Salvador, y uno grande. Esperemos que el d\u00eda de su circuncisi\u00f3n as\u00ed lo proclame a nosotros. S\u00ed, dice el ap\u00f3stol, \u201c\u00c9l es poderoso tambi\u00e9n para salvar perpetuamente a los que por \u00e9l se acercan a Dios\u201d (<span class='bible'>Heb 7:25<\/span>) .(<em>JASeiss, DD<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lc 2,21 Para los que circuncidan del Ni\u00f1o Circuncisi\u00f3n y bautismo La ense\u00f1anza de la circuncisi\u00f3n jud\u00eda se asemeja a la ense\u00f1anza del bautismo cristiano. Ambos exhiben la eliminaci\u00f3n de las inmundicias de la carne; el primero por una herida en el cuerpo (que recuerda acertadamente la severidad de la dispensaci\u00f3n mayor); el segundo por &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-221-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Lucas 2:21 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39252","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=39252"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39252\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=39252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=39252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=39252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}