{"id":39257,"date":"2022-07-16T08:50:35","date_gmt":"2022-07-16T13:50:35","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-227-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:50:35","modified_gmt":"2022-07-16T13:50:35","slug":"estudio-biblico-de-lucas-227-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-227-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Lucas 2:27 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Lc 2,27<\/span><\/p>\n<p><em>Tra\u00eddo en el Ni\u00f1o Jes\u00fas<\/em><\/p>\n<p><strong>Dedicando los ni\u00f1os al Se\u00f1or<\/strong><\/p>\n<p>Cuando el duque de Kent agonizaba, dese\u00f3 que se colocara a la princesita Victoria junto a \u00e9l, y luego ofreci\u00f3 una oraci\u00f3n muy conmovedora para que \u00absi alguna vez se convirtiera en la Reina de Inglaterra, podr\u00eda gobernar en el temor de Dios\u00bb.<\/p>\n<p>\u00bb \u00bfCu\u00e1ntas de las virtudes y buenas obras de nuestra noble Reina han result\u00f3 sin duda de su entrenamiento piadoso. En mi primer circuito conoc\u00ed a la excelente familia del difunto eminente reverendo Benjamin Field. En su nacimiento, su muy piadoso padre lo dedic\u00f3 solemnemente a Dios. Comenz\u00f3 a predicar a los diecisiete a\u00f1os, y por su ministerio y por su muy buen \u201cManual de Doctrinas B\u00edblicas\u201d, ha sido \u00fatil a miles. Los ni\u00f1os santos generalmente viven para ser \u201cgrandes a los ojos del Se\u00f1or\u201d y, si son fieles, con las bendiciones de Dios, eminentemente \u00fatiles. (<em>HR Burton.<\/em>)<\/p>\n<\/p>\n<p><strong>Unicidad de objetivo<\/strong><\/p>\n<p>Los padres deben tener un solo objetivo antes ellos en cuanto a sus hijos, y esto es, criarlos para el Se\u00f1or. A eso todo lo dem\u00e1s deber\u00eda ceder. La tendencia natural es criarlos muy gentilmente, muy respetablemente, educarlos para alg\u00fan puesto en el que puedan ganar mucho dinero. Esta es la tendencia natural por parte de los padres. Bien, pueden obtener el deseo de sus corazones, pero para perjuicio de las almas de sus hijos. \u00a1C\u00f3mo presionar\u00eda esto en los corazones de mis hermanos! Por supuesto, no quiero decir en absoluto que no deban tener la mejor educaci\u00f3n, y una educaci\u00f3n que sea adecuada a su posici\u00f3n en la vida. Pero todo debe ceder a este punto: mi hijo, mi hija, deben ser criados para el Se\u00f1or. Mi hijo, mi hija, se convertir\u00e1n en herederos del reino que no se desvanece. Todo deber\u00eda dar paso a este \u00fanico punto. Si no mantenemos esto ante nosotros, constantemente daremos pasos equivocados. Perm\u00edtanme dar una ilustraci\u00f3n. Un caballero cristiano de buena posici\u00f3n en la vida encomend\u00f3 a su hijo a un abogado muy malvado, notoriamente malvado. Este hijo sol\u00eda venir a casa los s\u00e1bados por la tarde para pasar el d\u00eda del Se\u00f1or con su familia. All\u00ed asisti\u00f3 a las oraciones familiares. Sol\u00eda decir cosas fuertes sobre las peticiones de su padre, tales como: \u201cMi padre ora por m\u00ed para que Dios me guarde en medio de la tentaci\u00f3n; \u00a1Me pone en la boca del le\u00f3n y luego le pide a Dios que me proteja!\u201d. (<em>George Muller.<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lc 2,27 Tra\u00eddo en el Ni\u00f1o Jes\u00fas Dedicando los ni\u00f1os al Se\u00f1or Cuando el duque de Kent agonizaba, dese\u00f3 que se colocara a la princesita Victoria junto a \u00e9l, y luego ofreci\u00f3 una oraci\u00f3n muy conmovedora para que \u00absi alguna vez se convirtiera en la Reina de Inglaterra, podr\u00eda gobernar en el temor de Dios\u00bb. &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-227-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Lucas 2:27 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39257","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=39257"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39257\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=39257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=39257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=39257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}