{"id":39267,"date":"2022-07-16T08:51:05","date_gmt":"2022-07-16T13:51:05","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-243-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:51:05","modified_gmt":"2022-07-16T13:51:05","slug":"estudio-biblico-de-lucas-243-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-243-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Lucas 2:43 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Lc 2,43<\/span><\/p>\n<p><em>Cuando tuvieron cumpli\u00f3 los d\u00edas<\/em><\/p>\n<p><strong>El evangelio de la Infancia<\/strong><\/p>\n<p>Notamos en el Ni\u00f1o Jes\u00fas&#8211;<\/p>\n<p><strong>1.<\/strong><\/p>\n<p>Una disposici\u00f3n santa. Fue esto lo que llev\u00f3 a Su madre a llevarlo con ella al Templo, y lo que lo llev\u00f3 a quedarse all\u00ed despu\u00e9s de que Su madre se hab\u00eda ido. Una disposici\u00f3n santa es la fuente y la fuente de toda bondad: <\/p>\n<p>la cera blanda de la que se moldea la imagen del amor, la pureza, la obediencia <span class='bible'>Santiago 3:17<\/span>). <\/p>\n<p><strong>2.<\/strong> Amor por la casa de Dios. Amaba el Templo mucho m\u00e1s que el foro o la plaza del mercado. Qued\u00f3 voluntariamente en la casa de su Padre celestial, atributo de un buen Hijo.<\/p>\n<p><strong>3.<\/strong> Deseo de santa conversaci\u00f3n. Se encontr\u00f3 que no jugaba con otros ni\u00f1os; no ocupado en deportes ociosos, sino conversando con los ancianos en el Templo; escuchando palabras de sobriedad, verdad y sabidur\u00eda. <\/p>\n<p><strong>4.<\/strong> Un profundo sentido de relaci\u00f3n espiritual. Aunque fue amoroso y obediente con sus padres terrenales, puso a su Padre espiritual delante de ellos. Como dice Agust\u00edn, am\u00f3 al Creador antes que al generador. <\/p>\n<p><strong>5.<\/strong> Una reverencia amorosa hacia Sus padres. \u00c9l estaba sujeto a ellos. \u00bfQui\u00e9n? \u00bfA quien? Dios al hombre. La humildad vista en su m\u00e1xima potencia. CONCLUSI\u00d3N: El ni\u00f1o es siempre el padre del hombre. Cuid\u00e9monos de formar y modelar las mentes infantiles encomendadas a nuestro cuidado seg\u00fan este glorioso y puro modelo. (<em>Guillermo de Auvernia.<\/em>)<\/p>\n<\/p>\n<p><strong>Obediencia filial<\/strong><\/p>\n<p>Nuestro Se\u00f1or nos proporciona una sorprendente ejemplo de obediencia filial. \u00c9l era Dios verdadero, Creador y Se\u00f1or de todo; sin embargo, se somete a s\u00ed mismo a su madre seg\u00fan la carne, y tambi\u00e9n a su padre adoptivo, para nuestra imitaci\u00f3n. De su santo ejemplo aprendan los hijos, en relaci\u00f3n con sus padres&#8211;<\/p>\n<p><strong>1.<\/strong> A amarlos honestamente, con sinceridad, con devoci\u00f3n; para retribuirles algo por el gran amor que sus padres se han dado a s\u00ed mismos. <\/p>\n<p><strong>2.<\/strong> Contestarlas respetuosamente. <\/p>\n<p><strong>3.<\/strong> Prestarles una obediencia leal. (<span class='bible'>Ef 6:1-2<\/span>; <span class='bible'>Col 3 :20<\/span>.) El ni\u00f1o desobediente hace al hombre pecador. <\/p>\n<p><strong>4.<\/strong> Para socorrerlos en necesidad. Es una ingratitud terrible no hacer nada por los que han hecho tanto por nosotros. Nuestro bendito Se\u00f1or tuvo un cuidado de Su madre incluso en la cruz. Una noble dama romana ministraba de su pecho a su madre en prisi\u00f3n. Recuerda, finalmente, que el amor filial siempre exige una bendici\u00f3n. (<em>J. Clichtove.<\/em>)<\/p>\n<\/p>\n<p><strong>Revelaci\u00f3n de la vida infantil perfecta<\/strong><\/p>\n<p>La vida de el ni\u00f1o es triple. No se vive en el mundo; es la vida del hogar, de la iglesia y de la escuela. Piense en Jes\u00fas en su vida de ni\u00f1o como un modelo para los ni\u00f1os cristianos. <\/p>\n<p><strong><br \/>Yo. <\/strong>VIDA EN CASA. <\/p>\n<p><strong>1.<\/strong> Obediencia a los padres. Este es un principio primordial en la vida del hogar, el germen de toda otra obediencia, social y nacional. Un h\u00e1bito de vida que es necesario para que podamos ser guiados a la obediencia a Cristo. <\/p>\n<p><strong>2.<\/strong> Sometimiento a la autoridad de origen. Demasiada obstinaci\u00f3n hoy en d\u00eda en los ni\u00f1os; est\u00e1n impacientes por la moderaci\u00f3n, quieren ser sus propios amos, emprender caminos en la vida cuando son muy j\u00f3venes. Nuestro Se\u00f1or probablemente trabaj\u00f3 en el oficio de Su supuesto padre. De todos modos, \u00c9l estaba sujeto a Sus padres, es decir, <\/p>\n<p><strong>(1)<\/strong> Nunca contradijo su autoridad. <\/p>\n<p><strong>(2)<\/strong> Nunca cruzaron sus deseos. <\/p>\n<p><strong>(3)<\/strong> Nunca cuestion\u00f3 su derecho a Su tiempo. <\/p>\n<p><strong>(4)<\/strong> Nunca murmur\u00f3 o se rebel\u00f3 contra ellos de palabra o de hecho. <\/p>\n<p><strong><br \/>II. <\/strong>VIDA DE LA IGLESIA. <\/p>\n<p><strong>1.<\/strong> La religi\u00f3n es tanto para los ni\u00f1os como para los adultos. Los ni\u00f1os son miembros de la Iglesia de Cristo y deben ser educados como tales. <\/p>\n<p><strong>2.<\/strong> Como los jud\u00edos, ense\u00f1emos a los ni\u00f1os la Sagrada Escritura desde temprana edad. Somos m\u00e1s favorecidos que ellos, al tener el evangelio para impartir a nuestros peque\u00f1os. <\/p>\n<p><strong>3.<\/strong> La vida infantil transcurre, por as\u00ed decirlo, entre la pila bautismal y la mesa sagrada. Con la confirmaci\u00f3n termina la vida del ni\u00f1o, estrictamente hablando. <\/p>\n<p><strong>4.<\/strong> Ens\u00e9\u00f1ese siempre al ni\u00f1o a mirar con anhelo y esperanza el momento en que pueda subir a la gran fiesta cristiana, la Sagrada Comuni\u00f3n. <\/p>\n<p><strong>5.<\/strong> Que los deberes religiosos se conviertan en una costumbre, para que, como con Jes\u00fas, puedan mantenerse instintivamente en los \u00faltimos a\u00f1os de la edad adulta. <\/p>\n<p><strong><br \/>III. <\/strong>VIDA ESCOLAR.. La educaci\u00f3n una cuesti\u00f3n del d\u00eda. La educaci\u00f3n religiosa la \u00fanica forma leg\u00edtima para un ni\u00f1o cristiano. Pero el papel del ni\u00f1o es aceptar y buscar el conocimiento. <\/p>\n<p><strong>1.<\/strong> Los ni\u00f1os deben estar contentos de aprender. La ense\u00f1anza es necesaria. Incluso Jes\u00fas recibi\u00f3 instrucci\u00f3n. <\/p>\n<p><strong>2.<\/strong> Se debe animar a los ni\u00f1os a investigar las cosas. (<em>Thos. H. Barnett.<\/em>)<\/p>\n<\/p>\n<p><strong>Servicio desinteresado<\/strong><\/p>\n<p>\u201cCuando hubieron cumplido los d\u00edas\u201d&#8211;St. Jos\u00e9 y la Sant\u00edsima Virgen no s\u00f3lo asistieron a la Pascua, que se celebraba el d\u00eda catorce del primer mes por la tarde, sino que tambi\u00e9n se quedaron en Jerusal\u00e9n todos los d\u00edas de la fiesta de los panes sin levadura; y as\u00ed no sali\u00f3 de la ciudad para volver a casa hasta la tarde del octavo d\u00eda despu\u00e9s de su llegada. No estaban obligados a quedarse tanto tiempo; podr\u00edan haber regresado antes sin hacer nada malo, con tal de que, durante todos los d\u00edas de la fiesta que segu\u00eda a la Pascua, hubieran tenido cuidado de no comer pan con levadura en su propia casa. Pero las personas devotas, como eran, no consideran cu\u00e1n poco de su tiempo pueden dar a Dios sin hacer el mal, sino que le dan todo lo que pueden y se deleitan en adorarlo. Piensa en esto, cuando te sientas tentado a acortar tus oraciones, o a dejar para el d\u00eda tu lectura de la Sagrada Escritura, o a sentir las horas del domingo como una restricci\u00f3n y un cansancio, y anhelando que vuelen m\u00e1s r\u00e1pido. La oraci\u00f3n, las Escrituras y el domingo s\u00f3lo son aburridos porque tu coraz\u00f3n no est\u00e1 en ellos, porque no tratas de poner tu mente en ellos, y as\u00ed crear para ti mismo un inter\u00e9s en ellos. Si tu coraz\u00f3n estuviera en ellos, ten por seguro que encontrar\u00edas en ellos el m\u00e1s puro de todos los placeres, y desear\u00edas tener m\u00e1s tiempo para dedicarles, no uno m\u00e1s corto. (<em>Dean Goulburn.<\/em>)<\/p>\n<\/p>\n<p><strong>Deberes y empleos de Pascua<\/strong><\/p>\n<p>Ser\u00e1 interesante saber c\u00f3mo San Jos\u00e9 y Santa Mar\u00eda pasaron los d\u00edas que aqu\u00ed se dice que \u00abcumplieron\u00bb, especialmente cuando recordamos que ten\u00edan al Santo Ni\u00f1o con ellos, cuya mente humana, podemos estar seguros, beber\u00eda con avidez todo lo que \u00c9l vio en la adoraci\u00f3n del Templo. \u00bfD\u00f3nde, pues, en primer lugar, vivieron durante estos d\u00edas? Algunos de los campesinos que sub\u00edan a celebrar la Pascua se alojaban en casas particulares. Este fue el caso de nuestro Se\u00f1or y Sus disc\u00edpulos, quienes comieron juntos Su \u00faltima Pascua en una casa privada, a la cual \u00c9l los dirigi\u00f3 con la se\u00f1al de un hombre que llevaba un c\u00e1ntaro de agua, que deb\u00eda entrar en \u00e9l. Era costumbre en estos casos que los invitados dejaran tras de s\u00ed, como una especie de pago por su alojamiento, la piel del cordero y los utensilios empleados para cocinarlo. Pero muy a menudo no se encontraba ese alojamiento; todas las posadas y casas particulares de Jerusal\u00e9n estaban bastante llenas, y en este caso la gente del campo se vio obligada a alojarse fuera de los muros en una tienda que trajeron consigo. Quiz\u00e1s San Jos\u00e9 y Santa Mar\u00eda hayan estado m\u00e1s dispuestos a hacer esto, porque, teniendo al Santo Ni\u00f1o con ellos, cuya vida ya hab\u00eda sido buscada por los que estaban en el poder, pudieron haber pensado que era prudente no ser visto en la ciudad m\u00e1s de lo absolutamente necesario. San Jos\u00e9 tendr\u00eda que ir al Templo la tarde del catorce de Abib para sacrificar su cordero pascual, y probablemente llevar\u00eda consigo a nuestro Se\u00f1or. El Santo Ni\u00f1o contempl\u00f3 la matanza del cordero, mientras la sangre brotaba de la herida en la copa de oro que sosten\u00eda uno de los sacerdotes para recibirla, y luego se vert\u00eda en un chorro al pie del altar del holocausto. . Luego regresaron a su tienda, llevando consigo el cad\u00e1ver del cordero, y prepararon la cena, de la cual, probablemente, ya que su familia debe haber sido demasiado peque\u00f1a para el cordero, y como se requer\u00edan al menos diez personas para hacer una Pascua. compa\u00f1\u00eda, algunos de la familia de San Jos\u00e9 o vecinos participaron con ellos. Lo primero ser\u00eda asar el cordero, lo que se hac\u00eda habitualmente pasando dos brochetas de madera de granado, una a lo largo del cuerpo de la criatura, y otra atraves\u00e1ndola por la pechuga y las patas delanteras, de manera que el cordero tuviera el aspecto de estar crucificado, y luego coloc\u00e1ndolo con cuidado en medio de un horno, cuyos ladrillos estaban al rojo vivo, pero sin dejar que tocara las paredes. Luego pon\u00edan la mesa, y pon\u00edan sobre el aparador, listo a la mano, un plato de panes sin levadura (galletas grandes y finas), otro de hierbas amargas, como escarola o lechuga silvestre, y una vasija que conten\u00eda una salsa espesa, hecha de la consistencia de la arcilla, para recordarles la fabricaci\u00f3n de ladrillos en Egipto, en cuya salsa se mojaba todo lo que se com\u00eda en la cena. Por \u00faltimo vendr\u00eda la participaci\u00f3n de la cena. San Jos\u00e9, como cabeza de familia, tomaba una copa de vino tinto en la mano y, despu\u00e9s de decir una gracia, la probaba y la repart\u00eda. Luego se pusieron las hierbas sobre la mesa y se comieron; luego el pan sin levadura; y hecho esto, se tra\u00eda el cordero asado y se pon\u00eda delante del cabeza de familia. Pero antes de que se comiera, se llen\u00f3 una segunda copa de vino; y entonces era costumbre que alg\u00fan ni\u00f1o (quiz\u00e1s, en este caso, pudo haber sido nuestro Se\u00f1or mismo) preguntarle al cabeza de familia: \u00ab\u00bfQu\u00e9 significa este servicio?\u00bb En respuesta, se recit\u00f3 la raz\u00f3n de guardar la Pascua, etc., despu\u00e9s de lo cual <span class='bible'>Sal 123:1-4; <\/span><span class='bible'>Sal 114:1-8<\/span>. fueron cantados. Luego el cordero fue cortado y comido; una tercera y una cuarta copa de vino sucedieron; y luego todo se concluy\u00f3 cantando Sal 115:-18. (<em>Decano Goulburn.<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lc 2,43 Cuando tuvieron cumpli\u00f3 los d\u00edas El evangelio de la Infancia Notamos en el Ni\u00f1o Jes\u00fas&#8211; 1. Una disposici\u00f3n santa. Fue esto lo que llev\u00f3 a Su madre a llevarlo con ella al Templo, y lo que lo llev\u00f3 a quedarse all\u00ed despu\u00e9s de que Su madre se hab\u00eda ido. Una disposici\u00f3n santa es &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-243-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Lucas 2:43 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39267","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=39267"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39267\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=39267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=39267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=39267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}