{"id":39269,"date":"2022-07-16T08:51:10","date_gmt":"2022-07-16T13:51:10","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-246-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:51:10","modified_gmt":"2022-07-16T13:51:10","slug":"estudio-biblico-de-lucas-246-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-246-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Lucas 2:46 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Lc 2,46<\/span><\/p>\n<p><em>Despu\u00e9s de tres d\u00edas lo encontraron en el Templo<\/em><\/p>\n<p><strong>El hallazgo de Jes\u00fas en el Templo<\/strong><\/p>\n<p><strong><br \/>I.<\/strong><\/p>\n<p>Una lecci\u00f3n para los ni\u00f1os y j\u00f3venes: LA HOMBRE DE LA OBEDIENCIA Y LA SUJECI\u00d3N A LA MADRE. <\/p>\n<p><strong><br \/>II. <\/strong>Los maestros pueden aprender EL MEJOR M\u00c9TODO PARA ADQUIRIR CONOCIMIENTO, haciendo y respondiendo preguntas. <\/p>\n<p><strong><br \/>III. <\/strong>Este incidente recuerda a las madres que SUS HIJOS TIENEN OTROS INTERESES QUE LOS DE ESTE MUNDO. <\/p>\n<p><strong><br \/>IV. <\/strong>Una lecci\u00f3n para todos: JES\u00daS, PERDIDO EN EL ALboroto Y LA EMOCI\u00d3N DE LA MULTITUD, SIEMPRE SE ENCUENTRA DE NUEVO EN EL TEMPLO. (<em>D. Longwill.<\/em>)<\/p>\n<\/p>\n<p><strong>El Salvador perdido y encontrado<\/strong><\/p>\n<p>Jesucristo es solo perdido por el pecado; cuando se pierde, debe ser hallado por el arrepentimiento y la gracia. <\/p>\n<p><strong><br \/>Yo. <\/strong>DEBEMOS SABER DE NUESTRA P\u00c9RDIDA Muchas veces lo perdemos, al principio, sin saberlo, tal como lo hicieron Sus padres; nosotros, como ellos, tarde o temprano nos enteramos de nuestra p\u00e9rdida. <\/p>\n<p><strong>1.<\/strong> Debemos saber de nuestra p\u00e9rdida si queremos recuperarla; no debemos buscar a Jesucristo si no sabemos que lo hemos perdido. El principio de la salvaci\u00f3n es el conocimiento del pecado. El que no sabe que peca, no est\u00e1 dispuesto a sufrir la correcci\u00f3n. <\/p>\n<p><strong>2.<\/strong> Debemos saber de nuestra p\u00e9rdida, o nunca podremos rendir a Dios el debido honor y gloria por nuestra recuperaci\u00f3n de ella. <\/p>\n<p><strong><br \/>II. <\/strong>NUESTRO CAMINO DEBE SER TRASLADADO. Debemos mirar hacia atr\u00e1s, mediante examen de conciencia, a esa vida pasada durante la cual hemos vivido sin Jesucristo. <\/p>\n<p><strong>1.<\/strong> Barrer todo pecado por nuestro aborrecimiento de \u00e9l (<span class='bible'>Luk 15:8<\/span> ). <\/p>\n<p><strong>2.<\/strong> Cubre todas nuestras impurezas con el manto de la gracia, a fin de que seamos dignos de Jesucristo (<span class='bible'>Hijo 3:2<\/span>). <\/p>\n<p><strong><br \/>III. <\/strong>DEBE LAMENTARSE LA P\u00c9RDIDA. La contrici\u00f3n sigue al examen. <\/p>\n<p><strong>1.<\/strong> Deshacer, en lo posible, la deshonra hecha a Dios. <\/p>\n<p><strong>2.<\/strong> Castigar el pecado en nosotros mismos. Siendo el coraz\u00f3n la fuente del pecado, lo afligimos con tristeza y remordimiento. <\/p>\n<p><strong><br \/>IV. <\/strong>RESERVAMOS NUESTRO TESORO RECUPERADO. <\/p>\n<p><strong>1.<\/strong> De nada sirve haber encontrado a Jesucristo con dolor y dolor, si se vuelve a perder. <\/p>\n<p><strong>2.<\/strong> Una segunda vez quiz\u00e1s no podamos encontrarlo. (<em>M. Faber.<\/em>)<\/p>\n<\/p>\n<p><strong>Jes\u00fas en casa en el Templo<\/strong><\/p>\n<p>Es f\u00e1cil comprender que el Templo debi\u00f3 tener para \u00c9l una maravillosa atracci\u00f3n, de modo que le result\u00f3 muy dif\u00edcil desprenderse de \u00e9l. Nuestro Se\u00f1or, habiendo dejado de ser un infante para convertirse en un ni\u00f1o, era plenamente consciente de qui\u00e9n era. Ahora pod\u00eda mirar hacia atr\u00e1s a Su anterior estado de existencia, cuando yac\u00eda en el seno de Su Padre desde toda la eternidad, y era adorado como una Persona en la Sant\u00edsima Trinidad por los santos \u00e1ngeles. A medida que Sus facultades se abrieran, su memoria amanecer\u00eda en lo que \u00c9l hab\u00eda sido. Ahora, por lo tanto, nota el efecto sobre \u00c9l, cuando \u00c9l ve por primera vez los servicios del Templo. El Templo era una peque\u00f1a figura o modelo del cielo; la m\u00fasica del Templo de las alabanzas de Dios cantadas continuamente en el cielo; los servicios del Templo del culto puro y santo que los \u00e1ngeles ofrecen continuamente en el cielo <span class='bible'>Heb 8:5<\/span>). Cuando vio los servicios del Templo por primera vez, tocaron una cuerda en Su memoria, que vibr\u00f3 dulce y solemnemente. Los sacerdotes y levitas, ofreciendo sus sacrificios y su incienso, y cantando sus salmos, le recordaron a los \u00e1ngeles benditos rindiendo homenaje a Dios y cantando Sus alabanzas en el cielo. Nunca antes hab\u00eda sido as\u00ed sobre la tierra; y es muy probable que, en un mundo de pecado y dolor, el bendito Jes\u00fas (aun cuando era ni\u00f1o) se sintiera fuera de lugar y lejos de su verdadero hogar. \u00bfNo pueden imaginarse a una persona que pas\u00f3 su primera infancia en un clima del sur, donde hab\u00eda p\u00e1jaros de rico plumaje, hermosas estrellas en la noche, siendo repentinamente desterrado al Polo Norte, donde sus ojos se posan en nada m\u00e1s que hielo y nieve, y todas las bellezas de la naturaleza parecen estar encerradas por un invierno perpetuo? De repente, le traen como regalo del sur un ramo de flores brillantes o un p\u00e1jaro de hermoso plumaje. Le recuerda a su pa\u00eds natal y le trae de vuelta en un momento las flores, los p\u00e1jaros y los paisajes de esa tierra feliz. Algo as\u00ed pudo haber sido el recuerdo de nuestro bendito Se\u00f1or, al ver en su primera infancia los servicios del Templo. \u00c9l sentir\u00eda que el Templo daba una idea verdadera de la casa de Su Padre en el cielo\u2014era la casa de Su Padre en la tierra. Ahora bien, una casa del Padre es un hogar; y qu\u00e9 ni\u00f1o obediente hay que no ama el hogar; que no se siente atra\u00eddo hacia el hogar, cuando est\u00e1 lejos de \u00e9l; \u00bfQui\u00e9n no lo siente como un lugar de refugio, seguridad, felicidad y paz, y se aferra a \u00e9l en consecuencia? (<em>Dean Goulburn.<\/em>)<\/p>\n<\/p>\n<p><strong>Cristo dedicado al estudio de la Biblia<\/strong><\/p>\n<p>Jes\u00fas no estaba satisfecho con adoraci\u00f3n sola, ni a\u00fan con la audici\u00f3n pasiva de las exposiciones b\u00edblicas. Quer\u00eda participar en el estudio de la Biblia. Ten\u00eda preguntas que hacerles a los maestros y estaba dispuesto a ser cuestionado. Aunque era el Hijo de Dios, sinti\u00f3 la necesidad de estudiar la Biblia; y, sintiendo esa necesidad, fue a la escuela b\u00edblica, donde la necesidad pod\u00eda ser satisfecha. Si hay un hombre hoy en d\u00eda que piensa que no necesita estudiar la Biblia, o que est\u00e1 por debajo de su dignidad estar en la escuela b\u00edblica, parece suponer que sabe m\u00e1s de lo que Jes\u00fas sab\u00eda, o parece contarlo. dif\u00edcilmente seguro estar en el mismo plano con el Hijo de Dios. Sin embargo, hay hombres y mujeres que le dan un gran valor a la adoraci\u00f3n, y ninguno, por s\u00ed mismos, al estudio social de la Biblia. Est\u00e1n regularmente en los servicios de predicaci\u00f3n, pero nunca en la Escuela Dominical. \u00a1Pobres criaturas necesitadas y engre\u00eddas! (<em>HC Trumbull.<\/em>)<\/p>\n<\/p>\n<p><strong>El poder de la simplicidad<\/strong><\/p>\n<p>Una caracter\u00edstica sorprendente en la vida de Cristo sobre la tierra son los lugares inesperados donde lo encontramos. Su advenimiento fue una sorpresa por su humildad. La raz\u00f3n jam\u00e1s se habr\u00eda dignado a inclinarse hasta un pesebre por un Mes\u00edas. La filosof\u00eda apenas habr\u00eda so\u00f1ado con se\u00f1alar al Cristo de Dios con cepillo y martillo en el banco del carpintero. La fe misma se sorprendi\u00f3 al descubrirlo como un muchacho entre los doctores barbudos de Israel. Pero ah\u00ed est\u00e1 \u00c9l. Los eruditos del Templo, de grandes cejas, no sospechan en lo m\u00e1s m\u00ednimo el car\u00e1cter del maravilloso Ni\u00f1o que est\u00e1 en medio de ellos. Ellos debaten con \u00c9l y est\u00e1n desconcertados por Sus argumentos. Su ritualismo no aguantar\u00e1 ante ese rostro joven y radiante. \u00a1Cu\u00e1n poco se dan cuenta los Maestros que de esos tiernos labios, pronunciando cosas tan sublimemente sencillas, saldr\u00e1n palabras de fuego que consumir\u00e1n por completo todas sus tradiciones! Ese dulce joven, extraviado de Su madre, por Su vida tranquila y su lenguaje inocente, pronto expondr\u00e1 y derrocar\u00e1 el \u00faltimo vestigio de pretensiones y religi\u00f3n sacerdotal, y establecer\u00e1 una religi\u00f3n viva, vital con una energ\u00eda que vencer\u00e1 la muerte y la tumba. . Los rabinos han manipulado tanto el pergamino y murmurado tanto la carta, que no pueden entender el evangelio del Ni\u00f1o. \u00a1Cu\u00e1n a menudo se encuentra Cristo entre los sistemas y esquemas aprendidos de este mundo, desconocido e insospechado, porque es tan simple y discreto! (<em>Alexander Clark.<\/em>)<\/p>\n<\/p>\n<p><strong>Escuela Cristo en el Templo<\/strong><\/p>\n<p>No estaba en el en las partes m\u00e1s sagradas del Templo, ni en el Lugar Santo, ni aun en el Patio del Altar del Holocausto, que se hall\u00f3 nuestro Se\u00f1or. Hab\u00eda c\u00e1maras en los recintos del Templo, que a veces se usaban para las reuniones del Sanedr\u00edn, a veces como escuelas donde los doctores pod\u00edan ense\u00f1ar. Este \u00faltimo fue un arreglo muy apropiado: porque la formaci\u00f3n de j\u00f3venes en la Mand\u00edbula de Dios es una obra de piedad muy aceptable a Dios, y puede llevarse a cabo adecuadamente en la casa de oraci\u00f3n. Quiz\u00e1s nuestro Se\u00f1or, durante los ocho d\u00edas de la estad\u00eda de Sus padres en Jerusal\u00e9n, pudo haber sido atra\u00eddo por las escuelas en el Templo, y le gust\u00f3 quedarse all\u00ed y escuchar lo que estaba pasando. Y as\u00ed Sus padres pueden haber pensado en buscarlo en estas escuelas, sintiendo que, si es que estaba en Jerusal\u00e9n, \u00c9l estaba seguro de estar all\u00ed. Observemos que lo que lo atrajo al Templo no fue solo el hermoso y solemne culto que se desarrollaba en \u00e9l, sino la ense\u00f1anza que all\u00ed se impart\u00eda. Amaba no solo la oraci\u00f3n y la alabanza, sino tambi\u00e9n el aprendizaje. \u00a1Oh, que hubiera m\u00e1s ni\u00f1os como \u00c9l! mientras que hay algunos a quienes les gusta bastante el servicio de la Iglesia, si se lleva a cabo con majestuosidad y m\u00fasica, cu\u00e1n pocos son los que muestran un deseo de instrucci\u00f3n religiosa, que se complacen mucho en su preparaci\u00f3n para la confirmaci\u00f3n y escuchan los sermones con entusiasmo, tratando de sacar lo bueno que pueden de ellos. (<em>Dean Goulburn.<\/em>)<\/p>\n<\/p>\n<p><strong>El esp\u00edritu y el m\u00e9todo para aprender<\/strong><\/p>\n<p>Los j\u00f3venes debe estar ansioso por aprender, como lo estuvo Cristo en su ni\u00f1ez. <\/p>\n<p><strong>1.<\/strong> Mostr\u00f3 sed por el conocimiento de la ley de Dios, cuando ten\u00eda apenas doce a\u00f1os; y \u00bfc\u00f3mo vamos a juzgar de lo que est\u00e1 mal en nosotros, sino tom\u00e1ndolo a \u00c9l como nuestro modelo, y preguntando qu\u00e9 hay en nosotros, que no mira con Su ejemplo? As\u00ed como una regla aplicada a una l\u00ednea que hemos trazado con nuestra mano, muestra que no es recta, as\u00ed el ejemplo de nuestro Se\u00f1or, aplicado a cualquier conducta humana en particular, muestra de inmediato cu\u00e1n lejos est\u00e1 de ser lo que deber\u00eda ser. . <\/p>\n<p><strong>2.<\/strong> Nuestro Se\u00f1or se someti\u00f3 a aprender de los maestros designados de Su naci\u00f3n. Seguramente no es mucho lo que debe exigir de nosotros la sumisi\u00f3n a todos los que tienen autoridad sobre nosotros. <\/p>\n<p><strong>3.<\/strong> Vemos tambi\u00e9n que la mejor manera de aprender es que el alumno haga preguntas al profesor. Solo que sean preguntas bien pensadas. Nada abrir\u00e1 m\u00e1s la mente del ense\u00f1ado que la explicaci\u00f3n de una dificultad que ha surgido en la mente por algo que ha dicho el maestro. Muy a menudo, la pregunta tambi\u00e9n ser\u00e1 \u00fatil para el maestro, llev\u00e1ndolo a una l\u00ednea de pensamiento nueva e interesante sobre un tema antiguo y trillado. Las preguntas obligan a la gente a pensar. (<em>Dean Goulburn.<\/em>)<\/p>\n<\/p>\n<p><strong>Respuestas<\/strong><\/p>\n<p><strong><br \/>I. <\/strong>Cristo da una respuesta clara sobre el mundo espiritual. <\/p>\n<p><strong><br \/>II. <\/strong>Otro grito del alma es respondido por Jes\u00fas cuando nos dice que Dios es el Padre celestial de la humanidad. <\/p>\n<p><strong><br \/>III. <\/strong>El Se\u00f1or Jes\u00fas respondi\u00f3 a otra pregunta de la humanidad al mostrar que nuestro Padre celestial conoce la vida interior secreta de cada hombre. <\/p>\n<p><strong><br \/>IV. <\/strong>Jes\u00fas responde al clamor del alma dici\u00e9ndonos que la obra de nuestro Padre es la obra m\u00e1s alta de la humanidad. (<em>W. Abedul.<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lc 2,46 Despu\u00e9s de tres d\u00edas lo encontraron en el Templo El hallazgo de Jes\u00fas en el Templo I. Una lecci\u00f3n para los ni\u00f1os y j\u00f3venes: LA HOMBRE DE LA OBEDIENCIA Y LA SUJECI\u00d3N A LA MADRE. II. Los maestros pueden aprender EL MEJOR M\u00c9TODO PARA ADQUIRIR CONOCIMIENTO, haciendo y respondiendo preguntas. III. Este incidente &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-246-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Lucas 2:46 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39269","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=39269"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39269\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=39269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=39269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=39269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}