{"id":39286,"date":"2022-07-16T08:51:57","date_gmt":"2022-07-16T13:51:57","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-315-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:51:57","modified_gmt":"2022-07-16T13:51:57","slug":"estudio-biblico-de-lucas-315-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-315-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Lucas 3:15 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Lc 3:15<\/span><\/p>\n<p><em>Si \u00e9l fuera el Cristo o no<\/em><\/p>\n<p><strong>La actitud del Bautista hacia Cristo<\/strong><\/p>\n<p>Observe aqu\u00ed&#8211;<\/p>\n<p><strong>1. <\/strong><\/p>\n<p> C\u00f3mo lo extraordinario de la persona del Bautista, la seriedad de su predicaci\u00f3n, la aceptabilidad de su doctrina y la ejemplaridad de su conversaci\u00f3n, atrajeron a todas las personas a una admiraci\u00f3n por \u00e9l; tanto que empezaron a pensar dentro de s\u00ed mismos, si no ser\u00eda el mismo Mes\u00edas. Les dice claramente que no lo era, sino Su siervo, Su heraldo y precursor. <\/p>\n<p><strong>2.<\/strong> La alta opini\u00f3n que Juan ten\u00eda de Cristo. \u201c\u00c9l es m\u00e1s poderoso que yo\u201d;<em> es decir, <\/em>una persona de mayor autoridad, dignidad y excelencia que yo. <\/p>\n<p><strong>3.<\/strong> La humilde y baja estimaci\u00f3n que el Bautista ten\u00eda de s\u00ed mismo. \u201cLa correa de cuyo calzado no soy digno de desatar\u201d: un discurso proverbial, implicando que \u00e9l era indigno de hacer los oficios m\u00e1s bajos y los servicios m\u00e1s bajos para Cristo. \u00a1Cu\u00e1n bien la humildad mental, la humilde estimaci\u00f3n y la baja opini\u00f3n de s\u00ed mismos, llegan a ser los mensajeros y ministros de Cristo! <\/p>\n<p><strong>4.<\/strong> Juan no s\u00f3lo declara la dignidad de la persona de Cristo, sino la excelencia de su oficio. \u201c\u00c9l os bautizar\u00e1 con el <em>Esp\u00edritu Santo<\/em> y con fuego\u201d. Como si dijera, Yo s\u00f3lo lavo el cuerpo con agua, pero Cristo limpia el alma por la operaci\u00f3n de Su Esp\u00edritu Santo, que es como fuego en sus efectos, purificando del pecado los corazones de Su pueblo, y consumiendo sus lujurias y corrupciones. ; pero al mismo tiempo teniendo ira de fuego y juicios llameantes, para destruir y quemar a los pecadores impenitentes como hojarasca seca. Es observable en la Escritura, que Cristo es representado por una y la misma met\u00e1fora del fuego, en forma de consuelo para Sus hijos, y en forma de terror para Sus enemigos; \u00c9l es fuego para ambos. \u00c9l se sienta en los corazones de Su pueblo como fuego purificador; \u00c9l est\u00e1 entre Sus enemigos como un fuego consumidor: un fuego para que Su Iglesia se consuele, un fuego para que Sus enemigos perezcan. <\/p>\n<p><strong>5.<\/strong> El Bautista compara a Cristo con un labrador, ya la Iglesia jud\u00eda con el suelo de un granero; el oficio de un labrador es trillar, aventar y aventar Su grano, separ\u00e1ndolo de la paja, conservando uno y consumiendo el otro. <\/p>\n<p><strong>(1)<\/strong> La Iglesia es el piso de Cristo. <\/p>\n<p><strong>(2)<\/strong> Este piso Cristo lo limpiar\u00e1, y eso a fondo. <\/p>\n<p><strong>(3)<\/strong> La Palabra de Cristo es el abanico en Su mano, por y con el cual \u00c9l limpiar\u00e1 a fondo Su suelo. <\/p>\n<p>La Iglesia es comparada a una era, por la mezcla de buenos y malos en ella, santos y pecadores, hip\u00f3critas y cristianos sinceros, as\u00ed como en una era hay tanto paja como grano, la paja como el ma\u00edz, la ciza\u00f1a como el trigo, la ciza\u00f1a como la buena semilla. Pero Cristo limpiar\u00e1 Su Iglesia; l\u00edmpiala de sus corrupciones, sin destruir su esencia ni su existencia, por el abanico de Su Santa Palabra, acompa\u00f1ada del ala de la disciplina. (<em>W. Burkitt, MA<\/em>)<\/p>\n<\/p>\n<p><strong>Ning\u00fan verdadero maestro puede permitirse vivir de impresiones err\u00f3neas<\/strong><\/p>\n<p>La gente reflexionaba sobre si Juan era el Cristo o no. Un hombre irreal y ego\u00edsta habr\u00eda convertido esta duda en su propia cuenta. Esta fue la tentaci\u00f3n de Juan. Jes\u00fas fue tentado en una direcci\u00f3n y Juan en otra; pero en cada caso la tentaci\u00f3n fue directa y real. Todo ministerio debe ser tentado, al igual que todo cristiano. \u00bfAlguna vez has tenido la tentaci\u00f3n de considerarte a ti mismo como alguien grande? \u00bfNo has encubierto tu pobre y marchito nombre con la reputaci\u00f3n de hombres fuertes y brillantes? \u00bfNo ha recibido aplausos por las originalidades que usted tiene pero que cita de otros? La declaraci\u00f3n de Juan acerca de Cristo es muy notable. Nada dice de predicar el evangelio o de morir por los pecados del mundo, ni de la gran misi\u00f3n evang\u00e9lica; la declaraci\u00f3n se refiere \u00fanicamente al bautismo ya la discriminaci\u00f3n de car\u00e1cter. \u00a1Pero qu\u00e9 bautismo! \u00a1Y qu\u00e9 discriminaci\u00f3n! No puede haber error acerca de cualquier hombre que haya recibido el bautismo de fuego; el fuego lo iluminar\u00e1 o lo consumir\u00e1, de modo que ser\u00e1 una luz que brilla a lo lejos, o un alma quemada y est\u00e9ril que ha apagado el Esp\u00edritu. El bautismo por <em>agua <\/em>s\u00f3lo puede ser inicial o simb\u00f3lico; el bautismo <em>de fuego<\/em> es el gran testimonio de Dios para la purificaci\u00f3n y aceptaci\u00f3n del alma. Juan se\u00f1ala dos usos distintos del fuego: Jes\u00fas bautizar\u00e1 con fuego, y con fuego inextinguible quemar\u00e1 la paja. <\/p>\n<p>Esto es precisamente lo que hace el evangelio. Es sabor de vida para vida, o de muerte para muerte. (<em>J. Parker, DD<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lc 3:15 Si \u00e9l fuera el Cristo o no La actitud del Bautista hacia Cristo Observe aqu\u00ed&#8211; 1. C\u00f3mo lo extraordinario de la persona del Bautista, la seriedad de su predicaci\u00f3n, la aceptabilidad de su doctrina y la ejemplaridad de su conversaci\u00f3n, atrajeron a todas las personas a una admiraci\u00f3n por \u00e9l; tanto que empezaron &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-315-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Lucas 3:15 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39286","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=39286"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39286\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=39286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=39286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=39286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}