{"id":39291,"date":"2022-07-16T08:52:12","date_gmt":"2022-07-16T13:52:12","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-321-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:52:12","modified_gmt":"2022-07-16T13:52:12","slug":"estudio-biblico-de-lucas-321-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-321-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Lucas 3:21 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Lc 3,21<\/span><\/p>\n<p><em>Siendo tambi\u00e9n Jes\u00fas bautizados&#8211;<\/em><\/p>\n<p><strong>Encuentro de Jes\u00fas con Juan<\/strong><\/p>\n<p>La gente, le\u00ed, \u201creflexionaba\u201d, pregunt\u00e1ndose si Juan era el Mes\u00edas esperado. .<\/p>\n<p>John tambi\u00e9n, reflexion\u00f3, podemos estar seguros. \u00ab\u00a1Palabras! \u00a1palabras! \u00a1palabras!\u00bb al final de cada d\u00eda largo y bochornoso, mientras lo acostaba en alguna cueva rocosa, a qu\u00e9 hora el sol se hund\u00eda repentinamente y las estrellas colgaban como bolas de fuego en el cielo p\u00farpura, y se escuchaba el grito de la bestia salvaje mientras avanzaba sigilosamente. para beber en los vados del Jord\u00e1n. &#8216; Puedo bautizarlos con agua. Puedo decirles que se arrepientan. Pobres ovejas desamparadas sobre las monta\u00f1as, \u00bfd\u00f3nde encontrar\u00e1n a su pastor? Soy la voz que clama en el desierto: \u00bfd\u00f3nde est\u00e1 el Divino Profeta? Yo bautizo con agua, \u00bfqui\u00e9n les dar\u00e1 el bautismo de fuego del alma? \u00bfQui\u00e9n les ayudar\u00e1 a buscar y les animar\u00e1 a actuar? \u201cY luego vino Uno cierta ma\u00f1ana tranquila, temprano, tal vez, antes del calor del d\u00eda, con solo unos pocos celosos rezagados, esperando el bautismo, y Juan lo encontr\u00f3 junto al r\u00edo Jord\u00e1n. No hace falta explicar. Alma con alma. Juan conoc\u00eda a su Maestro con tanta certeza como lo hizo el fr\u00e1gil Pedro cuando grit\u00f3: \u201cAp\u00e1rtate de m\u00ed, que soy un hombre pecador\u201d; o dudar de Tom\u00e1s cuando, con el coraz\u00f3n destrozado, murmur\u00f3: \u201c\u00a1Se\u00f1or m\u00edo, y Dios m\u00edo!\u201d \u201cTengo necesidad,\u201d fueron las primeras palabras de Juan\u2014s\u00ed, todos tenemos necesidad cara a cara con Jes\u00fas\u2014\u201cTengo necesidad de ser bautizado por Ti.\u201d Y luego vinieron las primeras palabras del ministerio de Cristo, tocaron la nota clave del evangelio: \u201cDeja ahora, porque as\u00ed nos conviene cumplir toda justicia\u201d. El coraz\u00f3n del cristianismo est\u00e1 ah\u00ed; Cristo el Compa\u00f1ero del hombre, el Ejemplo del hombre. El Salvador, porque revelador de una uni\u00f3n divina entre Dios y el hombre, de una vida espiritual en el hombre. Y a la ma\u00f1ana siguiente el Bautista lo vio caminando junto al r\u00edo, y se\u00f1al\u00e1ndolo, exclam\u00f3: \u00ab\u00a1He aqu\u00ed el Cordero de Dios!\u00bb &amp;C. \u00a1Mensaje a las edades! \u00a1Llama a cada Peregrino de la noche! Ten buen \u00e1nimo, tu ayuda est\u00e1 cerca. Dios en Cristo es tu Salvador, porque Cristo en la naturaleza humana significa Cristo en ti, el poder divino revelado en cada hombre, en la medida en que es capaz de recibirlo y usarlo. Que esa visi\u00f3n permanezca con nosotros. Bendito resplandor de la luz de la ma\u00f1ana. Veo a Jes\u00fas descendiendo al Jord\u00e1n para ser bautizado, uno con nosotros, para no separarse nunca m\u00e1s de nosotros. \u00a1Gran Hermano Mayor, querido Amigo! Cerca de nosotros en las aguas de la purificaci\u00f3n, cerca de nosotros en la carga y el calor del d\u00eda, cerca de nosotros en la sombra de nuestro Getseman\u00ed, cerca de nosotros en el Calvario de nuestro dolor, el Cordero de Dios que quita los pecados del mundo. (<em>HR Haweis, MA<\/em>)<\/p>\n<\/p>\n<p><strong>Cristo y Juan<\/strong><\/p>\n<p>La relaci\u00f3n entre Jes\u00fas y Juan se asemeja a dos estrellas que se suceden a corta distancia, ambas pasando por circunstancias similares. El anuncio de la aparici\u00f3n de uno sigue de cerca al de la aparici\u00f3n del otro, lo mismo ocurre con sus dos nacimientos. Esta relaci\u00f3n se repite en el comienzo de sus respectivos ministerios; y, por \u00faltimo, en las cat\u00e1strofes que acaban con sus vidas. Y, sin embargo, en todo el curso de la carrera de estos dos, hubo un solo encuentro personal: en el bautismo de Jes\u00fas. Despu\u00e9s de este momento, cuando una de estas estrellas cruz\u00f3 r\u00e1pidamente la \u00f3rbita del \u00e9ter, se separaron, cada uno para seguir el camino que le hab\u00eda sido se\u00f1alado. (<em>F. Godet, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Jes\u00fas bautizado<\/strong><\/p>\n<p><strong><br \/>Yo. <\/strong>1. La predicaci\u00f3n de Juan el Bautista fue la se\u00f1al de que el ministerio activo del Mes\u00edas iba a comenzar ahora. El Verbo Encarnado hab\u00eda estado escondido entre los hombres. Ahora debe manifestarse Su presencia y establecerse Su reino. <\/p>\n<p><strong>2.<\/strong> Su primer acto al pasar de Su vida oculta a Su vida activa, es identificarse con esa raza pecadora a cuya semejanza hab\u00eda venido. <\/p>\n<p><strong>3.<\/strong> Esta humillaci\u00f3n fue temporal y voluntaria: \u201cD\u00e9jalo ahora\u201d, es decir, <em>, <\/em>\u201cpor ahora\u201d; \u201cporque as\u00ed nos conviene\u201d\u2014no \u201ces necesario\u201d\u2014\u201ccumplir toda justicia\u201d. <\/p>\n<p><strong>4.<\/strong> Observe c\u00f3mo Aquel que en Su ni\u00f1ez \u201cdebe estar en los negocios de Su Padre\u201d, en Su madurez debe \u201ccumplir con toda justicia\u201d. <\/p>\n<p><strong><br \/>II. <\/strong>1. Hay un sentido profundo en el que este experimentar el bautismo de Juan fue el cumplimiento de toda justicia. Fue una revelaci\u00f3n que la naturaleza del hombre necesita no solo mejorar sino tambi\u00e9n renovarse. El bautismo representa la muerte del hombre viejo y la resurrecci\u00f3n del nuevo. <\/p>\n<p><strong>2.<\/strong> Es para que \u00c9l, que as\u00ed se humill\u00f3 por nosotros, cumpla toda justicia en nosotros, por lo que oramos: \u201cPor tu bautismo,\u2026 buen Se\u00f1or, l\u00edbranos\u201d. (<em>Canon Vernon Hutton, MA<\/em>)<\/p>\n<\/p>\n<p><strong>El significado del bautismo de Cristo<\/strong><\/p>\n<p>Un prop\u00f3sito de Su bautismo lo menciona el mismo Se\u00f1or, para satisfacer los escr\u00fapulos del Bautista reacio; \u201cSufre ahora, porque as\u00ed nos conviene cumplir toda justicia\u201d. El primer y obvio sentido de esto es que, puesto que el bautismo de Juan era de Dios, le conven\u00eda, como nacido en el pueblo al que Dios lo hab\u00eda dado, someterse a \u00e9l como ordenanza de Dios. Pero entonces, podr\u00edan incluirse otros motivos en esto, como involucrados en el car\u00e1cter y la persona de Aquel que as\u00ed se someti\u00f3. Las palabras pueden haberse dejado, a prop\u00f3sito, sin definir, para comprender m\u00e1s. \u201c\u00c9l no a\u00f1adi\u00f3\u201d, dice San Jer\u00f3nimo, \u201cla justicia de la ley, o de la naturaleza, para que podamos entender ambas\u201d. La justicia cumplida fue en \u00c9l la humildad que sobrepasa todo pensamiento, en que siendo Dios \u00c9l recibi\u00f3 el bautismo de los pecadores cuya naturaleza \u00c9l hab\u00eda tomado; en \u00c9l fue amor, que es el cumplimiento de la ley, en cuanto recibi\u00f3 lo que no necesitaba, para que los que lo necesitan lo reciban con mayor alegr\u00eda; y as\u00ed tambi\u00e9n puede ser que \u00c9l fue bautizado, no s\u00f3lo para dar ejemplo de obediencia, o sanamente para avergonzar a aquellos que para su destrucci\u00f3n la hubieran despreciado, sino para cumplir en ella toda justicia, limpiando la naturaleza pecaminosa en la semejanza de la cual hab\u00eda venido, y para impartirle en su conjunto la justicia que despu\u00e9s deb\u00eda comunicar, uno por uno, a los que acudieran al bautismo que as\u00ed hab\u00eda consagrado. Y adem\u00e1s, toda la justicia puede haberse cumplido en \u00e9l, en el sentido de que se introdujo una justicia eterna y se consagr\u00f3 el elemento mediante el cual la eficacia justificadora de Su meritoria Cruz y Pasi\u00f3n deb\u00eda transmitirse a todos los creyentes. Un sentido no excluir\u00e1 al otro; como de todas las acciones y palabras de nuestro bendito Salvador, se debe creer que tienen una profundidad y un significado m\u00faltiples, de los cuales cada aplicaci\u00f3n saca a relucir solo una porci\u00f3n; estos dones son una \u201cpiedra preciosa\u201d, \u201cdondequiera que se vuelve, prospera\u201d. (<em>EBPusey, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Cristo someti\u00e9ndose al bautismo<\/strong><\/p>\n<p>Al presentarse para el bautismo, Jes\u00fas tuvo que hacer, como otros (<span class='bible'>Mat 3:6<\/span>; <span class='bible'> Mar 1:7<\/span>), Su confesi\u00f3n de pecados. \u00bfDe qu\u00e9 pecados, sino de los de su pueblo y del mundo en general? Puso ante Juan un cuadro impresionante de ellos, no con ese orgullo y desd\u00e9n con que los jud\u00edos hablaban de los pecados de los paganos, y los fariseos de los pecados de los publicanos, sino con el tono humilde y compasivo de un Isa\u00edas (cap. . 63.), un Daniel (cap. 9.), o un Nehem\u00edas (cap. 9.), cuando confesaron las miserias de su pueblo, como si la carga fuera suya. \u00c9l no podr\u00eda haber bajado al agua despu\u00e9s de tal acto de comuni\u00f3n con nuestra miseria, a menos que estuviera decidido a entregarse por completo a la obra de poner fin al reino del pecado. No se content\u00f3 con hacer un voto. Or\u00f3, nos dice el texto; Le rog\u00f3 a Dios todo lo que necesitaba para el cumplimiento de esta gran tarea, para quitar el pecado del mundo. Pidi\u00f3 sabidur\u00eda, fortaleza espiritual y, en particular, la soluci\u00f3n del misterio que los registros familiares, las Escrituras y su propia santidad hab\u00edan creado sobre su persona. Podemos entender c\u00f3mo Juan, despu\u00e9s de o\u00edrle confesar y orar as\u00ed, dijera: \u201c\u00a1He aqu\u00ed el Cordero de Dios, que quita el pecado del mundo!<em>\u201d <\/em>(<em>F. Godet, DD <\/em>)<\/p>\n<\/p>\n<p><strong>El bautismo de Cristo da virtud al nuestro<\/strong><\/p>\n<p>Su \u00faltima acci\u00f3n, o m\u00e1s bien pasi\u00f3n, fue Su bautismo con sangre; El primero fue Su bautismo con agua: ambos limpian al mundo de sus pecados. S\u00ed, este \u00faltimo no s\u00f3lo lav\u00f3 las almas de los hombres, sino que lava esa misma agua por la cual somos lavados; de aqu\u00ed es que es hecho tanto limpio como santo, y puede tanto limpiarnos como santificarnos. (<em>Bishop Hall.<\/em>)<\/p>\n<\/p>\n<p><strong>La escena del bautismo de Cristo<\/strong><\/p>\n<p>Un r\u00edo que nunca hab\u00eda sido navegable, desembocando en un mar que nunca hab\u00eda conocido un puerto? Un r\u00edo casi igual en longitud a nuestro propio T\u00e1mesis, pero sin una gran ciudad reunida en sus orillas, y serpenteando a trav\u00e9s de un paisaje grandioso o pintoresco. Tal era el r\u00edo de Dios, del cual cantaba el salmista hebreo; el r\u00edo sagrado de la historia del Antiguo Testamento, sobre el cual Lot, el emigrante errante, una vez alz\u00f3 sus ojos; la cual Jacob, volviendo del exilio, atraves\u00f3 con su vara, y por la cual hab\u00edan pasado los descendientes de los doce hijos del patriarca, una naci\u00f3n poderosa, emancipada y tra\u00edda de lejos para heredar la tierra. Desde entonces, a lo largo de sus costas hab\u00eda rodado la marea de muchas batallas trascendentales; sus aguas hab\u00edan limpiado al leproso; y entre sus adelfas rosadas y cal\u00e9ndulas amarillas, los profetas se hab\u00edan demorado en meditar, o escuchado a medianoche mensajes del cielo que les erizaba la piel. Fue mientras estaba parado en su borde que El\u00edas, el jefe de una l\u00ednea ilustre, hab\u00eda sido arrastrado en el carro del torbellino; y por el sonido de sus olas, David, el pr\u00edncipe de los reyes, hab\u00eda tronado en la lucha victoriosa, y llorado en la miseria. Pero ahora, por fin, hay algo nuevo, algo sorprendente. En uno de los vados superiores de este antiguo r\u00edo, aparece el Redentor del mundo: no obrando obras maravillosas, ni atrayendo multitudes a su alrededor por la magia de sus palabras llenas de gracia, sino d\u00f3cilmente solicitando recibir de manos del predicador reformador del d\u00eda, que hab\u00eda estado declarando a la naci\u00f3n moralmente impura, y llam\u00e1ndola al arrepentimiento, un rito sumamente humillante; un rito que se entend\u00eda para expresar la convicci\u00f3n de pecado del receptor y su necesidad de purificaci\u00f3n. (<em>NR Wood.<\/em>)<\/p>\n<\/p>\n<p><strong>El bautismo de Cristo<\/strong><\/p>\n<p>Hay una cosa para nosotros para recordar, en conclusi\u00f3n: a saber, que el bautismo que San Juan predic\u00f3, pero que vacil\u00f3 en administrar al inmaculado y santo Jes\u00fas, tuvo su significado m\u00e1s plenamente expresado solo cuando se le administr\u00f3 a \u00c9l; porque \u00bfqu\u00e9 pretend\u00eda exponer? \u00a1La carga consciente de pecado de la naci\u00f3n! \u00bfY qui\u00e9n, de todas las multitudes que acud\u00edan para ser bautizados, sinti\u00f3 esa carga como Cristo? Algunos hubo, sin duda, entre la multitud, que lloraron verdadera y profundamente sus transgresiones y las transgresiones de la \u00e9poca; hombres devotos, como el canoso Sime\u00f3n, que hac\u00eda mucho tiempo que no estaba satisfecho consigo mismo y con el estado de cosas existente; pero ninguno, ni siquiera de los m\u00e1s profundamente conmovidos y vivificados, sinti\u00f3 la fealdad y el horror de sus pecados y de la corrupci\u00f3n de Israel, como \u00c9l la sinti\u00f3. No s\u00f3lo confes\u00f3 y se arrepinti\u00f3 <em>con <\/em>el pueblo, sino <em>por <\/em>ellos; sufriendo en Su alma justa lo que deber\u00edan haber sufrido, y no sufrieron, es m\u00e1s, no pudieron; ofreciendo a Dios lo que deber\u00edan haber ofrecido, y no ofrecieron, es m\u00e1s, no pudieron ofrecer: un sentimiento adecuado de pecado, un dolor adecuado y expiaci\u00f3n por \u00e9l. Verdaderamente se confesaron y se arrepintieron s\u00f3lo en \u00c9l; en \u00c9l se present\u00f3 la confesi\u00f3n y el arrepentimiento perfectos, de los cuales, en su mejor momento, se quedaron cortos. (<em>NR Wood.<\/em>)<\/p>\n<\/p>\n<p><strong>El bautismo de Juan alcanz\u00f3 su m\u00e1xima expresi\u00f3n en la sumisi\u00f3n de Cristo a \u00e9l<\/strong><\/p>\n<p>Ver a la madre, en medio de un grupo de peque\u00f1os, mezclando sus l\u00e1grimas con las de ellos, en la tumba del padre. Sienten que han perdido algo precioso; pero es ella sola la que siente, inclinada entre ellos, cu\u00e1nto han perdido. Todos se arrodillan juntos en el suelo, y los ojos de todos est\u00e1n igualmente llenos de dolor: pero \u00bfcu\u00e1l es su impresi\u00f3n del duelo que han sufrido, en comparaci\u00f3n con la de ella? \u00bfCu\u00e1l es la angustia de ellos por ellos mismos, en comparaci\u00f3n con la angustia de ella por los hu\u00e9rfanos? Por mucho que lloren los ni\u00f1os, toda la amargura de su p\u00e9rdida la soportan, no los ni\u00f1os, sino la madre que llora con ellos. As\u00ed que cuando Cristo se uni\u00f3 a la multitud en su bautismo de contrici\u00f3n, ninguno de ellos tuvo sus pecados ni la mitad de pesados y opresivos que lo fueron para \u00e9l; ninguno de ellos soport\u00f3, bajo sus m\u00e1s profundas convicciones, la mitad de lo que \u00c9l soport\u00f3 por ellos. El significado del bautismo de San Juan alcanz\u00f3 su m\u00e1xima expresi\u00f3n en <em>Su <\/em>sumisi\u00f3n a \u00e9l, sobre quien fue cargada la iniquidad de todos; quien, siendo a la vez el que no tiene pecado y el que ama, vio los pecados ya los pecadores con los ojos de Dios, y sinti\u00f3, en referencia a ellos, con el coraz\u00f3n de Dios. (<em>NR Wood.<\/em>)<\/p>\n<\/p>\n<p><strong>El bautismo de Jes\u00fas<\/strong><\/p>\n<p>El grito de Juan Bautista fue: arrepentirse; y su bautismo fue el de arrepentimiento. Entonces, \u00bfcu\u00e1l fue el significado del bautismo de nuestro Se\u00f1or? No pod\u00eda significar que \u00c9l se arrepinti\u00f3. Fue un acto simb\u00f3lico seguido por aquello de lo cual era el s\u00edmbolo: el bautismo del Esp\u00edritu Santo. Aprender&#8211;<\/p>\n<p><strong><br \/>I. <\/strong>LA IMPORTANCIA DE LA ORDENANZA DEL BAUTISMO. Aquello a lo que se someti\u00f3 nuestro Se\u00f1or no puede ser considerado indiferente por ninguno de sus disc\u00edpulos. <\/p>\n<p><strong><br \/>II. <\/strong>ORDENANZAS ESTABLECIDAS POR DIOS, SOMETIDAS CON REVERENCIA E INTELIGENCIA, A MENUDO SON LOS CANALES DE BENDICI\u00d3N. \u201cSiendo bautizados y orando, se abri\u00f3 el cielo\u201d, etc. Los ritos realizados de manera poco inteligente o supersticiosa a menudo ocultan la verdad y conducen a un error peligroso; pero cuando se entiende que simbolizan o declaran una verdad viva, a menudo son ayudas importantes para ense\u00f1ar la verdad y para estimular la adquisici\u00f3n de bendiciones espirituales. (<em>D. Longwill.<\/em>)<\/p>\n<\/p>\n<p><strong>El bautismo de Cristo<\/strong><\/p>\n<p>Era&#8211;<\/p>\n<p><strong><br \/>Yo. <\/strong>LA PROCLAMACI\u00d3N DE SU RELACI\u00d3N HUMANA CON EL HOMBRE Y CON DIOS. <\/p>\n<p><strong><br \/>II. <\/strong>Por este acto vincul\u00f3 en sumisi\u00f3n a la VOLUNTAD DE SU PADRE LAS DISPENSACIONES ANTIGUAS Y LAS NUEVAS, Y SE RECONOCI\u00d3 A S\u00cd MISMO COMO EL PUNTO CENTRAL DE LA HISTORIA. <\/p>\n<p><strong><br \/>III. <\/strong>LE CONSAGRA\u00d3 REY DEL REINO TEOCR\u00c1TICO, Y PROCLAM\u00d3 A TODOS LOS HOMBRES QUE HAB\u00cdA COMENZADO SU ORGANIZACI\u00d3N DE ESE REINO. <\/p>\n<p><strong><br \/>IV. <\/strong>\u00bfC\u00d3MO NOS HABLA EL BAUTISMO DE CRISTO? Tenemos ritos de consagraci\u00f3n, pero estos no son los paralelos en nuestras vidas a este momento en la vida de Jes\u00fas. Hay horas de consagraci\u00f3n en nuestras vidas de las que nadie sabe sino Dios y nosotros mismos. (<em>Stopford A. Brooke, MA<\/em>)<\/p>\n<\/p>\n<p><strong>La inauguraci\u00f3n<\/strong><\/p>\n<p>El ejemplo de Cristo muestra que la obediencia al Esp\u00edritu Divino de la \u00e9poca siempre trae revelaciones y testimonios m\u00e1s completos de la bendici\u00f3n Divina. Los cielos se abren a todo hombre obediente, y el Esp\u00edritu de Dios desciende sobre los \u00faltimos como sobre los primeros. El bautismo de Juan no hab\u00eda ido m\u00e1s all\u00e1 del arrepentimiento; pero Cristo, de pie con la paloma posada sobre \u00c9l, mostr\u00f3 que hab\u00eda un bautismo para la santidad. Por el bautismo de Juan, los hombres fueron puestos en una relaci\u00f3n correcta con el pasado: pero a medida que siguieron a Cristo, fueron puestos en una relaci\u00f3n correcta con el futuro; de la condici\u00f3n negativa de arrepentimiento pasaron a la actitud afirmativa de santidad. Esta es la culminaci\u00f3n de la historia humana. Hemos venido a trav\u00e9s de hombre, siervo, profeta, mensajero, hasta <em>Hijo. <\/em>La misma nomenclatura est\u00e1 pre\u00f1ada de un significado moral sublime. Pasamos de \u201checho\u201d a \u201cengendrado\u201d, de \u201crecto\u201d a \u201camado\u201d, del \u201cnosotros\u201d de la Trinidad creadora al \u201cm\u00edo\u201d del Padre benigno, del \u201cmuy bueno\u201d del primer Ad\u00e1n al \u201cbien complacido\u201d del segundo. (<em>J. Parker, DD<\/em>)<\/p>\n<\/p>\n<p><strong>La inauguraci\u00f3n de Cristo<\/strong><\/p>\n<p><em>La <\/em>el bautismo de Cristo fue, ante todo, el anuncio p\u00fablico y la inauguraci\u00f3n de Cristo a su obra. Juan el Bautista se hab\u00eda propuesto \u201cdar testimonio de la Luz\u201d, y ahora su obra estaba casi terminada. Quedaba por hacer un \u00faltimo acto, la solemne separaci\u00f3n de Cristo para su obra redentora. El bautismo cerr\u00f3 la vida privada de nuestro Se\u00f1or y comenz\u00f3 Su ministerio p\u00fablico. El que hab\u00eda descendido al agua conocida por los hombres como \u201cel Hijo de Mar\u00eda\u201d, subi\u00f3 declarado \u201cel Hijo de Dios\u201d, <\/p>\n<p>El bautismo, con los cielos abiertos, y el Esp\u00edritu descendiendo como una paloma, y permaneciendo en Jes\u00fas, y el testimonio dado por la voz de Dios mismo, fue la sublime inauguraci\u00f3n del Salvador del mundo a Su gran misi\u00f3n. A partir de esa hora se hizo la obra prof\u00e9tica de Juan. Expir\u00f3, para usar la hermosa imagen de Davison, como hab\u00eda expirado la profec\u00eda del Antiguo Testamento, con \u201cel evangelio en su lengua\u201d. (<em>GS Barrett, BA<\/em>)<\/p>\n<\/p>\n<p><strong>La gente fue bautizada<\/strong><\/p>\n<p>Hay muchos de cada clase de personas\u2014como podemos leer\u2014salvadas en el evangelio, pero de los fariseos no encontramos sino uno, a saber, Nicodemo; ning\u00fan tipo de hombre est\u00e1 m\u00e1s lejos del reino de Dios que los orgullosos justicieros. Porque como un vaso lleno de un licor no es capaz de otro, as\u00ed el alma que est\u00e1 llena de una vana vanidad de su propia justicia, no es capaz de la gracia de Cristo. La gracia no entra en tal alma, porque est\u00e1 llena, ni la gracia encuentra lugar para morar en ella. No hay lugar para que entre la gracia, donde el m\u00e9rito tiene posesi\u00f3n: lo que t\u00fa atribuyes a los m\u00e9ritos, es faltar a la gracia. No quiero nada de ese m\u00e9rito que excluye la gracia. (<em>Obispo Cowper.<\/em>)<\/p>\n<\/p>\n<p><strong>El bautismo de Cristo<\/strong><\/p>\n<p><strong>1.<\/strong> Por la presente \u00c9l honrar\u00eda el ministerio del hombre, en el sentido de que \u00c9l mismo se somete a \u00e9l y lo busca con mucho dolor y trabajo. <\/p>\n<p><strong>2.<\/strong> Como fue bautizado, no por un \u00e1ngel o pr\u00edncipe, sino por un hombre sencillo que viv\u00eda como un ermita\u00f1o en una forma de vida austera en cuanto a alimentaci\u00f3n y vestido; as\u00ed no debemos considerar m\u00e1s bajos de los sacramentos por la mezquindad del hombre, si un ministro leg\u00edtimo, viendo que Cristo no rechaz\u00f3 el sacramento de manos de Juan; tampoco debemos del ministro m\u00e1s humilde, viendo que el m\u00e1s peque\u00f1o en el reino de Dios es mayor que Juan. <\/p>\n<p><strong>3.<\/strong> Cristo se content\u00f3 con lavarse en un agua com\u00fan, en el torrente del Jord\u00e1n; No tem\u00eda infecci\u00f3n de ella, aunque all\u00ed lavaran a Naam\u00e1n el leproso; aunque los fariseos y los hip\u00f3critas se lavaran all\u00ed: sin embargo, \u00c9l no hace excepci\u00f3n, no contrae inmundicia; as\u00ed la maldad de otro comulgante no perjudica al que est\u00e1 bien preparado, aunque comulgue con \u00e9l en el sacramento, pero no en su pecado. Aunque no asumi\u00f3 el sacramento como un sacramento de regeneraci\u00f3n, o como un s\u00edmbolo de nueva vida, sin embargo, s\u00ed&#8211;<\/p>\n<p><strong>(1)<\/strong> Como era un sacramento de la sociedad cristiana (<span class='bible'>1Co 12:13<\/span>), porque as\u00ed como por ella los fieles son puestos en su cuerpo, as\u00ed tambi\u00e9n \u00c9l por ella ser\u00e1 puesto en el cuerpo de los santos, y toma sobre s\u00ed la marca com\u00fan y el privilegio de sus miembros; as\u00ed como vemos reyes y pr\u00edncipes, por quienes todos tienen su libertad, a veces ser\u00e1n liberados, y as\u00ed recibir\u00e1n un testimonio p\u00fablico de asociaci\u00f3n de su pueblo; y he aqu\u00ed, aqu\u00ed nuestro Pr\u00edncipe con los colores de un soldado raso. <\/p>\n<p><strong>(2)<\/strong> Como el bautismo es un s\u00edmbolo de aflicci\u00f3n, \u00c9l lo emprender\u00eda; entonces <span class='bible'>Mar 10:38<\/span>) Cristo llama a su cruz y muerte con el nombre de bautismo. <\/p>\n<p><strong>(3) Cristo ser\u00eda bautizado, no para lavarse a s\u00ed mismo, sino a nosotros; no para despojarnos del pecado como nosotros, sino para revestirnos de nuestro pecado, para que nuestro pecado en \u00c9l sea lavado, para que \u00c9l pueda santificar este sacramento. De nuevo, esto es para nuestra instrucci\u00f3n, para notar la excelencia y dignidad de este sacramento, y en qu\u00e9 estima debemos tenerlo; el Se\u00f1or le viene al siervo un fatigoso camino para buscarlo; sin embargo, muchos de nosotros, cuando se nos presenta, le damos la espalda. \u00bfQu\u00e9 precio le ponen los que huyen de la Iglesia cuando se ha de administrar este sacramento? \u00bfCristo, que no lo necesitaba, vendr\u00e1 a \u00e9l, y nosotros, los que lo necesitamos, huiremos de \u00e9l? Esto agregar\u00e9 a lo que he dicho en otra parte en gran parte, que cualquiera que no se presente con la debida reverencia y meditaci\u00f3n, sino que salga descuidada y profanamente cuando se administra el bautismo, est\u00e1 lejos del ejemplo de Cristo, y poco consuelo pueden tener de su bautismo, pero bien pueden temer, que aquellos misterios y beneficios ofrecidos y sellados a un miembro de la congregaci\u00f3n no les pertenezcan; porque si lo hicieran, los reconocer\u00edan y no huir\u00edan de ellos con desd\u00e9n; tan bueno nunca bautizado, como nunca meditar en ello. Pero, si t\u00fa mismo no tomaras ning\u00fan bien por el sacramento, al recordar tu propio pacto hecho en el bautismo, con el fruto en ti, sin embargo, el buen orden requiere tu presencia. <\/p>\n<p><strong>1.<\/strong> Porque la ordenanza pertenece no s\u00f3lo a los padres y fiadores de los infantes, sino a toda la congregaci\u00f3n, as\u00ed como la entrada de un hombre libre en una corporaci\u00f3n es por toda la . <\/p>\n<p><strong>2.<\/strong> Dios mira que debe ser agraciado, y no despreciado d\u00e1ndole la espalda. \u00bfNo ser\u00eda un desprecio de lo m\u00e1s irreverente quedarse sin la Palabra? \u00bfY no es tambi\u00e9n huir del sello? especialmente la Sant\u00edsima Trinidad siendo reunida con tal prop\u00f3sito, para sellar tales beneficios a un miembro de esa congregaci\u00f3n? <\/p>\n<p><strong>3.<\/strong> Tu presencia es necesaria para ayudar al infante con la oraci\u00f3n, para unirse a la congregaci\u00f3n en oraci\u00f3n y en alabanza por el injerto de un miembro en el cuerpo de Cristo. Pero, \u00bfqu\u00e9 ley u ordenanza hab\u00eda para el bautismo, a la cual Cristo deb\u00eda estar sujeto? <\/p>\n<p>Fue decretado por toda la Trinidad. <\/p>\n<p><strong>1.<\/strong> Que Cristo debe ser iniciado por esta ceremonia, en la cual tambi\u00e9n debe manifestarse como Autor de toda pureza y limpieza. <\/p>\n<p><strong>2.<\/strong> Juan lo hab\u00eda predicado, y mostr\u00f3 la necesidad de ello por autoridad divina. <\/p>\n<p><strong>3.<\/strong> No s\u00f3lo se someter\u00eda a la ordenaci\u00f3n de Su Padre, sino tambi\u00e9n por nosotros, cuya virtud de bautismo depende del Suyo, as\u00ed como tambi\u00e9n nos ayudar\u00eda con Su ejemplo. , y por lo tanto \u00c9l mismo har\u00eda lo que \u00c9l orden\u00f3 a otros que hicieran. <\/p>\n<p><strong>4.<\/strong> Cristo como Mediador, y en nuestro lugar, deb\u00eda ser nuestra justicia <span class='bible'>1Co 1: 30<\/span>); tres maneras: <\/p>\n<p><strong>(1)<\/strong> Al ser hecho una ofrenda por nosotros, por la cual \u00c9l deb\u00eda abolir nuestro pecado y maldici\u00f3n, y por Su perfecta obediencia satisfacer toda la ley para a nosotros. <\/p>\n<p><strong>(2)<\/strong> Al aplicar esa justicia comprada por Su sangre, de la cual nunca hubi\u00e9ramos podido beneficiarnos. <\/p>\n<p><strong>(3)<\/strong> Al designar y santificar medios e instrumentos para esa aplicaci\u00f3n, llamada ministerio del Esp\u00edritu, del cual una rama es la fuente de agua en la Palabra. Y as\u00ed, como en nuestro lugar, se mantuvo en general, obligado por la voluntad y ordenanza de Dios, en S\u00ed mismo a santificar el bautismo por nosotros. (<em>T. Taylor, DD<\/em>)<\/p>\n<\/p>\n<p><strong>El bautismo de Cristo<\/strong><\/p>\n<p><strong><br \/>I. <\/strong>St. Mateo nos da LA RAZ\u00d3N POR LA QUE TUVO LUGAR ESTE BAUTISMO. \u201cD\u00e9jalo ahora\u201d, le dijo a Juan, \u201cporque as\u00ed nos conviene cumplir toda justicia\u201d. Estaba ansioso por obedecer todas las leyes divinas, por conformarse a todas las instituciones divinas, por trabajar y completar una justicia tan amplia como los mandatos divinos. Y esta respuesta nos muestra al Salvador en dos personajes, cada uno de los cuales ilustra la propiedad de Su bautismo. <\/p>\n<p><strong>1.<\/strong> \u00c9l est\u00e1 aqu\u00ed como el Representante de Su pueblo. Ahora son un pueblo inmundo. Argumentamos a partir de Su aparici\u00f3n en la forma de ellos, que \u00c9l era el Representante de Su pueblo pecador; y luego argumentamos que \u00c9l es su Representante, que le conven\u00eda ser bautizado. <\/p>\n<p><strong>2.<\/strong> \u00c9l era tambi\u00e9n su Cabeza; estando en la relaci\u00f3n con ellos de un L\u00edder o Jefe. El Capit\u00e1n de nuestra salvaci\u00f3n se viste con el atuendo con el que viste a Sus soldados. El Comandante se somete primero al juramento que impone a Sus seguidores. <\/p>\n<p><strong><br \/>II. <\/strong>Veamos ahora Su BAUTISMO MISMO. <\/p>\n<p><strong>1.<\/strong> La primera circunstancia que nos llama la atenci\u00f3n en ella, es su simple obediencia a la ley divina. Te pide que obedezcas la ley Divina, no que la escanees. Te pide que hagas la voluntad de Dios, no que la critiques. Se debe hacer la voluntad de Dios y obedecer cada mandato de Dios. <\/p>\n<p><strong>2.<\/strong> Y noten la humildad manifestada aqu\u00ed, la asombrosa condescendencia de Cristo. Ahora estaba apareciendo entre los hombres para dar a conocer sus altas pretensiones. \u00bfY c\u00f3mo aparece \u00c9l? \u00bfObrando milagros y haciendo prodigios? \u00bfBrillando como el sol en su resplandor, \u201cglorioso en su vestido, viajando en la grandeza de su fuerza\u201d? No; \u201c\u00c9l vino de Galilea al Jord\u00e1n a Juan para ser bautizado por \u00e9l\u201d. Dif\u00edcilmente podemos formarnos una vaga idea del alcance de esta degradaci\u00f3n. No un pecador en verdad, pero apareciendo como uno, asumiendo un car\u00e1cter que \u00c9l hab\u00eda ordenado que los \u00e1ngeles y los arc\u00e1ngeles aborrecieran. El pesebre, el establo, la caba\u00f1a del carpintero y el trabajo del carpintero, todo era como nada; ninguna palabra suya hab\u00eda derramado desprecio sobre ninguno de ellos: sino ser la cosa que \u00c9l hab\u00eda marcado; salir a la vista como si fuera el personaje que aborrec\u00eda; en verdad, hermanos, esta fue la infinita humillaci\u00f3n de un Dios infinito. <\/p>\n<p><strong>3.<\/strong> Y f\u00edjate tambi\u00e9n en la devoci\u00f3n que el Salvador manifest\u00f3 en esta ocasi\u00f3n. <\/p>\n<p><strong><br \/>III. <\/strong>Llegamos ahora a nuestro tercer tema: EL MARAVILLOSO ACONTECIMIENTO QUE ASISTE A LA ESCENA DE LA HUMILLACI\u00d3N QUE HEMOS CONTEMPLADO. \u201cAconteci\u00f3\u201d, dice el evangelista, \u201cque siendo bautizado tambi\u00e9n Jes\u00fas y orando, se abri\u00f3 el cielo, y descendi\u00f3 sobre \u00e9l el Esp\u00edritu Santo en forma corporal, como paloma, y vino una voz del cielo, que dec\u00eda: T\u00fa eres Mi Hijo amado; en Ti tengo complacencia.\u201d <\/p>\n<p><strong>1.<\/strong> Obs\u00e9rvese aqu\u00ed la grandeza de Cristo; Su dignidad. Y es un hecho notable que a lo largo de Su vida, cada vez que lo vemos humillado de manera notable, generalmente vemos a Su Padre poni\u00e9ndole un honor se\u00f1alado. Nace en un pesebre, pero una estrella en los cielos anuncia su advenimiento, y sobre \u00c9l resuenan los c\u00e1nticos de los \u00e1ngeles. <\/p>\n<p><strong>2.<\/strong> Vemos aqu\u00ed tambi\u00e9n el Mesianismo de Cristo. Primero viene la voz de la profec\u00eda, se\u00f1alando al futuro Mes\u00edas como uno sobre quien el Esp\u00edritu del Se\u00f1or descender\u00eda y reposar\u00eda; uno que, al entrar en Su oficio, deb\u00eda ser ungido con el esp\u00edritu, as\u00ed como los monarcas y sacerdotes terrenales eran ungidos con el aceite santo. Adem\u00e1s, en todo esto hab\u00eda una referencia especial al mismo Juan. <\/p>\n<p><strong>3.<\/strong> Pero este evento establece otro punto. Mientras prueba la realidad del Mesianismo de nuestro Se\u00f1or, declara Sus calificaciones para el desempe\u00f1o de este oficio. El Esp\u00edritu descendi\u00f3 sobre \u00c9l en el Jord\u00e1n para calificarlo para lo que podemos llamar la parte moral de Su gran obra; para permitirle llegar a la mente del hombre, influenciarla y gobernarla. \u00c9l mismo nos lo dice. Guiado por el Esp\u00edritu que hab\u00eda recibido, va primero al desierto para poner a prueba su propia fe y obediencia; y cuando Su propia experiencia le ense\u00f1\u00f3 all\u00ed lo que este Esp\u00edritu pod\u00eda hacer por los que sufr\u00edan y eran tentados, comienza Su ministerio p\u00fablico en Nazaret declarando las calificaciones que se le otorgan para el desempe\u00f1o de Su oficio. \u201cEl Esp\u00edritu del Se\u00f1or\u201d, dice, \u201cest\u00e1 sobre m\u00ed, por cuanto me ha ungido para predicar el evangelio a los pobres; Me ha enviado a sanar a los quebrantados de coraz\u00f3n, a predicar liberaci\u00f3n a los cautivos, y vista a los ciegos; para poner en libertad a los heridos.\u201d Y este Esp\u00edritu repos\u00f3 en \u00c9l. San <\/p>\n<p>Mateo nos informa que la paloma \u201cdescans\u00f3\u201d, as\u00ed como tambi\u00e9n descendi\u00f3 sobre \u00c9l; y San Lucas habla de \u00c9l subiendo del r\u00edo al desierto, \u201clleno del Esp\u00edritu Santo\u201d. Sus benditos dones le son entregados, puestos a Su disposici\u00f3n; y con este fin, para que los comunique a quien quiera. <\/p>\n<p><strong>4.<\/strong> Tambi\u00e9n se nos ense\u00f1a aqu\u00ed la alta estima en que Su Padre tiene al Salvador ungido; la complacencia y el deleite con que lo mira. De un repaso de esta historia aprendemos, primero, la importancia que Dios le da a sus propias ordenanzas, el honor que les da. \u201cVemos aqu\u00ed tambi\u00e9n la insuficiencia de las ordenanzas. El bautismo, aunque administrado por un profeta y recibido por Cristo, carec\u00eda de poder; o si tuvo alguna eficacia, esa eficacia fue limitada; evidentemente dej\u00f3 mucho sin hacer. No pudo tocar el alma de Jes\u00fas; no lo calific\u00f3 para su obra mediadora. Para lograr estos fines, el Esp\u00edritu Santo desciende de lo alto, descansa y permanece sobre \u00c9l. (<em>C. Bradley, MA<\/em>)<\/p>\n<\/p>\n<p><strong>Y orando. <\/strong><\/p>\n<p><strong>Cristo orando<\/strong><\/p>\n<p>Para la mayor\u00eda, si no para todos nosotros, el hecho de que nuestro Salvador or\u00f3 es en s\u00ed mismo una maravilla. Sin embargo, esto no parece haber impresionado a los escritores de los evangelios. Oraciones de Cristo preciosas, como mostrando cu\u00e1n completamente humano se hizo, viviendo como nosotros, una vida de dependencia, de comuni\u00f3n y de sumisi\u00f3n. <\/p>\n<p><strong><br \/>Yo. <\/strong>LA OCASI\u00d3N EN QUE EL SALVADOR HA DICHO HABER ORADO. COMO experimentado por Cristo, el rito del bautismo parece haber tenido un doble significado. <\/p>\n<p><strong>1.<\/strong> Ten\u00eda la intenci\u00f3n de ser un s\u00edmbolo de su total unidad con la raza que vino a salvar. <\/p>\n<p><strong>2.<\/strong> Ten\u00eda la intenci\u00f3n de ser emblem\u00e1tico de su completa consagraci\u00f3n a la salvaci\u00f3n de la raza a la que vino. <\/p>\n<p><strong><br \/>II. <\/strong>LAS RAZONES QUE LO LLEVARON A ORAR. <\/p>\n<p><strong>1.<\/strong> No debemos suponer que la oraci\u00f3n de Cristo en esta ocasi\u00f3n <\/p>\n<p><strong>(a)<\/strong> surgi\u00f3 de alguna duda en Su mente en cuanto a la propiedad de la obra en la que estaba entrando;<\/p>\n<p><strong>(b)<\/strong> surgieron de cualquier duda en cuanto a su propia designaci\u00f3n para ella; <\/p>\n<p><strong>(c)<\/strong> se debi\u00f3 a cualquier incertidumbre en cuanto a Su idoneidad personal para ello. No, pero&#8211;<\/p>\n<p><strong>2.<\/strong> Teniendo en cuenta el significado del bautismo con el que se asoci\u00f3 Su oraci\u00f3n, podemos imaginar que Su oraci\u00f3n en esta ocasi\u00f3n brotar\u00eda&#8211;<\/p>\n<p><strong>(a)<\/strong> de su pura pasi\u00f3n por la glorificaci\u00f3n del Padre; <\/p>\n<p><strong>(b)<\/strong> de su intenso anhelo por la salvaci\u00f3n del mundo; <\/p>\n<p><strong>(c)<\/strong> de Su v\u00edvida anticipaci\u00f3n de las dificultades que se avecinaban; <\/p>\n<p><strong>(d)<\/strong> de Su aguda previsi\u00f3n de los dolores que le esperaban. <\/p>\n<p><strong><br \/>III. <\/strong>LA RESPUESTA QUE LLEG\u00d3 A LA ORACI\u00d3N DE NUESTRO SALVADOR. <\/p>\n<p><strong>1.<\/strong> Hubo una comunicaci\u00f3n especial del Esp\u00edritu Divino. <\/p>\n<p><strong>2.<\/strong> Hab\u00eda una seguridad especial de la complacencia Divina. Lecci\u00f3n pr\u00e1ctica: LA ORACI\u00d3N PREPARACI\u00d3N AL SERVICIO. (<em>B. Wilkinson, FGS<\/em>)<\/p>\n<\/p>\n<p>Porque el primero, ya fue bautizado, y respecto a eso or\u00f3, y nos ense\u00f1a: <\/p>\n<p><strong>1.<\/strong> En cuanto \u00c9l primero fue bautizado, y luego or\u00f3, que primero debemos ser limpiados y santificados, y luego orar: los hombres deben levantar manos puras con corazones puros en cada lugar (<span class='bible'>Isa 1:16<\/span>). Al recibir el sacramento, un coraz\u00f3n santo sabe que tiene que ver con Dios, y se eleva por encima de los elementos sensibles; trabaja para aprobarse ante Dios, y no mira a los hombres, sino a Dios y su alianza, y se renueva con la fe, el arrepentimiento y la invocaci\u00f3n. <\/p>\n<p><strong>2.<\/strong> En que Cristo va a Dios para una bendici\u00f3n sobre el sacramento recibido, aprendemos que toda la gracia, santidad y eficacia de cualquier sacramento se debe obtener, continuaci\u00f3n y aumentada por medio de la oraci\u00f3n. <\/p>\n<p>Por lo segundo, Cristo or\u00f3 con respecto a lo que \u00c9l deb\u00eda hacer. <\/p>\n<p><strong>1.<\/strong> Ahora iba a ser declarado el gran Profeta de Su Iglesia <span class='bible'>Dt 18:18<\/a>). Y todo el ministerio del Nuevo Testamento deb\u00eda ahora ser entregado y consagrado en \u00c9l, y por lo tanto, al emprender esta gran obra, \u00c9l va a Su Padre para bendici\u00f3n y \u00e9xito en ella. <\/p>\n<p><strong>2.<\/strong> Ahora estaba solemnemente apartado, por diversos testimonios del cielo, para la obra de la redenci\u00f3n, y perdi\u00e9ndose la salvaci\u00f3n de los hombres, ministerio que los hombres y los \u00e1ngeles eran demasiado d\u00e9biles para; y no es maravilla, si \u00c9l ora a Su Padre por suficiente fuerza y gracia para sufrir lo mismo. <\/p>\n<p><strong>3.<\/strong> Sab\u00eda que los cielos iban a ser abiertos, y por eso estar\u00e1 en oraci\u00f3n, para mostrar el poder de la oraci\u00f3n, que traspasa los cielos, y entra en el presencia de Dios, y prevalece para bendici\u00f3n. <\/p>\n<p><strong>4.<\/strong> El Esp\u00edritu deb\u00eda descender sobre \u00c9l, y por lo tanto estar\u00eda en oraci\u00f3n para ense\u00f1arnos que las oraciones de los hijos de Dios son de esa fuerza que hacen descender el Esp\u00edritu Santo. Fantasma con todas las gracias sobre la tierra. <\/p>\n<p><strong>5.<\/strong> Que la oraci\u00f3n fiel hace que Dios d\u00e9 alg\u00fan testimonio evidente sobre aquellos en quienes tiene complacencia. <\/p>\n<p><strong>6.<\/strong> Que cualquier cosa que emprendamos, debemos emprenderla con reverencia y oraci\u00f3n, pero especialmente dos cosas por encima de otras. <\/p>\n<p><strong>(1)<\/strong> La parte del culto santo de Dios. <\/p>\n<p><strong>(2)<\/strong> Los deberes de nuestros llamamientos. <\/p>\n<p><strong>2.<\/strong> Tal es nuestra debilidad, que cuando hacemos algo lo mejor que podemos, tenemos necesidad de orar para hacerlo mejor, y por perd\u00f3n que lo hemos hecho no mejor: lo cual, si es verdad en las cosas y deberes externos, en lo cual nos conocemos mejor; mucho m\u00e1s en lo espiritual, donde nuestra capacidad es mucho menor. <\/p>\n<p><strong>3.<\/strong> Nunca recibimos tanto favor de Dios, pero todav\u00eda tenemos la necesidad de anhelar m\u00e1s; ni nunca tan poco, sino que tenemos mucho que agradecer. Esta doctrina sirve para reprender a los que se contentan con la obra de adoraci\u00f3n de Dios; que acuden a la palabra ya los sacramentos, pero no ruegan de antemano una bendici\u00f3n de Dios; mientras que Cristo mismo no se content\u00f3 con los medios externos, sino que or\u00f3 por una bendici\u00f3n. Y esta es la causa misma por la cual los hombres encuentran tan poco gusto, fuerza y poder en estas ordenanzas, porque la bendici\u00f3n de Dios no va con los medios; y por lo tanto est\u00e1 apartado de Sus propias ordenanzas, porque no se pide. \u00bfEs alguna maravilla que cuando los hombres vienen descuidadamente, carnal y profanamente, sin reverencia ni religi\u00f3n a los ejercicios de la religi\u00f3n, se van tan brutalmente como vinieron; y cuanto m\u00e1s profanan as\u00ed las cosas santas de Dios, m\u00e1s insensatos e incurables se vuelven por ellas, m\u00e1s endurecidos y sin esperanza. \u00bfQu\u00e9 bien han obtenido muchos hombres al acostumbrarse a la palabra y los sacramentos durante muchos a\u00f1os juntos? por su conocimiento, los ni\u00f1os pueden plantearlos en principios; por su conciencia, podemos prevalecer pronto con los ni\u00f1os de tres a\u00f1os, para que se sienten con reverencia y atenci\u00f3n, como algunos de sesenta o sesenta, que por la ma\u00f1ana tienen tanto sue\u00f1o, como si estuvieran en sus camas en casa, o tomen orden de traer sus camas con ellos: y por su provecho en sus lugares, o reforma de cualquier cosa en p\u00fablico, o en sus familias privadas, o su propia persona, Dios ni el hombre no pueden ver tal cosa. Ahora quisiera preguntarles a estos hombres, a pesar de su edad, cu\u00e1ntas veces pueden recordar que se han humillado ante Dios, que \u00c9l bendecir\u00e1 la Palabra para ellos, y que la entiendan y tomen conciencia de ella, para reformar sus caminos, para consolar sus conciencias? \u00a1Ay, hombres muertos! este es un movimiento extra\u00f1o para ellos; y ahora concluimos, ninguna bendici\u00f3n pidi\u00f3, ninguna obtuvo, pero una maldici\u00f3n los acompa\u00f1\u00f3 a\u00fan m\u00e1s para endurecerlos: mientras que la oraci\u00f3n humilde y sensible habr\u00eda abierto los cielos y bajado el Esp\u00edritu para haber acompa\u00f1ado la ordenanza; y as\u00ed se habr\u00eda visto alg\u00fan testimonio, de que Dios se hubiera complacido m\u00e1s con ellos y con su obra. <\/p>\n<p><strong>3.<\/strong> Es una valla notable contra el pecado: porque cuanto m\u00e1s prevalece el pecado, menos puede orar el hombre; porque cuanto m\u00e1s ora, menos lo alcanza el pecado. Cuando el verdadero hombre es asaltado, si grita pidiendo ayuda, el ladr\u00f3n huye; y tambi\u00e9n el pecado (un ladr\u00f3n que siempre nos persigue y nos acosa para robarnos y robarnos la gracia) si podemos clamar poderosamente a Dios. <\/p>\n<p><strong>4.<\/strong> Familiar\u00edzate con Dios; porque vendr\u00e1n tiempos en que nada te sostendr\u00e1 sino Su ayuda; y por lo tanto usa la oraci\u00f3n, para familiarizarte con \u00c9l: con\u00f3celo ahora en el tiempo de tu oraci\u00f3n, para que \u00c9l pueda conocerte en el d\u00eda de tu angustia. (<em>T. Taylor, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Conducir sin oraci\u00f3n<\/strong><\/p>\n<p>\u00c9l sabe verdaderamente c\u00f3mo Vive bien el que sabe orar bien. Pero las mejores acciones sin la oraci\u00f3n, que les alcanzan la gracia, son como los cuerpos sin esp\u00edritu: s\u00ed, como el cuerpo sin respirar no puede vivir para hacer ninguna obra adecuada a una vida natural, as\u00ed el alma, sin la oraci\u00f3n, no puede hacer ninguna obra que verdaderamente es espiritual (<em>Obispo Cowper.<\/em>)<\/p>\n<\/p>\n<p>El cielo se abri\u00f3.<br \/>No se deduce que hablamos de esos tres eventos admirables, que siguieron la oraci\u00f3n de Cristo. <\/p>\n<p><strong>1.<\/strong> La apertura sensible de los cielos. <\/p>\n<p><strong>2.<\/strong> El descenso visible del Esp\u00edritu Santo. <\/p>\n<p><strong>3.<\/strong> La voz audible de Dios el Padre, dando testimonio a muchos, tanto con los ojos como con los o\u00eddos, de la solemne entrega e inducci\u00f3n de Cristo a Su oficio y obra de mediaci\u00f3n y ministerio. De lo cual debemos saber, que como nunca hubo en todo el mundo un oficio tan alto y excelente como el de Cristo (porque el m\u00e1s grande de los reyes, y el sumo sacerdote, que sin embargo eran ungidos y delegados para sus oficios con gran estado y observaci\u00f3n, fueran s\u00f3lo sombras de esto), as\u00ed Dios quiso que Cristo entrara en ella con tal magnificencia y gloria como nunca fue capaz el hombre ni la criatura. En la coronaci\u00f3n de un pr\u00edncipe, \u00a1con qu\u00e9 gloria, pompa y suntuosidad, hasta la admiraci\u00f3n, se presenta con sus nobles y s\u00fabditos! Pero todo esto no es m\u00e1s que gloria terrenal, de los hombres terrenales a un rey terrenal. Pero ahora, en la coronaci\u00f3n del Pr\u00edncipe de la Paz, Dios se levanta desde el cielo para honrarlo; y con este prop\u00f3sito \u00c9l se revela m\u00e1s familiarmente, y a\u00fan m\u00e1s gloriosamente, a toda la humanidad, de lo que nunca antes lo hab\u00eda hecho desde la creaci\u00f3n del mundo; y nunca hubo ninguna ceremonia en todo el mundo tan honrada como lo fue este bautismo de Cristo. Los antiguos sacrificios de la instituci\u00f3n de Dios fueron honrados por signos manifiestos de Su presencia llena de gracia, como por el fuego que bajaba del cielo continuamente para consumirlos: el Arca fue honrada con signos especiales de Su presencia gloriosa, sentada entre los querubines, respondiendo por or\u00e1culo. y voz a los casos propuestos: el Templo mismo en Jerusal\u00e9n, en la oraci\u00f3n y dedicaci\u00f3n de Salom\u00f3n, se llen\u00f3 de la gloria de Dios, manifestada en esa nube que llen\u00f3 la Casa del Se\u00f1or (<span class='biblia'>1Re 8:10<\/span>), y esta nube todav\u00eda vigilaba el Tabern\u00e1culo (<span class='bible'>Ex 40:34<\/span>). Pero todo esto no era m\u00e1s que sombras de esto, en el que el Se\u00f1or no nubl\u00f3 ni ocult\u00f3 Su presencia, ni revel\u00f3 Su presencia en alguna se\u00f1al; pero la Divina Majestad se manifest\u00f3 distintamente, como podemos decir, en persona, s\u00ed, en la distinci\u00f3n de las tres Personas, el Padre testificando Su deleite en Su amado Hijo, el Hijo de pie en el Jord\u00e1n, y recibiendo el testimonio de Su Padre; y el Esp\u00edritu Santo descendiendo en forma visible de paloma. Parece, pues, que es cierto que el cielo se dividi\u00f3 sensiblemente y se parti\u00f3 en dos, como lo estaba la tierra cuando Cor\u00e9 y su compa\u00f1\u00eda fueron tragados. <\/p>\n<p>Ahora bien, las razones por las que se abrieron los cielos fueron varias. <\/p>\n<p><strong>1.<\/strong> Para manifestar la verdad y certeza de las otras se\u00f1ales que segu\u00edan, para que viendo los cielos abiertos, no concibiesen que ni la paloma ni la voz vinieran de otra parte. lugar. <a class='bible'>Juan 3:31<\/span>) \u201c El que ha venido del cielo est\u00e1 sobre todos.\u201d <\/p>\n<p><strong>3.<\/strong> Que como su persona, as\u00ed tambi\u00e9n su doctrina era divina y celestial (<span class='bible'>Lc 3:34 <\/span>). Aquel a quien Dios ha enviado, habla las palabras de Dios: y esta fue la obra especial de Su oficina doctoral, revelar la voluntad de Su Padre. \u201cA Dios nadie le ha visto jam\u00e1s, el Hijo unig\u00e9nito, que est\u00e1 en el seno del Padre, le ha dado a conocer\u201d (<span class='bible'>Juan 1:18<\/a>). El poder y la gracia con que obraba milagros no proced\u00edan de Belceb\u00fa, sino del cielo. <\/p>\n<p><strong>4.<\/strong> Para mostrar que su oficio, en el que ahora hab\u00eda entrado, era y es abrir de nuevo el cielo para nosotros, que por el pecado lo hab\u00edamos cerrado contra nosotros; \u00c9l ha hecho nuestro camino hacia el trono de la gracia. Y as\u00ed este segundo Ad\u00e1n est\u00e1 en oposici\u00f3n con el primero; \u00c9l nos excluy\u00f3 del para\u00edso, en se\u00f1al de que est\u00e1bamos excluidos del cielo: pero esto nos permite entrar de nuevo en el para\u00edso de Dios. Los cielos son abiertos por Su pasi\u00f3n, no por Su bautismo <span class='bible'>Heb 10:19<\/span>). Se abren por Su muerte como por una causa com\u00fan, que debe aplicarse especial y singularmente, y es por el bautismo: por lo cual se dice: \u201cSomos bautizados en Su muerte\u201d (<span class='bible'>Rom 6,3-4<\/span>), es decir, beneficiarse de su muerte. N\u00f3tese, pues, que Cristo, al cumplir toda justicia, abri\u00f3 el cielo para nosotros, y por consiguiente la justificaci\u00f3n de un pecador no es s\u00f3lo por la obediencia de su pasi\u00f3n, sino tambi\u00e9n por su obediencia activa en el cumplimiento de la ley. (<em>T. Taylor, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Como una paloma sobre \u00c9l<\/strong><\/p>\n<p><strong> El descenso del Esp\u00edritu sobre Cristo como una paloma<\/strong><\/p>\n<p>Por lo tanto, podemos observar que la religi\u00f3n de Jes\u00fas consiste en un temperamento de paloma. Trataremos de ilustrar esta observaci\u00f3n. Para que podamos proceder con seguridad, no daremos rienda suelta a la imaginaci\u00f3n, sino que seguiremos estrictamente las alusiones que encontramos en las Escrituras. <\/p>\n<p><strong>1.<\/strong> La paloma es emblema de pureza. En la ley de Mois\u00e9s esto se contaba como un ave limpia, y se seleccionaba para una ofrenda en la ceremonia de purificaci\u00f3n. Sus preceptos, Sus doctrinas, Su ejemplo nos ense\u00f1an a ser santos, sin mancha y separados de los pecadores. <\/p>\n<p><strong>2.<\/strong> Cristo dirige a sus disc\u00edpulos a ser inofensivos como palomas. El mismo esp\u00edritu manso e inofensivo que estaba en \u00c9l debe estar tambi\u00e9n en nosotros. <\/p>\n<p><strong>3.<\/strong> La paloma, en el libro de los C\u00e1nticos, es emblema de alegr\u00eda y gozo. \u201cHe aqu\u00ed, el invierno ha pasado y se ha ido, las flores aparecen en la tierra; ha llegado la hora del canto de los p\u00e1jaros: la voz de la tortuga se oye en nuestra tierra.\u201d El temperamento de paloma del evangelio es dulce, sereno y agradable. <\/p>\n<p><strong>4.<\/strong> Las palomas se distinguen por su mutua fidelidad y amor. A esta propiedad social y afectiva hay frecuentes alusiones en la Escritura. El novio, en el libro de los C\u00e1nticos, llama a la novia con este, entre otros nombres entra\u00f1ables: \u201cPaloma m\u00eda, d\u00e9jame ver tu rostro y o\u00edr tu voz, porque tu voz es dulce y tu rostro hermoso\u201d. Las personas en aflicci\u00f3n son descritas como \u201cdolientes como palomas\u201d que han perdido a sus compa\u00f1eros. El amor mutuo es el car\u00e1cter del evangelio. <\/p>\n<p><strong>5.<\/strong> La paloma es un ave indefensa. De ah\u00ed que se la describa como \u201cque habita en las hendiduras de las rocas, y en los lugares secretos de las escaleras\u201d; y como \u201cvolando hacia sus ventanas\u201d en tiempos de peligro. Desde este punto de vista, ella es un emblema de la fe cristiana y la humildad. Los verdaderos creyentes, conscientes de su debilidad y de los peligros que los acechan, no conf\u00edan en s\u00ed mismos, sino en el poder y la gracia de su Salvador. <\/p>\n<p><strong>6.<\/strong> La gloria excelsa, que descendi\u00f3 como paloma y se pos\u00f3 sobre Jes\u00fas, podr\u00eda estar destinada a representar las bellezas de su Iglesia, adornada y dignificada por las gracias de su Esp\u00edritu. . La paloma, que es un p\u00e1jaro hermoso, es un emblema natural de las buenas y virtuosas obras que distinguen el car\u00e1cter cristiano. \u201cAunque os hubiereis acostado entre las ollas, ser\u00e9is como las alas de una paloma, cubiertas de plata, y sus plumas de oro amarillo\u201d. <\/p>\n<p><strong>7.<\/strong> La paloma, que es un ave fecunda, es, por Isa\u00edas, hecha emblema del crecimiento de la Iglesia en sus \u00e9pocas felices y pr\u00f3speras. Entonces los conversos volar\u00e1n al altar de Dios, \u201ccomo palomas a sus ventanas\u201d. (<em>J. Lathrop. DD<\/em>)<\/p>\n<\/p>\n<p><strong>El Esp\u00edritu se asemeja a una paloma<\/strong><\/p>\n<p><strong>1.<\/strong> Nuestro tema nos sugiere que el Esp\u00edritu de Cristo generalmente viene al alma de una manera suave y apacible. Sus operaciones son como Sus frutos, semejantes a palomas, dulces y amables. La naturaleza ben\u00e9vola y amistosa de la dispensaci\u00f3n que Cristo estaba a punto de introducir qued\u00f3 insinuada en la forma del descenso del Esp\u00edritu. La ley, que era un ministerio de muerte y condenaci\u00f3n, fue entregada al pueblo en circunstancias de terror y asombro. Como Su manera de ense\u00f1ar, las doctrinas que ense\u00f1\u00f3 fueron amables y llenas de gracia. <\/p>\n<p><strong>2.<\/strong> Nuestro tema nos ense\u00f1a adem\u00e1s, que s\u00f3lo ellos son guiados por el Esp\u00edritu de Dios, quienes tienen un temperamento de paloma. Es absurdo, pues, imputar a una influencia poco com\u00fan del Esp\u00edritu cualquier error de conducta, exceso de pasi\u00f3n, extravagancia de celo, o amargura de censura; porque el Esp\u00edritu viene como la paloma. <\/p>\n<p><strong>3.<\/strong> Nuestro tema nos recuerda nuestra obligaci\u00f3n de adornar con buenas obras nuestro car\u00e1cter cristiano, y de recomendar a la elecci\u00f3n de los dem\u00e1s la religi\u00f3n que profesamos. Debemos asemejarnos a la paloma, cuyas alas est\u00e1n cubiertas de plata y sus plumas de oro amarillo. La belleza de la religi\u00f3n depende mucho de que mantengamos las virtudes m\u00e1s amables y atractivas; como la caridad, la paz, la humildad y la mansedumbre. <\/p>\n<p><strong>4.<\/strong> Nuestro tema nos ense\u00f1a nuestra obligaci\u00f3n de trabajar por el aumento de la Iglesia de Cristo, no solo para participar nosotros mismos, sino tambi\u00e9n para animar a otros a venir y unirse. lo. (<em>J. Lathrop. DD <\/em>)<\/p>\n<\/p>\n<p><strong>Con apariencia de paloma<\/strong><\/p>\n<p><strong> <br \/>Yo. <\/strong>El Esp\u00edritu Santo descendi\u00f3 en forma corporal COMO UN arco. <\/p>\n<p><strong>1.<\/strong> La paloma era un ave de pureza. Sabes que lo usaban los pobres en los sacrificios, y por lo tanto se consideraba limpio. <\/p>\n<p><strong>2.<\/strong> El Esp\u00edritu Santo es como una paloma porque es una criatura inofensiva. La paloma nunca lastima al p\u00e1jaro m\u00e1s peque\u00f1o con el que entra en contacto. El Esp\u00edritu Santo no se compara con el \u00e1guila, ni con el gavil\u00e1n, ni con el buitre, aves de rapi\u00f1a; pero a la paloma\u2014una criatura inofensiva. <\/p>\n<p><strong>3.<\/strong> El Esp\u00edritu Santo es como una paloma porque la paloma es una criatura tan gentil. Sus influencias son de lo m\u00e1s benignas. <\/p>\n<p><strong>4.<\/strong> El Esp\u00edritu Santo tambi\u00e9n es como la paloma, porque la paloma tiene una vista muy aguda. En el Libro de los C\u00e1nticos leemos: \u201cTienes ojos de paloma\u201d. Las palomas son notables por su gran agudeza de visi\u00f3n. El Esp\u00edritu Santo \u201cescudri\u00f1a todas las cosas\u201d. <\/p>\n<p><strong>5.<\/strong> El Esp\u00edritu Santo es como la paloma porque la paloma era emblema de paz y de primavera. La paloma volvi\u00f3 a llevar la hoja de olivo a su boca, indic\u00e1ndole a No\u00e9 que las aguas se hab\u00edan calmado y que el diluvio de la ira pronto terminar\u00eda. La paloma tambi\u00e9n se menciona en los C\u00e1nticos como un heraldo de la primavera: \u201cHa llegado el tiempo del canto de los p\u00e1jaros, y la voz de la tortuga se oye en la tierra\u201d. Y cada vez que el Esp\u00edritu Santo viene al coraz\u00f3n de un hombre, hay una se\u00f1al de que ese coraz\u00f3n estar\u00e1 en paz con Dios. <\/p>\n<p><strong>6.<\/strong> El Esp\u00edritu Santo, por \u00faltimo, es como una paloma porque la paloma se entreg\u00f3 al luto. \u201cMe lam\u00e9 como una paloma\u201d, dice Isa\u00edas. \u201cEl Esp\u00edritu tambi\u00e9n nos ayuda en nuestras debilidades\u201d\u2014toma nuestras debilidades sobre S\u00ed mismo. Su obra es de car\u00e1cter amoroso. <\/p>\n<p><strong><br \/>II. <\/strong>En segundo lugar, tenemos LAS CARACTER\u00cdSTICAS DE CRISTO. Mucho se ense\u00f1a en la conexi\u00f3n del texto concerniente a la misi\u00f3n de Cristo, mientras que nuestro texto mismo da los elementos principales de Su car\u00e1cter. En primer lugar, tenemos algo acerca de Su misi\u00f3n. Fue ordenado divinamente, porque <em>Dios <\/em>envi\u00f3 el Esp\u00edritu Santo para testificar al mundo que \u00c9l fue comisionado por \u00c9l para llevar a cabo la redenci\u00f3n del hombre. Tenemos aqu\u00ed el prop\u00f3sito de Su misi\u00f3n. El cielo se abri\u00f3 y el Esp\u00edritu Santo descendi\u00f3. Fue el prop\u00f3sito de Cristo abrir el cielo. El primer Ad\u00e1n nos cerr\u00f3 el cielo. Pero el car\u00e1cter de Cristo fue desarrollado por la influencia del Esp\u00edritu Santo. Jes\u00fas no logr\u00f3 Su obra en virtud de la divinidad que estaba en \u00c9l solamente, sino en virtud de las gracias del Esp\u00edritu sobre \u00c9l. La paloma era inofensiva. Cristo dijo: \u201cSoy manso y humilde de coraz\u00f3n\u201d. La paloma se entreg\u00f3 al luto. Jes\u00fas fue \u201cun var\u00f3n de dolores, experimentado en quebranto\u201d. La paloma menea inocente. Jesucristo fue la pureza personificada. \u201c\u00bfQui\u00e9n de vosotros me convence de pecado?\u201d dij\u00f3 el. \u00c9l era santo, inocente, sin mancha y, en un sentido enf\u00e1tico, la paloma era emblem\u00e1tica de \u00c9l. <\/p>\n<p><strong><br \/>III. <\/strong>AS\u00cd ES TAMBI\u00c9N CON UN CRISTIANO. No hay car\u00e1cter verdadero que no sea edificado por la influencia del Esp\u00edritu Santo. La paloma est\u00e1 indefensa. No tiene nada que lo proteja excepto las rocas, y cuando lo persiguen, su \u00fanico refugio es volar all\u00ed. El cristiano no tiene nada para protegerse contra las asechanzas del diablo y las tentaciones del mundo, excepto \u201cla Roca de la Eternidad\u201d. La paloma se mantiene en su propia compa\u00f1\u00eda. Se deleita cuando est\u00e1 con sus semejantes. As\u00ed que el cristiano se siente como en casa cuando se encuentra entre personajes de naturaleza similar. La paloma se lamenta por la ausencia de su pareja; y el car\u00e1cter que el Esp\u00edritu Santo nos da es tal que nos hace llorar cuando nuestro Se\u00f1or Jes\u00fas est\u00e1 lejos, de modo que no tenemos descanso si estamos separados de \u00c9l. No puedes tener este car\u00e1cter excepto por la aplicaci\u00f3n personal del Esp\u00edritu Santo a tu coraz\u00f3n. (<em>T. Gamble.<\/em>)<\/p>\n<\/p>\n<p><strong>El Esp\u00edritu Santo descendiendo como una paloma<\/strong><\/p>\n<p><strong><br \/>Yo. <\/strong>Primero, como la meditaci\u00f3n del Esp\u00edritu de Dios sobre la faz del orden profundo producido y la vida en el principio, as\u00ed \u00c9l imparte nueva vida al alma y abre los ojos del entendimiento, para que podamos contemplar las maravillas de la ley de Dios. <\/p>\n<p><strong><br \/>II. <\/strong>Nuevamente: En el hecho de que el Esp\u00edritu Santo descendi\u00f3 sobre el Se\u00f1or Jes\u00fas en forma de paloma, se nos recuerda que la quietud es a menudo esencial para muchas de las operaciones de la gracia. \u201cUna persona muy inquieta nunca ser\u00e1 muy piadosa, y una muy piadosa nunca ser\u00e1 muy inquieta. &#8216;Estad quietos y sabed que yo soy Dios&#8217;\u201d. <\/p>\n<p><strong><br \/>III. <\/strong>Otro punto sugerido por el texto es que as\u00ed como la paloma es un emblema apropiado del amor, as\u00ed el alma que es influenciada por el bendito Esp\u00edritu abundar\u00e1 en amor a Dios y amor a Su pueblo. Se iba a derribar el campanario de una antigua iglesia de pueblo para preparar el camino para algunas mejoras modernas, y se at\u00f3 una cuerda larga cerca de la parte superior para evitar que aplastara el edificio en su ca\u00edda. Pronto todo estuvo listo, y el maestro carpintero grit\u00f3 en voz alta a los hombres que tiraran. Cuando el viejo campanario comenz\u00f3 a temblar y a balancearse de un lado a otro, se observ\u00f3 que una hermosa paloma blanca volaba dando vueltas y vueltas, sin atreverse a entrar en su lugar acostumbrado y, sin embargo, evidentemente sin querer irse. Parec\u00eda ser consciente de que una gran calamidad estaba a punto de ocurrir, mientras un centenar de voces gritaban: \u201c\u00a1Mira esa paloma!\u201d. \u00ab\u00a1Pobre cosa!\u00bb el carpintero jefe observ\u00f3, \u201cdebe tener cr\u00edas en el campanario\u201d. De nuevo los obreros dieron un vigoroso tir\u00f3n a la cuerda, y el viejo campanario se tambale\u00f3 y tambale\u00f3. La angustia de la pobre paloma se hizo tan grande, que todos sintieron l\u00e1stima por ella, y no se dijo una palabra. El p\u00e1jaro revolote\u00f3 un momento sobre sus alas, y en el instante en que las vigas chirriantes comenzaron a derrumbarse, se precipit\u00f3 hacia el campanario y se ocult\u00f3 de la vista. Cuando se retir\u00f3 la basura, se la encontr\u00f3 acostada entre sus dos peque\u00f1os, los tres aplastados hasta la muerte. El p\u00e1jaro devoto estaba dispuesto a morir con y por ellos, pero no pudo salvarlos. Hubo un espect\u00e1culo de amor devoto, \u00a1amor hasta la muerte!<\/p>\n<p><strong><br \/>IV.<br \/> Observo, en cuarto lugar, que la venida del Esp\u00edritu Santo, en forma de paloma, debe recordarnos que la mansedumbre es una marca distintiva del car\u00e1cter cristiano en la que la mayor\u00eda de nosotros tenemos mucho que aprender.<br \/> Audubon, el ornit\u00f3logo, relata este incidente en su autobiograf\u00eda: \u201cUn hombre, que una vez fue pirata, me asegur\u00f3 que varias veces, estando en ciertos pozos excavados en las arenas ardientes y conchas, las notas suaves y melanc\u00f3licas de las palomas despertaron en su coraz\u00f3n sentimientos que hab\u00edan estado dormidos durante mucho tiempo, derritiendo su coraz\u00f3n al arrepentimiento.<br \/> Se sinti\u00f3 tan profundamente conmovido por ellos, los \u00fanicos sonidos tranquilizadores que hab\u00eda escuchado durante su vida de horrores, que a trav\u00e9s de ellos se vio inducido a escapar de su nave, abandonar a sus turbulentos compa\u00f1eros y regresar con una familia que deploraba su vida. ausencia, y ahora vive en paz en medio de sus amigos.<\/strong><\/p>\n<p><strong>\u201d \u201cTe suplico por la dulzura de Chr ist\u201d, fue la exhortaci\u00f3n de san Pablo a los cristianos de Corinto (<\/strong><span class='bible'>2Co 10,1<\/span>); y la \u201cmansedumbre\u201d, asegura a los g\u00e1latas (v. 22), es uno de los frutos destacados del Esp\u00edritu. Henry Martyn, cuyo temperamento naturalmente no era el m\u00e1s gentil, escribi\u00f3 en su diario: \u201cEntr\u00e9 en el pueblo donde el bote se detuvo para pasar la noche y encontr\u00e9 a los adoradores de Call por el sonido de sus tambores y c\u00edmbalos. No les habl\u00e9 por ser bangaleeses; pero siendo invitado a caminar por los brahmanes, me acerqu\u00e9 a las rejas e hice algunas preguntas sobre el \u00eddolo. El brahm\u00e1n, que hablaba mal hindostanee, disput\u00f3 con gran vehemencia, y su lengua corri\u00f3 m\u00e1s r\u00e1pido de lo que pude seguir, y la gente grit\u00f3 aplausos. Continu\u00e9 haciendo mis preguntas, sin hacer ning\u00fan comentario sobre las respuestas&#8230; El hombre se calm\u00f3 bastante y dijo que eran \u00abbuenas palabras\u00bb, y finalmente me pregunt\u00f3 seriamente si la adoraci\u00f3n de \u00eddolos era verdadera o falsa. Sent\u00ed que era una cuesti\u00f3n de agradecimiento poder dar a conocer la verdad de Dios, aunque solo era un tartamudo; y tambi\u00e9n aprend\u00ed esto, que el poder de la mansedumbre es irresistible. Una vez m\u00e1s: la paloma siempre ha sido el tipo de la pureza, y el Esp\u00edritu Santo es el purificador del coraz\u00f3n. Cuando \u00c9l logra entrar en \u00e9l, el pecado y la inmundicia deben desaparecer. (<em>JN Norton, DD<\/em>)<\/p>\n<\/p>\n<p><strong>El Esp\u00edritu Santo como una paloma<\/strong><\/p>\n<p>As\u00ed que aqu\u00ed el El Esp\u00edritu aparec\u00eda en forma de paloma, para notar&#8211;<\/p>\n<p><strong>1.<\/strong> Qu\u00e9 tipo de Esp\u00edritu era el de Cristo. <\/p>\n<p><strong>2.<\/strong> Qu\u00e9 clase de dones fueron los que fueron cotejados y otorgados a \u00c9l: y&#8211;<\/p>\n<p><strong>3.<\/strong> Qu\u00e9 fue el fruto de esos dones. (<em>J. Taylor, DD<\/em>)<\/p>\n<\/p>\n<p><strong>El Esp\u00edritu Divino en el ministerio<\/strong><\/p>\n<p>Nota, como Cristo fue apartado tanto por el ministerio del hombre como por el Esp\u00edritu, por cuya apariencia visible Dios manifestar\u00eda que \u00c9l era apto para ello; as\u00ed en todos aquellos que son apartados por el hombre para el ministerio, debe haber un descenso aparente del Esp\u00edritu, aunque no en forma visible, pero s\u00ed en dones y gracias evidentes. (<em>J. Taylor, DD<\/em>)<\/p>\n<\/p>\n<p><strong>El Esp\u00edritu de Dios semejante a \u00c9l<\/strong><\/p>\n<p>El El Esp\u00edritu de Dios es en todas partes semejante a \u00c9l, tanto en la cabeza como en los miembros, como el mismo jugo est\u00e1 en la ra\u00edz y las ramas, en el \u00e1rbol y en los frutos. Mira cu\u00e1les fueron los frutos del Esp\u00edritu en Cristo, los mismos tambi\u00e9n est\u00e1n en los miembros (<span class='bible'>Gal 5:23<\/span>). (<em>J. Taylor, DD<\/em>)<\/p>\n<\/p>\n<p><strong>La Trinidad Divina comprometida en la redenci\u00f3n<\/strong><\/p>\n<p>Aqu\u00ed, luego, para nuestro mayor consuelo, tenemos que considerar c\u00f3mo las tres Personas de la Sant\u00edsima Trinidad concurren juntas para realizar la gran obra de nuestra redenci\u00f3n; porque aqu\u00ed est\u00e1 el Padre dise\u00f1ando, ordenando, proclamando; aqu\u00ed est\u00e1 el Hijo aceptando, y el Esp\u00edritu Santo ungiendo. (<em>Obispo Cowper.<\/em>)<\/p>\n<\/p>\n<p><strong>El Esp\u00edritu Santo como paloma<\/strong><\/p>\n<p>El Esp\u00edritu que descendi\u00f3 sobre Jes\u00fas como una paloma se convertir\u00eda, y se convirti\u00f3, cuando \u00c9l lo exhal\u00f3, en un fuego consumidor (<span class='bible'>Luk 3:16<\/span>). \u00bfPor qu\u00e9, en su descenso sobre \u00c9l, fue el suave anidamiento de una paloma? \u00bfNo podemos responder con una palabra que en \u00c9l no encontr\u00f3 ninguna fuerza pecaminosa, ninguna masa de mala pasi\u00f3n o disposici\u00f3n indigna con la que luchar; sino s\u00f3lo bellos g\u00e9rmenes que desarrollar, s\u00f3lo derechos, simpat\u00edas y aspiraciones que animar, dirigir e intensificar? S\u00ed; encontr\u00f3 en \u00c9l s\u00f3lo lo que era acorde y congenial; el Santo Ni\u00f1o para expandirse en el Hombre Santo; nada contrario a ella, cuya resistencia habr\u00eda encendido una llama; nada contra lo que arder y quemar, para Su perfeccionamiento; ninguna falsa voluntad de afectos por la cual ser resistida y resistir, hasta que sea conquistada. El Esp\u00edritu de lo alto simplemente se encendi\u00f3 y extendi\u00f3 sus alas, y se sent\u00f3 meditando sobre la simplicidad divina del nazareno de todo coraz\u00f3n. Es cierto que \u00c9l tuvo que soportar en s\u00ed mismo un bautismo de fuego, como resultado del descenso sobre \u00c9l desde lo alto. Pero fue a trav\u00e9s de su contacto, as\u00ed cargado de Esp\u00edritu, con el elemento malo que lo rodeaba, que sufri\u00f3 lo que sufri\u00f3; no a trav\u00e9s del contacto del Esp\u00edritu con alg\u00fan elemento malo en \u00c9l. No encontr\u00f3 nada en \u00c9l para causar una llama dolorosa; al tocarlo, ten\u00eda que convertirse en fuego purgante y devorador. Repos\u00f3 sobre \u00c9l como una paloma empollando sobre su nido. (<em>Bebida SA.<\/em>)<\/p>\n<\/p>\n<p><strong>T\u00fa eres Mi Hijo amado, en Ti tengo complacencia<\/strong><\/p>\n<p><strong>La voz del cielo<\/strong><\/p>\n<p><strong><br \/>I. <\/strong>LA PERSONA CUYA VOZ ERA ES DIOS PADRE; porque \u00c9l dice: \u201cT\u00fa eres mi Hijo amado\u201d. Todo testimonio recibe validez y autoridad del testador, por lo que es necesario que \u00e9ste sea s\u00f3lido y bueno. Dios hab\u00eda dado testimonio de Cristo por medio de muchos hombres famosos, incluso todos los profetas, y ahora \u00faltimamente por Juan Bautista, quien era m\u00e1s grande que un profeta, que Cristo era m\u00e1s grande que \u00e9l; s\u00ed, m\u00e1s a\u00fan, hab\u00eda dado testimonio de \u00c9l por medio de una multitud de \u00e1ngeles celestiales (<span class='bible'>Luk 1:30<\/span>; <span class='bible'>Lucas 13:1-35<\/span>). Pero no contento con todo esto, da desde el cielo su propio testimonio de s\u00ed mismo. <\/p>\n<p><strong>1.<\/strong> Para impresionarnos con reverencia al recibir este testimonio, que tiene este privilegio sobre otras partes de la Escritura, que fue pronunciado por la propia boca de Dios, no por hombres o \u00e1ngeles. . <\/p>\n<p><strong>2.<\/strong> Para confirmarnos en la verdad del testimonio, procedente de Aquel que es <em>prima veritas, <\/em>la verdad misma (no s\u00f3lo verdadera) en Su esencia, y mucho m\u00e1s en sus palabras y obras, que no puede ser enga\u00f1ado, ni enga\u00f1arnos. <\/p>\n<p><strong>3.<\/strong> Mostrar la necesidad de creer en este testimonio, siendo el primer y \u00fanico principio de la religi\u00f3n cristiana, sin el cual no puede haber fundamento ni religi\u00f3n ni salvaci\u00f3n, como vemos en los jud\u00edos y los turcos. Para que podamos creer m\u00e1s firmemente en el Hijo de Dios de por vida, la propia boca de Dios testifica tan honrosamente de \u00c9l. <\/p>\n<p><strong>4.<\/strong> Para que tan gloriosa encomienda de este testimonio suscite nuestra mejor atenci\u00f3n y afecto en el desarrollo del mismo, tenemos aqu\u00ed la palabra de un Rey que nunca se manch\u00f3 , y eso no lo pronunci\u00f3 ning\u00fan heraldo o un lord canciller, sino de Su propia boca, lo que tiene m\u00e1s peso. Si Dios habla, \u00a1ay del que no oye! <\/p>\n<p><strong><br \/>II. <\/strong>EL LUGAR DE DONDE&#8211;DEL CIELO. Por estas razones: <\/p>\n<p><strong>1.<\/strong> Para dar m\u00e1s autoridad a la persona de Cristo, a quien Dios honra desde los cielos. Y si Dios lo honra as\u00ed, \u00bfc\u00f3mo debemos honrarlo nosotros? <span class='bible'>2Pe 1:17<\/span>.) \u00c9l recibi\u00f3 de Dios Padre honor y gloria, cuando le vino tal voz desde la gloria excelsa: \u201c Este es mi Hijo amado\u201d; lo cual se verific\u00f3 no s\u00f3lo en el tiempo de Su Transfiguraci\u00f3n, sino aqu\u00ed tambi\u00e9n. <\/p>\n<p><strong>2.<\/strong> Porque el testimonio contiene la suma de todo el evangelio, para declarar que la doctrina del evangelio, que Cristo entreg\u00f3 al mundo, era del cielo, porque Dios de el cielo as\u00ed lo testifica. En lo cual difiere de la doctrina de la Ley, que, aunque Dios la renov\u00f3 desde el cielo en tablas de piedra, sin embargo, fue escrita en el coraz\u00f3n del hombre por naturaleza. As\u00ed no era el evangelio. Pero as\u00ed como despu\u00e9s de la Ca\u00edda, Dios lo entreg\u00f3 inmediatamente a Ad\u00e1n en la promesa, as\u00ed aqu\u00ed, por la misma voz del cielo, se confirm\u00f3 que era Divino y celestial. <\/p>\n<p><strong>3.<\/strong> Con respecto a nosotros, que atendamos m\u00e1s cuidadosamente al testimonio mismo que procede de la excelente gloria, y que de la boca del Dios de la gloria sentado en Su silla de estado, viendo la palabra de un Rey en ese lugar es m\u00e1s considerado. El desprecio de la Ley dada en el Monte Sina\u00ed, en manos de los \u00e1ngeles, fue requerido de sus manos; \u00bfC\u00f3mo escapar\u00e1n, pues, los que desprecian al que habla desde los cielos? (<span class='bible'>Hebreos 2:2-3<\/span>.) Transgredida la Ley, el evangelio del cielo modera y perdona al hombre; pero siendo menospreciado el evangelio del cielo, \u00bfqu\u00e9 podr\u00e1 abogar por \u00e9l? <\/p>\n<p><strong>4.<\/strong> Para mostrar la extensi\u00f3n del evangelio, que ha de ser predicado, y vincula a la fe de \u00e9l a todas las personas debajo del cielo. Y en esto no deb\u00eda ser inferior a la Ley, que Dios habr\u00eda reconocido como propia pronunci\u00e1ndola desde el cielo, y eso no antes de haber enviado a Mois\u00e9s, para que no se pensara que era suya, aunque era tan fuerte. y penetrante, como no podr\u00eda ser sino Divina, no humana. <\/p>\n<p><strong><br \/>III. <\/strong>LA MANERA DEL TESTIMONIO&#8211;POR UNA VOZ AUDIBLE Y SENSIBLE. C\u00d3MO el Padre pronuncia esta voz es innecesario preguntar, ya que sabemos que Aquel que hizo la lengua puede hablar sin lengua o por inspiraci\u00f3n y revelaci\u00f3n secreta, como Isa\u00edas (<span class='bible'>2 Reyes 20:4<\/span>). o formar una lengua y \u00f3rganos de voz a Su placer, para pronunciar y dar a conocer Su voluntad y benepl\u00e1cito a Sus criaturas, o hablar por medio de criaturas, como \u00e1ngeles en forma humana, u otras criaturas sensibles, como el asno de Balaam; o insensible, como la zarza de fuego. Es mucho m\u00e1s material investigar el fin y el uso de ella, que era dar a conocer al Hijo de Dios al mundo, para que la fe de los hombres pudiera estar fijada en \u00c9l para salvaci\u00f3n. <\/p>\n<p><strong>1.<\/strong> Por lo tanto, f\u00edjate, en que el Se\u00f1or desde el cielo ense\u00f1a por la voz Su maravilloso cuidado, que no har\u00e1 que nos falte ning\u00fan medio para ayudarnos en el conocimiento de la medio de salvaci\u00f3n. \u00c9l les hab\u00eda ense\u00f1ado a ellos ya nosotros antes, por el sentido de la vista, viendo los cielos abiertos, y el Esp\u00edritu visiblemente descendiendo; y ahora \u00c9l ense\u00f1a el o\u00eddo por medio de la voz, porque \u00c9l conoce nuestra torpeza, seguridad, lentitud de coraz\u00f3n para creer, y se aplica de todas las maneras posibles para ayudarnos. \u00c9l manifiesta Su gloria por Sus obras y criaturas; \u00c9l a\u00f1ade Su Palabra confirmada por muchos milagros poderosos; a su Palabra audible ha anexado Su Palabra visible, los sacramentos; \u00c9l ha establecido un ministerio constante en Su Iglesia, y todo lo ha adaptado para la edificaci\u00f3n de Su pueblo, de modo que ahora puede decir: \u00bfQu\u00e9 m\u00e1s podr\u00eda hacer por ti, oh Israel? \u00bfTiene Dios cuidado de que nos aprovechemos en todos los sentidos? Entonces, \u00a1cu\u00e1n condenable e inexcusable ser\u00e1 el descuido de la mayor\u00eda en el asunto de su salvaci\u00f3n! En cuanto a esto, hubiera sido bueno para muchos hombres que Dios nunca les hubiera dado a conocer Su voluntad, que nunca hubieran escuchado la Palabra, o recibido los sacramentos, por casi tender a su condenaci\u00f3n m\u00e1s profunda, a causa de su descuido y uso formal. Cuando nuestro Salvador dijo de Judas: \u201cHubiera sido bueno para \u00e9l que nunca hubiera nacido\u201d, \u00bfno dijo en realidad lo mismo, \u201cHab\u00eda sido bueno para \u00e9l que nunca hubiera sido un disc\u00edpulo de Cristo, nunca hubiera escuchado a Cristo, o predicaba a Cristo, porque cuanto m\u00e1s excelentes medios ten\u00eda, mayor era su pecado y juicio. Nuevamente, por la presente Dios aclara Su justo juicio en la justa condenaci\u00f3n de los imp\u00edos e incr\u00e9dulos. Oh Israel, tu destrucci\u00f3n es de ti mismo. No digas, \u00bfQu\u00e9 puedo remediarlo, si Dios no me salvar\u00e1? No, \u00bfqu\u00e9 puede hacer Dios m\u00e1s de lo que ha hecho? \u00c9l te ha dado medios fuertes y excelentes, y ha predicado el evangelio desde el cielo por su propia boca, y lo ha enviado a todas las naciones bajo el cielo en su propio idioma con una voz audible e inteligible. Si ahora reh\u00fasas voluntariamente los medios, tu sangre sea sobre tu propia cabeza; lo que va a morir, que muera. Est\u00e1s en el mar de tus pecados, listo para ser ahogado, se ofrece buena ayuda, pero la rechazas, y debes morir en tu pecado. Tu caso es el de Jerusal\u00e9n: \u201c\u00a1Cu\u00e1ntas veces quise reunirte y no quisiste!\u201d <\/p>\n<p><strong>2.<\/strong> Tenga en cuenta que es el placer de Dios que se nos ense\u00f1e el asunto de la salvaci\u00f3n por voz, y que prestemos atenci\u00f3n a eso. Aqu\u00ed hab\u00eda una apertura visible de los cielos, una presencia gloriosa del Esp\u00edritu en forma de paloma posada sobre Cristo; pero cuando el Se\u00f1or quiera que Cristo sea publicado y proclamado el Mes\u00edas, esto debe hacerse por voz. <\/p>\n<p>\u201cO\u00edste una voz, pero no viste imagen; por tanto, cu\u00eddate y no te corrompas con ninguna imagen\u201d (<span class='bible'>Deu 4:12<\/span>; <span class='bible'>Dt 4:14<\/span>). <\/p>\n<p><strong>1.<\/strong> En esto Su misericordia ha se\u00f1alado una instrucci\u00f3n familiar y adecuada, adecuada para nuestra debilidad, no viniendo a Su Iglesia en Su propia Majestad. <\/p>\n<p><strong>2.<\/strong> En esto adelant\u00f3 nuestra naturaleza, ense\u00f1\u00e1ndonos grandes misterios por medio de nosotros mismos, santificando las lenguas de los hombres, y no de los \u00e1ngeles. <\/p>\n<p><strong>3.<\/strong> En esto magnifica su poder el que con medios tan d\u00e9biles obra la salvaci\u00f3n. Se usan vasijas de barro, para que se vea que el poder es de <span class='bible'>2Co 4:7<\/span>). La voz de los hombres por el poder de Dios conquista el mundo. <\/p>\n<p><strong>4.<\/strong> En esto \u00c9l prueba nuestra obediencia, si cederemos a una voz d\u00e9bil, mientras que \u00c9l podr\u00eda forzarnos con poder. Razones: Si Dios nos mira en nosotros mismos y en la masa com\u00fan, estamos tan cubiertos de pecado, que debe pronunciar de nosotros como una vez lo hizo con la humanidad: \u201cMe arrepiento de haber hecho al hombre\u201d. \u00c9l debe necesariamente traer la maldici\u00f3n de la Ley sobre nuestros cuellos. Pero mir\u00e1ndonos a trav\u00e9s de Cristo, \u00c9l cambia Su voz, que como cuando miramos una cosa a trav\u00e9s de un vidrio rojo, verde o coloreado, todo parece del color del vidrio. As\u00ed que Dios, mir\u00e1ndonos a trav\u00e9s de Cristo, recibimos el tinte y la tintura de Su sangre y obediencia, y as\u00ed somos justificados y considerados inocentes y puros. Y as\u00ed, como se dice de la Iglesia (<span class='bible'>Ez 16,14<\/span>), recuperamos nuestra antigua hermosura, que se perfecciona en Su hermosura . (<em>T. Taylor, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Treinta a\u00f1os<\/strong><\/p>\n<p><strong>A\u00f1os de silencio y preparaci\u00f3n<\/strong><\/p>\n<p>En el humilde hogar de Nazaret Jes\u00fas pas\u00f3 treinta a\u00f1os; lo m\u00e1s maravilloso en esto, que nada maravilloso se registra de ellos. La bondad era tan perfecta, el deber tan uniformemente cumplido, el brillo de la santidad tan suave y constante, que los hermanos y hermanas y los rudos vecinos nazarenos llegaron a tomar todo esto como algo natural, no vieron en ello nada sobrehumano; y cuando por fin se hizo a un lado el disfraz, y el profeta-rey de Israel, el Mes\u00edas prometido, apareci\u00f3 sin velo, s\u00f3lo pudieron preguntar est\u00fapidamente: \u00ab\u00bfNo es este Jes\u00fas, el carpintero?\u00bb La imaginaci\u00f3n puede esforzarse en descorrer el velo que la inspiraci\u00f3n ha dejado corrido en estos treinta a\u00f1os, el precioso episodio de la visita a Jerusal\u00e9n. Para algunas mentes, el intento tendr\u00e1 una fascinaci\u00f3n irresistible, para otras ser\u00e1 completamente desagradable; y ninguno puede juzgar al otro. Pero la fe y el amor nunca deben perder de vista las lecciones que hablan en el mismo silencio de aquellos a\u00f1os. Diez veces m\u00e1s de la vida que nuestro Se\u00f1or Jes\u00fas ocup\u00f3 en el ministerio p\u00fablico, la pas\u00f3 en la vida privada, sin predicar ning\u00fan serm\u00f3n, sin iniciar ning\u00fan movimiento p\u00fablico, sin obrar ning\u00fan milagro. El ideal divino de la santidad perfecta en la ni\u00f1ez, la juventud y la edad adulta se realiz\u00f3 durante treinta a\u00f1os en una vida de oscura privacidad, trabajo mec\u00e1nico y afecto y deber hogare\u00f1os. (<em>ERConder, DD<\/em>)<\/p>\n<\/p>\n<p>Treinta a\u00f1os de preparaci\u00f3n y unos tres a\u00f1os de trabajo. Cu\u00e1n contrario a nuestras nociones de una sabia econom\u00eda del trabajo. poderes de una vida humana! Es posible que haya una referencia a la edad en que, seg\u00fan la ley, los levitas deb\u00edan comenzar sus ministerios; pero cuando consideramos el breve tiempo que dur\u00f3 el ministerio actual, ciertamente podemos sacar la conclusi\u00f3n de que para hacer una gran obra en poco tiempo es necesaria una preparaci\u00f3n larga y paciente; y que los que quieren ser ministros \u00fatiles de la Iglesia de Cristo no deben escatimar tiempo ni cantidad de trabajo para prepararse para la gran obra que se les ha encomendado. (<em>Obispo Harvey Goodwin.<\/em>)<\/p>\n<\/p>\n<p>El autor del \u201cNuevo Fedo\u201d considera los treinta a\u00f1os la \u00e9poca de la partida de la juventud; por lo cual, por supuesto, no pretende significar una decadencia incipiente, siendo nuestros cuerpos tan j\u00f3venes como lo eran cinco a\u00f1os antes, mientras que la mente ha estado madurando; por juventud se refiere a la estaci\u00f3n creciente y progresiva, cuya partida es visible s\u00f3lo en la medida en que nos hemos vuelto, por as\u00ed decirlo, fijos y estacionarios. Las cualidades que pertenecen peculiarmente a la juventud, sus fantas\u00edas r\u00e1pidas y palpitantes, su exuberancia de energ\u00eda y sentimiento, dejan, seg\u00fan sus c\u00e1lculos, de ser nuestras distinciones a los treinta. <br \/>Maynard, en la obra, habla de s\u00ed mismo como de casi treinta a\u00f1os: \u00abadvertencia de treinta\u00bb. \u00ab\u00bfAdvertencia treinta?\u00bb repite su compa\u00f1ero, medio burl\u00f3n, medio inquisitivo. El otro explica: \u201cEs la mitad del viaje, Tom. Depende de ello, despu\u00e9s de los treinta, es hora de contar los hitos\u201d. A la edad de treinta a\u00f1os, seg\u00fan Lord Lytton, el car\u00e1cter de la mayor\u00eda de los hombres pasa por una revoluci\u00f3n; hemos reducido a la sobria prueba de la realidad las visiones de la juventud; ya no perseguimos frivolidades ni esperamos quimeras; y ahora podemos llegar con mejor \u00e9xito que Rasselas a la elecci\u00f3n de la vida. Siempre debe notarse el hecho significativo de que cuando nuestro Se\u00f1or ten\u00eda unos treinta a\u00f1os de edad, entonces comenz\u00f3 Su obra en serio, Su ministerio en p\u00fablico. Para muchos, esa edad es la se\u00f1al de la indulgencia ego\u00edsta en los arrepentimientos. Para \u00c9l lleg\u00f3 la hora del trabajo duro, trabajo que debe cesar sino en la muerte. (<em>F. Jacox.<\/em>)<\/p>\n<\/p>\n<p><strong>Los logros de la juventud<\/strong><\/p>\n<p>Casi todo lo que es grande ha sido hecho por j\u00f3venes. Para la vida en general no hay m\u00e1s que un decreto. La juventud es un error garrafal; la virilidad una lucha; la vejez un arrepentimiento. No supongas que sostengo que la juventud es genio; todo lo que es genio, cuando joven, es Divino. \u00a1Vaya, los m\u00e1s grandes capitanes de los tiempos antiguos y modernos conquistaron Italia a los veinticinco a\u00f1os! La juventud, la extrema juventud, derroc\u00f3 al imperio persa. Don Juan de Austria gan\u00f3 Lepanto a los veinticinco a\u00f1os, la mayor batalla de los tiempos modernos. Si no hubiera sido por los celos de Felipe, al a\u00f1o siguiente habr\u00eda sido emperador de Mauritania. Gaston de Foix ten\u00eda s\u00f3lo veintid\u00f3s a\u00f1os cuando se alz\u00f3 victorioso en la llanura de R\u00e1vena. Todos recuerdan a Conde y Rocroy a la misma edad. Gustavus Adolphus muri\u00f3 a los treinta y ocho. F\u00edjate en sus capitanes: ese maravilloso duque de Weimar, de s\u00f3lo treinta y seis a\u00f1os cuando muri\u00f3; El mismo Banter, despu\u00e9s de todos sus milagros, muri\u00f3 a los cuarenta y cinco. Cort\u00e9s ten\u00eda poco m\u00e1s de treinta a\u00f1os cuando contempl\u00f3 las c\u00fapulas doradas de M\u00e9xico. Cuando Mauricio de Sajonia muri\u00f3 a los treinta y dos a\u00f1os, toda Europa reconoci\u00f3 la p\u00e9rdida del capit\u00e1n m\u00e1s grande y el estadista m\u00e1s profundo de la \u00e9poca. Luego est\u00e1n Nelson, Clive, pero estos son guerreros, y tal vez pienses que hay cosas m\u00e1s grandes que la guerra. Yo no; Adoro al Se\u00f1or de los ej\u00e9rcitos. Pero tomemos los logros m\u00e1s ilustres de la prudencia civil. Inocencio III, el m\u00e1s grande de los Papas, fue el d\u00e9spota de la cristiandad a los treinta y siete a\u00f1os. Juan de Medici era cardenal a los quince a\u00f1os y, nos dice Guicciardini, desconcert\u00f3 con su arte de gobernar al mismo Fernando de Arag\u00f3n; fue Papa como Le\u00f3n X. a los treinta y siete a\u00f1os. Lutero le rob\u00f3 incluso a \u00e9l su provincia m\u00e1s rica a los treinta y cinco a\u00f1os. Tomemos a Ignacio de Loyola y Juan Wesley; trabajaron con cerebros j\u00f3venes. Ignacio ten\u00eda solo treinta a\u00f1os cuando hizo su peregrinaje y escribi\u00f3 los \u201cEjercicios Espirituales\u201d. Pascal escribi\u00f3 una gran obra a los diecis\u00e9is a\u00f1os, el m\u00e1s grande de los franceses, y muri\u00f3 a los treinta y siete. \u00a1Ah, ese fatal treinta y siete! \u00bfFue la experiencia la que gui\u00f3 el l\u00e1piz de Rafael cuando pint\u00f3 los palacios de Roma? Muri\u00f3 a los treinta y siete. Richelieu era secretario de Estado a los treinta y un a\u00f1os. Luego estaban Bolingbroke y Pitt, ambos ministros antes de que otros hombres dejaran el cricket. Grotius ten\u00eda una gran pr\u00e1ctica a los diecisiete a\u00f1os y Fiscal General a los veinticuatro. Y Acquaviva&#8230; Acquaviva fue general de los jesuitas, gobern\u00f3 todos los gabinetes de Europa y coloniz\u00f3 Am\u00e9rica antes de cumplir los treinta y siete a\u00f1os. \u00a1Qu\u00e9 carrera! No hace falta multiplicar las instancias. La historia de los h\u00e9roes es la historia de la juventud.(<em>Lord Beaconsfield.<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lc 3,21 Siendo tambi\u00e9n Jes\u00fas bautizados&#8211; Encuentro de Jes\u00fas con Juan La gente, le\u00ed, \u201creflexionaba\u201d, pregunt\u00e1ndose si Juan era el Mes\u00edas esperado. . John tambi\u00e9n, reflexion\u00f3, podemos estar seguros. \u00ab\u00a1Palabras! \u00a1palabras! \u00a1palabras!\u00bb al final de cada d\u00eda largo y bochornoso, mientras lo acostaba en alguna cueva rocosa, a qu\u00e9 hora el sol se hund\u00eda repentinamente &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-321-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Lucas 3:21 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39291","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=39291"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39291\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=39291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=39291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=39291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}