{"id":39312,"date":"2022-07-16T08:53:23","date_gmt":"2022-07-16T13:53:23","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-433-37-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:53:23","modified_gmt":"2022-07-16T13:53:23","slug":"estudio-biblico-de-lucas-433-37-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-433-37-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Lucas 4:33-37 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Lc 4,33-37<\/span><\/p>\n<p> <em>Y en la sinagoga hab\u00eda un hombre que ten\u00eda un esp\u00edritu de un demonio inmundo<\/em><\/p>\n<p><strong>La expulsi\u00f3n del esp\u00edritu inmundo<\/strong><\/p>\n<p><strong><br \/>I.<\/strong><\/p>\n<p>Observar LA CONFESI\u00d3N DEL ESP\u00cdRITU INMUNDO acerca del Redentor. Aqu\u00ed se admiten la justicia y la pureza de Cristo. <\/p>\n<p><strong>1.<\/strong> Se declara que es \u201cel Santo de Dios\u201d. <\/p>\n<p><strong>(1)<\/strong> Hijo de Dios\u2014Siervo de Dios. <\/p>\n<p><strong>(2)<\/strong> Tener la naturaleza y los atributos santos de Dios. <\/p>\n<p><strong>(3)<\/strong> Formal en cuanto a Su humanidad por la sombra del Esp\u00edritu Santo. <\/p>\n<p><strong>(4)<\/strong> Viniendo al mundo para exhibir en toda su excelencia la santa ley de Dios. <\/p>\n<p><strong>(5)<\/strong> En la santa misi\u00f3n de redimir a los hombres del pecado y llevarlos a la bienaventuranza de la santidad personal. <\/p>\n<p><strong>(6)<\/strong> En el mundo con el prop\u00f3sito expreso de establecer un reino santo, un reino de justicia, paz y gozo en el Esp\u00edritu Santo. <\/p>\n<p><strong>2.<\/strong> Esta confesi\u00f3n fue audaz y p\u00fablica. <\/p>\n<p><strong>3.<\/strong> Era despectivo. El lenguaje del terror. Los demonios sab\u00edan que su tiempo era limitado, su poder estaba circunscrito y que su gobierno y dominio infernales iban a ser derrocados por el Hijo de Dios. <\/p>\n<p><strong><br \/>II. <\/strong>Observar EL CURSO CRISTO ADOPTADO. <\/p>\n<p><strong>1.<\/strong> Reprensi\u00f3n. <\/p>\n<p><strong>2.<\/strong> Expulsi\u00f3n. <\/p>\n<p><strong><br \/>III. <\/strong>Observe LOS RESULTADOS QUE SIGUEN. <\/p>\n<p><strong>1.<\/strong> El esp\u00edritu inmundo da una \u00faltima lucha para herir a su v\u00edctima. <\/p>\n<p><strong>2.<\/strong> Sali\u00f3 del hombre. <\/p>\n<p><strong>3.<\/strong> El pueblo rindi\u00f3 homenaje y gloria a Cristo. <\/p>\n<p><strong>4.<\/strong> La fama de Cristo se extendi\u00f3 por todo el mundo. <\/p>\n<p>Aplicaci\u00f3n: <\/p>\n<p><strong>1.<\/strong> La mente no renovada est\u00e1 bajo el poder del esp\u00edritu inmundo. <\/p>\n<p><strong>2.<\/strong> Aquellos que son as\u00ed influenciados est\u00e1n en circunstancias de miseria y peligro. <\/p>\n<p><strong>3.<\/strong> Solo Cristo tiene poder para salvar y liberar. <\/p>\n<p><strong>4.<\/strong> En el evangelio se proclama esta liberaci\u00f3n. (<em>Jabez Burns, DD<\/em>)<\/p>\n<\/p>\n<p><strong>Posesi\u00f3n demon\u00edaca<\/strong><\/p>\n<p>\u00bfDeber\u00edan los pose\u00eddos mencionados por los evangelistas ser considerados simplemente como personas afligidas de la misma manera que nuestros lun\u00e1ticos, cuyo trastorno fue atribuido por la superstici\u00f3n jud\u00eda y pagana a la influencia sobrenatural? \u00bfO realmente permiti\u00f3 Dios, en esta \u00e9poca extraordinaria de la historia, una exhibici\u00f3n excepcional de poder diab\u00f3lico? O, por \u00faltimo, \u00bfdeber\u00edan atribuirse, tambi\u00e9n en la actualidad, a la acci\u00f3n de causas superiores ciertas condiciones morbosas, ahora existentes, que la ciencia m\u00e9dica atribuye a causas puramente naturales, ya sean f\u00edsicas o ps\u00edquicas? Estas son las tres hip\u00f3tesis que se presentan a la mente. Varios de los endemoniados sanados por Jes\u00fas ciertamente exhiben s\u00edntomas muy parecidos a los que se observan en la actualidad en aquellos que simplemente est\u00e1n afligidos; por ejemplo, el ni\u00f1o epil\u00e9ptico (<span class='bible'>Luk 9:37<\/span>). Estas extra\u00f1as condiciones en todos los casos, por lo tanto, se basaban en un verdadero desorden, ya sea f\u00edsico o psicops\u00edquico. Los evangelistas est\u00e1n tan lejos de ignorar esto, que constantemente clasifican a los endemoniados bajo la categor\u00eda de los enfermos, nunca bajo la de los viciosos. Los pose\u00eddos no tienen nada en com\u00fan con los \u201chijos del diablo\u201d. Sin embargo, estas personas afligidas se convierten constantemente en una clase por s\u00ed mismas. \u00bfEn qu\u00e9 descansa esta distinci\u00f3n? Sobre este hecho principal, que aquellos que simplemente est\u00e1n enfermos disfrutan de su propia conciencia personal y est\u00e1n en posesi\u00f3n de su propia voluntad; mientras que en el pose\u00eddo estas facultades son, por as\u00ed decirlo, confiscadas a una potencia extranjera, con la que el enfermo se identifica. \u00bfC\u00f3mo se explica este peculiar sistema? Josefo, bajo la influencia hel\u00e9nica, pens\u00f3 que deber\u00eda atribuirse a las almas de los hombres malvados que vinieron despu\u00e9s de la muerte buscando un domicilio en los vivos. A los ojos de la gente el extra\u00f1o hu\u00e9sped era un demonio, un \u00e1ngel ca\u00eddo. Esta \u00faltima opini\u00f3n Jes\u00fas debe haberla compartido. Estrictamente hablando, sus coloquios con los demon\u00edacos podr\u00edan explicarse por una acomodaci\u00f3n al prejuicio popular y los sentimientos de aquellos que estaban as\u00ed afligidos; pero en Sus conversaciones privadas con Sus disc\u00edpulos, \u00c9l debe haber revelado Sus verdaderos pensamientos, cualquiera que sea la verdad, y procurado iluminarlos. Pero \u00c9l no hace nada por el estilo; al contrario, da a los ap\u00f3stoles y disc\u00edpulos poder para \u201cechar fuera demonios\u201d (<span class='bible'>Lc 9,1<\/span>), y para hollar \u201ctoda el poder del enemigo\u201d (<span class='bible'>Lc 10,19<\/span>). En <span class='bible'>Mar 9:29<\/span> \u00c9l distingue una cierta clase de demonios que solo pueden ser expulsados con oraci\u00f3n y ayuno. En <span class='bible'>Lc 11,21<\/span> explica la facilidad con que echa fuera demonios por la victoria personal que hab\u00eda logrado sobre Satan\u00e1s en el principio. Por lo tanto, admiti\u00f3 la intervenci\u00f3n de este ser en estas condiciones misteriosas. Si esto es as\u00ed, \u00bfno es natural admitir que Aquel que ejerci\u00f3 sobre esta, como sobre toda otra clase de enfermedades, tal poder absoluto, comprendi\u00f3 mejor su naturaleza, y que por lo tanto Sus puntos de vista sobre el punto deben determinar los nuestros? \u00bfNo hay momentos en que Dios permite que un poder maligno superior invada a la humanidad? As\u00ed como Dios envi\u00f3 a Jes\u00fas en un per\u00edodo de la historia cuando el mal moral y social hab\u00eda llegado a su punto culminante, \u00bfno permiti\u00f3 tambi\u00e9n que se produjera al mismo tiempo una extraordinaria manifestaci\u00f3n de poder diab\u00f3lico? Por este medio Jes\u00fas podr\u00eda ser proclamado externa y visiblemente como el vencedor del enemigo de los hombres, como Aquel que vino a \u201cdestruir las obras del diablo\u201d en el sentido moral de la expresi\u00f3n. En cuanto al estado actual de las cosas, no debe compararse con los tiempos de Jes\u00fas. Este \u00faltimo no s\u00f3lo podr\u00eda haber tenido un car\u00e1cter excepcional; pero la influencia ben\u00e9fica que ha ejercido el evangelio al restaurar al hombre a s\u00ed mismo y poner su conciencia bajo el poder del Dios santo y verdadero, puede haber producido un cambio completo en el mundo espiritual. Finalmente, aparte de todo esto, no hay nada misterioso, desde un punto de vista cient\u00edfico, en ciertos casos de perturbaci\u00f3n mental, particularmente en aquellas condiciones en las que la voluntad es, por as\u00ed decirlo, confiscada y paralizada por un poder desconocido. ? Y despu\u00e9s de haber hecho la deducci\u00f3n de todas aquellas formas de enfermedades mentales que un an\u00e1lisis discriminatorio puede explicar por relaciones morales y f\u00edsicas, \u00bfno admitir\u00e1 un m\u00e9dico imparcial que hay un residuo de casos respecto de los cuales debe decir: Non liquet? La posesi\u00f3n es una caricatura de la inspiraci\u00f3n. Este \u00faltimo, adhiri\u00e9ndose a la esencia moral de un hombre, lo confirma para siempre en la posesi\u00f3n de su verdadero yo; el primero, aunque profundamente opuesto a la naturaleza del sujeto, se aprovecha de su estado de pasividad morbosa y conduce a la p\u00e9rdida de la personalidad. El uno es la obra m\u00e1s alta de Dios; el otro, del diablo. (<em>F. Coder, DD<\/em>)<\/p>\n<\/p>\n<p><strong>El endemoniado en la sinagoga<\/strong><\/p>\n<p>Hombres extra\u00f1os en lugares extra\u00f1os \u00a1Pienso en un diablo en la sinagoga! Es lo mismo hoy. El santuario atrae a s\u00ed mismo todo tipo de car\u00e1cter humano; no s\u00f3lo est\u00e1n los ricos y los pobres, sino tambi\u00e9n los mejores y los peores. El mal conoce el bien y lo odia. El mal no es tan poderoso en realidad como el bien, aunque aparentemente mucho m\u00e1s poderoso. Jes\u00fas es mayor que todos los esp\u00edritus malignos. \u201c\u00bfHas venido a destruirnos?\u201d es una indagaci\u00f3n significativa. \u201cPara esto fue manifestado, para deshacer las obras del diablo.\u201d (<em>J. Parker, DD<\/em>)<\/p>\n<\/p>\n<p><strong>El Rey expulsando malos esp\u00edritus<\/strong><\/p>\n<p>La superstici\u00f3n que conecta a los demonios con un desierto se ha usado para explicar la tentaci\u00f3n de nuestro Se\u00f1or. Esa explicaci\u00f3n no tiene nada que ver con la historia que nos dan los evangelistas. Describen el encuentro del Esp\u00edritu de Cristo con el esp\u00edritu del mal; la prueba de su veracidad est\u00e1 en la experiencia de los seres humanos tanto en las ciudades como en los desiertos, tanto en un per\u00edodo como en otro. Me parece, pues, muy razonable, no s\u00f3lo por algo que haya sido peculiar de ese tiempo, sino por el bien de todos los tiempos, que el evangelista d\u00e9 a estas victorias sobre los demonios un lugar destacado en la historia de Redenci\u00f3n. La impresi\u00f3n producida en la sinagoga de Capernaum es el testimonio m\u00e1s simple de la naturaleza de tal signo. \u201c\u00bfQu\u00e9 palabra es esta? \u00bb ellos dijeron. Exist\u00eda la sensaci\u00f3n de Aquel que no \u00abhac\u00eda desaparecer los males con una mirada o un toque\u00bb. La serena energ\u00eda divina con la que declar\u00f3 que el reino de Dios estaba verdaderamente entre los hombres, que el poder de Dios se manifestaba como en la antig\u00fcedad rompiendo grillos y liberando a los cautivos, se manifest\u00f3 en el mandato de que el esp\u00edritu inmundo se fuera. El esp\u00edritu maligno no era el se\u00f1or del hombre. Los reinos de este mundo y la gloria de ellos no eran suyos. La santidad era m\u00e1s poderosa. (<em>FD Maurice.<\/em>)<\/p>\n<\/p>\n<p><strong>Pose\u00eddo por el diablo<\/strong><\/p>\n<p>Un caso conmovedor fue el de William Pope, de Bolton, en Lancashire. En este lugar hay un n\u00famero considerable de personas de\u00edstas, que se re\u00fanen los domingos para confirmarse mutuamente en su infidelidad. Los juramentos e imprecaciones que se pronuncian en esa reuni\u00f3n son demasiado horribles para relatarlos, mientras arrojan la Palabra de Dios al suelo, la patean alrededor de la casa y la pisotean. Este William Pope, que hab\u00eda sido un metodista constante durante algunos a\u00f1os, se convirti\u00f3 finalmente en un de\u00edsta profeso y se uni\u00f3 a esta pandilla infernal. Despu\u00e9s de haber sido socio de esta compa\u00f1\u00eda por alg\u00fan tiempo, enferm\u00f3, y la naturaleza de su dolencia fue tal, que confes\u00f3 que la mano de Dios estaba sobre \u00e9l, y declar\u00f3 que deseaba morir para poder ir a infierno, muchas veces orando fervientemente por la condenaci\u00f3n. Dos de los predicadores metodistas, los Sres. Rhodes y Barrowclough, fueron enviados para hablar y orar con el hombre infeliz. Pero estaba tan lejos de estar agradecido por su consejo y ayuda, que les escupi\u00f3 en la cara, les arroj\u00f3 todo lo que pudo, golpe\u00f3 a uno de ellos en la cabeza con todas sus fuerzas, y a menudo gritaba, cuando estaban orando, \u201c\u00a1Se\u00f1or, no escuches sus oraciones!\u201d Si dec\u00edan: \u201cSe\u00f1or, salva su scull\u201d, \u00e9l gritaba: \u201cSe\u00f1or, maldita sea mi scull\u201d, y a menudo agregaba: \u201c\u00a1Mi condenaci\u00f3n est\u00e1 sellada y anhelo estar en el infierno!\u201d. As\u00ed sigui\u00f3, unas veces mejor y otras peor, hasta que muri\u00f3. Fue visitado con frecuencia por sus hermanos de\u00edstas durante su enfermedad, quienes de buena gana habr\u00edan persuadido al p\u00fablico de que estaba fuera de s\u00ed, lo que de ninguna manera fue f\u00e1cil. El escritor de este relato vio al infeliz una vez, pero nunca dese\u00f3 volver a verlo. El Sr. Rhodes dijo con raz\u00f3n que estaba tan lleno del diablo como pod\u00eda contener. (<em>Simpson&#8217;s \u201cPlea for religion.\u201d<\/em>)<\/p>\n<\/p>\n<p><strong>El testimonio del esp\u00edritu maligno a Cristo, y su negativa a aceptarlo<\/strong><\/p>\n<p>La tierra no ha reconocido a su Rey; pero el cielo ha dado testimonio de \u00c9l, y ahora el infierno tambi\u00e9n debe dar su testimonio. Pero \u00bfcu\u00e1l pudo haber sido el motivo de este testimonio, as\u00ed dado? Es extra\u00f1o que el esp\u00edritu maligno, sin compulsi\u00f3n, proclame al mundo la presencia en medio de \u00e9l del Santo de Dios, de Aquel que as\u00ed traer\u00e1 a todos los imp\u00edos, sobre los cuales se ciment\u00f3 y por los cuales vivi\u00f3. , hasta el fin. \u00bfNo podr\u00edamos m\u00e1s bien esperar que \u00e9l hubiera negado, o tratado de oscurecer, la gloria de la persona de Cristo? No se puede replicar que esta fue una confesi\u00f3n involuntaria de la verdad, arrancada a la fuerza por el poder superior de Cristo, ya que desagradaba a Aquel en cuyo favor profesaba ser dada, y esto tanto que \u00c9l inmediatamente tap\u00f3 la boca del que la pronunciaba. Queda, pues, por entender esto como el grito de un temor abyecto y servil, que con adulaciones y halagos desear\u00eda apartar de s\u00ed mismo el destino que, con la presencia de Cristo en el mundo, evidentemente debe estar cerca; o bien, considerar este testimonio como destinado \u00fanicamente a da\u00f1ar la estimaci\u00f3n de Aquel en cuyo favor se rindi\u00f3. Hab\u00eda esperanza de que la verdad misma pudiera ser sospechosa y desacreditada, recibiendo as\u00ed el testimonio del esp\u00edritu de la mentira; y estas confesiones de Jes\u00fas como el Cristo pueden haber tenido la intenci\u00f3n de trastornar y estropear Su obra. El hecho de que Cristo no permitir\u00eda el testimonio hace que esta sea la explicaci\u00f3n preferible. Observe que no est\u00e1 aqu\u00ed como en otros lugares, \u00abJehov\u00e1 te reprenda\u00bb, sino que \u00c9l reprende en Su propio nombre y por Su propia autoridad. (<em>Arzobispo Trench.<\/em>)<\/p>\n<\/p>\n<p><strong>Cristo en Capernaum<\/strong><\/p>\n<p><strong><br \/> YO. <\/strong>SU PREDICACI\u00d3N: \u201cDescendi\u00f3 a Cafarna\u00fam, ciudad de Galilea, y les ense\u00f1aba en los d\u00edas de reposo. Y se asombraban de su doctrina, porque su palabra era con poder.\u201d <\/p>\n<p><strong>1.<\/strong> Observa el lugar: Capernaum. <\/p>\n<p><strong>2.<\/strong> La temporada: \u201cLos d\u00edas de reposo\u201d. No es que se abstuviera de otros d\u00edas; Sus labios siempre \u201cca\u00edan como un panal de miel\u201d. <\/p>\n<p><strong>3.<\/strong> Luego la impresi\u00f3n. <\/p>\n<p><strong><br \/>II. <\/strong>PASEMOS DE SU ENSE\u00d1ANZA A SU MILAGRO. <\/p>\n<p><strong>1.<\/strong> Echemos un vistazo al tema de este milagro. Era \u201cun hombre que estaba pose\u00eddo por un esp\u00edritu de un demonio inmundo\u201d. Satan\u00e1s tiene mucho que hacer en la sinagoga, mucho m\u00e1s que en muchos otros lugares. En \u201cDi\u00e1logos de demonios\u201d de Macgowan existe esta relaci\u00f3n. Habi\u00e9ndose encontrado dos esp\u00edritus infernales, uno de ellos muy c\u00e1lido y cansado, y el otro fr\u00edo y vivo; despu\u00e9s de una peque\u00f1a explicaci\u00f3n se descubri\u00f3 que \u00e9l, que era tranquilo y animado, hab\u00eda estado en la casa de juegos donde no ten\u00eda nada que hacer, donde todos estaban con \u00e9l, donde todos estaban de una mente, todos haciendo su trabajo: mientras que el otro quien estaba acalorado y cansado, dijo: \u201cHe estado en un lugar de adoraci\u00f3n, y ten\u00eda mucho que hacer all\u00ed; para hacer un poco de sue\u00f1o; inducir a algunos a escuchar por otros en lugar de ellos mismos; para llevar los pensamientos de algunos, como el ojo del necio, hasta los confines de la tierra; recoger lo m\u00e1s r\u00e1pido que pudiera la semilla que fue sembrada en el coraz\u00f3n; y para apartar la punta de la espada del Esp\u00edritu, que es la Palabra de Dios, para que no traspase hasta dividir el alma y el cuerpo, las coyunturas y los tu\u00e9tanos, y discierna los pensamientos y las intenciones de el coraz\u00f3n.\u00bb Espero que ninguno <em>ustedes<\/em> lo empleen as\u00ed. <\/p>\n<p><strong>(1)<\/strong> Primero, aversi\u00f3n. \u201cD\u00e9janos solos\u201d, como est\u00e1 en el margen, \u201cfuera\u201d; me voy. Satan\u00e1s no deseaba tener nada que ver con Cristo. <\/p>\n<p><strong>(2)<\/strong> Luego expres\u00f3 temor: \u00ab\u00bfHas venido a destruirnos?\u00bb <\/p>\n<p><strong>(3)<\/strong> Expres\u00f3 elogio: \u201cTe conozco, qui\u00e9n eres, el Santo de Dios. <\/p>\n<p>Aqu\u00ed, ya ves, el diablo no s\u00f3lo cre\u00eda mucho, sino que hablaba bien. <\/p>\n<p><strong>2.<\/strong> Miremos al Autor de este milagro, y veremos c\u00f3mo el enemigo de las almas est\u00e1 bajo el dominio del Se\u00f1or Jes\u00fas; que aunque es un adversario, sin embargo, est\u00e1 restringido, est\u00e1 encadenado. <\/p>\n<p><strong>3.<\/strong> Entonces, en cuanto a los espectadores: \u201cTodos estaban at\u00f3nitos, y hablaban entre s\u00ed, diciendo: \u00a1Qu\u00e9 palabra es \u00e9sta, que con autoridad y poder ordena! los esp\u00edritus inmundos, y salen\u201d. \u00a1Vaya! \u00a1si hubieran mejorado tanto como admirado! <\/p>\n<p><strong><br \/>III. <\/strong>ENTONCES AQU\u00cd EST\u00c1 SU FALSO: \u201cY su fama se difundi\u00f3 por todos los lugares de la tierra de alrededor\u201d. \u00bfQui\u00e9n no se regocija en esta difusi\u00f3n de Su fama? \u00bfQui\u00e9n no desea que su fama se extienda por todas partes? La gratitud requiere que est\u00e9s as\u00ed empleado. Pues la benevolencia requiere que os dediqu\u00e9is a ello, Muchos est\u00e1n pereciendo; y est\u00e1n pereciendo por falta de conocimiento, y del conocimiento de \u00c9l; porque \u201cconocerlo es vida eterna.\u201d(<em>W. Jay.<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lc 4,33-37 Y en la sinagoga hab\u00eda un hombre que ten\u00eda un esp\u00edritu de un demonio inmundo La expulsi\u00f3n del esp\u00edritu inmundo I. Observar LA CONFESI\u00d3N DEL ESP\u00cdRITU INMUNDO acerca del Redentor. Aqu\u00ed se admiten la justicia y la pureza de Cristo. 1. Se declara que es \u201cel Santo de Dios\u201d. (1) Hijo de Dios\u2014Siervo &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-433-37-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Lucas 4:33-37 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39312","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=39312"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39312\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=39312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=39312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=39312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}