{"id":39318,"date":"2022-07-16T08:53:39","date_gmt":"2022-07-16T13:53:39","guid":{"rendered":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-443-comentario-ilustrado-de-la-biblia\/"},"modified":"2022-07-16T08:53:39","modified_gmt":"2022-07-16T13:53:39","slug":"estudio-biblico-de-lucas-443-comentario-ilustrado-de-la-biblia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-443-comentario-ilustrado-de-la-biblia\/","title":{"rendered":"Estudio B\u00edblico de Lucas 4:43 | Comentario Ilustrado de la Biblia"},"content":{"rendered":"<p><span class='bible'>Lc 4,43<\/span><\/p>\n<p><em>Debo predicar el reino de Dios a otras ciudades&#8211;<\/em><\/p>\n<p><strong>Un precedente para los predicadores<\/strong><\/p>\n<p>Cristo as\u00ed admirado y deseado para quedarse en Cafarna\u00fam, no quiso h\u00e1ganlo tambi\u00e9n, como teniendo un ojo en Su comodidad o conveniencia all\u00ed, pero deben esforzarse por predicar en otros lugares.<\/p>\n<p>Ense\u00f1\u00e1ndonos que no debemos medir nuestros servicios de nosotros mismos o conveniencias, ni en ellos buscar nuestro propia facilidad o aceptaci\u00f3n entre los hombres; pero ll\u00e9venlas como sea posible para la gloria de Dios y nuestro propio sano consuelo. Nuestro Salvador Cristo no admiti\u00f3 su moci\u00f3n, pero les dio esta respuesta en las palabras del texto: \u201cCiertamente tambi\u00e9n yo debo predicar\u201d. En donde se consideran cinco puntos. <\/p>\n<p><strong>1.<\/strong> La obra que Cristo debe hacer\u2014\u00c9l debe \u201cpredicar\u201d. <\/p>\n<p><strong>2.<\/strong> La necesidad de ello: \u00abDebo\u00bb. <\/p>\n<p><strong>3.<\/strong> El asunto de lo que \u00c9l debe predicar: \u201cel reino de Dios\u201d. <\/p>\n<p><strong>4.<\/strong> El objeto o la gente a quien&#8211;\u201ca otras ciudades tambi\u00e9n\u201d. <\/p>\n<p><strong>5.<\/strong> El lazo de esta necesidad&#8211;\u201cPor eso soy enviado.\u201d <\/p>\n<p><strong><br \/>Yo. <\/strong>LA OBRA ES LA PREDICACI\u00d3N. As\u00ed, la predicaci\u00f3n se llama la revelaci\u00f3n del misterio de Cristo, y la publicaci\u00f3n del misterio del evangelio, y la revelaci\u00f3n de un misterio escondido desde el principio del mundo. Por tanto, obs\u00e9rvese la grandeza de la obra de la predicaci\u00f3n, y la gran estimaci\u00f3n de la misma, para cuyo fin el Hijo de Dios mismo vino del cielo. La gran obra de Dios considerada en los medios parece vil y vil, y nada aturde m\u00e1s la mente de los hombres carnales que la bajeza de los medios, comparada con la magnificencia de los efectos. A los hombres de Jeric\u00f3 les parecer\u00eda rid\u00edculo que el sonido de los cuernos de carnero y el sonido de las trompetas derribaran los muros de piedra, y no es de extra\u00f1ar que se rieran de medios tan inveros\u00edmiles; pero sin embargo fue as\u00ed: as\u00ed que esta obra de predicar a los ojos de un hombre carnal es una locura, como <span class='bible'>1Co 1:21<\/span>, pero sin embargo \u201ca los que son llamados, es el poder de Dios para salvaci\u00f3n.\u201d Aqu\u00ed he aqu\u00ed que la debilidad se encuentra con la fuerza y la domina, la sencillez supera la pol\u00edtica y el poder de Dios prevalece en sus propios medios d\u00e9biles. <\/p>\n<p><strong><br \/>II. <\/strong>La segunda parte del texto es LA NECESIDAD DE LA PREDICACI\u00d3N: \u201cDebo predicar\u201d. No depende de Su voluntad, ni se deja a Su discreci\u00f3n; pero \u00c9l debe hacerlo. Ahora bien, mucha m\u00e1s necesidad recae sobre nosotros sus ministros. Ahora bien, si estamos obligados a predicar, est\u00e1is obligados a o\u00edr; si estamos obligados a entregar la Palabra, vosotros est\u00e1is obligados a recibir la Palabra, no como la palabra de un hombre; sino como es verdaderamente la Palabra de Dios, con toda reverencia, deber y piedad. <\/p>\n<p><strong><br \/>III. <\/strong>El tercer punto es EL TEMA DE ESTA PREDICACI\u00d3N: el reino de Dios. El reino de Dios es doble. <\/p>\n<p><strong>1.<\/strong> De la gracia. <\/p>\n<p><strong>2.<\/strong> De gloria. <\/p>\n<p>En el primero Dios reina en nosotros. En este \u00faltimo reinamos con Dios. El primero es en esta vida, el segundo en la venidera. El uno desemboca en el otro, y ambos se hacen uno: porque no leemos de los reinos de Dios en plural, sino de Su reino, que es uno solo. Este es el tabern\u00e1culo de Dios que est\u00e1 con los hombres. A este reino Dios nos llama por la predicaci\u00f3n, y aqu\u00ed debe comenzar por la justicia, el arrepentimiento, la mortificaci\u00f3n, y tendr\u00e1 plenitud en lo sucesivo. Todos los hombres desean participar del reino de Cristo y de la gloria, pero pocos estar\u00e1n sujetos a su Padre en el reino de la gracia. Nosotros, a quienes Dios ha encomendado la predicaci\u00f3n de Su Palabra, debemos tener cuidado de promover este reino y atraer a muchos para que sean s\u00fabditos de \u00e9l, esperando esa gloriosa recompensa de brillar como las estrellas en el firmamento por los siglos de los siglos. <\/p>\n<p><strong><br \/>IV.<\/strong> LAS PERSONAS A QUIENES CRISTO DEBE PREDICAR&#8211;\u201ca otras ciudades\u201d. As\u00ed como el sol rodea el mundo y no se detiene en ninguna parte, as\u00ed Cristo, el Sol de Justicia, nunca se posa en un solo lugar, sino que busca dispersar por todas partes Su bendita luz. Hab\u00eda estado en el poder de Cristo mismo haber mantenido un lugar siempre, y haber enviado a sus disc\u00edpulos a todos los dem\u00e1s, pero no quiso: que con su ejemplo aprendamos a no rehuir el trabajo, sino a emplear nuestros dolores y diligencia en la edificaci\u00f3n del reino. de Dios, y en buscar y salvar lo que se ha perdido. As\u00ed fue Cristo como un M\u00e9dico compasivo, que no siendo llamado, ofrece sus cuidados y dolores, dispuesto a salvar a los que est\u00e1n en peligro. <\/p>\n<p><strong><br \/>V. <\/strong>El v\u00ednculo de esta necesidad&#8211;\u201cporque por eso he sido enviado\u201d. Deber\u00eda traicionar el fin de Su venida si no predicara. El punto que debemos aprender aqu\u00ed es que cada hombre debe servir al fin y uso para el que ha sido llamado, y cumplir cuidadosamente la confianza que se le ha encomendado (<span class='bible'>Rm 12,7-8<\/span>). Los paganos consideraban vergonzoso y peligroso fallar en materia de confianza, como si la parte hubiera cometido un robo. (<em>T. Taylor, DD<\/em>)<\/p>\n<p>. <\/p>\n<p><\/p>\n<p><strong><br \/><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lc 4,43 Debo predicar el reino de Dios a otras ciudades&#8211; Un precedente para los predicadores Cristo as\u00ed admirado y deseado para quedarse en Cafarna\u00fam, no quiso h\u00e1ganlo tambi\u00e9n, como teniendo un ojo en Su comodidad o conveniencia all\u00ed, pero deben esforzarse por predicar en otros lugares. Ense\u00f1\u00e1ndonos que no debemos medir nuestros servicios de &hellip; <a href=\"https:\/\/www.biblia.work\/comentario\/estudio-biblico-de-lucas-443-comentario-ilustrado-de-la-biblia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio B\u00edblico de Lucas 4:43 | Comentario Ilustrado de la Biblia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39318","post","type-post","status-publish","format-standard","hentry","category-comentario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/comments?post=39318"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/posts\/39318\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/media?parent=39318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/categories?post=39318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/comentario\/wp-json\/wp\/v2\/tags?post=39318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}