{"id":15295,"date":"2022-10-15T17:10:10","date_gmt":"2022-10-15T22:10:10","guid":{"rendered":"https:\/\/www.biblia.work\/diccionario-biblia\/significado-biblico-de-dinero\/"},"modified":"2022-10-15T17:10:10","modified_gmt":"2022-10-15T22:10:10","slug":"significado-biblico-de-dinero","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionario-biblia\/significado-biblico-de-dinero\/","title":{"rendered":"Significado B\u00edblico de DINERO"},"content":{"rendered":"<p>  <\/p>\n<h2>Significado de Dinero<\/h2>\n<p> Ver Concordancia <\/p>\n<p> Medio de intercambio, emitido por la autoridad de un gobierno reconocido, que <br \/>representa un valor fijo y que circula en los tiempos modernos como monedas o <br \/>como certificados en papel. El mundo antiguo no conoc\u00eda el dinero en la forma <br \/>de materiales perecederos, como el papel moneda o las monedas met\u00e1licas, hasta <br \/>el s VIII a.C. Antes de esa \u00e9poca, todos los pagos se hac\u00edan en productos o en <br \/>metal, el valor de los cuales se med\u00eda por el peso. Se usaban balanzas con <br \/>pesas de piedra o de metal m\u00e1s o menos normalizadas. Como la plata era el <br \/>metal m\u00e1s usado para el intercambio, con frecuencia se usaba la palabra heb. <br \/>kese\u0192, \u00abplata\u00bb, con el sentido de \u00abdinero\u00bb (como ocurr\u00eda tambi\u00e9n con el bab. <br \/>kaspu y el fen. ksp). Del mismo modo, los t\u00e9rminos \u00abpagar\u00bb y \u00abpesar\u00bb se <br \/>expresaban con el mismo verbo heb. sh\u00e2qal (ac. shaq\u00e2\u00edu). Por ello encontramos <br \/>que Abrah\u00e1n pes\u00f3 400 siclos de plata por la tierra que compr\u00f3 cerca de Hebr\u00f3n <br \/>(Gn. 23:16), y que David dio a Om\u00e1n \u00abel peso de seiscientos siclos de oro\u00bb por <br \/>la era del jebuseo (1 Cr. 21:25). V\u00e9anse Balanza; Medidas y Pesas. <\/p>\n<p>El sistema monetario que se usaba en Cana\u00e1n durante el 2\u00ba milenio a. C. era el <br \/>babil\u00f3nico, como lo revelan las Cartas de Amarna* del s XIV a.C. Dado que los <br \/>t\u00e9rminos del AT para los valores monetarios, \u00absiclo\u00bb y \u00abmina\u00bb, derivan del bab. <br \/>shiqlu y man\u00fb, por lo general se supone que los israelitas tambi\u00e9n usaban el <br \/>sistema monetario babil\u00f3nico en vez del egipcio, el que aparentemente no usaban <br \/>fuera del Egipto ni siquiera sus vasallos. V\u00e9ase Mina; Siclo; Talento. <\/p>\n<p>Las frases \u00abpieza de dinero\u00bb o \u00abmoneda\u00bb* son traducciones un tanto vagas de <br \/>palabras hebreas no claras que denotan cierta cantidad de metal precioso cuyo <br \/>equivalente exacto se desconoce (Gn. 33:19; 1 S. 2:36). En algunos pasajes se <br \/>a\u00f1adi\u00f3 la palabra \u00absiclos\u00bb (Jue. 17:2; 2 S. 18:11) que se deber\u00eda tomar en <br \/>sentido neutro para indicar un peso o valor impl\u00edcitos en el hebreo, pero no <br \/>expresado. En las notas de Gn. 33:19 (BJ) y Jos. 24:32 (DHH) aparece la <br \/>palabra kesitas, transliteraci\u00f3n del heb. qe\u00d1\u00eetah, que representa una antigua <br \/>unidad de peso que se usaba para los pagos. Parece que se dej\u00f3 de emplear <br \/>despu\u00e9s de la conquista de Cana\u00e1n, ya que nunca m\u00e1s se la menciona en los <br \/>libros posteriores de la Biblia. Se desconoce su valor. En Mt. 26:15 y 27:9 <br \/>la frase \u00abpiezas de plata\u00bb representa un siclo o su equivalente (c\u0192 Zac. <br \/>11:12). <\/p>\n<p>La moneda acu\u00f1ada se introdujo por 1\u00aa vez en Lidia, c 700 a.C. Desde all\u00ed, el <br \/>proceso de fabricar monedas de metal de tama\u00f1o y peso uniformes se difundi\u00f3 <br \/>r\u00e1pidamente en Grecia, cuyas primeras monedas datan de antes del 650 a.C. <br \/>Cuando Ciro tom\u00f3 Sardis (547 a.C.) y toda el Asia Menor lleg\u00f3 a ser posesi\u00f3n de <br \/>los persas, \u00e9stos adoptaron la moneda acu\u00f1ada y la introdujeron en todas partes <br \/>de su imperio -que abarcaba todo el Cercano Oriente-, pocos a\u00f1os despu\u00e9s de la <br \/>conquista de Lidia. Las monedas de oro eran acu\u00f1adas s\u00f3lo por el rey, pero las <br \/>de plata tambi\u00e9n eran emitidas por los gobiernos provinciales. Seg\u00fan se <br \/>conoce, las monedas persas son las primeras que llevaban retratos humanos (la <br \/>del rey que las emit\u00eda) en vez de figuras de animales o de divinidades. Dar\u00edo <br \/>I introdujo la moneda de oro normalizada, que se llam\u00f3 dareik\u00f3s, \u00abd\u00e1rico\u00bb, y <br \/>que pesaba unos 8,4 g (fig. 366). <\/p>\n<p>Como el valor del oro y de la plata var\u00eda mucho actualmente, no se puede dar un <br \/>precio exacto de las monedas, de modo que si el lector desea saberlo deber\u00e1 <br \/>multiplicar su peso en gramos por el valor corriente del gramo de oro o de <br \/>plata en su pa\u00eds, como lo indiquen las p\u00e1ginas financieras de los diarios <br \/>locales. <\/p>\n<p>Las monedas acu\u00f1adas m\u00e1s antiguas, mencionadas en el AT, son las \u00abdracmas\u00bb <br \/>griegas o el \u00abd\u00e1rico\u00bb (Esd. 2:69; Neh. 7:70-72). En Betsur se descubri\u00f3 una <br \/>moneda del s V a.C., que imitaba la dracma ateniense (fig 365). Su inscripci\u00f3n <br \/>hebrea menciona: 1. A un cierto Ezequ\u00edas, probablemente el sumo sacerdote a <br \/>quien Josefo sindica como amigo de Tolomeo I. 2. El nombre \u00abJud\u00e1\u00bb como pa\u00eds <br \/>emisor. Este descubrimiento muestra que los jud\u00edos usaban dracmas como monedas <br \/>de plata, y que aun; las emitieron localmente durante los per\u00edodos persa y <br \/>helen\u00edstico temprano. Al mismo tiempo, tambi\u00e9n usaron las monedas persas como <br \/>el d\u00e1rico (Esd. 8:27). Las \u00abdracmas\u00bb de 1 Cr 29:7 son la traducci\u00f3n del heb. <br \/>\u00aadark\u00f4n. Este t\u00e9rmino probablemente fue usado por el autor de 1 Cr. para <br \/>convertir el valor monetario del tiempo de David a la moneda de su propia <br \/>\u00e9poca. En realidad, muchos comentadores creen que las diversas referencias a <br \/>monedas que hay en Cr., Esd. y Neh., no importa cu\u00e1l haya sido el empleo de los <br \/>t\u00e9rminos hebreos, 331 se aplican al d\u00e1rico persa, y que esta moneda bien <br \/>conocida se us\u00f3 para que los valores monetarios anteriores fueran <br \/>significativos para los lectores de su \u00e9poca. <\/p>\n<p>Alrededor del 140 a.C., Ant\u00edoco VII dict\u00f3 un decreto que permiti\u00f3 a Sim\u00f3n <br \/>Macabeo (143\/42-135 a.C.) emitir su propia moneda (1 Mac. 15:6). Sin embargo, <br \/>esta concesi\u00f3n parece haber sido anulada alg\u00fan tiempo despu\u00e9s, pues no se han <br \/>encontrado hasta ahora monedas de este Sim\u00f3n. (Las monedas anteriormente <br \/>atribuidas a \u00e9l son de la primera rebeli\u00f3n contra los romanos.) Juan Hircano I, <br \/>hijo de Sim\u00f3n, por lo tanto, fue el primer gobernante jud\u00edo que emiti\u00f3 monedas <br \/>macabeas. Estas, que incluyen las de los sucesores de Hircano, todas de <br \/>bronce, fueron emitidas; hasta el per\u00edodo romano. En armon\u00eda con el mandato de <br \/>no hacer im\u00e1genes, no presentan semejanzas de animales o de seres humanos, sino <br \/>m\u00e1s bien dise\u00f1os de s\u00edmbolos militares, como la de un nav\u00edo de guerra (fig 89) <br \/>o un casco, o s\u00edmbolos religiosos, como un c\u00e1lice que se usaba para las <br \/>libaciones (fig 462). Generalmente, llevaban inscripciones griegas y hebreas, <br \/>pero, desde Herodes el Grande, algunas s\u00f3lo ten\u00edan textos en hebreo. <\/p>\n<p>169. Monedas romanas durante los tiempos del NT. Los n\u00fameros 1, 6, 9 y 12 son <br \/>dupondii; las 3 y 5 son assarii; las 2, 4, 7, 8, 10, 11, y 13-15 son denarii. <\/p>\n<p>Como la emisi\u00f3n de monedas era una se\u00f1al de soberan\u00eda, especialmente las de <br \/>plata y de oro, a los jud\u00edos se les permiti\u00f3 s\u00f3lo emitir de bronce o cobre, <br \/>Esta restricci\u00f3n presentaba un problema cuando se trataba de las necesidades <br \/>del templo. El impuesto anual para el templo, que cada jud\u00edo var\u00f3n desde los <br \/>20 a\u00f1os deb\u00eda pagar, equival\u00eda a 1\/2 siclo de plata. Cabe se\u00f1alar que en <br \/>tiempos del NT la palabra siclo se us\u00f3 para aplicarla al tetradracma (4 <br \/>dracmas) de Tiro (gr. stater, \u00abestatero\u00bb; Mt. 17:27), la moneda que se aceptaba <br \/>para pagar el impuesto anual destinado al templo. Por consiguiente, los <br \/>gobernantes jud\u00edos escogieron para pagar el impuesto anual el tetradracma 332 <br \/>de Tiro, acu\u00f1ada en esa ciudad entre el 126 a.C. y el 66 d.C., pues por lo <br \/>general era de buena cualidad, uniforme en peso y bastante abundante (fig 170). <br \/> Esta era la moneda que junto con el didracma (llamadas respectivamente siclo y <br \/>medio siclo), hab\u00edan aprobado los sacerdotes para el uso del templo. Los <br \/>visitantes que ten\u00edan monedas de otros pa\u00edses y de otros valores deb\u00edan <br \/>cambiarlas por estas monedas autorizadas. Judas traicion\u00f3 a Jes\u00fas por 30 <br \/>tetradracmas tirias del tesoro del templo. V\u00e9anse Cambista; Tributo del <br \/>templo. <\/p>\n<p>170. Un tetradracma de Tiro, usado como un siclo para el pago de los impuestos <br \/>del templo. El anverso muestra al dios fenicio Melkart (Baal). El anverso <br \/>retrata un \u00e1guila y tiene una flecha (equivalente al 30 a.C.) con la <br \/>inscripci\u00f3n: \u00abTiro, la santa e inviolable\u00bb. <\/p>\n<p>Bib.: F. A. Banks, Coins o\u0192 Bible Days [Monedas de los tiempos b\u00edblicos] (Nueva <br \/>York, 1955); A. Reifenberg, \u00abAncient Jewish Coins\u00bb [Antiguas monedas jud\u00edas], <br \/>JPOS 19 (1941):59-81, 286-313; F. W. Madden, History o\u0192 Jewish Coinage and o\u0192 <br \/>Money in the Old and New Testament [Historia de la acu\u00f1aci\u00f3n jud\u00eda y del dinero <br \/>en el AT y el NT] (ed. rev., Nueva York, 1967); M. Wacks, The Handbook o\u0192 <br \/>Biblical Numismatics [Manual de numism\u00e1tica b\u00edblica] (Houston, 1976); Herodoto <br \/>i.94; FJ-AA i.22. <\/p>\n<p><b><a href='http:\/\/www.biblia.work\/diccionarios\/dinero\/'>Diccionario Enciclop\u00e9dico de Biblia y Teolog\u00eda: DINERO<\/a><\/b><\/p>\n<h2>\n<p align=\"justify\"><strong>DINERO seg\u00fan la Biblia: Se hace menci\u00f3n del dinero ya en \u00e9poca tan temprana como Gn. 17:12, 13, donde se habla de personas compradas \u00abpor dinero\u00bb.<\/strong><\/p>\n<\/h2>\n<p align=\"justify\">Se hace menci\u00f3n del dinero ya en \u00e9poca tan temprana como Gn. 17:12, 13, donde se habla de personas compradas \u00abpor dinero\u00bb.<\/p>\n<p> De G\u00e9nesis a Zacar\u00edas se menciona como no contado, sino pesado. Ello daba el verdadero valor de los metales preciosos en forma de anillos o en trozos peque\u00f1os de oro o plata.<\/p>\n<p> Las cantidades de dinero que se usaban en el AT corresponden con Gera, Beka, Siclo, Maneh y Talento.<br \/> Al volver los jud\u00edos del exilio en el a\u00f1o 536 a.C., se usaba entonces dinero persa. Ello fue seguido del dinero griego. <\/p>\n<p> Ant\u00edoco VII, alrededor del a\u00f1o 140 a.C., dio permiso a Sim\u00f3n Macabeo para acu\u00f1ar dinero jud\u00edo.<br \/> Los siclos se acu\u00f1aban con el grabado de un vaso de man\u00e1 y una vara de almendro.<br \/> Bajo los romanos, se usaba dinero romano. <\/p>\n<p><b><a href='http:\/\/www.biblia.work\/diccionarios\/dinero\/'>Diccionario Enciclop\u00e9dico de Biblia y Teolog\u00eda: DINERO<\/a><\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Significado de Dinero Ver Concordancia Medio de intercambio, emitido por la autoridad de un gobierno reconocido, que representa un valor fijo y que circula en los tiempos modernos como monedas o como certificados en papel. El mundo antiguo no conoc\u00eda el dinero en la forma de materiales perecederos, como el papel moneda o las monedas &hellip; <a href=\"https:\/\/www.biblia.work\/diccionario-biblia\/significado-biblico-de-dinero\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abSignificado B\u00edblico de DINERO\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-15295","post","type-post","status-publish","format-standard","hentry","category-diccionario-moderno-de-la-biblia"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionario-biblia\/wp-json\/wp\/v2\/posts\/15295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionario-biblia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionario-biblia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionario-biblia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionario-biblia\/wp-json\/wp\/v2\/comments?post=15295"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionario-biblia\/wp-json\/wp\/v2\/posts\/15295\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionario-biblia\/wp-json\/wp\/v2\/media?parent=15295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionario-biblia\/wp-json\/wp\/v2\/categories?post=15295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionario-biblia\/wp-json\/wp\/v2\/tags?post=15295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}