{"id":9230,"date":"2021-08-27T18:15:30","date_gmt":"2021-08-27T23:15:30","guid":{"rendered":"https:\/\/www.biblia.work\/diccionario-biblia\/neco-persona-heb-nkh-nch-faraon-egipcio-de-la-26a-dinastia-saite-e-hijo\/"},"modified":"2021-08-27T18:15:30","modified_gmt":"2021-08-27T23:15:30","slug":"neco-persona-heb-nkh-nch-faraon-egipcio-de-la-26a-dinastia-saite-e-hijo","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionario-biblia\/neco-persona-heb-nkh-nch-faraon-egipcio-de-la-26a-dinastia-saite-e-hijo\/","title":{"rendered":"NECO&nbsp;(PERSONA) [Heb&nbsp;N&#277;k&#333;h&nbsp;(&nbsp;Nch)&nbsp;].&nbsp;Fara\u00f3n egipcio de la 26\u00aa dinast\u00eda (Saite) e hijo&#8230;"},"content":{"rendered":"<p><b>NECO<\/b>&nbsp;(PERSONA) [Heb&nbsp;N&#277;k&#333;h&nbsp;(&nbsp;Nch)&nbsp;].&nbsp;Fara\u00f3n egipcio de la 26\u00aa dinast\u00eda (Saite) e hijo de su fundador, Psammetichus I (Psamtik; 663-609 a.&nbsp;C.&nbsp;).&nbsp;Necao (o Necao) gobern\u00f3 desde 609 hasta 595 a.&nbsp;C.&nbsp;Es m\u00e1s conocido por su papel en la muerte de Jos\u00edas de Jud\u00e1 en Meguido en 609 (2 Reyes 23: 28-30 = 2 Cr\u00f3nicas 35: 20-27), y por su breve control sobre Siria-Palestina en los \u00faltimos a\u00f1os del siglo VII a.&nbsp;C.&nbsp;Seg\u00fan fuentes babil\u00f3nicas, fue un enemigo importante de Babilonia durante los \u00faltimos a\u00f1os de Asiria a finales del siglo VII a.&nbsp;C.<\/p>\n<p class=MsoNormal style-bible='margin-bottom:0cm;text-indent:9.0pt;line-height:normal'>Las fuentes del reinado de Necao son b\u00edblicas, acadias y cl\u00e1sicas, por lo que est\u00e1n escritas desde una perspectiva que no refleja el punto de vista egipcio.&nbsp;Consisten en parte del relato b\u00edblico de las \u00faltimas d\u00e9cadas del reino de Jud\u00e1 (2 Reyes 23-24), una poes\u00eda muy emotiva de la tradici\u00f3n prof\u00e9tica (Jer 46: 1-12), fragmentos de las Cr\u00f3nicas neobabil\u00f3nicas, y la historia de Herodoto.&nbsp;De las fuentes, Herodoto parece ser la m\u00e1s sospechosa, ya que no ofrece ning\u00fan relato de la participaci\u00f3n de Necao en los grandes eventos de la ca\u00edda de Asiria.&nbsp;Sin embargo, tanto los registros b\u00edblicos como los acadios tienen una agenda distinta y tambi\u00e9n son muy selectivos con su informaci\u00f3n.&nbsp;Los relatos b\u00edblicos de la participaci\u00f3n de Necao en la muerte de Jos\u00edas no coinciden en todos los detalles.<\/p>\n<p class=MsoNormal style-bible='margin-bottom:0cm;text-indent:9.0pt;line-height:normal'>A partir de estos datos selectivos, podemos reconstruir el siguiente esquema esquem\u00e1tico de la carrera de Neco y los eventos que la condujeron.&nbsp;A principios del siglo VII a.&nbsp;C.,&nbsp;As\u00fbs\u00fburbanipal de Asiria (&nbsp;ca.&nbsp;668-627 a.&nbsp;C.&nbsp;) invadi\u00f3 Egipto y dispers\u00f3 a los pr\u00edncipes del Delta, entre ellos Taharqa y Neco (I) (&nbsp;ANET&nbsp;, 294-97), y luego saque\u00f3 la capital del siglo XX. Dinast\u00eda (et\u00edope) en Tebas.&nbsp;Neco que luego fue derrotado por el et\u00edope Shabaka, pero su hijo, Psam\u00e9tico I (664-610&nbsp;AC&nbsp;), consolid\u00f3 su poder en la nueva capital Sais con la ayuda de jonios y carios, y se embarc\u00f3 en campa\u00f1as al N y&nbsp;E&nbsp;.&nbsp;El conflicto con Siria-Palestina culmin\u00f3 con la captura egipcia de Ashdod en el 635 a.&nbsp;C.(&nbsp;Hdt.&nbsp;2: 157).&nbsp;El hijo de Psam\u00e9tico, Necao II, se aprovech\u00f3 de una Siria debilitada y expandi\u00f3 el comercio egipcio hacia el este y el&nbsp;oeste&nbsp;(Hdt. 4:42).&nbsp;Luego se dedic\u00f3 a la guerra con sus vecinos del este, incluidos los sirios y los \u00e1rabes, y captur\u00f3 la ciudad fronteriza de Gaza, un evento que probablemente se refleja en Jerem\u00edas 47: 1-7.<\/p>\n<p class=MsoNormal style-bible='margin-bottom:0cm;text-indent:9.0pt;line-height:normal'>Las actividades de Neco inciden m\u00e1s directamente en la historia de Jud\u00e1 con una reconstrucci\u00f3n de los movimientos de Neco que se encuentran en fuentes b\u00edblicas y acadias.&nbsp;2 Reyes 23: 29-35 (= 2 Cr\u00f3nicas 35: 20-36: 4) se refieren al traslado de Necao al N para ayudar a Asiria en 609 a.&nbsp;C.&nbsp;De fuentes acadias (Wiseman 1956: 54-63;&nbsp;ANET&nbsp;, 305), aprendemos que Neco hab\u00eda tomado un ej\u00e9rcito N para ayudar a&nbsp;A\u009a\u009auruballi&#7789; a&nbsp;recuperar Harran de una peque\u00f1a guarnici\u00f3n babil\u00f3nica.&nbsp;Un contraataque babil\u00f3nico, bajo Nabopolasar, no tuvo \u00e9xito, pero con los asirios y los egipcios comprometidos en Harran, el ej\u00e9rcito babil\u00f3nico saque\u00f3 a su antojo en el norte de Asiria.&nbsp;Es posible que&nbsp;A\u009a\u009auruballi&#7789;&nbsp;muriera en esta campa\u00f1a.&nbsp;En cualquier caso, no se vuelve a saber de \u00e9l.<\/p>\n<p class=MsoNormal style-bible='margin-bottom:0cm;text-indent:9.0pt;line-height:normal'>Hacia el 606 a.&nbsp;C.el ej\u00e9rcito egipcio estaba ahora a las puertas de Carquemis, pero no necesariamente bajo el liderazgo directo de Neco, y realiz\u00f3 una exitosa campa\u00f1a contra Kimuhu (Commagene) y Qaramati.&nbsp;El ej\u00e9rcito babil\u00f3nico, ahora bajo el pr\u00edncipe heredero Nabucodonosor, atac\u00f3 al a\u00f1o siguiente y derrot\u00f3 por completo a la fuerza egipcia.&nbsp;Seg\u00fan el expediente, -.&nbsp;.&nbsp;.&nbsp;el ej\u00e9rcito egipcio se retir\u00f3 ante [Nabucodonosor].&nbsp;Logr\u00f3 su derrota y la no existencia [los golpe\u00f3].&nbsp;En cuanto al resto del ej\u00e9rcito egipcio que hab\u00eda escapado de la derrota.&nbsp;.&nbsp;.&nbsp;las tropas babil\u00f3nicas los alcanzaron y derrotaron, de modo que ni un solo hombre escap\u00f3 a su propio pa\u00eds -(Wiseman 1956: 67-69).&nbsp;Esta completa aniquilaci\u00f3n del ej\u00e9rcito egipcio fue celebrada con igual regocijo por el profeta Jerem\u00edas (Jer 46: 2-12).BCE&nbsp;Neco ahora estaba confinado a su antiguo territorio.&nbsp;-.&nbsp;.&nbsp;.&nbsp;el rey de Egipto no volvi\u00f3 a salir de su tierra, porque el rey de Babilonia hab\u00eda tomado todo lo que pertenec\u00eda al rey de Egipto, desde el arroyo de Egipto (Wadi el-Arish) hasta el r\u00edo \u00c9ufrates -(2 Reyes 24: 7).<\/p>\n<p class=MsoNormal style-bible='margin-bottom:0cm;text-indent:9.0pt;line-height:normal'>Fue durante el primer avance de Necao hacia el norte (609 a.&nbsp;EC&nbsp;) que Jos\u00edas lo encontr\u00f3 en Meguido y muri\u00f3 (2 Reyes 23: 29-33).&nbsp;Despu\u00e9s de un breve reinado del hijo de Jos\u00edas, Joacaz, Necao puso a Eliaquim (Joacim), el hijo menor de Jos\u00edas, en el trono de Jud\u00e1, y durante los a\u00f1os siguientes Jud\u00e1 fue un vasallo pagador de tributos de Egipto (2 Reyes 24: 31-35 ).&nbsp;Es de suponer que fue durante el avance del ej\u00e9rcito babil\u00f3nico en el 604 a.&nbsp;C.&nbsp;a las fronteras de Egipto cuando Joacim cambi\u00f3 su lealtad a Babilonia.&nbsp;Sin embargo, el fracaso de Nabucodonosor para entrar en Egipto en 601&nbsp;AC&nbsp;anim\u00f3 al rey a deshacerse del control babil\u00f3nico (2 Reyes 24: 1) y buscar apoyo en el S, a pesar de las advertencias prof\u00e9ticas (Jer 46: 14-28).&nbsp;Tras la repulsi\u00f3n del ej\u00e9rcito babil\u00f3nico, las dos naciones de Egipto y Babilonia cesaron las hostilidades y no se supo nada m\u00e1s directamente de Necao.&nbsp;Muri\u00f3 en el 595 a.&nbsp;C.&nbsp;y fue sucedido por su hijo, Psammetichus (Psamtik) II.<\/p>\n<p class=MsoNormal style-bible='margin-bottom:0cm;text-indent:9.0pt;line-height:normal'>En 2 Reyes 23: 28-30 y claramente en 2 Cr\u00f3nicas 35: 20-27 se da la impresi\u00f3n de que Jos\u00edas muri\u00f3 en la batalla contra Necao.&nbsp;Algunos, sin embargo, han dudado de esto y han argumentado que Neco arrest\u00f3 y ejecut\u00f3 a Josiah (Cogan, Tadmor&nbsp;2 Kings&nbsp;AB, 300-301), quien hab\u00eda ido al N, no buscando batalla, sino simplemente para encontrarse con Neco.&nbsp;Esto es posible pero poco probable.&nbsp;El motivo de la mudanza de Jos\u00edas solo se puede adivinar, pero tiene sentido que \u00e9l tema tanto un resurgimiento del poder asirio en Jud\u00e1 como un Egipto resurgente.&nbsp;Estrat\u00e9gicamente, una batalla en Meguido era la mejor opci\u00f3n, pero la estrategia fall\u00f3 y, al igual que su predecesor Thutmoses III en 1468 a.&nbsp;C.&nbsp;, Neco derrot\u00f3 a una fuerza local en este importante sitio.<\/p>\n<p class=MsoNormal style-bible='margin-top:0cm;margin-right:0cm;margin-bottom:0cm; margin-left:18.0pt;text-indent:-18.0pt;line-height:normal'><b>Bibliograf\u00eda<\/b><\/p>\n<p class=MsoNormal style-bible='margin-top:0cm;margin-right:0cm;margin-bottom:0cm; margin-left:18.0pt;text-indent:-18.0pt;line-height:normal'>Gardiner, A. 1961. El&nbsp;Egipto de los faraones.&nbsp;Londres.<\/p>\n<p class=MsoNormal style-bible='margin-top:0cm;margin-right:0cm;margin-bottom:0cm; margin-left:18.0pt;text-indent:-18.0pt;line-height:normal'>Malamat, A. 1973. Josiah&#8217;s Bid for Armageddon.&nbsp;JANES&nbsp;5: 267-79.<\/p>\n<p class=MsoNormal style-bible='margin-top:0cm;margin-right:0cm;margin-bottom:0cm; margin-left:18.0pt;text-indent:-18.0pt;line-height:normal'>Wiseman, DJ 1956.&nbsp;Cr\u00f3nicas de los reyes caldeos (626-556 aC) en el Museo Brit\u00e1nico.&nbsp;Londres.<\/p>\n<p class=MsoNormal style-bible='margin-bottom:0cm;line-height:normal'>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;TR HOBBS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NECO&nbsp;(PERSONA) [Heb&nbsp;N&#277;k&#333;h&nbsp;(&nbsp;Nch)&nbsp;].&nbsp;Fara\u00f3n egipcio de la 26\u00aa dinast\u00eda (Saite) e hijo de su fundador, Psammetichus I (Psamtik; 663-609 a.&nbsp;C.&nbsp;).&nbsp;Necao (o Necao) gobern\u00f3 desde 609 hasta 595 a.&nbsp;C.&nbsp;Es m\u00e1s conocido por su papel en la muerte de Jos\u00edas de Jud\u00e1 en Meguido en 609 (2 Reyes 23: 28-30 = 2 Cr\u00f3nicas 35: 20-27), y por su breve &hellip; <a href=\"https:\/\/www.biblia.work\/diccionario-biblia\/neco-persona-heb-nkh-nch-faraon-egipcio-de-la-26a-dinastia-saite-e-hijo\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abNECO&nbsp;(PERSONA) [Heb&nbsp;N&#277;k&#333;h&nbsp;(&nbsp;Nch)&nbsp;].&nbsp;Fara\u00f3n egipcio de la 26\u00aa dinast\u00eda (Saite) e hijo&#8230;\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9230","post","type-post","status-publish","format-standard","hentry","category-diccionario-moderno-de-la-biblia"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionario-biblia\/wp-json\/wp\/v2\/posts\/9230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionario-biblia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionario-biblia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionario-biblia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionario-biblia\/wp-json\/wp\/v2\/comments?post=9230"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionario-biblia\/wp-json\/wp\/v2\/posts\/9230\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionario-biblia\/wp-json\/wp\/v2\/media?parent=9230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionario-biblia\/wp-json\/wp\/v2\/categories?post=9230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionario-biblia\/wp-json\/wp\/v2\/tags?post=9230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}