{"id":10484,"date":"2016-02-05T07:29:14","date_gmt":"2016-02-05T12:29:14","guid":{"rendered":"http:\/\/www.biblia.work\/diccionarios\/discernimiento\/"},"modified":"2016-02-05T07:29:14","modified_gmt":"2016-02-05T12:29:14","slug":"discernimiento","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/diccionarios\/discernimiento\/","title":{"rendered":"DISCERNIMIENTO"},"content":{"rendered":"<p>v. Entendimiento, Inteligencia<br \/>\nPsa 14:4 \u00bfno tienen d .. los que hacen iniquidad<br \/>\n1Co 12:10 otro, profec\u00eda; a otro, d de esp\u00edritus<br \/>\nHeb 5:14 sentidos ejercitados en el d del bien<\/p>\n<hr>\n<p>[500]<br \/>\n   Acci\u00f3n de la inteligencia pr\u00e1ctica de diferenciar lo conveniente de lo que no lo es. Es un deber del ser libre y un acto de la prudencia y de la raz\u00f3n.<\/p>\n<p>     De manera particular el discernimiento afecta a situaciones, valores o procedimientos que exigen tomar opciones comprometedoras y responsables. Y por eso se hace referencia a la reflexi\u00f3n y a la prudencia.<\/p>\n<p>     El discernimiento puede ser reclamado por determinadas situaciones o cuestiones de trascendencia para la vida, por ejemplo para la elecci\u00f3n de la vocaci\u00f3n (Discernimiento vocacional), para la soluci\u00f3n de problemas profesionales (discernimiento \u00e9tico o deontol\u00f3gico), como son los sacerdotales (Discernimiento sacerdotal) o cuando cuestiones de conciencia dificultan la claridad sobre lo que es m\u00e1s conveniente hacer (Discernimiento de esp\u00ed\u00adritus), situaciones que se presentan con frecuencia.<\/p>\n<p>    El discernimiento tiene una fuerte connotaci\u00f3n evang\u00e9lica. Unas 22 veces se emplea en el Nuevo Testamento el concepto \u00abdiscernir\u00bb (dokimasein) y se mira como un deber el pensar ante Dios las acciones y las decisiones: 1 Cor. 11. 28-29; 2 Cor. 13. 5-6; Gal. 6. 4-5)<\/p>\n<p>    El discernimiento cristiano tiene que ver con la responsabilidad de la propia conciencia, pero tambi\u00e9n con las necesidades o las conveniencias de la comunidad. Determinados sacramentos, bautismo, perd\u00f3n de los pecados, matrimonio, ordenaciones sacerdotales no son s\u00f3lo cuesti\u00f3n de cada persona. Entran en juego los intereses de la comunidad eclesial.<\/p>\n<p>    El acto o el proceso de discernimiento estricto no debe ser confundido con otras operaciones pastorales y educativas en las que tambi\u00e9n entre la prudencia y la reflexi\u00f3n. As\u00ed\u00ad, por ejemplo, una cosa es el discernimiento vocacional (si hay o no hay vocaci\u00f3n, para esto o para aquello) y otra cosa es la animaci\u00f3n, el acompa\u00f1amiento, la invitaci\u00f3n.<\/p>\n<p>    La orientaci\u00f3n vocacional, implica la previa acci\u00f3n de discernimiento. y se realiza no s\u00f3lo de una forma inicial iluminando la mente, sino en el sereno acompa\u00f1amiento con intenci\u00f3n de llegar a los objetivos finales personalizados.<\/p>\n<p>     Y tambi\u00e9n hay que diferenciar lo que es consejer\u00ed\u00ada espiritual, direcci\u00f3n espiritual o animaci\u00f3n, de lo que estrictamente es \u00abdiscernimiento de esp\u00ed\u00adritus\u00bb<\/p>\n<p>Pedro Chico Gonz\u00e1lez, Diccionario de Catequesis y Pedagog\u00ed\u00ada Religiosa, Editorial Bru\u00f1o, Lima, Per\u00fa 2006<\/p>\n<p><b>Fuente: Diccionario de Catequesis y Pedagog\u00eda Religiosa<\/b><\/p>\n<p>SUMARIO: 1. Datos de la Escritura. -2. Aportaciones de la teolog\u00ed\u00ada conciliar. &#8211; 3. El amor como experiencia del discernimiento. &#8211; 4. Criterios de discernimiento pastoral.<\/p>\n<p>El objetivo propio del discernimiento cristiano consiste en la b\u00fasqueda de la voluntad de Dios para una persona o comunidad en una situaci\u00f3n concreta. Esto supone un procedimiento que encuentra en la persona de Jes\u00fas de Nazaret, el discernidor por antonomasia, la referencia \u00faltima. El discernimiento vocacional es fundamental en el proceso de maduraci\u00f3n personal de la fe; el discernimiento en situaciones especiales en que se ha de tomar una decisi\u00f3n importante es ineludible; y el discernimiento pastoral afecta al modo permanente del ser y actuar de la Iglesia. Jes\u00fas de Nazaret form\u00f3 a sus disc\u00ed\u00adpulos para que supieran discernir la acci\u00f3n de Dios en los momentos del nacimiento de la Iglesia; las primeras comunidades en su dinamismo evangelizador y misionero son un ejemplo de c\u00f3mo discernir. Y San Pablo nos leg\u00f3 una teolog\u00ed\u00ada b\u00e1sica sobre el discernimiento cristiano.<\/p>\n<p>1. Datos de la Escritura<br \/>\nToda la Sagrada Escritura manifiesta la iniciativa de Dios que gu\u00ed\u00ada a su pueblo a trav\u00e9s de situaciones distintas y variadas. La vida del creyente adquiere un talante cr\u00ed\u00adtico ante la realidad y se abre al horizonte escatol\u00f3gico del Reino; el cristiano sabe que \u00abDios sondea nuestros corazones\u00bb (1 Tes. 2,4) y en un di\u00e1logo de profundidad, bajo la acci\u00f3n del Esp\u00ed\u00adritu Santo, es invitado a acoger la voluntad de Dios y a ponerla en pr\u00e1ctica. Esto no es posible sin un camino de conversi\u00f3n que nos hace crecer en fe, esperanza y caridad al \u00abconocer interiormente la persona de Jesucristo y su Evangelio\u00bb.<\/p>\n<p>Ser cristiano es hacer \u00ablo que agrada a Dios\u00bb, como lo hizo Jes\u00fas de Nazaret (Rom. 12,2; 14,8; 2 Cor. 5,9, Ef. 5,10; Flp. 4,18; Col. 3,20; Tit. 2,9). En el N.T. aparece 22 veces el t\u00e9rmino dokim\u00e1sein con el significado de llegar a conocer lo que se debe hacer y lo que se debe rechazar a trav\u00e9s de una comprobaci\u00f3n. Esto se aplica para el discernimiento personal (1 Cor. 11,28- 29; 2 Cor. 13, 5- 6; G\u00e1l. 6,4- 5) y para el discernimiento comunitario (1 Tes. 5, 19-22).<\/p>\n<p>El discernimiento cristiano no se puede hacer desde el propio criterio e inter\u00e9s; se necesita una nueva mentalidad, la que Dios nos da al pasar del \u00abhombre viejo\u00bb al \u00abhombre nuevo\u00bb (1Cor. 1,10). Esta nueva mentalidad conlleva el no \u00abamoldarse al mundo\u00bb (Rom. 12,2); hay que romper con el orden vigente caracterizado por el tener, el poder y el competir para poder discernir.<\/p>\n<p>Jesucristo nos liber\u00f3 de vivir la ley como la expresi\u00f3n de la voluntad de Dios (Rom. 13,8-10) con una actitud poco madura (G\u00e1l. 3,23-26); positivamente, nos abre a la novedad de la comuni\u00f3n trinitaria (1 Jn. 2,20. 27; 3,24; 4,6. 17; 5,6- 9) y a la docilidad al Esp\u00ed\u00adritu Santo (Rom. 8,14), para llegar a la edad adulta en la fe (G\u00e1l. 4,19; Ef 1,3.14) que se expresa en el amor a los necesitados (Mt. 25,31-46).<\/p>\n<p>2. Aportaciones de la teolog\u00ed\u00ada conciliar<br \/>\nEl Vaticano II insisti\u00f3 en la necesidad de que los fieles y pastores (PO 9) entr\u00e1ramos a fondo en la lectura de los signos de los tiempos (E. S.4). Estos necesitan ser analizados en profundidad y con talante evang\u00e9lico (G.S. 11, 18, 27, 37; PO 28, 36; PDV40).<\/p>\n<p>La Iglesia es y quiere ser \u00absacramento de salvaci\u00f3n\u00bb (G.S.1) para el mundo; por lo mismo, la relaci\u00f3n Iglesia- mundo tiene que verse en t\u00e9rminos de colaboraci\u00f3n y ayuda (G.S. 36. 38; 41-43). Hoy tambi\u00e9n podemos repetir las palabras de Pablo VI en la clausura del Concilio: \u00abla antigua historia del samaritano ha sido el paradigma de la espiritualidad del Concilio\u00bb.<\/p>\n<p>El plan de salvaci\u00f3n de Dios consiste en que todos los hombres conozcan el Evangelio y se conviertan a Jesucristo para vivir como hijos de Dios y hermanos. C\u00f3mo llevar esto a la vida en cada tiempo y lugar es objetivo del discernimiento personal y comunitario.<\/p>\n<p>La evangelizaci\u00f3n del mundo contempor\u00e1neo plantea a la Iglesia algunos retos importantes; que deben ser cuidadosamente discernidos; subrayamos los siguientes: la inculturaci\u00f3n de la fe, las nuevas presencias eclesiales, el di\u00e1logo interreligioso y el ecumenismo, la opci\u00f3n preferencial por los m\u00e1s pobres, los cauces de corresponsabilidad en la Iglesia, la evangelizaci\u00f3n de los alejados, los procesos de fe que desemboquen en comunidades maduras, y el compromiso socio-pol\u00ed\u00adtico del cristiano.<\/p>\n<p>3. El amor como experiencia del discernimiento<br \/>\nLas expresiones paulinas para indicar la meta del discernimiento son variadas y muy significativas. Discernir es saber \u00ablo que agrada al Se\u00f1or\u00bb (Ef. 5, 10), conocer \u00abla voluntad de Dios\u00bb (Rom. 12,2), \u00ablo bueno\u00bb (FIp. 1,9-10; 1 Tes. 5,21-22), etc. A esto no se llega aplicando deductivamente unos principios, unos valores \u00e9ticos o una norma; es algo m\u00e1s interior, experiencia) y fundante. El discernimiento proviene del amor evang\u00e9lico que va configurando al creyente en una nueva sensibilidad y unos criterios que le permiten ver con m\u00e1s claridad lo que es conforme al querer de Dios revelado en Jesucristo (FI. 1,9-10). La forma en que se vive, los valores por los que se trabaja y las causas en las que se implica la vida facilitan o dificultan el discernimiento cristiano. El \u00abtener los mismos sentimientos de Cristo Jes\u00fas\u00bb (Flp. 2,5) es el camino pr\u00e1ctico que nos permite conocer la voluntad del Padre. La capacidad de discernir no se improvisa; por el contrario, se prepara adecuadamente cuando se cultiva la lectura, la reflexi\u00f3n, la introspecci\u00f3n, el an\u00e1lisis de la realidad, el examen de conciencia, y se pasan los acontecimientos por el coraz\u00f3n. La propia interioridad es el \u00e1mbito privilegiado del encuentro con Dios; por consiguiente, en la oraci\u00f3n personal es donde Dios se comunica en el fondo del coraz\u00f3n como Padre. Sin la familiaridad con Dios que proporciona la oraci\u00f3n no es posible el discernimiento, pues nos faltar\u00ed\u00ada la comnaturalidad con El y su proyecto de salvaci\u00f3n; en la oraci\u00f3n vamos descubriendo nuestras reacciones y nuestros sentimientos a lo que la Palabra de Dios nos va proponiendo.El an\u00e1lisis de lo que va pasando por dentro nos permite mirar al futuro y tomar uno u otro compromiso; esta decisi\u00f3n es don de Dios y exigencia en orden a la transformaci\u00f3n de la realidad para que el Reino de Dios sea. La validaci\u00f3n de la opci\u00f3n tomada est\u00e1 en los frutos de humanizaci\u00f3n que produzca en favor de los m\u00e1s necesitados, y la alegr\u00ed\u00ada interior de los que la llevan delante, a pesar de todas las dificultades.<\/p>\n<p>Para poder hacer bien el discernimiento es necesario centrar bien el tema que se quiere discernir, querer buscar ante todo y sobretodo la voluntad de Dios, y situarse en la presencia de Dios en actitud de completa disponibilidad. Est\u00e1 disponible quien se muestra indiferente a los propios intereses y dispuesto a acoger y hacer lo que Dios le pida; si al hacer este ejercicio se siente paz, alegr\u00ed\u00ada y confianza significa que hay madurez en la fe y disposici\u00f3n sincera de buscar la voluntad de Dios, sea lo que sea, y aunque contravenga nuestros planes.<\/p>\n<p>A la hora de discernir es necesario distinguir claramente el fin y los medios; el fin es la b\u00fasqueda de la voluntad de Dios que enmarca y orienta el discernimiento; lo que se disciernen son los medios que permitan hacer la voluntad de Dios. Aqu\u00ed\u00ad suelen aparecer las \u00abafecciones desordenadas\u00bb, es decir, los intereses y ego\u00ed\u00adsmos que terminan anteponiendo nuestra voluntad a la de Dios. Importa mucho que conozcamos las limitaciones, los condicionamientos y las ambig\u00fcedades que nos impiden estar verdaderamente disponibles para lo que Dios quiera.<\/p>\n<p>El \u00e1rbol se conoce por sus por sus frutos, dice Jes\u00fas en el Evangelio (Mt. 12,33; Lc. 6,43-44); lo que nos confirma que el discernimiento se ha hecho adecuadamente son las obras (Ef. 5,8-10; Flp. 1,9-11; G\u00e1l. 15,22), que se refieren directamente al amor al hermano; en caso contrario, aunque hici\u00e9ramos maravillas, si nos falta el amor, nada vale (1 Cor. 13,1-3). Y esto tiene una traducci\u00f3n interpersonal, pero tambi\u00e9n social y estructural hasta conseguir un orden internacional m\u00e1s justo y solidario (G.S. 40).<\/p>\n<p>4. Criterios de discernimiento pastoral<br \/>\nTeniendo en cuenta la situaci\u00f3n eclesial actual, y desde la perspectiva de la acci\u00f3n pastoral vamos a recordar algunos criterios que orienten la nueva evangelizaci\u00f3n y la educaci\u00f3n de la fe.<\/p>\n<p>a) Potenciar el discernimiento b\u00e1sico<br \/>\nEl discernimiento no es un saber te\u00f3rico si no pr\u00e1ctico; es decir, \u00fanicamente se puede discernir adecuadamente desde una determinada manera de vivir en que se distinga claramente el bien del mal; lo bueno, \u00e9ticamente hablando, nos pone en relaci\u00f3n con el Reino de Dios, y lo malo nos aleja de Dios y su justicia. El conocimiento de la voluntad de Dios no es algo as\u00e9ptico a lo que se pueda llegar de una manera abstracta, independientemente de d\u00f3nde tengamos puesto el coraz\u00f3n, los deseos y los intereses. La sinton\u00ed\u00ada con Dios solo es posible desde una purificaci\u00f3n del coraz\u00f3n y la nueva mentalidad fruto de la conversi\u00f3n; en consecuencia, el primer paso para adentrarnos en los caminos del Esp\u00ed\u00adritu es dejar la vida de pecado y progresar en la gracia. Esto tan sencillo y b\u00e1sico est\u00e1 bastante olvidado, y por eso nos encontramos con el contrasentido y la incoherencia de querer avanzar en el camino de Dios sin haber puesto el fundamento. Sin conversi\u00f3n no se puede avanzar en los caminos del Esp\u00ed\u00adritu.<\/p>\n<p>b) La referencia permanente de Jesucristo<br \/>\nLo fundamental para el cristiano es el encuentro con el Dios de Jes\u00fas en lo cotidiano de la vida; el camino para llegar al Padre y para descubrir la hondura de lo humano es Jesucristo, Camino, Verdad y Vida. El aprendizaje principal en la catequesis consiste en situar a Jesucristo y su Evangelio como el centro de la vida; esto no es posible sin entrar en comuni\u00f3n con la persona, el mensaje y la causa de Jes\u00fas de Nazaret. El seguimiento de Jes\u00fas, la vivencia de los misterios de su vida y la apertura al Esp\u00ed\u00adritu es lo que nos hace renacer a los valores, criterios y actitudes del hombre nuevo. La vida cristiana consiste en la constante y progresiva configuraci\u00f3n en, con y por Jesucristo. La evangelizaci\u00f3n debe realizarse de forma que \u00abalcance y transforme los criterios de juicio, los valores determinantes, los puntos de inter\u00e9s, las l\u00ed\u00adneas de pensamiento, las fuentes y los modelos vitales\u00bb (EN. 19). La referencia permanente a Jesucristo no define tanto la tensi\u00f3n de nuestro caminar hacia El, cuanto el \u00abdejarnos alcanzar\u00bb por El para que nuestra existencia sea una respuesta de fe. Esta verdad de fondo conlleva una pastoral m\u00e1s oracional, experiencial y centrada en la maduraci\u00f3n de la actitud religiosa. El cultivo de la vida espiritual constituye el n\u00facleo de la acci\u00f3n pastoral de la Iglesia.<\/p>\n<p>c) La vocacional como la perspectiva de toda la pastoral<br \/>\nPor vivencia vocacional de la fe entendemos la formulaci\u00f3n de la vida cristiana desde las virtudes teologales (fe, esperanza y caridad) que dan unidad a la persona y llevan a la s\u00ed\u00adntesis fe-vida. Los procesos catecumenales por su propia naturaleza apuntan a una vivencia vocacional de la fe como fructificaci\u00f3n del Bautismo y de la Confirmaci\u00f3n. Esta meta constituye la perspectiva m\u00e1s id\u00f3nea para plantear las acciones pastorales de la Iglesia; el aspecto que globaliza y unifica la pastoral en y de la Iglesia es lo vocacional. Ayudar a cada cristiano a descubrir y responder a la voluntad de Dios es el objetivo \u00faltimo que focaliza toda la acci\u00f3n pastoral. Esta perspectiva ayudar\u00ed\u00ada mucho a centrarse en lo fundamental y a dar unidad a tantos proyectos y actividades que funcionan con escasa conexi\u00f3n entre ellos y con poca coherencia interna.<\/p>\n<p>c) Una pedagog\u00ed\u00ada de la fe en clave de personalizaci\u00f3n<br \/>\nLas dos grandes fidelidades del evangelizador son la fidelidad al mensaje que transmite y la fidelidad a las personas que acompa\u00f1a. La personalizaci\u00f3n de la fe evita el subjetivismo que ignora la objetividad de la revelaci\u00f3n y al mismo tiempo, valora y respeta el proceso de maduraci\u00f3n de cada persona. Hay que personalizar las grandes experiencias de fe que tienen un car\u00e1cter estructurante de la personalidad cristiana; nos referimos a las experiencias de conversi\u00f3n, de seguimiento de Jes\u00fas, de an\u00e1lisis cr\u00ed\u00adtico-creyente de la realidad, de compromiso con el Reino, de experiencia oracional de Dios, de identificaci\u00f3n eclesial y de disponibilidad vocacional.<\/p>\n<p>Es pr\u00e1cticamente imposible que estas experiencias del proceso de fe se puedan vivir s\u00f3lo con las aportaciones del grupo; siendo el grupo imprescindible, necesita ser complementado con el acompa\u00f1amiento personal. El creyente que se est\u00e1 haciendo necesita a su lado otro creyente, en condiscipulado, que le ayuda desde su s\u00ed\u00adntesis personal a ir creando las condiciones necesarias para que el Esp\u00ed\u00adritu Santo pueda actuar en su coraz\u00f3n. Los modos de hacer de Dios nos sorprenden y sobrepasan; necesitamos conocer la \u00abgram\u00e1tica\u00bb con la que Dios habla por medio con la ayuda de un maestro de espiritualidad que, desde la cercan\u00ed\u00ada, nos ayuda a no autoenga\u00f1arnos y a responder con sinceridad. La veracidad de que lo que vivimos es aut\u00e9nticamente una experiencia cristiana de fe es lo que m\u00e1s nos debe importar. La personalizaci\u00f3n de la fe \u00abayuda a los j\u00f3venes a preguntarse y descubrir el sentido de la vida, a descubrir y asimilar la dignidad y exigencias de ser el cristiano, les propone las diversas posibilidades de vivir la vocaci\u00f3n humana en la Iglesia y en la sociedad y les anima y acompa\u00f1a en su compromiso por la construcci\u00f3n del Reino\u00bb (OPJ 15; Cfr. Ch L 54).<\/p>\n<p>e) El discernimiento comunitario<br \/>\nLa pr\u00e1ctica comunitaria del discernimiento es muy beneficiosa, tanto para el dinamismo espiritual del grupo, como para la toma de decisiones de forma corresponsable en temas importantes.<\/p>\n<p>Es imposible el discernimiento comunitario si los integrantes del grupo no tienen pr\u00e1ctica en el discernimiento personal. Requiere tiempo suficiente, ambiente adecuado, manejo de los datos, actitud de disponibilidad, libertad de esp\u00ed\u00adritu y oraci\u00f3n compartida. El animador del grupo debe asegurar que se dan los presupuestos para el discernimiento y que se sigue el procedimiento adecuado. Las personas que intervienen en el discernimiento comunitario han de tener claro las claves de lectura de las mociones y los modos de tomar las decisiones para que en el grupo se pueda dar el asentimiento de corazones. No se trata de defender los puntos de vista personales, sino de conocer la voluntad de Dios y de concretarla de la manera m\u00e1s evang\u00e9lica que se pueda. Discernir comunitariamente tiene que ver m\u00e1s con la b\u00fasqueda y acogida de \u00ablo que agrade m\u00e1s a Dios\u00bb que de la prevalencia de una opini\u00f3n mayoritaria; por lo mismo, lo que cada hermano ve y propone no es una opini\u00f3n m\u00e1s sino una propuesta desde la experiencia de Dios y desde las urgencias del Reino. El Esp\u00ed\u00adritu Santo -si se le deja actuar- es capaz de abrir las mentes y de conjuntar las miradas y los corazones en una respuesta com\u00fan. Las posibilidades de humanizaci\u00f3n personal y la liberaci\u00f3n integral para los m\u00e1s desfavorecidos son los criterios que avalan el que lo escogido es voluntad de Dios. Y esto vivido con paz y alegr\u00ed\u00ada en el coraz\u00f3n.<\/p>\n<p>f) Acompa\u00f1amiento personal<br \/>\nEs el cauce normal para que un creyente en proceso de formaci\u00f3n y maduraci\u00f3n de fe aprenda a discernir. El \u00e1mbito principal de aplicaci\u00f3n del discernimiento es la vocaci\u00f3n personal a la que cada uno se siente llamado por Dios en la Iglesia y en este mundo. Antes de llegar al discernimiento vocacional hay que acompa\u00f1ar otras experiencias estructurantes de la vida cristiana, tales como la conversi\u00f3n, el camino de oraci\u00f3n, el an\u00e1lisis cr\u00ed\u00adtico creyente de la realidad, el sentido comunitario de la fe y la disponibilidad vocacional. La fe que se descubre en el seguimiento de Jes\u00fas coge a la persona entera; este car\u00e1cter totalizante de la actitud religiosa pide la presencia cercana de alguien que nos ayude a ir aprendiendo la \u00abgram\u00e1tica\u00bb con la que Dios habla, a asumir el pasado, a configurarse como creyente y a mirar al futuro con decisi\u00f3n y esperanza. El paso de Dios por la vida de las personas y los caminos del Esp\u00ed\u00adritu sorprenden y desconciertan en no pocas ocasiones; el acompa\u00f1ante espiritual nos ayuda a ir dando nombre a todo lo que ocurre en nuestro interior, a confirmar lo que es de Dios, a desvelar los autoenga\u00f1os y a responder a los nuevos retos. Por la misma naturaleza de la catequesis y las exigencias de la fe madura, no se puede ser catequista de j\u00f3venes sin tener experiencia de acompa\u00f1amiento personal.<\/p>\n<p>g) Conocer y seguir un m\u00e9todo de discernimiento<br \/>\nEl discernimiento es una experiencia com\u00fan que ha sido abordada por diferentes maestros espirituales y se ha concretado en escuelas distintas seg\u00fan las \u00e9pocas y sensibilidades de los que las formularon. Algunas espiritualidades han hecho del discernimiento el elemento b\u00e1sico de la configuraci\u00f3n y el crecimiento de la fe. Da la impresi\u00f3n de que muchos cristianos hablan de la vida espiritual en t\u00e9rminos gen\u00e9ricos y confusos; incluso, cuando en el proceso de crecimiento de fe se llega a un determinado punto ya no se sabe avanzar, pues no se conoce bien lo que pasa y tampoco se disponen de las herramientas que permitan manejar la situaci\u00f3n. La vida espiritual tiene su l\u00f3gica interna, requiere un proceso largo, pasa por etapas muy distintas y precisa de acompa\u00f1amiento personalizado. Los educadores de la fe deber\u00ed\u00adamos saber responder con precisi\u00f3n a esta cuesti\u00f3n: \u00bfqu\u00e9 tiene que pasar en el interior de un catec\u00fameno para que llegue a madurar en la fe?. Conocer y acompa\u00f1ar este proceso es lo m\u00e1s importante; quiz\u00e1s formulamos muchos proyectos pastorales, pero sabemos poco de los procesos interiores de fe.<\/p>\n<p>Para abordar en profundidad este tema, el conocimiento de alg\u00fan m\u00e9todo o escuela de espiritualidad nos permite concretar y avanzar con pedagog\u00ed\u00ada. No nos quepa duda, ayudar a la experiencia cristiana y a que la actitud religiosa madure debe ser hilo conductor de toda la acci\u00f3n pastoral de la Iglesia; y la madurez en la fe tiene que ver directamente con la pr\u00e1ctica del discernimiento cristiano a nivel personal, comunitario y pastoral.<\/p>\n<p>BIBL. &#8211; BOFF, L, El destino del hombre y del mundo, Sal Terrae 1985; BoRos, L., El discernimiento de esp\u00ed\u00adritus: Conc 129 (1977) 368-375; CASTILLO, J. Discernimiento, Conceptos Fundamentales de Pastoral, Cristiandad 1983, 264-272; CASTA\u00ed\u2018O, C., Psicolog\u00ed\u00ada y orientaci\u00f3n vocacional, Marova 19902; GONZ\u00ed\u0081LEZ VALLES, C., Saber escoger. El arte del discernimiento, Sal Terrea 1984; MART\u00ed\u008dNEZ, J. M., El educador y su funci\u00f3n orientadora, SPx 1980; ORTA, M., Di\u00e1logo Pastoral con adolescentes, PPC 1988; PIKAZA, J, El discernimiento de esp\u00ed\u00adritus en el Nuevo Testamento: VR 285 (1975) 259-271; Ro1AS, J, Metodolog\u00ed\u00ada para practicar el discernimiento, Buena Prensa, M\u00e9xico 1985; Ruiz JURADO, M, El discernimiento cristiano, BAC 1995; SASTRE, j, El discernimiento vocacional, San Pablo 1996; SOBRINO, J, El seguimiento de Jes\u00fas como discernimiento: Conc 139 (1978) 517-529; URE\u00ed\u2018A, E. M., Discernimiento cristiano, psicoan\u00e1lisis y an\u00e1lisis marxista: Conc 139 (1978).<\/p>\n<p>Jes\u00fas Sastre<\/p>\n<p>Vicente M\u00c2\u00aa Pedrosa &#8211; Jes\u00fas Sastre &#8211; Ra\u00fal Berzosa (Directores), Diccionario de Pastoral y Evangelizaci\u00f3n, Diccionarios \u00abMC\u00bb, Editorial Monte Carmelo, Burgos, 2001<\/p>\n<p><b>Fuente: Diccionario de Pastoral y Evangelizaci\u00f3n<\/b><\/p>\n<p>El \u00abdiscernimiento espiritual\u00bb, una palabra muy conocida para la Biblia y la tradici\u00f3n espiritual cristiana, es el esfuerzo por evaluar, distinguir, localizar, entre las distintas actitudes humanas, las que proceden y las que no proceden de un movimiento interior del Esp\u00ed\u00adritu Santo.  Todo aquello que de aut\u00e9ntico se hace en la Iglesia emana de la escucha del Esp\u00ed\u00adritu. Por cada gesto genuinamente eclesial se puede repetir el estribillo que marca las siete cartas dirigidas a las Iglesias, recogidas en los primeros cap\u00ed\u00adtulos de! Apocalipsis: \u00abEl que tenga o\u00ed\u00addos, que escuche lo que el Esp\u00ed\u00adritu dice a las Iglesias\u00bb. Pero hay distintas formas de escucha. A veces la escucha es un \u00abreconocimiento\u00bb, cuando consiste en ver, acoger y proclamar las fundamentales realidades cristianas que componen la esencia misma de la vida eclesial, es la actitud de escucha frente a realidades como la Palabra, la eucarist\u00ed\u00ada, la comunidad, el ministerio pastoral: en estos casos, \u00abescuchar\u00bb significa reconocer la voz del pastor, seg\u00fan Juan. Otras veces, en cambio, la escucha adquiere m\u00e1s espec\u00ed\u00adficamente la forma de un \u00abdiscernimiento\u00bb: en este caso, el objeto inmediato ya no es simplemente una realidad divina que hay que reconocer como normativa para la propia vida, sino un comportamiento humano, un fen\u00f3meno hist\u00f3rico, una decisi\u00f3n comunitaria, de la que uno se pregunta si, c\u00f3mo, hasta qu\u00e9 punto, en qu\u00e9 condiciones y con qu\u00e9 consecuencias se realizan en la historia los perennes valores que Cristo ha confiado a la Iglesia.<\/p>\n<p> Carlo Mar\u00ed\u00ada Martini, Diccionario Espiritual, PPC, Madrid, 1997<\/p>\n<p><b>Fuente: Diccionario Espiritual<\/b><\/p>\n<p>El t\u00e9rmino \u00abdiscernimiento\u00bb (di\u00e1krisis) se usa en la espiritualidad como capacidad de distinguir los esp\u00ed\u00adritus; tiene una importancia capital en la tradici\u00f3n espiritual. En el evangelio aparece como capacidad de leer \u00bb los signos de los tiempos\u00bb (Mt 16,3), en el sentido de reconocer a Jes\u00fas como signo por excelencia. Para Pablo el discernimiento de los esp\u00ed\u00adritus es un poder y un carisma (Rom 12,10), la facultad de leer y de juzgar el discurso prof\u00e9tico y las tensiones en las relaciones fraternas (1 Cor 14,29. 6,5): en una palabra, es el don de \u00abdistinguir lo bueno y lo malo\u00bb (Heb 5,14).<\/p>\n<p> En la tradici\u00f3n del desierto \u00abel discernimiento es una segura percepci\u00f3n de la voluntad de Dios en todas las ocasiones, en todo lugar y en cualquier circunstancia; se encuentra en los que son puros de coraz\u00f3n, de cuerpo y de labios\u00bb (Juan Cl\u00ed\u00admaco, escal\u00e1 del para\u00ed\u00adso, 26, 1). Efectivamente, entre los maestros espirituales, en el camino espiritual de una persona los demonios se transforman de ordinario en \u00e1ngeles de luz (2 Cor 11,14), cuando experimentan la ineficacia de las tentaciones habituales, bien present\u00e1ndose ante ellos en esta funci\u00f3n a trav\u00e9s de sue\u00f1os y de visiones, bien inspir\u00e1ndoles pensamientos aparentemente buenos que sin embargo arrastran a la perdici\u00f3n. Entonces, el discernimiento no tiene s\u00f3lo una connotaci\u00f3n moral en la distinci\u00f3n entre el bien y el mal, o entre lo que est\u00e1 bien y lo que est\u00e1 mal en una persona determinada, sino que es un discernimiento de esp\u00ed\u00adritus propiamente dicho. Seg\u00fan Diadoco de Fotica es obra del Esp\u00ed\u00adritu Santo \u00abla l\u00e1mpara de la ciencia, encendida continuamente en nosotros\u00bb, que \u00abpurifica la mirada del alma\u00bb, por medio de la cual \u00ablos asaltos duros y tenebrosos de los demonios no solamente son claros al esp\u00ed\u00adritu, sino que pierden mucho de su vigor al quedar iluminados por la luz santa y gloriosa del Esp\u00ed\u00adritu\u00bb (Cien consideraciones sobre la fe, 28). En efecto, en el camino espiritual, \u00abcon la consolaci\u00f3n del Esp\u00ed\u00adritu Santo n tambi\u00e9n \u00bb Satan\u00e1s consuela al alma como con cierto sentimiento de falsa dulzura\u00bb. Entonces, cuando \u00bb el enga\u00f1ador se da cuenta de que el esp\u00ed\u00adritu se aplica al santo nombre del Se\u00f1or Jes\u00fas&#8230;, se retira de sus asechanzas y desde aquel momento combate contra el alma a campo abierto. En consecuencia, reconociendo exactamente las mistificaciones del maligno, el esp\u00ed\u00adritu progresa cada vez m\u00e1s en la experiencia del juicio\u00bb (Ib\u00ed\u00add., 31). La experiencia del discernimiento es, por consiguiente, inseparable del don del Esp\u00ed\u00adritu Santo, dador de la caridad espiritual que nos gu\u00ed\u00ada mediante la oraci\u00f3n y la ascesis para que nos apoderemos del \u00abcarisma del discernimiento de esp\u00ed\u00adritus\u00bb, a fin de \u00abconocer lo que concierne a cada uno de los demonios&#8230;n y poder de este modo rechazarlos (Atanasio, Vida de Antonio, 22).<\/p>\n<p>Seg\u00fan Evagrio P\u00f3ntico, se necesita  \u00bb una larga observaci\u00f3n\u00bb para adquirir una intuici\u00f3n espiritual y lograr distinguir entre \u00bb pensamientos ang\u00e9licos, pensamientos humanos y pensamientos que nos vienen de los demonios\u00bb (Tratado pr\u00e1ctico, 51). En la tradici\u00f3n espiritual antigua hay fundamentalmente dos modos de practicar el discernimiento: uno especialmente de tipo intelectual, controlando los pensamientos que sugiere el demonio (Evagrio), con la ayuda de padres espirituales expertos; el otro, observando el comportamiento que la acci\u00f3n de los esp\u00ed\u00adritus crea en el alma (Antonio).<\/p>\n<p>La regla de oro del discernimiento  de las buenas apariciones, seg\u00fan Antonio, es que hacen brotar \u00abun gozo inefable, buen humor, coraje, renovaci\u00f3n interior, firmeza de pensamientos, fuerza y amor a Dios\u00bb; las otras, por el contrario, traen \u00abpavor del alma, agitaci\u00f3n y desorden de pensamientos, tristeza. odio contra los ascetas, pereza&#8230;, malos deseos, pusilanimidad para las virtudes y desarreglo de las costumbres\u00bb (Vida de Antonio, 36).<\/p>\n<p>Seg\u00fan Juan Cl\u00ed\u00admaco, el primer discernimiento que se presenta a la persona en el camino espiritual tiene tres grados en la experiencia de las virtudes, sobre los que hay que practicar un continuo examen d\u00e9 conciencia \u00abcon la ayuda del maestro\u00bb. Un \u00abalfabeto\u00bb &#8211; dice el autor de la Scala paradisi &#8211; que todos sin distinci\u00f3n tienen que practicar: obediencia, ayuno, cilicio, cenizas, l\u00e1grimas, confesi\u00f3n, silencio, humildad, vigilias, coraje, fr\u00ed\u00ado, cansancio, pena, humillaci\u00f3n, contrici\u00f3n, olvido de las ofensas, amor fraterno, dulzura, fe simple y sin deseos de indagar, desinter\u00e9s por las cosas del mundo, indiferencia exenta de odio con los parientes, insensibilidad, simplicidad inocente, humillaci\u00f3n voluntaria.<\/p>\n<p> El programa y la materia de examen  para los avanzados en el progreso espiritual, son: la huida de la vanagloria, la ausencia de c\u00f3lera, la firme esperanza, la hesich\u00ed\u00ada, el discernimiento, el recuerdo continuo del juicio, la compasi6n, la hospitalidad, la moderaci6n en los reproches, la oraci6n en la impasibilidad, el despego del dinero.<\/p>\n<p>El discernimiento se refiere en primer lugar al conocimiento de la santa voluntad de Dios. Discernirla representa un arte que no est\u00e1 al alcance de todos. S61o las personas dotadas de discreci6n y de un don especial del Esp\u00ed\u00adritu Santo, recibido por todos los que hayan alcanzado un grado muy alto de perfecci6n, son capaces de hacer un r\u00e1pido diagn6stico y preciso en orden a un discernimiento tan dif\u00ed\u00adcil como es la voluntad de Dios sobre una persona. Entre los autores antiguos, estas personas fueron llamadas \u00abpadres espirituales n, no necesariamente sacerdotes, y \u00abmadres espirituales\u00bb Dotado de sencillez y de humildad,. dispuesto a escuchar y a consultar a los dem\u00e1s, el \u00abpadre espiritual\u00bb se hace \u00abdiacr\u00ed\u00adtico\u00bb, capaz de registrar los \u00bb movimientos del alma\u00bb, de \u00ableer en el coraz6nn de su \u00abhijo espiritual\u00bb y de guiarlo en aquella \u00ablucha invisible\u00bb contra los malos pensamientos que intenta fundamentalmente la renuncia a s\u00ed\u00ad mismo. El mejor padre espiritual ser\u00e1 aquel que logre transformar al hombre de esclavo de su propia vanidad en hijo de Dios, buscando solamente la voluntad de Dios en todo, la \u00abcontemplaci6n de la Providencia\u00bb.<br \/>\nT. Z. TenSek<\/p>\n<p> Bibl.: M. Vidal, El discernimiento \u00e9tico,  Cristiandad, Madrid 1980; G. M. Columb\u00e1s, El discernimiento de esp\u00ed\u00adritus, en El monacato primitivo, 11, BAC, Madrid 1975; 250256; AA. VV., Discernimiento de esp\u00ed\u00adritus, en Concilium 139 (1978); P. Penning de Vries, Discernimiento. Din\u00e1mica existencial de la doctrina y del esp\u00ed\u00adritu de san Ignacio de Loyola, Mensajero, Bilbao 1967<\/p>\n<p>PACOMIO, Luciano [et al.], Diccionario Teol\u00f3gico Enciclop\u00e9dico, Verbo Divino, Navarra, 1995<\/p>\n<p><b>Fuente: Diccionario Teol\u00f3gico Enciclop\u00e9dico<\/b><\/p>\n<p>SUMARIO: I. El discernimiento espiritual en el dinamismo de la experiencia cristiana: 1. El dinamismo de la existencia cristiana: 2. El discernimiento entre las tensiones y las ambig\u00fcedades de la existencia &#8211; 1I. El discernimiento espiritual en la Sagrada Escritura: 1. Actitud cr\u00ed\u00adtica del cristiano para avanzar por el camino de Dios; 2. B\u00fasqueda de la autenticidad cristiana: 3. Criterios de discernimiento seg\u00fan san Pablo &#8211; lll. El discernimiento personal: 1. Relaci\u00f3n dial\u00e9ctica entre discernimiento personal y comunitario: 2. El itinerario del discernimiento personal seg\u00fan san Ignacio de Loyola &#8211; IV. El discernimiento comunitario: 1. En qu\u00e9 consiste: 2. Sus fundamentos, 3. Condiciones psicol\u00f3gico-espirituales: 4. T\u00e9cnica del discernimiento comunitario.<\/p>\n<p>1. El discernimiento espiritual<br \/>\nen el dinamismo de la experiencia cristiana<br \/>\nLa instancia del discernimiento espiritual nace de la experiencia que el cristianismo realiza de su vida de fe en Cristo, en la Iglesia y en el mundo. La complejidad de las situaciones en que es llamado a vivir y obrar para llevar a cabo el plan de Dios respecto a s\u00ed\u00ad mismo y a los dem\u00e1s, le imponen una atenta consideraci\u00f3n de los impulsos y de las motivaciones que le inducen a determinadas opciones. Dios llama a cada hombre y a cada grupo de personas reunidas en su nombre con una vocaci\u00f3n particular, que se inserta en el contexto de la misi\u00f3n que \u00e9l conf\u00ed\u00ada al pueblo que se ha elegido. Lo que es bueno para uno no es bueno para otro, y lo que es mejor para uno no siempre lo es para otro. De ah\u00ed\u00ad nace el problema: \u00bfC\u00f3mo reconocer los signos de Dios en una determinada situaci\u00f3n y, sobre todo, frente a ciertas opciones?<br \/>\n1. DINAMISMO DE LA EXISTENCIA CRISTIANA &#8211; La existencia cristiana no es una realidad est\u00e1tica. Es vida y, como tal, posee todas las caracter\u00ed\u00adsticas de la vida. La vitalidad cristiana la experimentamos en nuestra vitalidad existencial, constituida por pensamientos, sentimientos, actividades, tendencias y relaciones con los dem\u00e1s, con las cosas, con el mundo y con la sociedad. La existencia cristiana tiene en nosotros su nacimiento y su desarrollo continuo. En el origen de esta nueva existencia, como ense\u00f1a san Pablo (Rom 3,6.8), est\u00e1 la fe en Jesucristo, el bautismo y el don del Esp\u00ed\u00adritu Santo: tres realidades que se integran rec\u00ed\u00adprocamente y suscitan en nosotros una acci\u00f3n vivificadora y santificadora de Dios, el cual establece una relaci\u00f3n din\u00e1mica con nuestra existencia, llam\u00e1ndola a la salvaci\u00f3n. La tr\u00ed\u00adada -fe, esperanza y caridad (1 Tes 1,2s: 5,8-10: 1 Cor 13,13: Col 1,4s)&#8217; constituye la dimensi\u00f3n fundamental en que la existencia cristiana se manifiesta, realiza y crece en nosotros. El bautismo, como \u00absacramento de la fe\u00bb, expresa tambi\u00e9n en el plano sensible la muerte y la resurrecci\u00f3n de Cristo con el simbolismo eficaz de su rito (Rom 6,3-11), hace participar con plena responsabilidad de la vida eclesial para formar un solo cuerpo en Cristo (1 Cor 12,13) y hace pasar de una existencia de tinieblas a una existencia de luz (Ef 5,8.14), que impone el paso de la muerte al pecado a la vida nueva en Cristo (Rom 6,11-12). Convertido en luz, el cristiano debe caminar como hijo de la luz. Esto le impone la tarea de discernir para percibir continuamente la voluntad de Dios (Ef 5.8.10.17). Ello lo consigue en la medida en que ha recibido el don del Esp\u00ed\u00adritu, agente divino en \u00e9l, principio din\u00e1mico y norma de su obrar (Rom 8). El Esp\u00ed\u00adritu divino entabla con el esp\u00ed\u00adritu humano un di\u00e1logo misterioso, que obliga al hombre a una continua confrontaci\u00f3n para dar una respuesta d\u00f3cil que lo lleve a un constante dinamismo de transformaci\u00f3n interior y de renovaci\u00f3n, capaz de permitir reconocer el sendero que traza Dios y seguirlo&#8217;. Por tanto, el discernimiento espiritual se impone como una constante de la vida del cristiano para pasar de la edad infantil de la fe a la del hombre perfecto o maduro&#8217; [ \/&#8217;Madurez espiritual].<\/p>\n<p>2. El. DISCERNIMIENTO ENTRE LAS TENSIONES Y LAS AMBIG\u00dcEDADES DE LA EXISTENCIA &#8211; As\u00ed\u00ad pues, para que la existencia cristiana pueda desarrollarse en su autenticidad, es necesario una continua confrontaci\u00f3n entre los impulsos y la gu\u00ed\u00ada de Dios, que se revela en Cristo, en la Iglesia, y los tirones de los instintos humanos o de las potencias del mal, que son contrarias al Esp\u00ed\u00adritu de Dios. No es f\u00e1cil distinguir entre la acci\u00f3n del Esp\u00ed\u00adritu de Dios, la del esp\u00ed\u00adritu humano y la del esp\u00ed\u00adritu malo&#8217;. Ante todo, la vida interior del hombre es compleja, y \u00ab\u00e9ste, por error, puede considerar como una manifestaci\u00f3n de lo absoluto o de Cristo algo que, de hecho, no es m\u00e1s que fruto de una elaboraci\u00f3n subjetiva\u00bb&#8216;. La dificultad proviene tambi\u00e9n de que, estando el Esp\u00ed\u00adritu de Dios presente en nuestro esp\u00ed\u00adritu humano, el esp\u00ed\u00adritu malo intenta imitar al Esp\u00ed\u00adritu de Dios para enga\u00f1ar al hombre y apartarle as\u00ed\u00ad del plan de salvaci\u00f3n.<\/p>\n<p>Pablo dice que si, mediante el Esp\u00ed\u00adritu, damos muerte a las acciones pecaminosas de nuestro yo, viviremos: \u00abEn efecto, cuantos son guiados por el Esp\u00ed\u00adritu de Dios, \u00e9stos son hijos de Dios\u00bb (Rom 8,14). Pero nuestra tendencia al pecado y a la enemistad con Dios (Rom 8,7) subsiste incluso despu\u00e9s de habernos justificado Dios mediante la fe y el bautismo. Tambi\u00e9n Jes\u00fas, inmediatamente despu\u00e9s del bautismo, fue tentado por Satan\u00e1s a abusar de su poder mesi\u00e1nico, desvi\u00e1ndolo del fin para el cual se lo hab\u00ed\u00ada Dios concedido. Esta experiencia de Jes\u00fas se repite en la vida del cristiano. Este siente el poder del esp\u00ed\u00adritu malo, que intenta separarle de Dios, sacarle de su plan o al menos disminuir su capacidad de obrar el bien. Por eso Pablo pone en guardia a los efesios: \u00abRevest\u00ed\u00ados de la armadura de Dios para que pod\u00e1is resistir las tentaciones del diablo\u00bb (6,11). Hay que tomar en serio el combate espiritual: \u00abNuestra lucha no es contra la carne y la sangre, sino contra los principados y potestades, contra los dominadores de este mundo tenebroso, contra los esp\u00ed\u00adritus malos que andan por los aires\u00bb (Ef 6,12)0.<\/p>\n<p>A veces la acci\u00f3n del poder del mal es muy sutil. Se encamina a proponer acciones o actitudes a primera vista buenas, pero para llevar a consecuencias malas, siguiendo la t\u00e1ctica de la exageraci\u00f3n: abusar de la propia libertad por el hecho de ser don de Dios, exagerar en la penitencia para llevar luego al cansancio y al rechazo de la vida espiritual; dejarlo todo y a todos, radicalizando la ense\u00f1anza evang\u00e9lica para exonerar de responsabilidades personales y sociales; usar para la propia gloria los dones recibidos de Dios para la edificaci\u00f3n de la Iglesia, etc. Satan\u00e1s, como dice san Juan, es el \u00abpadre de la mentira\u00bb (8,44): por eso debemos \u00abdistinguir el esp\u00ed\u00adritu de la verdad y el esp\u00ed\u00adritu del error\u00bb (1 In 4,6). Por lo dem\u00e1s, la historia de la Iglesia ense\u00f1a que algunos dones aut\u00e9nticos del Esp\u00ed\u00adritu no han podido desplegar toda su eficacia o han sido incluso desviados del bien, ya sea porque quienes los pose\u00ed\u00adan no supieron discernir entre inspiraci\u00f3n de Dios, impulsos y deseos humanos o desviaciones operadas por Satan\u00e1s [ \/&#8217;Diablo\/exorcismo], ya sea porque quienes ten\u00ed\u00adan la misi\u00f3n de guiar estos dones m\u00e1s bien los apagaron.<\/p>\n<p>II. El discernimiento espiritual<br \/>\nen la Sagrada Escritura<br \/>\nBuscar en la Escritura qu\u00e9 es el discernimiento espiritual significa recorrerla en su totalidad. M\u00e1s que una teor\u00ed\u00ada sobre el discernimiento, en la Escritura se encuentra un discernimiento en acci\u00f3n, inflen; por una parte, el discernimiento que Dios lleva a cabo en la historia de Israel o en la Iglesia; por otra, lo que el hombre hace para entrar por el camino de la fe y de la justificaci\u00f3n y para aumentar la operatividad de su existencia cristiana en la Iglesia y en el mundo&#8217;.<\/p>\n<p>1. ACTITUD CR\u00ed\u008dTICA DEL CRISTIANO PARA AVANZAR POR EL CAMINO DE Dios &#8211; En el AT Dios elige: a Ad\u00e1n (G\u00e9n 2,17), a Abrah\u00e1n (G\u00e9n 12,4), al pueblo de Israel (Ex 19,8; 24,3; Jue 24,15; Dt 28,1,15&#8230;), a los soberanos y a los caudillos del pueblo. Para responder a esta elecci\u00f3n, es preciso liberarse de motivos y condiciones oscuras y comprometerse en un camino continuo de b\u00fasqueda de fe. Tanto m\u00e1s que junto a la voz de Dios est\u00e1 la del pecado (G\u00e9n 4,7) y la de Satan\u00e1s, adversario de Dios, tambi\u00e9n ella llena de misterio&#8217;. Para el pueblo elegido se trata de aceptar la visi\u00f3n misma de Dios, su discernimiento. Esto implica dos momentos: el de la pasividad, es decir, dejarse guiar por \u00e9l, recordar sus beneficios, dar gracias, volver a los or\u00ed\u00adgenes para comprender nuevamente su vocaci\u00f3n, fortalecerse en la confianza de la promesa; el de la actividad, de compromiso, de b\u00fasqueda de lo nuevo, siempre bajo la gu\u00ed\u00ada de Dios.<\/p>\n<p>El discernimiento de \u00abesp\u00ed\u00adritus\u00bb o de \u00abinspiraciones\u00bb se encuentra a lo largo de todo el NT, particularmente en san Pablo. Adem\u00e1s de la menci\u00f3n expl\u00ed\u00adcita de la diakrisis pneumaton, del \u00abdiscernimiento de esp\u00ed\u00adritus\u00bb (1 Cor 12,10), se usa el verbo dokimazein y t\u00e9rminos afines, krino\/krisis y la rica serie de vocablos contenida en Flp 1,3-11; Col 1,9-14; Ef 1,15-23; 4,11-16; Rom 12,1-8. El verbo dokimazein expresa el significado fundamental del discernimiento, a saber: el de probar, catar, examinar. La necesidad del discernimiento proviene de la instancia cr\u00ed\u00adtica del cristiano sobre el horizonte escatol\u00f3gico. En efecto, la existencia cristiana se caracteriza, por un lado, por la aceptaci\u00f3n de la fe con el compromiso que implica y, por otro, por la inminencia del juicio. La vida del hombre y de la comunidad est\u00e1 sujeta al examen de Dios, en el cual hay que ofrecer una buena prueba; el juicio final es el resumen de este examen (1 Cor 3,13; Sant 1,12). Por esto es Dios ante todo el que \u00abdiscierne\u00bb el coraz\u00f3n del hombre; Dios en la historia es el dokimazon tas kardias hemon, es el \u00abDios que sondea nuestros corazones\u00bb (1 Tes 2,4).<\/p>\n<p>En los sin\u00f3pticos, aunque sin un t\u00e9rmino que la especifique, tenemos la realidad del discernimiento, que consiste sustancialmente en \u00abreconocer\u00bb en la persona y en la acci\u00f3n de Jes\u00fas el poder del Esp\u00ed\u00adritu de Dios y la derrota del esp\u00ed\u00adritu del mal. Jes\u00fas es signo de contradicci\u00f3n (Lc 2,34) y, por tanto, objeto de discernimiento; quienes lo acogen descubren en \u00e9l los caminos del Esp\u00ed\u00adritu; los dem\u00e1s siguen leyendo las Escrituras sin comprenderlas y ven pasar a Jes\u00fas sin reconocer que Dios est\u00e1 en \u00e9l.<\/p>\n<p>Para los Hechos de los Ap\u00f3stoles, m\u00e1s all\u00e1 de toda teor\u00ed\u00ada, la din\u00e1mica del discernimiento est\u00e1 clara: \u00abEl Esp\u00ed\u00adritu de Dios se impone con su misma fuerza y aporta su luz; sus iniciativas son siempre maravillosas y a veces desconcertantes, pero nunca turbulentas y desordenadas; su acci\u00f3n se ejerce siempre en la Iglesia, cuya paz y expansi\u00f3n asegura; su obra consiste en dar a conocer y en irradiar el nombre del Se\u00f1or Jes\u00fas\u00bb.<\/p>\n<p>2. B\u00daSQUEDA DE LA AUTENTICIDAD CRISTIANA &#8211; Para san Pablo, el discernimiento es parte imprescindible de la b\u00fasqueda din\u00e1mica de la autenticidad cristiana, por lo cual es preciso mantenerlo siempre en acci\u00f3n. Hay que distinguir las mociones que llevan la impronta del Esp\u00ed\u00adritu Santo de las que le son contrarias. Mociones, o sea sentimientos, experiencias, actitudes, impulsos hacia determinadas opciones, etc. Todo cristiano que haya experimentado el Esp\u00ed\u00adritu ha de habituarse a esa percepci\u00f3n espiritual, a esa finura del esp\u00ed\u00adritu que le mantiene en su identidad. A algunos el Esp\u00ed\u00adritu les concede el carisma del \u00abdiscernimiento de esp\u00ed\u00adritus\u00bb (1 Cor 12,10), es decir, la capacidad de reconocer si una determinada inspiraci\u00f3n viene del Esp\u00ed\u00adritu divino o del esp\u00ed\u00adritu del mal. Mas a todos los creyentes se les da el \u00abdon del Esp\u00ed\u00adritu\u00bb, que se recibe radicalmente con la fe y el bautismo, y que \u00abhabita en nosotros\u00bb (Rom 8,9) y nos gu\u00ed\u00ada, haci\u00e9ndonos vivir como hijos de Dios (Rom 8,14). El Esp\u00ed\u00adritu es, pues, el elemento constitutivo de nuestro ser de cristianos y el principio din\u00e1mico y la norma de acci\u00f3n, constituy\u00e9ndonos hijos \u00aben la Iglesia\u00bb (1 Cor 12,13)\u00bb. Para san Pablo, el discernimiento es la virtud del tiempo de la Iglesia, situado entre el hecho de la muerte y resurrecci\u00f3n de Cristo y la parus\u00ed\u00ada. Caracteriza a la Iglesia de los \u00ab\u00faltimos tiempos\u00bb (1 Cor 10,11), per\u00ed\u00adodo en el cual hay que afrontar el \u00abpresente siglo malo\u00bb (G\u00e1l 1,4). El cristiano no puede conformarse seg\u00fan el a \u00abmundo\u00bb; debe superarlo, aunque sea en la prueba y en la aflicci\u00f3n. Con la superaci\u00f3n de estas pruebas y tribulaciones, mediante un atento discernimiento, el cristiano manifiesta su autenticidad en una \u00abfe purificada\u00bb y aprobada por Dios, en una \u00abesperanza probada\u00bb en la oscuridad del tiempo presente, en una \u00abcaridad filial\u00bb, \u00abderramada en nuestros corazones por medio del Esp\u00ed\u00adritu Santo que se nos ha dado\u00bb (Rom 5,3-5). El cristiano no se somete a las pruebas de la vida, sino que las discierne para descubrir en ellas la voluntad de Dios, el cual permite que formen parte de la pedagog\u00ed\u00ada de la salvaci\u00f3n. Ante los tiempos escatol\u00f3gicos, las pruebas y las tribulaciones asumen el significado de anticipaci\u00f3n, en el tiempo de la Iglesia, del discernimiento final y se convierten en participaci\u00f3n del juicio escatol\u00f3gico ya realizado en la muerte y resurrecci\u00f3n de Cristo\u00bb.<\/p>\n<p>El discernimiento, en su aspecto moral, tiene por objeto la \u00abvoluntad de Dios\u00bb (Rom 12,2), el imperativo moral que impone una vida santa y grata a Dios (1 Tes 4,1-3). Este imperativo implica un camino de conversi\u00f3n continua. El \u00abconocimiento\u00bb de que habla a menudo san Pablo (Flm 5-6; Ef 1,15-18; 4,13; Flp 1,9; Col 1,9-10) representa justamente este car\u00e1cter din\u00e1mico de progreso y de crecimiento, que interioriza y conduce a un nivel cada vez m\u00e1s alto la fe, la esperanza y la caridad\u00bb Analizando el acto concreto del discernimiento, Therrien dice que es al mismo tiempo uno y complejo, humano y divino, personal y eclesial, \u00aben situaci\u00f3n\u00bb e inserto en el plan \u00fanico de salvaci\u00f3n, que mira a la edificaci\u00f3n de los hermanos y est\u00e1 ordenado a la gloria de Dios, realizado en el tiempo, pero que participa ya del juicio escatol\u00f3gico \u00ab.<\/p>\n<p>3. CRITERIOS DE DISCERNIMIENTO SEG\u00daN SAN PABLO &#8211; San Juan, en su primera carta, pone en guardia a los cristianos para que adopten una actitud cr\u00ed\u00adtica frente a las inspiraciones: \u00abQuerid\u00ed\u00adsimos, no os fi\u00e9is de todo esp\u00ed\u00adritu, sino examinad los esp\u00ed\u00adritus, a ver si son de Dios\u00bb (4,1)\u00bb. Mas \u00bfcu\u00e1les son los criterios por los que podemos estar seguros de que una determinada inspiraci\u00f3n viene efectivamente de Dios? De la doctrina paulina se obtienen algunos de estos criterios16:<\/p>\n<p>a. Los frutos. El esp\u00ed\u00adritu bueno y el malo se reconocen por sus frutos: \u00abLas obras de la carne son manifiestas: fornicaci\u00f3n, impureza, lujuria&#8230; Por el contrario, los frutos del Esp\u00ed\u00adritu son: caridad, alegr\u00ed\u00ada, paz, longanimidad, benignidad, bondad, fe, mansedumbre, continencia\u00bb (G\u00e1l 5,14-22; cf Ef 5,8-10; Rom 7,4-5.19-20).<\/p>\n<p>b. La comuni\u00f3n eclesial. Los dones aut\u00e9nticos del Esp\u00ed\u00adritu son los que edifican la Iglesia (1 Cor 14,4.12.26). Los carismas son dones fecundos para la Iglesia; sobre todo la profec\u00ed\u00ada, la cual es una palabra eficaz que da paz, \u00e1nimo y confianza.<\/p>\n<p>c. La fuerza en la debilidad. El Esp\u00ed\u00adritu se manifiesta con signos de poder: milagros, seguridad para proclamar la palabra de Dios y afrontar las persecuciones (1 Tes 1,4-5; 2 Cor 12,12). Son signos que resultan tanto m\u00e1s aut\u00e9nticos cuanto m\u00e1s contrastan con la debilidad del ap\u00f3stol (2 Cor 2,4; 12,9).<\/p>\n<p>d. La inmediatez de Dios. Seguridad de una vocaci\u00f3n divina en la docilidad eclesial. Por una parte, Dios da la certeza de su vocaci\u00f3n (Rom 1,1; G\u00e1l 1,15; Flp 3,12) y, por otra, esa llamada debe ser autenticada por la comunidad eclesial (G\u00e1l 1,18) y por sus responsables.<\/p>\n<p>e. La luz y la paz. Los dones del Esp\u00ed\u00adritu no son impulsos ciegos que suscitan dificultades y desorden (1 Cor 14,33). Esto vale no s\u00f3lo de las manifestaciones extraordinarias, sino tambi\u00e9n de las mociones interiores: \u00abLa tristeza que es seg\u00fan Dios causa penitencia saludable e irrevocable, mientras que la tristeza del mundo engendra la muerte\u00bb (2 Cor 7,10), \u00abporque el pensamiento de la carne es muerte, pero el pensamiento del esp\u00ed\u00adritu es vida y paz\u00bb (Rom 8,6; cf 14,17-18).<\/p>\n<p>f. La comuni\u00f3n fraterna. Es el criterio m\u00e1s seguro e importante que revela los signos de la presencia del Esp\u00ed\u00adritu (1 Cor 13). La caridad hace tambi\u00e9n respetar y amar los carismas de los otros (1 Cor 12).<\/p>\n<p>g. \u00c2\u00a1Jes\u00fas es el Se\u00f1or! El criterio supremo del discernimiento es el alcance y las consecuencias que ciertas mociones o actitudes tienen respecto a Jes\u00fas: \u00abNadie, hablando en el Esp\u00ed\u00adritu de Dios, dice: &#8216;Maldito es Jes\u00fas&#8217;, ni nadie puede decir: &#8216;Jes\u00fas es el Se\u00f1or&#8217;, sino el Esp\u00ed\u00adritu\u00bb (1 Cor 12,3). Confesar que Jes\u00fas es el Se\u00f1or no es s\u00f3lo pronunciar una f\u00f3rmula, sino descubrir el secreto de su persona, proclamar su divinidad, adherirse a \u00e9l por la fe y el amor, lo cual no es posible m\u00e1s que con la gracia del Esp\u00ed\u00adritu Santo.<\/p>\n<p>III. El discernimiento personal<br \/>\nDistinguimos entre discernimiento personal y discernimiento comunitario. Por el primero entendemos la b\u00fasqueda de la voluntad de Dios realizada por una persona particular; por el segundo, la realizada por la comunidad o por un grupo de personas unidas por un v\u00ed\u00adnculo particular y, en \u00faltima instancia, por la Iglesia.<\/p>\n<p>1. RELACI\u00ed\u201cN DIALECTICA ENTRE DISCERNIMIENTO PERSONAL Y COMUNITARIO &#8211; LOS dos aspectos, personal y comunitario, son distintos, pero no est\u00e1n separados. El segundo supone el primero, porque una comunidad o un grupo puede ponerse en situaci\u00f3n de discernimiento en la medida en que los individuos hayan hecho o hagan en su vida una experiencia profunda de la b\u00fasqueda de Dios y se dejen guiar por el Esp\u00ed\u00adritu en sus opciones. Tambi\u00e9n el primero supone el segundo, al menos de forma embrionaria, en cuanto que la escucha de Dios en la vida personal pasa necesariamente a trav\u00e9s de la mediaci\u00f3n de la Iglesia, que lee los signos de los tiempos de la sociedad en que se vive. La expresi\u00f3n m\u00ed\u00adnima de esta mediaci\u00f3n est\u00e1 constituida por el di\u00e1logo con el consejero o director espiritual. Cuando nos sentimos inspirados a tomar una opci\u00f3n determinada o una determinada orientaci\u00f3n espiritual, es preciso medir estos impulsos con dos criterios fundamentales: la conformidad con la palabra de Dios y la ense\u00f1anza de la Iglesia (dejarse juzgar por la fe de la Iglesia: Rom 12,6; 1 Cor 14,29-32; 1 In 4,2) y el servicio para la edificaci\u00f3n de la Iglesia y de la sociedad (es el fin para el cual el Esp\u00ed\u00adritu Santo otorga los dones: 1 Cor 12,7; 14,12.26; lo contrario de la edificaci\u00f3n es la divisi\u00f3n, que no puede venir del Esp\u00ed\u00adritu: 1 Cor 1,10-13).<\/p>\n<p>La mediaci\u00f3n del consejero espiritual tiene por fin objetivar las experiencias y la mociones personales\u00bb, aclarar lo que quiz\u00e1 se advierte de modo confuso y situarse en un horizonte eclesial en el cual tomar conciencia de que el Esp\u00ed\u00adritu es \u00fanico y no puede contradecirse [.&#8211;n Padre espiritual].<\/p>\n<p>2. EL ITINERARIO DEL DISCERNIMIENTO PERSONAL SEG\u00daN SAN IGNACIO DE LOYOLA &#8211;<br \/>\nEntre los numerosos autores espirituales que han tratado del discernimiento\u00bb, san Ignacio de Loyola ocupa un puesto relevante debido a la experiencia espiritual que tuvo de la alternancia de diversas mociones espirituales a partir de su conversi\u00f3n\u00bb, experiencia que describi\u00f3 en sus Ejercicios espiritualesRO, los cuales est\u00e1n guiados enteramente por el discernimiento espiritual con vistas a una elecci\u00f3n de vida que ha de hacerse para la mayor gloria de Dios (nn. 169-189). Veamos los elementos m\u00e1s destacados de este itinerario:<\/p>\n<p>a) Conquistar la libertad interior, don del Esp\u00ed\u00adritu Santo. Toda predeterminaci\u00f3n o prejuicio bloquea el proceso de conocimiento y de b\u00fasqueda de la voluntad de Dios. Por eso hay que \u00abvencerse a uno mismo y ordenar la vida sin dejarse determinar por ning\u00fan afecto desordenado\u00bb (n. 21; 1). No hay que ocultar la dificultad que existe para llegar a una mirada de fe y a un impulso de amor tan purificados. Es preciso estar animado por el deseo del \u00abmagis\u00bb (n. 23) para emprender este itinerario \u00abcon gran \u00e1nimo y liberalidad con su<br \/>\nCreador y Se\u00f1or, ofreci\u00e9ndole todo su querer y libertad, para que su Divina Majestad, as\u00ed\u00ad de su persona como de todo lo que tiene, se sirva conforme a su sant\u00ed\u00adsima voluntad\u00bb (n. 5). Toda la persona debe dedicarse a discernir entre la diversidad de las mociones espirituales, sobre todo su afectividad profunda para \u00absentir y gustar de las cosas interiormente\u00bb (n. 2).<\/p>\n<p>b) Escucha de la palabra y compromiso din\u00e1micos. Dios se comunica mediante la palabra que libera; el hombre debe colaborar con su adhesi\u00f3n personal. Por eso san Ignacio dice: \u00abdemandar la gracia que quiero\u00bb (n. 91). Por una parte, es preciso pedir, sabiendo que no puede uno dar por s\u00ed\u00ad mismo lo que se busca en el plano de la salvaci\u00f3n y de la perfecci\u00f3n cristiana; por otra, hay que desear lo que se pide, con una participaci\u00f3n comprometida de toda la persona en la acci\u00f3n de Dios.<\/p>\n<p>c) Prontitud para el cambio. El discernimiento supone la prontitud para cuestionarse frente a la interpelaci\u00f3n de la palabra de Dios y estar dispuesto a cambiar lo que sea en la vida personal, social o comunitaria. S\u00f3lo Dios es lo absoluto y lo inmutable; todo el resto (\u00ablas cosas creadas\u00bb, n. 23) es relativo, y frente a ello \u00abes menester hacernos indiferentes\u00bb (n. 23). La indiferencia es la actitud positiva consistente en optar fundamentalmente por Dios y por su plan sobre nosotros, por lo que todo el resto se vuelve innecesario y s\u00f3lo se acoge en la medida en que sea manifestaci\u00f3n de la voluntad divina. Esto implica saber poner en discusi\u00f3n toda opci\u00f3n, preferencia o seguridad que no encuentre confirmaci\u00f3n en Dios. Hay que dejarse llevar por el Esp\u00ed\u00adritu, que es fuente de perenne novedad y creatividad. Renunciar al cambio es cerrarse a la novedad del Esp\u00ed\u00adritu, que puede abrir un camino nuevo que nos lleve m\u00e1s cerca de Dios y de los hermanos. Esta prontitud para el cambio, en los Ejercicios, es tratada en el \u00abpre\u00e1mbulo para hacer elecci\u00f3n\u00bb en dos actitudes, una positiva al cambio y la otra negativa. La primera es la del que se coloca frente al problema de una elecci\u00f3n con \u00abojo simple\u00bb, solamente \u00abmirando para lo que soy creado, es, a saber, para alabanza de Dios nuestro Se\u00f1or y salvaci\u00f3n de mi alma\u00bb (n. 169). La segunda es la del que invierte el orden de las cosas: primero escoge el medio y luego intenta atraer a Dios a lo que ha elegido (n. 169).<\/p>\n<p>d) La experiencia de consolaciones y de desolaciones. San Ignacio describe la resonancia interior que la palabra de Dios y sus mociones suscitan en nosotros, con alternancia de euforia y de depresi\u00f3n, mediante los t\u00e9rminos de consolaci\u00f3n y de desolaci\u00f3n espiritual. \u00bfQu\u00e9 es la consolaci\u00f3n espiritual? \u00abLlamo consolaci\u00f3n espiritual cuando en el alma se causa alguna moci\u00f3n interior, con la cual viene el alma a inflamarse en amor de su Creador y Se\u00f1or y, por consiguiente, cuando ninguna cosa criada sobre la faz de la tierra puede amar en s\u00ed\u00ad, sino en el Creador de todas ellas&#8230; Finalmente, llamo consolaci\u00f3n a todo aumento de esperanza, fe y caridad y a toda alegr\u00ed\u00ada interna que llama y atrae a las cosas celestiales y a la propia salud de su alma, tranquiliz\u00e1ndola y pacific\u00e1ndola en su Creador y Se\u00f1or\u00bb (n. 316). Se trata, pues, de una experiencia de los \u00abfrutos\u00bb del Esp\u00ed\u00adritu, de un incremento de las actitudes fundamentales de la existencia cristiana, a saber: de la fe, de la esperanza y de la caridad.<\/p>\n<p>La desolaci\u00f3n, en cambio, es lo contrario de la consolaci\u00f3n: \u00abAs\u00ed\u00ad como oscuridad del alma, turbaci\u00f3n en ella, moci\u00f3n hacia las cosas bajas y terrenas, inquietud de varias agitaciones y tentaciones que mueven a desconfianza, sin esperanza, sin amor, hall\u00e1ndose del todo perezosa, tibia, triste y como separada de su Creador y Se\u00f1or\u00bb (n. 317). Por consiguiente, la consolaci\u00f3n es energ\u00ed\u00ada del Esp\u00ed\u00adritu Santo para emprender o confirmarse en una elecci\u00f3n dada; la desolaci\u00f3n lleva lejos del Se\u00f1or y es signo de la acci\u00f3n en nosotros del esp\u00ed\u00adritu malo, \u00abcon cuyos consejos no podemos tomar el camino para acertar\u00bb (n. 318).<\/p>\n<p>e) La din\u00e1mica de una elecci\u00f3n. A trav\u00e9s de la experiencia del discernimiento de las mociones interiores se puede llegar a una elecci\u00f3n seg\u00fan Dios. Pero ante todo es necesario que el objeto de la elecci\u00f3n sea bueno o indiferente (n. 170). Fuera del caso de una intervenci\u00f3n extraordinaria de Dios, que nos manifestar\u00ed\u00ada as\u00ed\u00ad su voluntad, una elecci\u00f3n ha de realizarse a trav\u00e9s de una \u00absuficiente claridad y conocimiento por experiencia de consolaciones y desolaciones y por experiencia de discernimiento de varios esp\u00ed\u00adritus\u00bb (n. 176). Cuanto m\u00e1s profunda es esta experiencia espiritual, tanto m\u00e1s es posible desenmascarar tambi\u00e9n las \u00absutilezas\u00bb de la acci\u00f3n del enemigo, el cual \u00abse transforma en \u00e1ngel de luz\u00bb, insin\u00faapensamientos aparentemente buenos, pero que luego resultan ser espiritualmente nocivos (n. 332), por lo cual es preciso examinar \u00abel discurso de los pensamientos\u00bb para ver si terminan \u00aben alguna cosa mala o distractiva o menos buena\u00bb (n. 353). Este proceso, sin embargo, no exime de emplear las energ\u00ed\u00adas humanas, a saber: de examinar serenamente los motivos en pro y en contra de una determinada elecci\u00f3n, que ha de hacerse en el \u00abtiempo tranquilo\u00bb, \u00abcuando el alma no est\u00e1 agitada por varios esp\u00ed\u00adritus y usa sus potencias naturales libre y tranquilamente\u00bb (n. 177). De la elecci\u00f3n que ha de hacerse en este tiempo tranquilo, san Ignacio describe un itinerario concreto: 1) precisar el objeto de la elecci\u00f3n; 2) fijar el fin, a saber: Dios y su alabanza, y encontrarse en la indiferencia, pronto a \u00abseguir lo que sintiere ser m\u00e1s en gloria y alabanza de Dios nuestro Se\u00f1or y salvaci\u00f3n de mi alma\u00bb (n. 179); 3) pedir al Se\u00f1or que oriente las mociones interiores hacia su voluntad; 4) considerar las ventajas y las desventajas del objeto de la elecci\u00f3n s\u00f3lo con vistas al fin; 5) deliberar seg\u00fan motivos razonables; 6) presentar en la oraci\u00f3n la elecci\u00f3n hecha a Dios para que la confirme (nn. 179-183).<\/p>\n<p>IV. El discernimiento comunitario<br \/>\nLas instancias y el itinerario del discernimiento personal se aplican de modo an\u00e1logo al discernimiento comunitario.<\/p>\n<p>1. EN QUE CONSISTE &#8211; Un grupo de personas, unido por un vinculo particular, como puede ser una comunidad religiosa, un grupo de oraci\u00f3n o de compromiso apost\u00f3lico, sobre todo si se tiene que tomar opciones, est\u00e1 llamado a realizar, en cuanto grupo, un discernimiento de la voluntad de Dios tocante a su modo de vivir la fe y de comprometerse en la Iglesia y en la sociedad. Se trata de interrogarse delante de Dios para comprender si la decisi\u00f3n que hay que tomar es conforme al proyecto evang\u00e9lico y si responde a los tiempos de la Iglesia y a las exigencias de los hombres de nuestro tiempo. Es una actitud de b\u00fasqueda desinteresada, en la cual cada miembro del grupo se siente corresponsable y colabora en la valoraci\u00f3n de las mociones del Esp\u00ed\u00adritu para que el grupo como tal llegue a la decisi\u00f3n que m\u00e1s agrada al Se\u00f1or. El discernimiento comunitario se aplica de modo particular a la comunidad religiosa, sea local o provincial, o al instituto entero. El Vat. II alienta ese estilo de b\u00fasqueda com\u00fan de la voluntad de Dios en orden a la renovaci\u00f3n de la vida religiosa.<\/p>\n<p>2. SUS FUNDAMENTOS &#8211; Como el discernimiento personal tiene supuestos necesarios, tambi\u00e9n el comunitario se funda en algunas premisas, que aseguran su posibilidad y rectitud.<\/p>\n<p>a. Cada miembro del grupo debe haber tenido la experiencia del discernimiento personal. Esto supone una vida interior genuina que haya ense\u00f1ado a buscar la voluntad de Dios con libertad espiritual.<\/p>\n<p>b. El discernimiento es posible \u00fanicamente como experiencia fuerte de fe, no s\u00f3lo personal, sino tambi\u00e9n comunitaria. Es un acto de abandono, de escucha, de confianza en Dios, que gu\u00ed\u00ada a las personas, a los grupos y la historia. Es Dios el que, en su presente de gracia, interpela a la comunidad sobre su identidad y su misi\u00f3n apost\u00f3lica. El le dirige su palabra en Cristo, en la Iglesia y a trav\u00e9s de los signos de los tiempos. \u00abEl amor que me hace elegir\u00bb -dice san Ignacio- debe descender \u00abde arriba, del amor de Dios\u00bb, de modo que la elecci\u00f3n. se haga \u00ab\u00fanicamente por su Creador y Se\u00f1or\u00bb (n. 184). El grupo debe vivir as\u00ed\u00ad el \u00abnosotros\u00bb de la fe y estar abierto a la fe de la Iglesia entera.<\/p>\n<p>c. El grupo que intenta discernir la voluntad de Dios debe abrirse al Esp\u00ed\u00adritu Santo, el cual \u00abguiar\u00e1 a la verdad completa\u00bb (Jn 16,13). El discernimiento, en efecto, es \u00abespiritual\u00bb, es decir, se hace s\u00f3lo en el Esp\u00ed\u00adritu, bajo su influjo. Esta apertura al Esp\u00ed\u00adritu requiere la purificaci\u00f3n del coraz\u00f3n y de las intenciones y una profunda conversi\u00f3n a Cristo y al evangelio.<\/p>\n<p>d. La oraci\u00f3n, que crea el clima para el discernimiento, debe vivirse no s\u00f3lo a nivel personal, sino tambi\u00e9n a nivel comunitario, en una relaci\u00f3n filial con Dios que haga sentirse a todos hijos de un mismo Padre y lleve a exclamar \u00abAbba, Padre\u00bb (G\u00e1l 4,6; Rom 8,15).<\/p>\n<p>3. CONDICIONES PSICOL\u00ed\u201cGICO-ESPIRITUALES &#8211; Las leyes de la psicolog\u00ed\u00ada de grupo desempe\u00f1an su papel en el discernimiento comunitario. Ayudan a distinguir lo que facilita y lo que obstaculiza una aut\u00e9ntica b\u00fasqueda de loscaminos de Dios. He aqu\u00ed\u00ad algunas condiciones para crear premisas de autenticidad:<\/p>\n<p>a. El prop\u00f3sito inicial debe ser el de \u00abbuscar y encontrar la voluntad de Dios\u00bb (n. 1). Ha de adoptarse no un punto de vista sujeto a intereses humanos o ego\u00ed\u00adstas, sino el del plan salv\u00ed\u00adfico que Dios tiene sobre la comunidad y, a trav\u00e9s de ella, sobre la Iglesia y sobre el mundo. Es contraria a esto la actitud del que quiere hacer prevalecer, dentro de ese grupo, su parecer o su posici\u00f3n.<\/p>\n<p>b. Para un encuentro con los dem\u00e1s en la b\u00fasqueda de Dios es preciso purificarse de las pasiones, que bloquean una aut\u00e9ntica relaci\u00f3n interpersonal. Tales son, por ejemplo, la incomunicabilidad con los hermanos, sentimientos cultivados de envidia, de celos, de no participaci\u00f3n en la alegr\u00ed\u00ada y el dolor ajenos, etc.<\/p>\n<p>c. Condici\u00f3n importante es la de aceptaci\u00f3n de que los dem\u00e1s nos cuestionen, as\u00ed\u00ad como Dios a trav\u00e9s de los mismos. Esta disponibilidad pone al desnudo la verdad que somos y que buscamos. Desenmascara nuestras ambig\u00fcedades, los prejuicios, las predeterminaciones; verifica si algunas de nuestras seguridades son aut\u00e9nticas o falsas, si buscamos el inter\u00e9s de Dios o nos buscamos a nosotros mismos.<\/p>\n<p>d. Renunciar a la autosuficiencia, a la pretensi\u00f3n de conocer en solitario la voluntad de Dios. Esta se encuentra mediatizada por el testimonio y la experiencia espiritual de los otros, de la Iglesia y de la sociedad. Al rechazar sentirse constituido en un sistema cerrado y est\u00e1tico de verdad, nos abrimos a la posibilidad de ser completados por los otros, por su competencia, sensibilidad y experiencia. Con frecuencia algunas elecciones importantes se preparan cuidadosamente con una investigaci\u00f3n sociol\u00f3gica, psicol\u00f3gica y pol\u00ed\u00adtica para captar las instancias que provienen de una sociedad en r\u00e1pida mutaci\u00f3n. El discernimiento espiritual no puede ignorar estos datos, sino que los ve en una perspectiva diversa de aquella con que una administraci\u00f3n puede programar su ejercicio. La perspectiva es la evang\u00e9lica, en la cual entran factores imponderables con un metro puramente humano.<\/p>\n<p>e. Condici\u00f3n concomitante de la precedente es la de dar cabida a los dem\u00e1s en uno mismo, en los propios puntos de vista y convicciones. Es una actitud de respeto a la persona de losdem\u00e1s, de sincera caridad evang\u00e9lica, por encima de ciertas ideolog\u00ed\u00adas que dividen.<\/p>\n<p>f. Condici\u00f3n importante es tambi\u00e9n la de que un grupo o comunidad no se cierre en s\u00ed\u00ad mismo, sino que se sienta parte de comunidades m\u00e1s vastas y de la Iglesia entera, viviendo sus orientaciones universales.<\/p>\n<p>4. TECNICA DEL DISCERNIMIENTO COMUNITARIO &#8211; La palabra \u00abt\u00e9cnica\u00bb no debe hacer pensar en una planificaci\u00f3n con ritmos mec\u00e1nicos. El discernimiento es una actividad espiritual que se desarrolla bajo la moci\u00f3n del Esp\u00ed\u00adritu, el cual obra con libertad y pide a los hombres una respuesta libre. En este clima debe vivir el cristiano. Por discernimiento comunitario (y tambi\u00e9n personal) se entiende, pues, ante todo, un estilo de vida evang\u00e9lica permanente; una vigilancia evang\u00e9lica pronta siempre a acoger la voz de Dios y a actuar en consecuencia, y contraria a toda visi\u00f3n ego\u00ed\u00adsta. La actitud de buscar primero el reino de Dios lleva a discernir los caminos de Dios de modo espont\u00e1neo en las circunstancias ordinarias de la vida y en las decisiones m\u00e1s comunes y necesarias.<\/p>\n<p>En cambio, el discernimiento comunitario en el sentido restringido del t\u00e9rmino se impone en algunos momentos fuertes de la vida de un grupo o de una comunidad cuando est\u00e1n en juego valores importantes para la vida cristiana y la misi\u00f3n eclesial. En este caso, dando por supuesto cuanto queda dicho antes, se requiere tambi\u00e9n una cierta t\u00e9cnica, la cual ha de ser el\u00e1stica para adaptarse a las circunstancias y a la madurez espiritual de los individuos y del grupo. El discernimiento comunitario, por lo dem\u00e1s, tiene diversos grados de realizaci\u00f3n y diversas fases de profundizaci\u00f3n.<\/p>\n<p>De todos modos, las etapas esenciales del discernimiento comunitario deber\u00ed\u00adan ser las siguientes: a) Vivificar en el grupo un clima de fe, de escucha de Dios y de los otros, de disponibilidad y de oraci\u00f3n. b) Precisar con exactitud el tema que ha de ser objeto de discernimiento y de eventual decisi\u00f3n. Por eso el que est\u00e9 encargado de dirigir y alentar el discernimiento ha de proporcionar todas las informaciones objetivas sobre el tema, de modo que todos conozcan con exactitud los \u00abdatos\u00bb necesarios. Debe tratarse de un tema cuya discusi\u00f3n competa al grupo y que sea de importancia y trascendencia para su vida y su misi\u00f3n religiosa. c) Comenzar con un tiempo de oraci\u00f3n personal, para ponerse a la escucha de Dios, presentarle el tema sobre el que se invoca su luz y poder captar las mociones espirituales que proceden del Esp\u00ed\u00adritu Santo con un coraz\u00f3n libre de afectos desordenados. d) A esto puede seguir una reuni\u00f3n de \u00abescucha\u00bb, en la cual cada uno puede expresar lo que ha experimentado en la oraci\u00f3n, siendo escuchado por los dem\u00e1s con aut\u00e9ntica participaci\u00f3n, sin discutir su experiencia. e) Puede dedicarse otro tiempo de oraci\u00f3n personal para pedir al Se\u00f1or discernimiento sobre motivos en favor o en contra del tema de que se trata.,n Luego sigue una reuni\u00f3n de \u00abdiscusi\u00f3n\u00bb y de an\u00e1lisis de los argumentos que cada uno aduce y que est\u00e1n iluminados por las mociones del Esp\u00ed\u00adritu, por la consolaci\u00f3n o desolaci\u00f3n espirituales. g) Cuando el discernimiento llega a un punto de maduraci\u00f3n suficiente, se pasa a la fase deliberativa. Lo ideal es que la b\u00fasqueda desapasionada lleve a una decisi\u00f3n un\u00e1nime. Si \u00e9sta no se diese, seria preciso que al menos hubiese unanimidad en la aceptaci\u00f3n de lo que la mayor\u00ed\u00ada ha decidido como lo mejor. h) Por \u00faltimo, sigue la confirmaci\u00f3n de la decisi\u00f3n tomada, que se manifiesta a varios niveles. En el caso de una comunidad religiosa, tenemos la confirmaci\u00f3n del superior, el cual \u00abtoma la decisi\u00f3n\u00bb y asegura as\u00ed\u00ad a la comunidad que se encuentra en el camino justo. Est\u00e1 luego la confirmaci\u00f3n que viene del mismo Esp\u00ed\u00adritu Santo, el cual infunde un aumento de fe, de esperanza y de caridad despu\u00e9s de tomada la decisi\u00f3n. Finalmente. hay una confirmaci\u00f3n \u00abapost\u00f3lica\u00bb, o sea la experiencia de que la elecci\u00f3n hecha libera nuevas energ\u00ed\u00adas apost\u00f3licas, da un sentido m\u00e1s vivo de la Iglesia y un mayor entusiasmo misionero. Estos signos de la acci\u00f3n de Esp\u00ed\u00adritu en el discernimiento realizado llevan a un sentido de agradecimiento y de alabanza del Se\u00f1or.<\/p>\n<p>A. Barruffo<br \/>\nBIBL.-AA. VV., El discernimiento (Equipo Mundo Mejor, n. 43, 1975).-AA. VV., Dicernimiento comunitario, Inst. Teol. Vida Religiosa, Madrid 1976.-AA. VV., Discernimiento de esp\u00ed\u00adritus, en \u00abConcilium\u00bb, 139 (1978).-AA. VV., Discernimiento espiritual en tiempos dif\u00ed\u00adciles, en \u00abRev. de Espiritualidad\u00bb, 153 (1979).-Castillo, J. M. El discernimiento cristiano seg\u00fan san Pablo, Facultad de Teolog\u00ed\u00ada, Granada 1975.-Laplace, J, Discernement pour temps de Irise, Chalet, Par\u00ed\u00ads 1978.-Penning de Vries, P, Discernimiento. Din\u00e1mica existencial de la doctrina y del esp\u00ed\u00adritu de san Ignacio de Loyola, Mensajero, Bilbao 1967.-Therrien, G, Le discernement dans les \u00e9crits pauliniens, Gabalda, Par\u00ed\u00ads 1973.<\/p>\n<p>S. de Fiores &#8211; T. Goffi &#8211; Augusto Guerra, Nuevo Diccionario de Espiritualidad, Ediciones Paulinas, Madrid 1987<\/p>\n<p><b>Fuente: Nuevo Diccionario de Espiritualidad<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>v. Entendimiento, Inteligencia Psa 14:4 \u00bfno tienen d .. los que hacen iniquidad 1Co 12:10 otro, profec\u00eda; a otro, d de esp\u00edritus Heb 5:14 sentidos ejercitados en el d del bien [500] Acci\u00f3n de la inteligencia pr\u00e1ctica de diferenciar lo conveniente de lo que no lo es. Es un deber del ser libre y un &hellip; <a href=\"https:\/\/www.biblia.work\/diccionarios\/discernimiento\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abDISCERNIMIENTO\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-10484","post","type-post","status-publish","format-standard","hentry","category-diccionario"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/10484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/comments?post=10484"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/posts\/10484\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/media?parent=10484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/categories?post=10484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/diccionarios\/wp-json\/wp\/v2\/tags?post=10484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}